{"id":5404,"date":"2015-09-23T16:52:25","date_gmt":"2015-09-23T21:52:25","guid":{"rendered":"http:\/\/regnumchristi.es\/?page_id=5404"},"modified":"2023-06-09T10:01:15","modified_gmt":"2023-06-09T08:01:15","slug":"safe-environments","status":"publish","type":"page","link":"https:\/\/regnumchristi.org\/en\/ambientes-seguros\/","title":{"rendered":"Safe environments"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"5404\" class=\"elementor elementor-5404\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7e04024 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7e04024\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8ed7849\" data-id=\"8ed7849\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-892f32f elementor-widget elementor-widget-heading\" data-id=\"892f32f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">AMBIENTES<br><b>SEGUROS<\/b><\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2d6c359 elementor-section-stretched elementor-hidden-desktop elementor-hidden-tablet elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2d6c359\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;sticky&quot;:&quot;top&quot;,&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;sticky_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;],&quot;sticky_offset&quot;:0,&quot;sticky_effects_offset&quot;:0,&quot;sticky_anchor_link_offset&quot;:0}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-eb3f5fe\" data-id=\"eb3f5fe\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d935403 elementor-mobile-align-end elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"d935403\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/regnumchristi.org\/ambientes-seguros\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-square-full\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">... Un compromiso de todos en el RC<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-573004c\" data-id=\"573004c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f58870f elementor-mobile-align-end elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"f58870f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/regnumchristi.org\/ambientes-seguros-legionarios-de-cristo\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-square-full\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">.............................. Legionarios de Cristo<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-1b860d7\" data-id=\"1b860d7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7660f13 elementor-mobile-align-end elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"7660f13\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/regnumchristi.org\/ambientes-seguros-consagradas\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-square-full\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">............................................... Consagradas<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-6e422c0\" data-id=\"6e422c0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-64c0c6f elementor-mobile-align-end elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"64c0c6f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/regnumchristi.org\/ambientes-seguros-laicos-consagrados\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-square-full\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">.................................. Laicos consagrados<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-d8e52fa\" data-id=\"d8e52fa\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-09bec5a elementor-section-stretched elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"09bec5a\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;sticky&quot;:&quot;top&quot;,&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;sticky_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;],&quot;sticky_offset&quot;:0,&quot;sticky_effects_offset&quot;:0,&quot;sticky_anchor_link_offset&quot;:0}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-8f8744c\" data-id=\"8f8744c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2a0be63 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"2a0be63\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/regnumchristi.org\/ambientes-seguros\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-square-full\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">....... Un compromiso de todos en el RC<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-095ffb8\" data-id=\"095ffb8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-882ec0f elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"882ec0f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/regnumchristi.org\/ambientes-seguros-legionarios-de-cristo\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-square-full\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">....... Legionarios de Cristo<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-70a4153\" data-id=\"70a4153\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2751647 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"2751647\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/regnumchristi.org\/ambientes-seguros-consagradas\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-square-full\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">....... Consagradas<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-d747693\" data-id=\"d747693\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b585da5 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"b585da5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/regnumchristi.org\/ambientes-seguros-laicos-consagrados\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-square-full\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">....... Laicos consagrados<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-850b6bc elementor-section-height-min-height elementor-section-full_width elementor-section-content-space-between elementor-section-stretched elementor-section-height-default elementor-section-items-middle\" data-id=\"850b6bc\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c2b7ab9\" data-id=\"c2b7ab9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-79a4bbb elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"79a4bbb\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9b9981d\" data-id=\"9b9981d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a220f96 elementor-widget elementor-widget-text-editor\" data-id=\"a220f96\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4 style=\"text-align: center;\"><strong>Un compromiso de todos en el Regnum Christi<\/strong><\/h4>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-7e263fa elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7e263fa\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-847b019\" data-id=\"847b019\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-769358d elementor-widget elementor-widget-text-editor\" data-id=\"769358d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>El Regnum Christi est\u00e1 firmemente comprometido en crear y mantener ambientes seguros para los menores y adultos vulnerables que participan en su obra educativa, apost\u00f3lica y pastoral.<\/p><p>Dada la verdad de su historia, se est\u00e1 buscando favorecer caminos de sanaci\u00f3n para las personas que hayan sido v\u00edctima de alg\u00fan abuso, y poniendo los medios para que nunca m\u00e1s algo as\u00ed pueda suceder. Es un compromiso de todos. Y es irrenunciable.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-327a9d9\" data-id=\"327a9d9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1dd0294 elementor-widget elementor-widget-text-editor\" data-id=\"1dd0294\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Se han establecido c\u00f3digos de conducta para los legionarios de Cristo, consagradas, consagrados y laicos que tienen contacto con menores,\u00a0y procedimientos de prevenci\u00f3n y actuaci\u00f3n inmediata para que cualquier denuncia sea atendida y reportada a las autoridades. Los procedimientos est\u00e1n sometidos a la acreditaci\u00f3n de una instituci\u00f3n externa especializada para\u00a0asegurar los criterios m\u00e1s exigentes en la creaci\u00f3n de ambientes seguros.\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e81c318 elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e81c318\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-80cffe0\" data-id=\"80cffe0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bd3ab88 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"bd3ab88\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"fas fa-square-full\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4aeaf2e elementor-hidden-desktop elementor-hidden-tablet elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4aeaf2e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-015c624\" data-id=\"015c624\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b4bb79f elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"b4bb79f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"fas fa-square-full\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fc48485 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fc48485\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-3cb4b5e\" data-id=\"3cb4b5e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fa904d0 elementor-widget elementor-widget-text-editor\" data-id=\"fa904d0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default elementor-inline-editing pen\" style=\"font-style: normal; margin-bottom: 0px;\" data-elementor-setting-key=\"title\" data-pen-placeholder=\"Teclea aqu\u00ed...\"><strong>Los 4 pilares<\/strong><br \/><strong>de nuestros <\/strong><br \/><strong>Ambientes <\/strong><br \/><strong>Seguros<\/strong><\/h4>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-0c66d72\" data-id=\"0c66d72\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-78c0bc9 elementor-widget elementor-widget-spacer\" data-id=\"78c0bc9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8909c8a elementor-widget elementor-widget-text-editor\" data-id=\"8909c8a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Las pol\u00edticas y procedimientos implementados por las diferentes realidades del Regnum Christi tienen en cuenta la legislaci\u00f3n civil, las disposiciones dadas por la Santa Sede y las conferencias episcopales. Se someten a las exigencias de la acreditadora internacional especializada en prevenci\u00f3n de abusos Praesidium, y est\u00e1n organizadas en cuatro \u00e1reas o pilares:<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-66d827e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"66d827e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-52cd126\" data-id=\"52cd126\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4576c82 elementor-widget elementor-widget-image\" data-id=\"4576c82\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/regnumchristi.org\/wp-content\/uploads\/2022\/06\/icon_atencion-victimas-red-circle-RC.png\" class=\"attachment-full size-full wp-image-65992\" alt=\"\" srcset=\"https:\/\/regnumchristi.org\/wp-content\/uploads\/2022\/06\/icon_atencion-victimas-red-circle-RC.png 600w, https:\/\/regnumchristi.org\/wp-content\/uploads\/2022\/06\/icon_atencion-victimas-red-circle-RC-300x300.png 300w, https:\/\/regnumchristi.org\/wp-content\/uploads\/2022\/06\/icon_atencion-victimas-red-circle-RC-150x150.png 150w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-39510d1 elementor-widget elementor-widget-icon-box\" data-id=\"39510d1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h1 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tEscucha y accountability\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h1>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tCanales independiente e institucional de escucha y denuncia\nPrograma de reparaci\u00f3n a v\u00edctimas\nAccountability y transparencia\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-8cc19d7\" data-id=\"8cc19d7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3ca575d elementor-widget elementor-widget-image\" data-id=\"3ca575d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/regnumchristi.org\/wp-content\/uploads\/2022\/06\/icon_prevencion-red-circle-RC.png\" class=\"attachment-full size-full wp-image-65991\" alt=\"\" srcset=\"https:\/\/regnumchristi.org\/wp-content\/uploads\/2022\/06\/icon_prevencion-red-circle-RC.png 600w, https:\/\/regnumchristi.org\/wp-content\/uploads\/2022\/06\/icon_prevencion-red-circle-RC-300x300.png 300w, https:\/\/regnumchristi.org\/wp-content\/uploads\/2022\/06\/icon_prevencion-red-circle-RC-150x150.png 150w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9531112 elementor-widget elementor-widget-icon-box\" data-id=\"9531112\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tPrevenci\u00f3n\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tC\u00f3digos de conducta<\/br>\nFormaci\u00f3n y sensibilizaci\u00f3n\nCriterios de selecci\u00f3n\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-ecdfb26\" data-id=\"ecdfb26\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-59fc5a1 elementor-widget elementor-widget-image\" data-id=\"59fc5a1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/regnumchristi.org\/wp-content\/uploads\/2022\/06\/icon_actuacion-red-circle-RC.png\" class=\"attachment-full size-full wp-image-65993\" alt=\"\" srcset=\"https:\/\/regnumchristi.org\/wp-content\/uploads\/2022\/06\/icon_actuacion-red-circle-RC.png 600w, https:\/\/regnumchristi.org\/wp-content\/uploads\/2022\/06\/icon_actuacion-red-circle-RC-300x300.png 300w, https:\/\/regnumchristi.org\/wp-content\/uploads\/2022\/06\/icon_actuacion-red-circle-RC-150x150.png 150w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1ad59e2 elementor-widget elementor-widget-icon-box\" data-id=\"1ad59e2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tRespuesta y actuaci\u00f3n\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tProtocolos de actuaci\u00f3n ante denuncias y se\u00f1alaciones\nColaboraci\u00f3n con autoridades\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-8f9641d\" data-id=\"8f9641d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-82884d5 elementor-widget elementor-widget-image\" data-id=\"82884d5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/regnumchristi.org\/wp-content\/uploads\/2022\/06\/icon_supervison-red-circle-RC.png\" class=\"attachment-full size-full wp-image-65994\" alt=\"\" srcset=\"https:\/\/regnumchristi.org\/wp-content\/uploads\/2022\/06\/icon_supervison-red-circle-RC.png 600w, https:\/\/regnumchristi.org\/wp-content\/uploads\/2022\/06\/icon_supervison-red-circle-RC-300x300.png 300w, https:\/\/regnumchristi.org\/wp-content\/uploads\/2022\/06\/icon_supervison-red-circle-RC-150x150.png 150w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0855222 elementor-widget elementor-widget-icon-box\" data-id=\"0855222\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tSupervisi\u00f3n\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tCertificaci\u00f3n independiente\n\nMedidas de acompa\u00f1amiento y control a las personas que han hecho da\u00f1o\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8c7a431 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8c7a431\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-c63134a\" data-id=\"c63134a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2f1025c elementor-widget elementor-widget-heading\" data-id=\"2f1025c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\"><b>Coordinadores de Ambientes seguros,\natenci\u00f3n a v\u00edctimas\ny canal institucional<\/b><\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fc66e4e elementor-widget elementor-widget-text-editor\" data-id=\"fc66e4e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Si alguien hubiera sufrido un abuso por parte de un miembro del Regnum Christi, le invitamos a contactar a las autoridades competentes, independientemente de cu\u00e1ndo hayan ocurrido los hechos.<\/p><p>\u00a0<\/p><p><span style=\"color: #333333;\">Le pedimos que tambi\u00e9n contacte al coordinador de ambientes seguros a trav\u00e9s del canal de denuncias institucional, o al canal independiente.\u00a0<span style=\"background-color: var( --e-global-color-14cd57d ); font-style: inherit; font-weight: inherit;\">Queremos escuchar su historia, conocer los hechos, y recorrer un camino de sanaci\u00f3n.<\/span><\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-cfef6d9\" data-id=\"cfef6d9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-f1f78eb elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f1f78eb\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-e0c1ea9\" data-id=\"e0c1ea9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5066148 elementor-widget elementor-widget-text-editor\" data-id=\"5066148\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h5><strong>Legionarios de Cristo<\/strong><strong>\u00a0<\/strong><\/h5>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-10ca8f6 elementor-align-left elementor-widget elementor-widget-button\" data-id=\"10ca8f6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.0abusos.org\/ambientes-seguros\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">ENCARGADOS POR TERRITORIO<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a0e69da elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"a0e69da\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h5><strong>Consagradas del Regnum Christi<\/strong><\/h5>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-753e5a3 elementor-align-left elementor-widget elementor-widget-button\" data-id=\"753e5a3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/consagradasrc.org\/contacto\/#ambientes\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">ENCARGADAS POR TERRITORIO<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e83bccb elementor-widget elementor-widget-text-editor\" data-id=\"e83bccb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h5><strong>Laicos Consagrados del Regnum Christi<\/strong><\/h5>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2196ab5 elementor-align-left elementor-widget elementor-widget-button\" data-id=\"2196ab5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/laicosconsagradosrc.org\/ambientes-seguros\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">ENCARGADOS POR TERRITORIO<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-320946f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"320946f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-6dbde61\" data-id=\"6dbde61\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-617d647 elementor-widget elementor-widget-image\" data-id=\"617d647\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"200\" height=\"200\" src=\"https:\/\/regnumchristi.org\/wp-content\/uploads\/2022\/07\/Logo-Praesidium.jpg\" class=\"attachment-full size-full wp-image-69294\" alt=\"\" srcset=\"https:\/\/regnumchristi.org\/wp-content\/uploads\/2022\/07\/Logo-Praesidium.jpg 200w, https:\/\/regnumchristi.org\/wp-content\/uploads\/2022\/07\/Logo-Praesidium-150x150.jpg 150w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-00630a1\" data-id=\"00630a1\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6228e00 elementor-widget elementor-widget-heading\" data-id=\"6228e00\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\"><b>Acreditados por Praesidium<br>\ncomo instituci\u00f3n que logra el m\u00e1s alto est\u00e1ndar en la prevenci\u00f3n de abusos<\/b><\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cd71bf5 elementor-widget elementor-widget-text-editor\" data-id=\"cd71bf5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"background-color: var(--ast-global-color-5); color: #333333; font-family: Lato; font-size: 18px; font-style: inherit;\">Los est\u00e1ndares de Ambientes Seguros que se implementan en las diferentes realidades del Regnum Christi est\u00e1n dise\u00f1ados por Praesidium, una agencia internacional independiente, especializada en medidas de prevenci\u00f3n de abuso de menores y evaluaci\u00f3n de las mismas.\u00a0 Cada tres a\u00f1os examina y certifica el cumplimiento y correcta implementaci\u00f3n de estas exigencias que se actualizan en el tiempo, para asegurar que &#8220;se logra satisfacer el est\u00e1ndar m\u00e1s elevado en la prevenci\u00f3n de abuso infantil&#8221;.<\/span><\/p><p><span style=\"background-color: var(--ast-global-color-5);\">\u00a0<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1ad4449 elementor-align-start elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"1ad4449\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.0abusos.org\/estandares-acreditacion-2020\/\" target=\"_blank\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" id=\"Layer_1\" x=\"0px\" y=\"0px\" viewBox=\"0 0 600 600\" style=\"enable-background:new 0 0 600 600;\" xml:space=\"preserve\"><style type=\"text\/css\">\t.st0{fill:#FFFFFF;}\t.st1{fill:none;stroke:#17365F;stroke-width:9;stroke-linecap:round;stroke-linejoin:round;stroke-miterlimit:10;}\t.st2{fill:none;stroke:#17365F;stroke-width:9;stroke-miterlimit:10;}\t.st3{fill:none;stroke:#17365F;stroke-width:9;stroke-linejoin:round;stroke-miterlimit:10;}\t.st4{fill:#941A2D;}<\/style><circle class=\"st0\" cx=\"303.84\" cy=\"279.5\" r=\"258.54\"><\/circle><g>\t<path class=\"st4\" d=\"M441.36,344.12c0-9.61,0.05-19.21-0.03-28.82c-0.04-5.12-2.29-7.27-7.33-7.3c-5.1-0.03-10.19-0.01-15.85-0.01  c0-2.09,0-3.7,0-5.3c0-62.5,0-125,0-187.49c0-7.68-1.6-9.31-9.09-9.31c-53.52,0-107.03,0.04-160.55-0.08  c-3.83-0.01-6.55,1.19-9.2,3.86c-22.77,22.92-45.6,45.79-68.55,68.52c-3.18,3.15-4.51,6.39-4.51,10.86  c0.1,84.7,0.08,169.41,0.08,254.11c0,1-0.03,2,0.01,2.99c0.23,4.79,2.47,6.99,7.31,6.99c79.09,0.01,158.18,0.01,237.27,0  c4.79,0,7.06-2.24,7.21-7.09c0.11-3.49-0.23-7.01,0.13-10.47c0.2-1.9,0.97-4.12,2.25-5.48c5.57-5.89,11.32-11.61,17.2-17.2  c2.65-2.52,3.73-5.29,3.71-8.92C441.31,384.04,441.37,364.08,441.36,344.12z M239.51,128.61c0,16.09,0,33.1,0,50.38  c-17.17,0-34.3,0-50.38,0C205.61,162.51,222.68,145.44,239.51,128.61z M405.55,441.01c-75.48,0-151,0-226.71,0  c0-83.16,0-166.19,0-249.8c1.28,0,2.59,0,3.91,0c20.46,0,40.91,0.01,61.37,0c5.78,0,7.85-2.04,7.86-7.91  c0.03-20.21,0.01-40.41,0.01-60.62c0-1.47,0-2.93,0-4.61c51.32,0,102.28,0,153.71,0c0,63.3,0,126.37,0,189.94c-1.65,0-3.23,0-4.8,0  c-62.62,0-125.23,0-187.85,0c-6.61,0-8.52,1.85-8.53,8.36c-0.01,29.31-0.01,58.62,0,87.94c0,6.58,1.9,8.47,8.43,8.47  c62.62,0,125.23,0,187.85,0c1.48,0,2.97,0,4.76,0C405.55,422.24,405.55,431.5,405.55,441.01z M428.89,400.57  c-70.58,0-141.09,0-211.84,0c0-26.78,0-53.5,0-80.42c70.56,0,140.97,0,211.84,0C428.89,347.03,428.89,373.67,428.89,400.57z\"><\/path>\t<path class=\"st4\" d=\"M209.56,231.53c1.08,0.23,2.24,0.1,3.36,0.1c26.44,0,52.89,0,79.33,0c26.19,0,52.39,0,78.58,0  c1,0,2,0.04,2.99-0.02c3.47-0.19,6-2.67,6.06-5.88c0.05-3.18-2.5-5.81-5.9-6.03c-0.87-0.06-1.75-0.02-2.62-0.02  c-52.76,0-105.53,0-158.29,0c-1.12,0-2.26-0.09-3.36,0.07c-2.9,0.4-5.31,3.15-5.09,6.01C204.86,228.79,206.49,230.88,209.56,231.53  z\"><\/path>\t<path class=\"st4\" d=\"M209.91,285.47c0.98,0.12,1.99,0.05,2.99,0.05c52.89,0,105.78,0,158.66,0c1.12,0,2.28,0.13,3.36-0.1  c3.08-0.65,4.7-2.74,4.93-5.78c0.21-2.86-2.2-5.61-5.1-6c-1.1-0.15-2.24-0.07-3.36-0.07c-26.32,0-52.64,0-78.96,0  c-26.32,0-52.64,0-78.96,0c-1.12,0-2.25-0.07-3.37,0.04c-3.14,0.3-5.57,2.99-5.52,6.02C204.64,282.53,206.96,285.11,209.91,285.47z  \"><\/path>\t<path class=\"st4\" d=\"M293.27,177.72c26.56,0.02,53.13,0.01,79.69-0.01c1.1,0,2.3-0.06,3.27-0.51c2.64-1.23,4.04-3.43,3.5-6.34  c-0.63-3.37-2.84-5.09-6.36-5.08c-13.34,0.02-26.69,0.01-40.03,0.01c-13.34,0-26.69-0.01-40.03,0.01  c-4.31,0.01-7.11,2.39-7.12,5.95C286.17,175.29,288.98,177.72,293.27,177.72z\"><\/path>\t<path class=\"st4\" d=\"M298.69,382.14c0.05,4.38,2.36,6.63,6.74,6.66c6.98,0.05,13.95,0.07,20.93,0c11.44-0.11,20.98-9,21.71-20.48  c0.33-5.21,0.34-10.47,0.02-15.68c-0.71-11.72-10.21-20.58-21.89-20.67c-6.73-0.05-13.45-0.03-20.18-0.01  c-5.1,0.02-7.3,2.16-7.34,7.2c-0.04,6.98-0.01,13.95-0.01,20.93C298.67,367.44,298.61,374.79,298.69,382.14z M310.95,344.47  c5.88,0,11.7-0.44,17.42,0.14c4.57,0.47,7.55,4.59,7.7,9.22c0.14,4.35,0.13,8.72,0.01,13.07c-0.15,5.17-3.83,9.38-8.96,9.84  c-4.2,0.38-8.46,0.14-12.69,0.15c-1.09,0-2.19-0.11-3.48-0.18C310.95,365.87,310.95,355.22,310.95,344.47z\"><\/path>\t<path class=\"st4\" d=\"M247.88,387.87c1.6-1.21,2.77-3.85,2.94-5.93c0.42-5.05,0.14-10.16,0.14-15.57c7.04,0,13.63,0.05,20.21-0.01  c9.66-0.08,17.08-7.48,17.17-17.03c0.09-9.66-7.44-17.28-17.24-17.35c-8.11-0.05-16.22-0.02-24.33-0.01  c-5.98,0.01-7.94,2.01-7.95,8.15c-0.02,6.24,0,12.47,0,18.71c0,7.73-0.08,15.47,0.03,23.2  C238.93,387.47,243.98,390.82,247.88,387.87z M251.16,343.95c6.87,0,13.56-0.17,20.24,0.08c2.89,0.11,4.85,2,4.79,5.17  c-0.06,3.34-2.19,5.06-5.26,5.14c-6.46,0.18-12.94,0.06-19.77,0.06C251.16,350.71,251.16,347.53,251.16,343.95z\"><\/path>\t<path class=\"st4\" d=\"M358.63,382.68c0.19,3.74,2.78,6.19,6.18,6.13c3.28-0.06,5.57-2.35,5.85-6c0.12-1.61,0.07-3.24,0.07-4.86  c0.01-3.8,0-7.61,0-11.59c4.36,0,8.09,0.03,11.82-0.01c4.33-0.05,6.9-2.4,6.79-6.16c-0.1-3.59-2.59-5.73-6.8-5.77  c-3.82-0.04-7.63-0.01-11.63-0.01c0-3.64,0-6.83,0-10.51c10.24,0,20.07,0.01,29.91-0.01c4.68-0.01,7.3-2.25,7.23-6.09  c-0.06-3.71-2.6-5.83-7.11-5.84c-11.59-0.02-23.18-0.02-34.76,0c-5.49,0.01-7.59,2.13-7.6,7.73c-0.03,11.21-0.01,22.43-0.01,33.64  C358.58,376.45,358.47,379.58,358.63,382.68z\"><\/path><\/g><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Est\u00e1ndares Praesidium de acreditaci\u00f3n de ambientes seguros para institutos religiosos cat\u00f3licos y sociedades de vida apost\u00f3lica<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-55653ef elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"55653ef\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-c281eee\" data-id=\"c281eee\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-79cd40d elementor-widget elementor-widget-heading\" data-id=\"79cd40d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">ACCOUNTABILITY<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a7fc886 elementor-widget elementor-widget-heading\" data-id=\"a7fc886\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\"><b>Informes<\/br> de casos<\/b><\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-0d9f130\" data-id=\"0d9f130\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5fbac62 elementor-widget elementor-widget-text-editor\" data-id=\"5fbac62\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h6>Legionarios de Cristo<\/h6><p>El 22 de marzo de 2020 se public\u00f3 el I Informe anual Verdad, justicia y sanaci\u00f3n, en el que los Legionarios de Cristo a nivel mundial rindieron cuentas en sus compromisos para atenci\u00f3n a victimas de abuso y generaci\u00f3n de ambientes seguros. Desde entonces cada a\u00f1o se publica un informe de rendici\u00f3n de cuentas. Se actualizan los datos estad\u00edsticos y la informaci\u00f3n pertinente en <strong><a href=\"https:\/\/www.0abusos.org\/\" target=\"_blank\" rel=\"noopener\">0abusos.org<\/a><\/strong><\/p><h6>\u00a0<\/h6>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e3230f9 elementor-widget elementor-widget-button\" data-id=\"e3230f9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.0abusos.org\/accountability\/#casos\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-address-book\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">CASOS DE DE LEGIONARIOS DE CRISTO EN EL MUNDO<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f183531 elementor-widget elementor-widget-text-editor\" data-id=\"f183531\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h6>Laicos consagrados<\/h6><p>Los Laicos Consagrados publicaron el 3 de marzo de 2022 su primer informe anual con los avances y acciones dados en el campo de ambientes seguros, acreditaci\u00f3n, formaci\u00f3n, acompa\u00f1amiento y respuesta a denuncias. Desde entonces cada a\u00f1o se publica un informe de rendici\u00f3n de cuentas. Se actualizan los datos estad\u00edsticos y la informaci\u00f3n pertinente\u00a0<strong><a href=\"https:\/\/laicosconsagradosrc.org\/ambientes-seguros\/\" target=\"_blank\" rel=\"noopener\">aqu\u00ed.<\/a><\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-91fbd91 elementor-widget elementor-widget-button\" data-id=\"91fbd91\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/laicosconsagradosrc.org\/ambientes-seguros\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-address-book\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">CASOS DE LAICOS CONSAGRADOS EN EL MUNDO<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p> [&hellip;]<\/p>\n","protected":false},"author":49,"featured_media":66578,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"site-sidebar-layout":"no-sidebar","site-content-layout":"page-builder","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"_daextrevop_audio_file_creation_date":"","_daextrevop_text_to_speech":"","_daextrevop_document_type":"","footnotes":""},"class_list":["post-5404","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ambientes seguros - Regnum Christi Internacional<\/title>\n<meta name=\"description\" content=\"El Regnum Christi est\u00e1 firmemente comprometido en crear y mantener ambientes seguros para los menores y adultos vulnerables que tienen contacto con las personas que participan en sus actividades apost\u00f3licas, educativas y pastorales.Acreditados por Praesidium.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/regnumchristi.org\/en\/safe-environments\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ambientes seguros - Regnum Christi Internacional\" \/>\n<meta property=\"og:description\" content=\"El Regnum Christi est\u00e1 firmemente comprometido en crear y mantener ambientes seguros para los menores y adultos vulnerables que tienen contacto con las personas que participan en sus actividades apost\u00f3licas, educativas y pastorales.Acreditados por Praesidium.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/regnumchristi.org\/en\/safe-environments\/\" \/>\n<meta property=\"og:site_name\" content=\"Regnum Christi Internacional\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/RegnumChristiEspana\/\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-09T08:01:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/regnumchristi.org\/wp-content\/uploads\/2022\/04\/Ambientes-seguros-en-Espana.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"904\" \/>\n\t<meta property=\"og:image:height\" content=\"546\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/ambientes-seguros\\\/\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/ambientes-seguros\\\/\",\"name\":\"Ambientes seguros - Regnum Christi Internacional\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/ambientes-seguros\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/ambientes-seguros\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/regnumchristi.org\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/Ambientes-seguros-en-Espana.jpeg\",\"datePublished\":\"2015-09-23T21:52:25+00:00\",\"dateModified\":\"2023-06-09T08:01:15+00:00\",\"description\":\"El Regnum Christi est\u00e1 firmemente comprometido en crear y mantener ambientes seguros para los menores y adultos vulnerables que tienen contacto con las personas que participan en sus actividades apost\u00f3licas, educativas y pastorales.Acreditados por Praesidium.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/ambientes-seguros\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/regnumchristi.org\\\/ambientes-seguros\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/ambientes-seguros\\\/#primaryimage\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/Ambientes-seguros-en-Espana.jpeg\",\"contentUrl\":\"https:\\\/\\\/regnumchristi.org\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/Ambientes-seguros-en-Espana.jpeg\",\"width\":904,\"height\":546},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/ambientes-seguros\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/regnumchristi.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ambientes seguros\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#website\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/\",\"name\":\"Regnum Christi Internacional\",\"description\":\"El Regnum Christi es una realidad de la Iglesia cat\u00f3lica cuya misi\u00f3n es hacer presente el Reino de Cristo\",\"publisher\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/regnumchristi.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#organization\",\"name\":\"Regnum Christi Internacional\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/regnumchristi.es\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Favicon-RC_ligh-cuadrado.png\",\"contentUrl\":\"https:\\\/\\\/regnumchristi.es\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Favicon-RC_ligh-cuadrado.png\",\"width\":1080,\"height\":1080,\"caption\":\"Regnum Christi Internacional\"},\"image\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/RegnumChristiEspana\\\/\",\"https:\\\/\\\/x.com\\\/rc_espana\",\"https:\\\/\\\/www.instagram.com\\\/rc_espana\\\/\",\"https:\\\/\\\/es.linkedin.com\\\/company\\\/regnumchristiespaa\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ambientes seguros - Regnum Christi Internacional","description":"El Regnum Christi est\u00e1 firmemente comprometido en crear y mantener ambientes seguros para los menores y adultos vulnerables que tienen contacto con las personas que participan en sus actividades apost\u00f3licas, educativas y pastorales.Acreditados por Praesidium.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/regnumchristi.org\/en\/safe-environments\/","og_locale":"en_US","og_type":"article","og_title":"Ambientes seguros - Regnum Christi Internacional","og_description":"El Regnum Christi est\u00e1 firmemente comprometido en crear y mantener ambientes seguros para los menores y adultos vulnerables que tienen contacto con las personas que participan en sus actividades apost\u00f3licas, educativas y pastorales.Acreditados por Praesidium.","og_url":"https:\/\/regnumchristi.org\/en\/safe-environments\/","og_site_name":"Regnum Christi Internacional","article_publisher":"https:\/\/www.facebook.com\/RegnumChristiEspana\/","article_modified_time":"2023-06-09T08:01:15+00:00","og_image":[{"width":904,"height":546,"url":"https:\/\/regnumchristi.org\/wp-content\/uploads\/2022\/04\/Ambientes-seguros-en-Espana.jpeg","type":"image\/jpeg"}],"twitter_misc":{"Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/regnumchristi.org\/ambientes-seguros\/","url":"https:\/\/regnumchristi.org\/ambientes-seguros\/","name":"Ambientes seguros - Regnum Christi Internacional","isPartOf":{"@id":"https:\/\/regnumchristi.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/regnumchristi.org\/ambientes-seguros\/#primaryimage"},"image":{"@id":"https:\/\/regnumchristi.org\/ambientes-seguros\/#primaryimage"},"thumbnailUrl":"https:\/\/regnumchristi.org\/wp-content\/uploads\/2022\/04\/Ambientes-seguros-en-Espana.jpeg","datePublished":"2015-09-23T21:52:25+00:00","dateModified":"2023-06-09T08:01:15+00:00","description":"El Regnum Christi est\u00e1 firmemente comprometido en crear y mantener ambientes seguros para los menores y adultos vulnerables que tienen contacto con las personas que participan en sus actividades apost\u00f3licas, educativas y pastorales.Acreditados por Praesidium.","breadcrumb":{"@id":"https:\/\/regnumchristi.org\/ambientes-seguros\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/regnumchristi.org\/ambientes-seguros\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/regnumchristi.org\/ambientes-seguros\/#primaryimage","url":"https:\/\/regnumchristi.org\/wp-content\/uploads\/2022\/04\/Ambientes-seguros-en-Espana.jpeg","contentUrl":"https:\/\/regnumchristi.org\/wp-content\/uploads\/2022\/04\/Ambientes-seguros-en-Espana.jpeg","width":904,"height":546},{"@type":"BreadcrumbList","@id":"https:\/\/regnumchristi.org\/ambientes-seguros\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/regnumchristi.org\/es\/"},{"@type":"ListItem","position":2,"name":"Ambientes seguros"}]},{"@type":"WebSite","@id":"https:\/\/regnumchristi.org\/#website","url":"https:\/\/regnumchristi.org\/","name":"Regnum Christi International","description":"Regnum Christi is a reality of the Catholic Church whose mission is to make present the Kingdom of Christ.","publisher":{"@id":"https:\/\/regnumchristi.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/regnumchristi.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/regnumchristi.org\/#organization","name":"Regnum Christi International","url":"https:\/\/regnumchristi.org\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/regnumchristi.org\/#\/schema\/logo\/image\/","url":"https:\/\/regnumchristi.es\/wp-content\/uploads\/2023\/03\/Favicon-RC_ligh-cuadrado.png","contentUrl":"https:\/\/regnumchristi.es\/wp-content\/uploads\/2023\/03\/Favicon-RC_ligh-cuadrado.png","width":1080,"height":1080,"caption":"Regnum Christi Internacional"},"image":{"@id":"https:\/\/regnumchristi.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/RegnumChristiEspana\/","https:\/\/x.com\/rc_espana","https:\/\/www.instagram.com\/rc_espana\/","https:\/\/es.linkedin.com\/company\/regnumchristiespaa"]}]}},"_links":{"self":[{"href":"https:\/\/regnumchristi.org\/en\/wp-json\/wp\/v2\/pages\/5404","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/regnumchristi.org\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/regnumchristi.org\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/regnumchristi.org\/en\/wp-json\/wp\/v2\/users\/49"}],"replies":[{"embeddable":true,"href":"https:\/\/regnumchristi.org\/en\/wp-json\/wp\/v2\/comments?post=5404"}],"version-history":[{"count":115,"href":"https:\/\/regnumchristi.org\/en\/wp-json\/wp\/v2\/pages\/5404\/revisions"}],"predecessor-version":[{"id":107900,"href":"https:\/\/regnumchristi.org\/en\/wp-json\/wp\/v2\/pages\/5404\/revisions\/107900"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/regnumchristi.org\/en\/wp-json\/wp\/v2\/media\/66578"}],"wp:attachment":[{"href":"https:\/\/regnumchristi.org\/en\/wp-json\/wp\/v2\/media?parent=5404"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}