{"id":10126,"date":"2022-11-04T20:00:24","date_gmt":"2022-11-05T02:00:24","guid":{"rendered":"http:\/\/www.regnumchristi.org\/es\/?p=10126"},"modified":"2023-08-02T13:35:46","modified_gmt":"2023-08-02T19:35:46","slug":"sabado-5-de-noviembre-de-2022-no-hay-criado-que-pueda-servir-a-dos-amos","status":"publish","type":"post","link":"https:\/\/regnumchristi.org\/en\/sabado-5-de-noviembre-de-2022-no-hay-criado-que-pueda-servir-a-dos-amos\/","title":{"rendered":"S\u00e1bado 5 de noviembre de 2022 &#8211; \u00abNo hay criado que pueda servir a dos amos\u00bb"},"content":{"rendered":"<p><em>Hiram Gal\u00e1n, LC<\/em><\/p>\n<p>In the name of the Father and of the Son and of the Holy Spirit.<br \/>\nAmen.<\/p>\n<p>Christ, our King.<br \/>\nThy Kingdom come!<\/p>\n<p><span style=\"color: #800000;\"><strong>Preparatory prayer<\/strong><\/span> <em>(to put me in the presence of God)<\/em><\/p>\n<p>Se\u00f1or, est\u00e1s a la puerta y llamas\u2026 Cu\u00e1ntas veces has tocado a la puerta de mi coraz\u00f3n y yo continuamente te ignoro. Hoy al menos quiero regalarte este momento; si bien no me siento capaz de abrirte pues me da miedo que me puedas pedir algo, te dejo la puerta de mi coraz\u00f3n sin seguro para que pases y seas T\u00fa el que vea la necesidades que hay en \u00e9l.<\/p>\n<p><span style=\"color: #800000;\"><strong>Gospel of the day<\/strong><\/span> <em>(to guide your meditation)<br \/>\n<\/em>From the Holy Gospel according to Luke 16:9-15<\/p>\n<p>En aquel tiempo, Jes\u00fas dijo a sus disc\u00edpulos: &#8220;Con el dinero, tan lleno de injusticias, g\u00e1nense amigos que, cuando ustedes mueran, los reciban en el cielo. El que es fiel en las cosas peque\u00f1as, tambi\u00e9n es fiel en las grandes; y el que es infiel en las cosas peque\u00f1as, tambi\u00e9n es infiel en las grandes. Si ustedes no son fieles administradores del dinero, tan lleno de injusticias, \u00bfqui\u00e9n les confiar\u00e1 los bienes verdaderos? Y si no han sido fieles en lo que no es de ustedes, \u00bfqui\u00e9n les confiar\u00e1 lo que s\u00ed es de ustedes? No hay criado que pueda servir a dos amos, pues odiar\u00e1 a uno y amar\u00e1 al otro, o se apegar\u00e1 al primero y despreciar\u00e1 al segundo. En resumen, no pueden ustedes servir a Dios y al dinero&#8221;. Al o\u00edr estas cosas, los fariseos, que son amantes del dinero, se burlaban de Jes\u00fas. Pero \u00e9l les dijo: &#8220;Ustedes pretenden pasar por justos delante de los hombres; pero Dios conoce sus corazones, y lo que es muy estimable para los hombres es detestable para Dios&#8221;.<\/p>\n<p><em>Word of the Lord.<\/em><\/p>\n<p><span style=\"color: #800000;\"><strong>Meditate on what God tells you in the Gospel<\/strong><\/span><\/p>\n<p>\u00c9sta es una de las frases evang\u00e9licas m\u00e1s conocidas por la sociedad, pero parad\u00f3jicamente es tambi\u00e9n la que muchos parecen intentar vivir de manera contraria. La gran mayor\u00eda de los cat\u00f3licos tenemos muy en claro que amamos a Dios sobre todas las cosas, y que si bien no todos tenemos un compromiso activo con la iglesia, si tratamos de vivir de acuerdo a las leyes de Dios. Pero la verdadera interrogante llega cuando el amar a Dios sobre todas las cosas pasa de la teor\u00eda a la vida real.<\/p>\n<p>\u00bfCu\u00e1ntas veces hemos estado dispuestos a hacer lo que sea con tal de ganar m\u00e1s dinero? Si se nos presenta la oportunidad de mentir, modificar e incluso hacer alguna trampilla para ahorrarnos o ganarnos unos centavos, \u00bfpreferimos optar por vivir en la verdad y pagar el precio de ello?<\/p>\n<p>Creo que no, una prueba clara de ello est\u00e1 en nuestro comportamiento diario, ya sea en la evasi\u00f3n de impuestos, en la mordida que le damos al oficial de tr\u00e1nsito para evitar una multa mayor, o en las simples mentiras diarias que nos permiten conservar nuestro puesto de trabajo o incluso granjearnos un ascenso.<\/p>\n<p>\u00bfEsto es amar a Dios sobre todas las cosas? \u00bfEn verdad podemos pretender llevar una doble vida de amor a Dios y amor al dinero?<\/p>\n<p>Nuestra vida se desarrolla en una continua b\u00fasqueda de la felicidad, y eso est\u00e1 perfecto, cuando tenemos bien claro que nuestra felicidad s\u00f3lo est\u00e1 en Cristo. Pero cuando buscamos la felicidad en otros sitios, no s\u00f3lo no la encontramos sino que terminamos m\u00e1s infelices y vac\u00edos de como empezamos.<\/p>\n<p>El dinero no es malo, es malo darle un lugar privilegiado en nuestra jerarqu\u00eda de valores, o peor a\u00fan, suplantar el lugar que le debemos a Dios poniendo al dios dinero. Recordemos siempre que nos veamos agobiados y preocupados por algo que no sea Dios, que \u00abno podemos servir a dos amos pues terminaremos amando a uno y odiando al otro\u00bb.<\/p>\n<p><em>\u00abLa Palabra de Dios nos conduce a una elecci\u00f3n final: \u201cning\u00fan criado puede servir a dos se\u00f1ores porque aborrecer\u00e1 a uno y amar\u00e1 al otro; o bien se entregar\u00e1 a uno y despreciar\u00e1 al otro\u201d. El estafador ama la estafa y odia la honestidad. El estafador ama los sobornos los acuerdos oscuros, esos acuerdos que se hacen en la oscuridad. Y la cosa peor es que \u00e9l cree ser honesto. El estafador ama el dinero, ama las riquezas: las riquezas son un \u00eddolo. A \u00e9l no le importa \u2014como dice el profeta\u2014 pisotear a los pobres. Son los que tienen las grandes \u201cindustrias del trabajo esclavo\u201d. Y hoy en el mundo, el trabajo esclavo es un estilo de gesti\u00f3n\u00bb.<\/em><br \/>\n<em>(Homily of H.H. Francis, September 18, 2016).<\/em><\/p>\n<p><span style=\"color: #800000;\"><strong>Dialogue with Christ<\/strong><\/span><\/p>\n<p><em>This is the most important part of your prayer, prepare yourself to talk with much love with the One who loves you.<\/em><\/p>\n<p><span style=\"color: #800000;\"><strong>Purpose<\/strong><\/span><\/p>\n<p><em>Propose a personal one. The one that involves the most love in response to the Beloved... or, if you believe that this is what God is asking of you, live what is suggested below.<\/em><\/p>\n<p>Tratar\u00e9 de considerar que en el mundo existen personas que sobreviven con una cuarta parte de lo que yo tengo y buscar\u00e9 alg\u00fan medio por el cual pueda ayudar y ser solidario con los que menos tienen.<\/p>\n<p><span style=\"color: #800000;\"><strong>Farewell<\/strong><\/span><\/p>\n<p>We thank you, Lord, for all your benefits, you who live and reign forever and ever.<br \/>\nAmen.<\/p>\n<p>Christ, our King!<br \/>\nThy Kingdom come!<\/p>\n<p>Most prudent Virgin, Mary, Mother of the Church.<br \/>\nPray for us.<\/p>\n<p>In the name of the Father and of the Son and of the Holy Spirit.<br \/>\nAmen.<\/p>","protected":false},"excerpt":{"rendered":"<p> [&hellip;]<\/p>\n","protected":false},"author":58,"featured_media":34810,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"_daextrevop_audio_file_creation_date":"","_daextrevop_text_to_speech":"","_daextrevop_document_type":"","footnotes":""},"categories":[3164],"tags":[3162,3163,3067],"class_list":["post-10126","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-meditacion-del-dia","tag-evangelio","tag-meditacion","tag-reflexion"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>S\u00e1bado 5 de noviembre de 2022 - \u00abNo hay criado que pueda servir a dos amos\u00bb - Regnum Christi Internacional<\/title>\n<meta name=\"description\" content=\"El dinero no es malo, es malo darle un lugar privilegiado en nuestra jerarqu\u00eda de valores, o peor a\u00fan, suplantar el lugar que debemos a Dios.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/regnumchristi.org\/en\/sabado-5-de-noviembre-de-2022-no-hay-criado-que-pueda-servir-a-dos-amos\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"S\u00e1bado 5 de noviembre de 2022 - \u00abNo hay criado que pueda servir a dos amos\u00bb - Regnum Christi Internacional\" \/>\n<meta property=\"og:description\" content=\"El dinero no es malo, es malo darle un lugar privilegiado en nuestra jerarqu\u00eda de valores, o peor a\u00fan, suplantar el lugar que debemos a Dios.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/regnumchristi.org\/en\/sabado-5-de-noviembre-de-2022-no-hay-criado-que-pueda-servir-a-dos-amos\/\" \/>\n<meta property=\"og:site_name\" content=\"Regnum Christi Internacional\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/RegnumChristiEspana\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-11-05T02:00:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-08-02T19:35:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/regnumchristi.org\/wp-content\/uploads\/2022\/11\/Imagenes-Meditaciones-Diarias-5-de-noviembre.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"563\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Meditaciones Diarias\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Meditaciones Diarias\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/en\\\/sabado-5-de-noviembre-de-2022-no-hay-criado-que-pueda-servir-a-dos-amos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/en\\\/sabado-5-de-noviembre-de-2022-no-hay-criado-que-pueda-servir-a-dos-amos\\\/\"},\"author\":{\"name\":\"Meditaciones Diarias\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#\\\/schema\\\/person\\\/a5ad8b3c4bd3cb3a0abe8a1474fe8f0a\"},\"headline\":\"S\u00e1bado 5 de noviembre de 2022 &#8211; \u00abNo hay criado que pueda servir a dos amos\u00bb\",\"datePublished\":\"2022-11-05T02:00:24+00:00\",\"dateModified\":\"2023-08-02T19:35:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/en\\\/sabado-5-de-noviembre-de-2022-no-hay-criado-que-pueda-servir-a-dos-amos\\\/\"},\"wordCount\":975,\"publisher\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/en\\\/sabado-5-de-noviembre-de-2022-no-hay-criado-que-pueda-servir-a-dos-amos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/regnumchristi.org\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/Imagenes-Meditaciones-Diarias-5-de-noviembre.jpg\",\"keywords\":[\"Evangelio\",\"meditaci\u00f3n\",\"Reflexi\u00f3n\"],\"articleSection\":[\"Meditaci\u00f3n del d\u00eda\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/en\\\/sabado-5-de-noviembre-de-2022-no-hay-criado-que-pueda-servir-a-dos-amos\\\/\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/en\\\/sabado-5-de-noviembre-de-2022-no-hay-criado-que-pueda-servir-a-dos-amos\\\/\",\"name\":\"S\u00e1bado 5 de noviembre de 2022 - \u00abNo hay criado que pueda servir a dos amos\u00bb - Regnum Christi Internacional\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/en\\\/sabado-5-de-noviembre-de-2022-no-hay-criado-que-pueda-servir-a-dos-amos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/en\\\/sabado-5-de-noviembre-de-2022-no-hay-criado-que-pueda-servir-a-dos-amos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/regnumchristi.org\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/Imagenes-Meditaciones-Diarias-5-de-noviembre.jpg\",\"datePublished\":\"2022-11-05T02:00:24+00:00\",\"dateModified\":\"2023-08-02T19:35:46+00:00\",\"description\":\"El dinero no es malo, es malo darle un lugar privilegiado en nuestra jerarqu\u00eda de valores, o peor a\u00fan, suplantar el lugar que debemos a Dios.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/en\\\/sabado-5-de-noviembre-de-2022-no-hay-criado-que-pueda-servir-a-dos-amos\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/regnumchristi.org\\\/en\\\/sabado-5-de-noviembre-de-2022-no-hay-criado-que-pueda-servir-a-dos-amos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/en\\\/sabado-5-de-noviembre-de-2022-no-hay-criado-que-pueda-servir-a-dos-amos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/Imagenes-Meditaciones-Diarias-5-de-noviembre.jpg\",\"contentUrl\":\"https:\\\/\\\/regnumchristi.org\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/Imagenes-Meditaciones-Diarias-5-de-noviembre.jpg\",\"width\":900,\"height\":563,\"caption\":\"\u00bfMe invitar\u00eda Jes\u00fas al banquete?\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/en\\\/sabado-5-de-noviembre-de-2022-no-hay-criado-que-pueda-servir-a-dos-amos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/regnumchristi.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"S\u00e1bado 5 de noviembre de 2022 &#8211; \u00abNo hay criado que pueda servir a dos amos\u00bb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#website\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/\",\"name\":\"Regnum Christi Internacional\",\"description\":\"El Regnum Christi es una realidad de la Iglesia cat\u00f3lica cuya misi\u00f3n es hacer presente el Reino de Cristo\",\"publisher\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/regnumchristi.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#organization\",\"name\":\"Regnum Christi Internacional\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/regnumchristi.es\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Favicon-RC_ligh-cuadrado.png\",\"contentUrl\":\"https:\\\/\\\/regnumchristi.es\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Favicon-RC_ligh-cuadrado.png\",\"width\":1080,\"height\":1080,\"caption\":\"Regnum Christi Internacional\"},\"image\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/RegnumChristiEspana\\\/\",\"https:\\\/\\\/x.com\\\/rc_espana\",\"https:\\\/\\\/www.instagram.com\\\/rc_espana\\\/\",\"https:\\\/\\\/es.linkedin.com\\\/company\\\/regnumchristiespaa\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#\\\/schema\\\/person\\\/a5ad8b3c4bd3cb3a0abe8a1474fe8f0a\",\"name\":\"Meditaciones Diarias\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/en\\\/author\\\/meditacionesd\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"S\u00e1bado 5 de noviembre de 2022 - \u00abNo hay criado que pueda servir a dos amos\u00bb - Regnum Christi Internacional","description":"El dinero no es malo, es malo darle un lugar privilegiado en nuestra jerarqu\u00eda de valores, o peor a\u00fan, suplantar el lugar que debemos a Dios.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/regnumchristi.org\/en\/sabado-5-de-noviembre-de-2022-no-hay-criado-que-pueda-servir-a-dos-amos\/","og_locale":"en_US","og_type":"article","og_title":"S\u00e1bado 5 de noviembre de 2022 - \u00abNo hay criado que pueda servir a dos amos\u00bb - Regnum Christi Internacional","og_description":"El dinero no es malo, es malo darle un lugar privilegiado en nuestra jerarqu\u00eda de valores, o peor a\u00fan, suplantar el lugar que debemos a Dios.","og_url":"https:\/\/regnumchristi.org\/en\/sabado-5-de-noviembre-de-2022-no-hay-criado-que-pueda-servir-a-dos-amos\/","og_site_name":"Regnum Christi Internacional","article_publisher":"https:\/\/www.facebook.com\/RegnumChristiEspana\/","article_published_time":"2022-11-05T02:00:24+00:00","article_modified_time":"2023-08-02T19:35:46+00:00","og_image":[{"width":900,"height":563,"url":"https:\/\/regnumchristi.org\/wp-content\/uploads\/2022\/11\/Imagenes-Meditaciones-Diarias-5-de-noviembre.jpg","type":"image\/jpeg"}],"author":"Meditaciones Diarias","twitter_misc":{"Written by":"Meditaciones Diarias","Est. reading time":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/regnumchristi.org\/en\/sabado-5-de-noviembre-de-2022-no-hay-criado-que-pueda-servir-a-dos-amos\/#article","isPartOf":{"@id":"https:\/\/regnumchristi.org\/en\/sabado-5-de-noviembre-de-2022-no-hay-criado-que-pueda-servir-a-dos-amos\/"},"author":{"name":"Meditaciones Diarias","@id":"https:\/\/regnumchristi.org\/#\/schema\/person\/a5ad8b3c4bd3cb3a0abe8a1474fe8f0a"},"headline":"S\u00e1bado 5 de noviembre de 2022 &#8211; \u00abNo hay criado que pueda servir a dos amos\u00bb","datePublished":"2022-11-05T02:00:24+00:00","dateModified":"2023-08-02T19:35:46+00:00","mainEntityOfPage":{"@id":"https:\/\/regnumchristi.org\/en\/sabado-5-de-noviembre-de-2022-no-hay-criado-que-pueda-servir-a-dos-amos\/"},"wordCount":975,"publisher":{"@id":"https:\/\/regnumchristi.org\/#organization"},"image":{"@id":"https:\/\/regnumchristi.org\/en\/sabado-5-de-noviembre-de-2022-no-hay-criado-que-pueda-servir-a-dos-amos\/#primaryimage"},"thumbnailUrl":"https:\/\/regnumchristi.org\/wp-content\/uploads\/2022\/11\/Imagenes-Meditaciones-Diarias-5-de-noviembre.jpg","keywords":["Evangelio","meditaci\u00f3n","Reflexi\u00f3n"],"articleSection":["Meditaci\u00f3n del d\u00eda"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/regnumchristi.org\/en\/sabado-5-de-noviembre-de-2022-no-hay-criado-que-pueda-servir-a-dos-amos\/","url":"https:\/\/regnumchristi.org\/en\/sabado-5-de-noviembre-de-2022-no-hay-criado-que-pueda-servir-a-dos-amos\/","name":"S\u00e1bado 5 de noviembre de 2022 - \u00abNo hay criado que pueda servir a dos amos\u00bb - Regnum Christi Internacional","isPartOf":{"@id":"https:\/\/regnumchristi.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/regnumchristi.org\/en\/sabado-5-de-noviembre-de-2022-no-hay-criado-que-pueda-servir-a-dos-amos\/#primaryimage"},"image":{"@id":"https:\/\/regnumchristi.org\/en\/sabado-5-de-noviembre-de-2022-no-hay-criado-que-pueda-servir-a-dos-amos\/#primaryimage"},"thumbnailUrl":"https:\/\/regnumchristi.org\/wp-content\/uploads\/2022\/11\/Imagenes-Meditaciones-Diarias-5-de-noviembre.jpg","datePublished":"2022-11-05T02:00:24+00:00","dateModified":"2023-08-02T19:35:46+00:00","description":"El dinero no es malo, es malo darle un lugar privilegiado en nuestra jerarqu\u00eda de valores, o peor a\u00fan, suplantar el lugar que debemos a Dios.","breadcrumb":{"@id":"https:\/\/regnumchristi.org\/en\/sabado-5-de-noviembre-de-2022-no-hay-criado-que-pueda-servir-a-dos-amos\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/regnumchristi.org\/en\/sabado-5-de-noviembre-de-2022-no-hay-criado-que-pueda-servir-a-dos-amos\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/regnumchristi.org\/en\/sabado-5-de-noviembre-de-2022-no-hay-criado-que-pueda-servir-a-dos-amos\/#primaryimage","url":"https:\/\/regnumchristi.org\/wp-content\/uploads\/2022\/11\/Imagenes-Meditaciones-Diarias-5-de-noviembre.jpg","contentUrl":"https:\/\/regnumchristi.org\/wp-content\/uploads\/2022\/11\/Imagenes-Meditaciones-Diarias-5-de-noviembre.jpg","width":900,"height":563,"caption":"\u00bfMe invitar\u00eda Jes\u00fas al banquete?"},{"@type":"BreadcrumbList","@id":"https:\/\/regnumchristi.org\/en\/sabado-5-de-noviembre-de-2022-no-hay-criado-que-pueda-servir-a-dos-amos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/regnumchristi.org\/es\/"},{"@type":"ListItem","position":2,"name":"S\u00e1bado 5 de noviembre de 2022 &#8211; \u00abNo hay criado que pueda servir a dos amos\u00bb"}]},{"@type":"WebSite","@id":"https:\/\/regnumchristi.org\/#website","url":"https:\/\/regnumchristi.org\/","name":"Regnum Christi International","description":"Regnum Christi is a reality of the Catholic Church whose mission is to make present the Kingdom of Christ.","publisher":{"@id":"https:\/\/regnumchristi.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/regnumchristi.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/regnumchristi.org\/#organization","name":"Regnum Christi International","url":"https:\/\/regnumchristi.org\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/regnumchristi.org\/#\/schema\/logo\/image\/","url":"https:\/\/regnumchristi.es\/wp-content\/uploads\/2023\/03\/Favicon-RC_ligh-cuadrado.png","contentUrl":"https:\/\/regnumchristi.es\/wp-content\/uploads\/2023\/03\/Favicon-RC_ligh-cuadrado.png","width":1080,"height":1080,"caption":"Regnum Christi Internacional"},"image":{"@id":"https:\/\/regnumchristi.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/RegnumChristiEspana\/","https:\/\/x.com\/rc_espana","https:\/\/www.instagram.com\/rc_espana\/","https:\/\/es.linkedin.com\/company\/regnumchristiespaa"]},{"@type":"Person","@id":"https:\/\/regnumchristi.org\/#\/schema\/person\/a5ad8b3c4bd3cb3a0abe8a1474fe8f0a","name":"Daily Meditations","url":"https:\/\/regnumchristi.org\/en\/author\/meditacionesd\/"}]}},"_links":{"self":[{"href":"https:\/\/regnumchristi.org\/en\/wp-json\/wp\/v2\/posts\/10126","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/regnumchristi.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/regnumchristi.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/regnumchristi.org\/en\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/regnumchristi.org\/en\/wp-json\/wp\/v2\/comments?post=10126"}],"version-history":[{"count":1,"href":"https:\/\/regnumchristi.org\/en\/wp-json\/wp\/v2\/posts\/10126\/revisions"}],"predecessor-version":[{"id":93987,"href":"https:\/\/regnumchristi.org\/en\/wp-json\/wp\/v2\/posts\/10126\/revisions\/93987"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/regnumchristi.org\/en\/wp-json\/wp\/v2\/media\/34810"}],"wp:attachment":[{"href":"https:\/\/regnumchristi.org\/en\/wp-json\/wp\/v2\/media?parent=10126"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/regnumchristi.org\/en\/wp-json\/wp\/v2\/categories?post=10126"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/regnumchristi.org\/en\/wp-json\/wp\/v2\/tags?post=10126"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}