{"id":103282,"date":"2024-07-19T19:00:39","date_gmt":"2024-07-20T01:00:39","guid":{"rendered":"https:\/\/regnumchristi.org\/es\/?p=103282"},"modified":"2024-07-21T16:59:42","modified_gmt":"2024-07-21T22:59:42","slug":"sabado-20-de-julio-de-2024-no-quebrara-la-cana-doblada","status":"publish","type":"post","link":"https:\/\/regnumchristi.org\/en\/sabado-20-de-julio-de-2024-no-quebrara-la-cana-doblada\/","title":{"rendered":"S\u00e1bado 20 de julio de 2024 &#8211; \u00abNo quebrar\u00e1 la ca\u00f1a doblada\u00bb"},"content":{"rendered":"<p>In the name of the Father and of the Son and of the Holy Spirit.<br \/>\nAmen.<\/p>\n<p>Christ, our King.<br \/>\nThy Kingdom come!<\/p>\n<p><span style=\"color: #800000;\"><strong>Preparatory prayer<\/strong><\/span>\u00a0<em>(to put me in the presence of God)<\/em><\/p>\n<p>Se\u00f1or, me pongo en tu presencia en este d\u00eda. T\u00f3mame de las manos, Padre m\u00edo, y conduce mi alma en esta meditaci\u00f3n y durante toda mi vida. Te agradezco tantas gracias que me has concedido sin yo merecerlas: mi vida, la fe, mi familia, tu amor y tu perd\u00f3n. Por todo te doy gracias, Se\u00f1or.<\/p>\n<p><span style=\"color: #800000;\"><strong>Gospel of the day<\/strong><\/span>\u00a0<em>(to guide your meditation)<\/em><br \/>\nDel Santo Evangelio seg\u00fan San Mateo 12, 14-21<\/p>\n<p>En seguida los fariseos salieron y se confabularon para buscar la forma de acabar con \u00e9l. Al enterarse de esto, Jes\u00fas se alej\u00f3 de all\u00ed. Muchos lo siguieron, y los cur\u00f3 a todos. Pero \u00e9l les orden\u00f3 severamente que no lo dieran a conocer, para que se cumpliera lo anunciado por el profeta Isa\u00edas: \u00abEste es mi servidor, a quien eleg\u00ed, mi muy querido, en quien tengo puesta mi predilecci\u00f3n. Derramar\u00e9 mi esp\u00edritu sobre \u00e9l y anunciar\u00e1 la justicia a las naciones. No discutir\u00e1 ni gritar\u00e1, y nadie oir\u00e1 su voz en las plazas. No quebrar\u00e1 la ca\u00f1a doblada y no apagar\u00e1 la mecha humeante, hasta que haga triunfar la justicia; y las naciones pondr\u00e1n la esperanza en su nombre\u00bb.<\/p>\n<p><em>Word of the Lord.<\/em><\/p>\n<p><span style=\"color: #800000;\"><strong>Meditate on what God tells you in the Gospel<\/strong><\/span><\/p>\n<p>El Evangelio de hoy nos muestra la misericordia y la bondad de Dios.<\/p>\n<p>\u00abNo quebrar\u00e1 la ca\u00f1a doblada y no apagar\u00e1 la mecha humeante, hasta que haga triunfar la justicia; y las naciones pondr\u00e1n la esperanza en su nombre\u00bb.<\/p>\n<p>Cuando vemos algo a punto de romperse, con frecuencia lo terminamos de romper o simplemente lo desechamos de inmediato. Dios no es as\u00ed, \u00c9l es misericordioso. Las ca\u00f1as ya maltrechas o las mechas casi extintas, pueden ser nuestras almas fr\u00edas por la rutina o dobladas por la inconsciencia, la tibieza o el pecado. M\u00e1s \u00c9l no termina de romper, apagar y desechar nuestras almas, sino que espera. A\u00fan m\u00e1s, \u00a1cu\u00e1ntas veces nos rehace y enciende de nuevo! Porque \u00c9l mismo dijo: \u00abNo vengo a condenar sino a dar la salvaci\u00f3n\u00bb. No condena sino que espera el momento de nuestra conversi\u00f3n, porque nos ama y porque su misericordia es eterna.<\/p>\n<p>Lo que Cristo desea es que regresemos. Por eso aguarda con amor a que volvamos a \u00c9l para encender la llama de su amor en nuestro coraz\u00f3n.<\/p>\n<p>\u00abEste es mi servidor\u00bb. Evidentemente estas palabras se refieren a Jes\u00fas. No obstante, el Padre nos dice a cada uno: \u00abEste es mi servidor quien pregonar\u00e1 por toda la tierra mi amor y misericordia\u00bb.<\/p>\n<p>Por el bautismo, cada cristiano es constituido mensajero de la Buena Nueva, el Evangelio. A nosotros nos corresponde ayudar a otros a fijar sus ojos en el Se\u00f1or y que su reino llegue a todos los confines de la tierra.<\/p>\n<p><em>\u00abAs\u00ed era la vida de Jes\u00fas: \u201cRecorri\u00f3 toda Galilea, predicando en sus sinagogas y expulsando los demonios\u201d. Jes\u00fas que predica y Jes\u00fas que cura. Toda la jornada era as\u00ed: predica al pueblo, ense\u00f1a la Ley, ense\u00f1a el Evangelio. Y la gente lo busca para escucharlo y tambi\u00e9n porque sana a los enfermos. \u201cAl anochecer, cuando se puso el sol, le llevaron a todos los enfermos y endemoniados\u2026 Cur\u00f3 a muchos enfermos de diversos males y expuls\u00f3 a muchos demonios\u201d. Y nosotros estamos delante de Jes\u00fas en esta celebraci\u00f3n: Jes\u00fas es quien preside esta celebraci\u00f3n. Nosotros, sacerdotes, estamos en el nombre de Jes\u00fas, pero es \u00c9l quien preside, \u00c9l es el verdadero Sacerdote que ofrece el sacrificio al Padre. Podemos preguntarnos si yo dejo que Jes\u00fas me predique. Cada uno de nosotros: \u201c\u00bfDejo que Jes\u00fas me predique, o yo s\u00e9 todo? \u00bfEscucho a Jes\u00fas o prefiero escuchar cualquier otra cosa, quiz\u00e1 las habladur\u00edas de la gente, o historias\u2026?\u201d. Escuchar a Jes\u00fas. Escuchar la predicaci\u00f3n de Jes\u00fas. \u201c\u00bfY c\u00f3mo puedo hacer esto, padre? \u00bfEn qu\u00e9 canal de televisi\u00f3n habla Jes\u00fas?\u201d. Te habla en el Evangelio. Y esta es una costumbre que a\u00fan no tenemos: ir a buscar la palabra de Jes\u00fas en el Evangelio. Llevar siempre un Evangelio con nosotros, peque\u00f1o, y tenerlo al alcance de la mano\u00bb.<\/em><br \/>\n(Homil\u00eda de S.S. Francisco, 8 de febrero de 2015).<\/p>\n<p><span style=\"color: #800000;\"><strong>Dialogue with Christ<\/strong><\/span><\/p>\n<p><em>This is the most important part of your prayer, prepare yourself to talk with much love with the One who loves you.<\/em><\/p>\n<p><span style=\"color: #800000;\"><strong>Purpose<\/strong><\/span><\/p>\n<p><em>Propose a personal one. The one that involves the most love in response to the Beloved... or, if you believe that this is what God is asking of you, live what is suggested below.<\/em><\/p>\n<p>Hoy dar\u00e9 testimonio de mi fe en Cristo siendo amable con todos los que trate.<\/p>\n<p><span style=\"color: #800000;\"><strong>Farewell<\/strong><\/span><\/p>\n<p>Christ, our King!<br \/>\nThy Kingdom come!<\/p>\n<p>Most prudent Virgin, Mary, Mother of the Church.<br \/>\nPray for us.<\/p>\n<p>In the name of the Father and of the Son and of the Holy Spirit.<br \/>\nAmen.<\/p>","protected":false},"excerpt":{"rendered":"<p> [&hellip;]<\/p>\n","protected":false},"author":58,"featured_media":33909,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"default","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"_daextrevop_audio_file_creation_date":"","_daextrevop_text_to_speech":"","_daextrevop_document_type":"","footnotes":""},"categories":[3164],"tags":[3162,3163,3067],"class_list":["post-103282","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-meditacion-del-dia","tag-evangelio","tag-meditacion","tag-reflexion"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>S\u00e1bado 20 de julio de 2024 - \u00abNo quebrar\u00e1 la ca\u00f1a doblada\u00bb - Regnum Christi Internacional<\/title>\n<meta name=\"description\" content=\"T\u00f3mame de las manos, Padre m\u00edo, y conduce mi alma en esta meditaci\u00f3n y durante toda mi vida. No quebrar\u00e1 la ca\u00f1a doblada.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/regnumchristi.org\/en\/sabado-20-de-julio-de-2024-no-quebrara-la-cana-doblada\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"S\u00e1bado 20 de julio de 2024 - \u00abNo quebrar\u00e1 la ca\u00f1a doblada\u00bb - Regnum Christi Internacional\" \/>\n<meta property=\"og:description\" content=\"T\u00f3mame de las manos, Padre m\u00edo, y conduce mi alma en esta meditaci\u00f3n y durante toda mi vida. No quebrar\u00e1 la ca\u00f1a doblada.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/regnumchristi.org\/en\/sabado-20-de-julio-de-2024-no-quebrara-la-cana-doblada\/\" \/>\n<meta property=\"og:site_name\" content=\"Regnum Christi Internacional\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/RegnumChristiEspana\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-20T01:00:39+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-21T22:59:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/regnumchristi.org\/wp-content\/uploads\/2022\/07\/Imagenes-Meditaciones-Diarias-22-de-julio.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"563\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Meditaciones Diarias\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Meditaciones Diarias\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/en\\\/sabado-20-de-julio-de-2024-no-quebrara-la-cana-doblada\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/en\\\/sabado-20-de-julio-de-2024-no-quebrara-la-cana-doblada\\\/\"},\"author\":{\"name\":\"Meditaciones Diarias\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#\\\/schema\\\/person\\\/a5ad8b3c4bd3cb3a0abe8a1474fe8f0a\"},\"headline\":\"S\u00e1bado 20 de julio de 2024 &#8211; \u00abNo quebrar\u00e1 la ca\u00f1a doblada\u00bb\",\"datePublished\":\"2024-07-20T01:00:39+00:00\",\"dateModified\":\"2024-07-21T22:59:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/en\\\/sabado-20-de-julio-de-2024-no-quebrara-la-cana-doblada\\\/\"},\"wordCount\":880,\"publisher\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/en\\\/sabado-20-de-julio-de-2024-no-quebrara-la-cana-doblada\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/regnumchristi.org\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/Imagenes-Meditaciones-Diarias-22-de-julio.jpg\",\"keywords\":[\"Evangelio\",\"meditaci\u00f3n\",\"Reflexi\u00f3n\"],\"articleSection\":[\"Meditaci\u00f3n del d\u00eda\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/en\\\/sabado-20-de-julio-de-2024-no-quebrara-la-cana-doblada\\\/\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/en\\\/sabado-20-de-julio-de-2024-no-quebrara-la-cana-doblada\\\/\",\"name\":\"S\u00e1bado 20 de julio de 2024 - \u00abNo quebrar\u00e1 la ca\u00f1a doblada\u00bb - Regnum Christi Internacional\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/en\\\/sabado-20-de-julio-de-2024-no-quebrara-la-cana-doblada\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/en\\\/sabado-20-de-julio-de-2024-no-quebrara-la-cana-doblada\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/regnumchristi.org\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/Imagenes-Meditaciones-Diarias-22-de-julio.jpg\",\"datePublished\":\"2024-07-20T01:00:39+00:00\",\"dateModified\":\"2024-07-21T22:59:42+00:00\",\"description\":\"T\u00f3mame de las manos, Padre m\u00edo, y conduce mi alma en esta meditaci\u00f3n y durante toda mi vida. No quebrar\u00e1 la ca\u00f1a doblada.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/en\\\/sabado-20-de-julio-de-2024-no-quebrara-la-cana-doblada\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/regnumchristi.org\\\/en\\\/sabado-20-de-julio-de-2024-no-quebrara-la-cana-doblada\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/en\\\/sabado-20-de-julio-de-2024-no-quebrara-la-cana-doblada\\\/#primaryimage\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/Imagenes-Meditaciones-Diarias-22-de-julio.jpg\",\"contentUrl\":\"https:\\\/\\\/regnumchristi.org\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/Imagenes-Meditaciones-Diarias-22-de-julio.jpg\",\"width\":900,\"height\":563,\"caption\":\"No quebrar\u00e1 la ca\u00f1a doblada\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/en\\\/sabado-20-de-julio-de-2024-no-quebrara-la-cana-doblada\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/regnumchristi.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"S\u00e1bado 20 de julio de 2024 &#8211; \u00abNo quebrar\u00e1 la ca\u00f1a doblada\u00bb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#website\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/\",\"name\":\"Regnum Christi Internacional\",\"description\":\"El Regnum Christi es una realidad de la Iglesia cat\u00f3lica cuya misi\u00f3n es hacer presente el Reino de Cristo\",\"publisher\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/regnumchristi.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#organization\",\"name\":\"Regnum Christi Internacional\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/regnumchristi.es\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Favicon-RC_ligh-cuadrado.png\",\"contentUrl\":\"https:\\\/\\\/regnumchristi.es\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Favicon-RC_ligh-cuadrado.png\",\"width\":1080,\"height\":1080,\"caption\":\"Regnum Christi Internacional\"},\"image\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/RegnumChristiEspana\\\/\",\"https:\\\/\\\/x.com\\\/rc_espana\",\"https:\\\/\\\/www.instagram.com\\\/rc_espana\\\/\",\"https:\\\/\\\/es.linkedin.com\\\/company\\\/regnumchristiespaa\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#\\\/schema\\\/person\\\/a5ad8b3c4bd3cb3a0abe8a1474fe8f0a\",\"name\":\"Meditaciones Diarias\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/en\\\/author\\\/meditacionesd\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"S\u00e1bado 20 de julio de 2024 - \u00abNo quebrar\u00e1 la ca\u00f1a doblada\u00bb - Regnum Christi Internacional","description":"T\u00f3mame de las manos, Padre m\u00edo, y conduce mi alma en esta meditaci\u00f3n y durante toda mi vida. No quebrar\u00e1 la ca\u00f1a doblada.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/regnumchristi.org\/en\/sabado-20-de-julio-de-2024-no-quebrara-la-cana-doblada\/","og_locale":"en_US","og_type":"article","og_title":"S\u00e1bado 20 de julio de 2024 - \u00abNo quebrar\u00e1 la ca\u00f1a doblada\u00bb - Regnum Christi Internacional","og_description":"T\u00f3mame de las manos, Padre m\u00edo, y conduce mi alma en esta meditaci\u00f3n y durante toda mi vida. No quebrar\u00e1 la ca\u00f1a doblada.","og_url":"https:\/\/regnumchristi.org\/en\/sabado-20-de-julio-de-2024-no-quebrara-la-cana-doblada\/","og_site_name":"Regnum Christi Internacional","article_publisher":"https:\/\/www.facebook.com\/RegnumChristiEspana\/","article_published_time":"2024-07-20T01:00:39+00:00","article_modified_time":"2024-07-21T22:59:42+00:00","og_image":[{"width":900,"height":563,"url":"https:\/\/regnumchristi.org\/wp-content\/uploads\/2022\/07\/Imagenes-Meditaciones-Diarias-22-de-julio.jpg","type":"image\/jpeg"}],"author":"Meditaciones Diarias","twitter_misc":{"Written by":"Meditaciones Diarias","Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/regnumchristi.org\/en\/sabado-20-de-julio-de-2024-no-quebrara-la-cana-doblada\/#article","isPartOf":{"@id":"https:\/\/regnumchristi.org\/en\/sabado-20-de-julio-de-2024-no-quebrara-la-cana-doblada\/"},"author":{"name":"Meditaciones Diarias","@id":"https:\/\/regnumchristi.org\/#\/schema\/person\/a5ad8b3c4bd3cb3a0abe8a1474fe8f0a"},"headline":"S\u00e1bado 20 de julio de 2024 &#8211; \u00abNo quebrar\u00e1 la ca\u00f1a doblada\u00bb","datePublished":"2024-07-20T01:00:39+00:00","dateModified":"2024-07-21T22:59:42+00:00","mainEntityOfPage":{"@id":"https:\/\/regnumchristi.org\/en\/sabado-20-de-julio-de-2024-no-quebrara-la-cana-doblada\/"},"wordCount":880,"publisher":{"@id":"https:\/\/regnumchristi.org\/#organization"},"image":{"@id":"https:\/\/regnumchristi.org\/en\/sabado-20-de-julio-de-2024-no-quebrara-la-cana-doblada\/#primaryimage"},"thumbnailUrl":"https:\/\/regnumchristi.org\/wp-content\/uploads\/2022\/07\/Imagenes-Meditaciones-Diarias-22-de-julio.jpg","keywords":["Evangelio","meditaci\u00f3n","Reflexi\u00f3n"],"articleSection":["Meditaci\u00f3n del d\u00eda"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/regnumchristi.org\/en\/sabado-20-de-julio-de-2024-no-quebrara-la-cana-doblada\/","url":"https:\/\/regnumchristi.org\/en\/sabado-20-de-julio-de-2024-no-quebrara-la-cana-doblada\/","name":"S\u00e1bado 20 de julio de 2024 - \u00abNo quebrar\u00e1 la ca\u00f1a doblada\u00bb - Regnum Christi Internacional","isPartOf":{"@id":"https:\/\/regnumchristi.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/regnumchristi.org\/en\/sabado-20-de-julio-de-2024-no-quebrara-la-cana-doblada\/#primaryimage"},"image":{"@id":"https:\/\/regnumchristi.org\/en\/sabado-20-de-julio-de-2024-no-quebrara-la-cana-doblada\/#primaryimage"},"thumbnailUrl":"https:\/\/regnumchristi.org\/wp-content\/uploads\/2022\/07\/Imagenes-Meditaciones-Diarias-22-de-julio.jpg","datePublished":"2024-07-20T01:00:39+00:00","dateModified":"2024-07-21T22:59:42+00:00","description":"T\u00f3mame de las manos, Padre m\u00edo, y conduce mi alma en esta meditaci\u00f3n y durante toda mi vida. No quebrar\u00e1 la ca\u00f1a doblada.","breadcrumb":{"@id":"https:\/\/regnumchristi.org\/en\/sabado-20-de-julio-de-2024-no-quebrara-la-cana-doblada\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/regnumchristi.org\/en\/sabado-20-de-julio-de-2024-no-quebrara-la-cana-doblada\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/regnumchristi.org\/en\/sabado-20-de-julio-de-2024-no-quebrara-la-cana-doblada\/#primaryimage","url":"https:\/\/regnumchristi.org\/wp-content\/uploads\/2022\/07\/Imagenes-Meditaciones-Diarias-22-de-julio.jpg","contentUrl":"https:\/\/regnumchristi.org\/wp-content\/uploads\/2022\/07\/Imagenes-Meditaciones-Diarias-22-de-julio.jpg","width":900,"height":563,"caption":"No quebrar\u00e1 la ca\u00f1a doblada"},{"@type":"BreadcrumbList","@id":"https:\/\/regnumchristi.org\/en\/sabado-20-de-julio-de-2024-no-quebrara-la-cana-doblada\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/regnumchristi.org\/es\/"},{"@type":"ListItem","position":2,"name":"S\u00e1bado 20 de julio de 2024 &#8211; \u00abNo quebrar\u00e1 la ca\u00f1a doblada\u00bb"}]},{"@type":"WebSite","@id":"https:\/\/regnumchristi.org\/#website","url":"https:\/\/regnumchristi.org\/","name":"Regnum Christi International","description":"Regnum Christi is a reality of the Catholic Church whose mission is to make present the Kingdom of Christ.","publisher":{"@id":"https:\/\/regnumchristi.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/regnumchristi.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/regnumchristi.org\/#organization","name":"Regnum Christi International","url":"https:\/\/regnumchristi.org\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/regnumchristi.org\/#\/schema\/logo\/image\/","url":"https:\/\/regnumchristi.es\/wp-content\/uploads\/2023\/03\/Favicon-RC_ligh-cuadrado.png","contentUrl":"https:\/\/regnumchristi.es\/wp-content\/uploads\/2023\/03\/Favicon-RC_ligh-cuadrado.png","width":1080,"height":1080,"caption":"Regnum Christi Internacional"},"image":{"@id":"https:\/\/regnumchristi.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/RegnumChristiEspana\/","https:\/\/x.com\/rc_espana","https:\/\/www.instagram.com\/rc_espana\/","https:\/\/es.linkedin.com\/company\/regnumchristiespaa"]},{"@type":"Person","@id":"https:\/\/regnumchristi.org\/#\/schema\/person\/a5ad8b3c4bd3cb3a0abe8a1474fe8f0a","name":"Daily Meditations","url":"https:\/\/regnumchristi.org\/en\/author\/meditacionesd\/"}]}},"_links":{"self":[{"href":"https:\/\/regnumchristi.org\/en\/wp-json\/wp\/v2\/posts\/103282","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/regnumchristi.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/regnumchristi.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/regnumchristi.org\/en\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/regnumchristi.org\/en\/wp-json\/wp\/v2\/comments?post=103282"}],"version-history":[{"count":1,"href":"https:\/\/regnumchristi.org\/en\/wp-json\/wp\/v2\/posts\/103282\/revisions"}],"predecessor-version":[{"id":103283,"href":"https:\/\/regnumchristi.org\/en\/wp-json\/wp\/v2\/posts\/103282\/revisions\/103283"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/regnumchristi.org\/en\/wp-json\/wp\/v2\/media\/33909"}],"wp:attachment":[{"href":"https:\/\/regnumchristi.org\/en\/wp-json\/wp\/v2\/media?parent=103282"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/regnumchristi.org\/en\/wp-json\/wp\/v2\/categories?post=103282"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/regnumchristi.org\/en\/wp-json\/wp\/v2\/tags?post=103282"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}