{"id":104155,"date":"2024-08-23T19:43:20","date_gmt":"2024-08-24T01:43:20","guid":{"rendered":"https:\/\/regnumchristi.org\/es\/?p=104155"},"modified":"2024-08-23T19:43:20","modified_gmt":"2024-08-24T01:43:20","slug":"sabado-24-de-agosto-de-2024-encuentro-de-jesus-con-natanael","status":"publish","type":"post","link":"https:\/\/regnumchristi.org\/en\/sabado-24-de-agosto-de-2024-encuentro-de-jesus-con-natanael\/","title":{"rendered":"Saturday, August 24, 2024 - \u00abJesus\u00bb Encounter with Nathanael\".\u00bb"},"content":{"rendered":"<p>In the name of the Father and of the Son and of the Holy Spirit.<br \/>\nAmen.<\/p>\n<p>Christ, our King.<br \/>\nThy Kingdom come!<\/p>\n<p><span style=\"color: #800000;\"><strong>Preparatory prayer<\/strong><\/span>\u00a0<em>(to put me in the presence of God)<\/em><\/p>\n<p>Jes\u00fas, eres el hijo de Dios, el rey de mi vida y mi mejor amigo, maestro y pastor. Me tomas de la mano y me conduces al Padre. Me insistes en la conversi\u00f3n, pues s\u00f3lo un coraz\u00f3n decidido puede a orar en la fe. Ay\u00fadame a orar disponiendo mi coraz\u00f3n para hacer la voluntad del Padre.<\/p>\n<p><span style=\"color: #800000;\"><strong>Gospel of the day<\/strong><\/span>\u00a0<em>(to guide your meditation)<\/em><br \/>\nFrom the Holy Gospel according to John 1:45-51<\/p>\n<p>En aquel tiempo, Felipe encuentra a Natanael y le dice: Aquel de quien escribieron Mois\u00e9s y la Ley y los Profetas lo hemos encontrado: a Jes\u00fas, hijo de Jos\u00e9, de Nazaret. Natanael le replic\u00f3: \u00bfDe Nazaret puede salir algo bueno? Felipe le contest\u00f3: Ven y ver\u00e1s. Vio Jes\u00fas que se acercaba Natanael y dijo de \u00e9l: Ah\u00ed ten\u00e9is a un israelita de verdad, en quien no hay enga\u00f1o. Natanael le contesta: \u00bfDe qu\u00e9 me conoces? Jes\u00fas le responde: Antes de que Felipe te llamara, cuando estabas debajo de la higuera, te vi. Natanael respondi\u00f3: Rab\u00ed, t\u00fa eres el Hijo de Dios, t\u00fa eres el Rey de Israel. Jes\u00fas le contest\u00f3: \u00bfPor haberte dicho que te vi debajo de la higuera, crees? Has de ver cosas mayores. Y le a\u00f1adi\u00f3: Yo os aseguro: ver\u00e9is el cielo abierto y a los \u00e1ngeles de Dios subir y bajar sobre el Hijo del Hombre.<\/p>\n<p><em>Word of the Lord<\/em><\/p>\n<p><span style=\"color: #800000;\"><strong>Meditate on what God tells you in the Gospel<\/strong><\/span><\/p>\n<p>\u00abVen y lo ver\u00e1s\u00bb. Cada uno de nosotros ha llegado a conocer a Cristo gracias a otra persona. Un sacerdote nos bautiz\u00f3 y nos da los dem\u00e1s sacramentos; en casa o en la parroquia nos ense\u00f1aron el catecismo; seguramente alg\u00fan amigo o amiga en concreto nos ha atra\u00eddo m\u00e1s hacia la fe&#8230; En cada cristiano, a lo largo de los siglos, se repite el evento de Felipe, Natanael y Jes\u00fas.<\/p>\n<p>Gracias, Se\u00f1or, por todos aquellos que me han llevado a ti. \u00bfQu\u00e9 ser\u00eda de m\u00ed sin la ayuda de mis pap\u00e1s, de los sacerdotes, de mis amigos y hermanos en la fe? Gracias, Jes\u00fas, porque entraste en mi vida gracias a las personas que amo y s\u00e9 que me aman; gracias por ser ese tesoro que he recibido de otros. Gracias, por la oportunidad de venir y verte, de conocerte m\u00e1s de cerca y de descubrir tu amor. Gracias porque, siendo el Hijo de Dios, has querido vivir entre nosotros.<\/p>\n<p>Quien ha conocido a Cristo, ha recibido el mayor don de esta vida. Pero con el don viene una responsabilidad. \u00a1Cu\u00e1nta gente no ha escuchado hablar de Cristo! \u00a1Cu\u00e1ntos saben de \u00c9l, pero no lo conocen en realidad, y por eso no lo aman! Y cu\u00e1ntos de ellos viven a nuestro lado, trabajan junto a nosotros, pasan por nuestras mismas calles. No podemos guardarnos el mayor tesoro de la humanidad para nosotros mismos. Tenemos que compartirlo, transmitir la gran noticia: \u00a1hemos encontrado a Aqu\u00e9l que tanto anhela el coraz\u00f3n humano!<\/p>\n<p>Jesucristo, T\u00fa tienes el gran deseo de que todos te conozcan, para que encuentren el verdadero Amor del Padre. Pero has querido hacerte necesitado de mi boca para hablar de ti. Cuenta conmigo. Aqu\u00ed mismo donde vivo, en mi puesto de trabajo, entre mis amigos, s\u00e9 que algunos no te conocen. Dame ese fuego misionero, la gracia de transmitir el encuentro contigo.<\/p>\n<p><em>\u00abDios nos ha escogido y bendecido con un prop\u00f3sito: \u201cPara que fu\u00e9semos santos e irreprochables en su presencia\u201d. Nos eligi\u00f3 a cada uno de nosotros para ser testigos de su verdad y su justicia en este mundo. Cre\u00f3 el mundo como un hermoso jard\u00edn y nos pidi\u00f3 que cuid\u00e1ramos de \u00e9l. Pero, con el pecado, el hombre desfigur\u00f3 aquella belleza natural; destruy\u00f3 tambi\u00e9n la unidad y la belleza de nuestra familia humana, dando lugar a estructuras sociales que perpet\u00faan la pobreza, la falta de educaci\u00f3n y la corrupci\u00f3n\u00bb.<\/em><br \/>\n(Homil\u00eda de S.S. Francisco, 18 de enero de 2015).<\/p>\n<p><span style=\"color: #800000;\"><strong>Dialogue with Christ<\/strong><\/span><\/p>\n<p><em>This is the most important part of your prayer, prepare yourself to talk with much love with the One who loves you.<\/em><\/p>\n<p><span style=\"color: #800000;\"><strong>Purpose<\/strong><\/span><\/p>\n<p><em>Propose a personal one. The one that involves the most love in response to the Beloved... or, if you believe that this is what God is asking of you, live what is suggested below.<\/em><\/p>\n<p>Restar importancia a mis puntos de vista, para estar m\u00e1s abierto a la opini\u00f3n de los dem\u00e1s.<\/p>\n<p><span style=\"color: #800000;\"><strong>Farewell<\/strong><\/span><\/p>\n<p>Christ, our King!<br \/>\nThy Kingdom come!<\/p>\n<p>Most prudent Virgin, Mary, Mother of the Church.<br \/>\nPray for us.<\/p>\n<p>In the name of the Father and of the Son and of the Holy Spirit.<br \/>\nAmen.<\/p>","protected":false},"excerpt":{"rendered":"<p> [&hellip;]<\/p>\n","protected":false},"author":58,"featured_media":34146,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"default","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"_daextrevop_audio_file_creation_date":"","_daextrevop_text_to_speech":"","_daextrevop_document_type":"","footnotes":""},"categories":[3164],"tags":[],"class_list":["post-104155","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-meditacion-del-dia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>S\u00e1bado 24 de agosto de 2024 - \u00abEncuentro de Jes\u00fas con Natanael\u00bb - Regnum Christi Internacional<\/title>\n<meta name=\"description\" content=\"Jes\u00fas, eres el hijo de Dios, mi mejor amigo, maestro y pastor. Me tomas de la mano y me conduces al Padre. Encuentro de Jes\u00fas con Natanael.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/regnumchristi.org\/en\/sabado-24-de-agosto-de-2024-encuentro-de-jesus-con-natanael\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"S\u00e1bado 24 de agosto de 2024 - \u00abEncuentro de Jes\u00fas con Natanael\u00bb - Regnum Christi Internacional\" \/>\n<meta property=\"og:description\" content=\"Jes\u00fas, eres el hijo de Dios, mi mejor amigo, maestro y pastor. Me tomas de la mano y me conduces al Padre. Encuentro de Jes\u00fas con Natanael.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/regnumchristi.org\/en\/sabado-24-de-agosto-de-2024-encuentro-de-jesus-con-natanael\/\" \/>\n<meta property=\"og:site_name\" content=\"Regnum Christi Internacional\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/RegnumChristiEspana\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-08-24T01:43:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/regnumchristi.org\/wp-content\/uploads\/2022\/08\/Imagenes-Meditaciones-Diarias-24-de-agosto.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"563\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Meditaciones Diarias\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Meditaciones Diarias\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/sabado-24-de-agosto-de-2024-encuentro-de-jesus-con-natanael\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/sabado-24-de-agosto-de-2024-encuentro-de-jesus-con-natanael\\\/\"},\"author\":{\"name\":\"Meditaciones Diarias\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#\\\/schema\\\/person\\\/a5ad8b3c4bd3cb3a0abe8a1474fe8f0a\"},\"headline\":\"S\u00e1bado 24 de agosto de 2024 &#8211; \u00abEncuentro de Jes\u00fas con Natanael\u00bb\",\"datePublished\":\"2024-08-24T01:43:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/sabado-24-de-agosto-de-2024-encuentro-de-jesus-con-natanael\\\/\"},\"wordCount\":842,\"publisher\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/sabado-24-de-agosto-de-2024-encuentro-de-jesus-con-natanael\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/regnumchristi.org\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/Imagenes-Meditaciones-Diarias-24-de-agosto.jpg\",\"articleSection\":[\"Meditaci\u00f3n del d\u00eda\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/sabado-24-de-agosto-de-2024-encuentro-de-jesus-con-natanael\\\/\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/sabado-24-de-agosto-de-2024-encuentro-de-jesus-con-natanael\\\/\",\"name\":\"S\u00e1bado 24 de agosto de 2024 - \u00abEncuentro de Jes\u00fas con Natanael\u00bb - Regnum Christi Internacional\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/sabado-24-de-agosto-de-2024-encuentro-de-jesus-con-natanael\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/sabado-24-de-agosto-de-2024-encuentro-de-jesus-con-natanael\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/regnumchristi.org\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/Imagenes-Meditaciones-Diarias-24-de-agosto.jpg\",\"datePublished\":\"2024-08-24T01:43:20+00:00\",\"description\":\"Jes\u00fas, eres el hijo de Dios, mi mejor amigo, maestro y pastor. Me tomas de la mano y me conduces al Padre. Encuentro de Jes\u00fas con Natanael.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/sabado-24-de-agosto-de-2024-encuentro-de-jesus-con-natanael\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/regnumchristi.org\\\/sabado-24-de-agosto-de-2024-encuentro-de-jesus-con-natanael\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/sabado-24-de-agosto-de-2024-encuentro-de-jesus-con-natanael\\\/#primaryimage\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/Imagenes-Meditaciones-Diarias-24-de-agosto.jpg\",\"contentUrl\":\"https:\\\/\\\/regnumchristi.org\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/Imagenes-Meditaciones-Diarias-24-de-agosto.jpg\",\"width\":900,\"height\":563,\"caption\":\"Encuentro de Jes\u00fas con Natanael\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/sabado-24-de-agosto-de-2024-encuentro-de-jesus-con-natanael\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/regnumchristi.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"S\u00e1bado 24 de agosto de 2024 &#8211; \u00abEncuentro de Jes\u00fas con Natanael\u00bb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#website\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/\",\"name\":\"Regnum Christi Internacional\",\"description\":\"El Regnum Christi es una realidad de la Iglesia cat\u00f3lica cuya misi\u00f3n es hacer presente el Reino de Cristo\",\"publisher\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/regnumchristi.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#organization\",\"name\":\"Regnum Christi Internacional\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/regnumchristi.es\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Favicon-RC_ligh-cuadrado.png\",\"contentUrl\":\"https:\\\/\\\/regnumchristi.es\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Favicon-RC_ligh-cuadrado.png\",\"width\":1080,\"height\":1080,\"caption\":\"Regnum Christi Internacional\"},\"image\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/RegnumChristiEspana\\\/\",\"https:\\\/\\\/x.com\\\/rc_espana\",\"https:\\\/\\\/www.instagram.com\\\/rc_espana\\\/\",\"https:\\\/\\\/es.linkedin.com\\\/company\\\/regnumchristiespaa\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#\\\/schema\\\/person\\\/a5ad8b3c4bd3cb3a0abe8a1474fe8f0a\",\"name\":\"Meditaciones Diarias\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/en\\\/author\\\/meditacionesd\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"S\u00e1bado 24 de agosto de 2024 - \u00abEncuentro de Jes\u00fas con Natanael\u00bb - Regnum Christi Internacional","description":"Jes\u00fas, eres el hijo de Dios, mi mejor amigo, maestro y pastor. Me tomas de la mano y me conduces al Padre. Encuentro de Jes\u00fas con Natanael.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/regnumchristi.org\/en\/sabado-24-de-agosto-de-2024-encuentro-de-jesus-con-natanael\/","og_locale":"en_US","og_type":"article","og_title":"S\u00e1bado 24 de agosto de 2024 - \u00abEncuentro de Jes\u00fas con Natanael\u00bb - Regnum Christi Internacional","og_description":"Jes\u00fas, eres el hijo de Dios, mi mejor amigo, maestro y pastor. Me tomas de la mano y me conduces al Padre. Encuentro de Jes\u00fas con Natanael.","og_url":"https:\/\/regnumchristi.org\/en\/sabado-24-de-agosto-de-2024-encuentro-de-jesus-con-natanael\/","og_site_name":"Regnum Christi Internacional","article_publisher":"https:\/\/www.facebook.com\/RegnumChristiEspana\/","article_published_time":"2024-08-24T01:43:20+00:00","og_image":[{"width":900,"height":563,"url":"https:\/\/regnumchristi.org\/wp-content\/uploads\/2022\/08\/Imagenes-Meditaciones-Diarias-24-de-agosto.jpg","type":"image\/jpeg"}],"author":"Meditaciones Diarias","twitter_misc":{"Written by":"Meditaciones Diarias","Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/regnumchristi.org\/sabado-24-de-agosto-de-2024-encuentro-de-jesus-con-natanael\/#article","isPartOf":{"@id":"https:\/\/regnumchristi.org\/sabado-24-de-agosto-de-2024-encuentro-de-jesus-con-natanael\/"},"author":{"name":"Meditaciones Diarias","@id":"https:\/\/regnumchristi.org\/#\/schema\/person\/a5ad8b3c4bd3cb3a0abe8a1474fe8f0a"},"headline":"S\u00e1bado 24 de agosto de 2024 &#8211; \u00abEncuentro de Jes\u00fas con Natanael\u00bb","datePublished":"2024-08-24T01:43:20+00:00","mainEntityOfPage":{"@id":"https:\/\/regnumchristi.org\/sabado-24-de-agosto-de-2024-encuentro-de-jesus-con-natanael\/"},"wordCount":842,"publisher":{"@id":"https:\/\/regnumchristi.org\/#organization"},"image":{"@id":"https:\/\/regnumchristi.org\/sabado-24-de-agosto-de-2024-encuentro-de-jesus-con-natanael\/#primaryimage"},"thumbnailUrl":"https:\/\/regnumchristi.org\/wp-content\/uploads\/2022\/08\/Imagenes-Meditaciones-Diarias-24-de-agosto.jpg","articleSection":["Meditaci\u00f3n del d\u00eda"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/regnumchristi.org\/sabado-24-de-agosto-de-2024-encuentro-de-jesus-con-natanael\/","url":"https:\/\/regnumchristi.org\/sabado-24-de-agosto-de-2024-encuentro-de-jesus-con-natanael\/","name":"S\u00e1bado 24 de agosto de 2024 - \u00abEncuentro de Jes\u00fas con Natanael\u00bb - Regnum Christi Internacional","isPartOf":{"@id":"https:\/\/regnumchristi.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/regnumchristi.org\/sabado-24-de-agosto-de-2024-encuentro-de-jesus-con-natanael\/#primaryimage"},"image":{"@id":"https:\/\/regnumchristi.org\/sabado-24-de-agosto-de-2024-encuentro-de-jesus-con-natanael\/#primaryimage"},"thumbnailUrl":"https:\/\/regnumchristi.org\/wp-content\/uploads\/2022\/08\/Imagenes-Meditaciones-Diarias-24-de-agosto.jpg","datePublished":"2024-08-24T01:43:20+00:00","description":"Jes\u00fas, eres el hijo de Dios, mi mejor amigo, maestro y pastor. Me tomas de la mano y me conduces al Padre. Encuentro de Jes\u00fas con Natanael.","breadcrumb":{"@id":"https:\/\/regnumchristi.org\/sabado-24-de-agosto-de-2024-encuentro-de-jesus-con-natanael\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/regnumchristi.org\/sabado-24-de-agosto-de-2024-encuentro-de-jesus-con-natanael\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/regnumchristi.org\/sabado-24-de-agosto-de-2024-encuentro-de-jesus-con-natanael\/#primaryimage","url":"https:\/\/regnumchristi.org\/wp-content\/uploads\/2022\/08\/Imagenes-Meditaciones-Diarias-24-de-agosto.jpg","contentUrl":"https:\/\/regnumchristi.org\/wp-content\/uploads\/2022\/08\/Imagenes-Meditaciones-Diarias-24-de-agosto.jpg","width":900,"height":563,"caption":"Encuentro de Jes\u00fas con Natanael"},{"@type":"BreadcrumbList","@id":"https:\/\/regnumchristi.org\/sabado-24-de-agosto-de-2024-encuentro-de-jesus-con-natanael\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/regnumchristi.org\/es\/"},{"@type":"ListItem","position":2,"name":"S\u00e1bado 24 de agosto de 2024 &#8211; \u00abEncuentro de Jes\u00fas con Natanael\u00bb"}]},{"@type":"WebSite","@id":"https:\/\/regnumchristi.org\/#website","url":"https:\/\/regnumchristi.org\/","name":"Regnum Christi International","description":"Regnum Christi is a reality of the Catholic Church whose mission is to make present the Kingdom of Christ.","publisher":{"@id":"https:\/\/regnumchristi.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/regnumchristi.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/regnumchristi.org\/#organization","name":"Regnum Christi International","url":"https:\/\/regnumchristi.org\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/regnumchristi.org\/#\/schema\/logo\/image\/","url":"https:\/\/regnumchristi.es\/wp-content\/uploads\/2023\/03\/Favicon-RC_ligh-cuadrado.png","contentUrl":"https:\/\/regnumchristi.es\/wp-content\/uploads\/2023\/03\/Favicon-RC_ligh-cuadrado.png","width":1080,"height":1080,"caption":"Regnum Christi Internacional"},"image":{"@id":"https:\/\/regnumchristi.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/RegnumChristiEspana\/","https:\/\/x.com\/rc_espana","https:\/\/www.instagram.com\/rc_espana\/","https:\/\/es.linkedin.com\/company\/regnumchristiespaa"]},{"@type":"Person","@id":"https:\/\/regnumchristi.org\/#\/schema\/person\/a5ad8b3c4bd3cb3a0abe8a1474fe8f0a","name":"Daily Meditations","url":"https:\/\/regnumchristi.org\/en\/author\/meditacionesd\/"}]}},"_links":{"self":[{"href":"https:\/\/regnumchristi.org\/en\/wp-json\/wp\/v2\/posts\/104155","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/regnumchristi.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/regnumchristi.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/regnumchristi.org\/en\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/regnumchristi.org\/en\/wp-json\/wp\/v2\/comments?post=104155"}],"version-history":[{"count":1,"href":"https:\/\/regnumchristi.org\/en\/wp-json\/wp\/v2\/posts\/104155\/revisions"}],"predecessor-version":[{"id":104156,"href":"https:\/\/regnumchristi.org\/en\/wp-json\/wp\/v2\/posts\/104155\/revisions\/104156"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/regnumchristi.org\/en\/wp-json\/wp\/v2\/media\/34146"}],"wp:attachment":[{"href":"https:\/\/regnumchristi.org\/en\/wp-json\/wp\/v2\/media?parent=104155"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/regnumchristi.org\/en\/wp-json\/wp\/v2\/categories?post=104155"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/regnumchristi.org\/en\/wp-json\/wp\/v2\/tags?post=104155"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}