{"id":111350,"date":"2025-07-02T20:03:46","date_gmt":"2025-07-03T02:03:46","guid":{"rendered":"https:\/\/regnumchristi.org\/es\/?p=111350"},"modified":"2025-07-03T11:53:41","modified_gmt":"2025-07-03T17:53:41","slug":"promesa-que-el-sostiene-consagradas-celebran-su-25-aniversario","status":"publish","type":"post","link":"https:\/\/regnumchristi.org\/en\/promesa-que-el-sostiene-consagradas-celebran-su-25-aniversario\/","title":{"rendered":"A promise he keeps: consecrated women celebrate their 25th anniversary"},"content":{"rendered":"<p><em><span class=\"TextRun SCXW93606041 BCX8\" lang=\"ES-US\" xml:lang=\"ES-US\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW93606041 BCX8\">Cinco mujeres, cinco historias entrelazadas por una misma vocaci\u00f3n y un mismo carisma, se detienen para mirar lo que han vivido y hacia d\u00f3nde caminan. \u00bfC\u00f3mo se sostiene una entrega total a Dios cuando el camino incluye desaf\u00edos personales, pruebas institucionales y llamados a renovarse continuamente? \u00bfQu\u00e9 significa hoy vivir una vocaci\u00f3n consagrada en medio de una sociedad en constante cambio? Sus voces, profundas y serenas, nos abren la puerta a una experiencia de fidelidad discreta, de esperanza luminosa y de una vida consagrada que se reinventa sin perder su ra\u00edz.<\/span><\/span><\/em><\/p>\n<p><strong><span class=\"TextRun MacChromeBold SCXW251976479 BCX8\" lang=\"ES-US\" xml:lang=\"ES-US\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW251976479 BCX8\">Una celebraci\u00f3n en el coraz\u00f3n de la Iglesia<\/span><\/span><\/strong><\/p>\n<p><span class=\"TextRun SCXW26334413 BCX8\" lang=\"ES-US\" xml:lang=\"ES-US\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW26334413 BCX8\">In the <\/span><span class=\"NormalTextRun SCXW26334413 BCX8\">year<\/span><span class=\"NormalTextRun SCXW26334413 BCX8\"> del Jubileo de la Esperanza y con el tel\u00f3n de fondo de una Roma siempre viva, luminosa y espiritual, un grupo de <\/span><\/span><a class=\"Hyperlink SCXW26334413 BCX8\" href=\"https:\/\/consecratedwomen.org\/\" target=\"_blank\" rel=\"noreferrer noopener\"><span class=\"TextRun Underlined SCXW26334413 BCX8\" lang=\"ES-US\" xml:lang=\"ES-US\" data-contrast=\"none\"><span class=\"NormalTextRun SCXW26334413 BCX8\" data-ccp-charstyle=\"Hyperlink\">consecrated members of Regnum Christi<\/span><\/span><\/a><span class=\"TextRun SCXW26334413 BCX8\" lang=\"ES-US\" xml:lang=\"ES-US\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW26334413 BCX8\"> se dio cita para conmemorar <\/span><span class=\"NormalTextRun SCXW26334413 BCX8\">este importante acontecimiento<\/span><span class=\"NormalTextRun SCXW26334413 BCX8\">: 25 a\u00f1os de vida consagrada. Fue una peregrinaci\u00f3n para dar gracias por un camino recorrido con fe, por una historia vivida entre gozos y pruebas, y por la fidelidad inquebrantable de un Dios que, como coinciden en decir, <\/span><span class=\"NormalTextRun SCXW26334413 BCX8\">\u00ab<\/span><span class=\"NormalTextRun SCXW26334413 BCX8\">no se deja ganar en generosidad<\/span><span class=\"NormalTextRun SCXW26334413 BCX8\">\u00bb<\/span><span class=\"NormalTextRun SCXW26334413 BCX8\">.<\/span><\/span><\/p>\n<p><span class=\"NormalTextRun SCXW126672961 BCX8\">Cada una de ellas lleg\u00f3 a esta celebraci\u00f3n con su propia historia, marcada por decisiones tomadas en <\/span><span class=\"NormalTextRun SCXW126672961 BCX8\">su primera <\/span><span class=\"NormalTextRun SCXW126672961 BCX8\">juventud, por <\/span><span class=\"NormalTextRun SCXW126672961 BCX8\">un camino <\/span><span class=\"NormalTextRun SCXW126672961 BCX8\">que p<\/span><span class=\"NormalTextRun SCXW126672961 BCX8\">one a p<\/span><span class=\"NormalTextRun SCXW126672961 BCX8\">rueba la autenticidad de los <\/span><span class=\"NormalTextRun SCXW126672961 BCX8\">compromisos, y por la certeza \u2014<\/span> <span class=\"NormalTextRun SCXW126672961 BCX8\">renovada cada d\u00eda<\/span> <span class=\"NormalTextRun SCXW126672961 BCX8\">\u2014 de que decirle <\/span><span class=\"NormalTextRun SCXW126672961 BCX8\">\u00ab<\/span><span class=\"NormalTextRun SCXW126672961 BCX8\">yes<\/span><span class=\"NormalTextRun SCXW126672961 BCX8\">\u00bb<\/span><span class=\"NormalTextRun SCXW126672961 BCX8\"> a Dios es una promesa que \u00c9l mismo se encarga de sostener.<\/span><\/p>\n<p><span class=\"NormalTextRun CommentStart CommentHighlightPipeClicked CommentHighlightClicked CommentImportant SCXW103859773 BCX8\">Andrea Mel\u00e9ndez Gonz\u00e1lez, una de las consagradas que celebr\u00f3 este aniversario, describe c\u00f3mo un v<\/span><span class=\"NormalTextRun CommentHighlightClicked CommentImportant SCXW103859773 BCX8\">\u00ed<\/span><span class=\"NormalTextRun CommentHighlightClicked CommentImportant SCXW103859773 BCX8\">deo que grab\u00f3 su pap\u00e1 en la primera visita que le hizo cuando ella estaba iniciando su formaci\u00f3n, reaviv\u00f3 la memoria de su llamado. \u00ab<span data-olk-copy-source=\"MessageBody\">En una parte del video, que tom\u00f3 un tono m\u00e1s serio, toqu\u00e9 el punto de hacerles comprender lo que era seguir un llamado. Les compart\u00eda esto: \u201cvivo una vida sencilla, pero todo con una intenci\u00f3n: amar a Dios en cada cosa que hago\u201d. Me vi en esas im\u00e1genes siguiendo mi llamado, eso que s\u00f3lo uno identifica en el interior, y que ha estado ah\u00ed latente a trav\u00e9s de toda mi historia<\/span><\/span><span class=\"NormalTextRun CommentHighlightClicked CommentImportant SCXW103859773 BCX8\">\u00bb<\/span><span class=\"NormalTextRun CommentHighlightClicked CommentImportant SCXW103859773 BCX8\">.<\/span><\/p>\n<figure id=\"attachment_111374\" aria-describedby=\"caption-attachment-111374\" style=\"width: 898px\" class=\"wp-caption aligncenter\"><img fetchpriority=\"high\" decoding=\"async\" class=\"wp-image-111374 size-full\" src=\"https:\/\/regnumchristi.org\/wp-content\/uploads\/2025\/07\/Andrea.webp\" alt=\"Promise He Keeps: Consecrated women celebrate their 25th Anniversary\" width=\"898\" height=\"596\" srcset=\"https:\/\/regnumchristi.org\/wp-content\/uploads\/2025\/07\/Andrea.webp 898w, https:\/\/regnumchristi.org\/wp-content\/uploads\/2025\/07\/Andrea-300x199.webp 300w, https:\/\/regnumchristi.org\/wp-content\/uploads\/2025\/07\/Andrea-768x510.webp 768w, https:\/\/regnumchristi.org\/wp-content\/uploads\/2025\/07\/Andrea-18x12.webp 18w\" sizes=\"(max-width: 898px) 100vw, 898px\" \/><figcaption id=\"caption-attachment-111374\" class=\"wp-caption-text\">Andrea Mel\u00e9ndez Gonz\u00e1lez<\/figcaption><\/figure>\n<p><span class=\"TextRun SCXW89456478 BCX8\" lang=\"ES-US\" xml:lang=\"ES-US\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW89456478 BCX8\">Ese tipo de recuerdos reafirman convicciones. Andrea afirma que<\/span><span class=\"NormalTextRun SCXW89456478 BCX8\">,<\/span><span class=\"NormalTextRun SCXW89456478 BCX8\"> a su yo de hace 25 a\u00f1os<\/span><span class=\"NormalTextRun SCXW89456478 BCX8\">,<\/span><span class=\"NormalTextRun SCXW89456478 BCX8\"> no le cambiar\u00eda nada: <\/span><span class=\"NormalTextRun SCXW89456478 BCX8\">\u00ab<span data-olk-copy-source=\"MessageBody\">A mi yo de hace 25 a\u00f1os toda mi admiraci\u00f3n porque, sin saber lo que vendr\u00eda, inici\u00f3 feliz dispuesta a seguir a Dios. As\u00ed que le agradezco su fe, su ilusi\u00f3n, su valent\u00eda. Como bien me dijeron mis pap\u00e1s: \u201cve y sigue el llamado en tu coraz\u00f3n, lo \u00fanico que puede pasar es que Dios te haga muy feliz\u201d<\/span><\/span><span class=\"NormalTextRun CommentHighlightRest SCXW89456478 BCX8\">\u00bb<\/span><span class=\"NormalTextRun CommentHighlightRest SCXW89456478 BCX8\">.<\/span><\/span><\/p>\n<p><strong><span class=\"EOP CommentHighlightRest SCXW89456478 BCX8\" data-ccp-props=\"{}\"><span class=\"NormalTextRun SCXW136129470 BCX8\">M<\/span><span class=\"NormalTextRun SCXW136129470 BCX8\">adurez y misi\u00f3n en tiempos de renovaci\u00f3n<\/span><\/span><\/strong><\/p>\n<p><span class=\"EOP CommentHighlightRest SCXW89456478 BCX8\" data-ccp-props=\"{}\"> <span class=\"NormalTextRun SCXW205646179 BCX8\">Las consagradas del <\/span><span class=\"NormalTextRun SpellingErrorV2Themed SCXW205646179 BCX8\">Regnum<\/span><span class=\"NormalTextRun SCXW205646179 BCX8\"> Christi no celebran estos 25 a\u00f1os en un contexto idealizado. Ellas mismas han vivido \u2014<\/span> <span class=\"NormalTextRun SCXW205646179 BCX8\">y acompa\u00f1ado desde dentro<\/span> <span class=\"NormalTextRun SCXW205646179 BCX8\">\u2014 momentos de crisis, revisi\u00f3n y renovaci\u00f3n profunda dentro de su<\/span><span class=\"NormalTextRun SCXW205646179 BCX8\">s comunidades<\/span><span class=\"NormalTextRun SCXW205646179 BCX8\">. Desde las primeras etapas de formaci\u00f3n, pasando por momentos hist\u00f3ricos de purificaci\u00f3n, hasta el impulso actual por una misi\u00f3n m\u00e1s clara y encarnada, sus historias personales se entrelazan con una historia institucional marcada por el deseo de verdad, de sanaci\u00f3n y de fidelidad al Evangelio.<\/span><\/span><\/p>\n<p><span class=\"NormalTextRun SCXW220725815 BCX8\">\u00ab<span data-olk-copy-source=\"MessageBody\">A las consagradas de hoy las veo m\u00e1s conscientes, m\u00e1s humanas y echando m\u00e1s ra\u00edces en Dios. En mi camino me han acompa\u00f1ado grandes hermanas, que pensando en ellas veo mujeres de bien, mujeres de oraci\u00f3n, mujeres que han buscado hacer verdad y han vivido dando amor. Las veo y me alegro de poder gozar de su amistad, de su consejo, de compartir los retos que seguimos teniendo en crear comunidad, en vivir la obediencia y la humildad<\/span><\/span><span class=\"NormalTextRun CommentHighlightRest SCXW220725815 BCX8\">\u00bb, comenta Andrea<\/span><span class=\"NormalTextRun CommentHighlightPipeRest SCXW220725815 BCX8\">.<\/span><\/p>\n<figure id=\"attachment_111372\" aria-describedby=\"caption-attachment-111372\" style=\"width: 900px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" class=\"wp-image-111372 size-full\" src=\"https:\/\/regnumchristi.org\/wp-content\/uploads\/2025\/07\/Lula.webp\" alt=\"Promise He Keeps: Consecrated women celebrate their 25th Anniversary\" width=\"900\" height=\"600\" srcset=\"https:\/\/regnumchristi.org\/wp-content\/uploads\/2025\/07\/Lula.webp 900w, https:\/\/regnumchristi.org\/wp-content\/uploads\/2025\/07\/Lula-300x200.webp 300w, https:\/\/regnumchristi.org\/wp-content\/uploads\/2025\/07\/Lula-768x512.webp 768w, https:\/\/regnumchristi.org\/wp-content\/uploads\/2025\/07\/Lula-18x12.webp 18w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><figcaption id=\"caption-attachment-111372\" class=\"wp-caption-text\">Mar\u00eda de Lourdes Zorrilla Garza<\/figcaption><\/figure>\n<p><span class=\"NormalTextRun SCXW179805498 BCX8\">Mar\u00eda de Lourdes Zorrilla Garza comparte una mirada semejante. Su lectura de este momento hist\u00f3rico es directa y esperanzadora: <\/span><span class=\"NormalTextRun SCXW179805498 BCX8\">\u00ab<\/span><span class=\"NormalTextRun SCXW179805498 BCX8\">Hemos vivido momentos de prueba, de cuestionamientos profundos, de purificaci\u00f3n\u2026 pero tambi\u00e9n de gracia. No somos las mismas de hace unas d\u00e9cadas. Verlas me llena de orgullo y de profunda gratitud a Dios por sostenernos<\/span><span class=\"NormalTextRun SCXW179805498 BCX8\">\u00bb<\/span><span class=\"NormalTextRun SCXW179805498 BCX8\">. En sus palabras resuena una profunda transformaci\u00f3n interior, donde ya no se trata solo de <\/span><span class=\"NormalTextRun SCXW179805498 BCX8\">\u00ab<\/span><span class=\"NormalTextRun SCXW179805498 BCX8\">sostener estructuras<\/span><span class=\"NormalTextRun SCXW179805498 BCX8\">\u00bb<\/span><span class=\"NormalTextRun SCXW179805498 BCX8\">, sino de dejarse renovar por el Esp\u00edritu Santo, para dar un testimonio m\u00e1s audaz, m\u00e1s evang\u00e9lico, m\u00e1s humano.<\/span><\/p>\n<p><span class=\"TextRun SCXW236165428 BCX8\" lang=\"ES-US\" xml:lang=\"ES-US\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW236165428 BCX8\">Es una etapa de transici\u00f3n, pero tambi\u00e9n de testimonio. Mujeres que han atravesado desiertos con fe, que conocen el cansancio, pero tambi\u00e9n la esperanza. <\/span><span class=\"NormalTextRun SCXW236165428 BCX8\">\u00ab<\/span><span class=\"NormalTextRun SCXW236165428 BCX8\">Este es un momento de gracia<\/span><span class=\"NormalTextRun SCXW236165428 BCX8\">\u00bb<\/span><span class=\"NormalTextRun SCXW236165428 BCX8\">, concluye Lourdes, <\/span><span class=\"NormalTextRun SCXW236165428 BCX8\">\u00ab<\/span><span class=\"NormalTextRun SCXW236165428 BCX8\">si seguimos dej\u00e1ndonos modelar por la Palabra y por la realidad, el testimonio de las consagradas seguir\u00e1 siendo un signo luminoso del Reino<\/span><span class=\"NormalTextRun SCXW236165428 BCX8\">\u00bb<\/span><span class=\"NormalTextRun SCXW236165428 BCX8\">.<\/span><\/span><\/p>\n<p><strong><span class=\"NormalTextRun SCXW236858974 BCX8\">The <\/span><span class=\"NormalTextRun SpellingErrorV2Themed SCXW236858974 BCX8\">synodality<\/span><span class=\"NormalTextRun SCXW236858974 BCX8\">: un nuevo modo de caminar como familia espiritual<\/span><\/strong><\/p>\n<p><span class=\"NormalTextRun SCXW227799541 BCX8\">Uno de los grandes aprendizajes de este tiempo ha sido el ejercicio de la <\/span><span class=\"NormalTextRun SpellingErrorV2Themed SCXW227799541 BCX8\">synodality<\/span><span class=\"NormalTextRun SCXW227799541 BCX8\">, un t\u00e9rmino que para algun<\/span><span class=\"NormalTextRun SCXW227799541 BCX8\">i<\/span><span class=\"NormalTextRun SCXW227799541 BCX8\">s puede sonar abstracto, pero que <\/span><span class=\"NormalTextRun SCXW227799541 BCX8\">in the <\/span><span class=\"NormalTextRun SCXW227799541 BCX8\">vida cotidiana<\/span><span class=\"NormalTextRun SCXW227799541 BCX8\"> de las consagradas<\/span><span class=\"NormalTextRun SCXW227799541 BCX8\"> se traduce en algo concreto: compartir la misi\u00f3n con otras vocaciones, dialogar con humildad, construir juntos. <\/span><span class=\"NormalTextRun SpellingErrorV2Themed SCXW227799541 BCX8\">Virmar<\/span><span class=\"NormalTextRun SCXW227799541 BCX8\"> Visconti lo ha vivido como un don desde el inicio de su vida consagrada. <\/span><span class=\"NormalTextRun SCXW227799541 BCX8\">\u00ab<\/span><span class=\"NormalTextRun SCXW227799541 BCX8\">He podido colaborar con <\/span><span class=\"NormalTextRun SCXW227799541 BCX8\">l<\/span><span class=\"NormalTextRun SCXW227799541 BCX8\">egionarios de Cristo, laicos consagrados, y por supuesto con mis hermanas consagradas. Ha sido una riqueza, y tambi\u00e9n un aprendizaje continuo<\/span><span class=\"NormalTextRun SCXW227799541 BCX8\">\u00bb<\/span><span class=\"NormalTextRun SCXW227799541 BCX8\">.<\/span><\/p>\n<figure id=\"attachment_111376\" aria-describedby=\"caption-attachment-111376\" style=\"width: 900px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" class=\"wp-image-111376 size-full\" src=\"https:\/\/regnumchristi.org\/wp-content\/uploads\/2025\/07\/VirmarCapila.webp\" alt=\"Promise He Keeps: Consecrated women celebrate their 25th Anniversary\" width=\"900\" height=\"600\" srcset=\"https:\/\/regnumchristi.org\/wp-content\/uploads\/2025\/07\/VirmarCapila.webp 900w, https:\/\/regnumchristi.org\/wp-content\/uploads\/2025\/07\/VirmarCapila-300x200.webp 300w, https:\/\/regnumchristi.org\/wp-content\/uploads\/2025\/07\/VirmarCapila-768x512.webp 768w, https:\/\/regnumchristi.org\/wp-content\/uploads\/2025\/07\/VirmarCapila-18x12.webp 18w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><figcaption id=\"caption-attachment-111376\" class=\"wp-caption-text\">Virmar Visconti<\/figcaption><\/figure>\n<p><span class=\"NormalTextRun SCXW127045594 BCX8\">The <\/span><span class=\"NormalTextRun SpellingErrorV2Themed SCXW127045594 BCX8\">synodality<\/span><span class=\"NormalTextRun SCXW127045594 BCX8\"> no se improvisa. Exige apertura, escucha, humildad y tiempo. <\/span><span class=\"NormalTextRun SpellingErrorV2Themed SCXW127045594 BCX8\">Virmar<\/span><span class=\"NormalTextRun SCXW127045594 BCX8\"> reconoce los retos: <\/span><span class=\"NormalTextRun SCXW127045594 BCX8\">\u00ab<\/span><span class=\"NormalTextRun SCXW127045594 BCX8\">Superar visiones parciales, construir confianza mutua, aprender a ceder, saber esperar los tiempos del Esp\u00edritu<\/span><span class=\"NormalTextRun SCXW127045594 BCX8\">\u00bb<\/span><span class=\"NormalTextRun SCXW127045594 BCX8\">. Pero tambi\u00e9n afirma que cuando hay verdadera comuni\u00f3n, los frutos no son solo acuerdos operativos, sino experiencias profundas de Dios actuando entre ellos. <\/span><span class=\"NormalTextRun SCXW127045594 BCX8\">\u00ab<\/span><span class=\"NormalTextRun SCXW127045594 BCX8\">Este camino de <\/span><span class=\"NormalTextRun SpellingErrorV2Themed SCXW127045594 BCX8\">synodality<\/span><span class=\"NormalTextRun SCXW127045594 BCX8\"> nos est\u00e1 ayudando a madurar como familia espiritual<\/span><span class=\"NormalTextRun SCXW127045594 BCX8\">\u00bb<\/span><span class=\"NormalTextRun SCXW127045594 BCX8\">.<\/span><\/p>\n<p><span class=\"NormalTextRun SCXW198218993 BCX8\">For <\/span><span class=\"NormalTextRun SpellingErrorV2Themed SCXW198218993 BCX8\">Lizy<\/span><span class=\"NormalTextRun SCXW198218993 BCX8\"> Due\u00f1as Obreg\u00f3n, este proceso ha implicado un cambio cultural profundo. <\/span><span class=\"NormalTextRun SCXW198218993 BCX8\">\u00ab<\/span><span class=\"NormalTextRun SCXW198218993 BCX8\">Antes, cada rama consagrada iba por su cuenta. Hoy compartir la misi\u00f3n exige un gran esfuerzo por conocernos de verdad. No desde apariencias o prejuicios, sino darnos la oportunidad de vernos, valorarnos y complementarnos<\/span><span class=\"NormalTextRun SCXW198218993 BCX8\">\u00bb<\/span><span class=\"NormalTextRun SCXW198218993 BCX8\">. Reconoce que a\u00fan est\u00e1n en camino, pero tambi\u00e9n que hay belleza en la diversidad y riqueza en la identidad de cada vocaci\u00f3n. Aprender a vivir juntos el carisma del <\/span><span class=\"NormalTextRun SpellingErrorV2Themed SCXW198218993 BCX8\">Regnum<\/span><span class=\"NormalTextRun SCXW198218993 BCX8\"> Christi no es f\u00e1cil, pero es necesario.<\/span><\/p>\n<figure id=\"attachment_111356\" aria-describedby=\"caption-attachment-111356\" style=\"width: 900px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-111356\" src=\"https:\/\/regnumchristi.org\/wp-content\/uploads\/2025\/07\/25CLizy.webp\" alt=\"Promise He Keeps: Consecrated women celebrate their 25th Anniversary\" width=\"900\" height=\"600\" srcset=\"https:\/\/regnumchristi.org\/wp-content\/uploads\/2025\/07\/25CLizy.webp 900w, https:\/\/regnumchristi.org\/wp-content\/uploads\/2025\/07\/25CLizy-300x200.webp 300w, https:\/\/regnumchristi.org\/wp-content\/uploads\/2025\/07\/25CLizy-768x512.webp 768w, https:\/\/regnumchristi.org\/wp-content\/uploads\/2025\/07\/25CLizy-18x12.webp 18w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><figcaption id=\"caption-attachment-111356\" class=\"wp-caption-text\">Lizy Due\u00f1as Obreg\u00f3n<\/figcaption><\/figure>\n<p><span class=\"NormalTextRun SCXW114791580 BCX8\">Ren\u00e9e <\/span><span class=\"NormalTextRun SpellingErrorV2Themed SCXW114791580 BCX8\">Pomarico<\/span><span class=\"NormalTextRun SCXW114791580 BCX8\"> aporta <\/span><span class=\"NormalTextRun SCXW114791580 BCX8\">a<\/span><span class=\"NormalTextRun SCXW114791580 BCX8\">a perspectiva<\/span><span class=\"NormalTextRun SCXW114791580 BCX8\"> more<\/span><span class=\"NormalTextRun SCXW114791580 BCX8\">: la de <\/span><span class=\"NormalTextRun SCXW114791580 BCX8\">who<\/span><span class=\"NormalTextRun SCXW114791580 BCX8\"> dio su \u00abs\u00ed\u00bb a Dios,<\/span><span class=\"NormalTextRun SCXW114791580 BCX8\"> en Roma, en el A\u00f1o Jubilar 2000, y que hoy, 25 a\u00f1os despu\u00e9s, tiene la oportunidad de renovar su \u00abs\u00ed\u00bb en el mismo lugar y en el marco del <\/span><span class=\"NormalTextRun SCXW114791580 BCX8\">Jubileo de la Esperanza 2025. <\/span><span class=\"NormalTextRun SCXW114791580 BCX8\">\u00ab<\/span><span class=\"NormalTextRun SCXW114791580 BCX8\">Hoy vivo aqu\u00ed, y tuve la gracia de saludar al Papa Francisco y recibir su bendici\u00f3n. Mi coraz\u00f3n se llena de gratitud<\/span><span class=\"NormalTextRun SCXW114791580 BCX8\">\u00bb<\/span><span class=\"NormalTextRun SCXW114791580 BCX8\">. Su mirada sobre <\/span><span class=\"NormalTextRun SCXW114791580 BCX8\">el caminar d<\/span><span class=\"NormalTextRun SCXW114791580 BCX8\">the <\/span><span class=\"NormalTextRun SpellingErrorV2Themed SCXW114791580 BCX8\">Regnum<\/span><span class=\"NormalTextRun SCXW114791580 BCX8\"> Christi es clara: <\/span><span class=\"NormalTextRun SCXW114791580 BCX8\">\u00ab<\/span><span class=\"NormalTextRun SCXW114791580 BCX8\">Las consagradas han vivido esta transici\u00f3n con docilidad, en di\u00e1logo constante con las otras vocaciones. Ha habido desaf\u00edos, pero tambi\u00e9n mucha esperanza. Queremos seguir caminando <\/span><span class=\"NormalTextRun SCXW114791580 BCX8\">en con<\/span><span class=\"NormalTextRun SCXW114791580 BCX8\">junto como familia espiritual y cuerpo apost\u00f3lico<\/span><span class=\"NormalTextRun SCXW114791580 BCX8\">\u00bb<\/span><span class=\"NormalTextRun SCXW114791580 BCX8\">.<\/span><\/p>\n<figure id=\"attachment_107878\" aria-describedby=\"caption-attachment-107878\" style=\"width: 900px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-107878 size-full\" src=\"https:\/\/regnumchristi.org\/wp-content\/uploads\/2025\/01\/Papa-Francisco.webp\" alt=\"Reflexiones del \u00abXIV Seminario de Comunicaci\u00f3n Eclesial\u00bb\" width=\"900\" height=\"600\" srcset=\"https:\/\/regnumchristi.org\/wp-content\/uploads\/2025\/01\/Papa-Francisco.webp 900w, https:\/\/regnumchristi.org\/wp-content\/uploads\/2025\/01\/Papa-Francisco-300x200.webp 300w, https:\/\/regnumchristi.org\/wp-content\/uploads\/2025\/01\/Papa-Francisco-768x512.webp 768w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><figcaption id=\"caption-attachment-107878\" class=\"wp-caption-text\">Ren\u00e9e Pomarico en la misa donde el Papa Francisco bendijo su anillo de consagraci\u00f3n.<\/figcaption><\/figure>\n<p><strong><span class=\"TextRun MacChromeBold SCXW202945798 BCX8\" lang=\"ES-US\" xml:lang=\"ES-US\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW202945798 BCX8\">El tiempo como herencia: vivir el presente con horizonte de eternidad<\/span><\/span><\/strong><\/p>\n<p><span class=\"NormalTextRun SCXW73832311 BCX8\">Uno de los temas que atraviesa<\/span><span class=\"NormalTextRun SCXW73832311 BCX8\">o<\/span><span class=\"NormalTextRun SCXW73832311 BCX8\"> tod<\/span><span class=\"NormalTextRun SCXW73832311 BCX8\">.<\/span><span class=\"NormalTextRun SCXW73832311 BCX8\">s es el paso del tiempo. Pero no como un simple conteo de a\u00f1os, sino como una narrativa espiritual. \u00bfQu\u00e9 significa haber dado un <\/span><span class=\"NormalTextRun SCXW73832311 BCX8\">\u00ab<\/span><span class=\"NormalTextRun SCXW73832311 BCX8\">yes<\/span><span class=\"NormalTextRun SCXW73832311 BCX8\">\u00bb<\/span><span class=\"NormalTextRun SCXW73832311 BCX8\"> hace 25 a\u00f1os? \u00bfQu\u00e9 cambia, qu\u00e9 permanece? <\/span><span class=\"NormalTextRun SpellingErrorV2Themed SCXW73832311 BCX8\">Lizy<\/span><span class=\"NormalTextRun SCXW73832311 BCX8\"> Due\u00f1as lo expresa <\/span><span class=\"NormalTextRun SCXW73832311 BCX8\">so<\/span><span class=\"NormalTextRun SCXW73832311 BCX8\">: <\/span><span class=\"NormalTextRun SCXW73832311 BCX8\">\u00ab<\/span><span class=\"NormalTextRun SCXW73832311 BCX8\">La vida se pasa r\u00e1pido. Pero al detenerme un poco, veo tanta presencia de Dios en cada momento. Vivir el momento presente es la invitaci\u00f3n de Dios en todos los tiempos<\/span><span class=\"NormalTextRun SCXW73832311 BCX8\">\u00bb<\/span><span class=\"NormalTextRun SCXW73832311 BCX8\">.<\/span><\/p>\n<p><span class=\"TextRun SCXW149058794 BCX8\" lang=\"ES-US\" xml:lang=\"ES-US\" data-contrast=\"auto\"><span class=\"NormalTextRun SpellingErrorV2Themed SCXW149058794 BCX8\">Virmar<\/span><span class=\"NormalTextRun SCXW149058794 BCX8\"> retoma el salmo 15 para resumir lo que siente: <\/span><span class=\"NormalTextRun SCXW149058794 BCX8\">\u00ab<\/span><span class=\"NormalTextRun SCXW149058794 BCX8\">El Se\u00f1or es la porci\u00f3n de mi heredad. Me ha tocado un lote hermoso y me encanta mi heredad<\/span><span class=\"NormalTextRun SCXW149058794 BCX8\">\u00bb<\/span><span class=\"NormalTextRun SCXW149058794 BCX8\">. Y concluye <\/span><span class=\"NormalTextRun SCXW149058794 BCX8\">diciendo<\/span><span class=\"NormalTextRun SCXW149058794 BCX8\">: <\/span><span class=\"NormalTextRun SCXW149058794 BCX8\">\u00ab<\/span><span class=\"NormalTextRun SCXW149058794 BCX8\">Definitivamente, Dios no se deja ganar en generosidad. Vale la pena darlo todo por Cristo<\/span><span class=\"NormalTextRun SCXW149058794 BCX8\">\u00bb<\/span><span class=\"NormalTextRun SCXW149058794 BCX8\">.<\/span><\/span><span class=\"EOP SCXW149058794 BCX8\" data-ccp-props=\"{}\">\u00a0<\/span><\/p>\n<p><span class=\"NormalTextRun SCXW99618002 BCX8\">Mar\u00eda de Lourdes tambi\u00e9n mira hacia atr\u00e1s con un mensaje <\/span><span class=\"NormalTextRun SCXW99618002 BCX8\">very<\/span><span class=\"NormalTextRun SCXW99618002 BCX8\"> vera<\/span><span class=\"NormalTextRun SCXW99618002 BCX8\">z<\/span><span class=\"NormalTextRun SCXW99618002 BCX8\">: <\/span><span class=\"NormalTextRun SCXW99618002 BCX8\">\u00ab<\/span><span class=\"NormalTextRun SCXW99618002 BCX8\">Lo que hoy te parece renuncia, con el tiempo lo ver\u00e1s como plenitud. Ama sin medida, conf\u00eda sin <\/span><span class=\"NormalTextRun SCXW99618002 BCX8\">reservas, y recuerda siempre por qu\u00e9 dijiste <\/span><span class=\"NormalTextRun SCXW99618002 BCX8\">\u201c<\/span><span class=\"NormalTextRun SCXW99618002 BCX8\">yes<\/span><span class=\"NormalTextRun SCXW99618002 BCX8\">\u201d<\/span><span class=\"NormalTextRun SCXW99618002 BCX8\">. Ese s\u00ed ser\u00e1 sostenido cada d\u00eda por la gracia<\/span><span class=\"NormalTextRun SCXW99618002 BCX8\">\u00bb<\/span><span class=\"NormalTextRun SCXW99618002 BCX8\">.<\/span><\/p>\n<p><span class=\"NormalTextRun SCXW252743586 BCX8\">Ren\u00e9e <\/span><span class=\"NormalTextRun SCXW252743586 BCX8\">c<\/span><span class=\"NormalTextRun SCXW252743586 BCX8\">onstat<\/span><span class=\"NormalTextRun SCXW252743586 BCX8\">.<\/span><span class=\"NormalTextRun SCXW252743586 BCX8\"> que ha habido grandes desaf\u00edos, curvas de aprendizaje y caminos de crecimiento. <\/span><span class=\"NormalTextRun SCXW252743586 BCX8\">\u00ab<\/span><span class=\"NormalTextRun SCXW252743586 BCX8\">He percibido un fuerte sentido de responsabilidad, madurez y creciente discernimiento en todo este proceso. Hemos experimentado la fidelidad de Dios, la caridad de nuestros hermanos legionarios, laicos consagrados y miembros laicos en el camino de renovaci\u00f3n y tenemos la firme esperanza de seguir caminando juntos como familia espiritual y cuerpo apost\u00f3lico en el <\/span><span class=\"NormalTextRun SpellingErrorV2Themed SCXW252743586 BCX8\">Regnum<\/span><span class=\"NormalTextRun SCXW252743586 BCX8\"> Christi family<\/span><span class=\"NormalTextRun SCXW252743586 BCX8\">\u00bb<\/span><span class=\"NormalTextRun SCXW252743586 BCX8\">.<\/span><\/p>\n<p><span class=\"NormalTextRun SCXW87159170 BCX8\">A 25 a\u00f1os de haber iniciado un camino que <\/span><span class=\"NormalTextRun SCXW87159170 BCX8\">hoy en d\u00eda <\/span><span class=\"NormalTextRun SCXW87159170 BCX8\">pocas <\/span><span class=\"NormalTextRun SCXW87159170 BCX8\">people <\/span><span class=\"NormalTextRun SCXW87159170 BCX8\">se atreven a recorrer, <\/span><span class=\"NormalTextRun SCXW87159170 BCX8\">the consecrated<\/span><span class=\"NormalTextRun SCXW87159170 BCX8\"> no solo celebran el pasado, sino que lo entregan nuevamente, conscientes de que lo m\u00e1s hermoso de su vocaci\u00f3n no est\u00e1 en el prestigio ni en el reconocimiento, sino en la fidelidad diaria, sencilla, escondida.<\/span><span class=\"NormalTextRun SCXW87159170 BCX8\"> Porque como bien dicen<\/span><span class=\"NormalTextRun SCXW87159170 BCX8\">:<\/span> <span class=\"NormalTextRun SCXW87159170 BCX8\">\u00ab<\/span><span class=\"NormalTextRun SCXW87159170 BCX8\">lo \u00fanico que puede pasar es que Dios te haga muy feliz<\/span><span class=\"NormalTextRun SCXW87159170 BCX8\">\u00bb<\/span><span class=\"NormalTextRun SCXW87159170 BCX8\">.<\/span><\/p>","protected":false},"excerpt":{"rendered":"<p>Las consagradas no solo celebran el pasado, sino que lo entregan nuevamente, conscientes de que lo m\u00e1s hermoso de su vocaci\u00f3n no est\u00e1 en el prestigio ni en el reconocimiento, sino en la fidelidad diaria, sencilla, escondida.<\/p>","protected":false},"author":49,"featured_media":111352,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"default","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"_daextrevop_audio_file_creation_date":"","_daextrevop_text_to_speech":"","_daextrevop_document_type":"","footnotes":""},"categories":[3469],"tags":[90,3462],"class_list":["post-111350","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticia","tag-consagradas-del-regnum-christi","tag-cultura-vocacional"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Promesa que \u00c9l sostiene: consagradas celebran su 25\u00b0 aniversario<\/title>\n<meta name=\"description\" content=\"Cinco historias entrelazadas por una misma vocaci\u00f3n y un mismo carisma, se detienen para mirar lo que han vivido y hacia d\u00f3nde caminan.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/regnumchristi.org\/en\/promesa-que-el-sostiene-consagradas-celebran-su-25-aniversario\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Promesa que \u00c9l sostiene: consagradas celebran su 25\u00b0 aniversario\" \/>\n<meta property=\"og:description\" content=\"Cinco historias entrelazadas por una misma vocaci\u00f3n y un mismo carisma, se detienen para mirar lo que han vivido y hacia d\u00f3nde caminan.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/regnumchristi.org\/en\/promesa-que-el-sostiene-consagradas-celebran-su-25-aniversario\/\" \/>\n<meta property=\"og:site_name\" content=\"Regnum Christi Internacional\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/RegnumChristiEspana\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-07-03T02:03:46+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-03T17:53:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/regnumchristi.org\/wp-content\/uploads\/2025\/07\/25C.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Autores varios\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Autores varios\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/en\\\/promesa-que-el-sostiene-consagradas-celebran-su-25-aniversario\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/en\\\/promesa-que-el-sostiene-consagradas-celebran-su-25-aniversario\\\/\"},\"author\":{\"name\":\"Autores varios\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#\\\/schema\\\/person\\\/73f2e414269cfbf8edecc2fd90af81f2\"},\"headline\":\"Una promesa que \u00c9l sostiene: consagradas celebran su 25\u00b0 aniversario\",\"datePublished\":\"2025-07-03T02:03:46+00:00\",\"dateModified\":\"2025-07-03T17:53:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/en\\\/promesa-que-el-sostiene-consagradas-celebran-su-25-aniversario\\\/\"},\"wordCount\":1609,\"publisher\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/en\\\/promesa-que-el-sostiene-consagradas-celebran-su-25-aniversario\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/regnumchristi.org\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/25C.webp\",\"keywords\":[\"Consagradas del Regnum Christi\",\"Cultura vocacional\"],\"articleSection\":[\"Noticia\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/en\\\/promesa-que-el-sostiene-consagradas-celebran-su-25-aniversario\\\/\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/en\\\/promesa-que-el-sostiene-consagradas-celebran-su-25-aniversario\\\/\",\"name\":\"Promesa que \u00c9l sostiene: consagradas celebran su 25\u00b0 aniversario\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/en\\\/promesa-que-el-sostiene-consagradas-celebran-su-25-aniversario\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/en\\\/promesa-que-el-sostiene-consagradas-celebran-su-25-aniversario\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/regnumchristi.org\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/25C.webp\",\"datePublished\":\"2025-07-03T02:03:46+00:00\",\"dateModified\":\"2025-07-03T17:53:41+00:00\",\"description\":\"Cinco historias entrelazadas por una misma vocaci\u00f3n y un mismo carisma, se detienen para mirar lo que han vivido y hacia d\u00f3nde caminan.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/en\\\/promesa-que-el-sostiene-consagradas-celebran-su-25-aniversario\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/regnumchristi.org\\\/en\\\/promesa-que-el-sostiene-consagradas-celebran-su-25-aniversario\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/en\\\/promesa-que-el-sostiene-consagradas-celebran-su-25-aniversario\\\/#primaryimage\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/25C.webp\",\"contentUrl\":\"https:\\\/\\\/regnumchristi.org\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/25C.webp\",\"width\":900,\"height\":600,\"caption\":\"Promesa que \u00c9l sostiene: consagradas celebran su 25\u00b0 aniversario\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/en\\\/promesa-que-el-sostiene-consagradas-celebran-su-25-aniversario\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/regnumchristi.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Una promesa que \u00c9l sostiene: consagradas celebran su 25\u00b0 aniversario\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#website\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/\",\"name\":\"Regnum Christi Internacional\",\"description\":\"El Regnum Christi es una realidad de la Iglesia cat\u00f3lica cuya misi\u00f3n es hacer presente el Reino de Cristo\",\"publisher\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/regnumchristi.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#organization\",\"name\":\"Regnum Christi Internacional\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/regnumchristi.es\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Favicon-RC_ligh-cuadrado.png\",\"contentUrl\":\"https:\\\/\\\/regnumchristi.es\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Favicon-RC_ligh-cuadrado.png\",\"width\":1080,\"height\":1080,\"caption\":\"Regnum Christi Internacional\"},\"image\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/RegnumChristiEspana\\\/\",\"https:\\\/\\\/x.com\\\/rc_espana\",\"https:\\\/\\\/www.instagram.com\\\/rc_espana\\\/\",\"https:\\\/\\\/es.linkedin.com\\\/company\\\/regnumchristiespaa\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#\\\/schema\\\/person\\\/73f2e414269cfbf8edecc2fd90af81f2\",\"name\":\"Autores varios\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/en\\\/author\\\/jarceocaesc-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Promise He Keeps: Consecrated women celebrate their 25th Anniversary","description":"Cinco historias entrelazadas por una misma vocaci\u00f3n y un mismo carisma, se detienen para mirar lo que han vivido y hacia d\u00f3nde caminan.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/regnumchristi.org\/en\/promesa-que-el-sostiene-consagradas-celebran-su-25-aniversario\/","og_locale":"en_US","og_type":"article","og_title":"Promesa que \u00c9l sostiene: consagradas celebran su 25\u00b0 aniversario","og_description":"Cinco historias entrelazadas por una misma vocaci\u00f3n y un mismo carisma, se detienen para mirar lo que han vivido y hacia d\u00f3nde caminan.","og_url":"https:\/\/regnumchristi.org\/en\/promesa-que-el-sostiene-consagradas-celebran-su-25-aniversario\/","og_site_name":"Regnum Christi Internacional","article_publisher":"https:\/\/www.facebook.com\/RegnumChristiEspana\/","article_published_time":"2025-07-03T02:03:46+00:00","article_modified_time":"2025-07-03T17:53:41+00:00","og_image":[{"width":900,"height":600,"url":"https:\/\/regnumchristi.org\/wp-content\/uploads\/2025\/07\/25C.webp","type":"image\/webp"}],"author":"Autores varios","twitter_misc":{"Written by":"Autores varios","Est. reading time":"8 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/regnumchristi.org\/en\/promesa-que-el-sostiene-consagradas-celebran-su-25-aniversario\/#article","isPartOf":{"@id":"https:\/\/regnumchristi.org\/en\/promesa-que-el-sostiene-consagradas-celebran-su-25-aniversario\/"},"author":{"name":"Autores varios","@id":"https:\/\/regnumchristi.org\/#\/schema\/person\/73f2e414269cfbf8edecc2fd90af81f2"},"headline":"Una promesa que \u00c9l sostiene: consagradas celebran su 25\u00b0 aniversario","datePublished":"2025-07-03T02:03:46+00:00","dateModified":"2025-07-03T17:53:41+00:00","mainEntityOfPage":{"@id":"https:\/\/regnumchristi.org\/en\/promesa-que-el-sostiene-consagradas-celebran-su-25-aniversario\/"},"wordCount":1609,"publisher":{"@id":"https:\/\/regnumchristi.org\/#organization"},"image":{"@id":"https:\/\/regnumchristi.org\/en\/promesa-que-el-sostiene-consagradas-celebran-su-25-aniversario\/#primaryimage"},"thumbnailUrl":"https:\/\/regnumchristi.org\/wp-content\/uploads\/2025\/07\/25C.webp","keywords":["Consagradas del Regnum Christi","Cultura vocacional"],"articleSection":["Noticia"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/regnumchristi.org\/en\/promesa-que-el-sostiene-consagradas-celebran-su-25-aniversario\/","url":"https:\/\/regnumchristi.org\/en\/promesa-que-el-sostiene-consagradas-celebran-su-25-aniversario\/","name":"Promise He Keeps: Consecrated women celebrate their 25th Anniversary","isPartOf":{"@id":"https:\/\/regnumchristi.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/regnumchristi.org\/en\/promesa-que-el-sostiene-consagradas-celebran-su-25-aniversario\/#primaryimage"},"image":{"@id":"https:\/\/regnumchristi.org\/en\/promesa-que-el-sostiene-consagradas-celebran-su-25-aniversario\/#primaryimage"},"thumbnailUrl":"https:\/\/regnumchristi.org\/wp-content\/uploads\/2025\/07\/25C.webp","datePublished":"2025-07-03T02:03:46+00:00","dateModified":"2025-07-03T17:53:41+00:00","description":"Cinco historias entrelazadas por una misma vocaci\u00f3n y un mismo carisma, se detienen para mirar lo que han vivido y hacia d\u00f3nde caminan.","breadcrumb":{"@id":"https:\/\/regnumchristi.org\/en\/promesa-que-el-sostiene-consagradas-celebran-su-25-aniversario\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/regnumchristi.org\/en\/promesa-que-el-sostiene-consagradas-celebran-su-25-aniversario\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/regnumchristi.org\/en\/promesa-que-el-sostiene-consagradas-celebran-su-25-aniversario\/#primaryimage","url":"https:\/\/regnumchristi.org\/wp-content\/uploads\/2025\/07\/25C.webp","contentUrl":"https:\/\/regnumchristi.org\/wp-content\/uploads\/2025\/07\/25C.webp","width":900,"height":600,"caption":"Promesa que \u00c9l sostiene: consagradas celebran su 25\u00b0 aniversario"},{"@type":"BreadcrumbList","@id":"https:\/\/regnumchristi.org\/en\/promesa-que-el-sostiene-consagradas-celebran-su-25-aniversario\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/regnumchristi.org\/es\/"},{"@type":"ListItem","position":2,"name":"Una promesa que \u00c9l sostiene: consagradas celebran su 25\u00b0 aniversario"}]},{"@type":"WebSite","@id":"https:\/\/regnumchristi.org\/#website","url":"https:\/\/regnumchristi.org\/","name":"Regnum Christi International","description":"Regnum Christi is a reality of the Catholic Church whose mission is to make present the Kingdom of Christ.","publisher":{"@id":"https:\/\/regnumchristi.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/regnumchristi.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/regnumchristi.org\/#organization","name":"Regnum Christi International","url":"https:\/\/regnumchristi.org\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/regnumchristi.org\/#\/schema\/logo\/image\/","url":"https:\/\/regnumchristi.es\/wp-content\/uploads\/2023\/03\/Favicon-RC_ligh-cuadrado.png","contentUrl":"https:\/\/regnumchristi.es\/wp-content\/uploads\/2023\/03\/Favicon-RC_ligh-cuadrado.png","width":1080,"height":1080,"caption":"Regnum Christi Internacional"},"image":{"@id":"https:\/\/regnumchristi.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/RegnumChristiEspana\/","https:\/\/x.com\/rc_espana","https:\/\/www.instagram.com\/rc_espana\/","https:\/\/es.linkedin.com\/company\/regnumchristiespaa"]},{"@type":"Person","@id":"https:\/\/regnumchristi.org\/#\/schema\/person\/73f2e414269cfbf8edecc2fd90af81f2","name":"Various authors","url":"https:\/\/regnumchristi.org\/en\/author\/jarceocaesc-com\/"}]}},"_links":{"self":[{"href":"https:\/\/regnumchristi.org\/en\/wp-json\/wp\/v2\/posts\/111350","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/regnumchristi.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/regnumchristi.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/regnumchristi.org\/en\/wp-json\/wp\/v2\/users\/49"}],"replies":[{"embeddable":true,"href":"https:\/\/regnumchristi.org\/en\/wp-json\/wp\/v2\/comments?post=111350"}],"version-history":[{"count":7,"href":"https:\/\/regnumchristi.org\/en\/wp-json\/wp\/v2\/posts\/111350\/revisions"}],"predecessor-version":[{"id":111381,"href":"https:\/\/regnumchristi.org\/en\/wp-json\/wp\/v2\/posts\/111350\/revisions\/111381"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/regnumchristi.org\/en\/wp-json\/wp\/v2\/media\/111352"}],"wp:attachment":[{"href":"https:\/\/regnumchristi.org\/en\/wp-json\/wp\/v2\/media?parent=111350"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/regnumchristi.org\/en\/wp-json\/wp\/v2\/categories?post=111350"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/regnumchristi.org\/en\/wp-json\/wp\/v2\/tags?post=111350"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}