{"id":13797,"date":"2020-08-12T05:00:18","date_gmt":"2020-08-12T10:00:18","guid":{"rendered":"http:\/\/www.regnumchristi.org\/es\/?p=13797"},"modified":"2025-10-03T11:48:38","modified_gmt":"2025-10-03T17:48:38","slug":"las-migajas-caen","status":"publish","type":"post","link":"https:\/\/regnumchristi.org\/en\/las-migajas-caen\/","title":{"rendered":"Las migajas que caen de la mesa (Mt 15,21-28)"},"content":{"rendered":"<p><strong><span style=\"color: #990000;\">Gospel:<\/span><\/strong>\u00a0<em>Mt 15,21-28<\/em><br \/>\nSaliendo de all\u00ed Jes\u00fas se retir\u00f3 hacia la regi\u00f3n de Tiro y Sid\u00f3n. En esto, una mujer cananea, que hab\u00eda salido de aquel territorio, gritaba diciendo: &#8220;\u00a1Ten piedad de m\u00ed, Se\u00f1or, hijo de David! Mi hija est\u00e1 malamente endemoniada&#8221;. Pero \u00e9l no le respondi\u00f3 palabra. Sus disc\u00edpulos, acerc\u00e1ndose, le rogaban: &#8220;Desp\u00eddela, que viene gritando detr\u00e1s de nosotros&#8221;. Respondi\u00f3 \u00e9l: &#8220;No he sido enviado m\u00e1s que a las ovejas perdidas de la casa de Israel&#8221;. Ella, no obstante, vino a postrarse ante \u00e9l y le dijo: &#8220;\u00a1Se\u00f1or, soc\u00f3rreme!&#8221;. \u00c9l respondi\u00f3: &#8220;No est\u00e1 bien tomar el pan de los hijos y ech\u00e1rselo a los perritos&#8221;. &#8220;S\u00ed, Se\u00f1or -repuso ella-, pero tambi\u00e9n los perritos comen de las migajas que caen de la mesa de sus amos&#8221;. Entonces Jes\u00fas le respondi\u00f3: &#8220;Mujer, grande es tu fe; que te suceda como deseas&#8221;. Y desde aquel momento qued\u00f3 curada su hija.<\/p>\n<p><strong><span style=\"color: #990000;\">Fruit:<\/span><\/strong> Revisar en mi vida cu\u00e1les son los \u00eddolos (las migajas) que impiden una vivencia transparente del Evangelio en mi d\u00eda a d\u00eda.<\/p>\n<p><span style=\"color: #990000;\"><strong>Guidelines for reflection:<\/strong><br \/>\n<\/span>Cristo nos da una lecci\u00f3n de lo que significa la apertura cultural del Evangelio, de inculturaci\u00f3n mostrada en el modo de llegar a los corazones de quienes son ajenos al cristianismo.<\/p>\n<p><em>1. \u00c9l no respondi\u00f3 palabra<\/em><br \/>\nQuiz\u00e1 malamente acostumbrados para ver solo lo negativo de las personas y criticar, hay quienes hurgan este pasaje del Evangelio para fundamentar la intolerancia del cristianismo, como queriendo basar sus razonamientos diciendo que Cristo no aceptaba culturas diversas a la suya; pero no es as\u00ed. M\u00e1s bien es una lecci\u00f3n de c\u00f3mo llevar el Evangelio a las personas ajenas a la cultura del pa\u00eds. Nuestro Se\u00f1or fue llevando de la mano la fe de la mujer para que demostrara su confianza en \u00c9l. No responderle en un determinado momento llev\u00f3 a la cananea a mostrar la grandeza de quien sabe ser humilde: se mostr\u00f3 confiada en el poder de Dios: \u00ab\u00a1Ten piedad de m\u00ed!\u00bb. Tambi\u00e9n hoy hay cristianos, y quiz\u00e1 en tu misma familia, que piensan el cristianismo como un club, como una membres\u00eda VIP. Son los que piensan que para ser cristiano, que para seguir a Cristo, hay que usar una camisa de fuerza elaborada por ellos mismos, y solo si la usas, te podr\u00edas llamar cristiano. Nada que ver. \u00bfQu\u00e9 tipo de cristianismo vivo y qu\u00e9 tipo de cristianismo proyecto?<\/p>\n<p><em>2. Desp\u00eddela, que viene gritando<br \/>\n<\/em>Los disc\u00edpulos ve\u00edan en ella un elemento negativo, no le ve\u00edan remedio pues era &#8220;diferente&#8221;, no cre\u00eda en lo mismo que ellos. Los cananeos ten\u00edan sus dioses y eran capaces de sacrificar sus alimentos para depositarlos como ofrendas en sus templos aunque se quedaran sin comer. Por eso Jes\u00fas le llama la atenci\u00f3n a la cananea: no eches las migajas del pan de tus hijos a los perros. Esto es muy actual tambi\u00e9n. La sociedad &#8220;moderna&#8221; nos presenta hoy muchos \u00eddolos (muchas migajas) ante los cuales somos capaces de sacrificar nuestra fe: todo lo que lleva a una cultura de la muerte. Qu\u00e9 f\u00e1ciles somos para dejarnos permear por los antivalores, los dejamos entrar sin preocupaci\u00f3n alguna; quiz\u00e1 para algunos, encontrar esto en la sociedad sea motivo de desesperaci\u00f3n: \u00a1No tiene remedio, desp\u00eddela, dale un adi\u00f3s agradable, ha perdido su fe! Pero Cristo nos invita a buscar modos m\u00e1s eficaces para que encuentre o renazca en ellos su fe.<\/p>\n<p><em>3. Mujer, grande es tu fe<\/em><br \/>\nEs tiempo de revisar nuestro coraz\u00f3n y ver qu\u00e9 aspectos vivenciales son contrarios al Evangelio, qu\u00e9 formas de pensar son contrarias a los valores humanos perennes del cristianismo, qu\u00e9 migajas est\u00e1mos echando a los perros. Es hora de demostrar al mundo la grandeza de nuestra fe, que nuestros valores est\u00e1n por encima de quienes quieren destruirlos y no dejaremos que nos permeen con ideolog\u00edas destructoras. D\u00e9mosle a Dios la satisfacci\u00f3n de que somos capaces de vivir el Evangelio, aliment\u00e1ndonos con mayor frecuencia de los sacramentos, especialmente de la confesi\u00f3n y de la Eucarist\u00eda. Y expresemos nuestra fe vivi\u00e9ndola sin problemas, sin complejos. No seamos cristianos de club VIP, tampoco pretendamos transmitir la fe a golpe de martillazo. La pedagog\u00eda de Jes\u00fas es de salir al encuentro, llevar el mensaje sin pleitos, sin pretender ser m\u00e1s papistas que el Papa para decidir qui\u00e9n s\u00ed o qui\u00e9n no es merecedor de estar &#8220;en el club&#8221; seg\u00fan las interpretaciones personales. El Magisterio de la Iglesia es la gu\u00eda segura, no las teor\u00edas de la conspiraci\u00f3n que alimentan un tipo de pensamiento r\u00edgido, de camisa de fuerza. La Canena con Jes\u00fas tuvo una puerta abierta para abrazar la fe; los &#8220;cananeos&#8221; de nuestro tiempo, \u00bfqu\u00e9 encontrar\u00e1n en m\u00ed, que me digo seguidor de Cristo?<\/p>\n<p><strong><span style=\"color: #990000;\">Purpose:<\/span><\/strong> Cortar con todo aquello que me aleje de Jes\u00fas.<\/p>\n<p><em>Listen also to our monthly online retreat.<\/em><\/p>","protected":false},"excerpt":{"rendered":"<p> [&hellip;]<\/p>\n","protected":false},"author":49,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"_daextrevop_audio_file_creation_date":"","_daextrevop_text_to_speech":"","_daextrevop_document_type":"","footnotes":""},"categories":[3243],"tags":[117,229],"class_list":["post-13797","post","type-post","status-publish","format-standard","hentry","category-hora-eucaristica","tag-hora-eucaristica","tag-hora-santa"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Las migajas que caen de la mesa (Mt 15,21-28) - Hora Eucar\u00edstica<\/title>\n<meta name=\"description\" content=\"La sociedad &quot;moderna&quot; presenta hoy \u00eddolos ante los cuales somos capaces de sacrificar nuestra fe, ofreciendo incluso migajas de felicidad.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/regnumchristi.org\/en\/las-migajas-caen\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Las migajas que caen de la mesa (Mt 15,21-28) - Hora Eucar\u00edstica\" \/>\n<meta property=\"og:description\" content=\"La sociedad &quot;moderna&quot; presenta hoy \u00eddolos ante los cuales somos capaces de sacrificar nuestra fe, ofreciendo incluso migajas de felicidad.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/regnumchristi.org\/en\/las-migajas-caen\/\" \/>\n<meta property=\"og:site_name\" content=\"Regnum Christi Internacional\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/RegnumChristiEspana\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-08-12T10:00:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-03T17:48:38+00:00\" \/>\n<meta name=\"author\" content=\"Autores varios\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Autores varios\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/las-migajas-caen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/las-migajas-caen\\\/\"},\"author\":{\"name\":\"Autores varios\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#\\\/schema\\\/person\\\/73f2e414269cfbf8edecc2fd90af81f2\"},\"headline\":\"Las migajas que caen de la mesa (Mt 15,21-28)\",\"datePublished\":\"2020-08-12T10:00:18+00:00\",\"dateModified\":\"2025-10-03T17:48:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/las-migajas-caen\\\/\"},\"wordCount\":867,\"publisher\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#organization\"},\"keywords\":[\"Hora Eucar\u00edstica\",\"hora santa\"],\"articleSection\":[\"Hora Eucar\u00edstica\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/las-migajas-caen\\\/\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/las-migajas-caen\\\/\",\"name\":\"Las migajas que caen de la mesa (Mt 15,21-28) - Hora Eucar\u00edstica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#website\"},\"datePublished\":\"2020-08-12T10:00:18+00:00\",\"dateModified\":\"2025-10-03T17:48:38+00:00\",\"description\":\"La sociedad \\\"moderna\\\" presenta hoy \u00eddolos ante los cuales somos capaces de sacrificar nuestra fe, ofreciendo incluso migajas de felicidad.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/las-migajas-caen\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/regnumchristi.org\\\/las-migajas-caen\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/las-migajas-caen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/regnumchristi.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Las migajas que caen de la mesa (Mt 15,21-28)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#website\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/\",\"name\":\"Regnum Christi Internacional\",\"description\":\"El Regnum Christi es una realidad de la Iglesia cat\u00f3lica cuya misi\u00f3n es hacer presente el Reino de Cristo\",\"publisher\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/regnumchristi.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#organization\",\"name\":\"Regnum Christi Internacional\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/regnumchristi.es\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Favicon-RC_ligh-cuadrado.png\",\"contentUrl\":\"https:\\\/\\\/regnumchristi.es\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Favicon-RC_ligh-cuadrado.png\",\"width\":1080,\"height\":1080,\"caption\":\"Regnum Christi Internacional\"},\"image\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/RegnumChristiEspana\\\/\",\"https:\\\/\\\/x.com\\\/rc_espana\",\"https:\\\/\\\/www.instagram.com\\\/rc_espana\\\/\",\"https:\\\/\\\/es.linkedin.com\\\/company\\\/regnumchristiespaa\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#\\\/schema\\\/person\\\/73f2e414269cfbf8edecc2fd90af81f2\",\"name\":\"Autores varios\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/en\\\/author\\\/jarceocaesc-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Las migajas que caen de la mesa (Mt 15,21-28) - Hora Eucar\u00edstica","description":"La sociedad \"moderna\" presenta hoy \u00eddolos ante los cuales somos capaces de sacrificar nuestra fe, ofreciendo incluso migajas de felicidad.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/regnumchristi.org\/en\/las-migajas-caen\/","og_locale":"en_US","og_type":"article","og_title":"Las migajas que caen de la mesa (Mt 15,21-28) - Hora Eucar\u00edstica","og_description":"La sociedad \"moderna\" presenta hoy \u00eddolos ante los cuales somos capaces de sacrificar nuestra fe, ofreciendo incluso migajas de felicidad.","og_url":"https:\/\/regnumchristi.org\/en\/las-migajas-caen\/","og_site_name":"Regnum Christi Internacional","article_publisher":"https:\/\/www.facebook.com\/RegnumChristiEspana\/","article_published_time":"2020-08-12T10:00:18+00:00","article_modified_time":"2025-10-03T17:48:38+00:00","author":"Autores varios","twitter_misc":{"Written by":"Autores varios","Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/regnumchristi.org\/las-migajas-caen\/#article","isPartOf":{"@id":"https:\/\/regnumchristi.org\/las-migajas-caen\/"},"author":{"name":"Autores varios","@id":"https:\/\/regnumchristi.org\/#\/schema\/person\/73f2e414269cfbf8edecc2fd90af81f2"},"headline":"Las migajas que caen de la mesa (Mt 15,21-28)","datePublished":"2020-08-12T10:00:18+00:00","dateModified":"2025-10-03T17:48:38+00:00","mainEntityOfPage":{"@id":"https:\/\/regnumchristi.org\/las-migajas-caen\/"},"wordCount":867,"publisher":{"@id":"https:\/\/regnumchristi.org\/#organization"},"keywords":["Hora Eucar\u00edstica","hora santa"],"articleSection":["Hora Eucar\u00edstica"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/regnumchristi.org\/las-migajas-caen\/","url":"https:\/\/regnumchristi.org\/las-migajas-caen\/","name":"Las migajas que caen de la mesa (Mt 15,21-28) - Hora Eucar\u00edstica","isPartOf":{"@id":"https:\/\/regnumchristi.org\/#website"},"datePublished":"2020-08-12T10:00:18+00:00","dateModified":"2025-10-03T17:48:38+00:00","description":"La sociedad \"moderna\" presenta hoy \u00eddolos ante los cuales somos capaces de sacrificar nuestra fe, ofreciendo incluso migajas de felicidad.","breadcrumb":{"@id":"https:\/\/regnumchristi.org\/las-migajas-caen\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/regnumchristi.org\/las-migajas-caen\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/regnumchristi.org\/las-migajas-caen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/regnumchristi.org\/es\/"},{"@type":"ListItem","position":2,"name":"Las migajas que caen de la mesa (Mt 15,21-28)"}]},{"@type":"WebSite","@id":"https:\/\/regnumchristi.org\/#website","url":"https:\/\/regnumchristi.org\/","name":"Regnum Christi International","description":"Regnum Christi is a reality of the Catholic Church whose mission is to make present the Kingdom of Christ.","publisher":{"@id":"https:\/\/regnumchristi.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/regnumchristi.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/regnumchristi.org\/#organization","name":"Regnum Christi International","url":"https:\/\/regnumchristi.org\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/regnumchristi.org\/#\/schema\/logo\/image\/","url":"https:\/\/regnumchristi.es\/wp-content\/uploads\/2023\/03\/Favicon-RC_ligh-cuadrado.png","contentUrl":"https:\/\/regnumchristi.es\/wp-content\/uploads\/2023\/03\/Favicon-RC_ligh-cuadrado.png","width":1080,"height":1080,"caption":"Regnum Christi Internacional"},"image":{"@id":"https:\/\/regnumchristi.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/RegnumChristiEspana\/","https:\/\/x.com\/rc_espana","https:\/\/www.instagram.com\/rc_espana\/","https:\/\/es.linkedin.com\/company\/regnumchristiespaa"]},{"@type":"Person","@id":"https:\/\/regnumchristi.org\/#\/schema\/person\/73f2e414269cfbf8edecc2fd90af81f2","name":"Various authors","url":"https:\/\/regnumchristi.org\/en\/author\/jarceocaesc-com\/"}]}},"_links":{"self":[{"href":"https:\/\/regnumchristi.org\/en\/wp-json\/wp\/v2\/posts\/13797","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/regnumchristi.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/regnumchristi.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/regnumchristi.org\/en\/wp-json\/wp\/v2\/users\/49"}],"replies":[{"embeddable":true,"href":"https:\/\/regnumchristi.org\/en\/wp-json\/wp\/v2\/comments?post=13797"}],"version-history":[{"count":2,"href":"https:\/\/regnumchristi.org\/en\/wp-json\/wp\/v2\/posts\/13797\/revisions"}],"predecessor-version":[{"id":113919,"href":"https:\/\/regnumchristi.org\/en\/wp-json\/wp\/v2\/posts\/13797\/revisions\/113919"}],"wp:attachment":[{"href":"https:\/\/regnumchristi.org\/en\/wp-json\/wp\/v2\/media?parent=13797"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/regnumchristi.org\/en\/wp-json\/wp\/v2\/categories?post=13797"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/regnumchristi.org\/en\/wp-json\/wp\/v2\/tags?post=13797"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}