{"id":15922,"date":"2021-01-27T05:00:48","date_gmt":"2021-01-27T11:00:48","guid":{"rendered":"http:\/\/www.regnumchristi.org\/es\/?p=15922"},"modified":"2025-10-03T11:48:39","modified_gmt":"2025-10-03T17:48:39","slug":"ensena-con-autoridad","status":"publish","type":"post","link":"https:\/\/regnumchristi.org\/en\/ensena-con-autoridad\/","title":{"rendered":"He teaches with authority (Mk 1:21-28)."},"content":{"rendered":"<p><span style=\"color: #990000;\"><strong>Gospel:<\/strong>\u00a0<\/span><em>Marcos<\/em>\u00a0<em>1,21-28<\/em><br \/>\nSe hallaba Jes\u00fas en Cafarna\u00fam y el s\u00e1bado fue a la sinagoga y se puso a ense\u00f1ar. Los oyentes quedaron asombrados de sus palabras, pues ense\u00f1aba como quien tiene autoridad y no como los escribas. Hab\u00eda en la sinagoga un hombre pose\u00eddo por un esp\u00edritu inmundo, que se puso a gritar: &#8220;\u00bfQu\u00e9 quieres t\u00fa con nosotros, Jes\u00fas de Nazaret? \u00bfHas venido a acabar con nosotros? Ya s\u00e9 qui\u00e9n eres: el Santo de Dios&#8221;. Jes\u00fas le orden\u00f3: &#8220;\u00a1C\u00e1llate y sal de \u00e9l!&#8221;. El esp\u00edritu inmundo, sacudiendo al hombre con violencia y dando un alarido, sali\u00f3 de \u00e9l. Todos quedaron estupefactos y se preguntaban: &#8220;\u00bfQu\u00e9 es esto? \u00bfQu\u00e9 nueva doctrina es esta? Este hombre tiene autoridad para mandar hasta a los esp\u00edritus inmundos y lo obedecen&#8221;. Y muy pronto se extendi\u00f3 su fama por toda Galilea.<\/p>\n<p><strong><span style=\"color: #990000;\">Fruit:<\/span><\/strong> Permitirle a Dios que cure todas mis dolencias f\u00edsicas y espirituales, acudiendo primeramente al sacramento de la reconciliaci\u00f3n.<\/p>\n<p><strong><span style=\"color: #990000;\">Guidelines for reflection:<br \/>\n<\/span><\/strong>El demonio reconoce la presencia del Se\u00f1or, incluso puede dialogar con \u00c9l; pero Dios tiene siempre la \u00faltima palabra, el poder de derrotarlo.<\/p>\n<p><em>1. Ense\u00f1aba como quien tiene autoridad<\/em><br \/>\nCristo es el Se\u00f1or, pero nos ense\u00f1\u00f3 que su autoridad es de servicio, de caridad hasta el extremo de dar su vida por amor a cada uno de nosotros. Su autoridad fue reconocida por la gente que lo vio y escuch\u00f3 porque ve\u00edan en \u00c9l a alguien coherente, donde sus obras y sus palabras coincid\u00edan plenamente. Ense\u00f1ar con autoridad no es simplemente ponerse a dar \u00f3rdenes, al menos Cristo nos dej\u00f3 claro que la autoridad en el cristiano est\u00e1 en el servicio a los dem\u00e1s, y ense\u00f1ar con autoridad significa dar ejemplo de servicio, el arremangarse y ponerse a trabajar a favor de los dem\u00e1s con una meta clara: que conozcan el amor de Dios.<\/p>\n<p><em>2. \u00bfHas venido a acabar con nosotros?<\/em><br \/>\nEl demonio reconoce en Cristo el poder capaz de vencerlo. Es curioso notar en este pasaje del Evangelio como se entabla un di\u00e1logo entre Cristo y el demonio. Pero el di\u00e1logo es liderado por el Se\u00f1or y de modo imperativo. Esta es una lecci\u00f3n muy clara: con las tentaciones no debemos ser consecuentes ni jugar con ellas, siempre tenemos que ser en\u00e9rgicos en rechazarlas y debemos estar por encima de ellas. Pero claro, es algo que solos no podemos realizar, s\u00f3lo con la gracia de Cristo y una voluntad decidida podemos vencer las tentaciones, pues, con nuestras propias fuerzas y sin la gracia de Dios dif\u00edcilmente lo podremos hacer.<\/p>\n<p><em>3. Este hombre tiene autoridad hasta en los esp\u00edritus inmundos<\/em><br \/>\nEl mal no puede vencer al bien, aunque pudiera parecer lo contrario. Porque, ciertamente, parecer\u00eda que el mal triunfa f\u00e1cilmente, pero hay que recordar que &#8220;hace m\u00e1s ruido un \u00e1rbol que cae que un bosque que crece&#8221;. El mal no puede sostenerse por s\u00ed mismo, es pasajero, mientras que el bien, tiene su fuerza en s\u00ed mismo y perdura para siempre. Por tanto, el mal no puede vencer al bien y est\u00e1 destinado a caer. Pero si el bien no vence o no remplaza el lugar que deja ese mal, ser\u00e1 sustituido por otro mal mayor, generando una cadena de males. Este hecho, posiblemente, lo constatamos en nuestra sociedad: cr\u00edmenes, asaltos, robos, tr\u00e1fico de estupefacientes, raptos, guerras, pero debemos recordar siempre que el mal no puede destruir al bien y, misteriosamente, el bien est\u00e1 latente incluso entre el mal que se expande. Despu\u00e9s de las tormentas, viene la calma. Dios es el sumo Bien. Un modo de vencer el mal es aferrarse a Dios. No podemos quedarnos s\u00f3lo con los brazos cruzados y vivir pasivamente los acontecimientos. M\u00e1s bien, debemos encomendarnos a Dios y trabajar por mejorar, brindar una mano a quien m\u00e1s lo necesite y no perder la esperanza de que el mal no puede vencer al bien.<\/p>\n<p><strong><span style=\"color: #990000;\">Purpose:<\/span><\/strong>\u00a0Vencer\u00e9 al mal con el bien en mi vida, reconociendo el poder y se\u00f1or\u00edo de Cristo en mi existencia. Para ello, acudir\u00e9 al sacramento de la confesi\u00f3n para que Dios triunfe en mi vida.<\/p>\n<p><em>Listen also to our monthly online retreat.<\/em><\/p>\n<p>You may be interested in: <a href=\"https:\/\/es.catholic.net\/op\/articulos\/56111\/cat\/30\/que-pueden-hacer-los-demonios-que-es-lo-que-no-pueden-hacer.html#modal\" target=\"_blank\" rel=\"noopener noreferrer\">\u00bfQu\u00e9 es lo que pueden hacer los demonios? \u00bfQu\u00e9 es lo que no pueden hacer?<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p> [&hellip;]<\/p>\n","protected":false},"author":49,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"_daextrevop_audio_file_creation_date":"","_daextrevop_text_to_speech":"","_daextrevop_document_type":"","footnotes":""},"categories":[3243],"tags":[117,229],"class_list":["post-15922","post","type-post","status-publish","format-standard","hentry","category-hora-eucaristica","tag-hora-eucaristica","tag-hora-santa"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ense\u00f1a con autoridad (Mc 1,21-28) - Hora Eucar\u00edstica<\/title>\n<meta name=\"description\" content=\"El demonio reconoce la presencia del Se\u00f1or, incluso dialoga con \u00c9l; pero Dios tiene la \u00faltima palabra, el poder y con autoridad lo derrota.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/regnumchristi.org\/en\/ensena-con-autoridad\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ense\u00f1a con autoridad (Mc 1,21-28) - Hora Eucar\u00edstica\" \/>\n<meta property=\"og:description\" content=\"El demonio reconoce la presencia del Se\u00f1or, incluso dialoga con \u00c9l; pero Dios tiene la \u00faltima palabra, el poder y con autoridad lo derrota.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/regnumchristi.org\/en\/ensena-con-autoridad\/\" \/>\n<meta property=\"og:site_name\" content=\"Regnum Christi Internacional\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/RegnumChristiEspana\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-01-27T11:00:48+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-03T17:48:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/regnumchristi.org\/wp-content\/uploads\/2021\/01\/C814024.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"1428\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Autores varios\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Autores varios\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/ensena-con-autoridad\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/ensena-con-autoridad\\\/\"},\"author\":{\"name\":\"Autores varios\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#\\\/schema\\\/person\\\/73f2e414269cfbf8edecc2fd90af81f2\"},\"headline\":\"Ense\u00f1a con autoridad (Mc 1,21-28)\",\"datePublished\":\"2021-01-27T11:00:48+00:00\",\"dateModified\":\"2025-10-03T17:48:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/ensena-con-autoridad\\\/\"},\"wordCount\":751,\"publisher\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#organization\"},\"keywords\":[\"Hora Eucar\u00edstica\",\"hora santa\"],\"articleSection\":[\"Hora Eucar\u00edstica\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/ensena-con-autoridad\\\/\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/ensena-con-autoridad\\\/\",\"name\":\"Ense\u00f1a con autoridad (Mc 1,21-28) - Hora Eucar\u00edstica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#website\"},\"datePublished\":\"2021-01-27T11:00:48+00:00\",\"dateModified\":\"2025-10-03T17:48:39+00:00\",\"description\":\"El demonio reconoce la presencia del Se\u00f1or, incluso dialoga con \u00c9l; pero Dios tiene la \u00faltima palabra, el poder y con autoridad lo derrota.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/ensena-con-autoridad\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/regnumchristi.org\\\/ensena-con-autoridad\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/ensena-con-autoridad\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/regnumchristi.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ense\u00f1a con autoridad (Mc 1,21-28)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#website\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/\",\"name\":\"Regnum Christi Internacional\",\"description\":\"El Regnum Christi es una realidad de la Iglesia cat\u00f3lica cuya misi\u00f3n es hacer presente el Reino de Cristo\",\"publisher\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/regnumchristi.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#organization\",\"name\":\"Regnum Christi Internacional\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/regnumchristi.es\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Favicon-RC_ligh-cuadrado.png\",\"contentUrl\":\"https:\\\/\\\/regnumchristi.es\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Favicon-RC_ligh-cuadrado.png\",\"width\":1080,\"height\":1080,\"caption\":\"Regnum Christi Internacional\"},\"image\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/RegnumChristiEspana\\\/\",\"https:\\\/\\\/x.com\\\/rc_espana\",\"https:\\\/\\\/www.instagram.com\\\/rc_espana\\\/\",\"https:\\\/\\\/es.linkedin.com\\\/company\\\/regnumchristiespaa\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#\\\/schema\\\/person\\\/73f2e414269cfbf8edecc2fd90af81f2\",\"name\":\"Autores varios\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/en\\\/author\\\/jarceocaesc-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ense\u00f1a con autoridad (Mc 1,21-28) - Hora Eucar\u00edstica","description":"El demonio reconoce la presencia del Se\u00f1or, incluso dialoga con \u00c9l; pero Dios tiene la \u00faltima palabra, el poder y con autoridad lo derrota.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/regnumchristi.org\/en\/ensena-con-autoridad\/","og_locale":"en_US","og_type":"article","og_title":"Ense\u00f1a con autoridad (Mc 1,21-28) - Hora Eucar\u00edstica","og_description":"El demonio reconoce la presencia del Se\u00f1or, incluso dialoga con \u00c9l; pero Dios tiene la \u00faltima palabra, el poder y con autoridad lo derrota.","og_url":"https:\/\/regnumchristi.org\/en\/ensena-con-autoridad\/","og_site_name":"Regnum Christi Internacional","article_publisher":"https:\/\/www.facebook.com\/RegnumChristiEspana\/","article_published_time":"2021-01-27T11:00:48+00:00","article_modified_time":"2025-10-03T17:48:39+00:00","og_image":[{"width":2048,"height":1428,"url":"https:\/\/regnumchristi.org\/wp-content\/uploads\/2021\/01\/C814024.jpg","type":"image\/jpeg"}],"author":"Autores varios","twitter_misc":{"Written by":"Autores varios","Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/regnumchristi.org\/ensena-con-autoridad\/#article","isPartOf":{"@id":"https:\/\/regnumchristi.org\/ensena-con-autoridad\/"},"author":{"name":"Autores varios","@id":"https:\/\/regnumchristi.org\/#\/schema\/person\/73f2e414269cfbf8edecc2fd90af81f2"},"headline":"Ense\u00f1a con autoridad (Mc 1,21-28)","datePublished":"2021-01-27T11:00:48+00:00","dateModified":"2025-10-03T17:48:39+00:00","mainEntityOfPage":{"@id":"https:\/\/regnumchristi.org\/ensena-con-autoridad\/"},"wordCount":751,"publisher":{"@id":"https:\/\/regnumchristi.org\/#organization"},"keywords":["Hora Eucar\u00edstica","hora santa"],"articleSection":["Hora Eucar\u00edstica"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/regnumchristi.org\/ensena-con-autoridad\/","url":"https:\/\/regnumchristi.org\/ensena-con-autoridad\/","name":"Ense\u00f1a con autoridad (Mc 1,21-28) - Hora Eucar\u00edstica","isPartOf":{"@id":"https:\/\/regnumchristi.org\/#website"},"datePublished":"2021-01-27T11:00:48+00:00","dateModified":"2025-10-03T17:48:39+00:00","description":"El demonio reconoce la presencia del Se\u00f1or, incluso dialoga con \u00c9l; pero Dios tiene la \u00faltima palabra, el poder y con autoridad lo derrota.","breadcrumb":{"@id":"https:\/\/regnumchristi.org\/ensena-con-autoridad\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/regnumchristi.org\/ensena-con-autoridad\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/regnumchristi.org\/ensena-con-autoridad\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/regnumchristi.org\/es\/"},{"@type":"ListItem","position":2,"name":"Ense\u00f1a con autoridad (Mc 1,21-28)"}]},{"@type":"WebSite","@id":"https:\/\/regnumchristi.org\/#website","url":"https:\/\/regnumchristi.org\/","name":"Regnum Christi International","description":"Regnum Christi is a reality of the Catholic Church whose mission is to make present the Kingdom of Christ.","publisher":{"@id":"https:\/\/regnumchristi.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/regnumchristi.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/regnumchristi.org\/#organization","name":"Regnum Christi International","url":"https:\/\/regnumchristi.org\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/regnumchristi.org\/#\/schema\/logo\/image\/","url":"https:\/\/regnumchristi.es\/wp-content\/uploads\/2023\/03\/Favicon-RC_ligh-cuadrado.png","contentUrl":"https:\/\/regnumchristi.es\/wp-content\/uploads\/2023\/03\/Favicon-RC_ligh-cuadrado.png","width":1080,"height":1080,"caption":"Regnum Christi Internacional"},"image":{"@id":"https:\/\/regnumchristi.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/RegnumChristiEspana\/","https:\/\/x.com\/rc_espana","https:\/\/www.instagram.com\/rc_espana\/","https:\/\/es.linkedin.com\/company\/regnumchristiespaa"]},{"@type":"Person","@id":"https:\/\/regnumchristi.org\/#\/schema\/person\/73f2e414269cfbf8edecc2fd90af81f2","name":"Various authors","url":"https:\/\/regnumchristi.org\/en\/author\/jarceocaesc-com\/"}]}},"_links":{"self":[{"href":"https:\/\/regnumchristi.org\/en\/wp-json\/wp\/v2\/posts\/15922","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/regnumchristi.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/regnumchristi.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/regnumchristi.org\/en\/wp-json\/wp\/v2\/users\/49"}],"replies":[{"embeddable":true,"href":"https:\/\/regnumchristi.org\/en\/wp-json\/wp\/v2\/comments?post=15922"}],"version-history":[{"count":1,"href":"https:\/\/regnumchristi.org\/en\/wp-json\/wp\/v2\/posts\/15922\/revisions"}],"predecessor-version":[{"id":113939,"href":"https:\/\/regnumchristi.org\/en\/wp-json\/wp\/v2\/posts\/15922\/revisions\/113939"}],"wp:attachment":[{"href":"https:\/\/regnumchristi.org\/en\/wp-json\/wp\/v2\/media?parent=15922"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/regnumchristi.org\/en\/wp-json\/wp\/v2\/categories?post=15922"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/regnumchristi.org\/en\/wp-json\/wp\/v2\/tags?post=15922"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}