{"id":15966,"date":"2021-02-03T05:00:33","date_gmt":"2021-02-03T11:00:33","guid":{"rendered":"http:\/\/www.regnumchristi.org\/es\/?p=15966"},"modified":"2025-10-03T11:48:39","modified_gmt":"2025-10-03T17:48:39","slug":"mejor-medico-todos","status":"publish","type":"post","link":"https:\/\/regnumchristi.org\/en\/mejor-medico-todos\/","title":{"rendered":"El mejor M\u00e9dico para todos (Mc 1,29-39)"},"content":{"rendered":"<p><span style=\"color: #990000;\"><strong>Gospel:<\/strong><\/span>\u00a0<em>Mc 1,29-39<\/em><br \/>\nAl salir Jes\u00fas de la sinagoga, fue con Santiago y Juan a casa de Sim\u00f3n y de Andr\u00e9s. La suegra de Sim\u00f3n estaba en cama con fiebre. Se lo dijeron a Jes\u00fas y \u00e9l se acerc\u00f3, la tom\u00f3 de la mano y la levant\u00f3. Se le quit\u00f3 la fiebre y se puso a servirles. Al atardecer, cuando el sol se pon\u00eda, le llevaron todos los enfermos y endemoniados. La poblaci\u00f3n entera se agolpaba a la puerta. El san\u00f3 entonces a muchos de diversos males y expuls\u00f3 a muchos demonios, pero a estos no los dejaba hablar, pues sab\u00edan qui\u00e9n era. Muy de madrugada, antes del amanecer, se levant\u00f3, sali\u00f3, se fue a un lugar solitario y all\u00ed comenz\u00f3 a orar. Sim\u00f3n y sus compa\u0144eros fueron en su busca. Cuando lo encontraron, le dijeron: &#8220;Todos te buscan&#8221;. Jes\u00fas les contest\u00f3: &#8220;Vamos a otra parte, a los pueblos vecinos, para predicar tambi\u00e9n all\u00ed, pues para esto he venido&#8221;. Y se fue a predicar en las sinagogas jud\u00edas por toda Galilea, expulsando los demonios.<\/p>\n<p><b><span style=\"color: #990000;\">Fruit:<\/span><\/b>\u00a0Reconocerme\u00a0necesitado de la gracia de Dios.<\/p>\n<p><b><span style=\"color: #990000;\">Guidelines for reflection:<\/span><br \/>\n<\/b>Jesucristo est\u00e1 empezando su vida p\u00fablica. Despu\u00e9s de\u00a030 a\u00f1os oculto en la casa de Nazaret, ahora recorre Palestina predicando\u00a0la buena noticia. Ya desde el inicio se encuentra con una realidad muy humana: la enfermedad, enfermedad del cuerpo y enfermedad del alma. \u00c9l es el mejor M\u00e9dico para todos.<\/p>\n<p><em>1. La enfermedad del mundo<\/em><br \/>\nEn m\u00e1s de una ocasi\u00f3n habremos visto el panorama del mundo que nos rodea. Las noticias que escuchamos cada d\u00eda nos recuerdan gran cantidad de problemas que tiene nuestra sociedad actual: acciones terroristas, atentados, guerras civiles, crisis econ\u00f3micas, contaminaci\u00f3n y peligro ecol\u00f3gico, violencia dom\u00e9stica, asesinato de inocentes, secuestros, abortos y un largu\u00edsimo etc\u00e9tera. La lista puede caer como una losa sobre nuestra esperanza.<\/p>\n<p><em>2. La enfermedad personal<\/em><br \/>\nLa sociedad no es algo que se considere en general, abstracta. La sociedad somos\u00a0t\u00fa, yo, cada uno de los seres humanos. Si la sociedad est\u00e1 en crisis, \u00bfno ser\u00e1 porque quienes la conformamos tambi\u00e9n estamos en crisis? Nos quejamos con facilidad de la violencia imperante en el mundo de hoy; \u00bfno habr\u00e1 tambi\u00e9n violencia en mi vida? Pensemos, por ejemplo, en el modo como trato a mi esposa \/ esposo, a mis hijos \/ padres, a mis compa\u00f1eros de estudio o de trabajo; pensemos con cu\u00e1nta facilidad explota la impaciencia ante un fallo ajeno; pensemos con cu\u00e1nta dificultad perdonamos una ofensa. Resulta f\u00e1cil acusar al mundo de sus males, de la injusticia, de la violencia, del odio, de la falta de amor&#8230; Sin embargo, esos males que veo en la sociedad tienen su ra\u00edz en personas concretas, quiz\u00e1s tambi\u00e9n en m\u00ed. Por eso, si quiero sanar al mundo actual, tengo que\u00a0empezar por sanarme a m\u00ed. El cuerpo est\u00e1 sano cuando todas sus partes est\u00e1n sanas.<\/p>\n<p><em>3. Jes\u00fas, el mejor m\u00e9dico<\/em><br \/>\nEl evangelio que estamos considerando nos ense\u00f1a d\u00f3nde est\u00e1 la mejor soluci\u00f3n: Jes\u00fas, desde el inicio de su ministerio apost\u00f3lico, se encontr\u00f3 con la enfermedad y nos ense\u00f1\u00f3 su deseo de liberarnos de ella. Lleg\u00f3 a la casa de la suegra de Pedro, y con s\u00f3lo tocarla, la fiebre desapareci\u00f3; bendijo a los j\u00f3venes que se agolpan y los cura de toda enfermedad y dolencia. Jes\u00fas ha venido a curar al hombre y a la sociedad de sus males. S\u00f3lo necesita una cosa: que nos acerquemos a \u00c9l, con humildad, reconociendo nuestra debilidad. Un m\u00e9dico, para poder curar una enfermedad, necesita que el enfermo acuda a \u00e9l y le diga: <i>me duele aqu\u00ed; tengo este problema concreto<\/i>. En su gran coraz\u00f3n, Jes\u00fas va todav\u00eda m\u00e1s all\u00e1: no s\u00f3lo cura a los enfermos que acuden a \u00c9l, sino que sale a buscar a otros enfermos, tambi\u00e9n necesitados de \u00e9l. Se levant\u00f3 muy de ma\u00f1ana para rezar, nos dice el evangelio, y a continuaci\u00f3n explica a sus primeros seguidores:\u00a0<i>Vamos a otra parte, a los pueblos vecinos, para predicar tambi\u00e9n all\u00ed, pues para esto he venido<\/i>, para buscar al hombre, necesitado de salud, necesitado de salvaci\u00f3n, en busca de sentido.<\/p>\n<p><b><span style=\"color: #990000;\">Purpose:<\/span><\/b> Como promotor de la paz en mi familia, tratar\u00e9 a todos con especial respeto. Y buscar\u00e9 sanar las heridas de mi vida familiar, acudiendo siempre primero al mejor M\u00e9dico.<\/p>\n<p><em>Listen also to our monthly online retreat.<\/em><\/p>\n<p>You may be interested in: <a href=\"https:\/\/es.catholic.net\/op\/articulos\/41825\/cat\/901\/sanacion-interior-de-las-heridas.html#modal\" target=\"_blank\" rel=\"noopener noreferrer\">Sanaci\u00f3n interior de las heridas<\/a>.<\/p>\n<p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p> [&hellip;]<\/p>\n","protected":false},"author":49,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"_daextrevop_audio_file_creation_date":"","_daextrevop_text_to_speech":"","_daextrevop_document_type":"","footnotes":""},"categories":[3243],"tags":[117,229],"class_list":["post-15966","post","type-post","status-publish","format-standard","hentry","category-hora-eucaristica","tag-hora-eucaristica","tag-hora-santa"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El mejor M\u00e9dico para todos (Mc 1,29-39) - Hora Eucar\u00edstica<\/title>\n<meta name=\"description\" content=\"Desde el inicio, Jesucristo, se encuentra con una realidad muy humana: la enfermedad, del cuerpo y del alma. \u00c9l es el mejor M\u00e9dico.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/regnumchristi.org\/en\/mejor-medico-todos\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El mejor M\u00e9dico para todos (Mc 1,29-39) - Hora Eucar\u00edstica\" \/>\n<meta property=\"og:description\" content=\"Desde el inicio, Jesucristo, se encuentra con una realidad muy humana: la enfermedad, del cuerpo y del alma. \u00c9l es el mejor M\u00e9dico.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/regnumchristi.org\/en\/mejor-medico-todos\/\" \/>\n<meta property=\"og:site_name\" content=\"Regnum Christi Internacional\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/RegnumChristiEspana\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-02-03T11:00:33+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-03T17:48:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/regnumchristi.org\/wp-content\/uploads\/2018\/01\/23915927_1901739026506189_4999863008980230522_n.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Autores varios\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Autores varios\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/en\\\/mejor-medico-todos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/en\\\/mejor-medico-todos\\\/\"},\"author\":{\"name\":\"Autores varios\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#\\\/schema\\\/person\\\/73f2e414269cfbf8edecc2fd90af81f2\"},\"headline\":\"El mejor M\u00e9dico para todos (Mc 1,29-39)\",\"datePublished\":\"2021-02-03T11:00:33+00:00\",\"dateModified\":\"2025-10-03T17:48:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/en\\\/mejor-medico-todos\\\/\"},\"wordCount\":791,\"publisher\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#organization\"},\"keywords\":[\"Hora Eucar\u00edstica\",\"hora santa\"],\"articleSection\":[\"Hora Eucar\u00edstica\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/en\\\/mejor-medico-todos\\\/\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/en\\\/mejor-medico-todos\\\/\",\"name\":\"El mejor M\u00e9dico para todos (Mc 1,29-39) - Hora Eucar\u00edstica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#website\"},\"datePublished\":\"2021-02-03T11:00:33+00:00\",\"dateModified\":\"2025-10-03T17:48:39+00:00\",\"description\":\"Desde el inicio, Jesucristo, se encuentra con una realidad muy humana: la enfermedad, del cuerpo y del alma. \u00c9l es el mejor M\u00e9dico.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/en\\\/mejor-medico-todos\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/regnumchristi.org\\\/en\\\/mejor-medico-todos\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/en\\\/mejor-medico-todos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/regnumchristi.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El mejor M\u00e9dico para todos (Mc 1,29-39)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#website\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/\",\"name\":\"Regnum Christi Internacional\",\"description\":\"El Regnum Christi es una realidad de la Iglesia cat\u00f3lica cuya misi\u00f3n es hacer presente el Reino de Cristo\",\"publisher\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/regnumchristi.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#organization\",\"name\":\"Regnum Christi Internacional\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/regnumchristi.es\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Favicon-RC_ligh-cuadrado.png\",\"contentUrl\":\"https:\\\/\\\/regnumchristi.es\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Favicon-RC_ligh-cuadrado.png\",\"width\":1080,\"height\":1080,\"caption\":\"Regnum Christi Internacional\"},\"image\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/RegnumChristiEspana\\\/\",\"https:\\\/\\\/x.com\\\/rc_espana\",\"https:\\\/\\\/www.instagram.com\\\/rc_espana\\\/\",\"https:\\\/\\\/es.linkedin.com\\\/company\\\/regnumchristiespaa\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#\\\/schema\\\/person\\\/73f2e414269cfbf8edecc2fd90af81f2\",\"name\":\"Autores varios\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/en\\\/author\\\/jarceocaesc-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El mejor M\u00e9dico para todos (Mc 1,29-39) - Hora Eucar\u00edstica","description":"Desde el inicio, Jesucristo, se encuentra con una realidad muy humana: la enfermedad, del cuerpo y del alma. \u00c9l es el mejor M\u00e9dico.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/regnumchristi.org\/en\/mejor-medico-todos\/","og_locale":"en_US","og_type":"article","og_title":"El mejor M\u00e9dico para todos (Mc 1,29-39) - Hora Eucar\u00edstica","og_description":"Desde el inicio, Jesucristo, se encuentra con una realidad muy humana: la enfermedad, del cuerpo y del alma. \u00c9l es el mejor M\u00e9dico.","og_url":"https:\/\/regnumchristi.org\/en\/mejor-medico-todos\/","og_site_name":"Regnum Christi Internacional","article_publisher":"https:\/\/www.facebook.com\/RegnumChristiEspana\/","article_published_time":"2021-02-03T11:00:33+00:00","article_modified_time":"2025-10-03T17:48:39+00:00","og_image":[{"width":960,"height":720,"url":"https:\/\/regnumchristi.org\/wp-content\/uploads\/2018\/01\/23915927_1901739026506189_4999863008980230522_n.jpg","type":"image\/jpeg"}],"author":"Autores varios","twitter_misc":{"Written by":"Autores varios","Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/regnumchristi.org\/en\/mejor-medico-todos\/#article","isPartOf":{"@id":"https:\/\/regnumchristi.org\/en\/mejor-medico-todos\/"},"author":{"name":"Autores varios","@id":"https:\/\/regnumchristi.org\/#\/schema\/person\/73f2e414269cfbf8edecc2fd90af81f2"},"headline":"El mejor M\u00e9dico para todos (Mc 1,29-39)","datePublished":"2021-02-03T11:00:33+00:00","dateModified":"2025-10-03T17:48:39+00:00","mainEntityOfPage":{"@id":"https:\/\/regnumchristi.org\/en\/mejor-medico-todos\/"},"wordCount":791,"publisher":{"@id":"https:\/\/regnumchristi.org\/#organization"},"keywords":["Hora Eucar\u00edstica","hora santa"],"articleSection":["Hora Eucar\u00edstica"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/regnumchristi.org\/en\/mejor-medico-todos\/","url":"https:\/\/regnumchristi.org\/en\/mejor-medico-todos\/","name":"El mejor M\u00e9dico para todos (Mc 1,29-39) - Hora Eucar\u00edstica","isPartOf":{"@id":"https:\/\/regnumchristi.org\/#website"},"datePublished":"2021-02-03T11:00:33+00:00","dateModified":"2025-10-03T17:48:39+00:00","description":"Desde el inicio, Jesucristo, se encuentra con una realidad muy humana: la enfermedad, del cuerpo y del alma. \u00c9l es el mejor M\u00e9dico.","breadcrumb":{"@id":"https:\/\/regnumchristi.org\/en\/mejor-medico-todos\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/regnumchristi.org\/en\/mejor-medico-todos\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/regnumchristi.org\/en\/mejor-medico-todos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/regnumchristi.org\/es\/"},{"@type":"ListItem","position":2,"name":"El mejor M\u00e9dico para todos (Mc 1,29-39)"}]},{"@type":"WebSite","@id":"https:\/\/regnumchristi.org\/#website","url":"https:\/\/regnumchristi.org\/","name":"Regnum Christi International","description":"Regnum Christi is a reality of the Catholic Church whose mission is to make present the Kingdom of Christ.","publisher":{"@id":"https:\/\/regnumchristi.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/regnumchristi.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/regnumchristi.org\/#organization","name":"Regnum Christi International","url":"https:\/\/regnumchristi.org\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/regnumchristi.org\/#\/schema\/logo\/image\/","url":"https:\/\/regnumchristi.es\/wp-content\/uploads\/2023\/03\/Favicon-RC_ligh-cuadrado.png","contentUrl":"https:\/\/regnumchristi.es\/wp-content\/uploads\/2023\/03\/Favicon-RC_ligh-cuadrado.png","width":1080,"height":1080,"caption":"Regnum Christi Internacional"},"image":{"@id":"https:\/\/regnumchristi.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/RegnumChristiEspana\/","https:\/\/x.com\/rc_espana","https:\/\/www.instagram.com\/rc_espana\/","https:\/\/es.linkedin.com\/company\/regnumchristiespaa"]},{"@type":"Person","@id":"https:\/\/regnumchristi.org\/#\/schema\/person\/73f2e414269cfbf8edecc2fd90af81f2","name":"Various authors","url":"https:\/\/regnumchristi.org\/en\/author\/jarceocaesc-com\/"}]}},"_links":{"self":[{"href":"https:\/\/regnumchristi.org\/en\/wp-json\/wp\/v2\/posts\/15966","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/regnumchristi.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/regnumchristi.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/regnumchristi.org\/en\/wp-json\/wp\/v2\/users\/49"}],"replies":[{"embeddable":true,"href":"https:\/\/regnumchristi.org\/en\/wp-json\/wp\/v2\/comments?post=15966"}],"version-history":[{"count":1,"href":"https:\/\/regnumchristi.org\/en\/wp-json\/wp\/v2\/posts\/15966\/revisions"}],"predecessor-version":[{"id":113940,"href":"https:\/\/regnumchristi.org\/en\/wp-json\/wp\/v2\/posts\/15966\/revisions\/113940"}],"wp:attachment":[{"href":"https:\/\/regnumchristi.org\/en\/wp-json\/wp\/v2\/media?parent=15966"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/regnumchristi.org\/en\/wp-json\/wp\/v2\/categories?post=15966"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/regnumchristi.org\/en\/wp-json\/wp\/v2\/tags?post=15966"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}