{"id":16363,"date":"2021-02-24T05:00:41","date_gmt":"2021-02-24T11:00:41","guid":{"rendered":"http:\/\/www.regnumchristi.org\/es\/?p=16363"},"modified":"2025-10-03T11:48:39","modified_gmt":"2025-10-03T17:48:39","slug":"los-buenos-momentos","status":"publish","type":"post","link":"https:\/\/regnumchristi.org\/en\/los-buenos-momentos\/","title":{"rendered":"Los buenos momentos (Mc 9,2-10)"},"content":{"rendered":"<p><strong><span style=\"color: #990000;\">Gospel:<\/span><\/strong>\u00a0<em>Mc 9,2-10<\/em><br \/>\nEn aquel tiempo, Jes\u00fas se llev\u00f3 a Pedro, a Santiago y a Juan, subi\u00f3 con ellos a una monta\u00f1a alta y se transfigur\u00f3 en su presencia. Sus vestidos se volvieron de una blancura deslumbrante, como nadie en el mundo podr\u00eda blanquearlos. Se les aparecieron El\u00edas y Mois\u00e9s conversando con Jes\u00fas. Entonces Pedro tom\u00f3 la palabra y dijo a Jes\u00fas: &#8220;Maestro, \u00a1qu\u00e9 bien se est\u00e1 aqu\u00ed! Hagamos tres chozas: una para ti, otra para Mois\u00e9s y otra para El\u00edas&#8221;. Estaban tan asustados que no sab\u00eda lo que dec\u00eda. Vino entonces una nube que los cubri\u00f3 y se oy\u00f3 una voz desde la nube: &#8220;Este es mi Hijo amado; escuchadlo&#8221;. En ese momento miraron alrededor y vieron s\u00f3lo a Jes\u00fas con ellos. Cuando bajaban de la monta\u00f1a, Jes\u00fas les mand\u00f3 que no contaran a nadie lo que hab\u00edan visto hasta que el Hijo del hombre hubiera resucitado de entre los muertos. Ellos guardaron el secreto, pero discut\u00edan entre s\u00ed qu\u00e9 querr\u00eda decir aquello de resucitar de entre los muertos.<\/p>\n<p><b><span style=\"color: #990000;\">Fruit:<\/span><\/b> Buscar en esta Cuaresma, hacer la experiencia de Cristo misericordioso a trav\u00e9s del sacramento de la reconciliaci\u00f3n.<\/p>\n<p><b><span style=\"color: #cc0000;\"><span style=\"color: #990000;\">Guidelines for reflection:<\/span><br \/>\n<\/span><\/b>Llama la atenci\u00f3n que la Iglesia nos ponga este pasaje evang\u00e9lico de la transfiguraci\u00f3n en un per\u00edodo de conversi\u00f3n, penitencia, sacrificio, como es la Cuaresma. Como madre que es, experta en humanidad, quiere ense\u00f1arnos que la abnegaci\u00f3n por s\u00ed misma no tiene valor; es preciso dulcificarla con el amor a Cristo. Reflexionemos un poco en este pasaje, y veamos qu\u00e9 nos puede ense\u00f1ar en este per\u00edodo de la Cuaresma.<\/p>\n<p><em>1. Cristo se adelanta a la prueba<\/em><br \/>\nSon muchos los\u00a0eruditos de la Biblia\u00a0que localizan este episodio evang\u00e9lico un a\u00f1o antes de la pasi\u00f3n. \u00bfCoincidencia? Algo m\u00e1s, pues, bien es dicho que para el cristiano no hay coincidencia; todo es providencia. Jes\u00fas conoc\u00eda bien a sus ap\u00f3stoles, y sab\u00eda que no entender\u00edan f\u00e1cilmente que el Mes\u00edas, tan largamente esperado, tuviese que morir\u00a0despreciado por los jefes de su pueblo en una cruz. Por ello, como quien prepara un duro momento, regala a Pedro, Santiago y Juan este momento de consolaci\u00f3n, esta clara manifestaci\u00f3n de su divinidad. Sabe que vendr\u00e1n momentos muy duros, y quiere mostrarles claramente su divinidad. \u00a1Cu\u00e1ntas veces nos sucede a nosotros lo mismo! Si miramos hacia el pasado encontramos algunos momentos de consolaci\u00f3n: Jesucristo nos ha cuidado mucho, nos ha hecho ver su amor, nos ha hecho experimentar la alegr\u00eda de haberle conocido. A veces Jes\u00fas nos regala estos\u00a0<i>buenos momentos<\/i>\u00a0para fortalecer nuestra fe, para que ante las dificultades recordemos que \u00c9l es Dios,\u00a0amor pleno\u00a0y entrega incondicional hacia nosotros.<\/p>\n<p><em>2. \u00a1Qu\u00e9 bien se est\u00e1 aqu\u00ed!<\/em><br \/>\nLa reacci\u00f3n de Pedro ante esta consolaci\u00f3n es el reflejo de un coraz\u00f3n generoso: \u00a1Qu\u00e9 bien se est\u00e1 aqu\u00ed, en estos dulces momentos! Tanto entusiasmo tiene que le propone a Jesucristo construir tres chozas y ninguna para quedarse \u00e9l. Est\u00e1 feliz con Cristo, vi\u00e9ndole conversar con Mois\u00e9s y con El\u00edas;\u00a0quisiera que esa experiencia durara para siempre. \u00bfPor qu\u00e9 los acompa\u00f1antes de Jes\u00fas son Mois\u00e9s y El\u00edas? Jesucristo, tambi\u00e9n en estos momentos de consolaci\u00f3n nos quiere transmitir su ense\u00f1anza. El\u00edas representa a los profetas del antiguo testamento y Mois\u00e9s a los patriarcas, los primeros grandes hombres que fueron construyendo la historia de la salvaci\u00f3n. De este modo, Cristo nos ense\u00f1a que \u00c9l es la plenitud del antiguo testamento, el culmen de ese camino de amor que fue recorriendo el pueblo de Israel a lo largo de cientos de a\u00f1os. \u00a1Qu\u00e9 ense\u00f1anza m\u00e1s profunda! El amor de Dios, que se fue manifestando a lo largo del antiguo testamento, llega a su plenitud en Jes\u00fas, principalmente con la pasi\u00f3n y resurrecci\u00f3n que anunciar\u00e1 a estos tres ap\u00f3stoles al bajar del monte Tabor, despu\u00e9s de la transfiguraci\u00f3n.<\/p>\n<p><em>3. El mundo est\u00e1 abajo, esper\u00e1ndote<\/em><br \/>\nA pesar de los buenos deseos de Pedro, este hermoso momento llega a su fin. La nube de Dios Padre les cubre con su sombra, escuchan la voz del Padre: &#8220;<i>Este es mi Hijo amado, escuchadle&#8221;<\/i>, y todo vuelve a la normalidad. Pedro y sus compa\u00f1eros hubieran preferido continuar con esa hermosa revelaci\u00f3n de Jes\u00fas;\u00a0pero Jes\u00fas se les acerca y les dice: \u00a1\u00c1nimo, tenemos que bajar! El mundo est\u00e1 ah\u00ed abajo y tiene muchas necesidades. Esta experiencia no es un regalo para satisfacci\u00f3n y disfrute personal; es un don que deben de transmitir a los hombres, un sentido de la existencia que deben entregar a sus semejantes. En los momentos felices de la vida, en los de consolaci\u00f3n debemos recordar que Dios nos regala esas gracias para transmitirlas a los dem\u00e1s, y en los momentos de oscuridad, recordemos los buenos momentos y confiemos en la luz de Cristo, que sigue brillando por encima de las nubes que cierran nuestro horizonte.<\/p>\n<p><b><span style=\"color: #990000;\">Purpose:<\/span><\/b>\u00a0Recordar\u00e9 los regalos que Dios me han concedido recientemente, los\u00a0agradables y no tan agradables,\u00a0para agradecerlos y transmitir esa\u00a0experiencia de superaci\u00f3n\u00a0a los dem\u00e1s. \u00a1Con Dios todo se puede!<\/p>\n<p><em>Listen also to our monthly online retreat.<\/em><\/p>\n<p>You may be interested in: <a href=\"https:\/\/es.catholic.net\/op\/articulos\/23064\/cat\/304\/la-transfiguracion-cambia-la-vida.html\" target=\"_blank\" rel=\"noopener noreferrer\">La Transfiguraci\u00f3n cambia la vida<\/a>.<\/p>","protected":false},"excerpt":{"rendered":"<p> [&hellip;]<\/p>\n","protected":false},"author":49,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"_daextrevop_audio_file_creation_date":"","_daextrevop_text_to_speech":"","_daextrevop_document_type":"","footnotes":""},"categories":[3243],"tags":[117,229],"class_list":["post-16363","post","type-post","status-publish","format-standard","hentry","category-hora-eucaristica","tag-hora-eucaristica","tag-hora-santa"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Los buenos momentos (Mc 9,2-10) - Hora Eucar\u00edstica<\/title>\n<meta name=\"description\" content=\"La Iglesia nos invita a reflexionar en la transfiguraci\u00f3n como conversi\u00f3n. Todos experimentamos en la vida momentos buenos y momentos malos.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/regnumchristi.org\/en\/los-buenos-momentos\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Los buenos momentos (Mc 9,2-10) - Hora Eucar\u00edstica\" \/>\n<meta property=\"og:description\" content=\"La Iglesia nos invita a reflexionar en la transfiguraci\u00f3n como conversi\u00f3n. Todos experimentamos en la vida momentos buenos y momentos malos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/regnumchristi.org\/en\/los-buenos-momentos\/\" \/>\n<meta property=\"og:site_name\" content=\"Regnum Christi Internacional\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/RegnumChristiEspana\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-02-24T11:00:41+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-03T17:48:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/regnumchristi.org\/wp-content\/uploads\/2018\/02\/horasanta10.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"639\" \/>\n\t<meta property=\"og:image:height\" content=\"428\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Autores varios\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Autores varios\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/los-buenos-momentos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/los-buenos-momentos\\\/\"},\"author\":{\"name\":\"Autores varios\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#\\\/schema\\\/person\\\/73f2e414269cfbf8edecc2fd90af81f2\"},\"headline\":\"Los buenos momentos (Mc 9,2-10)\",\"datePublished\":\"2021-02-24T11:00:41+00:00\",\"dateModified\":\"2025-10-03T17:48:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/los-buenos-momentos\\\/\"},\"wordCount\":931,\"publisher\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#organization\"},\"keywords\":[\"Hora Eucar\u00edstica\",\"hora santa\"],\"articleSection\":[\"Hora Eucar\u00edstica\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/los-buenos-momentos\\\/\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/los-buenos-momentos\\\/\",\"name\":\"Los buenos momentos (Mc 9,2-10) - Hora Eucar\u00edstica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#website\"},\"datePublished\":\"2021-02-24T11:00:41+00:00\",\"dateModified\":\"2025-10-03T17:48:39+00:00\",\"description\":\"La Iglesia nos invita a reflexionar en la transfiguraci\u00f3n como conversi\u00f3n. Todos experimentamos en la vida momentos buenos y momentos malos.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/los-buenos-momentos\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/regnumchristi.org\\\/los-buenos-momentos\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/los-buenos-momentos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/regnumchristi.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Los buenos momentos (Mc 9,2-10)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#website\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/\",\"name\":\"Regnum Christi Internacional\",\"description\":\"El Regnum Christi es una realidad de la Iglesia cat\u00f3lica cuya misi\u00f3n es hacer presente el Reino de Cristo\",\"publisher\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/regnumchristi.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#organization\",\"name\":\"Regnum Christi Internacional\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/regnumchristi.es\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Favicon-RC_ligh-cuadrado.png\",\"contentUrl\":\"https:\\\/\\\/regnumchristi.es\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Favicon-RC_ligh-cuadrado.png\",\"width\":1080,\"height\":1080,\"caption\":\"Regnum Christi Internacional\"},\"image\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/RegnumChristiEspana\\\/\",\"https:\\\/\\\/x.com\\\/rc_espana\",\"https:\\\/\\\/www.instagram.com\\\/rc_espana\\\/\",\"https:\\\/\\\/es.linkedin.com\\\/company\\\/regnumchristiespaa\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#\\\/schema\\\/person\\\/73f2e414269cfbf8edecc2fd90af81f2\",\"name\":\"Autores varios\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/en\\\/author\\\/jarceocaesc-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Los buenos momentos (Mc 9,2-10) - Hora Eucar\u00edstica","description":"La Iglesia nos invita a reflexionar en la transfiguraci\u00f3n como conversi\u00f3n. Todos experimentamos en la vida momentos buenos y momentos malos.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/regnumchristi.org\/en\/los-buenos-momentos\/","og_locale":"en_US","og_type":"article","og_title":"Los buenos momentos (Mc 9,2-10) - Hora Eucar\u00edstica","og_description":"La Iglesia nos invita a reflexionar en la transfiguraci\u00f3n como conversi\u00f3n. Todos experimentamos en la vida momentos buenos y momentos malos.","og_url":"https:\/\/regnumchristi.org\/en\/los-buenos-momentos\/","og_site_name":"Regnum Christi Internacional","article_publisher":"https:\/\/www.facebook.com\/RegnumChristiEspana\/","article_published_time":"2021-02-24T11:00:41+00:00","article_modified_time":"2025-10-03T17:48:39+00:00","og_image":[{"width":639,"height":428,"url":"https:\/\/regnumchristi.org\/wp-content\/uploads\/2018\/02\/horasanta10.jpg","type":"image\/jpeg"}],"author":"Autores varios","twitter_misc":{"Written by":"Autores varios","Est. reading time":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/regnumchristi.org\/los-buenos-momentos\/#article","isPartOf":{"@id":"https:\/\/regnumchristi.org\/los-buenos-momentos\/"},"author":{"name":"Autores varios","@id":"https:\/\/regnumchristi.org\/#\/schema\/person\/73f2e414269cfbf8edecc2fd90af81f2"},"headline":"Los buenos momentos (Mc 9,2-10)","datePublished":"2021-02-24T11:00:41+00:00","dateModified":"2025-10-03T17:48:39+00:00","mainEntityOfPage":{"@id":"https:\/\/regnumchristi.org\/los-buenos-momentos\/"},"wordCount":931,"publisher":{"@id":"https:\/\/regnumchristi.org\/#organization"},"keywords":["Hora Eucar\u00edstica","hora santa"],"articleSection":["Hora Eucar\u00edstica"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/regnumchristi.org\/los-buenos-momentos\/","url":"https:\/\/regnumchristi.org\/los-buenos-momentos\/","name":"Los buenos momentos (Mc 9,2-10) - Hora Eucar\u00edstica","isPartOf":{"@id":"https:\/\/regnumchristi.org\/#website"},"datePublished":"2021-02-24T11:00:41+00:00","dateModified":"2025-10-03T17:48:39+00:00","description":"La Iglesia nos invita a reflexionar en la transfiguraci\u00f3n como conversi\u00f3n. Todos experimentamos en la vida momentos buenos y momentos malos.","breadcrumb":{"@id":"https:\/\/regnumchristi.org\/los-buenos-momentos\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/regnumchristi.org\/los-buenos-momentos\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/regnumchristi.org\/los-buenos-momentos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/regnumchristi.org\/es\/"},{"@type":"ListItem","position":2,"name":"Los buenos momentos (Mc 9,2-10)"}]},{"@type":"WebSite","@id":"https:\/\/regnumchristi.org\/#website","url":"https:\/\/regnumchristi.org\/","name":"Regnum Christi International","description":"Regnum Christi is a reality of the Catholic Church whose mission is to make present the Kingdom of Christ.","publisher":{"@id":"https:\/\/regnumchristi.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/regnumchristi.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/regnumchristi.org\/#organization","name":"Regnum Christi International","url":"https:\/\/regnumchristi.org\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/regnumchristi.org\/#\/schema\/logo\/image\/","url":"https:\/\/regnumchristi.es\/wp-content\/uploads\/2023\/03\/Favicon-RC_ligh-cuadrado.png","contentUrl":"https:\/\/regnumchristi.es\/wp-content\/uploads\/2023\/03\/Favicon-RC_ligh-cuadrado.png","width":1080,"height":1080,"caption":"Regnum Christi Internacional"},"image":{"@id":"https:\/\/regnumchristi.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/RegnumChristiEspana\/","https:\/\/x.com\/rc_espana","https:\/\/www.instagram.com\/rc_espana\/","https:\/\/es.linkedin.com\/company\/regnumchristiespaa"]},{"@type":"Person","@id":"https:\/\/regnumchristi.org\/#\/schema\/person\/73f2e414269cfbf8edecc2fd90af81f2","name":"Various authors","url":"https:\/\/regnumchristi.org\/en\/author\/jarceocaesc-com\/"}]}},"_links":{"self":[{"href":"https:\/\/regnumchristi.org\/en\/wp-json\/wp\/v2\/posts\/16363","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/regnumchristi.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/regnumchristi.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/regnumchristi.org\/en\/wp-json\/wp\/v2\/users\/49"}],"replies":[{"embeddable":true,"href":"https:\/\/regnumchristi.org\/en\/wp-json\/wp\/v2\/comments?post=16363"}],"version-history":[{"count":1,"href":"https:\/\/regnumchristi.org\/en\/wp-json\/wp\/v2\/posts\/16363\/revisions"}],"predecessor-version":[{"id":113942,"href":"https:\/\/regnumchristi.org\/en\/wp-json\/wp\/v2\/posts\/16363\/revisions\/113942"}],"wp:attachment":[{"href":"https:\/\/regnumchristi.org\/en\/wp-json\/wp\/v2\/media?parent=16363"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/regnumchristi.org\/en\/wp-json\/wp\/v2\/categories?post=16363"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/regnumchristi.org\/en\/wp-json\/wp\/v2\/tags?post=16363"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}