{"id":25313,"date":"2020-03-20T17:30:55","date_gmt":"2020-03-20T23:30:55","guid":{"rendered":"https:\/\/www.regnumchristi.org\/es\/?p=25313"},"modified":"2020-03-20T17:30:55","modified_gmt":"2020-03-20T23:30:55","slug":"sabado-21-de-marzo-del-2020-ponerme-en-los-zapatos-del-otro","status":"publish","type":"post","link":"https:\/\/regnumchristi.org\/en\/sabado-21-de-marzo-del-2020-ponerme-en-los-zapatos-del-otro\/","title":{"rendered":"S\u00e1bado 21 de marzo del 2020 &#8211; Ponerme en los zapatos del otro."},"content":{"rendered":"<p>Br. Juli\u00e1n \u00c1lvarez, L.C.<br \/>\nIn the name of the Father and of the Son and of the Holy Spirit. Amen.<br \/>\nChrist, our King, Thy Kingdom come!<\/p>\n<p><strong>Preparatory prayer\u00a0<\/strong><em>(to put me in the presence of God)<\/em><br \/>\nDame, Jes\u00fas, la gracia de abrirte mi coraz\u00f3n para contemplar, sentir y amar como T\u00fa lo haces.<\/p>\n<p><strong>Gospel of the day\u00a0<\/strong><em>(to guide your meditation)<\/em><br \/>\nFrom the Holy Gospel according to Luke 18, 9-14<br \/>\nEn aquel tiempo, Jes\u00fas dijo esta par\u00e1bola sobre algunos que se ten\u00edan por buenos y despreciaban a los dem\u00e1s:<br \/>\n&#8220;Dos hombres subieron al templo para orar: uno era fariseo y el otro, publicano. El fariseo, erguido, oraba as\u00ed en su interior: &#8216;Dios m\u00edo, te doy gracias porque no soy como los dem\u00e1s hombres: ladrones, injustos y ad\u00falteros; tampoco soy como ese publicano. Ayuno dos veces por semana y pago el diezmo de todas mis ganancias&#8217;.<br \/>\nEl publicano, en cambio, se qued\u00f3 lejos y no se atrev\u00eda a levantar los ojos al cielo. Lo \u00fanico que hac\u00eda era golpearse el pecho, diciendo: &#8216;Dios m\u00edo, api\u00e1date de m\u00ed, que soy un pecador&#8217;.<br \/>\nPues bien, yo les aseguro que \u00e9ste baj\u00f3 a su casa justificado y aqu\u00e9l no; porque todo el que se enaltece ser\u00e1 humillado y el que se humilla ser\u00e1 enaltecido&#8221;.<br \/>\nWord of the Lord.<\/p>\n<p><strong>Meditate on what God tells you in the Gospel<\/strong><br \/>\nEn repetidas ocasiones he aprendido a ponerme en los zapatos del otro. Creo que generalmente juzgamos las apariencias pero, las apariencias enga\u00f1an. Creo que tambi\u00e9n, con la gracia de Dios, poco a poco nos vamos dando cuenta de que los hechos concretos que vemos son el \u00faltimo minuto de la pel\u00edcula y es con lo que nos quedamos.<\/p>\n<p>Est\u00e1 en nuestra esencia como cristianos amar a los que est\u00e1n a nuestro lado. Sean como sean, nuestros hijos, nuestros hermanos y, a\u00fan m\u00e1s, a los desconocidos. Cuan diferente ser\u00e1n nuestras acciones si en vez de justificarnos para no ayudar a los dem\u00e1s los presentamos ante Dios y les arrimamos nuestro hombro.<\/p>\n<p>En ocasiones quienes m\u00e1s nos necesitan, incluso los mendigos, m\u00e1s que dinero, necesitan a alguien que les mire a los ojos, necesitan a alguien que les levante y ponga en pie su dignidad. \u00a1Dios necesita de nuestras manos y de nuestros ojos! En vez de criticar, trabajemos por\u00a0 restaurar la dignidad de aquellos que m\u00e1s nos necesitan, que necesitan de Dios.<\/p>\n<p>\u00abConsiderarse justos es dejar a Dios, el \u00fanico justo, fuera de casa. Es tan importante esta actitud de partida que Jes\u00fas nos lo muestra con una comparaci\u00f3n parad\u00f3jica, poniendo juntos en la par\u00e1bola a la persona m\u00e1s piadosa y devota de aquel tiempo, el fariseo, y al pecador p\u00fablico por excelencia, el publicano. Y el juicio se invierte: el que es bueno pero presuntuoso fracasa; a quien es desastroso pero humilde Dios lo exalta. Si nos miramos por dentro con sinceridad, vemos en nosotros a los dos, al publicano y al fariseo. Somos un poco publicanos, por pecadores, y un poco fariseos, por presuntuosos, capaces de justificarnos a nosotros mismos, campeones en justificarnos deliberadamente. Con los dem\u00e1s, a menudo funciona, pero con Dios no. Con Dios el maquillaje no funciona. Recemos para pedir la gracia de sentirnos necesitados de misericordia, interiormente pobres. Tambi\u00e9n para eso nos hace bien estar a menudo con los pobres, para recordarnos que somos pobres, para recordarnos que s\u00f3lo en un clima de pobreza interior act\u00faa la salvaci\u00f3n de Dios.\u00bb (Homil\u00eda de S.S. Francisco, 27 de octubre de 2019).<\/p>\n<p><strong>Dialogue with Christ<\/strong><br \/>\n<em>This is the most important part of your prayer, prepare yourself to talk with much love with the One who loves you.<\/em><\/p>\n<p><strong>Purpose<\/strong><br \/>\n<em>Propose a personal one. The one that involves the most love in response to the Beloved... or, if you believe that this is what God is asking of you, live what is suggested below.<\/em><br \/>\nMirar a los ojos al pr\u00f3ximo mendigo que me encuentre y decirle: \u00abDios te ama\u00bb.<\/p>\n<p><strong>Farewell<\/strong><br \/>\nWe thank You, Lord, for all Your benefits, You who live and reign forever and ever.<br \/>\nAmen.<\/p>\n<p>Christ, our King!<br \/>\nThy Kingdom come!<\/p>\n<p>Most prudent Virgin, Mary, Mother of the Church.<br \/>\nPray for us.<\/p>\n<p>In the name of the Father and of the Son and of the Holy Spirit. Amen.<\/p>","protected":false},"excerpt":{"rendered":"<p> [&hellip;]<\/p>\n","protected":false},"author":33,"featured_media":25315,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"_daextrevop_audio_file_creation_date":"","_daextrevop_text_to_speech":"","_daextrevop_document_type":"","footnotes":""},"categories":[3164],"tags":[],"class_list":["post-25313","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-meditacion-del-dia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>S\u00e1bado 21 de marzo del 2020 - Ponerme en los zapatos del otro. - Regnum Christi Internacional<\/title>\n<meta name=\"description\" content=\"Cuan diferente ser\u00e1n nuestras acciones si en vez de justificarnos para no ayudar a los dem\u00e1s los presentamos ante Dios y les arrimamos nuestro hombro.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/regnumchristi.org\/en\/sabado-21-de-marzo-del-2020-ponerme-en-los-zapatos-del-otro\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"S\u00e1bado 21 de marzo del 2020 - Ponerme en los zapatos del otro. - Regnum Christi Internacional\" \/>\n<meta property=\"og:description\" content=\"Cuan diferente ser\u00e1n nuestras acciones si en vez de justificarnos para no ayudar a los dem\u00e1s los presentamos ante Dios y les arrimamos nuestro hombro.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/regnumchristi.org\/en\/sabado-21-de-marzo-del-2020-ponerme-en-los-zapatos-del-otro\/\" \/>\n<meta property=\"og:site_name\" content=\"Regnum Christi Internacional\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/RegnumChristiEspana\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-03-20T23:30:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/regnumchristi.org\/wp-content\/uploads\/2020\/03\/210320.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"628\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Mar Morales\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mar Morales\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/sabado-21-de-marzo-del-2020-ponerme-en-los-zapatos-del-otro\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/sabado-21-de-marzo-del-2020-ponerme-en-los-zapatos-del-otro\\\/\"},\"author\":{\"name\":\"Mar Morales\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#\\\/schema\\\/person\\\/390cded3fbd2800d0daee38acaecd350\"},\"headline\":\"S\u00e1bado 21 de marzo del 2020 &#8211; Ponerme en los zapatos del otro.\",\"datePublished\":\"2020-03-20T23:30:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/sabado-21-de-marzo-del-2020-ponerme-en-los-zapatos-del-otro\\\/\"},\"wordCount\":758,\"publisher\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/sabado-21-de-marzo-del-2020-ponerme-en-los-zapatos-del-otro\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/regnumchristi.org\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/210320.jpg\",\"articleSection\":[\"Meditaci\u00f3n del d\u00eda\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/sabado-21-de-marzo-del-2020-ponerme-en-los-zapatos-del-otro\\\/\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/sabado-21-de-marzo-del-2020-ponerme-en-los-zapatos-del-otro\\\/\",\"name\":\"S\u00e1bado 21 de marzo del 2020 - Ponerme en los zapatos del otro. - Regnum Christi Internacional\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/sabado-21-de-marzo-del-2020-ponerme-en-los-zapatos-del-otro\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/sabado-21-de-marzo-del-2020-ponerme-en-los-zapatos-del-otro\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/regnumchristi.org\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/210320.jpg\",\"datePublished\":\"2020-03-20T23:30:55+00:00\",\"description\":\"Cuan diferente ser\u00e1n nuestras acciones si en vez de justificarnos para no ayudar a los dem\u00e1s los presentamos ante Dios y les arrimamos nuestro hombro.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/sabado-21-de-marzo-del-2020-ponerme-en-los-zapatos-del-otro\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/regnumchristi.org\\\/sabado-21-de-marzo-del-2020-ponerme-en-los-zapatos-del-otro\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/sabado-21-de-marzo-del-2020-ponerme-en-los-zapatos-del-otro\\\/#primaryimage\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/210320.jpg\",\"contentUrl\":\"https:\\\/\\\/regnumchristi.org\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/210320.jpg\",\"width\":1200,\"height\":628,\"caption\":\"justificamos\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/sabado-21-de-marzo-del-2020-ponerme-en-los-zapatos-del-otro\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/regnumchristi.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"S\u00e1bado 21 de marzo del 2020 &#8211; Ponerme en los zapatos del otro.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#website\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/\",\"name\":\"Regnum Christi Internacional\",\"description\":\"El Regnum Christi es una realidad de la Iglesia cat\u00f3lica cuya misi\u00f3n es hacer presente el Reino de Cristo\",\"publisher\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/regnumchristi.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#organization\",\"name\":\"Regnum Christi Internacional\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/regnumchristi.es\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Favicon-RC_ligh-cuadrado.png\",\"contentUrl\":\"https:\\\/\\\/regnumchristi.es\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Favicon-RC_ligh-cuadrado.png\",\"width\":1080,\"height\":1080,\"caption\":\"Regnum Christi Internacional\"},\"image\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/RegnumChristiEspana\\\/\",\"https:\\\/\\\/x.com\\\/rc_espana\",\"https:\\\/\\\/www.instagram.com\\\/rc_espana\\\/\",\"https:\\\/\\\/es.linkedin.com\\\/company\\\/regnumchristiespaa\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#\\\/schema\\\/person\\\/390cded3fbd2800d0daee38acaecd350\",\"name\":\"Mar Morales\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/en\\\/author\\\/mmoralesserviciosrc-org\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"S\u00e1bado 21 de marzo del 2020 - Ponerme en los zapatos del otro. - Regnum Christi Internacional","description":"Cuan diferente ser\u00e1n nuestras acciones si en vez de justificarnos para no ayudar a los dem\u00e1s los presentamos ante Dios y les arrimamos nuestro hombro.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/regnumchristi.org\/en\/sabado-21-de-marzo-del-2020-ponerme-en-los-zapatos-del-otro\/","og_locale":"en_US","og_type":"article","og_title":"S\u00e1bado 21 de marzo del 2020 - Ponerme en los zapatos del otro. - Regnum Christi Internacional","og_description":"Cuan diferente ser\u00e1n nuestras acciones si en vez de justificarnos para no ayudar a los dem\u00e1s los presentamos ante Dios y les arrimamos nuestro hombro.","og_url":"https:\/\/regnumchristi.org\/en\/sabado-21-de-marzo-del-2020-ponerme-en-los-zapatos-del-otro\/","og_site_name":"Regnum Christi Internacional","article_publisher":"https:\/\/www.facebook.com\/RegnumChristiEspana\/","article_published_time":"2020-03-20T23:30:55+00:00","og_image":[{"width":1200,"height":628,"url":"https:\/\/regnumchristi.org\/wp-content\/uploads\/2020\/03\/210320.jpg","type":"image\/jpeg"}],"author":"Mar Morales","twitter_misc":{"Written by":"Mar Morales","Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/regnumchristi.org\/sabado-21-de-marzo-del-2020-ponerme-en-los-zapatos-del-otro\/#article","isPartOf":{"@id":"https:\/\/regnumchristi.org\/sabado-21-de-marzo-del-2020-ponerme-en-los-zapatos-del-otro\/"},"author":{"name":"Mar Morales","@id":"https:\/\/regnumchristi.org\/#\/schema\/person\/390cded3fbd2800d0daee38acaecd350"},"headline":"S\u00e1bado 21 de marzo del 2020 &#8211; Ponerme en los zapatos del otro.","datePublished":"2020-03-20T23:30:55+00:00","mainEntityOfPage":{"@id":"https:\/\/regnumchristi.org\/sabado-21-de-marzo-del-2020-ponerme-en-los-zapatos-del-otro\/"},"wordCount":758,"publisher":{"@id":"https:\/\/regnumchristi.org\/#organization"},"image":{"@id":"https:\/\/regnumchristi.org\/sabado-21-de-marzo-del-2020-ponerme-en-los-zapatos-del-otro\/#primaryimage"},"thumbnailUrl":"https:\/\/regnumchristi.org\/wp-content\/uploads\/2020\/03\/210320.jpg","articleSection":["Meditaci\u00f3n del d\u00eda"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/regnumchristi.org\/sabado-21-de-marzo-del-2020-ponerme-en-los-zapatos-del-otro\/","url":"https:\/\/regnumchristi.org\/sabado-21-de-marzo-del-2020-ponerme-en-los-zapatos-del-otro\/","name":"S\u00e1bado 21 de marzo del 2020 - Ponerme en los zapatos del otro. - Regnum Christi Internacional","isPartOf":{"@id":"https:\/\/regnumchristi.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/regnumchristi.org\/sabado-21-de-marzo-del-2020-ponerme-en-los-zapatos-del-otro\/#primaryimage"},"image":{"@id":"https:\/\/regnumchristi.org\/sabado-21-de-marzo-del-2020-ponerme-en-los-zapatos-del-otro\/#primaryimage"},"thumbnailUrl":"https:\/\/regnumchristi.org\/wp-content\/uploads\/2020\/03\/210320.jpg","datePublished":"2020-03-20T23:30:55+00:00","description":"Cuan diferente ser\u00e1n nuestras acciones si en vez de justificarnos para no ayudar a los dem\u00e1s los presentamos ante Dios y les arrimamos nuestro hombro.","breadcrumb":{"@id":"https:\/\/regnumchristi.org\/sabado-21-de-marzo-del-2020-ponerme-en-los-zapatos-del-otro\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/regnumchristi.org\/sabado-21-de-marzo-del-2020-ponerme-en-los-zapatos-del-otro\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/regnumchristi.org\/sabado-21-de-marzo-del-2020-ponerme-en-los-zapatos-del-otro\/#primaryimage","url":"https:\/\/regnumchristi.org\/wp-content\/uploads\/2020\/03\/210320.jpg","contentUrl":"https:\/\/regnumchristi.org\/wp-content\/uploads\/2020\/03\/210320.jpg","width":1200,"height":628,"caption":"justificamos"},{"@type":"BreadcrumbList","@id":"https:\/\/regnumchristi.org\/sabado-21-de-marzo-del-2020-ponerme-en-los-zapatos-del-otro\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/regnumchristi.org\/es\/"},{"@type":"ListItem","position":2,"name":"S\u00e1bado 21 de marzo del 2020 &#8211; Ponerme en los zapatos del otro."}]},{"@type":"WebSite","@id":"https:\/\/regnumchristi.org\/#website","url":"https:\/\/regnumchristi.org\/","name":"Regnum Christi International","description":"Regnum Christi is a reality of the Catholic Church whose mission is to make present the Kingdom of Christ.","publisher":{"@id":"https:\/\/regnumchristi.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/regnumchristi.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/regnumchristi.org\/#organization","name":"Regnum Christi International","url":"https:\/\/regnumchristi.org\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/regnumchristi.org\/#\/schema\/logo\/image\/","url":"https:\/\/regnumchristi.es\/wp-content\/uploads\/2023\/03\/Favicon-RC_ligh-cuadrado.png","contentUrl":"https:\/\/regnumchristi.es\/wp-content\/uploads\/2023\/03\/Favicon-RC_ligh-cuadrado.png","width":1080,"height":1080,"caption":"Regnum Christi Internacional"},"image":{"@id":"https:\/\/regnumchristi.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/RegnumChristiEspana\/","https:\/\/x.com\/rc_espana","https:\/\/www.instagram.com\/rc_espana\/","https:\/\/es.linkedin.com\/company\/regnumchristiespaa"]},{"@type":"Person","@id":"https:\/\/regnumchristi.org\/#\/schema\/person\/390cded3fbd2800d0daee38acaecd350","name":"Mar Morales","url":"https:\/\/regnumchristi.org\/en\/author\/mmoralesserviciosrc-org\/"}]}},"_links":{"self":[{"href":"https:\/\/regnumchristi.org\/en\/wp-json\/wp\/v2\/posts\/25313","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/regnumchristi.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/regnumchristi.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/regnumchristi.org\/en\/wp-json\/wp\/v2\/users\/33"}],"replies":[{"embeddable":true,"href":"https:\/\/regnumchristi.org\/en\/wp-json\/wp\/v2\/comments?post=25313"}],"version-history":[{"count":0,"href":"https:\/\/regnumchristi.org\/en\/wp-json\/wp\/v2\/posts\/25313\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/regnumchristi.org\/en\/wp-json\/wp\/v2\/media\/25315"}],"wp:attachment":[{"href":"https:\/\/regnumchristi.org\/en\/wp-json\/wp\/v2\/media?parent=25313"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/regnumchristi.org\/en\/wp-json\/wp\/v2\/categories?post=25313"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/regnumchristi.org\/en\/wp-json\/wp\/v2\/tags?post=25313"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}