{"id":32436,"date":"2022-02-21T09:49:22","date_gmt":"2022-02-21T15:49:22","guid":{"rendered":"https:\/\/www.regnumchristi.org\/es\/?p=32436"},"modified":"2022-02-21T09:49:22","modified_gmt":"2022-02-21T15:49:22","slug":"50-vida-consagrada-dios-fiel","status":"publish","type":"post","link":"https:\/\/regnumchristi.org\/en\/50-vida-consagrada-dios-fiel\/","title":{"rendered":"50 years of consecrated life: \u00abGod is faithful, I have felt him present in my life\u00bb.\u00bb"},"content":{"rendered":"<p>Este a\u00f1o es muy especial para Teresa Vaca, originaria de Zit\u00e1cuaro Michoac\u00e1n, Griselda Su\u00e1rez de Morelia Michoac\u00e1n, y para Mar\u00eda Laura Moreno, de Le\u00f3n Guanajuato, quienes celebran 50 a\u00f1os de vida consagrada en el Regnum Christi. Actualmente son 500 <a href=\"https:\/\/consecratedwomen.org\/\" target=\"_blank\" rel=\"noopener noreferrer\">consecrated members of Regnum Christi<\/a> en el mundo.<\/p>\n<p>Para Mar\u00eda Laura, la situaci\u00f3n de crisis, violencia y falta de felicidad que se vive en la sociedad es debido a la falta de experimentar y vivir la presencia de Dios, algo que a ella a pesar de sentirse d\u00e9bil y muy peque\u00f1a, la ha fortalecido en su apostolado: \u201cMe siento muy peque\u00f1a y d\u00e9bil, pero con Jes\u00fas en m\u00ed soy muy grande y dichosa. Me siento segura en el servicio y en mi apostolado porque tengo la fuerza y la existencia de Dios\u201d.<\/p>\n<p>Ella estudi\u00f3 la licenciatura de Administraci\u00f3n Educacional,\u00a0 tiene tres diplomados y un maestr\u00eda. Fund\u00f3 los centros de consagradas en la Ciudad de M\u00e9xico y Guadalajara. Actualmente, a sus 70 a\u00f1os, sigue trabajando en la evangelizaci\u00f3n de ni\u00f1os y j\u00f3venes en Michoac\u00e1n.<\/p>\n<p>\u201cAnimo a los j\u00f3venes a que se atrevan a vivir la experiencia de Dios, que se acerquen a la Eucarist\u00eda, ella nunca deja indiferente a nadie, hagan un intento, ya luego Dios se encarga de los dem\u00e1s, \u00c9l va transformado a las personas poco a poco y ser\u00e1n felices\u2026\u201d dijo Mar\u00eda Laura.<\/p>\n<p>Griselda Su\u00e1rez, de 71 a\u00f1os, asegura que la comunicaci\u00f3n actual es mucho en redes sociales, y que ah\u00ed se debe llevar el Evangelio, pero sin dejar de tener un experiencia presencial ante la adoraci\u00f3n a la Eucarist\u00eda. Comparte su testimonio: \u201cYo he sentido la presencia de Dios, de manera m\u00e1s fuerte cuando tengo tribulaciones, pero nunca me he alejado de la Eucarist\u00eda, ni de la Virgen Mar\u00eda, as\u00ed nunca te alejas de Dios\u201d. \u00a0Ella fue la sexta de 12 hijos, ha trabajado en la Evangelizaci\u00f3n de ni\u00f1os con clubes del <a href=\"https:\/\/www.ecyd.org\/\" target=\"_blank\" rel=\"noopener noreferrer\">ECYD<\/a> en Espa\u00f1a y M\u00e9xico, actualmente trabaja con j\u00f3venes en una Escuela Normal de Michoac\u00e1n.<\/p>\n<p>Finalmente, Teresa Vaca en estos 50 a\u00f1os de vida consagrada expresa gratitud y anima a las personas a no tener miedo: \u201cLe doy gracias a Dios por haberme llamado a la vida consagrada y por concederme llegar a este 50\u00b0 Aniversario, Dios es fiel, lo he sentido presente en mi vida y es una alegr\u00eda y satisfacci\u00f3n darlo a los dem\u00e1s y llevarlos a \u00c9l. Me siento plenamente realizada y feliz en mi vocaci\u00f3n. La sociedad necesita de personas, ap\u00f3stoles comprometidos para extender el amor de Cristo en el mundo entero. No teman abrirle las puertas a Cristo\u201d. Teresa fue Maestra en Morelia. Ha trabajado con se\u00f1oras y j\u00f3venes en Michoac\u00e1n y Guadalajara, fue directora del Colegio La Paz y responsable de la pastoral en ese colegio. A la fecha sigue llevado despensas y medicamentos a zonas marginadas en Michoac\u00e1n.<\/p>\n<p>La Sociedad de Vida Apost\u00f3lica \u201cConsagradas del Regnum Christi\u201d es una sociedad de derecho pontificio, aprobada por la Santa Sede, cuyos miembros se consagran a Dios en el estado laical mediante los consejos evang\u00e9licos de castidad, pobreza y obediencia. Se dedican enteramente al servicio de la Iglesia y de las personas seg\u00fan el carisma del Regnum Christi y viven vida fraterna en com\u00fan. Realizan su labor de evangelizaci\u00f3n especialmente por:<\/p>\n<ul>\n<li>Anuncio de la fe y difusi\u00f3n de la doctrina cat\u00f3lica.<\/li>\n<li>Formaci\u00f3n cristiana y educaci\u00f3n de la ni\u00f1ez, adolescencia y juventud.<\/li>\n<li>La formaci\u00f3n de la mujer y de personas consagradas.<\/li>\n<li>Promoci\u00f3n del matrimonio y la familia.<\/li>\n<li>Pastoral vocacional.<\/li>\n<li>Evangelizaci\u00f3n de los ambientes profesionales, de la cultura y de los medios de comunicaci\u00f3n social.<\/li>\n<li>Promoci\u00f3n de la justicia social.<\/li>\n<li>Pr\u00e1ctica de las obras de misericordia.<\/li>\n<\/ul>\n<p>Source: <a href=\"https:\/\/www.regnumchristi.mx\/\" target=\"_blank\" rel=\"noopener noreferrer\">regnumchristi.mx<\/a><\/p>\n<h5><a href=\"https:\/\/regnumchristi.org\/en\/consecrated\/\" target=\"_blank\" rel=\"noopener noreferrer\"><em>Consecrated Women of Regnum Christi<\/em><\/a><\/h5>","protected":false},"excerpt":{"rendered":"<p> [&hellip;]<\/p>\n","protected":false},"author":49,"featured_media":32437,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"_daextrevop_audio_file_creation_date":"","_daextrevop_text_to_speech":"","_daextrevop_document_type":"","footnotes":""},"categories":[3031,1687],"tags":[1023,90,124],"class_list":["post-32436","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-destacadas","category-noticias","tag-50-aniversario","tag-consagradas-del-regnum-christi","tag-vocacion"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>50 a\u00f1os de vida consagrada: Dios es fiel, lo he sentido presente en mi vida<\/title>\n<meta name=\"description\" content=\"Teresa, Griselda y Mar\u00eda Laura celebraron 50 a\u00f1os de vida consagrada en el Regnum Christi. &quot;Dios es fiel, lo he sentido presente en mi vida&quot;.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/regnumchristi.org\/en\/50-vida-consagrada-dios-fiel\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"50 a\u00f1os de vida consagrada: Dios es fiel, lo he sentido presente en mi vida\" \/>\n<meta property=\"og:description\" content=\"Teresa, Griselda y Mar\u00eda Laura celebraron 50 a\u00f1os de vida consagrada en el Regnum Christi. &quot;Dios es fiel, lo he sentido presente en mi vida&quot;.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/regnumchristi.org\/en\/50-vida-consagrada-dios-fiel\/\" \/>\n<meta property=\"og:site_name\" content=\"Regnum Christi Internacional\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/RegnumChristiEspana\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-02-21T15:49:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/regnumchristi.org\/wp-content\/uploads\/2022\/02\/Captura-de-Pantalla-2022-02-22-a-las-11.49.52-a.m-1024x631.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"631\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Autores varios\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Autores varios\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/50-vida-consagrada-dios-fiel\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/50-vida-consagrada-dios-fiel\\\/\"},\"author\":{\"name\":\"Autores varios\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#\\\/schema\\\/person\\\/73f2e414269cfbf8edecc2fd90af81f2\"},\"headline\":\"50 a\u00f1os de vida consagrada: \u00abDios es fiel, lo he sentido presente en mi vida\u00bb\",\"datePublished\":\"2022-02-21T15:49:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/50-vida-consagrada-dios-fiel\\\/\"},\"wordCount\":684,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/50-vida-consagrada-dios-fiel\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/regnumchristi.org\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/Captura-de-Pantalla-2022-02-22-a-las-11.49.52-a.m.png\",\"keywords\":[\"50 aniversario\",\"Consagradas del Regnum Christi\",\"vocaci\u00f3n\"],\"articleSection\":[\"Destacadas\",\"Noticias\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/regnumchristi.org\\\/50-vida-consagrada-dios-fiel\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/50-vida-consagrada-dios-fiel\\\/\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/50-vida-consagrada-dios-fiel\\\/\",\"name\":\"50 a\u00f1os de vida consagrada: Dios es fiel, lo he sentido presente en mi vida\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/50-vida-consagrada-dios-fiel\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/50-vida-consagrada-dios-fiel\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/regnumchristi.org\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/Captura-de-Pantalla-2022-02-22-a-las-11.49.52-a.m.png\",\"datePublished\":\"2022-02-21T15:49:22+00:00\",\"description\":\"Teresa, Griselda y Mar\u00eda Laura celebraron 50 a\u00f1os de vida consagrada en el Regnum Christi. \\\"Dios es fiel, lo he sentido presente en mi vida\\\".\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/50-vida-consagrada-dios-fiel\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/regnumchristi.org\\\/50-vida-consagrada-dios-fiel\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/50-vida-consagrada-dios-fiel\\\/#primaryimage\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/Captura-de-Pantalla-2022-02-22-a-las-11.49.52-a.m.png\",\"contentUrl\":\"https:\\\/\\\/regnumchristi.org\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/Captura-de-Pantalla-2022-02-22-a-las-11.49.52-a.m.png\",\"width\":1419,\"height\":875,\"caption\":\"50 a\u00f1os de vida consagrada: \u00abDios es fiel, lo he sentido presente en mi vida\u00bb\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/50-vida-consagrada-dios-fiel\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/regnumchristi.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"50 a\u00f1os de vida consagrada: \u00abDios es fiel, lo he sentido presente en mi vida\u00bb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#website\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/\",\"name\":\"Regnum Christi Internacional\",\"description\":\"El Regnum Christi es una realidad de la Iglesia cat\u00f3lica cuya misi\u00f3n es hacer presente el Reino de Cristo\",\"publisher\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/regnumchristi.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#organization\",\"name\":\"Regnum Christi Internacional\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/regnumchristi.es\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Favicon-RC_ligh-cuadrado.png\",\"contentUrl\":\"https:\\\/\\\/regnumchristi.es\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Favicon-RC_ligh-cuadrado.png\",\"width\":1080,\"height\":1080,\"caption\":\"Regnum Christi Internacional\"},\"image\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/RegnumChristiEspana\\\/\",\"https:\\\/\\\/x.com\\\/rc_espana\",\"https:\\\/\\\/www.instagram.com\\\/rc_espana\\\/\",\"https:\\\/\\\/es.linkedin.com\\\/company\\\/regnumchristiespaa\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#\\\/schema\\\/person\\\/73f2e414269cfbf8edecc2fd90af81f2\",\"name\":\"Autores varios\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/en\\\/author\\\/jarceocaesc-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"50 a\u00f1os de vida consagrada: Dios es fiel, lo he sentido presente en mi vida","description":"Teresa, Griselda y Mar\u00eda Laura celebraron 50 a\u00f1os de vida consagrada en el Regnum Christi. \"Dios es fiel, lo he sentido presente en mi vida\".","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/regnumchristi.org\/en\/50-vida-consagrada-dios-fiel\/","og_locale":"en_US","og_type":"article","og_title":"50 a\u00f1os de vida consagrada: Dios es fiel, lo he sentido presente en mi vida","og_description":"Teresa, Griselda y Mar\u00eda Laura celebraron 50 a\u00f1os de vida consagrada en el Regnum Christi. \"Dios es fiel, lo he sentido presente en mi vida\".","og_url":"https:\/\/regnumchristi.org\/en\/50-vida-consagrada-dios-fiel\/","og_site_name":"Regnum Christi Internacional","article_publisher":"https:\/\/www.facebook.com\/RegnumChristiEspana\/","article_published_time":"2022-02-21T15:49:22+00:00","og_image":[{"width":1024,"height":631,"url":"https:\/\/regnumchristi.org\/wp-content\/uploads\/2022\/02\/Captura-de-Pantalla-2022-02-22-a-las-11.49.52-a.m-1024x631.png","type":"image\/png"}],"author":"Autores varios","twitter_misc":{"Written by":"Autores varios","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/regnumchristi.org\/50-vida-consagrada-dios-fiel\/#article","isPartOf":{"@id":"https:\/\/regnumchristi.org\/50-vida-consagrada-dios-fiel\/"},"author":{"name":"Autores varios","@id":"https:\/\/regnumchristi.org\/#\/schema\/person\/73f2e414269cfbf8edecc2fd90af81f2"},"headline":"50 a\u00f1os de vida consagrada: \u00abDios es fiel, lo he sentido presente en mi vida\u00bb","datePublished":"2022-02-21T15:49:22+00:00","mainEntityOfPage":{"@id":"https:\/\/regnumchristi.org\/50-vida-consagrada-dios-fiel\/"},"wordCount":684,"commentCount":0,"publisher":{"@id":"https:\/\/regnumchristi.org\/#organization"},"image":{"@id":"https:\/\/regnumchristi.org\/50-vida-consagrada-dios-fiel\/#primaryimage"},"thumbnailUrl":"https:\/\/regnumchristi.org\/wp-content\/uploads\/2022\/02\/Captura-de-Pantalla-2022-02-22-a-las-11.49.52-a.m.png","keywords":["50 aniversario","Consagradas del Regnum Christi","vocaci\u00f3n"],"articleSection":["Destacadas","Noticias"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/regnumchristi.org\/50-vida-consagrada-dios-fiel\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/regnumchristi.org\/50-vida-consagrada-dios-fiel\/","url":"https:\/\/regnumchristi.org\/50-vida-consagrada-dios-fiel\/","name":"50 a\u00f1os de vida consagrada: Dios es fiel, lo he sentido presente en mi vida","isPartOf":{"@id":"https:\/\/regnumchristi.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/regnumchristi.org\/50-vida-consagrada-dios-fiel\/#primaryimage"},"image":{"@id":"https:\/\/regnumchristi.org\/50-vida-consagrada-dios-fiel\/#primaryimage"},"thumbnailUrl":"https:\/\/regnumchristi.org\/wp-content\/uploads\/2022\/02\/Captura-de-Pantalla-2022-02-22-a-las-11.49.52-a.m.png","datePublished":"2022-02-21T15:49:22+00:00","description":"Teresa, Griselda y Mar\u00eda Laura celebraron 50 a\u00f1os de vida consagrada en el Regnum Christi. \"Dios es fiel, lo he sentido presente en mi vida\".","breadcrumb":{"@id":"https:\/\/regnumchristi.org\/50-vida-consagrada-dios-fiel\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/regnumchristi.org\/50-vida-consagrada-dios-fiel\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/regnumchristi.org\/50-vida-consagrada-dios-fiel\/#primaryimage","url":"https:\/\/regnumchristi.org\/wp-content\/uploads\/2022\/02\/Captura-de-Pantalla-2022-02-22-a-las-11.49.52-a.m.png","contentUrl":"https:\/\/regnumchristi.org\/wp-content\/uploads\/2022\/02\/Captura-de-Pantalla-2022-02-22-a-las-11.49.52-a.m.png","width":1419,"height":875,"caption":"50 a\u00f1os de vida consagrada: \u00abDios es fiel, lo he sentido presente en mi vida\u00bb"},{"@type":"BreadcrumbList","@id":"https:\/\/regnumchristi.org\/50-vida-consagrada-dios-fiel\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/regnumchristi.org\/es\/"},{"@type":"ListItem","position":2,"name":"50 a\u00f1os de vida consagrada: \u00abDios es fiel, lo he sentido presente en mi vida\u00bb"}]},{"@type":"WebSite","@id":"https:\/\/regnumchristi.org\/#website","url":"https:\/\/regnumchristi.org\/","name":"Regnum Christi International","description":"Regnum Christi is a reality of the Catholic Church whose mission is to make present the Kingdom of Christ.","publisher":{"@id":"https:\/\/regnumchristi.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/regnumchristi.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/regnumchristi.org\/#organization","name":"Regnum Christi International","url":"https:\/\/regnumchristi.org\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/regnumchristi.org\/#\/schema\/logo\/image\/","url":"https:\/\/regnumchristi.es\/wp-content\/uploads\/2023\/03\/Favicon-RC_ligh-cuadrado.png","contentUrl":"https:\/\/regnumchristi.es\/wp-content\/uploads\/2023\/03\/Favicon-RC_ligh-cuadrado.png","width":1080,"height":1080,"caption":"Regnum Christi Internacional"},"image":{"@id":"https:\/\/regnumchristi.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/RegnumChristiEspana\/","https:\/\/x.com\/rc_espana","https:\/\/www.instagram.com\/rc_espana\/","https:\/\/es.linkedin.com\/company\/regnumchristiespaa"]},{"@type":"Person","@id":"https:\/\/regnumchristi.org\/#\/schema\/person\/73f2e414269cfbf8edecc2fd90af81f2","name":"Various authors","url":"https:\/\/regnumchristi.org\/en\/author\/jarceocaesc-com\/"}]}},"_links":{"self":[{"href":"https:\/\/regnumchristi.org\/en\/wp-json\/wp\/v2\/posts\/32436","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/regnumchristi.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/regnumchristi.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/regnumchristi.org\/en\/wp-json\/wp\/v2\/users\/49"}],"replies":[{"embeddable":true,"href":"https:\/\/regnumchristi.org\/en\/wp-json\/wp\/v2\/comments?post=32436"}],"version-history":[{"count":0,"href":"https:\/\/regnumchristi.org\/en\/wp-json\/wp\/v2\/posts\/32436\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/regnumchristi.org\/en\/wp-json\/wp\/v2\/media\/32437"}],"wp:attachment":[{"href":"https:\/\/regnumchristi.org\/en\/wp-json\/wp\/v2\/media?parent=32436"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/regnumchristi.org\/en\/wp-json\/wp\/v2\/categories?post=32436"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/regnumchristi.org\/en\/wp-json\/wp\/v2\/tags?post=32436"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}