{"id":36039,"date":"2023-03-31T20:00:35","date_gmt":"2023-04-01T02:00:35","guid":{"rendered":"https:\/\/www.regnumchristi.org\/es\/?p=36039"},"modified":"2023-08-02T13:26:46","modified_gmt":"2023-08-02T19:26:46","slug":"sabado-1-de-abril-de-2023-de-la-muerte-de-uno-a-la-salvacion-de-todos","status":"publish","type":"post","link":"https:\/\/regnumchristi.org\/en\/sabado-1-de-abril-de-2023-de-la-muerte-de-uno-a-la-salvacion-de-todos\/","title":{"rendered":"S\u00e1bado 1\u00b0 de abril de 2023 \u2013 \u00abDe la muerte de \u201cUno\u201d a la salvaci\u00f3n de todos\u00bb"},"content":{"rendered":"<p><i><span data-contrast=\"none\">Ang\u00e9lica Roa, CRC<\/span><\/i><\/p>\n<p><span data-contrast=\"none\">In the name of the Father and of the Son and of the Holy Spirit.<\/span><br \/>\n<span data-contrast=\"none\">Amen.<\/span><\/p>\n<p><span data-contrast=\"none\">Christ, our King.<\/span><br \/>\n<span data-contrast=\"none\">Thy Kingdom come!<\/span><\/p>\n<p><span style=\"color: #800000;\"><b>Preparatory prayer <\/b><\/span><i><span data-contrast=\"none\">(to put me in the presence of God)<\/span><\/i><\/p>\n<p><span data-contrast=\"none\">Se\u00f1or, \u00a1c\u00f3mo nos cuesta entrar en la Semana Santa! Distintos sentimientos nos llenan el coraz\u00f3n: miedo a sufrir, deseos de alejarnos y olvidarnos de todo, deseos de que todo pase r\u00e1pido\u2026, pero tambi\u00e9n nos vienen deseos de acercarnos a ti y a vivir estos d\u00edas a tu lado, deseos a abrirnos a tu gracia, a tu redenci\u00f3n\u2026 Me pongo bajo el manto de tu Madre, para poder perseverar en mi deseo de estar contigo.<\/span><\/p>\n<p><span style=\"color: #800000;\"><b>Gospel of the day <\/b><\/span><i><span data-contrast=\"none\">(to guide your meditation)<\/span><\/i><br \/>\n<span data-contrast=\"none\">Del santo Evangelio seg\u00fan san Juan 11, 45-57<\/span><\/p>\n<p><span data-contrast=\"none\">En aquel tiempo, muchos jud\u00edos que hab\u00edan venido a casa de Mar\u00eda, al ver lo que hab\u00eda hecho Jes\u00fas, creyeron en \u00e9l. Pero algunos acudieron a los fariseos y les contaron lo que hab\u00eda hecho Jes\u00fas. Los sumos sacerdotes y los fariseos convocaron el Sanedr\u00edn y dijeron: &#8220;\u00bfQu\u00e9 hacemos? Este hombre hace muchos signos. Si lo dejamos seguir, todos creer\u00e1n en \u00e9l, y vendr\u00e1n los romanos y nos destruir\u00e1n el lugar santo y la naci\u00f3n&#8221;. Uno de ellos, Caif\u00e1s, que era sumo sacerdote aquel a\u00f1o, les dijo: &#8220;Vosotros no entend\u00e9is ni palabra; no comprend\u00e9is que os conviene que uno muera por el pueblo, y que no perezca la naci\u00f3n entera&#8221;. Esto no lo dijo por propio impulso, sino que, por ser sumo sacerdote aquel a\u00f1o, habl\u00f3 prof\u00e9ticamente, anunciando que Jes\u00fas iba a morir por la naci\u00f3n; y no s\u00f3lo por la naci\u00f3n, sino tambi\u00e9n para reunir a los hijos de Dios dispersos. Y aquel d\u00eda decidieron darle muerte. Por eso Jes\u00fas ya no andaba p\u00fablicamente con los jud\u00edos, sino que se retir\u00f3 a la regi\u00f3n vecina al desierto, a una ciudad llamada Efra\u00edn, y pasaba all\u00ed el tiempo con los disc\u00edpulos. Se acercaba la Pascua de los jud\u00edos, y muchos de aquella regi\u00f3n sub\u00edan a Jerusal\u00e9n, antes de la Pascua, para purificarse. Buscaban a Jes\u00fas y, estando en el templo, se preguntaban: &#8220;\u00bfQu\u00e9 os parece? \u00bfNo vendr\u00e1 a la fiesta?&#8221;. Los sumos sacerdotes y fariseos hab\u00edan mandado que el que se enterase de d\u00f3nde estaba les avisara para prenderlo.<\/span><\/p>\n<p><i><span data-contrast=\"none\">Word of the Lord<\/span><\/i><span data-contrast=\"none\">.<\/span><\/p>\n<p><span style=\"color: #800000;\"><b>Meditate on what God tells you in the Gospel<\/b><\/span><\/p>\n<p><i><span data-contrast=\"none\">&#8220;\u00bfQu\u00e9 hacemos? Este hombre hace muchos signos. Si lo dejamos seguir, todos creer\u00e1n en \u00e9l, y vendr\u00e1n los romanos y nos destruir\u00e1n el lugar santo y la naci\u00f3n&#8221;<\/span><\/i><span data-contrast=\"none\">. \u00bfPor qu\u00e9 nos asustamos cuando vemos grandes signos y milagros? \u00bfPor qu\u00e9 tememos cuando se nos presenta algo grandioso y maravilloso, que amenaza nuestras peque\u00f1eces? \u00bfPor qu\u00e9 temblamos ante un Dios que se hace hombre para venir a salvarnos? \u00a1Cu\u00e1ntas contradicciones encontramos en nuestros corazones! Deseamos la felicidad, la paz, el bien, la prosperidad\u2026 y cuando Dios mismo nos lo ofrece, nos cerramos y nos apegamos a nuestras pobres y falsas seguridades.<\/span><\/p>\n<p><i><span data-contrast=\"none\">&#8220;Vosotros no entend\u00e9is ni palabra; no comprend\u00e9is que os conviene que uno muera por el pueblo, y que no perezca la naci\u00f3n entera&#8221;.<\/span><\/i><span data-contrast=\"none\"> Estas palabras, dichas por Caif\u00e1s \u2013Sumo sacerdote aquel a\u00f1o\u2013 revelaron el sentido de la muerte redentora del Hijo de Dios.<\/span><\/p>\n<p><span data-contrast=\"none\">\u00a1T\u00fa muerte, Jes\u00fas, tu muerte ignominiosa, a cambio de nuestra vida verdadera! S\u00f3lo el ofrecimiento de la vida del Hijo divino, amado del Padre, pod\u00eda reparar la ofensa infinita del hombre con su pecado, que lo llevaba a la muerte. Este ha sido el camino de nuestra Redenci\u00f3n, para poder volver a la casa del Padre. La vida del Hijo a cambio de nuestra vida.<\/span><\/p>\n<p><span data-contrast=\"none\">Jes\u00fas, quiero acompa\u00f1arte estos d\u00edas de Pasi\u00f3n, acogiendo la salvaci\u00f3n que nos alcanzas, queriendo, as\u00ed, ser un consuelo para ti; queriendo ser uno de aquellos que hace fructificar tu Sangre redentora. Y quisiera unirme a ti, con mi peque\u00f1a cruz, para que, como tanto lo anhelas, mis hermanos y hermanas \u2013la naci\u00f3n entera\u2013 se salve.<\/span><\/p>\n<p><i><span data-contrast=\"none\">\u00abEn el Crucificado vemos a Dios humillado, al Omnipotente reducido a un despojo. Y con la gracia del estupor entendemos que, acogiendo a quien es descartado, acerc\u00e1ndonos a quien es humillado por la vida, amamos a Jes\u00fas. Porque \u00c9l est\u00e1 en los \u00faltimos, en los rechazados, en aquellos que nuestra cultura farisaica condena\u00bb. (S.S. Francisco, Homil\u00eda del 28 de marzo de 2021).<\/span><\/i><\/p>\n<p><span style=\"color: #800000;\"><b>Dialogue with Christ<\/b><\/span><\/p>\n<p><i><span data-contrast=\"none\">This is the most important part of your prayer, prepare yourself to talk with much love with the One who loves you.<\/span><\/i><\/p>\n<p><span style=\"color: #800000;\"><b>Purpose<\/b><\/span><\/p>\n<p><i><span data-contrast=\"none\">Propose a personal one. The one that involves the most love in response to the Beloved... or, if you believe that this is what God is asking of you, live what is suggested below.<\/span><\/i><\/p>\n<p><span data-contrast=\"none\">Dedicar un ratito a pensar c\u00f3mo quiero acompa\u00f1ar a Cristo en su Pasi\u00f3n, en esta Semana Santa (con medios concretos que dispongan interiormente mi alma para estar con \u00c9l).<\/span><\/p>\n<p><span style=\"color: #800000;\"><b>Farewell<\/b><\/span><\/p>\n<p><span data-contrast=\"none\">We thank you, Lord, for all your benefits, you who live and reign forever and ever.<\/span><br \/>\n<span data-contrast=\"none\">Amen.<\/span><\/p>\n<p><span data-contrast=\"none\">Christ, our King!<\/span><br \/>\n<span data-contrast=\"none\">Thy Kingdom come!<\/span><\/p>\n<p><span data-contrast=\"none\">Most prudent Virgin, Mary, Mother of the Church.<\/span><br \/>\n<span data-contrast=\"none\">Pray for us.<\/span><\/p>\n<p><span data-contrast=\"none\">In the name of the Father and of the Son and of the Holy Spirit.<\/span><br \/>\n<span data-contrast=\"none\">Amen.<\/span><\/p>","protected":false},"excerpt":{"rendered":"<p> [&hellip;]<\/p>\n","protected":false},"author":58,"featured_media":36177,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"_daextrevop_audio_file_creation_date":"","_daextrevop_text_to_speech":"","_daextrevop_document_type":"","footnotes":""},"categories":[3164],"tags":[3162,3163,3067],"class_list":["post-36039","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-meditacion-del-dia","tag-evangelio","tag-meditacion","tag-reflexion"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>S\u00e1bado 1\u00b0 de abril de 2023 \u2013 \u00abDe la muerte de \u201cUno\u201d a la salvaci\u00f3n de todos\u00bb - Regnum Christi Internacional<\/title>\n<meta name=\"description\" content=\"Me pongo bajo el manto de tu Madre, para poder perseverar en mi deseo de estar contigo. Se\u00f1or, \u00a1c\u00f3mo nos cuesta entrar en la Semana Santa!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/regnumchristi.org\/en\/sabado-1-de-abril-de-2023-de-la-muerte-de-uno-a-la-salvacion-de-todos\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"S\u00e1bado 1\u00b0 de abril de 2023 \u2013 \u00abDe la muerte de \u201cUno\u201d a la salvaci\u00f3n de todos\u00bb - Regnum Christi Internacional\" \/>\n<meta property=\"og:description\" content=\"Me pongo bajo el manto de tu Madre, para poder perseverar en mi deseo de estar contigo. Se\u00f1or, \u00a1c\u00f3mo nos cuesta entrar en la Semana Santa!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/regnumchristi.org\/en\/sabado-1-de-abril-de-2023-de-la-muerte-de-uno-a-la-salvacion-de-todos\/\" \/>\n<meta property=\"og:site_name\" content=\"Regnum Christi Internacional\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/RegnumChristiEspana\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-04-01T02:00:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-08-02T19:26:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/regnumchristi.org\/wp-content\/uploads\/2023\/03\/imagenes_meditaciones_diarias_1abr.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"563\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Meditaciones Diarias\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Meditaciones Diarias\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/sabado-1-de-abril-de-2023-de-la-muerte-de-uno-a-la-salvacion-de-todos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/sabado-1-de-abril-de-2023-de-la-muerte-de-uno-a-la-salvacion-de-todos\\\/\"},\"author\":{\"name\":\"Meditaciones Diarias\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#\\\/schema\\\/person\\\/a5ad8b3c4bd3cb3a0abe8a1474fe8f0a\"},\"headline\":\"S\u00e1bado 1\u00b0 de abril de 2023 \u2013 \u00abDe la muerte de \u201cUno\u201d a la salvaci\u00f3n de todos\u00bb\",\"datePublished\":\"2023-04-01T02:00:35+00:00\",\"dateModified\":\"2023-08-02T19:26:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/sabado-1-de-abril-de-2023-de-la-muerte-de-uno-a-la-salvacion-de-todos\\\/\"},\"wordCount\":946,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/sabado-1-de-abril-de-2023-de-la-muerte-de-uno-a-la-salvacion-de-todos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/regnumchristi.org\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/imagenes_meditaciones_diarias_1abr.jpg\",\"keywords\":[\"Evangelio\",\"meditaci\u00f3n\",\"Reflexi\u00f3n\"],\"articleSection\":[\"Meditaci\u00f3n del d\u00eda\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/regnumchristi.org\\\/sabado-1-de-abril-de-2023-de-la-muerte-de-uno-a-la-salvacion-de-todos\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/sabado-1-de-abril-de-2023-de-la-muerte-de-uno-a-la-salvacion-de-todos\\\/\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/sabado-1-de-abril-de-2023-de-la-muerte-de-uno-a-la-salvacion-de-todos\\\/\",\"name\":\"S\u00e1bado 1\u00b0 de abril de 2023 \u2013 \u00abDe la muerte de \u201cUno\u201d a la salvaci\u00f3n de todos\u00bb - Regnum Christi Internacional\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/sabado-1-de-abril-de-2023-de-la-muerte-de-uno-a-la-salvacion-de-todos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/sabado-1-de-abril-de-2023-de-la-muerte-de-uno-a-la-salvacion-de-todos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/regnumchristi.org\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/imagenes_meditaciones_diarias_1abr.jpg\",\"datePublished\":\"2023-04-01T02:00:35+00:00\",\"dateModified\":\"2023-08-02T19:26:46+00:00\",\"description\":\"Me pongo bajo el manto de tu Madre, para poder perseverar en mi deseo de estar contigo. Se\u00f1or, \u00a1c\u00f3mo nos cuesta entrar en la Semana Santa!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/sabado-1-de-abril-de-2023-de-la-muerte-de-uno-a-la-salvacion-de-todos\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/regnumchristi.org\\\/sabado-1-de-abril-de-2023-de-la-muerte-de-uno-a-la-salvacion-de-todos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/sabado-1-de-abril-de-2023-de-la-muerte-de-uno-a-la-salvacion-de-todos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/imagenes_meditaciones_diarias_1abr.jpg\",\"contentUrl\":\"https:\\\/\\\/regnumchristi.org\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/imagenes_meditaciones_diarias_1abr.jpg\",\"width\":900,\"height\":563},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/sabado-1-de-abril-de-2023-de-la-muerte-de-uno-a-la-salvacion-de-todos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/regnumchristi.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"S\u00e1bado 1\u00b0 de abril de 2023 \u2013 \u00abDe la muerte de \u201cUno\u201d a la salvaci\u00f3n de todos\u00bb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#website\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/\",\"name\":\"Regnum Christi Internacional\",\"description\":\"El Regnum Christi es una realidad de la Iglesia cat\u00f3lica cuya misi\u00f3n es hacer presente el Reino de Cristo\",\"publisher\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/regnumchristi.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#organization\",\"name\":\"Regnum Christi Internacional\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/regnumchristi.es\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Favicon-RC_ligh-cuadrado.png\",\"contentUrl\":\"https:\\\/\\\/regnumchristi.es\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Favicon-RC_ligh-cuadrado.png\",\"width\":1080,\"height\":1080,\"caption\":\"Regnum Christi Internacional\"},\"image\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/RegnumChristiEspana\\\/\",\"https:\\\/\\\/x.com\\\/rc_espana\",\"https:\\\/\\\/www.instagram.com\\\/rc_espana\\\/\",\"https:\\\/\\\/es.linkedin.com\\\/company\\\/regnumchristiespaa\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#\\\/schema\\\/person\\\/a5ad8b3c4bd3cb3a0abe8a1474fe8f0a\",\"name\":\"Meditaciones Diarias\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/en\\\/author\\\/meditacionesd\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"S\u00e1bado 1\u00b0 de abril de 2023 \u2013 \u00abDe la muerte de \u201cUno\u201d a la salvaci\u00f3n de todos\u00bb - Regnum Christi Internacional","description":"Me pongo bajo el manto de tu Madre, para poder perseverar en mi deseo de estar contigo. Se\u00f1or, \u00a1c\u00f3mo nos cuesta entrar en la Semana Santa!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/regnumchristi.org\/en\/sabado-1-de-abril-de-2023-de-la-muerte-de-uno-a-la-salvacion-de-todos\/","og_locale":"en_US","og_type":"article","og_title":"S\u00e1bado 1\u00b0 de abril de 2023 \u2013 \u00abDe la muerte de \u201cUno\u201d a la salvaci\u00f3n de todos\u00bb - Regnum Christi Internacional","og_description":"Me pongo bajo el manto de tu Madre, para poder perseverar en mi deseo de estar contigo. Se\u00f1or, \u00a1c\u00f3mo nos cuesta entrar en la Semana Santa!","og_url":"https:\/\/regnumchristi.org\/en\/sabado-1-de-abril-de-2023-de-la-muerte-de-uno-a-la-salvacion-de-todos\/","og_site_name":"Regnum Christi Internacional","article_publisher":"https:\/\/www.facebook.com\/RegnumChristiEspana\/","article_published_time":"2023-04-01T02:00:35+00:00","article_modified_time":"2023-08-02T19:26:46+00:00","og_image":[{"width":900,"height":563,"url":"https:\/\/regnumchristi.org\/wp-content\/uploads\/2023\/03\/imagenes_meditaciones_diarias_1abr.jpg","type":"image\/jpeg"}],"author":"Meditaciones Diarias","twitter_misc":{"Written by":"Meditaciones Diarias","Est. reading time":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/regnumchristi.org\/sabado-1-de-abril-de-2023-de-la-muerte-de-uno-a-la-salvacion-de-todos\/#article","isPartOf":{"@id":"https:\/\/regnumchristi.org\/sabado-1-de-abril-de-2023-de-la-muerte-de-uno-a-la-salvacion-de-todos\/"},"author":{"name":"Meditaciones Diarias","@id":"https:\/\/regnumchristi.org\/#\/schema\/person\/a5ad8b3c4bd3cb3a0abe8a1474fe8f0a"},"headline":"S\u00e1bado 1\u00b0 de abril de 2023 \u2013 \u00abDe la muerte de \u201cUno\u201d a la salvaci\u00f3n de todos\u00bb","datePublished":"2023-04-01T02:00:35+00:00","dateModified":"2023-08-02T19:26:46+00:00","mainEntityOfPage":{"@id":"https:\/\/regnumchristi.org\/sabado-1-de-abril-de-2023-de-la-muerte-de-uno-a-la-salvacion-de-todos\/"},"wordCount":946,"commentCount":0,"publisher":{"@id":"https:\/\/regnumchristi.org\/#organization"},"image":{"@id":"https:\/\/regnumchristi.org\/sabado-1-de-abril-de-2023-de-la-muerte-de-uno-a-la-salvacion-de-todos\/#primaryimage"},"thumbnailUrl":"https:\/\/regnumchristi.org\/wp-content\/uploads\/2023\/03\/imagenes_meditaciones_diarias_1abr.jpg","keywords":["Evangelio","meditaci\u00f3n","Reflexi\u00f3n"],"articleSection":["Meditaci\u00f3n del d\u00eda"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/regnumchristi.org\/sabado-1-de-abril-de-2023-de-la-muerte-de-uno-a-la-salvacion-de-todos\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/regnumchristi.org\/sabado-1-de-abril-de-2023-de-la-muerte-de-uno-a-la-salvacion-de-todos\/","url":"https:\/\/regnumchristi.org\/sabado-1-de-abril-de-2023-de-la-muerte-de-uno-a-la-salvacion-de-todos\/","name":"S\u00e1bado 1\u00b0 de abril de 2023 \u2013 \u00abDe la muerte de \u201cUno\u201d a la salvaci\u00f3n de todos\u00bb - Regnum Christi Internacional","isPartOf":{"@id":"https:\/\/regnumchristi.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/regnumchristi.org\/sabado-1-de-abril-de-2023-de-la-muerte-de-uno-a-la-salvacion-de-todos\/#primaryimage"},"image":{"@id":"https:\/\/regnumchristi.org\/sabado-1-de-abril-de-2023-de-la-muerte-de-uno-a-la-salvacion-de-todos\/#primaryimage"},"thumbnailUrl":"https:\/\/regnumchristi.org\/wp-content\/uploads\/2023\/03\/imagenes_meditaciones_diarias_1abr.jpg","datePublished":"2023-04-01T02:00:35+00:00","dateModified":"2023-08-02T19:26:46+00:00","description":"Me pongo bajo el manto de tu Madre, para poder perseverar en mi deseo de estar contigo. Se\u00f1or, \u00a1c\u00f3mo nos cuesta entrar en la Semana Santa!","breadcrumb":{"@id":"https:\/\/regnumchristi.org\/sabado-1-de-abril-de-2023-de-la-muerte-de-uno-a-la-salvacion-de-todos\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/regnumchristi.org\/sabado-1-de-abril-de-2023-de-la-muerte-de-uno-a-la-salvacion-de-todos\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/regnumchristi.org\/sabado-1-de-abril-de-2023-de-la-muerte-de-uno-a-la-salvacion-de-todos\/#primaryimage","url":"https:\/\/regnumchristi.org\/wp-content\/uploads\/2023\/03\/imagenes_meditaciones_diarias_1abr.jpg","contentUrl":"https:\/\/regnumchristi.org\/wp-content\/uploads\/2023\/03\/imagenes_meditaciones_diarias_1abr.jpg","width":900,"height":563},{"@type":"BreadcrumbList","@id":"https:\/\/regnumchristi.org\/sabado-1-de-abril-de-2023-de-la-muerte-de-uno-a-la-salvacion-de-todos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/regnumchristi.org\/es\/"},{"@type":"ListItem","position":2,"name":"S\u00e1bado 1\u00b0 de abril de 2023 \u2013 \u00abDe la muerte de \u201cUno\u201d a la salvaci\u00f3n de todos\u00bb"}]},{"@type":"WebSite","@id":"https:\/\/regnumchristi.org\/#website","url":"https:\/\/regnumchristi.org\/","name":"Regnum Christi International","description":"Regnum Christi is a reality of the Catholic Church whose mission is to make present the Kingdom of Christ.","publisher":{"@id":"https:\/\/regnumchristi.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/regnumchristi.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/regnumchristi.org\/#organization","name":"Regnum Christi International","url":"https:\/\/regnumchristi.org\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/regnumchristi.org\/#\/schema\/logo\/image\/","url":"https:\/\/regnumchristi.es\/wp-content\/uploads\/2023\/03\/Favicon-RC_ligh-cuadrado.png","contentUrl":"https:\/\/regnumchristi.es\/wp-content\/uploads\/2023\/03\/Favicon-RC_ligh-cuadrado.png","width":1080,"height":1080,"caption":"Regnum Christi Internacional"},"image":{"@id":"https:\/\/regnumchristi.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/RegnumChristiEspana\/","https:\/\/x.com\/rc_espana","https:\/\/www.instagram.com\/rc_espana\/","https:\/\/es.linkedin.com\/company\/regnumchristiespaa"]},{"@type":"Person","@id":"https:\/\/regnumchristi.org\/#\/schema\/person\/a5ad8b3c4bd3cb3a0abe8a1474fe8f0a","name":"Daily Meditations","url":"https:\/\/regnumchristi.org\/en\/author\/meditacionesd\/"}]}},"_links":{"self":[{"href":"https:\/\/regnumchristi.org\/en\/wp-json\/wp\/v2\/posts\/36039","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/regnumchristi.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/regnumchristi.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/regnumchristi.org\/en\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/regnumchristi.org\/en\/wp-json\/wp\/v2\/comments?post=36039"}],"version-history":[{"count":1,"href":"https:\/\/regnumchristi.org\/en\/wp-json\/wp\/v2\/posts\/36039\/revisions"}],"predecessor-version":[{"id":93839,"href":"https:\/\/regnumchristi.org\/en\/wp-json\/wp\/v2\/posts\/36039\/revisions\/93839"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/regnumchristi.org\/en\/wp-json\/wp\/v2\/media\/36177"}],"wp:attachment":[{"href":"https:\/\/regnumchristi.org\/en\/wp-json\/wp\/v2\/media?parent=36039"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/regnumchristi.org\/en\/wp-json\/wp\/v2\/categories?post=36039"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/regnumchristi.org\/en\/wp-json\/wp\/v2\/tags?post=36039"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}