{"id":36140,"date":"2023-04-01T20:00:54","date_gmt":"2023-04-02T02:00:54","guid":{"rendered":"https:\/\/www.regnumchristi.org\/es\/?p=36140"},"modified":"2023-08-02T13:26:46","modified_gmt":"2023-08-02T19:26:46","slug":"domingo-2-de-abril-de-2023-domingo-de-ramos-deseo-celebrar-la-pascua-en-tu-casa","status":"publish","type":"post","link":"https:\/\/regnumchristi.org\/en\/domingo-2-de-abril-de-2023-domingo-de-ramos-deseo-celebrar-la-pascua-en-tu-casa\/","title":{"rendered":"Domingo 2 de abril de 2023 \u2013 Domingo de Ramos \u2013 \u00abDeseo celebrar la Pascua en tu casa\u00bb"},"content":{"rendered":"<p><em>Michelle Gow, CRC\u00a0<\/em><\/p>\n<p><span data-contrast=\"none\">In the name of the Father and of the Son and of the Holy Spirit.<\/span><br \/>\n<span data-contrast=\"none\">Amen.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"none\">Christ, our King.<\/span><br \/>\n<span data-contrast=\"none\">Thy Kingdom come!<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><span style=\"color: #800000;\"><b>Preparatory prayer <\/b><\/span><i><span data-contrast=\"none\">(to put me in the presence of God)<\/span><\/i><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"none\">Jes\u00fas, quiero entrar contigo en esta semana, la m\u00e1s santa de todas las semanas. Me pongo en tu presencia para ver lo que T\u00fa ves, sentir lo que T\u00fa sientes y abandonarme a la voluntad del Padre como T\u00fa te abandonaste.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><span style=\"color: #800000;\"><b>Gospel of the day <\/b><\/span><i><span data-contrast=\"none\">(to guide your meditation)<\/span><\/i><br \/>\n<span data-contrast=\"none\">Del santo Evangelio seg\u00fan san Mateo 26, 14-27,66<\/span><\/p>\n<p class=\"p1\">En aquel tiempo uno de los Doce, llamado Judas Iscariote, fue a los sumos sacerdotes y les propuso: &#8220;\u00bfQu\u00e9 est\u00e1is dispuestos a darme si os lo entrego?\u201d. Ellos se ajustaron con \u00e9l en treinta monedas. Y desde entonces andaba buscando ocasi\u00f3n propicia para entregarlo. El primer d\u00eda de los \u00e1zimos se acercaron los disc\u00edpulos a Jes\u00fas y le preguntaron: &#8220;\u00bfD\u00f3nde quieres que te preparemos la cena de Pascua?\u201d. \u00c9l contest\u00f3: &#8220;Id a casa de Fulano y decidle: &#8216;El Maestro dice: Mi momento est\u00e1 cerca; deseo celebrar la Pascua en tu casa con mis disc\u00edpulos'&#8221;. Los disc\u00edpulos cumplieron las instrucciones de Jes\u00fas y prepararon la Pascua. Al atardecer se puso a la mesa con los Doce. Mientras com\u00edan dijo: &#8220;Os aseguro que uno de vosotros me va a entregar&#8221;. Ellos, consternados, se pusieron a preguntarle uno tras otro: &#8220;\u00bfSoy yo acaso, Se\u00f1or?\u201d. \u00c9l respondi\u00f3: &#8220;El que ha mojado en la misma fuente que yo, \u00e9se me va a entregar. El Hijo del hombre se va como est\u00e1 escrito de \u00e9l; pero \u00a1ay del que va a entregar al Hijo del hombre!, m\u00e1s le valdr\u00eda no haber nacido&#8221;. Entonces pregunt\u00f3 Judas, el que lo iba a entregar: &#8220;\u00bfSoy yo acaso, Maestro?&#8221;. \u00c9l respondi\u00f3: &#8220;As\u00ed es&#8221;. Durante la cena, Jes\u00fas cogi\u00f3 pan, pronunci\u00f3 la bendici\u00f3n, lo parti\u00f3 y lo dio a los disc\u00edpulos diciendo: &#8220;Tomad, comed: esto es mi cuerpo&#8221;. Y cogiendo un c\u00e1liz pronunci\u00f3 la acci\u00f3n de gracias y se lo pas\u00f3 diciendo: &#8220;Bebed todos; porque \u00e9sta es mi sangre, sangre de la alianza derramada por todos para el perd\u00f3n de los pecados. Y os digo que no beber\u00e9 m\u00e1s del fruto de la vid hasta el d\u00eda que beba con vosotros el vino nuevo en el Reino de mi Padre\u201d. Cantaron el salmo y salieron para el monte de los Olivos. Entonces Jes\u00fas les dijo: &#8220;Esta noche vais a caer todos por mi causa, porque est\u00e1 escrito: &#8220;Herir\u00e9 al pastor y se dispersar\u00e1n las ovejas del reba\u00f1o&#8221;. Pero cuando resucite, ir\u00e9 antes que vosotros a Galilea&#8221;. Pedro replic\u00f3: &#8220;Aunque todos caigan por tu causa, yo jam\u00e1s caer\u00e9&#8221;. Jes\u00fas les dijo: &#8220;Te aseguro que esta noche, antes que el gallo cante tres veces, me negar\u00e1s&#8221;. Pedro le replic\u00f3: &#8220;Aunque tenga que morir contigo, no te negar\u00e9&#8221;. Y lo mismo dec\u00edan los dem\u00e1s disc\u00edpulos. Entonces Jes\u00fas fue con ellos a un huerto, llamado Getseman\u00ed, y les dijo: &#8220;Sentaos aqu\u00ed mientras voy all\u00e1 a orar&#8221;. Y llev\u00e1ndose a Pedro y a los dos hijos de Zebedeo, empez\u00f3 a entristecerse y a angustiarse. Entonces dijo: &#8220;Me muero de tristeza: quedaos aqu\u00ed y velad conmigo&#8221;. Y adelant\u00e1ndose un poco cay\u00f3 rostro en tierra y oraba diciendo: &#8220;Padre m\u00edo, si es posible, que pase y se aleje d m\u00ed ese c\u00e1liz. pero no se haga lo que yo quiero, sino lo que t\u00fa quieres&#8221;. Y se acerc\u00f3 a los disc\u00edpulos y los encontr\u00f3 dormidos. Dijo a Pedro: &#8220;\u00bfNo hab\u00e9is podido velar una hora conmigo? Velad y orad para no caer en la tentaci\u00f3n, pues el esp\u00edritu es decidido, pero la carne es d\u00e9bil&#8221;. De nuevo se apart\u00f3 por segunda vez y oraba diciendo: &#8220;Padre m\u00edo, si este c\u00e1liz no puede pasar sin que yo lo beba, h\u00e1gase tu voluntad&#8221;. Y viniendo otra vez, los encontr\u00f3 dormidos, porque estaban muertos de sue\u00f1o. Dej\u00e1ndolos de nuevo, por tercera vez oraba repitiendo las mismas palabras. Luego se acerc\u00f3 a sus disc\u00edpulos y les dijo: &#8220;Ya pod\u00e9is dormir y descansar. Mirad, est\u00e1 cerca la hora y el Hijo del hombre va a ser entregado en manos de los pecadores. \u00a1Levantaos, vamos! Ya est\u00e1 cerca el que me entrega&#8221;. Todav\u00eda estaba hablando, cuando apareci\u00f3 Judas, uno de los Doce, acompa\u00f1ado de un tropel de gente, con espadas y palos, mandado por los sumos sacerdotes y los senadores del pueblo. El traidor les hab\u00eda dado esta contrase\u00f1a: &#8220;Al que yo bese, \u00e9se es: detenedlo&#8221;. Despu\u00e9s se acerc\u00f3 a Jes\u00fas y le dijo: &#8220;\u00a1Salve, Maestro!\u201d. Y lo bes\u00f3. Pero Jes\u00fas le contest\u00f3: &#8220;Amigo, \u00bfa qu\u00e9 vienes?\u201d. Entonces se acercaron a Jes\u00fas y le echaron mano para detenerlo. Uno de los que estaban con \u00e9l agarr\u00f3 la espada, la desenvain\u00f3 y de un tajo le cort\u00f3 la oreja al criado del sumo sacerdote. Jes\u00fas le dijo: &#8220;Envaina la espada: quien usa espada, a espada morir\u00e1. \u00bfPiensas t\u00fa que no puedo acudir a mi Padre? \u00c9l me mandar\u00eda en seguida m\u00e1s de doce legiones de \u00e1ngeles. Pero entonces no se cumplir\u00eda la Escritura que dice que esto tiene que pasar&#8221;. Entonces dijo Jes\u00fas a la gente: &#8220;Hab\u00e9is salido a prenderme con espadas y palos como a un bandido? A diario me sentaba en el templo a ense\u00f1ar y, sin embargo, no me detuvisteis&#8221;. Todo esto ocurri\u00f3 para que se cumpliera lo que escribieron los profetas. En aquel momento todos los disc\u00edpulos lo abandonaron y huyeron. Los que detuvieron a Jes\u00fas lo llevaron a casa de Caif\u00e1s, el sumo sacerdote, donde se hab\u00eda reunido los letrados y los senadores. Pedro lo segu\u00eda de lejos hasta el palacio del sumo sacerdote y, entrando dentro, se sent\u00f3 con los criados para ver en qu\u00e9 paraba aquello. Los sumos sacerdotes y el consejo en pleno buscaban un falso testimonio contra Jes\u00fas para condenarlo a muerte y no lo encontraban, a pesar de los muchos falsos testigos que comparec\u00edan. Finalmente, comparecieron dos que declararon: &#8220;Este ha dicho: &#8220;Puedo destruir el templo de Dios y reconstruirlo en tres d\u00edas&#8221;. El sumo sacerdote se puso en pie y le dijo: &#8220;\u00bfNo tienes nada que responder? \u00bfQu\u00e9 son estos cargos que levantan contra ti?\u201d. Pero Jes\u00fas callaba. Y el sumo sacerdote le dijo: &#8220;Te conjuro por Dios vivo a que nos digas si t\u00fa eres el Mes\u00edas, el Hijo de Dios&#8221;. Jes\u00fas respondi\u00f3: &#8220;T\u00fa lo has dicho. M\u00e1s a\u00fan, yo os digo: desde ahora ver\u00e9is que el Hijo del hombre est\u00e1 sentado a la derecha del Todopoderoso y que viene sobre las nubes del cielo. Entonces el sumo sacerdote rasg\u00f3 sus vestiduras diciendo: &#8220;Ha blasfemado. \u00bfQu\u00e9 necesidad tenemos ya de testigos? Acab\u00e1is de o\u00edr la blasfemia. \u00bfQu\u00e9 decid\u00eds?\u201d. Y ellos contestaron: &#8220;Es reo de muerte&#8221;. Entonces le escupieron a la cara y lo abofetearon; otros lo golpearon diciendo: &#8220;Haz de profeta, Mes\u00edas; dinos qui\u00e9n te ha pegado&#8221;. Pedro estaba sentado fuera en el patio y se le acerc\u00f3 una criada y le dijo: &#8220;Tambi\u00e9n t\u00fa andabas con Jes\u00fas el Galileo&#8221;. \u00c9l lo neg\u00f3 delante de todos diciendo: &#8220;No s\u00e9 qu\u00e9 quieres decir&#8221;. Y al salir al portal lo vio otra y dijo a los que estaban all\u00ed: &#8220;Este andaba con Jes\u00fas el Nazareno&#8221;. Otra vez neg\u00f3 \u00e9l con juramento: &#8220;No conozco a ese hombre&#8221;. Poco despu\u00e9s se acercaron los que estaban all\u00ed y dijeron: &#8220;Seguro; t\u00fa tambi\u00e9n eres de ellos, se te nota en el acento&#8221;. Entonces \u00e9l se puso a echar maldiciones y a jurar diciendo: &#8220;No conozco a ese hombre&#8221;. Y en seguida cant\u00f3 el gallo. Pedro se acord\u00f3 de aquellas palabras de Jes\u00fas: &#8220;Antes de que cante el gallo me negar\u00e1s tres veces&#8221;. Y saliendo afuera, llor\u00f3 amargamente. Al hacerse de d\u00eda, todos los sumos sacerdotes y los senadores del pueblo se reunieron para preparar la condena a muerte de Jes\u00fas. Y at\u00e1ndolo lo llevaron y lo entregaron a Pilato, el gobernador. Entonces el traidor sinti\u00f3 remordimiento y devolvi\u00f3 las treinta monedas de plata a los sumos sacerdotes y senadores diciendo: &#8220;He pecado, he entregado a la muerte a un inocente&#8221;. Pero ellos dijeron: &#8220;\u00bfA nosotros qu\u00e9? \u00a1All\u00e1 t\u00fa!\u201d. \u00c9l, arrojando las monedas en el templo, se march\u00f3; y fue y se ahorc\u00f3. Los sacerdotes, recogiendo las monedas, dijeron: &#8220;No es l\u00edcito echarlas en el arca de las ofrendas porque son precio de sangre&#8221;. Y, despu\u00e9s de discutirlo, compraron con ellas el Campo del Alfarero para cementerio de forasteros. Por eso aquel campo se llama todav\u00eda &#8220;Campo de Sangre&#8221;. As\u00ed se cumpli\u00f3 lo escrito por Jerem\u00edas el profeta: &#8220;Y tomaron las treinta monedas de plata, el precio de uno que fue tasado, seg\u00fan la tasa de los hijos de Israel, y pagaron con ellas el Campo del Alfarero, como me lo hab\u00eda ordenado el Se\u00f1or&#8221;. Jes\u00fas fue llevado ante el gobernador, y el gobernador le pregunt\u00f3: &#8220;\u00bfEres t\u00fa el rey de los jud\u00edos?\u201d. Jes\u00fas respondi\u00f3: &#8220;T\u00fa lo dices&#8221;. Y mientras la acusaban los sumos sacerdotes y los senadores no contestaba nada. Entonces Pilato le pregunt\u00f3: &#8220;\u00bfNo oyes cu\u00e1ntos cargos presentan contra ti?\u201d. Como no contestaba a ninguna pregunta, el gobernador estaba muy extra\u00f1ado. Por la fiesta, el gobernador sol\u00eda soltar un preso, el que la gente quisiera. Ten\u00eda entonces un preso famoso, llamado Barrab\u00e1s. Cuando la gente acudi\u00f3, dijo Pilato: &#8220;\u00bfA qui\u00e9n quer\u00e9is que os suelte, a Barrab\u00e1s o a Jes\u00fas, a quien llaman Mes\u00edas?\u201d. Pues sab\u00eda que se lo hab\u00edan entregado por envidia. Y mientras estaba sentado en el tribunal, su mujer le mand\u00f3 a decir: &#8220;No te metas con ese justo porque esta noche he sufrido mucho so\u00f1ando con \u00e9l\u201d. Pero los sumos sacerdotes y los senadores convencieron a la gente que pidieran el indulto de Barrab\u00e1s y la muerte de Jes\u00fas. El gobernador pregunt\u00f3: &#8220;\u00bfA cu\u00e1l de los dos quer\u00e9is que os suelte?\u201d. Ellos dijeron: &#8220;A Barrab\u00e1s&#8221;. Pilato les pregunt\u00f3: &#8220;\u00bfY qu\u00e9 hago con Jes\u00fas, llamado el Mes\u00edas?\u201d. Contestaron todos: &#8220;\u00a1Que lo crucifiquen!\u201d. Pilato insisti\u00f3: &#8220;Pues \u00bfqu\u00e9 mal ha hecho?\u201d. Pero ellos gritaban m\u00e1s fuerte: &#8220;\u00a1Que lo crucifiquen!\u201d. Al ver Pilato que todo era in\u00fatil y que, al contrario, se estaba formando un tumulto, tom\u00f3 agua y se lav\u00f3 las manos en presencia del pueblo, diciendo: &#8220;Soy inocente de esta sangre. \u00a1All\u00e1 vosotros!\u201d. Y el pueblo contest\u00f3: &#8220;\u00a1Su sangre caiga sobre nosotros y sobre nuestros hijos!&#8221; Entonces les solt\u00f3 a Barrab\u00e1s; y a Jes\u00fas, despu\u00e9s de azotado, lo entreg\u00f3 para que lo crucificaran. Los soldados del gobernador se llevaron a Jes\u00fas al pretorio y reunieron alrededor de \u00e9l a toda la compa\u00f1\u00eda: lo desnudaron y le pusieron un manto de color p\u00farpura y trenzando una corona de espinas se la ci\u00f1eron a la cabeza y le pusieron una ca\u00f1a en la mano derecha. Y, doblando ante \u00e9l la rodilla, se burlaban de \u00e9l diciendo: &#8220;\u00a1Salve, rey de los jud\u00edos&#8221;! Luego lo escup\u00edan, le quitaban la ca\u00f1a y le golpeaban con ella en la cabeza. Y terminada la burla, le quitaron el manto, le pusieron su ropa y lo llevaron a crucificar. Al salir, encontraron un hombre de Cirene, llamado Sim\u00f3n, y lo forzaron a que llevara la cruz. Cuando llegaron al lugar llamado G\u00f3lgota (que quiere decir &#8220;La Calavera&#8221;), le dieron a beber vino mezclado con hiel; \u00e9l lo, prob\u00f3, pero no quiso beberlo. Despu\u00e9s de crucificarlo, se repartieron su ropa ech\u00e1ndola a suertes y luego se sentaron a custodiarlo. Encima de la cabeza colocaron un letrero con la acusaci\u00f3n: &#8220;Este es el Rey de los Jud\u00edos&#8221;. Crucificaron con \u00e9l a dos bandidos, uno a la derecha y otro a la izquierda. los que pasaban, lo injuriaban y dec\u00edan meneando la cabeza: &#8220;T\u00fa que destru\u00edas el templo y lo reconstru\u00edas en tres d\u00edas, s\u00e1lvate a ti mismo; si eres Hijo de Dios, baja de la cruz&#8221;. Los sumos sacerdotes con los letrados y los senadores se burlaban tambi\u00e9n diciendo: &#8220;A otros ha salvado y \u00e9l no se puede salvar. \u00bfNo es el rey de Israel? Que baje ahora de la cruz y le creeremos. \u00bfNo ha confiado en Dios? Si tanto lo quiere Dios, que lo libre ahora. \u00bfNo dec\u00eda que era Hijo de Dios?&#8221;. Hasta los bandidos que estaban crucificados con \u00e9l lo insultaban. Desde el mediod\u00eda hasta la media tarde vinieron tinieblas sobre toda aquella regi\u00f3n. A media tarde, Jes\u00fas grit\u00f3: &#8220;El\u00ed, El\u00ed, lam\u00e1 sabaktan\u00ed&#8221; (Es decir: &#8220;Dios m\u00edo, Dios m\u00edo, \u00bfpor qu\u00e9 me has abandonado?&#8221;) Al o\u00edrlo algunos de los que estaban all\u00ed dijeron: &#8220;A El\u00edas llama \u00e9ste&#8221;. Uno de ellos fue corriendo; en seguida cogi\u00f3 una esponja empapada en vinagre y, sujet\u00e1ndola en una ca\u00f1a, le dio de beber. los dem\u00e1s dec\u00edan: &#8220;D\u00e9jalo, a ver si viene El\u00edas a salvarlo&#8221;. Jes\u00fas dio otro grito fuerte y exhal\u00f3 el esp\u00edritu. Entonces el velo del templo se rasg\u00f3 en dos de arriba abajo; la tierra tembl\u00f3, las rocas se rasgaron, las tumbas se abrieron y muchos cuerpos de santos que hab\u00edan muerto resucitaron. Despu\u00e9s que \u00e9l resucit\u00f3 salieron de las tumbas, entraron en la Ciudad Santa y se aparecieron a muchos. El centuri\u00f3n y sus hombres, que custodiaban a Jes\u00fas, al ver el terremoto y lo que pasaba dijeron aterrorizados: &#8220;Realmente \u00e9ste era Hijo de Dios\u201d. Hab\u00eda all\u00ed muchas mujeres que miraban desde lejos, aquellas que hab\u00edan seguido a Jes\u00fas desde Galilea para atenderle; entre ellas, Mar\u00eda Magdalena y Mar\u00eda, la madre de Santiago y Jos\u00e9, y la madre de los Zebedeos. Al anochecer lleg\u00f3 un hombre rico de Arimatea, llamado Jos\u00e9, que era tambi\u00e9n disc\u00edpulo de Jes\u00fas. \u00c9ste acudi\u00f3 a Pilato a pedirle el cuerpo de Jes\u00fas. Y Pilato mand\u00f3 que se lo entregaran. Jos\u00e9, tomando el cuerpo de Jes\u00fas, lo envolvi\u00f3 en una s\u00e1bana limpia, lo puso en el sepulcro nuevo que se hab\u00eda excavado en una roca, rod\u00f3 una piedra grande a la entrada del sepulcro y se march\u00f3. Mar\u00eda Magdalena y la otra Mar\u00eda se quedaron all\u00ed sentadas enfrente del sepulcro. A la ma\u00f1ana siguiente, pasado el d\u00eda de la preparaci\u00f3n, acudieron en grupo los sumos sacerdotes y los fariseos a Pilato y le dijeron: &#8220;Se\u00f1or, nos hemos acordado de que aquel impostor estando en vida anunci\u00f3: &#8220;A los tres d\u00edas resucitar\u00e9&#8221;. Por eso da orden de que vigilen el sepulcro hasta el tercer d\u00eda, no sea que vayan sus disc\u00edpulos, se lleven el cuerpo y digan al pueblo: &#8220;Ha resucitado de entre los muertos&#8221;. La \u00faltima impostura ser\u00eda peor que la primera. Pilato contest\u00f3: &#8220;Ah\u00ed ten\u00e9is la guardia: id vosotros y asegurad la vigilancia como sab\u00e9is&#8221;. Ellos fueron, sellaron la pierda y con la guardia aseguraron la vigilancia del sepulcro.<\/p>\n<p class=\"p2\"><i>Word of the Lord<\/i>.<\/p>\n<p class=\"p1\"><span style=\"color: #800000;\"><b>Meditate on what God tells you in the Gospel<\/b><\/span><\/p>\n<p class=\"p1\">En este Domingo de Ramos, leemos todo el relato de la Pasi\u00f3n de Jes\u00fas seg\u00fan San Mateo.<span class=\"Apple-converted-space\">\u00a0<\/span>\u00bfPor qu\u00e9 lo leemos completo? Porque queremos recordar de lo que celebramos, lo que vivir\u00e1 Jes\u00fas y con \u00c9l su Iglesia, en los d\u00edas santos de esta semana.<\/p>\n<p class=\"p1\">Jes\u00fas me dice \u201cdeseo celebrar la Pascua en tu casa\u201d. Tiene la esperanza de que nuestro coraz\u00f3n lo acoger\u00e1. \u00c9l pasar\u00e1 la semana prepar\u00e1ndose para el gran sacrificio de nuestra redenci\u00f3n. Quiere celebrar con nosotros, compartir con nosotros todo lo que pasa en su coraz\u00f3n. Me pide invitarle a mi casa, a mi familia, en esta Semana Santa. Me pide que ni un solo d\u00eda pase sin que lo acompa\u00f1e y lo escuche.<\/p>\n<p class=\"p1\">La Semana Santa tambi\u00e9n es una semana de prueba para los disc\u00edpulos de Jes\u00fas de ayer y hoy.<span class=\"Apple-converted-space\">\u00a0<\/span>Entre los disc\u00edpulos de Jes\u00fas uno lo traicion\u00f3, uno lo neg\u00f3 y todos cayeron. Hay tantas distracciones que me pueden alejar de esta contemplaci\u00f3n y acompa\u00f1amiento de Jes\u00fas. Est\u00e1n los quehaceres diarios, las necesidades de mi familia, de mi comunidad. Pueden ser fuente de gloria de Dios o de distracci\u00f3n.<\/p>\n<p class=\"p1\">Como Jes\u00fas, podemos vivir esta semana con gran decisi\u00f3n de coraz\u00f3n. Desde ahora podemos establecer lo momentos y las actitudes con las cu\u00e1les queremos acompa\u00f1ar a Jes\u00fas. El coraz\u00f3n de Jes\u00fas est\u00e1 firme, preparado para abrazar con amor la voluntad del Padre. Tambi\u00e9n nos invita: \u201cLev\u00e1ntense, vamos\u201d.<\/p>\n<p class=\"p1\">Tal vez en esta semana tambi\u00e9n experimentamos lo que Jes\u00fas sinti\u00f3 en la cruz: \u201cDios m\u00edo, Dios m\u00edo por qu\u00e9 me has abandonado\u201d. Al momento de esa gran tristeza, Jes\u00fas nos dijo desde Getseman\u00ed c\u00f3mo la podemos enfrentar. \u201cVelen y oren\u201d. Velar, buscar y anhelar el nuevo amanecer. A toda cruz viene una resurrecci\u00f3n. Orar para que, en la soledad de nuestro sufrimiento, de nuestra cruz nunca olvidemos la presencia de Dios que nos acompa\u00f1e y nos entiende.<\/p>\n<p class=\"p1\"><i>\u00abEn esta Semana Santa, levantemos nuestra mirada hacia la cruz para recibir la gracia del estupor. San Francisco de As\u00eds, mirando al Crucificado, se asombraba de que sus frailes no llorasen. Y nosotros, \u00bfsomos capaces todav\u00eda de dejarnos conmover por el amor de Dios? \u00bfPor qu\u00e9 hemos perdido la capacidad de asombrarnos ante \u00e9l? \u00bfPor qu\u00e9? Tal vez porque nuestra fe ha sido corro\u00edda por la costumbre. Tal vez porque permanecemos encerrados en nuestros remordimientos y nos dejamos paralizar por nuestras frustraciones. Tal vez porque hemos perdido la confianza en todo y nos creemos incluso fracasados. Pero detr\u00e1s de todos estos \u201ctal vez\u201d est\u00e1 el hecho de que no nos hemos abierto al don del Esp\u00edritu, que es Aquel que nos da la gracia del estupor\u00bb. (S.S. Francisco, Homil\u00eda del 28 de marzo de 2021).<\/i><\/p>\n<p class=\"p1\"><span style=\"color: #800000;\"><b>Dialogue with Christ<\/b><\/span><\/p>\n<p class=\"p1\"><i>This is the most important part of your prayer, prepare yourself to talk with much love with the One who loves you.<\/i><\/p>\n<p class=\"p1\"><span style=\"color: #800000;\"><b>Purpose<\/b><\/span><\/p>\n<p class=\"p1\"><i>Propose a personal one. The one that involves the most love in response to the Beloved... or, if you believe that this is what God is asking of you, live what is suggested below.<\/i><\/p>\n<p class=\"p1\">Durante el d\u00eda agradecer a Dios un detalle de su presencia en tu vida (una palabra de aliento, la belleza de la naturaleza, la compa\u00f1\u00eda de alguien querido\u2026) e invitarle nuevamente a celebrar su Pascua en tu casa.<\/p>\n<p class=\"p1\"><span style=\"color: #800000;\"><b>Farewell<\/b><\/span><\/p>\n<p class=\"p1\">We thank you, Lord, for all your benefits, you who live and reign forever and ever.<span class=\"s1\"><br \/>\n<\/span>Amen.<\/p>\n<p class=\"p1\">Christ, our King!<span class=\"s1\"><br \/>\n<\/span>Thy Kingdom come!<\/p>\n<p class=\"p1\">Most prudent Virgin, Mary, Mother of the Church.<span class=\"s1\"><br \/>\n<\/span>Pray for us.<\/p>\n<p class=\"p1\">In the name of the Father and of the Son and of the Holy Spirit.<span class=\"s1\"><br \/>\n<\/span>Amen.<\/p>","protected":false},"excerpt":{"rendered":"<p> [&hellip;]<\/p>\n","protected":false},"author":58,"featured_media":36178,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"_daextrevop_audio_file_creation_date":"","_daextrevop_text_to_speech":"","_daextrevop_document_type":"","footnotes":""},"categories":[3164],"tags":[3162,3163,3067],"class_list":["post-36140","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-meditacion-del-dia","tag-evangelio","tag-meditacion","tag-reflexion"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Domingo 2 de abril de 2023 \u2013 Domingo de Ramos \u2013 \u00abDeseo celebrar la Pascua en tu casa\u00bb - Regnum Christi Internacional<\/title>\n<meta name=\"description\" content=\"Jes\u00fas, quiero entrar contigo en esta semana, la m\u00e1s santa de todas las semanas. Me pongo en tu presencia para ver lo que T\u00fa ves.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/regnumchristi.org\/en\/domingo-2-de-abril-de-2023-domingo-de-ramos-deseo-celebrar-la-pascua-en-tu-casa\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Domingo 2 de abril de 2023 \u2013 Domingo de Ramos \u2013 \u00abDeseo celebrar la Pascua en tu casa\u00bb - Regnum Christi Internacional\" \/>\n<meta property=\"og:description\" content=\"Jes\u00fas, quiero entrar contigo en esta semana, la m\u00e1s santa de todas las semanas. Me pongo en tu presencia para ver lo que T\u00fa ves.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/regnumchristi.org\/en\/domingo-2-de-abril-de-2023-domingo-de-ramos-deseo-celebrar-la-pascua-en-tu-casa\/\" \/>\n<meta property=\"og:site_name\" content=\"Regnum Christi Internacional\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/RegnumChristiEspana\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-04-02T02:00:54+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-08-02T19:26:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/regnumchristi.org\/wp-content\/uploads\/2023\/04\/imagenes_meditaciones_diarias_2abr.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"563\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Meditaciones Diarias\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Meditaciones Diarias\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"16 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/domingo-2-de-abril-de-2023-domingo-de-ramos-deseo-celebrar-la-pascua-en-tu-casa\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/domingo-2-de-abril-de-2023-domingo-de-ramos-deseo-celebrar-la-pascua-en-tu-casa\\\/\"},\"author\":{\"name\":\"Meditaciones Diarias\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#\\\/schema\\\/person\\\/a5ad8b3c4bd3cb3a0abe8a1474fe8f0a\"},\"headline\":\"Domingo 2 de abril de 2023 \u2013 Domingo de Ramos \u2013 \u00abDeseo celebrar la Pascua en tu casa\u00bb\",\"datePublished\":\"2023-04-02T02:00:54+00:00\",\"dateModified\":\"2023-08-02T19:26:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/domingo-2-de-abril-de-2023-domingo-de-ramos-deseo-celebrar-la-pascua-en-tu-casa\\\/\"},\"wordCount\":3257,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/domingo-2-de-abril-de-2023-domingo-de-ramos-deseo-celebrar-la-pascua-en-tu-casa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/regnumchristi.org\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/imagenes_meditaciones_diarias_2abr.jpg\",\"keywords\":[\"Evangelio\",\"meditaci\u00f3n\",\"Reflexi\u00f3n\"],\"articleSection\":[\"Meditaci\u00f3n del d\u00eda\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/regnumchristi.org\\\/domingo-2-de-abril-de-2023-domingo-de-ramos-deseo-celebrar-la-pascua-en-tu-casa\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/domingo-2-de-abril-de-2023-domingo-de-ramos-deseo-celebrar-la-pascua-en-tu-casa\\\/\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/domingo-2-de-abril-de-2023-domingo-de-ramos-deseo-celebrar-la-pascua-en-tu-casa\\\/\",\"name\":\"Domingo 2 de abril de 2023 \u2013 Domingo de Ramos \u2013 \u00abDeseo celebrar la Pascua en tu casa\u00bb - Regnum Christi Internacional\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/domingo-2-de-abril-de-2023-domingo-de-ramos-deseo-celebrar-la-pascua-en-tu-casa\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/domingo-2-de-abril-de-2023-domingo-de-ramos-deseo-celebrar-la-pascua-en-tu-casa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/regnumchristi.org\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/imagenes_meditaciones_diarias_2abr.jpg\",\"datePublished\":\"2023-04-02T02:00:54+00:00\",\"dateModified\":\"2023-08-02T19:26:46+00:00\",\"description\":\"Jes\u00fas, quiero entrar contigo en esta semana, la m\u00e1s santa de todas las semanas. Me pongo en tu presencia para ver lo que T\u00fa ves.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/domingo-2-de-abril-de-2023-domingo-de-ramos-deseo-celebrar-la-pascua-en-tu-casa\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/regnumchristi.org\\\/domingo-2-de-abril-de-2023-domingo-de-ramos-deseo-celebrar-la-pascua-en-tu-casa\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/domingo-2-de-abril-de-2023-domingo-de-ramos-deseo-celebrar-la-pascua-en-tu-casa\\\/#primaryimage\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/imagenes_meditaciones_diarias_2abr.jpg\",\"contentUrl\":\"https:\\\/\\\/regnumchristi.org\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/imagenes_meditaciones_diarias_2abr.jpg\",\"width\":900,\"height\":563},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/domingo-2-de-abril-de-2023-domingo-de-ramos-deseo-celebrar-la-pascua-en-tu-casa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/regnumchristi.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Domingo 2 de abril de 2023 \u2013 Domingo de Ramos \u2013 \u00abDeseo celebrar la Pascua en tu casa\u00bb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#website\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/\",\"name\":\"Regnum Christi Internacional\",\"description\":\"El Regnum Christi es una realidad de la Iglesia cat\u00f3lica cuya misi\u00f3n es hacer presente el Reino de Cristo\",\"publisher\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/regnumchristi.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#organization\",\"name\":\"Regnum Christi Internacional\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/regnumchristi.es\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Favicon-RC_ligh-cuadrado.png\",\"contentUrl\":\"https:\\\/\\\/regnumchristi.es\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Favicon-RC_ligh-cuadrado.png\",\"width\":1080,\"height\":1080,\"caption\":\"Regnum Christi Internacional\"},\"image\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/RegnumChristiEspana\\\/\",\"https:\\\/\\\/x.com\\\/rc_espana\",\"https:\\\/\\\/www.instagram.com\\\/rc_espana\\\/\",\"https:\\\/\\\/es.linkedin.com\\\/company\\\/regnumchristiespaa\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#\\\/schema\\\/person\\\/a5ad8b3c4bd3cb3a0abe8a1474fe8f0a\",\"name\":\"Meditaciones Diarias\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/en\\\/author\\\/meditacionesd\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Domingo 2 de abril de 2023 \u2013 Domingo de Ramos \u2013 \u00abDeseo celebrar la Pascua en tu casa\u00bb - Regnum Christi Internacional","description":"Jes\u00fas, quiero entrar contigo en esta semana, la m\u00e1s santa de todas las semanas. Me pongo en tu presencia para ver lo que T\u00fa ves.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/regnumchristi.org\/en\/domingo-2-de-abril-de-2023-domingo-de-ramos-deseo-celebrar-la-pascua-en-tu-casa\/","og_locale":"en_US","og_type":"article","og_title":"Domingo 2 de abril de 2023 \u2013 Domingo de Ramos \u2013 \u00abDeseo celebrar la Pascua en tu casa\u00bb - Regnum Christi Internacional","og_description":"Jes\u00fas, quiero entrar contigo en esta semana, la m\u00e1s santa de todas las semanas. Me pongo en tu presencia para ver lo que T\u00fa ves.","og_url":"https:\/\/regnumchristi.org\/en\/domingo-2-de-abril-de-2023-domingo-de-ramos-deseo-celebrar-la-pascua-en-tu-casa\/","og_site_name":"Regnum Christi Internacional","article_publisher":"https:\/\/www.facebook.com\/RegnumChristiEspana\/","article_published_time":"2023-04-02T02:00:54+00:00","article_modified_time":"2023-08-02T19:26:46+00:00","og_image":[{"width":900,"height":563,"url":"https:\/\/regnumchristi.org\/wp-content\/uploads\/2023\/04\/imagenes_meditaciones_diarias_2abr.jpg","type":"image\/jpeg"}],"author":"Meditaciones Diarias","twitter_misc":{"Written by":"Meditaciones Diarias","Est. reading time":"16 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/regnumchristi.org\/domingo-2-de-abril-de-2023-domingo-de-ramos-deseo-celebrar-la-pascua-en-tu-casa\/#article","isPartOf":{"@id":"https:\/\/regnumchristi.org\/domingo-2-de-abril-de-2023-domingo-de-ramos-deseo-celebrar-la-pascua-en-tu-casa\/"},"author":{"name":"Meditaciones Diarias","@id":"https:\/\/regnumchristi.org\/#\/schema\/person\/a5ad8b3c4bd3cb3a0abe8a1474fe8f0a"},"headline":"Domingo 2 de abril de 2023 \u2013 Domingo de Ramos \u2013 \u00abDeseo celebrar la Pascua en tu casa\u00bb","datePublished":"2023-04-02T02:00:54+00:00","dateModified":"2023-08-02T19:26:46+00:00","mainEntityOfPage":{"@id":"https:\/\/regnumchristi.org\/domingo-2-de-abril-de-2023-domingo-de-ramos-deseo-celebrar-la-pascua-en-tu-casa\/"},"wordCount":3257,"commentCount":0,"publisher":{"@id":"https:\/\/regnumchristi.org\/#organization"},"image":{"@id":"https:\/\/regnumchristi.org\/domingo-2-de-abril-de-2023-domingo-de-ramos-deseo-celebrar-la-pascua-en-tu-casa\/#primaryimage"},"thumbnailUrl":"https:\/\/regnumchristi.org\/wp-content\/uploads\/2023\/04\/imagenes_meditaciones_diarias_2abr.jpg","keywords":["Evangelio","meditaci\u00f3n","Reflexi\u00f3n"],"articleSection":["Meditaci\u00f3n del d\u00eda"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/regnumchristi.org\/domingo-2-de-abril-de-2023-domingo-de-ramos-deseo-celebrar-la-pascua-en-tu-casa\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/regnumchristi.org\/domingo-2-de-abril-de-2023-domingo-de-ramos-deseo-celebrar-la-pascua-en-tu-casa\/","url":"https:\/\/regnumchristi.org\/domingo-2-de-abril-de-2023-domingo-de-ramos-deseo-celebrar-la-pascua-en-tu-casa\/","name":"Domingo 2 de abril de 2023 \u2013 Domingo de Ramos \u2013 \u00abDeseo celebrar la Pascua en tu casa\u00bb - Regnum Christi Internacional","isPartOf":{"@id":"https:\/\/regnumchristi.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/regnumchristi.org\/domingo-2-de-abril-de-2023-domingo-de-ramos-deseo-celebrar-la-pascua-en-tu-casa\/#primaryimage"},"image":{"@id":"https:\/\/regnumchristi.org\/domingo-2-de-abril-de-2023-domingo-de-ramos-deseo-celebrar-la-pascua-en-tu-casa\/#primaryimage"},"thumbnailUrl":"https:\/\/regnumchristi.org\/wp-content\/uploads\/2023\/04\/imagenes_meditaciones_diarias_2abr.jpg","datePublished":"2023-04-02T02:00:54+00:00","dateModified":"2023-08-02T19:26:46+00:00","description":"Jes\u00fas, quiero entrar contigo en esta semana, la m\u00e1s santa de todas las semanas. Me pongo en tu presencia para ver lo que T\u00fa ves.","breadcrumb":{"@id":"https:\/\/regnumchristi.org\/domingo-2-de-abril-de-2023-domingo-de-ramos-deseo-celebrar-la-pascua-en-tu-casa\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/regnumchristi.org\/domingo-2-de-abril-de-2023-domingo-de-ramos-deseo-celebrar-la-pascua-en-tu-casa\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/regnumchristi.org\/domingo-2-de-abril-de-2023-domingo-de-ramos-deseo-celebrar-la-pascua-en-tu-casa\/#primaryimage","url":"https:\/\/regnumchristi.org\/wp-content\/uploads\/2023\/04\/imagenes_meditaciones_diarias_2abr.jpg","contentUrl":"https:\/\/regnumchristi.org\/wp-content\/uploads\/2023\/04\/imagenes_meditaciones_diarias_2abr.jpg","width":900,"height":563},{"@type":"BreadcrumbList","@id":"https:\/\/regnumchristi.org\/domingo-2-de-abril-de-2023-domingo-de-ramos-deseo-celebrar-la-pascua-en-tu-casa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/regnumchristi.org\/es\/"},{"@type":"ListItem","position":2,"name":"Domingo 2 de abril de 2023 \u2013 Domingo de Ramos \u2013 \u00abDeseo celebrar la Pascua en tu casa\u00bb"}]},{"@type":"WebSite","@id":"https:\/\/regnumchristi.org\/#website","url":"https:\/\/regnumchristi.org\/","name":"Regnum Christi International","description":"Regnum Christi is a reality of the Catholic Church whose mission is to make present the Kingdom of Christ.","publisher":{"@id":"https:\/\/regnumchristi.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/regnumchristi.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/regnumchristi.org\/#organization","name":"Regnum Christi International","url":"https:\/\/regnumchristi.org\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/regnumchristi.org\/#\/schema\/logo\/image\/","url":"https:\/\/regnumchristi.es\/wp-content\/uploads\/2023\/03\/Favicon-RC_ligh-cuadrado.png","contentUrl":"https:\/\/regnumchristi.es\/wp-content\/uploads\/2023\/03\/Favicon-RC_ligh-cuadrado.png","width":1080,"height":1080,"caption":"Regnum Christi Internacional"},"image":{"@id":"https:\/\/regnumchristi.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/RegnumChristiEspana\/","https:\/\/x.com\/rc_espana","https:\/\/www.instagram.com\/rc_espana\/","https:\/\/es.linkedin.com\/company\/regnumchristiespaa"]},{"@type":"Person","@id":"https:\/\/regnumchristi.org\/#\/schema\/person\/a5ad8b3c4bd3cb3a0abe8a1474fe8f0a","name":"Daily Meditations","url":"https:\/\/regnumchristi.org\/en\/author\/meditacionesd\/"}]}},"_links":{"self":[{"href":"https:\/\/regnumchristi.org\/en\/wp-json\/wp\/v2\/posts\/36140","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/regnumchristi.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/regnumchristi.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/regnumchristi.org\/en\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/regnumchristi.org\/en\/wp-json\/wp\/v2\/comments?post=36140"}],"version-history":[{"count":1,"href":"https:\/\/regnumchristi.org\/en\/wp-json\/wp\/v2\/posts\/36140\/revisions"}],"predecessor-version":[{"id":93838,"href":"https:\/\/regnumchristi.org\/en\/wp-json\/wp\/v2\/posts\/36140\/revisions\/93838"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/regnumchristi.org\/en\/wp-json\/wp\/v2\/media\/36178"}],"wp:attachment":[{"href":"https:\/\/regnumchristi.org\/en\/wp-json\/wp\/v2\/media?parent=36140"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/regnumchristi.org\/en\/wp-json\/wp\/v2\/categories?post=36140"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/regnumchristi.org\/en\/wp-json\/wp\/v2\/tags?post=36140"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}