{"id":36604,"date":"2023-06-11T20:00:55","date_gmt":"2023-06-12T02:00:55","guid":{"rendered":"https:\/\/www.regnumchristi.org\/es\/?p=36604"},"modified":"2023-08-02T13:22:46","modified_gmt":"2023-08-02T19:22:46","slug":"lunes-12-de-junio-de-2023-querido-google-como-puedo-ser-feliz","status":"publish","type":"post","link":"https:\/\/regnumchristi.org\/en\/lunes-12-de-junio-de-2023-querido-google-como-puedo-ser-feliz\/","title":{"rendered":"Monday, June 12, 2023 - \u00abDear Google... how can I be happy?\u00bb"},"content":{"rendered":"<p><i><span data-contrast=\"none\">Camila Pinheiro, CRC<\/span><\/i><\/p>\n<p><span data-contrast=\"none\">In the name of the Father and of the Son and of the Holy Spirit.<\/span><br \/>\n<span data-contrast=\"none\">Amen.<\/span><\/p>\n<p><span data-contrast=\"none\">Christ, our King.<\/span><br \/>\n<span data-contrast=\"none\">Thy Kingdom come!<\/span><\/p>\n<p><span style=\"color: #800000;\"><b>Preparatory prayer <\/b><\/span><i><span data-contrast=\"none\">(to put me in the presence of God)<\/span><\/i><\/p>\n<p><i><span data-contrast=\"none\">Como anhela la cierva los arroyos, as\u00ed te anhela mi ser, Dios m\u00edo. Mi ser tiene sed de ti, Dios vivo; \u00bfcu\u00e1ndo podr\u00e9 ir a ver tu rostro?<\/span><\/i> <i><span data-contrast=\"none\">Son mis l\u00e1grimas mi pan de d\u00eda y de noche, cuando me dicen todo el d\u00eda: \u00bfD\u00f3nde est\u00e1 tu Dios? <\/span><\/i><span data-contrast=\"none\">(Sal 42). Jes\u00fas, me despiertas hoy con una invitaci\u00f3n: al\u00e9grate t\u00fa que duermes. Se levanta una pregunta en mi coraz\u00f3n: \u00bfpor qu\u00e9 debo de alegrarme? \u00bfCu\u00e1les son los motivos de mi alegr\u00eda si tantas veces experimento en el d\u00eda a d\u00eda motivos para llorar y las voces del mundo me dicen: D\u00f3nde est\u00e1 tu Dios? Despierta en mi hoy Jes\u00fas la alegr\u00eda. Abre mi mirada para comprender con tus santos, que desde dentro de la prueba su puede experimentar profunda alegr\u00eda.<\/span><\/p>\n<p><span style=\"color: #800000;\"><b>Gospel of the day <\/b><\/span><i><span data-contrast=\"none\">(to guide your meditation)<\/span><\/i><br \/>\n<span data-contrast=\"none\">From the Holy Gospel according to St. Matthew 5, 1-12<\/span><\/p>\n<p><span data-contrast=\"none\">En aquel tiempo, al ver Jes\u00fas el gent\u00edo, subi\u00f3 a la monta\u00f1a, se sent\u00f3, y se acercaron sus disc\u00edpulos; y \u00e9l se puso a hablar, ense\u00f1\u00e1ndoles: &#8220;Dichosos los pobres en el esp\u00edritu, porque de ellos es el reino de los cielos. Dichosos los que lloran, porque ellos ser\u00e1n consolados. Dichosos los sufridos, porque ellos heredar\u00e1n la tierra. Dichosos los que tienen hambre y sed de la justicia, porque ellos quedar\u00e1n saciados. Dichosos los misericordiosos, porque ellos alcanzar\u00e1n misericordia. Dichosos los limpios de coraz\u00f3n, porque ellos ver\u00e1n a Dios. Dichosos los que trabajan por la paz, porque ellos se llamar\u00e1n los Hijos de Dios. Dichosos los perseguidos por causa de la justicia, porque de ellos es el reino de los cielos. Dichosos vosotros cuando os insulten y os persigan y os calumnien de cualquier modo por mi causa. Estad alegres y contentos, porque vuestra recompensa ser\u00e1 grande en el cielo, que de la misma manera persiguieron a los profetas anteriores a vosotros&#8221;.<\/span><\/p>\n<p><i><span data-contrast=\"none\">Word of the Lord<\/span><\/i><span data-contrast=\"none\">.<\/span><\/p>\n<p><span style=\"color: #800000;\"><b>Meditate on what God tells you in the Gospel<\/b><\/span><\/p>\n<p><span data-contrast=\"none\">\u00bfC\u00f3mo puedo ser feliz? \u00c9sta ha sido una de las preguntas top en b\u00fasquedas de <\/span><i><span data-contrast=\"none\">Google<\/span><\/i><span data-contrast=\"none\"> a lo largo de los \u00faltimos a\u00f1os. Una pregunta existencial que da vueltas en el coraz\u00f3n de todo ser humano. \u00bfPuedo ser feliz? \u00bfC\u00f3mo ser feliz? \u00bfQu\u00e9 es la felicidad? Y as\u00ed por delante. Buscamos la felicidad en tantas partes, en el dinero, en el poseer, en el prestigio, en el \u00e9xito, en el placer, en el comer, en las relaciones interpersonales&#8230; todo parece que llega a un tope y nada parece cumplir la promesa inicial: \u201cTe dar\u00e9 lo que buscas\u201d.<\/span><\/p>\n<p><span data-contrast=\"none\">El Evangelio de hoy nos da las coordenadas para ello, dice: Jes\u00fas se sent\u00f3 y sus disc\u00edpulos se acercaron. \u00bfBuscas la felicidad? T\u00fa tambi\u00e9n puedes hoy acercarte a Jes\u00fas, ponerte a sus pies como lo hicieron tantos y, una vez con el coraz\u00f3n bien abierto, podr\u00e1s comprender el motivo de la alegr\u00eda cristiana.<\/span><\/p>\n<p><span data-contrast=\"none\">Las bienaventuranzas pueden ser le\u00eddas de dos formas, como una promesa o como una certeza. Le\u00eddas desde la primera frase se presentan como una promesa que nos alienta a perseverar ante las adversidades que tocamos en el mundo por consecuencia del pecado. Le\u00eddas desde la segunda frase se presentan como una certeza: Ser\u00e1s consolado, por eso, si lloras, al\u00e9grate.<\/span><\/p>\n<p><span data-contrast=\"none\">La promesa nos mantiene a la espera y la certeza es la roca s\u00f3lida que nos mantiene de pie. \u00bfY cu\u00e1l es el fundamento de nuestra certeza? \u00bfCu\u00e1l el motivo de nuestra esperanza? San Pablo nos responde: \u201csi morimos con Cristo, creemos que tambi\u00e9n viviremos con \u00e9l\u201d (<\/span><i><span data-contrast=\"none\">Rm<\/span><\/i><span data-contrast=\"none\"> 6, 8). Es gracias a la fe en Jes\u00fas y nuestra uni\u00f3n con \u00e9l por los sacramentos de iniciaci\u00f3n que nosotros podemos afirmar con certeza que esa vida, esa felicidad ya se nos fue dada, la poseemos: es Cristo.<\/span><\/p>\n<p><i><span data-contrast=\"none\">\u00abDios, para entregarse a nosotros, elige a menudo caminos impensables, tal vez los de nuestros l\u00edmites, los de nuestras l\u00e1grimas, los de nuestras derrotas. Es la alegr\u00eda pascual, de la que hablan nuestros hermanos orientales, la que tiene los estigmas, pero est\u00e1 viva, ha atravesado la muerte y ha experimentado la potencia de Dios. Las bienaventuranzas te llevan a la alegr\u00eda, siempre; son el camino para alcanzar la alegr\u00eda\u00bb. (S.S. Francisco, Catequesis del 29 de enero de 2020).<\/span><\/i><\/p>\n<p><span style=\"color: #800000;\"><b>Dialogue with Christ<\/b><\/span><\/p>\n<p><i><span data-contrast=\"none\">This is the most important part of your prayer, prepare yourself to talk with much love with the One who loves you.<\/span><\/i><\/p>\n<p><span style=\"color: #800000;\"><b>Purpose<\/b><\/span><\/p>\n<p><i><span data-contrast=\"none\">Propose a personal one. The one that involves the most love in response to the Beloved... or, if you believe that this is what God is asking of you, live what is suggested below.<\/span><\/i><\/p>\n<p><span data-contrast=\"none\">Ante las dificultades que tengas hoy preg\u00fantate \u00bfqui\u00e9n me puede separar del amor de Cristo? <\/span><span data-contrast=\"none\">(<\/span><i><span data-contrast=\"none\">Rm<\/span><\/i><span data-contrast=\"none\"> 8, 28)<\/span><\/p>\n<p><span style=\"color: #800000;\"><b>Farewell<\/b><\/span><\/p>\n<p><span data-contrast=\"none\">We thank you, Lord, for all your benefits, you who live and reign forever and ever.<\/span><br \/>\n<span data-contrast=\"none\">Amen.<\/span><\/p>\n<p><span data-contrast=\"none\">Christ, our King!<\/span><br \/>\n<span data-contrast=\"none\">Thy Kingdom come!<\/span><\/p>\n<p><span data-contrast=\"none\">Most prudent Virgin, Mary, Mother of the Church.<\/span><br \/>\n<span data-contrast=\"none\">Pray for us.<\/span><\/p>\n<p><span data-contrast=\"none\">In the name of the Father and of the Son and of the Holy Spirit.<\/span><br \/>\n<span data-contrast=\"none\">Amen.<\/span><\/p>","protected":false},"excerpt":{"rendered":"<p> [&hellip;]<\/p>\n","protected":false},"author":58,"featured_media":36738,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"_daextrevop_audio_file_creation_date":"","_daextrevop_text_to_speech":"","_daextrevop_document_type":"","footnotes":""},"categories":[3164],"tags":[3162,3163,3067],"class_list":["post-36604","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-meditacion-del-dia","tag-evangelio","tag-meditacion","tag-reflexion"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Lunes 12 de junio de 2023 \u2013 \u00abQuerido Google... \u00bfc\u00f3mo puedo ser feliz?\u00bb - Regnum Christi Internacional<\/title>\n<meta name=\"description\" content=\"Despierta en mi hoy Jes\u00fas la alegr\u00eda. Abre mi mirada para comprender con tus santos, que desde la prueba su puede experimentar alegr\u00eda.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/regnumchristi.org\/en\/lunes-12-de-junio-de-2023-querido-google-como-puedo-ser-feliz\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lunes 12 de junio de 2023 \u2013 \u00abQuerido Google... \u00bfc\u00f3mo puedo ser feliz?\u00bb - Regnum Christi Internacional\" \/>\n<meta property=\"og:description\" content=\"Despierta en mi hoy Jes\u00fas la alegr\u00eda. Abre mi mirada para comprender con tus santos, que desde la prueba su puede experimentar alegr\u00eda.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/regnumchristi.org\/en\/lunes-12-de-junio-de-2023-querido-google-como-puedo-ser-feliz\/\" \/>\n<meta property=\"og:site_name\" content=\"Regnum Christi Internacional\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/RegnumChristiEspana\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-06-12T02:00:55+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-08-02T19:22:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/regnumchristi.org\/wp-content\/uploads\/2023\/06\/imagenes_meditaciones_diarias_12jun.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"563\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Meditaciones Diarias\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Meditaciones Diarias\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/lunes-12-de-junio-de-2023-querido-google-como-puedo-ser-feliz\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/lunes-12-de-junio-de-2023-querido-google-como-puedo-ser-feliz\\\/\"},\"author\":{\"name\":\"Meditaciones Diarias\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#\\\/schema\\\/person\\\/a5ad8b3c4bd3cb3a0abe8a1474fe8f0a\"},\"headline\":\"Lunes 12 de junio de 2023 \u2013 \u00abQuerido Google&#8230; \u00bfc\u00f3mo puedo ser feliz?\u00bb\",\"datePublished\":\"2023-06-12T02:00:55+00:00\",\"dateModified\":\"2023-08-02T19:22:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/lunes-12-de-junio-de-2023-querido-google-como-puedo-ser-feliz\\\/\"},\"wordCount\":929,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/lunes-12-de-junio-de-2023-querido-google-como-puedo-ser-feliz\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/regnumchristi.org\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/imagenes_meditaciones_diarias_12jun.jpg\",\"keywords\":[\"Evangelio\",\"meditaci\u00f3n\",\"Reflexi\u00f3n\"],\"articleSection\":[\"Meditaci\u00f3n del d\u00eda\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/regnumchristi.org\\\/lunes-12-de-junio-de-2023-querido-google-como-puedo-ser-feliz\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/lunes-12-de-junio-de-2023-querido-google-como-puedo-ser-feliz\\\/\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/lunes-12-de-junio-de-2023-querido-google-como-puedo-ser-feliz\\\/\",\"name\":\"Lunes 12 de junio de 2023 \u2013 \u00abQuerido Google... \u00bfc\u00f3mo puedo ser feliz?\u00bb - Regnum Christi Internacional\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/lunes-12-de-junio-de-2023-querido-google-como-puedo-ser-feliz\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/lunes-12-de-junio-de-2023-querido-google-como-puedo-ser-feliz\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/regnumchristi.org\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/imagenes_meditaciones_diarias_12jun.jpg\",\"datePublished\":\"2023-06-12T02:00:55+00:00\",\"dateModified\":\"2023-08-02T19:22:46+00:00\",\"description\":\"Despierta en mi hoy Jes\u00fas la alegr\u00eda. Abre mi mirada para comprender con tus santos, que desde la prueba su puede experimentar alegr\u00eda.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/lunes-12-de-junio-de-2023-querido-google-como-puedo-ser-feliz\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/regnumchristi.org\\\/lunes-12-de-junio-de-2023-querido-google-como-puedo-ser-feliz\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/lunes-12-de-junio-de-2023-querido-google-como-puedo-ser-feliz\\\/#primaryimage\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/imagenes_meditaciones_diarias_12jun.jpg\",\"contentUrl\":\"https:\\\/\\\/regnumchristi.org\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/imagenes_meditaciones_diarias_12jun.jpg\",\"width\":900,\"height\":563},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/lunes-12-de-junio-de-2023-querido-google-como-puedo-ser-feliz\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/regnumchristi.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lunes 12 de junio de 2023 \u2013 \u00abQuerido Google&#8230; \u00bfc\u00f3mo puedo ser feliz?\u00bb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#website\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/\",\"name\":\"Regnum Christi Internacional\",\"description\":\"El Regnum Christi es una realidad de la Iglesia cat\u00f3lica cuya misi\u00f3n es hacer presente el Reino de Cristo\",\"publisher\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/regnumchristi.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#organization\",\"name\":\"Regnum Christi Internacional\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/regnumchristi.es\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Favicon-RC_ligh-cuadrado.png\",\"contentUrl\":\"https:\\\/\\\/regnumchristi.es\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Favicon-RC_ligh-cuadrado.png\",\"width\":1080,\"height\":1080,\"caption\":\"Regnum Christi Internacional\"},\"image\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/RegnumChristiEspana\\\/\",\"https:\\\/\\\/x.com\\\/rc_espana\",\"https:\\\/\\\/www.instagram.com\\\/rc_espana\\\/\",\"https:\\\/\\\/es.linkedin.com\\\/company\\\/regnumchristiespaa\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#\\\/schema\\\/person\\\/a5ad8b3c4bd3cb3a0abe8a1474fe8f0a\",\"name\":\"Meditaciones Diarias\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/en\\\/author\\\/meditacionesd\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lunes 12 de junio de 2023 \u2013 \u00abQuerido Google... \u00bfc\u00f3mo puedo ser feliz?\u00bb - Regnum Christi Internacional","description":"Despierta en mi hoy Jes\u00fas la alegr\u00eda. Abre mi mirada para comprender con tus santos, que desde la prueba su puede experimentar alegr\u00eda.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/regnumchristi.org\/en\/lunes-12-de-junio-de-2023-querido-google-como-puedo-ser-feliz\/","og_locale":"en_US","og_type":"article","og_title":"Lunes 12 de junio de 2023 \u2013 \u00abQuerido Google... \u00bfc\u00f3mo puedo ser feliz?\u00bb - Regnum Christi Internacional","og_description":"Despierta en mi hoy Jes\u00fas la alegr\u00eda. Abre mi mirada para comprender con tus santos, que desde la prueba su puede experimentar alegr\u00eda.","og_url":"https:\/\/regnumchristi.org\/en\/lunes-12-de-junio-de-2023-querido-google-como-puedo-ser-feliz\/","og_site_name":"Regnum Christi Internacional","article_publisher":"https:\/\/www.facebook.com\/RegnumChristiEspana\/","article_published_time":"2023-06-12T02:00:55+00:00","article_modified_time":"2023-08-02T19:22:46+00:00","og_image":[{"width":900,"height":563,"url":"https:\/\/regnumchristi.org\/wp-content\/uploads\/2023\/06\/imagenes_meditaciones_diarias_12jun.jpg","type":"image\/jpeg"}],"author":"Meditaciones Diarias","twitter_misc":{"Written by":"Meditaciones Diarias","Est. reading time":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/regnumchristi.org\/lunes-12-de-junio-de-2023-querido-google-como-puedo-ser-feliz\/#article","isPartOf":{"@id":"https:\/\/regnumchristi.org\/lunes-12-de-junio-de-2023-querido-google-como-puedo-ser-feliz\/"},"author":{"name":"Meditaciones Diarias","@id":"https:\/\/regnumchristi.org\/#\/schema\/person\/a5ad8b3c4bd3cb3a0abe8a1474fe8f0a"},"headline":"Lunes 12 de junio de 2023 \u2013 \u00abQuerido Google&#8230; \u00bfc\u00f3mo puedo ser feliz?\u00bb","datePublished":"2023-06-12T02:00:55+00:00","dateModified":"2023-08-02T19:22:46+00:00","mainEntityOfPage":{"@id":"https:\/\/regnumchristi.org\/lunes-12-de-junio-de-2023-querido-google-como-puedo-ser-feliz\/"},"wordCount":929,"commentCount":0,"publisher":{"@id":"https:\/\/regnumchristi.org\/#organization"},"image":{"@id":"https:\/\/regnumchristi.org\/lunes-12-de-junio-de-2023-querido-google-como-puedo-ser-feliz\/#primaryimage"},"thumbnailUrl":"https:\/\/regnumchristi.org\/wp-content\/uploads\/2023\/06\/imagenes_meditaciones_diarias_12jun.jpg","keywords":["Evangelio","meditaci\u00f3n","Reflexi\u00f3n"],"articleSection":["Meditaci\u00f3n del d\u00eda"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/regnumchristi.org\/lunes-12-de-junio-de-2023-querido-google-como-puedo-ser-feliz\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/regnumchristi.org\/lunes-12-de-junio-de-2023-querido-google-como-puedo-ser-feliz\/","url":"https:\/\/regnumchristi.org\/lunes-12-de-junio-de-2023-querido-google-como-puedo-ser-feliz\/","name":"Lunes 12 de junio de 2023 \u2013 \u00abQuerido Google... \u00bfc\u00f3mo puedo ser feliz?\u00bb - Regnum Christi Internacional","isPartOf":{"@id":"https:\/\/regnumchristi.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/regnumchristi.org\/lunes-12-de-junio-de-2023-querido-google-como-puedo-ser-feliz\/#primaryimage"},"image":{"@id":"https:\/\/regnumchristi.org\/lunes-12-de-junio-de-2023-querido-google-como-puedo-ser-feliz\/#primaryimage"},"thumbnailUrl":"https:\/\/regnumchristi.org\/wp-content\/uploads\/2023\/06\/imagenes_meditaciones_diarias_12jun.jpg","datePublished":"2023-06-12T02:00:55+00:00","dateModified":"2023-08-02T19:22:46+00:00","description":"Despierta en mi hoy Jes\u00fas la alegr\u00eda. Abre mi mirada para comprender con tus santos, que desde la prueba su puede experimentar alegr\u00eda.","breadcrumb":{"@id":"https:\/\/regnumchristi.org\/lunes-12-de-junio-de-2023-querido-google-como-puedo-ser-feliz\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/regnumchristi.org\/lunes-12-de-junio-de-2023-querido-google-como-puedo-ser-feliz\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/regnumchristi.org\/lunes-12-de-junio-de-2023-querido-google-como-puedo-ser-feliz\/#primaryimage","url":"https:\/\/regnumchristi.org\/wp-content\/uploads\/2023\/06\/imagenes_meditaciones_diarias_12jun.jpg","contentUrl":"https:\/\/regnumchristi.org\/wp-content\/uploads\/2023\/06\/imagenes_meditaciones_diarias_12jun.jpg","width":900,"height":563},{"@type":"BreadcrumbList","@id":"https:\/\/regnumchristi.org\/lunes-12-de-junio-de-2023-querido-google-como-puedo-ser-feliz\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/regnumchristi.org\/es\/"},{"@type":"ListItem","position":2,"name":"Lunes 12 de junio de 2023 \u2013 \u00abQuerido Google&#8230; \u00bfc\u00f3mo puedo ser feliz?\u00bb"}]},{"@type":"WebSite","@id":"https:\/\/regnumchristi.org\/#website","url":"https:\/\/regnumchristi.org\/","name":"Regnum Christi International","description":"Regnum Christi is a reality of the Catholic Church whose mission is to make present the Kingdom of Christ.","publisher":{"@id":"https:\/\/regnumchristi.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/regnumchristi.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/regnumchristi.org\/#organization","name":"Regnum Christi International","url":"https:\/\/regnumchristi.org\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/regnumchristi.org\/#\/schema\/logo\/image\/","url":"https:\/\/regnumchristi.es\/wp-content\/uploads\/2023\/03\/Favicon-RC_ligh-cuadrado.png","contentUrl":"https:\/\/regnumchristi.es\/wp-content\/uploads\/2023\/03\/Favicon-RC_ligh-cuadrado.png","width":1080,"height":1080,"caption":"Regnum Christi Internacional"},"image":{"@id":"https:\/\/regnumchristi.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/RegnumChristiEspana\/","https:\/\/x.com\/rc_espana","https:\/\/www.instagram.com\/rc_espana\/","https:\/\/es.linkedin.com\/company\/regnumchristiespaa"]},{"@type":"Person","@id":"https:\/\/regnumchristi.org\/#\/schema\/person\/a5ad8b3c4bd3cb3a0abe8a1474fe8f0a","name":"Daily Meditations","url":"https:\/\/regnumchristi.org\/en\/author\/meditacionesd\/"}]}},"_links":{"self":[{"href":"https:\/\/regnumchristi.org\/en\/wp-json\/wp\/v2\/posts\/36604","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/regnumchristi.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/regnumchristi.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/regnumchristi.org\/en\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/regnumchristi.org\/en\/wp-json\/wp\/v2\/comments?post=36604"}],"version-history":[{"count":1,"href":"https:\/\/regnumchristi.org\/en\/wp-json\/wp\/v2\/posts\/36604\/revisions"}],"predecessor-version":[{"id":93761,"href":"https:\/\/regnumchristi.org\/en\/wp-json\/wp\/v2\/posts\/36604\/revisions\/93761"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/regnumchristi.org\/en\/wp-json\/wp\/v2\/media\/36738"}],"wp:attachment":[{"href":"https:\/\/regnumchristi.org\/en\/wp-json\/wp\/v2\/media?parent=36604"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/regnumchristi.org\/en\/wp-json\/wp\/v2\/categories?post=36604"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/regnumchristi.org\/en\/wp-json\/wp\/v2\/tags?post=36604"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}