{"id":101000,"date":"2024-03-04T20:00:22","date_gmt":"2024-03-05T02:00:22","guid":{"rendered":"https:\/\/regnumchristi.org\/es\/?p=101000"},"modified":"2024-03-04T15:42:23","modified_gmt":"2024-03-04T21:42:23","slug":"martes-5-de-marzo-de-2024-hacer-del-amor-una-realidad","status":"publish","type":"post","link":"https:\/\/regnumchristi.org\/es\/martes-5-de-marzo-de-2024-hacer-del-amor-una-realidad\/","title":{"rendered":"Martes 5 de marzo de 2024 &#8211; \u00abHacer del Amor una realidad\u00bb"},"content":{"rendered":"<p><em>Adri\u00e1n Olvera, LC<\/em><\/p>\n<p>En el nombre del Padre y del Hijo y del Esp\u00edritu Santo.<br \/>\nAm\u00e9n.<\/p>\n<p>Cristo, Rey nuestro.<br \/>\n\u00a1Venga tu Reino!<\/p>\n<p><span style=\"color: #800000;\"><strong>Oraci\u00f3n preparatoria<\/strong><\/span>\u00a0<em>(para ponerme en presencia de Dios)<\/em><\/p>\n<p>Se\u00f1or, dame la gracia de hacer una experiencia\u2026, una experiencia real de tu amor.<\/p>\n<p><span style=\"color: #800000;\"><strong>Evangelio del d\u00eda<\/strong><\/span>\u00a0<em>(para orientar tu meditaci\u00f3n)<\/em><br \/>\nDel santo Evangelio seg\u00fan san Mateo 18, 21-35<\/p>\n<p>En aquel tiempo, Pedro se acerc\u00f3 a Jes\u00fas y le pregunt\u00f3: &#8220;Si mi hermano me ofende, \u00bfcu\u00e1ntas veces tengo que perdonarlo? \u00bfHasta siete veces?&#8221;. Jes\u00fas le contest\u00f3: &#8220;No s\u00f3lo hasta siete, sino hasta setenta veces siete&#8221;. Entonces Jes\u00fas les dijo: &#8220;El Reino de los cielos es semejante a un rey que quiso ajustar cuentas con sus servidores. El primero que le presentaron le deb\u00eda muchos millones. Como no ten\u00eda con qu\u00e9 pagar, el se\u00f1or mand\u00f3 que lo vendieran a \u00e9l, a su mujer, a sus hijos y todas sus posesiones, para saldar la deuda. El servidor, arroj\u00e1ndose a sus pies, le suplicaba, diciendo: &#8216;Ten paciencia conmigo y te lo pagar\u00e9 todo&#8217;. El rey tuvo l\u00e1stima de aquel servidor, lo solt\u00f3 y hasta le perdon\u00f3 la deuda. Pero, apenas hab\u00eda salido aquel servidor, se encontr\u00f3 con uno de sus compa\u00f1eros, que le deb\u00eda poco dinero. Entonces lo agarr\u00f3 por el cuello y casi lo estrangulaba, mientras le dec\u00eda: &#8216;P\u00e1game lo que me debes&#8217;. El compa\u00f1ero se le arrodill\u00f3 y le rogaba: &#8216;Ten paciencia conmigo y te lo pagar\u00e9 todo&#8217;. Pero el otro no quiso escucharlo, sino que fue y lo meti\u00f3 en la c\u00e1rcel hasta que le pagara la deuda. Al ver lo ocurrido, sus compa\u00f1eros se llenaron de indignaci\u00f3n y fueron a contar al rey lo sucedido. Entonces el se\u00f1or lo llam\u00f3 y le dijo: &#8216;Siervo malvado. Te perdon\u00e9 toda aquella deuda porque me lo suplicaste. \u00bfNo deb\u00edas t\u00fa tambi\u00e9n haber tenido compasi\u00f3n de tu compa\u00f1ero, como yo tuve compasi\u00f3n de ti?&#8217; Y el se\u00f1or, encolerizado, lo entreg\u00f3 a los verdugos para que no lo soltaran hasta que pagara lo que deb\u00eda. Pues lo mismo har\u00e1 mi Padre celestial con ustedes, si cada cual no perdona de coraz\u00f3n a su hermano&#8221;.<\/p>\n<p><em>Palabra del Se\u00f1or.<\/em><\/p>\n<p><span style=\"color: #800000;\"><strong>Medita lo que Dios te dice en el Evangelio<\/strong><\/span><\/p>\n<p>El ejemplo de Cristo no simplemente es algo que debemos admirar, que debemos contemplar o que debemos conocer. Su ejemplo no es como una pintura, un libro o una canci\u00f3n que, por su hermosura, por su originalidad o su musicalidad nos hace decir: \u00a1Qu\u00e9 hermoso\u2026! \u00a1Qu\u00e9 interesante!<\/p>\n<p>Es verdad que debemos hacer todas estas cosas, admirarlo, contemplarlo, conocerlo; pero si hay un verdadero encuentro con Aqu\u00e9l que admiramos, con Aqu\u00e9l que contemplamos, con Aqu\u00e9l que conocemos, vamos a querer plasmar todo aquello de lo que hemos sido testigos en nuestra vida.<\/p>\n<p>Admirar su paciencia es saber que Dios es paciente con cada uno de nosotros. Contemplar su misericordia es experimentar que Dios nos perdona. Conocer su amor es sabernos amado por \u00c9l.<\/p>\n<p>Todo inicia con un verdadero encuentro. No con la imagen de Dios, o con la idea que tenemos de \u00c9l pues, cuando es as\u00ed, el ser paciente o el perdonar depende de la mayor o menor intensidad de la imagen que tengamos de \u00c9l. Sin embargo, cuando verdaderamente hemos tenido un encuentro con su Amor, con su paciencia y misericordia; cuando hemos sido nosotros los que hemos sido perdonados, los que han sido amado, es ah\u00ed cuando nos damos cuenta que no simplemente podemos decir: \u00a1Qu\u00e9 interesante! Nos sentimos llamados a hacer de ese amor una realidad.<\/p>\n<p><em>\u00abComo el rey de la par\u00e1bola, Dios se apiada, prueba un sentimiento de piedad junto con el de la ternura: es una expresi\u00f3n para indicar su misericordia para con nosotros. Nuestro Padre se apiada siempre cuando estamos arrepentidos, y nos manda a casa con el coraz\u00f3n tranquilo y sereno, dici\u00e9ndonos que nos ha liberado y perdonado todo. El perd\u00f3n de Dios no conoce l\u00edmites; va m\u00e1s all\u00e1 de nuestra imaginaci\u00f3n y alcanza a quien reconoce, en el \u00edntimo del coraz\u00f3n, haberse equivocado y quiere volver a \u00e9l. Dios mira el coraz\u00f3n que pide ser perdonado. El problema, desgraciadamente, surge cuando nosotros nos ponemos a confrontarnos con nuestro hermano que nos ha hecho una peque\u00f1a injusticia\u00bb.<\/em><br \/>\n(Homil\u00eda de S.S. Francisco, 4 de agosto de 2016).<\/p>\n<p><span style=\"color: #800000;\"><strong>Di\u00e1logo con Cristo<\/strong><\/span><\/p>\n<p><em>\u00c9sta es la parte m\u00e1s importante de tu oraci\u00f3n, disponte a platicar con mucho amor con Aquel que te ama.<\/em><\/p>\n<p><span style=\"color: #800000;\"><strong>Prop\u00f3sito<\/strong><\/span><\/p>\n<p><em>Proponte uno personal. El que m\u00e1s amor implique en respuesta al Amado\u2026 o, si crees que es lo que Dios te pide, vive lo que se te sugiere a continuaci\u00f3n.<\/em><\/p>\n<p>Poner especial atenci\u00f3n a los signos de amor de Dios en este d\u00eda.<\/p>\n<p><span style=\"color: #800000;\"><strong>Despedida<\/strong><\/span><\/p>\n<p>Te damos gracias, Se\u00f1or, por todos tus beneficios, a ti que vives y reinas por los siglos de los siglos.<br \/>\nAm\u00e9n.<\/p>\n<p>\u00a1Cristo, Rey nuestro!<br \/>\n\u00a1Venga tu Reino!<\/p>\n<p>Virgen prudent\u00edsima, Mar\u00eda, Madre de la Iglesia.<br \/>\nRuega por nosotros.<\/p>\n<p>En el nombre del Padre y del Hijo y del Esp\u00edritu Santo.<br \/>\nAm\u00e9n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p> [&hellip;]<\/p>\n","protected":false},"author":58,"featured_media":101024,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"default","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"_daextrevop_audio_file_creation_date":"","_daextrevop_text_to_speech":"","_daextrevop_document_type":"","footnotes":""},"categories":[3164],"tags":[3162,3163,3067],"class_list":["post-101000","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-meditacion-del-dia","tag-evangelio","tag-meditacion","tag-reflexion"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Martes 5 de marzo de 2024 - \u00abHacer del Amor una realidad\u00bb - Regnum Christi Internacional<\/title>\n<meta name=\"description\" content=\"Admirar su paciencia es saber que Dios es paciente con cada uno de nosotros. Contemplar su misericordia es experimentar que Dios nos perdona.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/regnumchristi.org\/es\/martes-5-de-marzo-de-2024-hacer-del-amor-una-realidad\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Martes 5 de marzo de 2024 - \u00abHacer del Amor una realidad\u00bb - Regnum Christi Internacional\" \/>\n<meta property=\"og:description\" content=\"Admirar su paciencia es saber que Dios es paciente con cada uno de nosotros. Contemplar su misericordia es experimentar que Dios nos perdona.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/regnumchristi.org\/es\/martes-5-de-marzo-de-2024-hacer-del-amor-una-realidad\/\" \/>\n<meta property=\"og:site_name\" content=\"Regnum Christi Internacional\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/RegnumChristiEspana\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-05T02:00:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/regnumchristi.org\/wp-content\/uploads\/2024\/03\/imagenes_meditaciones_diarias_5mar.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"563\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Meditaciones Diarias\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Meditaciones Diarias\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/martes-5-de-marzo-de-2024-hacer-del-amor-una-realidad\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/martes-5-de-marzo-de-2024-hacer-del-amor-una-realidad\\\/\"},\"author\":{\"name\":\"Meditaciones Diarias\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#\\\/schema\\\/person\\\/a5ad8b3c4bd3cb3a0abe8a1474fe8f0a\"},\"headline\":\"Martes 5 de marzo de 2024 &#8211; \u00abHacer del Amor una realidad\u00bb\",\"datePublished\":\"2024-03-05T02:00:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/martes-5-de-marzo-de-2024-hacer-del-amor-una-realidad\\\/\"},\"wordCount\":898,\"publisher\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/martes-5-de-marzo-de-2024-hacer-del-amor-una-realidad\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/regnumchristi.org\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/imagenes_meditaciones_diarias_5mar.jpg\",\"keywords\":[\"Evangelio\",\"meditaci\u00f3n\",\"Reflexi\u00f3n\"],\"articleSection\":[\"Meditaci\u00f3n del d\u00eda\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/martes-5-de-marzo-de-2024-hacer-del-amor-una-realidad\\\/\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/martes-5-de-marzo-de-2024-hacer-del-amor-una-realidad\\\/\",\"name\":\"Martes 5 de marzo de 2024 - \u00abHacer del Amor una realidad\u00bb - Regnum Christi Internacional\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/martes-5-de-marzo-de-2024-hacer-del-amor-una-realidad\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/martes-5-de-marzo-de-2024-hacer-del-amor-una-realidad\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/regnumchristi.org\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/imagenes_meditaciones_diarias_5mar.jpg\",\"datePublished\":\"2024-03-05T02:00:22+00:00\",\"description\":\"Admirar su paciencia es saber que Dios es paciente con cada uno de nosotros. Contemplar su misericordia es experimentar que Dios nos perdona.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/martes-5-de-marzo-de-2024-hacer-del-amor-una-realidad\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/regnumchristi.org\\\/martes-5-de-marzo-de-2024-hacer-del-amor-una-realidad\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/martes-5-de-marzo-de-2024-hacer-del-amor-una-realidad\\\/#primaryimage\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/imagenes_meditaciones_diarias_5mar.jpg\",\"contentUrl\":\"https:\\\/\\\/regnumchristi.org\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/imagenes_meditaciones_diarias_5mar.jpg\",\"width\":900,\"height\":563},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/martes-5-de-marzo-de-2024-hacer-del-amor-una-realidad\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/regnumchristi.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Martes 5 de marzo de 2024 &#8211; \u00abHacer del Amor una realidad\u00bb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#website\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/\",\"name\":\"Regnum Christi Internacional\",\"description\":\"El Regnum Christi es una realidad de la Iglesia cat\u00f3lica cuya misi\u00f3n es hacer presente el Reino de Cristo\",\"publisher\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/regnumchristi.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#organization\",\"name\":\"Regnum Christi Internacional\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/regnumchristi.es\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Favicon-RC_ligh-cuadrado.png\",\"contentUrl\":\"https:\\\/\\\/regnumchristi.es\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Favicon-RC_ligh-cuadrado.png\",\"width\":1080,\"height\":1080,\"caption\":\"Regnum Christi Internacional\"},\"image\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/RegnumChristiEspana\\\/\",\"https:\\\/\\\/x.com\\\/rc_espana\",\"https:\\\/\\\/www.instagram.com\\\/rc_espana\\\/\",\"https:\\\/\\\/es.linkedin.com\\\/company\\\/regnumchristiespaa\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#\\\/schema\\\/person\\\/a5ad8b3c4bd3cb3a0abe8a1474fe8f0a\",\"name\":\"Meditaciones Diarias\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/es\\\/author\\\/meditacionesd\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Martes 5 de marzo de 2024 - \u00abHacer del Amor una realidad\u00bb - Regnum Christi Internacional","description":"Admirar su paciencia es saber que Dios es paciente con cada uno de nosotros. Contemplar su misericordia es experimentar que Dios nos perdona.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/regnumchristi.org\/es\/martes-5-de-marzo-de-2024-hacer-del-amor-una-realidad\/","og_locale":"es_MX","og_type":"article","og_title":"Martes 5 de marzo de 2024 - \u00abHacer del Amor una realidad\u00bb - Regnum Christi Internacional","og_description":"Admirar su paciencia es saber que Dios es paciente con cada uno de nosotros. Contemplar su misericordia es experimentar que Dios nos perdona.","og_url":"https:\/\/regnumchristi.org\/es\/martes-5-de-marzo-de-2024-hacer-del-amor-una-realidad\/","og_site_name":"Regnum Christi Internacional","article_publisher":"https:\/\/www.facebook.com\/RegnumChristiEspana\/","article_published_time":"2024-03-05T02:00:22+00:00","og_image":[{"width":900,"height":563,"url":"https:\/\/regnumchristi.org\/wp-content\/uploads\/2024\/03\/imagenes_meditaciones_diarias_5mar.jpg","type":"image\/jpeg"}],"author":"Meditaciones Diarias","twitter_misc":{"Escrito por":"Meditaciones Diarias","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/regnumchristi.org\/martes-5-de-marzo-de-2024-hacer-del-amor-una-realidad\/#article","isPartOf":{"@id":"https:\/\/regnumchristi.org\/martes-5-de-marzo-de-2024-hacer-del-amor-una-realidad\/"},"author":{"name":"Meditaciones Diarias","@id":"https:\/\/regnumchristi.org\/#\/schema\/person\/a5ad8b3c4bd3cb3a0abe8a1474fe8f0a"},"headline":"Martes 5 de marzo de 2024 &#8211; \u00abHacer del Amor una realidad\u00bb","datePublished":"2024-03-05T02:00:22+00:00","mainEntityOfPage":{"@id":"https:\/\/regnumchristi.org\/martes-5-de-marzo-de-2024-hacer-del-amor-una-realidad\/"},"wordCount":898,"publisher":{"@id":"https:\/\/regnumchristi.org\/#organization"},"image":{"@id":"https:\/\/regnumchristi.org\/martes-5-de-marzo-de-2024-hacer-del-amor-una-realidad\/#primaryimage"},"thumbnailUrl":"https:\/\/regnumchristi.org\/wp-content\/uploads\/2024\/03\/imagenes_meditaciones_diarias_5mar.jpg","keywords":["Evangelio","meditaci\u00f3n","Reflexi\u00f3n"],"articleSection":["Meditaci\u00f3n del d\u00eda"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/regnumchristi.org\/martes-5-de-marzo-de-2024-hacer-del-amor-una-realidad\/","url":"https:\/\/regnumchristi.org\/martes-5-de-marzo-de-2024-hacer-del-amor-una-realidad\/","name":"Martes 5 de marzo de 2024 - \u00abHacer del Amor una realidad\u00bb - Regnum Christi Internacional","isPartOf":{"@id":"https:\/\/regnumchristi.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/regnumchristi.org\/martes-5-de-marzo-de-2024-hacer-del-amor-una-realidad\/#primaryimage"},"image":{"@id":"https:\/\/regnumchristi.org\/martes-5-de-marzo-de-2024-hacer-del-amor-una-realidad\/#primaryimage"},"thumbnailUrl":"https:\/\/regnumchristi.org\/wp-content\/uploads\/2024\/03\/imagenes_meditaciones_diarias_5mar.jpg","datePublished":"2024-03-05T02:00:22+00:00","description":"Admirar su paciencia es saber que Dios es paciente con cada uno de nosotros. Contemplar su misericordia es experimentar que Dios nos perdona.","breadcrumb":{"@id":"https:\/\/regnumchristi.org\/martes-5-de-marzo-de-2024-hacer-del-amor-una-realidad\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/regnumchristi.org\/martes-5-de-marzo-de-2024-hacer-del-amor-una-realidad\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/regnumchristi.org\/martes-5-de-marzo-de-2024-hacer-del-amor-una-realidad\/#primaryimage","url":"https:\/\/regnumchristi.org\/wp-content\/uploads\/2024\/03\/imagenes_meditaciones_diarias_5mar.jpg","contentUrl":"https:\/\/regnumchristi.org\/wp-content\/uploads\/2024\/03\/imagenes_meditaciones_diarias_5mar.jpg","width":900,"height":563},{"@type":"BreadcrumbList","@id":"https:\/\/regnumchristi.org\/martes-5-de-marzo-de-2024-hacer-del-amor-una-realidad\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/regnumchristi.org\/es\/"},{"@type":"ListItem","position":2,"name":"Martes 5 de marzo de 2024 &#8211; \u00abHacer del Amor una realidad\u00bb"}]},{"@type":"WebSite","@id":"https:\/\/regnumchristi.org\/#website","url":"https:\/\/regnumchristi.org\/","name":"Regnum Christi Internacional","description":"El Regnum Christi es una realidad de la Iglesia cat\u00f3lica cuya misi\u00f3n es hacer presente el Reino de Cristo","publisher":{"@id":"https:\/\/regnumchristi.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/regnumchristi.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/regnumchristi.org\/#organization","name":"Regnum Christi Internacional","url":"https:\/\/regnumchristi.org\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/regnumchristi.org\/#\/schema\/logo\/image\/","url":"https:\/\/regnumchristi.es\/wp-content\/uploads\/2023\/03\/Favicon-RC_ligh-cuadrado.png","contentUrl":"https:\/\/regnumchristi.es\/wp-content\/uploads\/2023\/03\/Favicon-RC_ligh-cuadrado.png","width":1080,"height":1080,"caption":"Regnum Christi Internacional"},"image":{"@id":"https:\/\/regnumchristi.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/RegnumChristiEspana\/","https:\/\/x.com\/rc_espana","https:\/\/www.instagram.com\/rc_espana\/","https:\/\/es.linkedin.com\/company\/regnumchristiespaa"]},{"@type":"Person","@id":"https:\/\/regnumchristi.org\/#\/schema\/person\/a5ad8b3c4bd3cb3a0abe8a1474fe8f0a","name":"Meditaciones Diarias","url":"https:\/\/regnumchristi.org\/es\/author\/meditacionesd\/"}]}},"_links":{"self":[{"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/posts\/101000","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/comments?post=101000"}],"version-history":[{"count":2,"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/posts\/101000\/revisions"}],"predecessor-version":[{"id":101023,"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/posts\/101000\/revisions\/101023"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/media\/101024"}],"wp:attachment":[{"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/media?parent=101000"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/categories?post=101000"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/tags?post=101000"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}