{"id":101171,"date":"2024-03-29T20:00:28","date_gmt":"2024-03-30T02:00:28","guid":{"rendered":"https:\/\/regnumchristi.org\/es\/?p=101171"},"modified":"2024-03-25T21:49:01","modified_gmt":"2024-03-26T03:49:01","slug":"sabado-30-de-marzo-de-2024-sabado-santo-testigos-de-la-grandeza-de-dios","status":"publish","type":"post","link":"https:\/\/regnumchristi.org\/es\/sabado-30-de-marzo-de-2024-sabado-santo-testigos-de-la-grandeza-de-dios\/","title":{"rendered":"S\u00e1bado 30 de marzo de 2024 &#8211; S\u00e1bado Santo &#8211; \u00abTestigos de la grandeza de Dios\u00bb"},"content":{"rendered":"<p><em>Michael Vargas, LC<\/em><\/p>\n<p>En el nombre del Padre y del Hijo y del Esp\u00edritu Santo.<br \/>\nAm\u00e9n.<\/p>\n<p>Cristo, Rey nuestro.<br \/>\n\u00a1Venga tu Reino!<\/p>\n<p><span style=\"color: #800000;\"><strong>Oraci\u00f3n preparatoria<\/strong><\/span>\u00a0<em>(para ponerme en presencia de Dios)<\/em><\/p>\n<p>Se\u00f1or Jes\u00fas, ens\u00e9\u00f1anos a ser verdaderos testigos de tu grandeza. El S\u00e1bado Santo la Iglesia se abstiene de celebrar el sacrificio de la Misa hasta que, despu\u00e9s de la Vigilia solemne se desborda la alegr\u00eda pascual. Por eso hoy incluimos como Evangelio del d\u00eda el que se lee en la Vigilia Pascual.<\/p>\n<p><span style=\"color: #800000;\"><strong>Evangelio del d\u00eda<\/strong><\/span>\u00a0<em>(para orientar tu meditaci\u00f3n)<\/em><br \/>\nDel santo Evangelio seg\u00fan san Marcos 16, 1-7<\/p>\n<p>Transcurrido el s\u00e1bado, Mar\u00eda Magdalena, Mar\u00eda (la madre de Santiago) y Salom\u00e9, compraron perfumes para ir a embalsamar a Jes\u00fas. Muy de madrugada, el primer d\u00eda de la semana, a la salida del sol, se dirigieron al sepulcro. Por el camino se dec\u00edan unas a otras: &#8220;\u00bfQui\u00e9n nos quitar\u00e1 la piedra de la entrada del sepulcro?&#8221;. Al llegar, vieron que la piedra estaba quitada, y eso que era muy grande. Entraron en el sepulcro y vieron a un joven vestido con una t\u00fanica blanca, sentado en el lado derecho, y se llenaron de miedo. Pero \u00e9l les dijo: &#8220;No se espanten. Buscan a Jes\u00fas de Nazaret, el que fue crucificado. No est\u00e1 aqu\u00ed. Ha resucitado. Miren el sitio donde lo hab\u00edan puesto. Ahora vayan a decirles a sus disc\u00edpulos y a Pedro: &#8216;\u00c9l ir\u00e1 delante de ustedes a Galilea. All\u00e1 lo ver\u00e1n, como \u00e9l les dijo'&#8221;.<\/p>\n<p><em>Palabra del Se\u00f1or.<\/em><\/p>\n<p><span style=\"color: #800000;\"><strong>Medita lo que Dios te dice en el Evangelio<\/strong><\/span><\/p>\n<p>Hay hechos que marcan nuestra existencia. Momentos o situaciones en los cuales, nos encontramos de frente a una realidad que nos sobrepasa. Ante ello, nos maravillamos o nos angustiamos, nos alegramos o nos entristecemos; haciendo cambiar espont\u00e1neamente nuestra manera de pensar, nuestra manera de ver o incluso nuestra manera de actuar. Ante estos hechos hay que comprender la realidad, la cual nos convierte en testigos o protagonistas de una experiencia o un hecho vivido, un acontecimiento que nos ha marcado.<\/p>\n<p>En el Evangelio de hoy nos encontramos ante este gran acontecimiento, la resurrecci\u00f3n de Jesucristo, lo cual nos convierte en testigos de la resurrecci\u00f3n de aqu\u00e9l que ha muerto y vuelto a la vida por cada uno de sus hijos. Es por ello que no podemos ser indiferentes ante este hecho, sino que debe de marcar nuestras vidas, pues es aqu\u00ed donde se experimenta claramente la grandeza y la acci\u00f3n de Dios omnipotente.<\/p>\n<p>Al experimentar esta grandeza, nos convertimos como Mar\u00eda Magdalena, Mar\u00eda (la madre de Santiago) y Salom\u00e9, en testigos de la grandeza de Dios y m\u00e1s a\u00fan palpamos en el fondo de nuestro coraz\u00f3n la resurrecci\u00f3n de Jesucristo, pues aqu\u00e9l que es testigo, no est\u00e1 llamado a tener una actitud pasiva, al contrario, est\u00e1 llamado a dar testimonio de aquello que ha vivido, a compartir aquella experiencia que ha hecho y m\u00e1s a\u00fan a dejarse cambiar por la mano bondadosa de un Dios, omnipotente, que ha revivido para estar presente en cada instante de la vida. Est\u00e1 llamado a transmitir la alegr\u00eda, a ser portador del gozo de haber experimentado el amor de un Dios, que ha muerto, pero que hoy, m\u00e1s que nunca, ha resucitado.<\/p>\n<p>Quien hace esta experiencia se convierte en testigo de la Resurrecci\u00f3n, porque en cierto sentido ha resucitado \u00e9l mismo, ha resucitado ella misma. Entonces es capaz de llevar un &#8220;rayo&#8221; de la luz del Resucitado en las diversas situaciones: en las felices, haci\u00e9ndolas m\u00e1s bellas y preserv\u00e1ndolas del ego\u00edsmo; y en las dolorosas, llevando serenidad y esperanza.<\/p>\n<p><em>\u00abLas mujeres en el sepulcro. Fueron a encontrar a un muerto, su viaje parec\u00eda in\u00fatil. Tambi\u00e9n ustedes van por el mundo a contracorriente: la vida del mundo rechaza f\u00e1cilmente la pobreza, la castidad y la obediencia. Pero, al igual que aquellas mujeres, van adelante, a pesar de la preocupaci\u00f3n por las piedras pesadas que hay que remover. Y al igual que aquellas mujeres, las primeras que encontraron al Se\u00f1or resucitado y vivo, se abrazan a \u00c9l y lo anuncian inmediatamente a los hermanos, con los ojos que brillan de alegr\u00eda\u00bb.<\/em><br \/>\n(Homil\u00eda de S.S. Francisco, 2 de febrero de 2018).<\/p>\n<p><span style=\"color: #800000;\"><strong>Di\u00e1logo con Cristo<\/strong><\/span><\/p>\n<p><em>\u00c9sta es la parte m\u00e1s importante de tu oraci\u00f3n, disponte a platicar con mucho amor con Aquel que te ama.<\/em><\/p>\n<p><span style=\"color: #800000;\"><strong>Prop\u00f3sito<\/strong><\/span><\/p>\n<p><em>Proponte uno personal. El que m\u00e1s amor implique en respuesta al Amado\u2026 o, si crees que es lo que Dios te pide, vive lo que se te sugiere a continuaci\u00f3n.<\/em><\/p>\n<p>Hoy dedicar\u00e9 unos minutos para estar en compa\u00f1\u00eda de aqu\u00e9l que ha resucitado y que est\u00e1 siempre a nuestro lado.<\/p>\n<p><span style=\"color: #800000;\"><strong>Despedida<\/strong><\/span><\/p>\n<p>Te damos gracias, Se\u00f1or, por todos tus beneficios, a ti que vives y reinas por los siglos de los siglos.<br \/>\nAm\u00e9n.<\/p>\n<p>\u00a1Cristo, Rey nuestro!<br \/>\n\u00a1Venga tu Reino!<\/p>\n<p>Virgen prudent\u00edsima, Mar\u00eda, Madre de la Iglesia.<br \/>\nRuega por nosotros.<\/p>\n<p>En el nombre del Padre y del Hijo y del Esp\u00edritu Santo.<br \/>\nAm\u00e9n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p> [&hellip;]<\/p>\n","protected":false},"author":58,"featured_media":101208,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"default","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"_daextrevop_audio_file_creation_date":"","_daextrevop_text_to_speech":"","_daextrevop_document_type":"","footnotes":""},"categories":[3164],"tags":[3162,3163,3067],"class_list":["post-101171","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-meditacion-del-dia","tag-evangelio","tag-meditacion","tag-reflexion"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>S\u00e1bado 30 de marzo de 2024 - S\u00e1bado Santo - \u00abTestigos de la grandeza de Dios\u00bb - Regnum Christi Internacional<\/title>\n<meta name=\"description\" content=\"El S\u00e1bado Santo la Iglesia se abstiene de celebrar la Misa hasta que, despu\u00e9s de la Vigilia solemne se desborda la alegr\u00eda pascual.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/regnumchristi.org\/es\/sabado-30-de-marzo-de-2024-sabado-santo-testigos-de-la-grandeza-de-dios\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"S\u00e1bado 30 de marzo de 2024 - S\u00e1bado Santo - \u00abTestigos de la grandeza de Dios\u00bb - Regnum Christi Internacional\" \/>\n<meta property=\"og:description\" content=\"El S\u00e1bado Santo la Iglesia se abstiene de celebrar la Misa hasta que, despu\u00e9s de la Vigilia solemne se desborda la alegr\u00eda pascual.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/regnumchristi.org\/es\/sabado-30-de-marzo-de-2024-sabado-santo-testigos-de-la-grandeza-de-dios\/\" \/>\n<meta property=\"og:site_name\" content=\"Regnum Christi Internacional\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/RegnumChristiEspana\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-30T02:00:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/regnumchristi.org\/wp-content\/uploads\/2024\/03\/Mar30-2024.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"563\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Meditaciones Diarias\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Meditaciones Diarias\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/sabado-30-de-marzo-de-2024-sabado-santo-testigos-de-la-grandeza-de-dios\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/sabado-30-de-marzo-de-2024-sabado-santo-testigos-de-la-grandeza-de-dios\\\/\"},\"author\":{\"name\":\"Meditaciones Diarias\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#\\\/schema\\\/person\\\/a5ad8b3c4bd3cb3a0abe8a1474fe8f0a\"},\"headline\":\"S\u00e1bado 30 de marzo de 2024 &#8211; S\u00e1bado Santo &#8211; \u00abTestigos de la grandeza de Dios\u00bb\",\"datePublished\":\"2024-03-30T02:00:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/sabado-30-de-marzo-de-2024-sabado-santo-testigos-de-la-grandeza-de-dios\\\/\"},\"wordCount\":897,\"publisher\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/sabado-30-de-marzo-de-2024-sabado-santo-testigos-de-la-grandeza-de-dios\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/regnumchristi.org\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/Mar30-2024.jpg\",\"keywords\":[\"Evangelio\",\"meditaci\u00f3n\",\"Reflexi\u00f3n\"],\"articleSection\":[\"Meditaci\u00f3n del d\u00eda\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/sabado-30-de-marzo-de-2024-sabado-santo-testigos-de-la-grandeza-de-dios\\\/\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/sabado-30-de-marzo-de-2024-sabado-santo-testigos-de-la-grandeza-de-dios\\\/\",\"name\":\"S\u00e1bado 30 de marzo de 2024 - S\u00e1bado Santo - \u00abTestigos de la grandeza de Dios\u00bb - Regnum Christi Internacional\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/sabado-30-de-marzo-de-2024-sabado-santo-testigos-de-la-grandeza-de-dios\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/sabado-30-de-marzo-de-2024-sabado-santo-testigos-de-la-grandeza-de-dios\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/regnumchristi.org\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/Mar30-2024.jpg\",\"datePublished\":\"2024-03-30T02:00:28+00:00\",\"description\":\"El S\u00e1bado Santo la Iglesia se abstiene de celebrar la Misa hasta que, despu\u00e9s de la Vigilia solemne se desborda la alegr\u00eda pascual.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/sabado-30-de-marzo-de-2024-sabado-santo-testigos-de-la-grandeza-de-dios\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/regnumchristi.org\\\/sabado-30-de-marzo-de-2024-sabado-santo-testigos-de-la-grandeza-de-dios\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/sabado-30-de-marzo-de-2024-sabado-santo-testigos-de-la-grandeza-de-dios\\\/#primaryimage\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/Mar30-2024.jpg\",\"contentUrl\":\"https:\\\/\\\/regnumchristi.org\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/Mar30-2024.jpg\",\"width\":900,\"height\":563},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/sabado-30-de-marzo-de-2024-sabado-santo-testigos-de-la-grandeza-de-dios\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/regnumchristi.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"S\u00e1bado 30 de marzo de 2024 &#8211; S\u00e1bado Santo &#8211; \u00abTestigos de la grandeza de Dios\u00bb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#website\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/\",\"name\":\"Regnum Christi Internacional\",\"description\":\"El Regnum Christi es una realidad de la Iglesia cat\u00f3lica cuya misi\u00f3n es hacer presente el Reino de Cristo\",\"publisher\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/regnumchristi.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#organization\",\"name\":\"Regnum Christi Internacional\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/regnumchristi.es\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Favicon-RC_ligh-cuadrado.png\",\"contentUrl\":\"https:\\\/\\\/regnumchristi.es\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Favicon-RC_ligh-cuadrado.png\",\"width\":1080,\"height\":1080,\"caption\":\"Regnum Christi Internacional\"},\"image\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/RegnumChristiEspana\\\/\",\"https:\\\/\\\/x.com\\\/rc_espana\",\"https:\\\/\\\/www.instagram.com\\\/rc_espana\\\/\",\"https:\\\/\\\/es.linkedin.com\\\/company\\\/regnumchristiespaa\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#\\\/schema\\\/person\\\/a5ad8b3c4bd3cb3a0abe8a1474fe8f0a\",\"name\":\"Meditaciones Diarias\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/es\\\/author\\\/meditacionesd\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"S\u00e1bado 30 de marzo de 2024 - S\u00e1bado Santo - \u00abTestigos de la grandeza de Dios\u00bb - Regnum Christi Internacional","description":"El S\u00e1bado Santo la Iglesia se abstiene de celebrar la Misa hasta que, despu\u00e9s de la Vigilia solemne se desborda la alegr\u00eda pascual.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/regnumchristi.org\/es\/sabado-30-de-marzo-de-2024-sabado-santo-testigos-de-la-grandeza-de-dios\/","og_locale":"es_MX","og_type":"article","og_title":"S\u00e1bado 30 de marzo de 2024 - S\u00e1bado Santo - \u00abTestigos de la grandeza de Dios\u00bb - Regnum Christi Internacional","og_description":"El S\u00e1bado Santo la Iglesia se abstiene de celebrar la Misa hasta que, despu\u00e9s de la Vigilia solemne se desborda la alegr\u00eda pascual.","og_url":"https:\/\/regnumchristi.org\/es\/sabado-30-de-marzo-de-2024-sabado-santo-testigos-de-la-grandeza-de-dios\/","og_site_name":"Regnum Christi Internacional","article_publisher":"https:\/\/www.facebook.com\/RegnumChristiEspana\/","article_published_time":"2024-03-30T02:00:28+00:00","og_image":[{"width":900,"height":563,"url":"https:\/\/regnumchristi.org\/wp-content\/uploads\/2024\/03\/Mar30-2024.jpg","type":"image\/jpeg"}],"author":"Meditaciones Diarias","twitter_misc":{"Escrito por":"Meditaciones Diarias","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/regnumchristi.org\/sabado-30-de-marzo-de-2024-sabado-santo-testigos-de-la-grandeza-de-dios\/#article","isPartOf":{"@id":"https:\/\/regnumchristi.org\/sabado-30-de-marzo-de-2024-sabado-santo-testigos-de-la-grandeza-de-dios\/"},"author":{"name":"Meditaciones Diarias","@id":"https:\/\/regnumchristi.org\/#\/schema\/person\/a5ad8b3c4bd3cb3a0abe8a1474fe8f0a"},"headline":"S\u00e1bado 30 de marzo de 2024 &#8211; S\u00e1bado Santo &#8211; \u00abTestigos de la grandeza de Dios\u00bb","datePublished":"2024-03-30T02:00:28+00:00","mainEntityOfPage":{"@id":"https:\/\/regnumchristi.org\/sabado-30-de-marzo-de-2024-sabado-santo-testigos-de-la-grandeza-de-dios\/"},"wordCount":897,"publisher":{"@id":"https:\/\/regnumchristi.org\/#organization"},"image":{"@id":"https:\/\/regnumchristi.org\/sabado-30-de-marzo-de-2024-sabado-santo-testigos-de-la-grandeza-de-dios\/#primaryimage"},"thumbnailUrl":"https:\/\/regnumchristi.org\/wp-content\/uploads\/2024\/03\/Mar30-2024.jpg","keywords":["Evangelio","meditaci\u00f3n","Reflexi\u00f3n"],"articleSection":["Meditaci\u00f3n del d\u00eda"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/regnumchristi.org\/sabado-30-de-marzo-de-2024-sabado-santo-testigos-de-la-grandeza-de-dios\/","url":"https:\/\/regnumchristi.org\/sabado-30-de-marzo-de-2024-sabado-santo-testigos-de-la-grandeza-de-dios\/","name":"S\u00e1bado 30 de marzo de 2024 - S\u00e1bado Santo - \u00abTestigos de la grandeza de Dios\u00bb - Regnum Christi Internacional","isPartOf":{"@id":"https:\/\/regnumchristi.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/regnumchristi.org\/sabado-30-de-marzo-de-2024-sabado-santo-testigos-de-la-grandeza-de-dios\/#primaryimage"},"image":{"@id":"https:\/\/regnumchristi.org\/sabado-30-de-marzo-de-2024-sabado-santo-testigos-de-la-grandeza-de-dios\/#primaryimage"},"thumbnailUrl":"https:\/\/regnumchristi.org\/wp-content\/uploads\/2024\/03\/Mar30-2024.jpg","datePublished":"2024-03-30T02:00:28+00:00","description":"El S\u00e1bado Santo la Iglesia se abstiene de celebrar la Misa hasta que, despu\u00e9s de la Vigilia solemne se desborda la alegr\u00eda pascual.","breadcrumb":{"@id":"https:\/\/regnumchristi.org\/sabado-30-de-marzo-de-2024-sabado-santo-testigos-de-la-grandeza-de-dios\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/regnumchristi.org\/sabado-30-de-marzo-de-2024-sabado-santo-testigos-de-la-grandeza-de-dios\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/regnumchristi.org\/sabado-30-de-marzo-de-2024-sabado-santo-testigos-de-la-grandeza-de-dios\/#primaryimage","url":"https:\/\/regnumchristi.org\/wp-content\/uploads\/2024\/03\/Mar30-2024.jpg","contentUrl":"https:\/\/regnumchristi.org\/wp-content\/uploads\/2024\/03\/Mar30-2024.jpg","width":900,"height":563},{"@type":"BreadcrumbList","@id":"https:\/\/regnumchristi.org\/sabado-30-de-marzo-de-2024-sabado-santo-testigos-de-la-grandeza-de-dios\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/regnumchristi.org\/es\/"},{"@type":"ListItem","position":2,"name":"S\u00e1bado 30 de marzo de 2024 &#8211; S\u00e1bado Santo &#8211; \u00abTestigos de la grandeza de Dios\u00bb"}]},{"@type":"WebSite","@id":"https:\/\/regnumchristi.org\/#website","url":"https:\/\/regnumchristi.org\/","name":"Regnum Christi Internacional","description":"El Regnum Christi es una realidad de la Iglesia cat\u00f3lica cuya misi\u00f3n es hacer presente el Reino de Cristo","publisher":{"@id":"https:\/\/regnumchristi.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/regnumchristi.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/regnumchristi.org\/#organization","name":"Regnum Christi Internacional","url":"https:\/\/regnumchristi.org\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/regnumchristi.org\/#\/schema\/logo\/image\/","url":"https:\/\/regnumchristi.es\/wp-content\/uploads\/2023\/03\/Favicon-RC_ligh-cuadrado.png","contentUrl":"https:\/\/regnumchristi.es\/wp-content\/uploads\/2023\/03\/Favicon-RC_ligh-cuadrado.png","width":1080,"height":1080,"caption":"Regnum Christi Internacional"},"image":{"@id":"https:\/\/regnumchristi.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/RegnumChristiEspana\/","https:\/\/x.com\/rc_espana","https:\/\/www.instagram.com\/rc_espana\/","https:\/\/es.linkedin.com\/company\/regnumchristiespaa"]},{"@type":"Person","@id":"https:\/\/regnumchristi.org\/#\/schema\/person\/a5ad8b3c4bd3cb3a0abe8a1474fe8f0a","name":"Meditaciones Diarias","url":"https:\/\/regnumchristi.org\/es\/author\/meditacionesd\/"}]}},"_links":{"self":[{"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/posts\/101171","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/comments?post=101171"}],"version-history":[{"count":2,"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/posts\/101171\/revisions"}],"predecessor-version":[{"id":101212,"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/posts\/101171\/revisions\/101212"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/media\/101208"}],"wp:attachment":[{"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/media?parent=101171"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/categories?post=101171"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/tags?post=101171"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}