{"id":102586,"date":"2024-06-20T13:15:32","date_gmt":"2024-06-20T19:15:32","guid":{"rendered":"https:\/\/regnumchristi.org\/es\/?p=102586"},"modified":"2024-06-14T09:51:55","modified_gmt":"2024-06-14T15:51:55","slug":"yios-francia-explorando-la-teologia-del-cuerpo-y-el-amor-verdadero","status":"publish","type":"post","link":"https:\/\/regnumchristi.org\/es\/yios-francia-explorando-la-teologia-del-cuerpo-y-el-amor-verdadero\/","title":{"rendered":"Yi\u00f3s Francia: explorando la teolog\u00eda del cuerpo y el amor verdadero"},"content":{"rendered":"<p>Durante el fin de semana de Pentecost\u00e9s, el grupo RC J\u00f3venes de Francia organiz\u00f3 un evento formativo intensivo sobre la Teolog\u00eda del Cuerpo, doctrina desarrollada por el Papa San Juan Pablo II. Bajo el lema &#8220;Ni\u00f1os amados de Dios: heridos, redimidos y llamados a la santidad&#8221;, 42 participantes y formadores se reunieron para profundizar en la comprensi\u00f3n de su identidad y vocaci\u00f3n cristiana.<\/p>\n<p>El evento, denominado &#8220;Yi\u00f3s&#8221;, ofreci\u00f3 un espacio para la reflexi\u00f3n sobre la vocaci\u00f3n al amor abordando la forma en que esta se manifiesta tanto en el matrimonio como en la vida consagrada. Durante tres d\u00edas, los asistentes tuvieron la oportunidad de explorar en profundidad lo que significa ser hijos amados de Dios, reconocer sus heridas por el pecado, su redenci\u00f3n en Cristo y su llamado a la santidad.<\/p>\n<p><strong>Testimonios y reflexiones personales<\/strong><\/p>\n<p>Th\u00e9ophane, uno de los participantes, comparti\u00f3 su experiencia, destacando que lleg\u00f3 al evento con grandes expectativas y se fue con un profundo deseo de vivir el amor seg\u00fan el llamado de Dios. <em>\u00abEste fin de semana de formaci\u00f3n fue muy denso y cargado de emociones, especialmente por los encuentros, los testimonios compartidos y las vigilias de adoraci\u00f3n\u00bb,<\/em> coment\u00f3.<\/p>\n<p>Amandine, otra asistente, expres\u00f3 c\u00f3mo el evento respondi\u00f3 a sus dudas sobre la percepci\u00f3n de la Iglesia frente a la sexualidad y el cuerpo. \u00ab<em>Aprend\u00ed que debemos prestar atenci\u00f3n a nuestro cuerpo tanto como a nuestra alma\u00bb,<\/em> mencion\u00f3, a\u00f1adiendo que la formaci\u00f3n le permiti\u00f3 entender la visi\u00f3n de la Iglesia sobre el cuerpo y la sexualidad de una manera m\u00e1s racional y menos emocional.<\/p>\n<p><a href=\"https:\/\/regnumchristi.org\/wp-content\/uploads\/2024\/06\/yios-france1.webp\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone wp-image-102588 size-full\" src=\"https:\/\/regnumchristi.org\/wp-content\/uploads\/2024\/06\/yios-france1.webp\" alt=\"Yios Enfoque integral\" width=\"900\" height=\"511\" srcset=\"https:\/\/regnumchristi.org\/wp-content\/uploads\/2024\/06\/yios-france1.webp 900w, https:\/\/regnumchristi.org\/wp-content\/uploads\/2024\/06\/yios-france1-300x170.webp 300w, https:\/\/regnumchristi.org\/wp-content\/uploads\/2024\/06\/yios-france1-768x436.webp 768w, https:\/\/regnumchristi.org\/wp-content\/uploads\/2024\/06\/yios-france1-200x114.webp 200w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/a><\/p>\n<p><strong>Un enfoque integral sobre el amor y la vocaci\u00f3n<\/strong><\/p>\n<p>El programa del fin de semana se dividi\u00f3 en dos partes: la primera abord\u00f3 la creaci\u00f3n del hombre desde una perspectiva originaria, hist\u00f3rica y escatol\u00f3gica; la segunda, se centr\u00f3 en la vocaci\u00f3n al amor, ya sea a trav\u00e9s de la virginidad cristiana o el matrimonio. Los participantes reflexionaron sobre temas fundamentales como la soledad, la unidad y la fecundidad del cuerpo humano, y c\u00f3mo estas experiencias y significados est\u00e1n integrados en la fe cristiana.<\/p>\n<p>Josuah, quien tambi\u00e9n particip\u00f3 en la formaci\u00f3n, destac\u00f3 la riqueza de los momentos de comuni\u00f3n y oraci\u00f3n <em>\u00abLos formadores nos brindaron una explicaci\u00f3n cristiana del amor de Dios y se tomaron el tiempo para responder a nuestras preguntas. Abordamos temas concretos como la castidad, el sacramento del matrimonio y la fecundidad\u00bb<\/em>, afirm\u00f3.<\/p>\n<p><strong>Un entorno propicio para la reflexi\u00f3n y la comunidad<\/strong><\/p>\n<p>El evento se llev\u00f3 a cabo en la <a href=\"https:\/\/www.regnumchristi.fr\/maison-regnum-christi\/\" target=\"_blank\" rel=\"noopener\">Casa Regnum Christi de M\u00e9ry-sur-Marne<\/a>, un lugar que proporcion\u00f3 un ambiente tranquilo y adecuado para la formaci\u00f3n. Los asistentes pudieron disfrutar de la capilla, la sala de conferencias, el comedor y las instalaciones deportivas.<\/p>\n<p>Adem\u00e1s de las sesiones formativas, hubo tiempo para actividades recreativas y manuales, como modelar cer\u00e1mica, que ayudaron a los participantes a conectar de manera creativa con las ense\u00f1anzas recibidas. \u00ab<em>Modelamos un portavelas para representar a Dios que nos model\u00f3 por amor, y luego se lo ofrecimos durante un momento de oraci\u00f3n\u00bb,<\/em> relat\u00f3 Josuah.<\/p>\n<p><a href=\"https:\/\/regnumchristi.org\/wp-content\/uploads\/2024\/06\/Yios-france2.webp\"><img decoding=\"async\" class=\"alignnone wp-image-102589 size-full\" src=\"https:\/\/regnumchristi.org\/wp-content\/uploads\/2024\/06\/Yios-france2.webp\" alt=\"Yios llamado a profundizar\" width=\"900\" height=\"515\" srcset=\"https:\/\/regnumchristi.org\/wp-content\/uploads\/2024\/06\/Yios-france2.webp 900w, https:\/\/regnumchristi.org\/wp-content\/uploads\/2024\/06\/Yios-france2-300x172.webp 300w, https:\/\/regnumchristi.org\/wp-content\/uploads\/2024\/06\/Yios-france2-768x439.webp 768w, https:\/\/regnumchristi.org\/wp-content\/uploads\/2024\/06\/Yios-france2-200x114.webp 200w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/a><\/p>\n<p><strong>Un llamado a profundizar en la fe<\/strong><\/p>\n<p>El fin de semana dej\u00f3 una huella profunda en los participantes, muchos de los cuales expresaron su deseo de seguir explorando y profundizando en la Teolog\u00eda del Cuerpo. <em>\u00abRecomendar\u00eda a todos participar en esta formaci\u00f3n. Salgo de este fin de semana enriquecido espiritualmente y con mis convicciones personales reforzadas\u00bb,<\/em> concluy\u00f3 Josuah.<\/p>\n<p>Este evento no solo proporcion\u00f3 una comprensi\u00f3n m\u00e1s profunda de la visi\u00f3n de la Iglesia sobre el amor y la sexualidad, sino que tambi\u00e9n foment\u00f3 una comunidad de fe y apoyo entre los participantes, quienes se van con nuevas amistades y un renovado compromiso con su vocaci\u00f3n cristiana.<\/p>\n<p>Con informaci\u00f3n de <a href=\"https:\/\/www.regnumchristi.fr\/enfants-bien-aimes-de-dieu\/\" target=\"_blank\" rel=\"noopener\">Regnum Chriti Francia<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p> [&hellip;]<\/p>\n","protected":false},"author":49,"featured_media":102590,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"default","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"_daextrevop_audio_file_creation_date":"","_daextrevop_text_to_speech":"","_daextrevop_document_type":"","footnotes":""},"categories":[1687],"tags":[],"class_list":["post-102586","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Yi\u00f3s Francia: explorando la teolog\u00eda del cuerpo y el amor verdadero - Regnum Christi Internacional<\/title>\n<meta name=\"description\" content=\"Durante el fin de semana de Pentecost\u00e9s, el grupo RC J\u00f3venes de Yios Francia organiz\u00f3 un evento formativo sobre la Teolog\u00eda del Cuerpo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/regnumchristi.org\/es\/yios-francia-explorando-la-teologia-del-cuerpo-y-el-amor-verdadero\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Yi\u00f3s Francia: explorando la teolog\u00eda del cuerpo y el amor verdadero - Regnum Christi Internacional\" \/>\n<meta property=\"og:description\" content=\"Durante el fin de semana de Pentecost\u00e9s, el grupo RC J\u00f3venes de Yios Francia organiz\u00f3 un evento formativo sobre la Teolog\u00eda del Cuerpo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/regnumchristi.org\/es\/yios-francia-explorando-la-teologia-del-cuerpo-y-el-amor-verdadero\/\" \/>\n<meta property=\"og:site_name\" content=\"Regnum Christi Internacional\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/RegnumChristiEspana\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-20T19:15:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/regnumchristi.org\/wp-content\/uploads\/2024\/06\/Yios-portada.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Autores varios\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Autores varios\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/yios-francia-explorando-la-teologia-del-cuerpo-y-el-amor-verdadero\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/yios-francia-explorando-la-teologia-del-cuerpo-y-el-amor-verdadero\\\/\"},\"author\":{\"name\":\"Autores varios\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#\\\/schema\\\/person\\\/73f2e414269cfbf8edecc2fd90af81f2\"},\"headline\":\"Yi\u00f3s Francia: explorando la teolog\u00eda del cuerpo y el amor verdadero\",\"datePublished\":\"2024-06-20T19:15:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/yios-francia-explorando-la-teologia-del-cuerpo-y-el-amor-verdadero\\\/\"},\"wordCount\":671,\"publisher\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/yios-francia-explorando-la-teologia-del-cuerpo-y-el-amor-verdadero\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/regnumchristi.org\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Yios-portada.webp\",\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/yios-francia-explorando-la-teologia-del-cuerpo-y-el-amor-verdadero\\\/\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/yios-francia-explorando-la-teologia-del-cuerpo-y-el-amor-verdadero\\\/\",\"name\":\"Yi\u00f3s Francia: explorando la teolog\u00eda del cuerpo y el amor verdadero - Regnum Christi Internacional\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/yios-francia-explorando-la-teologia-del-cuerpo-y-el-amor-verdadero\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/yios-francia-explorando-la-teologia-del-cuerpo-y-el-amor-verdadero\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/regnumchristi.org\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Yios-portada.webp\",\"datePublished\":\"2024-06-20T19:15:32+00:00\",\"description\":\"Durante el fin de semana de Pentecost\u00e9s, el grupo RC J\u00f3venes de Yios Francia organiz\u00f3 un evento formativo sobre la Teolog\u00eda del Cuerpo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/yios-francia-explorando-la-teologia-del-cuerpo-y-el-amor-verdadero\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/regnumchristi.org\\\/yios-francia-explorando-la-teologia-del-cuerpo-y-el-amor-verdadero\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/yios-francia-explorando-la-teologia-del-cuerpo-y-el-amor-verdadero\\\/#primaryimage\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Yios-portada.webp\",\"contentUrl\":\"https:\\\/\\\/regnumchristi.org\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Yios-portada.webp\",\"width\":900,\"height\":600,\"caption\":\"Grupo de Yios Francia 2024\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/yios-francia-explorando-la-teologia-del-cuerpo-y-el-amor-verdadero\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/regnumchristi.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Yi\u00f3s Francia: explorando la teolog\u00eda del cuerpo y el amor verdadero\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#website\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/\",\"name\":\"Regnum Christi Internacional\",\"description\":\"El Regnum Christi es una realidad de la Iglesia cat\u00f3lica cuya misi\u00f3n es hacer presente el Reino de Cristo\",\"publisher\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/regnumchristi.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#organization\",\"name\":\"Regnum Christi Internacional\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/regnumchristi.es\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Favicon-RC_ligh-cuadrado.png\",\"contentUrl\":\"https:\\\/\\\/regnumchristi.es\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Favicon-RC_ligh-cuadrado.png\",\"width\":1080,\"height\":1080,\"caption\":\"Regnum Christi Internacional\"},\"image\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/RegnumChristiEspana\\\/\",\"https:\\\/\\\/x.com\\\/rc_espana\",\"https:\\\/\\\/www.instagram.com\\\/rc_espana\\\/\",\"https:\\\/\\\/es.linkedin.com\\\/company\\\/regnumchristiespaa\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#\\\/schema\\\/person\\\/73f2e414269cfbf8edecc2fd90af81f2\",\"name\":\"Autores varios\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/es\\\/author\\\/jarceocaesc-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Yi\u00f3s Francia: explorando la teolog\u00eda del cuerpo y el amor verdadero - Regnum Christi Internacional","description":"Durante el fin de semana de Pentecost\u00e9s, el grupo RC J\u00f3venes de Yios Francia organiz\u00f3 un evento formativo sobre la Teolog\u00eda del Cuerpo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/regnumchristi.org\/es\/yios-francia-explorando-la-teologia-del-cuerpo-y-el-amor-verdadero\/","og_locale":"es_MX","og_type":"article","og_title":"Yi\u00f3s Francia: explorando la teolog\u00eda del cuerpo y el amor verdadero - Regnum Christi Internacional","og_description":"Durante el fin de semana de Pentecost\u00e9s, el grupo RC J\u00f3venes de Yios Francia organiz\u00f3 un evento formativo sobre la Teolog\u00eda del Cuerpo","og_url":"https:\/\/regnumchristi.org\/es\/yios-francia-explorando-la-teologia-del-cuerpo-y-el-amor-verdadero\/","og_site_name":"Regnum Christi Internacional","article_publisher":"https:\/\/www.facebook.com\/RegnumChristiEspana\/","article_published_time":"2024-06-20T19:15:32+00:00","og_image":[{"width":900,"height":600,"url":"https:\/\/regnumchristi.org\/wp-content\/uploads\/2024\/06\/Yios-portada.webp","type":"image\/webp"}],"author":"Autores varios","twitter_misc":{"Escrito por":"Autores varios","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/regnumchristi.org\/yios-francia-explorando-la-teologia-del-cuerpo-y-el-amor-verdadero\/#article","isPartOf":{"@id":"https:\/\/regnumchristi.org\/yios-francia-explorando-la-teologia-del-cuerpo-y-el-amor-verdadero\/"},"author":{"name":"Autores varios","@id":"https:\/\/regnumchristi.org\/#\/schema\/person\/73f2e414269cfbf8edecc2fd90af81f2"},"headline":"Yi\u00f3s Francia: explorando la teolog\u00eda del cuerpo y el amor verdadero","datePublished":"2024-06-20T19:15:32+00:00","mainEntityOfPage":{"@id":"https:\/\/regnumchristi.org\/yios-francia-explorando-la-teologia-del-cuerpo-y-el-amor-verdadero\/"},"wordCount":671,"publisher":{"@id":"https:\/\/regnumchristi.org\/#organization"},"image":{"@id":"https:\/\/regnumchristi.org\/yios-francia-explorando-la-teologia-del-cuerpo-y-el-amor-verdadero\/#primaryimage"},"thumbnailUrl":"https:\/\/regnumchristi.org\/wp-content\/uploads\/2024\/06\/Yios-portada.webp","articleSection":["Noticias"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/regnumchristi.org\/yios-francia-explorando-la-teologia-del-cuerpo-y-el-amor-verdadero\/","url":"https:\/\/regnumchristi.org\/yios-francia-explorando-la-teologia-del-cuerpo-y-el-amor-verdadero\/","name":"Yi\u00f3s Francia: explorando la teolog\u00eda del cuerpo y el amor verdadero - Regnum Christi Internacional","isPartOf":{"@id":"https:\/\/regnumchristi.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/regnumchristi.org\/yios-francia-explorando-la-teologia-del-cuerpo-y-el-amor-verdadero\/#primaryimage"},"image":{"@id":"https:\/\/regnumchristi.org\/yios-francia-explorando-la-teologia-del-cuerpo-y-el-amor-verdadero\/#primaryimage"},"thumbnailUrl":"https:\/\/regnumchristi.org\/wp-content\/uploads\/2024\/06\/Yios-portada.webp","datePublished":"2024-06-20T19:15:32+00:00","description":"Durante el fin de semana de Pentecost\u00e9s, el grupo RC J\u00f3venes de Yios Francia organiz\u00f3 un evento formativo sobre la Teolog\u00eda del Cuerpo","breadcrumb":{"@id":"https:\/\/regnumchristi.org\/yios-francia-explorando-la-teologia-del-cuerpo-y-el-amor-verdadero\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/regnumchristi.org\/yios-francia-explorando-la-teologia-del-cuerpo-y-el-amor-verdadero\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/regnumchristi.org\/yios-francia-explorando-la-teologia-del-cuerpo-y-el-amor-verdadero\/#primaryimage","url":"https:\/\/regnumchristi.org\/wp-content\/uploads\/2024\/06\/Yios-portada.webp","contentUrl":"https:\/\/regnumchristi.org\/wp-content\/uploads\/2024\/06\/Yios-portada.webp","width":900,"height":600,"caption":"Grupo de Yios Francia 2024"},{"@type":"BreadcrumbList","@id":"https:\/\/regnumchristi.org\/yios-francia-explorando-la-teologia-del-cuerpo-y-el-amor-verdadero\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/regnumchristi.org\/es\/"},{"@type":"ListItem","position":2,"name":"Yi\u00f3s Francia: explorando la teolog\u00eda del cuerpo y el amor verdadero"}]},{"@type":"WebSite","@id":"https:\/\/regnumchristi.org\/#website","url":"https:\/\/regnumchristi.org\/","name":"Regnum Christi Internacional","description":"El Regnum Christi es una realidad de la Iglesia cat\u00f3lica cuya misi\u00f3n es hacer presente el Reino de Cristo","publisher":{"@id":"https:\/\/regnumchristi.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/regnumchristi.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/regnumchristi.org\/#organization","name":"Regnum Christi Internacional","url":"https:\/\/regnumchristi.org\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/regnumchristi.org\/#\/schema\/logo\/image\/","url":"https:\/\/regnumchristi.es\/wp-content\/uploads\/2023\/03\/Favicon-RC_ligh-cuadrado.png","contentUrl":"https:\/\/regnumchristi.es\/wp-content\/uploads\/2023\/03\/Favicon-RC_ligh-cuadrado.png","width":1080,"height":1080,"caption":"Regnum Christi Internacional"},"image":{"@id":"https:\/\/regnumchristi.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/RegnumChristiEspana\/","https:\/\/x.com\/rc_espana","https:\/\/www.instagram.com\/rc_espana\/","https:\/\/es.linkedin.com\/company\/regnumchristiespaa"]},{"@type":"Person","@id":"https:\/\/regnumchristi.org\/#\/schema\/person\/73f2e414269cfbf8edecc2fd90af81f2","name":"Autores varios","url":"https:\/\/regnumchristi.org\/es\/author\/jarceocaesc-com\/"}]}},"_links":{"self":[{"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/posts\/102586","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/users\/49"}],"replies":[{"embeddable":true,"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/comments?post=102586"}],"version-history":[{"count":1,"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/posts\/102586\/revisions"}],"predecessor-version":[{"id":102591,"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/posts\/102586\/revisions\/102591"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/media\/102590"}],"wp:attachment":[{"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/media?parent=102586"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/categories?post=102586"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/tags?post=102586"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}