{"id":105473,"date":"2024-09-13T19:09:48","date_gmt":"2024-09-14T01:09:48","guid":{"rendered":"https:\/\/regnumchristi.org\/es\/?p=105473"},"modified":"2024-09-13T19:09:48","modified_gmt":"2024-09-14T01:09:48","slug":"sabado-14-de-septiembre-de-2024-para-salvarte","status":"publish","type":"post","link":"https:\/\/regnumchristi.org\/es\/sabado-14-de-septiembre-de-2024-para-salvarte\/","title":{"rendered":"S\u00e1bado 14 de septiembre de 2024 &#8211; \u00abPara salvarte\u00bb"},"content":{"rendered":"<p>En el nombre del Padre y del Hijo y del Esp\u00edritu Santo.<br \/>\nAm\u00e9n.<\/p>\n<p>Cristo, Rey nuestro.<br \/>\n\u00a1Venga tu Reino!<\/p>\n<p><span style=\"color: #800000;\"><strong>Oraci\u00f3n preparatoria<\/strong><\/span>\u00a0<em>(para ponerme en presencia de Dios)<\/em><\/p>\n<p>Se\u00f1or Jes\u00fas, hoy que se celebra la Santa Cruz, en algunos pa\u00edses, quiero agradecerte el que hayas aceptado el anonadarte a ti mismo para venir a salvarme. Que nunca me acostumbre o sea indiferente ante tu sacrificio en la cruz. Conc\u00e9deme que en esta oraci\u00f3n pueda percibir un poco m\u00e1s tu amor, vivo y verdadero, para buscar, con tu gracia, corresponderte.<\/p>\n<p><span style=\"color: #800000;\"><strong>Evangelio del d\u00eda<\/strong><\/span>\u00a0<em>(para orientar tu meditaci\u00f3n)<\/em><br \/>\nSanto Evangelio seg\u00fan San Juan 3, 13-17<\/p>\n<p>En aquel tiempo Jes\u00fas dijo a Nicodemo: Nadie ha subido al cielo sino el que baj\u00f3 del cielo, el Hijo del hombre. Y como Mois\u00e9s levant\u00f3 la serpiente en el desierto, as\u00ed tiene que ser levantado el Hijo del hombre, para que todo el que crea tenga por \u00c9l vida eterna. Porque tanto am\u00f3 Dios al mundo que dio a su Hijo \u00fanico, para que todo el que crea en \u00c9l no perezca, sino que tenga vida eterna. Porque Dios no ha enviado a su Hijo al mundo para juzgar al mundo, sino para que el mundo se salve por \u00c9l.<\/p>\n<p><em>Palabra del Se\u00f1or<\/em><\/p>\n<p><span style=\"color: #800000;\"><strong>Medita lo que Dios te dice en el Evangelio<\/strong><\/span><\/p>\n<p>Hoy celebramos la fiesta de la Cruz, s\u00edmbolo del cristiano. En este di\u00e1logo entre Jes\u00fas y Nicodemo se anuncia de una manera oculta el momento supremo de la vida de nuestro Salvador: la crucifixi\u00f3n.<\/p>\n<p>La cruz no es s\u00f3lo un s\u00edmbolo material, sino la gu\u00eda de nuestra vida.<\/p>\n<p>Dios en su gran amor, viendo la necesidad que ten\u00eda el mundo de ser salvado, no dud\u00f3 en entregar a su propio Hijo para su salvaci\u00f3n. Las circunstancias hist\u00f3ricas concurrieron para que la redenci\u00f3n se realizara por medio de la cruz. A partir de este acontecimiento la cruz se ha convertido en se\u00f1al de salvaci\u00f3n para todo el que cree que Jes\u00fas es el redentor del hombre.<\/p>\n<p>A pesar de que Jes\u00fas se puso el primero en el padecer no nos resulta f\u00e1cil asumir la realidad de la cruz y todos la esquivamos de la mejor manera posible. Pero si ser cristiano es seguir al crucificado, \u00bfpor qu\u00e9 rehusamos seguir sus huellas? S\u00f3lo desde el amor se entiende esta entrega, y s\u00f3lo el amor hace posible convertir en alegr\u00eda las mayores angustias de la vida. Es cuesti\u00f3n de amor, y cuando algo nos cuesta mucho es se\u00f1al de que el term\u00f3metro del amor marca baja temperatura.<\/p>\n<p><em>\u00abLa oraci\u00f3n, expresi\u00f3n de apertura y de confianza en el Se\u00f1or: es el encuentro personal con \u00c9l, que acorta las distancias creadas por el pecado. Rezar significa decir: \u201cno soy autosuficiente, te necesito, T\u00fa eres mi vida y mi salvaci\u00f3n\u201d\u00bb.<\/em><br \/>\n(Homil\u00eda de S.S. Francisco, 10 de febrero de 2016).<\/p>\n<p><span style=\"color: #800000;\"><strong>Di\u00e1logo con Cristo<\/strong><\/span><\/p>\n<p><em>\u00c9sta es la parte m\u00e1s importante de tu oraci\u00f3n, disponte a platicar con mucho amor con Aquel que te ama.<\/em><\/p>\n<p><span style=\"color: #800000;\"><strong>Prop\u00f3sito<\/strong><\/span><\/p>\n<p><em>Proponte uno personal. El que m\u00e1s amor implique en respuesta al Amado\u2026 o, si crees que es lo que Dios te pide, vive lo que se te sugiere a continuaci\u00f3n.<\/em><\/p>\n<p>Participar en una hora eucar\u00edstica o hacer un acto de adoraci\u00f3n a la Santa Cruz.<\/p>\n<p><span style=\"color: #800000;\"><strong>Despedida<\/strong><\/span><\/p>\n<p>\u00a1Cristo, Rey nuestro!<br \/>\n\u00a1Venga tu Reino!<\/p>\n<p>Virgen prudent\u00edsima, Mar\u00eda, Madre de la Iglesia.<br \/>\nRuega por nosotros.<\/p>\n<p>En el nombre del Padre y del Hijo y del Esp\u00edritu Santo.<br \/>\nAm\u00e9n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p> [&hellip;]<\/p>\n","protected":false},"author":58,"featured_media":34334,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"default","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"_daextrevop_audio_file_creation_date":"","_daextrevop_text_to_speech":"","_daextrevop_document_type":"","footnotes":""},"categories":[3164],"tags":[3162,3163,3067],"class_list":["post-105473","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-meditacion-del-dia","tag-evangelio","tag-meditacion","tag-reflexion"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>S\u00e1bado 14 de septiembre de 2024 - \u00abPara salvarte\u00bb - Regnum Christi Internacional<\/title>\n<meta name=\"description\" content=\"Conc\u00e9deme que en esta oraci\u00f3n pueda percibir un poco m\u00e1s tu amor, vivo y verdadero. Para salvarte. Gracias, Se\u00f1or.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/regnumchristi.org\/es\/sabado-14-de-septiembre-de-2024-para-salvarte\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"S\u00e1bado 14 de septiembre de 2024 - \u00abPara salvarte\u00bb - Regnum Christi Internacional\" \/>\n<meta property=\"og:description\" content=\"Conc\u00e9deme que en esta oraci\u00f3n pueda percibir un poco m\u00e1s tu amor, vivo y verdadero. Para salvarte. Gracias, Se\u00f1or.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/regnumchristi.org\/es\/sabado-14-de-septiembre-de-2024-para-salvarte\/\" \/>\n<meta property=\"og:site_name\" content=\"Regnum Christi Internacional\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/RegnumChristiEspana\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-09-14T01:09:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/regnumchristi.org\/wp-content\/uploads\/2022\/09\/Imagenes-Meditaciones-Diarias-12-de-septiembre.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"563\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Meditaciones Diarias\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Meditaciones Diarias\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/sabado-14-de-septiembre-de-2024-para-salvarte\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/sabado-14-de-septiembre-de-2024-para-salvarte\\\/\"},\"author\":{\"name\":\"Meditaciones Diarias\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#\\\/schema\\\/person\\\/a5ad8b3c4bd3cb3a0abe8a1474fe8f0a\"},\"headline\":\"S\u00e1bado 14 de septiembre de 2024 &#8211; \u00abPara salvarte\u00bb\",\"datePublished\":\"2024-09-14T01:09:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/sabado-14-de-septiembre-de-2024-para-salvarte\\\/\"},\"wordCount\":627,\"publisher\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/sabado-14-de-septiembre-de-2024-para-salvarte\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/regnumchristi.org\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/Imagenes-Meditaciones-Diarias-12-de-septiembre.jpg\",\"keywords\":[\"Evangelio\",\"meditaci\u00f3n\",\"Reflexi\u00f3n\"],\"articleSection\":[\"Meditaci\u00f3n del d\u00eda\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/sabado-14-de-septiembre-de-2024-para-salvarte\\\/\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/sabado-14-de-septiembre-de-2024-para-salvarte\\\/\",\"name\":\"S\u00e1bado 14 de septiembre de 2024 - \u00abPara salvarte\u00bb - Regnum Christi Internacional\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/sabado-14-de-septiembre-de-2024-para-salvarte\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/sabado-14-de-septiembre-de-2024-para-salvarte\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/regnumchristi.org\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/Imagenes-Meditaciones-Diarias-12-de-septiembre.jpg\",\"datePublished\":\"2024-09-14T01:09:48+00:00\",\"description\":\"Conc\u00e9deme que en esta oraci\u00f3n pueda percibir un poco m\u00e1s tu amor, vivo y verdadero. Para salvarte. Gracias, Se\u00f1or.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/sabado-14-de-septiembre-de-2024-para-salvarte\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/regnumchristi.org\\\/sabado-14-de-septiembre-de-2024-para-salvarte\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/sabado-14-de-septiembre-de-2024-para-salvarte\\\/#primaryimage\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/Imagenes-Meditaciones-Diarias-12-de-septiembre.jpg\",\"contentUrl\":\"https:\\\/\\\/regnumchristi.org\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/Imagenes-Meditaciones-Diarias-12-de-septiembre.jpg\",\"width\":900,\"height\":563,\"caption\":\"Para salvarte\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/sabado-14-de-septiembre-de-2024-para-salvarte\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/regnumchristi.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"S\u00e1bado 14 de septiembre de 2024 &#8211; \u00abPara salvarte\u00bb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#website\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/\",\"name\":\"Regnum Christi Internacional\",\"description\":\"El Regnum Christi es una realidad de la Iglesia cat\u00f3lica cuya misi\u00f3n es hacer presente el Reino de Cristo\",\"publisher\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/regnumchristi.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#organization\",\"name\":\"Regnum Christi Internacional\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/regnumchristi.es\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Favicon-RC_ligh-cuadrado.png\",\"contentUrl\":\"https:\\\/\\\/regnumchristi.es\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Favicon-RC_ligh-cuadrado.png\",\"width\":1080,\"height\":1080,\"caption\":\"Regnum Christi Internacional\"},\"image\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/RegnumChristiEspana\\\/\",\"https:\\\/\\\/x.com\\\/rc_espana\",\"https:\\\/\\\/www.instagram.com\\\/rc_espana\\\/\",\"https:\\\/\\\/es.linkedin.com\\\/company\\\/regnumchristiespaa\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#\\\/schema\\\/person\\\/a5ad8b3c4bd3cb3a0abe8a1474fe8f0a\",\"name\":\"Meditaciones Diarias\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/es\\\/author\\\/meditacionesd\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"S\u00e1bado 14 de septiembre de 2024 - \u00abPara salvarte\u00bb - Regnum Christi Internacional","description":"Conc\u00e9deme que en esta oraci\u00f3n pueda percibir un poco m\u00e1s tu amor, vivo y verdadero. Para salvarte. Gracias, Se\u00f1or.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/regnumchristi.org\/es\/sabado-14-de-septiembre-de-2024-para-salvarte\/","og_locale":"es_MX","og_type":"article","og_title":"S\u00e1bado 14 de septiembre de 2024 - \u00abPara salvarte\u00bb - Regnum Christi Internacional","og_description":"Conc\u00e9deme que en esta oraci\u00f3n pueda percibir un poco m\u00e1s tu amor, vivo y verdadero. Para salvarte. Gracias, Se\u00f1or.","og_url":"https:\/\/regnumchristi.org\/es\/sabado-14-de-septiembre-de-2024-para-salvarte\/","og_site_name":"Regnum Christi Internacional","article_publisher":"https:\/\/www.facebook.com\/RegnumChristiEspana\/","article_published_time":"2024-09-14T01:09:48+00:00","og_image":[{"width":900,"height":563,"url":"https:\/\/regnumchristi.org\/wp-content\/uploads\/2022\/09\/Imagenes-Meditaciones-Diarias-12-de-septiembre.jpg","type":"image\/jpeg"}],"author":"Meditaciones Diarias","twitter_misc":{"Escrito por":"Meditaciones Diarias","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/regnumchristi.org\/sabado-14-de-septiembre-de-2024-para-salvarte\/#article","isPartOf":{"@id":"https:\/\/regnumchristi.org\/sabado-14-de-septiembre-de-2024-para-salvarte\/"},"author":{"name":"Meditaciones Diarias","@id":"https:\/\/regnumchristi.org\/#\/schema\/person\/a5ad8b3c4bd3cb3a0abe8a1474fe8f0a"},"headline":"S\u00e1bado 14 de septiembre de 2024 &#8211; \u00abPara salvarte\u00bb","datePublished":"2024-09-14T01:09:48+00:00","mainEntityOfPage":{"@id":"https:\/\/regnumchristi.org\/sabado-14-de-septiembre-de-2024-para-salvarte\/"},"wordCount":627,"publisher":{"@id":"https:\/\/regnumchristi.org\/#organization"},"image":{"@id":"https:\/\/regnumchristi.org\/sabado-14-de-septiembre-de-2024-para-salvarte\/#primaryimage"},"thumbnailUrl":"https:\/\/regnumchristi.org\/wp-content\/uploads\/2022\/09\/Imagenes-Meditaciones-Diarias-12-de-septiembre.jpg","keywords":["Evangelio","meditaci\u00f3n","Reflexi\u00f3n"],"articleSection":["Meditaci\u00f3n del d\u00eda"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/regnumchristi.org\/sabado-14-de-septiembre-de-2024-para-salvarte\/","url":"https:\/\/regnumchristi.org\/sabado-14-de-septiembre-de-2024-para-salvarte\/","name":"S\u00e1bado 14 de septiembre de 2024 - \u00abPara salvarte\u00bb - Regnum Christi Internacional","isPartOf":{"@id":"https:\/\/regnumchristi.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/regnumchristi.org\/sabado-14-de-septiembre-de-2024-para-salvarte\/#primaryimage"},"image":{"@id":"https:\/\/regnumchristi.org\/sabado-14-de-septiembre-de-2024-para-salvarte\/#primaryimage"},"thumbnailUrl":"https:\/\/regnumchristi.org\/wp-content\/uploads\/2022\/09\/Imagenes-Meditaciones-Diarias-12-de-septiembre.jpg","datePublished":"2024-09-14T01:09:48+00:00","description":"Conc\u00e9deme que en esta oraci\u00f3n pueda percibir un poco m\u00e1s tu amor, vivo y verdadero. Para salvarte. Gracias, Se\u00f1or.","breadcrumb":{"@id":"https:\/\/regnumchristi.org\/sabado-14-de-septiembre-de-2024-para-salvarte\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/regnumchristi.org\/sabado-14-de-septiembre-de-2024-para-salvarte\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/regnumchristi.org\/sabado-14-de-septiembre-de-2024-para-salvarte\/#primaryimage","url":"https:\/\/regnumchristi.org\/wp-content\/uploads\/2022\/09\/Imagenes-Meditaciones-Diarias-12-de-septiembre.jpg","contentUrl":"https:\/\/regnumchristi.org\/wp-content\/uploads\/2022\/09\/Imagenes-Meditaciones-Diarias-12-de-septiembre.jpg","width":900,"height":563,"caption":"Para salvarte"},{"@type":"BreadcrumbList","@id":"https:\/\/regnumchristi.org\/sabado-14-de-septiembre-de-2024-para-salvarte\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/regnumchristi.org\/es\/"},{"@type":"ListItem","position":2,"name":"S\u00e1bado 14 de septiembre de 2024 &#8211; \u00abPara salvarte\u00bb"}]},{"@type":"WebSite","@id":"https:\/\/regnumchristi.org\/#website","url":"https:\/\/regnumchristi.org\/","name":"Regnum Christi Internacional","description":"El Regnum Christi es una realidad de la Iglesia cat\u00f3lica cuya misi\u00f3n es hacer presente el Reino de Cristo","publisher":{"@id":"https:\/\/regnumchristi.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/regnumchristi.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/regnumchristi.org\/#organization","name":"Regnum Christi Internacional","url":"https:\/\/regnumchristi.org\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/regnumchristi.org\/#\/schema\/logo\/image\/","url":"https:\/\/regnumchristi.es\/wp-content\/uploads\/2023\/03\/Favicon-RC_ligh-cuadrado.png","contentUrl":"https:\/\/regnumchristi.es\/wp-content\/uploads\/2023\/03\/Favicon-RC_ligh-cuadrado.png","width":1080,"height":1080,"caption":"Regnum Christi Internacional"},"image":{"@id":"https:\/\/regnumchristi.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/RegnumChristiEspana\/","https:\/\/x.com\/rc_espana","https:\/\/www.instagram.com\/rc_espana\/","https:\/\/es.linkedin.com\/company\/regnumchristiespaa"]},{"@type":"Person","@id":"https:\/\/regnumchristi.org\/#\/schema\/person\/a5ad8b3c4bd3cb3a0abe8a1474fe8f0a","name":"Meditaciones Diarias","url":"https:\/\/regnumchristi.org\/es\/author\/meditacionesd\/"}]}},"_links":{"self":[{"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/posts\/105473","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/comments?post=105473"}],"version-history":[{"count":1,"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/posts\/105473\/revisions"}],"predecessor-version":[{"id":105474,"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/posts\/105473\/revisions\/105474"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/media\/34334"}],"wp:attachment":[{"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/media?parent=105473"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/categories?post=105473"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/tags?post=105473"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}