{"id":11356,"date":"2023-02-07T20:00:35","date_gmt":"2023-02-08T02:00:35","guid":{"rendered":"http:\/\/www.regnumchristi.org\/es\/?p=11356"},"modified":"2023-08-02T13:33:09","modified_gmt":"2023-08-02T19:33:09","slug":"miercoles-8-de-febrero-de-2023-un-corazon-nuevo","status":"publish","type":"post","link":"https:\/\/regnumchristi.org\/es\/miercoles-8-de-febrero-de-2023-un-corazon-nuevo\/","title":{"rendered":"Mi\u00e9rcoles 8 de febrero de 2023 &#8211; \u00abUn coraz\u00f3n nuevo\u00bb"},"content":{"rendered":"<p><em>Balam Loza, LC<\/em><\/p>\n<p>En el nombre del Padre y del Hijo y del Esp\u00edritu Santo.<br \/>\nAm\u00e9n.<\/p>\n<p>Cristo, Rey nuestro.<br \/>\n\u00a1Venga tu Reino!<\/p>\n<p><span style=\"color: #800000;\"><strong>Oraci\u00f3n preparatoria<\/strong><\/span> <em>(para ponerme en presencia de Dios)<\/em><\/p>\n<p>Se\u00f1or, purifica mi coraz\u00f3n, dame un coraz\u00f3n nuevo. Qu\u00edtame el coraz\u00f3n de piedra y dame un coraz\u00f3n de carne para que sepa amar. Ay\u00fadame a darme cuenta del gran amor que T\u00fa me tienes para que aprenda a ser un hermano con mis hermanos. Quiero gozar, en este momento, del gran amor que me tienes para despu\u00e9s llevar esta experiencia de tu amor a los que est\u00e1n necesitados de ti.<\/p>\n<p><span style=\"color: #800000;\"><strong>Evangelio del d\u00eda<\/strong><\/span> <em>(para orientar tu meditaci\u00f3n)<br \/>\n<\/em>Del santo Evangelio seg\u00fan san Marcos 7, 14-23<\/p>\n<p>En aquel tiempo, Jes\u00fas llam\u00f3 de nuevo a la gente y les dijo: \u201cEsc\u00fachenme todos y enti\u00e9ndanme. Nada que entre de fuera puede manchar al hombre; lo que s\u00ed lo mancha es lo que sale de dentro\u201d. Cuando entr\u00f3 en una casa para alejarse de la muchedumbre, los disc\u00edpulos le preguntaron qu\u00e9 quer\u00eda decir aquella par\u00e1bola. \u00c9l les dijo: \u201c\u00bfUstedes tambi\u00e9n son incapaces de comprender? \u00bfNo entienden que nada de lo que entra en el hombre desde afuera puede contaminarlo, porque no entra en su coraz\u00f3n, sino en el vientre y despu\u00e9s, sale del cuerpo?\u201d Con estas palabras declaraba limpios todos los alimentos. Luego agreg\u00f3: \u201cLo que s\u00ed mancha al hombre es lo que sale de dentro; porque del coraz\u00f3n del hombre salen las intenciones malas, las fornicaciones, los robos, los homicidios, los adulterios, las codicias, las injusticias, los fraudes, el desenfreno, las envidias, la difamaci\u00f3n, el orgullo y la frivolidad. Todas estas maldades salen de dentro y manchan al hombre\u201d.<\/p>\n<p><em>Palabra del Se\u00f1or.<\/em><\/p>\n<p><span style=\"color: #800000;\"><strong>Medita lo que Dios te dice en el Evangelio<\/strong><\/span><\/p>\n<p>\u00bfQu\u00e9 es lo que pasa cuando pensamos mal de alguien o lo criticamos? \u00bfDe d\u00f3nde vienen esos sentimientos negativos? \u00bfPor qu\u00e9 vemos de forma distinta los defectos del amigo y los defectos del vecino del cual ya estamos cansados? \u00bfQu\u00e9 pasar\u00eda si en lugar de centrarnos en los aspectos negativos y los defectos de alguien vi\u00e9semos sus cualidades? Y con estas preguntas nos podemos dar cuenta que muchas veces la visi\u00f3n del mundo parte de nuestro interior. Podemos ver las cosas con un esp\u00edritu positivo o podemos ver todo de forma oscura.<\/p>\n<p>Por eso es necesario renovar nuestro coraz\u00f3n y hacerlo como el de un ni\u00f1o. Dejar a un lado nuestros intereses y amar con un coraz\u00f3n puro. Pienso que los ni\u00f1os nos ense\u00f1an muchas cosas, a ser felices; a ver las cosas con sencillez y no hacernos l\u00edos; a saber re\u00edr de uno mismo y a perdonar. Los ni\u00f1os son grandes porque no se quedan encerrados en sus problemas sino que saben abrir el coraz\u00f3n para recibir a todos, sea quien sea y piense como piense.<\/p>\n<p>Jes\u00fas, dame un coraz\u00f3n que sepa amar sin c\u00e1lculos ni medidas. Un coraz\u00f3n que no se limite ante las dificultades sino que sepa abrir el coraz\u00f3n a todos, sin temor a ser herido o humillado. Un coraz\u00f3n con buen humor para que sepa ver mis propias flaquezas y re\u00edrme de ellas. Un coraz\u00f3n inteligente que sepa ver en el otro no una barrera sino un amigo y un compa\u00f1ero. Un coraz\u00f3n que sepa dar y ver en los dem\u00e1s a hermanos necesitados de un consejo o un abrazo. Un coraz\u00f3n de ni\u00f1o.<\/p>\n<p><em>\u00abDe diversos modos la Sagrada Escritura nos dice que las intenciones buenas y malas no entran en el hombre desde el exterior, sino que brotan de su \u201ccoraz\u00f3n\u201d. \u201cDe dentro \u2014afirma Jes\u00fas\u2014, del coraz\u00f3n de los hombres, salen las intenciones malas\u201d. En la Biblia, el coraz\u00f3n es el \u00f3rgano no s\u00f3lo de los afectos, sino tambi\u00e9n de las facultades espirituales, la raz\u00f3n y la voluntad, es la sede de las decisiones, del modo de pensar y de obrar. La sabidur\u00eda de las elecciones, abierta al movimiento del Esp\u00edritu Santo, compromete tambi\u00e9n el coraz\u00f3n. De aqu\u00ed nacen las obras buenas, pero tambi\u00e9n las que son fruto de una equivocaci\u00f3n, cuando se rechaza la verdad y las sugerencias del Esp\u00edritu\u00bb.<\/em><br \/>\n<em>(Homil\u00eda de S.S. Francisco, 3 de marzo de 2016).<\/em><\/p>\n<p><span style=\"color: #800000;\"><strong>Di\u00e1logo con Cristo<\/strong><\/span><\/p>\n<p><em>\u00c9sta es la parte m\u00e1s importante de tu oraci\u00f3n, disponte a platicar con mucho amor con Aquel que te ama.<\/em><\/p>\n<p><span style=\"color: #800000;\"><strong>Prop\u00f3sito<\/strong><\/span><\/p>\n<p><em>Proponte uno personal. El que m\u00e1s amor implique en respuesta al Amado\u2026 o, si crees que es lo que Dios te pide, vive lo que se te sugiere a continuaci\u00f3n.<\/em><\/p>\n<p>Hoy, Jes\u00fas, voy a vivir viendo lo positivo de todos. Voy a tratar a los dem\u00e1s con especial delicadeza y si alguien me cae mal pasar\u00e9 un tiempo con \u00e9l.<\/p>\n<p><span style=\"color: #800000;\"><strong>Despedida<\/strong><\/span><\/p>\n<p>Te damos gracias, Se\u00f1or, por todos tus beneficios, a ti que vives y reinas por los siglos de los siglos.<br \/>\nAm\u00e9n.<\/p>\n<p>\u00a1Cristo, Rey nuestro!<br \/>\n\u00a1Venga tu Reino!<\/p>\n<p>Virgen prudent\u00edsima, Mar\u00eda, Madre de la Iglesia.<br \/>\nRuega por nosotros.<\/p>\n<p>En el nombre del Padre y del Hijo y del Esp\u00edritu Santo.<br \/>\nAm\u00e9n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p> [&hellip;]<\/p>\n","protected":false},"author":58,"featured_media":35644,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"_daextrevop_audio_file_creation_date":"","_daextrevop_text_to_speech":"","_daextrevop_document_type":"","footnotes":""},"categories":[3164],"tags":[3162,3163,3067],"class_list":["post-11356","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-meditacion-del-dia","tag-evangelio","tag-meditacion","tag-reflexion"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mi\u00e9rcoles 8 de febrero de 2023 - \u00abUn coraz\u00f3n nuevo\u00bb - Regnum Christi Internacional<\/title>\n<meta name=\"description\" content=\"Se\u00f1or, purifica mi coraz\u00f3n, dame un coraz\u00f3n nuevo. Qu\u00edtame el coraz\u00f3n de piedra y dame un coraz\u00f3n de carne para que sepa amar.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/regnumchristi.org\/es\/miercoles-8-de-febrero-de-2023-un-corazon-nuevo\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mi\u00e9rcoles 8 de febrero de 2023 - \u00abUn coraz\u00f3n nuevo\u00bb - Regnum Christi Internacional\" \/>\n<meta property=\"og:description\" content=\"Se\u00f1or, purifica mi coraz\u00f3n, dame un coraz\u00f3n nuevo. Qu\u00edtame el coraz\u00f3n de piedra y dame un coraz\u00f3n de carne para que sepa amar.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/regnumchristi.org\/es\/miercoles-8-de-febrero-de-2023-un-corazon-nuevo\/\" \/>\n<meta property=\"og:site_name\" content=\"Regnum Christi Internacional\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/RegnumChristiEspana\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-02-08T02:00:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-08-02T19:33:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/regnumchristi.org\/wp-content\/uploads\/2023\/02\/imagenes_meditaciones_diarias_8feb.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"563\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Meditaciones Diarias\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Meditaciones Diarias\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/miercoles-8-de-febrero-de-2023-un-corazon-nuevo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/miercoles-8-de-febrero-de-2023-un-corazon-nuevo\\\/\"},\"author\":{\"name\":\"Meditaciones Diarias\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#\\\/schema\\\/person\\\/a5ad8b3c4bd3cb3a0abe8a1474fe8f0a\"},\"headline\":\"Mi\u00e9rcoles 8 de febrero de 2023 &#8211; \u00abUn coraz\u00f3n nuevo\u00bb\",\"datePublished\":\"2023-02-08T02:00:35+00:00\",\"dateModified\":\"2023-08-02T19:33:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/miercoles-8-de-febrero-de-2023-un-corazon-nuevo\\\/\"},\"wordCount\":910,\"publisher\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/miercoles-8-de-febrero-de-2023-un-corazon-nuevo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/regnumchristi.org\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/imagenes_meditaciones_diarias_8feb.jpg\",\"keywords\":[\"Evangelio\",\"meditaci\u00f3n\",\"Reflexi\u00f3n\"],\"articleSection\":[\"Meditaci\u00f3n del d\u00eda\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/miercoles-8-de-febrero-de-2023-un-corazon-nuevo\\\/\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/miercoles-8-de-febrero-de-2023-un-corazon-nuevo\\\/\",\"name\":\"Mi\u00e9rcoles 8 de febrero de 2023 - \u00abUn coraz\u00f3n nuevo\u00bb - Regnum Christi Internacional\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/miercoles-8-de-febrero-de-2023-un-corazon-nuevo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/miercoles-8-de-febrero-de-2023-un-corazon-nuevo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/regnumchristi.org\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/imagenes_meditaciones_diarias_8feb.jpg\",\"datePublished\":\"2023-02-08T02:00:35+00:00\",\"dateModified\":\"2023-08-02T19:33:09+00:00\",\"description\":\"Se\u00f1or, purifica mi coraz\u00f3n, dame un coraz\u00f3n nuevo. Qu\u00edtame el coraz\u00f3n de piedra y dame un coraz\u00f3n de carne para que sepa amar.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/miercoles-8-de-febrero-de-2023-un-corazon-nuevo\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/regnumchristi.org\\\/miercoles-8-de-febrero-de-2023-un-corazon-nuevo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/miercoles-8-de-febrero-de-2023-un-corazon-nuevo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/imagenes_meditaciones_diarias_8feb.jpg\",\"contentUrl\":\"https:\\\/\\\/regnumchristi.org\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/imagenes_meditaciones_diarias_8feb.jpg\",\"width\":900,\"height\":563},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/miercoles-8-de-febrero-de-2023-un-corazon-nuevo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/regnumchristi.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mi\u00e9rcoles 8 de febrero de 2023 &#8211; \u00abUn coraz\u00f3n nuevo\u00bb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#website\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/\",\"name\":\"Regnum Christi Internacional\",\"description\":\"El Regnum Christi es una realidad de la Iglesia cat\u00f3lica cuya misi\u00f3n es hacer presente el Reino de Cristo\",\"publisher\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/regnumchristi.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#organization\",\"name\":\"Regnum Christi Internacional\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/regnumchristi.es\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Favicon-RC_ligh-cuadrado.png\",\"contentUrl\":\"https:\\\/\\\/regnumchristi.es\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Favicon-RC_ligh-cuadrado.png\",\"width\":1080,\"height\":1080,\"caption\":\"Regnum Christi Internacional\"},\"image\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/RegnumChristiEspana\\\/\",\"https:\\\/\\\/x.com\\\/rc_espana\",\"https:\\\/\\\/www.instagram.com\\\/rc_espana\\\/\",\"https:\\\/\\\/es.linkedin.com\\\/company\\\/regnumchristiespaa\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#\\\/schema\\\/person\\\/a5ad8b3c4bd3cb3a0abe8a1474fe8f0a\",\"name\":\"Meditaciones Diarias\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/es\\\/author\\\/meditacionesd\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mi\u00e9rcoles 8 de febrero de 2023 - \u00abUn coraz\u00f3n nuevo\u00bb - Regnum Christi Internacional","description":"Se\u00f1or, purifica mi coraz\u00f3n, dame un coraz\u00f3n nuevo. Qu\u00edtame el coraz\u00f3n de piedra y dame un coraz\u00f3n de carne para que sepa amar.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/regnumchristi.org\/es\/miercoles-8-de-febrero-de-2023-un-corazon-nuevo\/","og_locale":"es_MX","og_type":"article","og_title":"Mi\u00e9rcoles 8 de febrero de 2023 - \u00abUn coraz\u00f3n nuevo\u00bb - Regnum Christi Internacional","og_description":"Se\u00f1or, purifica mi coraz\u00f3n, dame un coraz\u00f3n nuevo. Qu\u00edtame el coraz\u00f3n de piedra y dame un coraz\u00f3n de carne para que sepa amar.","og_url":"https:\/\/regnumchristi.org\/es\/miercoles-8-de-febrero-de-2023-un-corazon-nuevo\/","og_site_name":"Regnum Christi Internacional","article_publisher":"https:\/\/www.facebook.com\/RegnumChristiEspana\/","article_published_time":"2023-02-08T02:00:35+00:00","article_modified_time":"2023-08-02T19:33:09+00:00","og_image":[{"width":900,"height":563,"url":"https:\/\/regnumchristi.org\/wp-content\/uploads\/2023\/02\/imagenes_meditaciones_diarias_8feb.jpg","type":"image\/jpeg"}],"author":"Meditaciones Diarias","twitter_misc":{"Escrito por":"Meditaciones Diarias","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/regnumchristi.org\/miercoles-8-de-febrero-de-2023-un-corazon-nuevo\/#article","isPartOf":{"@id":"https:\/\/regnumchristi.org\/miercoles-8-de-febrero-de-2023-un-corazon-nuevo\/"},"author":{"name":"Meditaciones Diarias","@id":"https:\/\/regnumchristi.org\/#\/schema\/person\/a5ad8b3c4bd3cb3a0abe8a1474fe8f0a"},"headline":"Mi\u00e9rcoles 8 de febrero de 2023 &#8211; \u00abUn coraz\u00f3n nuevo\u00bb","datePublished":"2023-02-08T02:00:35+00:00","dateModified":"2023-08-02T19:33:09+00:00","mainEntityOfPage":{"@id":"https:\/\/regnumchristi.org\/miercoles-8-de-febrero-de-2023-un-corazon-nuevo\/"},"wordCount":910,"publisher":{"@id":"https:\/\/regnumchristi.org\/#organization"},"image":{"@id":"https:\/\/regnumchristi.org\/miercoles-8-de-febrero-de-2023-un-corazon-nuevo\/#primaryimage"},"thumbnailUrl":"https:\/\/regnumchristi.org\/wp-content\/uploads\/2023\/02\/imagenes_meditaciones_diarias_8feb.jpg","keywords":["Evangelio","meditaci\u00f3n","Reflexi\u00f3n"],"articleSection":["Meditaci\u00f3n del d\u00eda"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/regnumchristi.org\/miercoles-8-de-febrero-de-2023-un-corazon-nuevo\/","url":"https:\/\/regnumchristi.org\/miercoles-8-de-febrero-de-2023-un-corazon-nuevo\/","name":"Mi\u00e9rcoles 8 de febrero de 2023 - \u00abUn coraz\u00f3n nuevo\u00bb - Regnum Christi Internacional","isPartOf":{"@id":"https:\/\/regnumchristi.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/regnumchristi.org\/miercoles-8-de-febrero-de-2023-un-corazon-nuevo\/#primaryimage"},"image":{"@id":"https:\/\/regnumchristi.org\/miercoles-8-de-febrero-de-2023-un-corazon-nuevo\/#primaryimage"},"thumbnailUrl":"https:\/\/regnumchristi.org\/wp-content\/uploads\/2023\/02\/imagenes_meditaciones_diarias_8feb.jpg","datePublished":"2023-02-08T02:00:35+00:00","dateModified":"2023-08-02T19:33:09+00:00","description":"Se\u00f1or, purifica mi coraz\u00f3n, dame un coraz\u00f3n nuevo. Qu\u00edtame el coraz\u00f3n de piedra y dame un coraz\u00f3n de carne para que sepa amar.","breadcrumb":{"@id":"https:\/\/regnumchristi.org\/miercoles-8-de-febrero-de-2023-un-corazon-nuevo\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/regnumchristi.org\/miercoles-8-de-febrero-de-2023-un-corazon-nuevo\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/regnumchristi.org\/miercoles-8-de-febrero-de-2023-un-corazon-nuevo\/#primaryimage","url":"https:\/\/regnumchristi.org\/wp-content\/uploads\/2023\/02\/imagenes_meditaciones_diarias_8feb.jpg","contentUrl":"https:\/\/regnumchristi.org\/wp-content\/uploads\/2023\/02\/imagenes_meditaciones_diarias_8feb.jpg","width":900,"height":563},{"@type":"BreadcrumbList","@id":"https:\/\/regnumchristi.org\/miercoles-8-de-febrero-de-2023-un-corazon-nuevo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/regnumchristi.org\/es\/"},{"@type":"ListItem","position":2,"name":"Mi\u00e9rcoles 8 de febrero de 2023 &#8211; \u00abUn coraz\u00f3n nuevo\u00bb"}]},{"@type":"WebSite","@id":"https:\/\/regnumchristi.org\/#website","url":"https:\/\/regnumchristi.org\/","name":"Regnum Christi Internacional","description":"El Regnum Christi es una realidad de la Iglesia cat\u00f3lica cuya misi\u00f3n es hacer presente el Reino de Cristo","publisher":{"@id":"https:\/\/regnumchristi.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/regnumchristi.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/regnumchristi.org\/#organization","name":"Regnum Christi Internacional","url":"https:\/\/regnumchristi.org\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/regnumchristi.org\/#\/schema\/logo\/image\/","url":"https:\/\/regnumchristi.es\/wp-content\/uploads\/2023\/03\/Favicon-RC_ligh-cuadrado.png","contentUrl":"https:\/\/regnumchristi.es\/wp-content\/uploads\/2023\/03\/Favicon-RC_ligh-cuadrado.png","width":1080,"height":1080,"caption":"Regnum Christi Internacional"},"image":{"@id":"https:\/\/regnumchristi.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/RegnumChristiEspana\/","https:\/\/x.com\/rc_espana","https:\/\/www.instagram.com\/rc_espana\/","https:\/\/es.linkedin.com\/company\/regnumchristiespaa"]},{"@type":"Person","@id":"https:\/\/regnumchristi.org\/#\/schema\/person\/a5ad8b3c4bd3cb3a0abe8a1474fe8f0a","name":"Meditaciones Diarias","url":"https:\/\/regnumchristi.org\/es\/author\/meditacionesd\/"}]}},"_links":{"self":[{"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/posts\/11356","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/comments?post=11356"}],"version-history":[{"count":1,"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/posts\/11356\/revisions"}],"predecessor-version":[{"id":93892,"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/posts\/11356\/revisions\/93892"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/media\/35644"}],"wp:attachment":[{"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/media?parent=11356"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/categories?post=11356"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/tags?post=11356"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}