{"id":121654,"date":"2026-05-26T07:32:53","date_gmt":"2026-05-26T13:32:53","guid":{"rendered":"https:\/\/regnumchristi.org\/?p=121654"},"modified":"2026-05-26T07:32:53","modified_gmt":"2026-05-26T13:32:53","slug":"reset-un-diplomado-para-dialogar-con-la-cultura-posmoderna","status":"publish","type":"post","link":"https:\/\/regnumchristi.org\/es\/reset-un-diplomado-para-dialogar-con-la-cultura-posmoderna\/","title":{"rendered":"Ateneo Regina Apostolorum impulsa \u00abReset\u00bb, un diplomado para dialogar con la cultura posmoderna desde la verdad y el encuentro"},"content":{"rendered":"<p>En un contexto marcado por la polarizaci\u00f3n, la fragmentaci\u00f3n cultural y la b\u00fasqueda de sentido, <a href=\"https:\/\/www.regnumchristi.mx\/dialogopostmodernidad\/\" target=\"_blank\" rel=\"noopener\">el diplomado<\/a> Reset: Di\u00e1logo en una cultura posmoderna quiere ofrecer una respuesta concreta a una de las preguntas m\u00e1s urgentes de nuestro tiempo: \u00bfc\u00f3mo dialogar con el hombre de hoy desde la verdad y el encuentro?<\/p>\n<p>Impulsado por el <a href=\"https:\/\/www.upra.org\/es\/\" target=\"_blank\" rel=\"noopener\">Ateneo Pontificio Regina Apostolorum<\/a> y desarrollado en colaboraci\u00f3n con la <a href=\"https:\/\/www.anahuac.mx\/mexico\/\" target=\"_blank\" rel=\"noopener\">Universidad An\u00e1huac M\u00e9xico<\/a>, este diplomado busca formar educadores, agentes de pastoral, responsables de apostolados y l\u00edderes capaces de comprender la cultura contempor\u00e1nea y dialogar con ella desde una mirada cristiana, cercana y profundamente humana.<\/p>\n<p>La iniciativa tambi\u00e9n responde a las reflexiones de la <a href=\"https:\/\/regnumchristi.org\/es\/convencion-general-2024\/\" target=\"_blank\" rel=\"noopener\">Convenci\u00f3n General Ordinaria 2024<\/a> del Regnum Christi. En el n\u00famero 5, el <a href=\"https:\/\/regnumchristi.org\/es\/frutos-de-la-convencion-general-del-regnum-christi\/\" target=\"_blank\" rel=\"noopener\">comunicado final<\/a> plantea la necesidad de mirar con profundidad \u201cel mundo al que Dios nos env\u00eda hoy\u201d y discernir c\u00f3mo responder a \u00e9l como familia espiritual y como cuerpo apost\u00f3lico. M\u00e1s adelante, en los n\u00fameros 7 al 10, el texto describe el contexto actual como un verdadero cambio de \u00e9poca, marcado por transformaciones culturales, antropol\u00f3gicas y sociales que interpelan directamente la misi\u00f3n evangelizadora. Finalmente, el n\u00famero 19 invita a leer el mundo desde el coraz\u00f3n de Cristo y a discernir la presencia de la semilla del Reino en las realidades concretas de nuestro tiempo.<\/p>\n<figure id=\"attachment_121656\" aria-describedby=\"caption-attachment-121656\" style=\"width: 900px\" class=\"wp-caption aligncenter\"><img fetchpriority=\"high\" decoding=\"async\" class=\"size-full wp-image-121656\" src=\"https:\/\/regnumchristi.org\/wp-content\/uploads\/2026\/05\/Reset-1_1.webp\" alt=\"Reset: un diplomado para dialogar con la cultura posmoderna\" width=\"900\" height=\"600\" srcset=\"https:\/\/regnumchristi.org\/wp-content\/uploads\/2026\/05\/Reset-1_1.webp 900w, https:\/\/regnumchristi.org\/wp-content\/uploads\/2026\/05\/Reset-1_1-300x200.webp 300w, https:\/\/regnumchristi.org\/wp-content\/uploads\/2026\/05\/Reset-1_1-768x512.webp 768w, https:\/\/regnumchristi.org\/wp-content\/uploads\/2026\/05\/Reset-1_1-18x12.webp 18w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><figcaption id=\"caption-attachment-121656\" class=\"wp-caption-text\">Marta Rodr\u00edguez, consagrada y directora del diplomado Di\u00e1logo en la Postmodernidad, presentando el dimplomado. (Cr\u00e9dito de la imagen: Regnum Christi M\u00e9xico)<\/figcaption><\/figure>\n<h3>Comprender el mundo actual para entrar en di\u00e1logo<\/h3>\n<p>El diplomado parte de una convicci\u00f3n compartida por muchos pensadores contempor\u00e1neos: no vivimos simplemente una \u00e9poca de cambios, sino un verdadero cambio de \u00e9poca. La transformaci\u00f3n cultural actual afecta la manera de entender la verdad, la identidad, la libertad, las relaciones humanas y la experiencia de comunidad.<\/p>\n<p>Ante esta realidad, el curso propone un itinerario que ayude a comprender los fen\u00f3menos culturales contempor\u00e1neos y, al mismo tiempo, desarrollar capacidades concretas de escucha, discernimiento y di\u00e1logo.<\/p>\n<p>A trav\u00e9s de clases magistrales, talleres, din\u00e1micas y ejercicios pr\u00e1cticos, los participantes trabajan temas relacionados con la postmodernidad, la antropolog\u00eda filos\u00f3fica, la sexualidad, la \u00e9tica y algunos de los debates culturales m\u00e1s presentes en la actualidad, como la inteligencia artificial, el feminismo, el transhumanismo o la cultura digital.<\/p>\n<p>El diplomado busca formar personas capaces de sostener conversaciones profundas y fecundas en ambientes complejos, aprendiendo a escuchar al otro, a reconocer sus preguntas y a anunciar el Evangelio desde el encuentro.<\/p>\n<figure id=\"attachment_121657\" aria-describedby=\"caption-attachment-121657\" style=\"width: 900px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" class=\"size-full wp-image-121657\" src=\"https:\/\/regnumchristi.org\/wp-content\/uploads\/2026\/05\/Reset-2.webp\" alt=\"Reset: un diplomado para dialogar con la cultura posmoderna\" width=\"900\" height=\"600\" srcset=\"https:\/\/regnumchristi.org\/wp-content\/uploads\/2026\/05\/Reset-2.webp 900w, https:\/\/regnumchristi.org\/wp-content\/uploads\/2026\/05\/Reset-2-300x200.webp 300w, https:\/\/regnumchristi.org\/wp-content\/uploads\/2026\/05\/Reset-2-768x512.webp 768w, https:\/\/regnumchristi.org\/wp-content\/uploads\/2026\/05\/Reset-2-18x12.webp 18w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><figcaption id=\"caption-attachment-121657\" class=\"wp-caption-text\">P. Gabriel Wendt, L.C., director del diplomado Di\u00e1logo en la Postmodernidad, presentando el diplomado. (Cr\u00e9dito de la imagen: Regnum Christi M\u00e9xico)<\/figcaption><\/figure>\n<h3>M\u00f3dulos para integrar pensamiento, discernimiento y acci\u00f3n<\/h3>\n<p>El programa se estructura en tres m\u00f3dulos complementarios.<\/p>\n<p>El primero, <em>\u201cRe-conociendo la cultura postmoderna: \u00bfEs posible dialogar sin verdad?\u201d<\/em>, introduce a los participantes en los principales desaf\u00edos culturales contempor\u00e1neos y profundiza en conceptos como la cultura, la verdad, la posverdad y el di\u00e1logo.<\/p>\n<p>El segundo m\u00f3dulo, <em>\u201cRe-conociendo a la persona: Br\u00fajula para navegar en una cultura l\u00edquida\u201d<\/em>, aborda cuestiones relacionadas con la identidad, la libertad, la corporeidad, la \u00e9tica y los grandes debates antropol\u00f3gicos actuales.<\/p>\n<p>Finalmente, el tercer m\u00f3dulo, <em>\u201cRe-conoci\u00e9ndome: Di\u00e1logo en acci\u00f3n\u201d<\/em>, ofrece talleres y ejercicios pr\u00e1cticos para aplicar los aprendizajes adquiridos en contextos concretos como la educaci\u00f3n, la pastoral, el acompa\u00f1amiento y la vida comunitaria.<\/p>\n<figure id=\"attachment_121658\" aria-describedby=\"caption-attachment-121658\" style=\"width: 900px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" class=\"size-full wp-image-121658\" src=\"https:\/\/regnumchristi.org\/wp-content\/uploads\/2026\/05\/Reset-3.webp\" alt=\"Reset: un diplomado para dialogar con la cultura posmoderna\" width=\"900\" height=\"600\" srcset=\"https:\/\/regnumchristi.org\/wp-content\/uploads\/2026\/05\/Reset-3.webp 900w, https:\/\/regnumchristi.org\/wp-content\/uploads\/2026\/05\/Reset-3-300x200.webp 300w, https:\/\/regnumchristi.org\/wp-content\/uploads\/2026\/05\/Reset-3-768x512.webp 768w, https:\/\/regnumchristi.org\/wp-content\/uploads\/2026\/05\/Reset-3-18x12.webp 18w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><figcaption id=\"caption-attachment-121658\" class=\"wp-caption-text\">Jos\u00e9 Miguel Gonz\u00e1lez, de la Ciudad de M\u00e9xico, participando en el diplomado en la An\u00e1huac. (Cr\u00e9dito de la imagen: Regnum Christi M\u00e9xico)<\/figcaption><\/figure>\n<h3>Una respuesta concreta a un desaf\u00edo cultural<\/h3>\n<p>Seg\u00fan explica el P. Gabriel Wendt, L.C., director del diplomado y profesor de filosof\u00eda de la cultura y de antropolog\u00eda filos\u00f3fica en el Ateneo Pontificio Regina Apostolorum, esta iniciativa naci\u00f3 de constatar una dificultad creciente entre educadores y agentes de pastoral para dialogar con las nuevas generaciones.<\/p>\n<p>\u201cNos dijeron que les costaba mucho a los profesores y a los agentes de pastoral hablar el mismo idioma que los j\u00f3venes\u201d, explica. A partir de esa experiencia surgi\u00f3 la inquietud de crear un espacio capaz de ayudar a comprender la cultura contempor\u00e1nea y de desarrollar herramientas reales de encuentro y di\u00e1logo.<\/p>\n<p>Junto con una cercan\u00eda humana aut\u00e9ntica, el diplomado ofrece una conexi\u00f3n intelectual y cultural que permite comprender las preguntas, b\u00fasquedas y tensiones del hombre contempor\u00e1neo.<\/p>\n<p>El programa quiere ayudar especialmente a quienes trabajan en universidades, colegios, apostolados y ambientes formativos a superar ciertas barreras generacionales y cultivar una escucha profunda desde una raz\u00f3n abierta y una presencia cercana.<\/p>\n<figure id=\"attachment_121659\" aria-describedby=\"caption-attachment-121659\" style=\"width: 900px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-121659\" src=\"https:\/\/regnumchristi.org\/wp-content\/uploads\/2026\/05\/Reset-4.webp\" alt=\"Reset: un diplomado para dialogar con la cultura posmoderna\" width=\"900\" height=\"600\" srcset=\"https:\/\/regnumchristi.org\/wp-content\/uploads\/2026\/05\/Reset-4.webp 900w, https:\/\/regnumchristi.org\/wp-content\/uploads\/2026\/05\/Reset-4-300x200.webp 300w, https:\/\/regnumchristi.org\/wp-content\/uploads\/2026\/05\/Reset-4-768x512.webp 768w, https:\/\/regnumchristi.org\/wp-content\/uploads\/2026\/05\/Reset-4-18x12.webp 18w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><figcaption id=\"caption-attachment-121659\" class=\"wp-caption-text\">Gaby Mondrag\u00f3n, consagrada, participando en el diplomado. (Cr\u00e9dito de la imagen: Regnum Christi M\u00e9xico)<\/figcaption><\/figure>\n<p>A lo largo de los m\u00f3dulos, muchos participantes han reconocido que una de las experiencias m\u00e1s valiosas ha sido descubrir sus propios l\u00edmites en el di\u00e1logo y tomar conciencia de la necesidad de transformar el coraz\u00f3n para acoger verdaderamente al otro.<\/p>\n<p>En sus distintas ediciones y m\u00f3dulos, el diplomado ha reunido a participantes de M\u00e9xico y Centroam\u00e9rica: miembros del Regnum Christi, empresarios, universitarios, responsables de apostolados y representantes de instituciones educativas como los Colegios Regnum Christi, Mano Amiga y la Red de Universidades An\u00e1huac.<\/p>\n<p>La riqueza de vocaciones y experiencias ha permitido vivir el curso tambi\u00e9n como un espacio de encuentro y discernimiento compartido. Consagradas, laicos consagrados, legionarios y laicos han coincidido en la necesidad de aprender nuevas formas de di\u00e1logo capaces de responder a las inquietudes culturales y espirituales del hombre contempor\u00e1neo.<\/p>\n<p>Entre los docentes del diplomado participan especialistas como el P. Gabriel Wendt, L.C., director del programa y profesor de filosof\u00eda de la cultura y antropolog\u00eda filos\u00f3fica en el Ateneo Pontificio Regina Apostolorum; Marta Rodr\u00edguez, profesora de antropolog\u00eda, g\u00e9nero y feminismo; y Sonia Gonz\u00e1lez, consultora en transformaci\u00f3n cultural y coach dial\u00f3gico.<\/p>\n<figure id=\"attachment_121660\" aria-describedby=\"caption-attachment-121660\" style=\"width: 900px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-121660\" src=\"https:\/\/regnumchristi.org\/wp-content\/uploads\/2026\/05\/Reset-5.webp\" alt=\"Reset: un diplomado para dialogar con la cultura posmoderna\" width=\"900\" height=\"600\" srcset=\"https:\/\/regnumchristi.org\/wp-content\/uploads\/2026\/05\/Reset-5.webp 900w, https:\/\/regnumchristi.org\/wp-content\/uploads\/2026\/05\/Reset-5-300x200.webp 300w, https:\/\/regnumchristi.org\/wp-content\/uploads\/2026\/05\/Reset-5-768x512.webp 768w, https:\/\/regnumchristi.org\/wp-content\/uploads\/2026\/05\/Reset-5-18x12.webp 18w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><figcaption id=\"caption-attachment-121660\" class=\"wp-caption-text\">Carlos Abad, laico consagrado, participando en el diplomado. (Cr\u00e9dito de la imagen: Regnum Christi M\u00e9xico)<\/figcaption><\/figure>\n<h3>Evangelizar desde la escucha y la cercan\u00eda<\/h3>\n<p>Uno de los acentos m\u00e1s fuertes del diplomado es la convicci\u00f3n de que el di\u00e1logo aut\u00e9ntico exige humildad, escucha y apertura interior. Los participantes han destacado especialmente la importancia de aprender a acercarse al otro sin miedo, con claridad en las convicciones y, al mismo tiempo, con capacidad real de encuentro.<\/p>\n<p>En una cultura marcada por tensiones y polarizaci\u00f3n, el curso propone el di\u00e1logo como camino humano y cristiano para buscar juntos la verdad.<\/p>\n<p>Desde esa perspectiva, el diplomado quiere ayudar a formar personas capaces de generar espacios seguros de encuentro, acompa\u00f1ar procesos culturales complejos y ejercer liderazgos que iluminen la realidad desde el Evangelio.<\/p>\n<p>Reset se presenta como una experiencia formativa que impulsa a vivir una presencia cristiana significativa en el mundo contempor\u00e1neo.<\/p>\n<div class=\"ast-oembed-container \" style=\"height: 100%;\"><iframe title=\"Reset: Di\u00e1logo en una cultura postmoderna\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/Wx89LLr3n9k?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Una propuesta formativa para comprender el cambio de \u00e9poca y evangelizar desde el encuentro. El programa aborda temas como identidad, inteligencia artificial y cultura digital.<\/p>\n","protected":false},"author":49,"featured_media":121655,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"default","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"_daextrevop_audio_file_creation_date":"","_daextrevop_text_to_speech":"","_daextrevop_document_type":"text","footnotes":""},"categories":[3469],"tags":[205,3577],"class_list":["post-121654","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticia","tag-ateneo-pontificio-regina-apostolorum","tag-reset"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Reset: un diplomado para dialogar con la cultura posmoderna<\/title>\n<meta name=\"description\" content=\"Reset: Di\u00e1logo en una cultura posmoderna quiere ofrecer una respuesta concreta a una de las preguntas m\u00e1s urgentes de nuestro tiempo.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/regnumchristi.org\/es\/reset-un-diplomado-para-dialogar-con-la-cultura-posmoderna\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Reset: un diplomado para dialogar con la cultura posmoderna\" \/>\n<meta property=\"og:description\" content=\"Reset: Di\u00e1logo en una cultura posmoderna quiere ofrecer una respuesta concreta a una de las preguntas m\u00e1s urgentes de nuestro tiempo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/regnumchristi.org\/es\/reset-un-diplomado-para-dialogar-con-la-cultura-posmoderna\/\" \/>\n<meta property=\"og:site_name\" content=\"Regnum Christi Internacional\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/RegnumChristiEspana\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-26T13:32:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/regnumchristi.org\/wp-content\/uploads\/2026\/05\/Reset-Portada.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Autores varios\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Autores varios\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/reset-un-diplomado-para-dialogar-con-la-cultura-posmoderna\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/reset-un-diplomado-para-dialogar-con-la-cultura-posmoderna\\\/\"},\"author\":{\"name\":\"Autores varios\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#\\\/schema\\\/person\\\/73f2e414269cfbf8edecc2fd90af81f2\"},\"headline\":\"Ateneo Regina Apostolorum impulsa \u00abReset\u00bb, un diplomado para dialogar con la cultura posmoderna desde la verdad y el encuentro\",\"datePublished\":\"2026-05-26T13:32:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/reset-un-diplomado-para-dialogar-con-la-cultura-posmoderna\\\/\"},\"wordCount\":1237,\"publisher\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/reset-un-diplomado-para-dialogar-con-la-cultura-posmoderna\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/regnumchristi.org\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Reset-Portada.webp\",\"keywords\":[\"ateneo pontificio regina apostolorum\",\"Reset\"],\"articleSection\":[\"Noticia\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/reset-un-diplomado-para-dialogar-con-la-cultura-posmoderna\\\/\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/reset-un-diplomado-para-dialogar-con-la-cultura-posmoderna\\\/\",\"name\":\"Reset: un diplomado para dialogar con la cultura posmoderna\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/reset-un-diplomado-para-dialogar-con-la-cultura-posmoderna\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/reset-un-diplomado-para-dialogar-con-la-cultura-posmoderna\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/regnumchristi.org\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Reset-Portada.webp\",\"datePublished\":\"2026-05-26T13:32:53+00:00\",\"description\":\"Reset: Di\u00e1logo en una cultura posmoderna quiere ofrecer una respuesta concreta a una de las preguntas m\u00e1s urgentes de nuestro tiempo.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/reset-un-diplomado-para-dialogar-con-la-cultura-posmoderna\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/regnumchristi.org\\\/reset-un-diplomado-para-dialogar-con-la-cultura-posmoderna\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/reset-un-diplomado-para-dialogar-con-la-cultura-posmoderna\\\/#primaryimage\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Reset-Portada.webp\",\"contentUrl\":\"https:\\\/\\\/regnumchristi.org\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Reset-Portada.webp\",\"width\":900,\"height\":600,\"caption\":\"Reset: un diplomado para dialogar con la cultura posmoderna\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/reset-un-diplomado-para-dialogar-con-la-cultura-posmoderna\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/regnumchristi.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ateneo Regina Apostolorum impulsa \u00abReset\u00bb, un diplomado para dialogar con la cultura posmoderna desde la verdad y el encuentro\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#website\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/\",\"name\":\"Regnum Christi Internacional\",\"description\":\"El Regnum Christi es una realidad de la Iglesia cat\u00f3lica cuya misi\u00f3n es hacer presente el Reino de Cristo\",\"publisher\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/regnumchristi.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#organization\",\"name\":\"Regnum Christi Internacional\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/regnumchristi.es\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Favicon-RC_ligh-cuadrado.png\",\"contentUrl\":\"https:\\\/\\\/regnumchristi.es\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Favicon-RC_ligh-cuadrado.png\",\"width\":1080,\"height\":1080,\"caption\":\"Regnum Christi Internacional\"},\"image\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/RegnumChristiEspana\\\/\",\"https:\\\/\\\/x.com\\\/rc_espana\",\"https:\\\/\\\/www.instagram.com\\\/rc_espana\\\/\",\"https:\\\/\\\/es.linkedin.com\\\/company\\\/regnumchristiespaa\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#\\\/schema\\\/person\\\/73f2e414269cfbf8edecc2fd90af81f2\",\"name\":\"Autores varios\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/es\\\/author\\\/jarceocaesc-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Reset: un diplomado para dialogar con la cultura posmoderna","description":"Reset: Di\u00e1logo en una cultura posmoderna quiere ofrecer una respuesta concreta a una de las preguntas m\u00e1s urgentes de nuestro tiempo.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/regnumchristi.org\/es\/reset-un-diplomado-para-dialogar-con-la-cultura-posmoderna\/","og_locale":"es_MX","og_type":"article","og_title":"Reset: un diplomado para dialogar con la cultura posmoderna","og_description":"Reset: Di\u00e1logo en una cultura posmoderna quiere ofrecer una respuesta concreta a una de las preguntas m\u00e1s urgentes de nuestro tiempo.","og_url":"https:\/\/regnumchristi.org\/es\/reset-un-diplomado-para-dialogar-con-la-cultura-posmoderna\/","og_site_name":"Regnum Christi Internacional","article_publisher":"https:\/\/www.facebook.com\/RegnumChristiEspana\/","article_published_time":"2026-05-26T13:32:53+00:00","og_image":[{"width":900,"height":600,"url":"https:\/\/regnumchristi.org\/wp-content\/uploads\/2026\/05\/Reset-Portada.webp","type":"image\/webp"}],"author":"Autores varios","twitter_misc":{"Escrito por":"Autores varios","Tiempo de lectura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/regnumchristi.org\/reset-un-diplomado-para-dialogar-con-la-cultura-posmoderna\/#article","isPartOf":{"@id":"https:\/\/regnumchristi.org\/reset-un-diplomado-para-dialogar-con-la-cultura-posmoderna\/"},"author":{"name":"Autores varios","@id":"https:\/\/regnumchristi.org\/#\/schema\/person\/73f2e414269cfbf8edecc2fd90af81f2"},"headline":"Ateneo Regina Apostolorum impulsa \u00abReset\u00bb, un diplomado para dialogar con la cultura posmoderna desde la verdad y el encuentro","datePublished":"2026-05-26T13:32:53+00:00","mainEntityOfPage":{"@id":"https:\/\/regnumchristi.org\/reset-un-diplomado-para-dialogar-con-la-cultura-posmoderna\/"},"wordCount":1237,"publisher":{"@id":"https:\/\/regnumchristi.org\/#organization"},"image":{"@id":"https:\/\/regnumchristi.org\/reset-un-diplomado-para-dialogar-con-la-cultura-posmoderna\/#primaryimage"},"thumbnailUrl":"https:\/\/regnumchristi.org\/wp-content\/uploads\/2026\/05\/Reset-Portada.webp","keywords":["ateneo pontificio regina apostolorum","Reset"],"articleSection":["Noticia"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/regnumchristi.org\/reset-un-diplomado-para-dialogar-con-la-cultura-posmoderna\/","url":"https:\/\/regnumchristi.org\/reset-un-diplomado-para-dialogar-con-la-cultura-posmoderna\/","name":"Reset: un diplomado para dialogar con la cultura posmoderna","isPartOf":{"@id":"https:\/\/regnumchristi.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/regnumchristi.org\/reset-un-diplomado-para-dialogar-con-la-cultura-posmoderna\/#primaryimage"},"image":{"@id":"https:\/\/regnumchristi.org\/reset-un-diplomado-para-dialogar-con-la-cultura-posmoderna\/#primaryimage"},"thumbnailUrl":"https:\/\/regnumchristi.org\/wp-content\/uploads\/2026\/05\/Reset-Portada.webp","datePublished":"2026-05-26T13:32:53+00:00","description":"Reset: Di\u00e1logo en una cultura posmoderna quiere ofrecer una respuesta concreta a una de las preguntas m\u00e1s urgentes de nuestro tiempo.","breadcrumb":{"@id":"https:\/\/regnumchristi.org\/reset-un-diplomado-para-dialogar-con-la-cultura-posmoderna\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/regnumchristi.org\/reset-un-diplomado-para-dialogar-con-la-cultura-posmoderna\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/regnumchristi.org\/reset-un-diplomado-para-dialogar-con-la-cultura-posmoderna\/#primaryimage","url":"https:\/\/regnumchristi.org\/wp-content\/uploads\/2026\/05\/Reset-Portada.webp","contentUrl":"https:\/\/regnumchristi.org\/wp-content\/uploads\/2026\/05\/Reset-Portada.webp","width":900,"height":600,"caption":"Reset: un diplomado para dialogar con la cultura posmoderna"},{"@type":"BreadcrumbList","@id":"https:\/\/regnumchristi.org\/reset-un-diplomado-para-dialogar-con-la-cultura-posmoderna\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/regnumchristi.org\/es\/"},{"@type":"ListItem","position":2,"name":"Ateneo Regina Apostolorum impulsa \u00abReset\u00bb, un diplomado para dialogar con la cultura posmoderna desde la verdad y el encuentro"}]},{"@type":"WebSite","@id":"https:\/\/regnumchristi.org\/#website","url":"https:\/\/regnumchristi.org\/","name":"Regnum Christi Internacional","description":"El Regnum Christi es una realidad de la Iglesia cat\u00f3lica cuya misi\u00f3n es hacer presente el Reino de Cristo","publisher":{"@id":"https:\/\/regnumchristi.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/regnumchristi.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/regnumchristi.org\/#organization","name":"Regnum Christi Internacional","url":"https:\/\/regnumchristi.org\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/regnumchristi.org\/#\/schema\/logo\/image\/","url":"https:\/\/regnumchristi.es\/wp-content\/uploads\/2023\/03\/Favicon-RC_ligh-cuadrado.png","contentUrl":"https:\/\/regnumchristi.es\/wp-content\/uploads\/2023\/03\/Favicon-RC_ligh-cuadrado.png","width":1080,"height":1080,"caption":"Regnum Christi Internacional"},"image":{"@id":"https:\/\/regnumchristi.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/RegnumChristiEspana\/","https:\/\/x.com\/rc_espana","https:\/\/www.instagram.com\/rc_espana\/","https:\/\/es.linkedin.com\/company\/regnumchristiespaa"]},{"@type":"Person","@id":"https:\/\/regnumchristi.org\/#\/schema\/person\/73f2e414269cfbf8edecc2fd90af81f2","name":"Autores varios","url":"https:\/\/regnumchristi.org\/es\/author\/jarceocaesc-com\/"}]}},"_links":{"self":[{"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/posts\/121654","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/users\/49"}],"replies":[{"embeddable":true,"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/comments?post=121654"}],"version-history":[{"count":1,"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/posts\/121654\/revisions"}],"predecessor-version":[{"id":121661,"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/posts\/121654\/revisions\/121661"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/media\/121655"}],"wp:attachment":[{"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/media?parent=121654"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/categories?post=121654"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/tags?post=121654"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}