{"id":12570,"date":"2020-04-29T05:00:15","date_gmt":"2020-04-29T10:00:15","guid":{"rendered":"http:\/\/www.regnumchristi.org\/es\/?p=12570"},"modified":"2025-10-03T11:48:38","modified_gmt":"2025-10-03T17:48:38","slug":"buen-pastor-nos-llama","status":"publish","type":"post","link":"https:\/\/regnumchristi.org\/es\/buen-pastor-nos-llama\/","title":{"rendered":"El buen pastor que llama a cada uno por su nombre (Jn 10,1-10)"},"content":{"rendered":"<p><strong><span style=\"color: #990000;\">Evangelio:<\/span><\/strong> <em>Jn 10,1-10<\/em><br \/>\nEn verdad, en verdad os digo que el que no entra por la puerta en el aprisco de las ovejas, sino que sube por otra parte, ese es ladr\u00f3n y salteador; pero el que entra por la puerta, ese es pastor de las ovejas. A este le abre el portero, y las ovejas oyen su voz, y llama a sus ovejas por su nombre y las saca fuera; y cuando las ha sacado todas, va delante de ellas, y las ovejas le siguen, porque conocen su voz; pero no seguir\u00e1n al extra\u00f1o antes huir\u00e1n de \u00e9l, porque no conocen la voz de los extra\u00f1os. Les dijo esta semejanza; pero no entendieron que era lo que les hablaba. De nuevo Jes\u00fas: En verdad, en verdad os digo: Yo soy la puerta de las ovejas todos cuantos han venido eran ladrones y salteadores, pero las ovejas no los oyeron. Yo soy la puerta; el que por m\u00ed entrare se salvar\u00e1, y entrar\u00e1 y saldr\u00e1 y hallar\u00e1 pasto. El ladr\u00f3n no viene sino para robar, matar y destruir; yo he venido para que tengan vida, y la tengan abundante.<\/p>\n<p><span style=\"color: #990000;\"><b>Fruto<\/b>:<\/span> Jesucristo es el buen pastor que nos conoce, nos llama y quiere conducir al cielo.<\/p>\n<p><strong><span style=\"color: #990000;\">Pautas para la reflexi\u00f3n<\/span><\/strong><br \/>\nEl pastor conoce a sus ovejas. Ha puesto en ellas mucha dedicaci\u00f3n, ma\u00f1anas y noches de cansancio y preocupaciones. El buen pastor no piensa dos veces cuando se pierde una oveja: va en busca de ella. En el caso de Jesucristo vemos que lo hace simplemente por amor. \u00c9l es realmente el buen pastor que da su vida por las ovejas y nos llama personalmente con nuestro nombre.<\/p>\n<p><em>1. Jesucristo compara dos tipos de pastores<\/em><br \/>\nPrimero est\u00e1 el bueno, que es \u00c9l mismo,\u00a0y luego est\u00e1 el asalariado que descuida a las ovejas cuando se presenta el lobo. Jesucristo parece indicar que estos son los fariseos de su tiempo que enga\u00f1an a la gente: &#8220;Todos cuantos han venido eran ladrones y salteadores&#8221;. Tambi\u00e9n nosotros podemos tener dos posturas ante nuestras ovejas. \u00bfCu\u00e1les son? Pong\u00e1mosle nombres: familia, amigos, compa\u00f1eros de escuela o de trabajo, personas que trabajan con o para nosotros. \u00bfC\u00f3mo somos con ellos? \u00bfComo el buen pastor o como el asalariado?<\/p>\n<p><em>2. La imagen del pastor<\/em><br \/>\nUsar la imagen del pastor para describir a Dios era com\u00fan en el Antiguo Testamento. El oficio de pastor es muy abnegado porque es alguien que debe estar pendiente de las ovejas todo el tiempo. As\u00ed era Dios con su pueblo en el Antiguo Testamento: siempre atento, al pendiente de las necesidades de su pueblo. Y as\u00ed tambi\u00e9n lo es Cristo en nuestros d\u00edas: Ah\u00ed est\u00e1 la Eucarist\u00eda, ese silencioso y humilde pedacito de pan mendigando un di\u00e1logo con nosotros. \u00c9l conoce nuestras necesidades pero quiere que nuestro coraz\u00f3n se explaye para contarle todas y cada una de ellas. \u00a1Qu\u00e9 mejor lugar para colocar nuestros proyectos que en el Sagrario!<\/p>\n<p><em>3. Debemos seguir al buen pastor, Jesucristo<\/em><br \/>\nEscuchar su voz y no la de los impostores. El problema que tienen muchos no es el no encontrar un pastor, sino el acercarse a quienes ense\u00f1an una doctrina distinta. \u00bfC\u00f3mo se reconoce el verdadero pastor? El principio antiguo &#8220;Donde est\u00e1 Pedro, all\u00ed est\u00e1 la Iglesia&#8221;, ayuda mucho. Los que est\u00e1n en comuni\u00f3n con el Vicario de Jesucristo, el Papa, son los verdaderos pastores y los que trabajan siempre en comuni\u00f3n con los obispos.<\/p>\n<p><span style=\"color: #990000;\"><b>Prop\u00f3sito<\/b>:<\/span> Rezar un misterio del rosario por el Papa y por las ovejas que se nos ha confiado.<\/p>\n<p><em>Visita tambi\u00e9n nuestro retiro mensual en l\u00ednea<\/em>.<\/p>\n<p>Te puede interesar: <a href=\"http:\/\/es.catholic.net\/op\/articulos\/74428\/el-buen-pastor-esta-presente-en-mi.html#modal\" target=\"_blank\" rel=\"noopener noreferrer\">\u00bfEl Buen Pastor est\u00e1 presente en m\u00ed?<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p> [&hellip;]<\/p>\n","protected":false},"author":49,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"_daextrevop_audio_file_creation_date":"","_daextrevop_text_to_speech":"","_daextrevop_document_type":"","footnotes":""},"categories":[3243],"tags":[117,229],"class_list":["post-12570","post","type-post","status-publish","format-standard","hentry","category-hora-eucaristica","tag-hora-eucaristica","tag-hora-santa"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El buen pastor nos llama con el nombre (Jn 10,1-10) - Hora Eucar\u00edstica<\/title>\n<meta name=\"description\" content=\"Jesucristo es el buen pastor que nos llama y nos quiere conducir al cielo.\u00c9l es realmente el buen pastor que da su vida por las ovejas.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/regnumchristi.org\/es\/buen-pastor-nos-llama\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El buen pastor nos llama con el nombre (Jn 10,1-10) - Hora Eucar\u00edstica\" \/>\n<meta property=\"og:description\" content=\"Jesucristo es el buen pastor que nos llama y nos quiere conducir al cielo.\u00c9l es realmente el buen pastor que da su vida por las ovejas.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/regnumchristi.org\/es\/buen-pastor-nos-llama\/\" \/>\n<meta property=\"og:site_name\" content=\"Regnum Christi Internacional\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/RegnumChristiEspana\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-04-29T10:00:15+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-03T17:48:38+00:00\" \/>\n<meta name=\"author\" content=\"Autores varios\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Autores varios\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/buen-pastor-nos-llama\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/buen-pastor-nos-llama\\\/\"},\"author\":{\"name\":\"Autores varios\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#\\\/schema\\\/person\\\/73f2e414269cfbf8edecc2fd90af81f2\"},\"headline\":\"El buen pastor que llama a cada uno por su nombre (Jn 10,1-10)\",\"datePublished\":\"2020-04-29T10:00:15+00:00\",\"dateModified\":\"2025-10-03T17:48:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/buen-pastor-nos-llama\\\/\"},\"wordCount\":642,\"publisher\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#organization\"},\"keywords\":[\"Hora Eucar\u00edstica\",\"hora santa\"],\"articleSection\":[\"Hora Eucar\u00edstica\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/buen-pastor-nos-llama\\\/\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/buen-pastor-nos-llama\\\/\",\"name\":\"El buen pastor nos llama con el nombre (Jn 10,1-10) - Hora Eucar\u00edstica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#website\"},\"datePublished\":\"2020-04-29T10:00:15+00:00\",\"dateModified\":\"2025-10-03T17:48:38+00:00\",\"description\":\"Jesucristo es el buen pastor que nos llama y nos quiere conducir al cielo.\u00c9l es realmente el buen pastor que da su vida por las ovejas.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/buen-pastor-nos-llama\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/regnumchristi.org\\\/buen-pastor-nos-llama\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/buen-pastor-nos-llama\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/regnumchristi.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El buen pastor que llama a cada uno por su nombre (Jn 10,1-10)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#website\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/\",\"name\":\"Regnum Christi Internacional\",\"description\":\"El Regnum Christi es una realidad de la Iglesia cat\u00f3lica cuya misi\u00f3n es hacer presente el Reino de Cristo\",\"publisher\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/regnumchristi.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#organization\",\"name\":\"Regnum Christi Internacional\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/regnumchristi.es\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Favicon-RC_ligh-cuadrado.png\",\"contentUrl\":\"https:\\\/\\\/regnumchristi.es\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Favicon-RC_ligh-cuadrado.png\",\"width\":1080,\"height\":1080,\"caption\":\"Regnum Christi Internacional\"},\"image\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/RegnumChristiEspana\\\/\",\"https:\\\/\\\/x.com\\\/rc_espana\",\"https:\\\/\\\/www.instagram.com\\\/rc_espana\\\/\",\"https:\\\/\\\/es.linkedin.com\\\/company\\\/regnumchristiespaa\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#\\\/schema\\\/person\\\/73f2e414269cfbf8edecc2fd90af81f2\",\"name\":\"Autores varios\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/es\\\/author\\\/jarceocaesc-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El buen pastor nos llama con el nombre (Jn 10,1-10) - Hora Eucar\u00edstica","description":"Jesucristo es el buen pastor que nos llama y nos quiere conducir al cielo.\u00c9l es realmente el buen pastor que da su vida por las ovejas.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/regnumchristi.org\/es\/buen-pastor-nos-llama\/","og_locale":"es_MX","og_type":"article","og_title":"El buen pastor nos llama con el nombre (Jn 10,1-10) - Hora Eucar\u00edstica","og_description":"Jesucristo es el buen pastor que nos llama y nos quiere conducir al cielo.\u00c9l es realmente el buen pastor que da su vida por las ovejas.","og_url":"https:\/\/regnumchristi.org\/es\/buen-pastor-nos-llama\/","og_site_name":"Regnum Christi Internacional","article_publisher":"https:\/\/www.facebook.com\/RegnumChristiEspana\/","article_published_time":"2020-04-29T10:00:15+00:00","article_modified_time":"2025-10-03T17:48:38+00:00","author":"Autores varios","twitter_misc":{"Escrito por":"Autores varios","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/regnumchristi.org\/buen-pastor-nos-llama\/#article","isPartOf":{"@id":"https:\/\/regnumchristi.org\/buen-pastor-nos-llama\/"},"author":{"name":"Autores varios","@id":"https:\/\/regnumchristi.org\/#\/schema\/person\/73f2e414269cfbf8edecc2fd90af81f2"},"headline":"El buen pastor que llama a cada uno por su nombre (Jn 10,1-10)","datePublished":"2020-04-29T10:00:15+00:00","dateModified":"2025-10-03T17:48:38+00:00","mainEntityOfPage":{"@id":"https:\/\/regnumchristi.org\/buen-pastor-nos-llama\/"},"wordCount":642,"publisher":{"@id":"https:\/\/regnumchristi.org\/#organization"},"keywords":["Hora Eucar\u00edstica","hora santa"],"articleSection":["Hora Eucar\u00edstica"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/regnumchristi.org\/buen-pastor-nos-llama\/","url":"https:\/\/regnumchristi.org\/buen-pastor-nos-llama\/","name":"El buen pastor nos llama con el nombre (Jn 10,1-10) - Hora Eucar\u00edstica","isPartOf":{"@id":"https:\/\/regnumchristi.org\/#website"},"datePublished":"2020-04-29T10:00:15+00:00","dateModified":"2025-10-03T17:48:38+00:00","description":"Jesucristo es el buen pastor que nos llama y nos quiere conducir al cielo.\u00c9l es realmente el buen pastor que da su vida por las ovejas.","breadcrumb":{"@id":"https:\/\/regnumchristi.org\/buen-pastor-nos-llama\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/regnumchristi.org\/buen-pastor-nos-llama\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/regnumchristi.org\/buen-pastor-nos-llama\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/regnumchristi.org\/es\/"},{"@type":"ListItem","position":2,"name":"El buen pastor que llama a cada uno por su nombre (Jn 10,1-10)"}]},{"@type":"WebSite","@id":"https:\/\/regnumchristi.org\/#website","url":"https:\/\/regnumchristi.org\/","name":"Regnum Christi Internacional","description":"El Regnum Christi es una realidad de la Iglesia cat\u00f3lica cuya misi\u00f3n es hacer presente el Reino de Cristo","publisher":{"@id":"https:\/\/regnumchristi.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/regnumchristi.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/regnumchristi.org\/#organization","name":"Regnum Christi Internacional","url":"https:\/\/regnumchristi.org\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/regnumchristi.org\/#\/schema\/logo\/image\/","url":"https:\/\/regnumchristi.es\/wp-content\/uploads\/2023\/03\/Favicon-RC_ligh-cuadrado.png","contentUrl":"https:\/\/regnumchristi.es\/wp-content\/uploads\/2023\/03\/Favicon-RC_ligh-cuadrado.png","width":1080,"height":1080,"caption":"Regnum Christi Internacional"},"image":{"@id":"https:\/\/regnumchristi.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/RegnumChristiEspana\/","https:\/\/x.com\/rc_espana","https:\/\/www.instagram.com\/rc_espana\/","https:\/\/es.linkedin.com\/company\/regnumchristiespaa"]},{"@type":"Person","@id":"https:\/\/regnumchristi.org\/#\/schema\/person\/73f2e414269cfbf8edecc2fd90af81f2","name":"Autores varios","url":"https:\/\/regnumchristi.org\/es\/author\/jarceocaesc-com\/"}]}},"_links":{"self":[{"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/posts\/12570","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/users\/49"}],"replies":[{"embeddable":true,"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/comments?post=12570"}],"version-history":[{"count":1,"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/posts\/12570\/revisions"}],"predecessor-version":[{"id":113908,"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/posts\/12570\/revisions\/113908"}],"wp:attachment":[{"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/media?parent=12570"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/categories?post=12570"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/tags?post=12570"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}