{"id":13003,"date":"2020-06-03T05:00:46","date_gmt":"2020-06-03T10:00:46","guid":{"rendered":"http:\/\/www.regnumchristi.org\/es\/?p=13003"},"modified":"2025-10-03T11:48:15","modified_gmt":"2025-10-03T17:48:15","slug":"creer-para-salvarse","status":"publish","type":"post","link":"https:\/\/regnumchristi.org\/es\/creer-para-salvarse\/","title":{"rendered":"Creer para salvarse, actuar para salvarse (Jn 3,16-18)"},"content":{"rendered":"<p><strong><span style=\"color: #990000;\">Evangelio:<\/span><\/strong> <em>Jn 3,16-18<br \/>\n<\/em>Tanto am\u00f3 Dios al mundo, que le entreg\u00f3 a su Hijo \u00fanico, para que todo el que crea en \u00e9l no perezca, sino que tenga la vida eterna. Porque Dios no envi\u00f3 a su Hijo para condenar al mundo, sino para que el mundo se salvara por \u00e9l. El que cree en \u00e9l no ser\u00e1 condenado; pero el que no cree ya est\u00e1 condenado, por no haber cre\u00eddo en el Hijo de Dios.<\/p>\n<p><strong><span style=\"color: #990000;\">Fruto:<\/span><\/strong> Acrecentar nuestra\u00a0esperanza por la vida eterna.<\/p>\n<p><strong><span style=\"color: #990000;\">Pautas para la reflexi\u00f3n:<br \/>\n<\/span><\/strong>\u00bfAmar o condenar? \u00bfSalvar o condenar? Condenar suena fuerte. Nos cuesta trabajo pensar en un Dios que condena. Pero la respuesta est\u00e1 en nosotros. Dios hace siempre su parte, nosotros tambi\u00e9n debemos hacer la nuestra, precisamente para no condenarse sino para salvarse.<\/p>\n<p><em>1. El amor de Dios<\/em><br \/>\nTanto nos am\u00f3 que se entreg\u00f3 por nosotros, muri\u00f3 por nosotros, para salvarnos. No existe mayor amor que este. No hay en la historia universal un amor tan grande como el de Cristo que muere por cada uno de nosotros, los de hoy, los de ayer y los de ma\u00f1ana. Un amor que no tiene l\u00edmites, un amor que es eterno. Nos ama porque nos quiere en la eternidad. \u00bfC\u00f3mo correspondo a este amor de Dios? El cristiano tiene todo al alcance no para condenarse, sino para salvarse.<\/p>\n<p><em>2. La condenaci\u00f3n<\/em><br \/>\nHoy en d\u00eda casi no se menciona la condenaci\u00f3n. Sin embargo, hay ideolog\u00edas partidistas que dicen: &#8220;condenamos esto&#8221;, &#8220;condenamos la acci\u00f3n&#8221;, &#8220;pedimos que condenen&#8221;&#8230;, ellos s\u00ed condenan y parece que para muchos cristianos la palabra condenaci\u00f3n es un concepto que hay que borrar. Dios es muy claro: s\u00ed hay condenaci\u00f3n, s\u00ed existe, est\u00e1 latente. Es un hecho que Dios no quiere nuestra condenaci\u00f3n, pero si nosotros nos alejamos de \u00c9l, si nosotros no queremos (porque simplemente no queremos) vivir una vida sacramental, si rehuimos a la confesi\u00f3n, si nos da pereza la misa, si no rezamos, si nos apartamos de la vivencia de la virtud, etc., estamos abriendo la puerta de una posible condenaci\u00f3n.<\/p>\n<p><em>3. El que cree no ser\u00e1 condenado<\/em><br \/>\nEsa es la clave: creer. Pero la fe sin obras est\u00e1 muerta. Por ello, la fe es una fe concreta, no s\u00f3lo una teor\u00eda bonita y abstracta de decir: &#8220;s\u00ed, creo&#8221;. Tambi\u00e9n es necesaria la acci\u00f3n, que mis obras demuestren mi fe. El amor de Dios nunca nos faltar\u00e1, y depende mucho de nosotros el que deseemos estar con Cristo en la eternidad. Es una opci\u00f3n nuestra que se va haciendo todos los d\u00edas. \u00bfCondenarse o salvarse?<\/p>\n<p><strong><span style=\"color: #990000;\">Prop\u00f3sito:<\/span><\/strong> Hagamos, pues, el firme prop\u00f3sito de demostrar nuestra fe con obras. Sobre todo, que nos reconozcan por la vivencia del amor cristiano.<\/p>\n<p><em>Escucha tambi\u00e9n nuestro retiro mensual en l\u00ednea.<\/em><\/p>\n<p>Te puede interesar: <a href=\"https:\/\/es.catholic.net\/op\/articulos\/61775\/cat\/12\/vivir-y-morir-en-pecado-mortal-te-lleva-al-infierno.html#modal\" target=\"_blank\" rel=\"noopener noreferrer\">Vivir y morir en pecado mortal te lleva al infierno<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p> [&hellip;]<\/p>\n","protected":false},"author":49,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"_daextrevop_audio_file_creation_date":"","_daextrevop_text_to_speech":"","_daextrevop_document_type":"","footnotes":""},"categories":[3243],"tags":[117,229],"class_list":["post-13003","post","type-post","status-publish","format-standard","hentry","category-hora-eucaristica","tag-hora-eucaristica","tag-hora-santa"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Creer para salvarse, obrar para salvarse (Jn 3,16-18) - Hora Eucar\u00edstica<\/title>\n<meta name=\"description\" content=\"Dios hace siempre su parte, nosotros tambi\u00e9n debemos hacer la nuestra. Fe y obras, ni una sin la otra. Creer y obrar para salvarse.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/regnumchristi.org\/es\/creer-para-salvarse\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Creer para salvarse, obrar para salvarse (Jn 3,16-18) - Hora Eucar\u00edstica\" \/>\n<meta property=\"og:description\" content=\"Dios hace siempre su parte, nosotros tambi\u00e9n debemos hacer la nuestra. Fe y obras, ni una sin la otra. Creer y obrar para salvarse.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/regnumchristi.org\/es\/creer-para-salvarse\/\" \/>\n<meta property=\"og:site_name\" content=\"Regnum Christi Internacional\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/RegnumChristiEspana\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-06-03T10:00:46+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-03T17:48:15+00:00\" \/>\n<meta name=\"author\" content=\"Autores varios\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Autores varios\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/creer-para-salvarse\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/creer-para-salvarse\\\/\"},\"author\":{\"name\":\"Autores varios\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#\\\/schema\\\/person\\\/73f2e414269cfbf8edecc2fd90af81f2\"},\"headline\":\"Creer para salvarse, actuar para salvarse (Jn 3,16-18)\",\"datePublished\":\"2020-06-03T10:00:46+00:00\",\"dateModified\":\"2025-10-03T17:48:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/creer-para-salvarse\\\/\"},\"wordCount\":498,\"publisher\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#organization\"},\"keywords\":[\"Hora Eucar\u00edstica\",\"hora santa\"],\"articleSection\":[\"Hora Eucar\u00edstica\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/creer-para-salvarse\\\/\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/creer-para-salvarse\\\/\",\"name\":\"Creer para salvarse, obrar para salvarse (Jn 3,16-18) - Hora Eucar\u00edstica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#website\"},\"datePublished\":\"2020-06-03T10:00:46+00:00\",\"dateModified\":\"2025-10-03T17:48:15+00:00\",\"description\":\"Dios hace siempre su parte, nosotros tambi\u00e9n debemos hacer la nuestra. Fe y obras, ni una sin la otra. Creer y obrar para salvarse.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/creer-para-salvarse\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/regnumchristi.org\\\/creer-para-salvarse\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/creer-para-salvarse\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/regnumchristi.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Creer para salvarse, actuar para salvarse (Jn 3,16-18)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#website\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/\",\"name\":\"Regnum Christi Internacional\",\"description\":\"El Regnum Christi es una realidad de la Iglesia cat\u00f3lica cuya misi\u00f3n es hacer presente el Reino de Cristo\",\"publisher\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/regnumchristi.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#organization\",\"name\":\"Regnum Christi Internacional\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/regnumchristi.es\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Favicon-RC_ligh-cuadrado.png\",\"contentUrl\":\"https:\\\/\\\/regnumchristi.es\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Favicon-RC_ligh-cuadrado.png\",\"width\":1080,\"height\":1080,\"caption\":\"Regnum Christi Internacional\"},\"image\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/RegnumChristiEspana\\\/\",\"https:\\\/\\\/x.com\\\/rc_espana\",\"https:\\\/\\\/www.instagram.com\\\/rc_espana\\\/\",\"https:\\\/\\\/es.linkedin.com\\\/company\\\/regnumchristiespaa\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#\\\/schema\\\/person\\\/73f2e414269cfbf8edecc2fd90af81f2\",\"name\":\"Autores varios\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/es\\\/author\\\/jarceocaesc-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Creer para salvarse, obrar para salvarse (Jn 3,16-18) - Hora Eucar\u00edstica","description":"Dios hace siempre su parte, nosotros tambi\u00e9n debemos hacer la nuestra. Fe y obras, ni una sin la otra. Creer y obrar para salvarse.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/regnumchristi.org\/es\/creer-para-salvarse\/","og_locale":"es_MX","og_type":"article","og_title":"Creer para salvarse, obrar para salvarse (Jn 3,16-18) - Hora Eucar\u00edstica","og_description":"Dios hace siempre su parte, nosotros tambi\u00e9n debemos hacer la nuestra. Fe y obras, ni una sin la otra. Creer y obrar para salvarse.","og_url":"https:\/\/regnumchristi.org\/es\/creer-para-salvarse\/","og_site_name":"Regnum Christi Internacional","article_publisher":"https:\/\/www.facebook.com\/RegnumChristiEspana\/","article_published_time":"2020-06-03T10:00:46+00:00","article_modified_time":"2025-10-03T17:48:15+00:00","author":"Autores varios","twitter_misc":{"Escrito por":"Autores varios","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/regnumchristi.org\/creer-para-salvarse\/#article","isPartOf":{"@id":"https:\/\/regnumchristi.org\/creer-para-salvarse\/"},"author":{"name":"Autores varios","@id":"https:\/\/regnumchristi.org\/#\/schema\/person\/73f2e414269cfbf8edecc2fd90af81f2"},"headline":"Creer para salvarse, actuar para salvarse (Jn 3,16-18)","datePublished":"2020-06-03T10:00:46+00:00","dateModified":"2025-10-03T17:48:15+00:00","mainEntityOfPage":{"@id":"https:\/\/regnumchristi.org\/creer-para-salvarse\/"},"wordCount":498,"publisher":{"@id":"https:\/\/regnumchristi.org\/#organization"},"keywords":["Hora Eucar\u00edstica","hora santa"],"articleSection":["Hora Eucar\u00edstica"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/regnumchristi.org\/creer-para-salvarse\/","url":"https:\/\/regnumchristi.org\/creer-para-salvarse\/","name":"Creer para salvarse, obrar para salvarse (Jn 3,16-18) - Hora Eucar\u00edstica","isPartOf":{"@id":"https:\/\/regnumchristi.org\/#website"},"datePublished":"2020-06-03T10:00:46+00:00","dateModified":"2025-10-03T17:48:15+00:00","description":"Dios hace siempre su parte, nosotros tambi\u00e9n debemos hacer la nuestra. Fe y obras, ni una sin la otra. Creer y obrar para salvarse.","breadcrumb":{"@id":"https:\/\/regnumchristi.org\/creer-para-salvarse\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/regnumchristi.org\/creer-para-salvarse\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/regnumchristi.org\/creer-para-salvarse\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/regnumchristi.org\/es\/"},{"@type":"ListItem","position":2,"name":"Creer para salvarse, actuar para salvarse (Jn 3,16-18)"}]},{"@type":"WebSite","@id":"https:\/\/regnumchristi.org\/#website","url":"https:\/\/regnumchristi.org\/","name":"Regnum Christi Internacional","description":"El Regnum Christi es una realidad de la Iglesia cat\u00f3lica cuya misi\u00f3n es hacer presente el Reino de Cristo","publisher":{"@id":"https:\/\/regnumchristi.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/regnumchristi.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/regnumchristi.org\/#organization","name":"Regnum Christi Internacional","url":"https:\/\/regnumchristi.org\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/regnumchristi.org\/#\/schema\/logo\/image\/","url":"https:\/\/regnumchristi.es\/wp-content\/uploads\/2023\/03\/Favicon-RC_ligh-cuadrado.png","contentUrl":"https:\/\/regnumchristi.es\/wp-content\/uploads\/2023\/03\/Favicon-RC_ligh-cuadrado.png","width":1080,"height":1080,"caption":"Regnum Christi Internacional"},"image":{"@id":"https:\/\/regnumchristi.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/RegnumChristiEspana\/","https:\/\/x.com\/rc_espana","https:\/\/www.instagram.com\/rc_espana\/","https:\/\/es.linkedin.com\/company\/regnumchristiespaa"]},{"@type":"Person","@id":"https:\/\/regnumchristi.org\/#\/schema\/person\/73f2e414269cfbf8edecc2fd90af81f2","name":"Autores varios","url":"https:\/\/regnumchristi.org\/es\/author\/jarceocaesc-com\/"}]}},"_links":{"self":[{"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/posts\/13003","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/users\/49"}],"replies":[{"embeddable":true,"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/comments?post=13003"}],"version-history":[{"count":1,"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/posts\/13003\/revisions"}],"predecessor-version":[{"id":113892,"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/posts\/13003\/revisions\/113892"}],"wp:attachment":[{"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/media?parent=13003"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/categories?post=13003"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/tags?post=13003"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}