{"id":13173,"date":"2020-06-24T05:00:28","date_gmt":"2020-06-24T10:00:28","guid":{"rendered":"http:\/\/www.regnumchristi.org\/es\/?p=13173"},"modified":"2025-10-03T11:48:38","modified_gmt":"2025-10-03T17:48:38","slug":"pierda-vida-encontrara","status":"publish","type":"post","link":"https:\/\/regnumchristi.org\/es\/pierda-vida-encontrara\/","title":{"rendered":"\u00abEl que pierda su vida por m\u00ed la encontrar\u00e1\u00bb (Mt 10,37-42)"},"content":{"rendered":"<p><span style=\"color: #800000;\"><strong>Evangelio: Mt 10,37-42<\/strong><\/span><br \/>\n\u00abEl que ama a su padre o a su madre m\u00e1s que a m\u00ed, no es digno de m\u00ed; y el que ama a su hijo o a su hija m\u00e1s que a m\u00ed, no es digno de m\u00ed. El que no toma su cruz y me sigue, no es digno de m\u00ed. El que encuentre su vida, la perder\u00e1; y el que pierda su vida por m\u00ed, la encontrar\u00e1. El que los recibe a ustedes, me recibe a m\u00ed; y el que me recibe, recibe a aquel que me envi\u00f3. El que recibe a un profeta por ser profeta, tendr\u00e1 la recompensa de un profeta; y el que recibe a un justo, tendr\u00e1 la recompensa de un justo. Les aseguro que cualquiera que d\u00e9 a beber, aunque s\u00f3lo sea un vaso de agua fresca, a uno de estos peque\u00f1os por ser mi disc\u00edpulo, no quedar\u00e1 sin recompensa\u00bb.<\/p>\n<p><span style=\"color: #800000;\"><strong>Fruto:<\/strong><\/span> Que haga vida el primer mandamiento de &#8220;Amar a Dios sobre todas las cosas&#8221; y profundizar en lo que significa realmente que pierda mi vida para encontrarlo a \u00c9l.<\/p>\n<p><span style=\"color: #800000;\"><strong>Pautas para la reflexi\u00f3n<\/strong><\/span><br \/>\nEl amor a Dios tiene nombre y apellido, es nuestro pr\u00f3jimo. No podemos amar a Dios a quien no vemos si no amamos a nuestro pr\u00f3jimo a quien s\u00ed vemos. A lo largo del d\u00eda encontramos personas en el camino. Ciertamente no sabremos sus nombres, pero tienen rostro, tienen una historia y est\u00e1 en nosotros el que esas historias queden tocadas por la gracia de Dios a trav\u00e9s de nuestro testimonio.<\/p>\n<p><em>1. El que ama a su padre o a su madre m\u00e1s que a m\u00ed, no es digno de m\u00ed<\/em><br \/>\nQuien toma radicalmente esta expresi\u00f3n de Jes\u00fas puede pensar que el mismo Dios intenta separar a la familia. Pero no es as\u00ed. Hay que ver esto en su contexto y no s\u00f3lo de manera parcial. Todo esto se enmarca en el seguimiento de Jes\u00fas tomando la propia cruz, en ese perder la propia vida en Cristo para encontrarla nuevamente. Jes\u00fas no est\u00e1 diciendo que nos quitemos la vida, sino caminar por los caminos de la conversi\u00f3n, del cambio de mentalidad, cambio de vida hacia algo mejor. El camino que Jes\u00fas nos propone es un camino de santificaci\u00f3n, y seguirlo a veces implica decirle &#8220;no&#8221; a las sugerencias familiares materialistas para seguir con un &#8220;s\u00ed&#8221; una misi\u00f3n trascendente. Y ese &#8220;no&#8221; es un perderse para hallarse. En ning\u00fan momento se dice que el &#8220;no&#8221; significa una separaci\u00f3n radical de la familia.<\/p>\n<p><em>2. El que pierda su vida por m\u00ed la encontrar\u00e1<\/em><br \/>\nQue pierda la vida por Cristo quiere decir que el &#8220;hombre nuevo&#8221; revestido de la gracia de Dios sobresalga al &#8220;hombre viejo&#8221; guiado por las pasiones desordenadas. Quiere decir que, revestidos de generosidad venzamos la indiferencia, arropados por la caridad hagamos a un lado el odio y el rencor. Que pierda esa vida materialista, de consumismo desenfrenado y relativista para que impere en todo momento la vida de la gracia, y que sabe poner a Dios primero, por encima de todo y de todos, sus mandamientos, sus sacramentos, la vida de oraci\u00f3n, el apostolado, la acci\u00f3n solidaria ante el m\u00e1s necesitado: perderse al mundo para hallarse en Cristo.<\/p>\n<p><em>3. El que me recibe, recibe a Aquel que me envi\u00f3<\/em><br \/>\nAqu\u00ed est\u00e1 la raz\u00f3n \u00faltima por la cual debemos &#8220;perdernos&#8221; para estar con Cristo, porque estar con Cristo es estar con el Padre que lo envi\u00f3, meta \u00faltima de nuestro peregrinar en esta vida. Recibirlo a \u00c9l es dejarlo actuar en nuestra vida, dejar que sea \u00c9l quien reine en nuestra historia. Es abrirle la puerta de nuestro hogar, de nuestra familia, de nuestro trabajo. Es ese saber decir &#8220;no&#8221; a muchas opciones mundanas para decir un gran &#8220;s\u00ed&#8221; a las cosas de Dios. Haciendo esto lograremos avanzar cada d\u00eda hacia nuestra meta final: la eternidad con Dios.<\/p>\n<p><span style=\"color: #800000;\"><strong>Prop\u00f3sito:<\/strong><\/span> Ver qu\u00e9 es aquello que no permite a Dios obrar en mi vida y abrirle la puerta de mi coraz\u00f3n para que \u00c9l reine.<\/p>\n<p><em>Escucha tambi\u00e9n nuestro retiro mensual en l\u00ednea.<\/em><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p> [&hellip;]<\/p>\n","protected":false},"author":49,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"_daextrevop_audio_file_creation_date":"","_daextrevop_text_to_speech":"","_daextrevop_document_type":"","footnotes":""},"categories":[3243],"tags":[117,229],"class_list":["post-13173","post","type-post","status-publish","format-standard","hentry","category-hora-eucaristica","tag-hora-eucaristica","tag-hora-santa"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00abEl que pierda su vida por m\u00ed...\u00bb (Mt 10,37-42) - Hora eucar\u00edstica<\/title>\n<meta name=\"description\" content=\"\u00abEl que encuentre su vida, la perder\u00e1; y el que pierda su vida por m\u00ed, la encontrar\u00e1\u00bb. Se trata de perder el mundo para ganar a Dios.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/regnumchristi.org\/es\/pierda-vida-encontrara\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00abEl que pierda su vida por m\u00ed...\u00bb (Mt 10,37-42) - Hora eucar\u00edstica\" \/>\n<meta property=\"og:description\" content=\"\u00abEl que encuentre su vida, la perder\u00e1; y el que pierda su vida por m\u00ed, la encontrar\u00e1\u00bb. Se trata de perder el mundo para ganar a Dios.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/regnumchristi.org\/es\/pierda-vida-encontrara\/\" \/>\n<meta property=\"og:site_name\" content=\"Regnum Christi Internacional\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/RegnumChristiEspana\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-06-24T10:00:28+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-03T17:48:38+00:00\" \/>\n<meta name=\"author\" content=\"Autores varios\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Autores varios\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/pierda-vida-encontrara\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/pierda-vida-encontrara\\\/\"},\"author\":{\"name\":\"Autores varios\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#\\\/schema\\\/person\\\/73f2e414269cfbf8edecc2fd90af81f2\"},\"headline\":\"\u00abEl que pierda su vida por m\u00ed la encontrar\u00e1\u00bb (Mt 10,37-42)\",\"datePublished\":\"2020-06-24T10:00:28+00:00\",\"dateModified\":\"2025-10-03T17:48:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/pierda-vida-encontrara\\\/\"},\"wordCount\":715,\"publisher\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#organization\"},\"keywords\":[\"Hora Eucar\u00edstica\",\"hora santa\"],\"articleSection\":[\"Hora Eucar\u00edstica\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/pierda-vida-encontrara\\\/\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/pierda-vida-encontrara\\\/\",\"name\":\"\u00abEl que pierda su vida por m\u00ed...\u00bb (Mt 10,37-42) - Hora eucar\u00edstica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#website\"},\"datePublished\":\"2020-06-24T10:00:28+00:00\",\"dateModified\":\"2025-10-03T17:48:38+00:00\",\"description\":\"\u00abEl que encuentre su vida, la perder\u00e1; y el que pierda su vida por m\u00ed, la encontrar\u00e1\u00bb. Se trata de perder el mundo para ganar a Dios.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/pierda-vida-encontrara\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/regnumchristi.org\\\/pierda-vida-encontrara\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/pierda-vida-encontrara\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/regnumchristi.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00abEl que pierda su vida por m\u00ed la encontrar\u00e1\u00bb (Mt 10,37-42)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#website\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/\",\"name\":\"Regnum Christi Internacional\",\"description\":\"El Regnum Christi es una realidad de la Iglesia cat\u00f3lica cuya misi\u00f3n es hacer presente el Reino de Cristo\",\"publisher\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/regnumchristi.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#organization\",\"name\":\"Regnum Christi Internacional\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/regnumchristi.es\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Favicon-RC_ligh-cuadrado.png\",\"contentUrl\":\"https:\\\/\\\/regnumchristi.es\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Favicon-RC_ligh-cuadrado.png\",\"width\":1080,\"height\":1080,\"caption\":\"Regnum Christi Internacional\"},\"image\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/RegnumChristiEspana\\\/\",\"https:\\\/\\\/x.com\\\/rc_espana\",\"https:\\\/\\\/www.instagram.com\\\/rc_espana\\\/\",\"https:\\\/\\\/es.linkedin.com\\\/company\\\/regnumchristiespaa\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#\\\/schema\\\/person\\\/73f2e414269cfbf8edecc2fd90af81f2\",\"name\":\"Autores varios\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/es\\\/author\\\/jarceocaesc-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00abEl que pierda su vida por m\u00ed...\u00bb (Mt 10,37-42) - Hora eucar\u00edstica","description":"\u00abEl que encuentre su vida, la perder\u00e1; y el que pierda su vida por m\u00ed, la encontrar\u00e1\u00bb. Se trata de perder el mundo para ganar a Dios.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/regnumchristi.org\/es\/pierda-vida-encontrara\/","og_locale":"es_MX","og_type":"article","og_title":"\u00abEl que pierda su vida por m\u00ed...\u00bb (Mt 10,37-42) - Hora eucar\u00edstica","og_description":"\u00abEl que encuentre su vida, la perder\u00e1; y el que pierda su vida por m\u00ed, la encontrar\u00e1\u00bb. Se trata de perder el mundo para ganar a Dios.","og_url":"https:\/\/regnumchristi.org\/es\/pierda-vida-encontrara\/","og_site_name":"Regnum Christi Internacional","article_publisher":"https:\/\/www.facebook.com\/RegnumChristiEspana\/","article_published_time":"2020-06-24T10:00:28+00:00","article_modified_time":"2025-10-03T17:48:38+00:00","author":"Autores varios","twitter_misc":{"Escrito por":"Autores varios","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/regnumchristi.org\/pierda-vida-encontrara\/#article","isPartOf":{"@id":"https:\/\/regnumchristi.org\/pierda-vida-encontrara\/"},"author":{"name":"Autores varios","@id":"https:\/\/regnumchristi.org\/#\/schema\/person\/73f2e414269cfbf8edecc2fd90af81f2"},"headline":"\u00abEl que pierda su vida por m\u00ed la encontrar\u00e1\u00bb (Mt 10,37-42)","datePublished":"2020-06-24T10:00:28+00:00","dateModified":"2025-10-03T17:48:38+00:00","mainEntityOfPage":{"@id":"https:\/\/regnumchristi.org\/pierda-vida-encontrara\/"},"wordCount":715,"publisher":{"@id":"https:\/\/regnumchristi.org\/#organization"},"keywords":["Hora Eucar\u00edstica","hora santa"],"articleSection":["Hora Eucar\u00edstica"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/regnumchristi.org\/pierda-vida-encontrara\/","url":"https:\/\/regnumchristi.org\/pierda-vida-encontrara\/","name":"\u00abEl que pierda su vida por m\u00ed...\u00bb (Mt 10,37-42) - Hora eucar\u00edstica","isPartOf":{"@id":"https:\/\/regnumchristi.org\/#website"},"datePublished":"2020-06-24T10:00:28+00:00","dateModified":"2025-10-03T17:48:38+00:00","description":"\u00abEl que encuentre su vida, la perder\u00e1; y el que pierda su vida por m\u00ed, la encontrar\u00e1\u00bb. Se trata de perder el mundo para ganar a Dios.","breadcrumb":{"@id":"https:\/\/regnumchristi.org\/pierda-vida-encontrara\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/regnumchristi.org\/pierda-vida-encontrara\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/regnumchristi.org\/pierda-vida-encontrara\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/regnumchristi.org\/es\/"},{"@type":"ListItem","position":2,"name":"\u00abEl que pierda su vida por m\u00ed la encontrar\u00e1\u00bb (Mt 10,37-42)"}]},{"@type":"WebSite","@id":"https:\/\/regnumchristi.org\/#website","url":"https:\/\/regnumchristi.org\/","name":"Regnum Christi Internacional","description":"El Regnum Christi es una realidad de la Iglesia cat\u00f3lica cuya misi\u00f3n es hacer presente el Reino de Cristo","publisher":{"@id":"https:\/\/regnumchristi.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/regnumchristi.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/regnumchristi.org\/#organization","name":"Regnum Christi Internacional","url":"https:\/\/regnumchristi.org\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/regnumchristi.org\/#\/schema\/logo\/image\/","url":"https:\/\/regnumchristi.es\/wp-content\/uploads\/2023\/03\/Favicon-RC_ligh-cuadrado.png","contentUrl":"https:\/\/regnumchristi.es\/wp-content\/uploads\/2023\/03\/Favicon-RC_ligh-cuadrado.png","width":1080,"height":1080,"caption":"Regnum Christi Internacional"},"image":{"@id":"https:\/\/regnumchristi.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/RegnumChristiEspana\/","https:\/\/x.com\/rc_espana","https:\/\/www.instagram.com\/rc_espana\/","https:\/\/es.linkedin.com\/company\/regnumchristiespaa"]},{"@type":"Person","@id":"https:\/\/regnumchristi.org\/#\/schema\/person\/73f2e414269cfbf8edecc2fd90af81f2","name":"Autores varios","url":"https:\/\/regnumchristi.org\/es\/author\/jarceocaesc-com\/"}]}},"_links":{"self":[{"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/posts\/13173","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/users\/49"}],"replies":[{"embeddable":true,"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/comments?post=13173"}],"version-history":[{"count":1,"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/posts\/13173\/revisions"}],"predecessor-version":[{"id":113913,"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/posts\/13173\/revisions\/113913"}],"wp:attachment":[{"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/media?parent=13173"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/categories?post=13173"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/tags?post=13173"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}