{"id":16580,"date":"2023-03-17T20:00:24","date_gmt":"2023-03-18T02:00:24","guid":{"rendered":"http:\/\/www.regnumchristi.org\/es\/?p=16580"},"modified":"2023-08-02T13:32:28","modified_gmt":"2023-08-02T19:32:28","slug":"sabado-18-de-marzo-de-2023-dios-mio-apiadate-de-mi-que-soy-un-pecador","status":"publish","type":"post","link":"https:\/\/regnumchristi.org\/es\/sabado-18-de-marzo-de-2023-dios-mio-apiadate-de-mi-que-soy-un-pecador\/","title":{"rendered":"S\u00e1bado 18 de marzo de 2023 &#8211; \u00abDios m\u00edo, api\u00e1date de m\u00ed, que soy un pecador\u00bb"},"content":{"rendered":"<p align=\"justify\"><em>David Mauricio S\u00e1nchez Mej\u00eda, LC<\/em><\/p>\n<p align=\"justify\">En el nombre del Padre y del Hijo y del Esp\u00edritu Santo.<br \/>\nAm\u00e9n.<\/p>\n<p align=\"justify\">Cristo, Rey nuestro.<br \/>\n\u00a1Venga tu Reino!<\/p>\n<p align=\"left\"><span style=\"color: #800000;\"><strong>Oraci\u00f3n preparatoria<\/strong><\/span> <em>(para ponerme en presencia de Dios)<\/em><\/p>\n<p align=\"justify\">Gracias, Se\u00f1or, por tu amor por m\u00ed, porque me permites cada d\u00eda levantarme, ver la luz del sol y la sonrisa en el rostro de aquellos que amo. Aumenta mi fe para descubrirte en todo lo que me sucede. Aumenta mi esperanza para confiar en ti en los momentos dif\u00edciles. Aumenta mi amor para ser tu testigo fiel ante mis hermanos, los hombres.<\/p>\n<p align=\"left\"><span style=\"color: #800000;\"><strong>Evangelio del d\u00eda<\/strong><\/span> <em>(para orientar tu meditaci\u00f3n)<br \/>\n<\/em>Del santo Evangelio seg\u00fan san Lucas 18, 9-14<\/p>\n<p align=\"left\">En aquel tiempo, Jes\u00fas dijo esta par\u00e1bola sobre algunos que se ten\u00edan por buenos y despreciaban a los dem\u00e1s: &#8220;Dos hombres subieron al templo para orar: uno era fariseo y el otro, publicano. El fariseo, erguido, oraba as\u00ed en su interior: &#8216;Dios m\u00edo, te doy gracias porque no soy como los dem\u00e1s hombres: ladrones, injustos y ad\u00falteros; tampoco soy como ese publicano. Ayuno dos veces por semana y pago el diezmo de todas mis ganancias&#8217;. El publicano, en cambio, se qued\u00f3 lejos y no se atrev\u00eda a levantar los ojos al cielo. Lo \u00fanico que hac\u00eda era golpearse el pecho, diciendo: &#8216;Dios m\u00edo, api\u00e1date de m\u00ed, que soy un pecador&#8217;. Pues bien, yo les aseguro que \u00e9ste baj\u00f3 a su casa justificado y aqu\u00e9l no; porque todo el que se enaltece ser\u00e1 humillado y el que se humilla ser\u00e1 enaltecido&#8221;.<\/p>\n<p align=\"justify\"><em>Palabra del Se\u00f1or.<\/em><\/p>\n<p align=\"left\"><span style=\"color: #800000;\"><strong>Medita lo que Dios te dice en el Evangelio<\/strong><\/span><\/p>\n<p align=\"justify\">Jes\u00fas no quiere la muerte del pecador, sino que se convierta y viva. Quiere ayudarlo a regresar a la gracia y a la comuni\u00f3n con Dios y sus hermanos los hombres. Al final de la par\u00e1bola, sin embargo, hay uno justificado y otro no.<\/p>\n<p align=\"justify\">Dios desea ardientemente envolvernos en su misericordia y restaurar aquello que hemos perdido por culpa del pecado. S\u00f3lo basta con decir como el publicano: \u00abDios m\u00edo, api\u00e1date de m\u00ed, que soy un pecador\u00bb, para que el Se\u00f1or nos tienda la mano y comience a guiarnos en nuestro caminar.<\/p>\n<p align=\"justify\">Su amor llega al punto de dar la vida por nosotros, por cada uno de nosotros, y quiere que lo aceptemos libremente, reconociendo que tenemos necesidad de \u00c9l.<\/p>\n<p align=\"justify\">A este punto se borra la diferencia entre el justo y el pecador. Todos, todos, necesitamos a Dios, su amor y su misericordia.<\/p>\n<p align=\"justify\"><em>\u00abConsidero necesario dar un paso importante: no podemos analizar, reflexionar, y menos todav\u00eda rezar, sobre la realidad como si nosotros estuvi\u00e9semos en orillas o senderos diversos, como si estuvi\u00e9semos fuera de la historia. Todos tenemos necesidad de convertirnos, todos tenemos necesidad de ponernos delante del Se\u00f1or y renovar siempre de nuevo la alianza con \u00c9l y decir junto con el publicano: Dios m\u00edo, ten piedad de m\u00ed que soy pecador. Con este punto de partida, quedamos incluidos en la misma \u201cparte\u201d \u2014no separados, incluidos en la misma parte\u2014 y nos ponemos ante el Se\u00f1or con una actitud de humildad y de escucha.<\/em><br \/>\n<em>Justamente, mirar a nuestras familias con la delicadeza con la que las mira Dios nos ayuda a poner nuestra conciencia en su misma direcci\u00f3n\u00bb.<\/em><br \/>\n<em>(Homil\u00eda de S.S. Francisco, 16 de junio de 2016).<\/em><\/p>\n<p align=\"left\"><span style=\"color: #800000;\"><strong>Di\u00e1logo con Cristo<\/strong><\/span><\/p>\n<p align=\"justify\"><em>\u00c9sta es la parte m\u00e1s importante de tu oraci\u00f3n, disponte a platicar con mucho amor con Aquel que te ama.<\/em><\/p>\n<p align=\"left\"><span style=\"color: #800000;\"><strong>Prop\u00f3sito<\/strong><\/span><\/p>\n<p align=\"justify\"><em>Proponte uno personal. El que m\u00e1s amor implique en respuesta al Amado\u2026 o, si crees que es lo que Dios te pide, vive lo que se te sugiere a continuaci\u00f3n.<\/em><\/p>\n<p align=\"justify\">Hablar\u00e9 con Dios sobre aquel pecado que me cuesta reconocer o me impide acercarme a \u00c9l.<\/p>\n<p align=\"left\"><span style=\"color: #800000;\"><strong>Despedida<\/strong><\/span><\/p>\n<p align=\"justify\">Te damos gracias, Se\u00f1or, por todos tus beneficios, a ti que vives y reinas por los siglos de los siglos.<br \/>\nAm\u00e9n.<\/p>\n<p align=\"justify\">\u00a1Cristo, Rey nuestro!<br \/>\n\u00a1Venga tu Reino!<\/p>\n<p align=\"justify\">Virgen prudent\u00edsima, Mar\u00eda, Madre de la Iglesia.<br \/>\nRuega por nosotros.<\/p>\n<p align=\"justify\">En el nombre del Padre y del Hijo y del Esp\u00edritu Santo.<br \/>\nAm\u00e9n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p> [&hellip;]<\/p>\n","protected":false},"author":58,"featured_media":93433,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"_daextrevop_audio_file_creation_date":"","_daextrevop_text_to_speech":"","_daextrevop_document_type":"","footnotes":""},"categories":[3164],"tags":[3162,3163,3067],"class_list":["post-16580","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-meditacion-del-dia","tag-evangelio","tag-meditacion","tag-reflexion"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>S\u00e1bado 18 de marzo de 2023 - \u00abDios m\u00edo, api\u00e1date de m\u00ed, que soy un pecador\u00bb - Regnum Christi Internacional<\/title>\n<meta name=\"description\" content=\"Su amor llega al punto de dar la vida por nosotros, por cada uno de nosotros, y quiere que lo aceptemos libremente.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/regnumchristi.org\/es\/sabado-18-de-marzo-de-2023-dios-mio-apiadate-de-mi-que-soy-un-pecador\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"S\u00e1bado 18 de marzo de 2023 - \u00abDios m\u00edo, api\u00e1date de m\u00ed, que soy un pecador\u00bb - Regnum Christi Internacional\" \/>\n<meta property=\"og:description\" content=\"Su amor llega al punto de dar la vida por nosotros, por cada uno de nosotros, y quiere que lo aceptemos libremente.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/regnumchristi.org\/es\/sabado-18-de-marzo-de-2023-dios-mio-apiadate-de-mi-que-soy-un-pecador\/\" \/>\n<meta property=\"og:site_name\" content=\"Regnum Christi Internacional\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/RegnumChristiEspana\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-03-18T02:00:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-08-02T19:32:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/regnumchristi.org\/wp-content\/uploads\/2022\/02\/suscribete-a-lo-mas-rc-banner-web.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Meditaciones Diarias\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Meditaciones Diarias\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/sabado-18-de-marzo-de-2023-dios-mio-apiadate-de-mi-que-soy-un-pecador\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/sabado-18-de-marzo-de-2023-dios-mio-apiadate-de-mi-que-soy-un-pecador\\\/\"},\"author\":{\"name\":\"Meditaciones Diarias\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#\\\/schema\\\/person\\\/a5ad8b3c4bd3cb3a0abe8a1474fe8f0a\"},\"headline\":\"S\u00e1bado 18 de marzo de 2023 &#8211; \u00abDios m\u00edo, api\u00e1date de m\u00ed, que soy un pecador\u00bb\",\"datePublished\":\"2023-03-18T02:00:24+00:00\",\"dateModified\":\"2023-08-02T19:32:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/sabado-18-de-marzo-de-2023-dios-mio-apiadate-de-mi-que-soy-un-pecador\\\/\"},\"wordCount\":727,\"publisher\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/sabado-18-de-marzo-de-2023-dios-mio-apiadate-de-mi-que-soy-un-pecador\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/regnumchristi.org\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/imagenes_meditaciones_diarias_18mar.jpg\",\"keywords\":[\"Evangelio\",\"meditaci\u00f3n\",\"Reflexi\u00f3n\"],\"articleSection\":[\"Meditaci\u00f3n del d\u00eda\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/sabado-18-de-marzo-de-2023-dios-mio-apiadate-de-mi-que-soy-un-pecador\\\/\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/sabado-18-de-marzo-de-2023-dios-mio-apiadate-de-mi-que-soy-un-pecador\\\/\",\"name\":\"S\u00e1bado 18 de marzo de 2023 - \u00abDios m\u00edo, api\u00e1date de m\u00ed, que soy un pecador\u00bb - Regnum Christi Internacional\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/sabado-18-de-marzo-de-2023-dios-mio-apiadate-de-mi-que-soy-un-pecador\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/sabado-18-de-marzo-de-2023-dios-mio-apiadate-de-mi-que-soy-un-pecador\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/regnumchristi.org\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/imagenes_meditaciones_diarias_18mar.jpg\",\"datePublished\":\"2023-03-18T02:00:24+00:00\",\"dateModified\":\"2023-08-02T19:32:28+00:00\",\"description\":\"Su amor llega al punto de dar la vida por nosotros, por cada uno de nosotros, y quiere que lo aceptemos libremente.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/sabado-18-de-marzo-de-2023-dios-mio-apiadate-de-mi-que-soy-un-pecador\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/regnumchristi.org\\\/sabado-18-de-marzo-de-2023-dios-mio-apiadate-de-mi-que-soy-un-pecador\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/sabado-18-de-marzo-de-2023-dios-mio-apiadate-de-mi-que-soy-un-pecador\\\/#primaryimage\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/imagenes_meditaciones_diarias_18mar.jpg\",\"contentUrl\":\"https:\\\/\\\/regnumchristi.org\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/imagenes_meditaciones_diarias_18mar.jpg\",\"width\":900,\"height\":563},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/sabado-18-de-marzo-de-2023-dios-mio-apiadate-de-mi-que-soy-un-pecador\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/regnumchristi.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"S\u00e1bado 18 de marzo de 2023 &#8211; \u00abDios m\u00edo, api\u00e1date de m\u00ed, que soy un pecador\u00bb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#website\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/\",\"name\":\"Regnum Christi Internacional\",\"description\":\"El Regnum Christi es una realidad de la Iglesia cat\u00f3lica cuya misi\u00f3n es hacer presente el Reino de Cristo\",\"publisher\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/regnumchristi.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#organization\",\"name\":\"Regnum Christi Internacional\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/regnumchristi.es\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Favicon-RC_ligh-cuadrado.png\",\"contentUrl\":\"https:\\\/\\\/regnumchristi.es\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Favicon-RC_ligh-cuadrado.png\",\"width\":1080,\"height\":1080,\"caption\":\"Regnum Christi Internacional\"},\"image\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/RegnumChristiEspana\\\/\",\"https:\\\/\\\/x.com\\\/rc_espana\",\"https:\\\/\\\/www.instagram.com\\\/rc_espana\\\/\",\"https:\\\/\\\/es.linkedin.com\\\/company\\\/regnumchristiespaa\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#\\\/schema\\\/person\\\/a5ad8b3c4bd3cb3a0abe8a1474fe8f0a\",\"name\":\"Meditaciones Diarias\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/es\\\/author\\\/meditacionesd\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"S\u00e1bado 18 de marzo de 2023 - \u00abDios m\u00edo, api\u00e1date de m\u00ed, que soy un pecador\u00bb - Regnum Christi Internacional","description":"Su amor llega al punto de dar la vida por nosotros, por cada uno de nosotros, y quiere que lo aceptemos libremente.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/regnumchristi.org\/es\/sabado-18-de-marzo-de-2023-dios-mio-apiadate-de-mi-que-soy-un-pecador\/","og_locale":"es_MX","og_type":"article","og_title":"S\u00e1bado 18 de marzo de 2023 - \u00abDios m\u00edo, api\u00e1date de m\u00ed, que soy un pecador\u00bb - Regnum Christi Internacional","og_description":"Su amor llega al punto de dar la vida por nosotros, por cada uno de nosotros, y quiere que lo aceptemos libremente.","og_url":"https:\/\/regnumchristi.org\/es\/sabado-18-de-marzo-de-2023-dios-mio-apiadate-de-mi-que-soy-un-pecador\/","og_site_name":"Regnum Christi Internacional","article_publisher":"https:\/\/www.facebook.com\/RegnumChristiEspana\/","article_published_time":"2023-03-18T02:00:24+00:00","article_modified_time":"2023-08-02T19:32:28+00:00","og_image":[{"width":1500,"height":600,"url":"https:\/\/regnumchristi.org\/wp-content\/uploads\/2022\/02\/suscribete-a-lo-mas-rc-banner-web.jpg","type":"image\/jpeg"}],"author":"Meditaciones Diarias","twitter_misc":{"Escrito por":"Meditaciones Diarias","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/regnumchristi.org\/sabado-18-de-marzo-de-2023-dios-mio-apiadate-de-mi-que-soy-un-pecador\/#article","isPartOf":{"@id":"https:\/\/regnumchristi.org\/sabado-18-de-marzo-de-2023-dios-mio-apiadate-de-mi-que-soy-un-pecador\/"},"author":{"name":"Meditaciones Diarias","@id":"https:\/\/regnumchristi.org\/#\/schema\/person\/a5ad8b3c4bd3cb3a0abe8a1474fe8f0a"},"headline":"S\u00e1bado 18 de marzo de 2023 &#8211; \u00abDios m\u00edo, api\u00e1date de m\u00ed, que soy un pecador\u00bb","datePublished":"2023-03-18T02:00:24+00:00","dateModified":"2023-08-02T19:32:28+00:00","mainEntityOfPage":{"@id":"https:\/\/regnumchristi.org\/sabado-18-de-marzo-de-2023-dios-mio-apiadate-de-mi-que-soy-un-pecador\/"},"wordCount":727,"publisher":{"@id":"https:\/\/regnumchristi.org\/#organization"},"image":{"@id":"https:\/\/regnumchristi.org\/sabado-18-de-marzo-de-2023-dios-mio-apiadate-de-mi-que-soy-un-pecador\/#primaryimage"},"thumbnailUrl":"https:\/\/regnumchristi.org\/wp-content\/uploads\/2023\/03\/imagenes_meditaciones_diarias_18mar.jpg","keywords":["Evangelio","meditaci\u00f3n","Reflexi\u00f3n"],"articleSection":["Meditaci\u00f3n del d\u00eda"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/regnumchristi.org\/sabado-18-de-marzo-de-2023-dios-mio-apiadate-de-mi-que-soy-un-pecador\/","url":"https:\/\/regnumchristi.org\/sabado-18-de-marzo-de-2023-dios-mio-apiadate-de-mi-que-soy-un-pecador\/","name":"S\u00e1bado 18 de marzo de 2023 - \u00abDios m\u00edo, api\u00e1date de m\u00ed, que soy un pecador\u00bb - Regnum Christi Internacional","isPartOf":{"@id":"https:\/\/regnumchristi.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/regnumchristi.org\/sabado-18-de-marzo-de-2023-dios-mio-apiadate-de-mi-que-soy-un-pecador\/#primaryimage"},"image":{"@id":"https:\/\/regnumchristi.org\/sabado-18-de-marzo-de-2023-dios-mio-apiadate-de-mi-que-soy-un-pecador\/#primaryimage"},"thumbnailUrl":"https:\/\/regnumchristi.org\/wp-content\/uploads\/2023\/03\/imagenes_meditaciones_diarias_18mar.jpg","datePublished":"2023-03-18T02:00:24+00:00","dateModified":"2023-08-02T19:32:28+00:00","description":"Su amor llega al punto de dar la vida por nosotros, por cada uno de nosotros, y quiere que lo aceptemos libremente.","breadcrumb":{"@id":"https:\/\/regnumchristi.org\/sabado-18-de-marzo-de-2023-dios-mio-apiadate-de-mi-que-soy-un-pecador\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/regnumchristi.org\/sabado-18-de-marzo-de-2023-dios-mio-apiadate-de-mi-que-soy-un-pecador\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/regnumchristi.org\/sabado-18-de-marzo-de-2023-dios-mio-apiadate-de-mi-que-soy-un-pecador\/#primaryimage","url":"https:\/\/regnumchristi.org\/wp-content\/uploads\/2023\/03\/imagenes_meditaciones_diarias_18mar.jpg","contentUrl":"https:\/\/regnumchristi.org\/wp-content\/uploads\/2023\/03\/imagenes_meditaciones_diarias_18mar.jpg","width":900,"height":563},{"@type":"BreadcrumbList","@id":"https:\/\/regnumchristi.org\/sabado-18-de-marzo-de-2023-dios-mio-apiadate-de-mi-que-soy-un-pecador\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/regnumchristi.org\/es\/"},{"@type":"ListItem","position":2,"name":"S\u00e1bado 18 de marzo de 2023 &#8211; \u00abDios m\u00edo, api\u00e1date de m\u00ed, que soy un pecador\u00bb"}]},{"@type":"WebSite","@id":"https:\/\/regnumchristi.org\/#website","url":"https:\/\/regnumchristi.org\/","name":"Regnum Christi Internacional","description":"El Regnum Christi es una realidad de la Iglesia cat\u00f3lica cuya misi\u00f3n es hacer presente el Reino de Cristo","publisher":{"@id":"https:\/\/regnumchristi.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/regnumchristi.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/regnumchristi.org\/#organization","name":"Regnum Christi Internacional","url":"https:\/\/regnumchristi.org\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/regnumchristi.org\/#\/schema\/logo\/image\/","url":"https:\/\/regnumchristi.es\/wp-content\/uploads\/2023\/03\/Favicon-RC_ligh-cuadrado.png","contentUrl":"https:\/\/regnumchristi.es\/wp-content\/uploads\/2023\/03\/Favicon-RC_ligh-cuadrado.png","width":1080,"height":1080,"caption":"Regnum Christi Internacional"},"image":{"@id":"https:\/\/regnumchristi.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/RegnumChristiEspana\/","https:\/\/x.com\/rc_espana","https:\/\/www.instagram.com\/rc_espana\/","https:\/\/es.linkedin.com\/company\/regnumchristiespaa"]},{"@type":"Person","@id":"https:\/\/regnumchristi.org\/#\/schema\/person\/a5ad8b3c4bd3cb3a0abe8a1474fe8f0a","name":"Meditaciones Diarias","url":"https:\/\/regnumchristi.org\/es\/author\/meditacionesd\/"}]}},"_links":{"self":[{"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/posts\/16580","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/comments?post=16580"}],"version-history":[{"count":1,"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/posts\/16580\/revisions"}],"predecessor-version":[{"id":93854,"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/posts\/16580\/revisions\/93854"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/media\/93433"}],"wp:attachment":[{"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/media?parent=16580"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/categories?post=16580"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/tags?post=16580"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}