{"id":25227,"date":"2020-03-09T07:44:57","date_gmt":"2020-03-09T13:44:57","guid":{"rendered":"https:\/\/www.regnumchristi.org\/es\/?p=25227"},"modified":"2023-07-14T18:24:00","modified_gmt":"2023-07-14T16:24:00","slug":"concluye-la-asamblea-general-consagradas","status":"publish","type":"post","link":"https:\/\/regnumchristi.org\/es\/concluye-la-asamblea-general-consagradas\/","title":{"rendered":"Concluye la Asamblea General 2020 de las Consagradas del Regnum Christi"},"content":{"rendered":"<p>Las <a href=\"https:\/\/consagradasrc.org\/\" target=\"_blank\" rel=\"noopener noreferrer\">Consagradas del Regnum Christi<\/a> han concluido el viernes 6 de marzo su primera Asamblea General Ordinaria como <a href=\"https:\/\/www.regnumchristi.org\/rcstatutes\/es\/santa-sede-aprueba-sva-consagradas-laicos-consagrados-rc\/?utm_source=Env%C3%ADos++RC&amp;utm_campaign=447f36c076-EMAIL_CAMPAIGN_2020_03_08_06_47&amp;utm_medium=email&amp;utm_term=0_6fe1afa2a6-447f36c076-27838383\" target=\"_blank\" rel=\"noopener noreferrer\">Sociedad de Vida Apost\u00f3lica (SVA)<\/a>, y han hecho p\u00fablico su Comunicado general\u00a0con las reflexiones y decisiones tomadas sobre los temas tratados, que incluye otros documentos de inter\u00e9s. Puedes leer su rese\u00f1a conclusiva aqu\u00ed.<\/p>\n<p>\u201cAl terminar nuestra Asamblea\u201d, dice el Comunicado general, \u201cla experiencia del encuentro con Cristo genera en nosotras vida nueva y nos pone en salida con el deseo de dar vida y vida en abundancia. Queremos desplegar el don de la vida en Cristo recibido como semilla en nuestro bautismo\u201d, afirman.<\/p>\n<p>La Asamblea inici\u00f3 el 24 de enero en Roma. Sus tres tareas principales, como establecen el derecho can\u00f3nico y el derecho propio, eran la elecci\u00f3n del gobierno general para los pr\u00f3ximos seis a\u00f1os, el informe del gobierno anterior, as\u00ed como el an\u00e1lisis y discernimiento de los temas de relevancia para la Sociedad de Vida Apost\u00f3lica, entre los que se inclu\u00eda una revisi\u00f3n del derecho propio.<\/p>\n<h4>Temas abordados y nuevo gobierno<\/h4>\n<p>Durante los primeros d\u00edas, y tras escuchar el informe del gobierno saliente, las delegadas de la Asamblea decidieron incluir en la agenda de trabajo algunos temas adicionales a los ya previstos. As\u00ed, adem\u00e1s de la proyecci\u00f3n y sostenibilidad de la Sociedad de Vida Apost\u00f3lica, la misi\u00f3n, la pobreza, medios de crecimiento espiritual, y el cuidado de padres ancianos y enfermos de las consagradas, afrontaron cuestiones importantes como la postura institucional sobre la persona del fundador, abusos sexuales a menores o personas vulnerables, el ejercicio de la autoridad, y la reconciliaci\u00f3n y sanaci\u00f3n.<\/p>\n<p>La Asamblea General abord\u00f3 la elecci\u00f3n del nuevo gobierno el 11 de febrero. Nancy Nohrden, estadounidense de 46 a\u00f1os, fue elegida nueva directora general. Como consejeras generales, la Asamblea eligi\u00f3 a Elena Bartolom\u00e9, espa\u00f1ola; Eugenia \u00c1lvarez, venezolana; \u00c1frica Pem\u00e1n, espa\u00f1ola; Viviana Lim\u00f3n, mexicana; y Jacinta Curran, irlandesa.<\/p>\n<h4>Encargos al nuevo gobierno<\/h4>\n<p>A la luz de todo lo reflexionado y discernido, las delegadas votaron enmiendas a las constituciones y al reglamento propios. Tambi\u00e9n elaboraron los encargos\u00a0al gobierno, esto es, las acciones que la Asamblea General, en tanto que \u00f3rgano supremo de la Sociedad de Vida Apost\u00f3lica, le indica al gobierno entrante que debe realizar durante el pr\u00f3ximo sexenio. Puedes leer los encargos en la rese\u00f1a conclusiva aqu\u00ed.<\/p>\n<h4>En el marco de la Federaci\u00f3n Regnum Christi<\/h4>\n<p>La nueva directora general, Nancy Nohrden, formar\u00e1 parte del colegio directivo general del Regnum Christi junto a los nuevos directores generales de los <a href=\"https:\/\/laicosconsagradosrc.org\/\" target=\"_blank\" rel=\"noopener noreferrer\">Laicos Consagrados del Regnum Christi<\/a> (F\u00e9lix G\u00f3mez Rueda), los <a href=\"https:\/\/legionariosdecristo.org\/\" target=\"_blank\" rel=\"noopener noreferrer\">Legionarios de Cristo<\/a> (P. John Connor, L.C.), asistidos por dos laicos con voto consultivo (Francisco G\u00e1mez y \u00c1lvaro Abell\u00e1n). Su primer encuentro ser\u00e1 en la Plenaria General del Regnum Christi, a finales de marzo.<\/p>\n<p><strong>Enlaces de inter\u00e9s<\/strong><\/p>\n<ul>\n<li>Comunicado General de la Asamblea 2020<\/li>\n<li>Carta a los miembros del Regnum Christi<\/li>\n<li><a href=\"http:\/\/www.vatican.va\/content\/francesco\/es\/speeches\/2020\/february\/documents\/papa-francesco_20200229_legionari.html?fbclid=IwAR1R3MhTohQEwYM7nBBsmwutoy8fL_xozuahDrT69gZcoRYHaBuikIx4VgA\" target=\"_blank\" rel=\"noopener noreferrer\">Discurso del Santo Padre al Regnum Christi<\/a><\/li>\n<li>Rese\u00f1as semanales<\/li>\n<li><a href=\"https:\/\/www.flickr.com\/photos\/consagradasrc\/albums\/72157712726758328\" target=\"_blank\" rel=\"noopener noreferrer\">Fotogaler\u00eda<\/a><\/li>\n<li>V\u00eddeos<\/li>\n<\/ul>\n<h5><em>Fuente: Minuto RC de <a href=\"https:\/\/lomasrc.blogspot.com\/\" target=\"_blank\" rel=\"noopener noreferrer\">Lo+RC<\/a><\/em><\/h5>\n","protected":false},"excerpt":{"rendered":"<p> [&hellip;]<\/p>\n","protected":false},"author":49,"featured_media":25228,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"_daextrevop_audio_file_creation_date":"","_daextrevop_text_to_speech":"","_daextrevop_document_type":"","footnotes":""},"categories":[3031,1687],"tags":[3030,90,203],"class_list":["post-25227","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-destacadas","category-noticias","tag-asamblea-general","tag-consagradas-del-regnum-christi","tag-vida-consagrada"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Concluye la Asamblea General de las Consagradas del Regnum Christi<\/title>\n<meta name=\"description\" content=\"Las Consagradas del Regnum Christi han concluido el viernes 6 de marzo su primera Asamblea General Ordinaria como Sociedad de Vida Apost\u00f3lica (SVA).\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/regnumchristi.org\/es\/concluye-la-asamblea-general-consagradas\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Concluye la Asamblea General de las Consagradas del Regnum Christi\" \/>\n<meta property=\"og:description\" content=\"Las Consagradas del Regnum Christi han concluido el viernes 6 de marzo su primera Asamblea General Ordinaria como Sociedad de Vida Apost\u00f3lica (SVA).\" \/>\n<meta property=\"og:url\" content=\"https:\/\/regnumchristi.org\/es\/concluye-la-asamblea-general-consagradas\/\" \/>\n<meta property=\"og:site_name\" content=\"Regnum Christi Internacional\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/RegnumChristiEspana\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-03-09T13:44:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-07-14T16:24:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/regnumchristi.org\/wp-content\/uploads\/2020\/03\/49431524232_857a00ee2e_c.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"799\" \/>\n\t<meta property=\"og:image:height\" content=\"533\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Autores varios\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Autores varios\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/concluye-la-asamblea-general-consagradas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/concluye-la-asamblea-general-consagradas\\\/\"},\"author\":{\"name\":\"Autores varios\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#\\\/schema\\\/person\\\/73f2e414269cfbf8edecc2fd90af81f2\"},\"headline\":\"Concluye la Asamblea General 2020 de las Consagradas del Regnum Christi\",\"datePublished\":\"2020-03-09T13:44:57+00:00\",\"dateModified\":\"2023-07-14T16:24:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/concluye-la-asamblea-general-consagradas\\\/\"},\"wordCount\":532,\"publisher\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/concluye-la-asamblea-general-consagradas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/regnumchristi.org\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/49431524232_857a00ee2e_c.jpg\",\"keywords\":[\"Asamblea General\",\"Consagradas del Regnum Christi\",\"vida consagrada\"],\"articleSection\":[\"Destacadas\",\"Noticias\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/concluye-la-asamblea-general-consagradas\\\/\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/concluye-la-asamblea-general-consagradas\\\/\",\"name\":\"Concluye la Asamblea General de las Consagradas del Regnum Christi\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/concluye-la-asamblea-general-consagradas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/concluye-la-asamblea-general-consagradas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/regnumchristi.org\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/49431524232_857a00ee2e_c.jpg\",\"datePublished\":\"2020-03-09T13:44:57+00:00\",\"dateModified\":\"2023-07-14T16:24:00+00:00\",\"description\":\"Las Consagradas del Regnum Christi han concluido el viernes 6 de marzo su primera Asamblea General Ordinaria como Sociedad de Vida Apost\u00f3lica (SVA).\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/concluye-la-asamblea-general-consagradas\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/regnumchristi.org\\\/concluye-la-asamblea-general-consagradas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/concluye-la-asamblea-general-consagradas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/49431524232_857a00ee2e_c.jpg\",\"contentUrl\":\"https:\\\/\\\/regnumchristi.org\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/49431524232_857a00ee2e_c.jpg\",\"width\":799,\"height\":533,\"caption\":\"Concluye la Asamblea General 2020 de las Consagradas del Regnum Christi\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/concluye-la-asamblea-general-consagradas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/regnumchristi.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Concluye la Asamblea General 2020 de las Consagradas del Regnum Christi\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#website\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/\",\"name\":\"Regnum Christi Internacional\",\"description\":\"El Regnum Christi es una realidad de la Iglesia cat\u00f3lica cuya misi\u00f3n es hacer presente el Reino de Cristo\",\"publisher\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/regnumchristi.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#organization\",\"name\":\"Regnum Christi Internacional\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/regnumchristi.es\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Favicon-RC_ligh-cuadrado.png\",\"contentUrl\":\"https:\\\/\\\/regnumchristi.es\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Favicon-RC_ligh-cuadrado.png\",\"width\":1080,\"height\":1080,\"caption\":\"Regnum Christi Internacional\"},\"image\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/RegnumChristiEspana\\\/\",\"https:\\\/\\\/x.com\\\/rc_espana\",\"https:\\\/\\\/www.instagram.com\\\/rc_espana\\\/\",\"https:\\\/\\\/es.linkedin.com\\\/company\\\/regnumchristiespaa\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#\\\/schema\\\/person\\\/73f2e414269cfbf8edecc2fd90af81f2\",\"name\":\"Autores varios\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/es\\\/author\\\/jarceocaesc-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Concluye la Asamblea General de las Consagradas del Regnum Christi","description":"Las Consagradas del Regnum Christi han concluido el viernes 6 de marzo su primera Asamblea General Ordinaria como Sociedad de Vida Apost\u00f3lica (SVA).","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/regnumchristi.org\/es\/concluye-la-asamblea-general-consagradas\/","og_locale":"es_MX","og_type":"article","og_title":"Concluye la Asamblea General de las Consagradas del Regnum Christi","og_description":"Las Consagradas del Regnum Christi han concluido el viernes 6 de marzo su primera Asamblea General Ordinaria como Sociedad de Vida Apost\u00f3lica (SVA).","og_url":"https:\/\/regnumchristi.org\/es\/concluye-la-asamblea-general-consagradas\/","og_site_name":"Regnum Christi Internacional","article_publisher":"https:\/\/www.facebook.com\/RegnumChristiEspana\/","article_published_time":"2020-03-09T13:44:57+00:00","article_modified_time":"2023-07-14T16:24:00+00:00","og_image":[{"width":799,"height":533,"url":"https:\/\/regnumchristi.org\/wp-content\/uploads\/2020\/03\/49431524232_857a00ee2e_c.jpg","type":"image\/jpeg"}],"author":"Autores varios","twitter_misc":{"Escrito por":"Autores varios","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/regnumchristi.org\/concluye-la-asamblea-general-consagradas\/#article","isPartOf":{"@id":"https:\/\/regnumchristi.org\/concluye-la-asamblea-general-consagradas\/"},"author":{"name":"Autores varios","@id":"https:\/\/regnumchristi.org\/#\/schema\/person\/73f2e414269cfbf8edecc2fd90af81f2"},"headline":"Concluye la Asamblea General 2020 de las Consagradas del Regnum Christi","datePublished":"2020-03-09T13:44:57+00:00","dateModified":"2023-07-14T16:24:00+00:00","mainEntityOfPage":{"@id":"https:\/\/regnumchristi.org\/concluye-la-asamblea-general-consagradas\/"},"wordCount":532,"publisher":{"@id":"https:\/\/regnumchristi.org\/#organization"},"image":{"@id":"https:\/\/regnumchristi.org\/concluye-la-asamblea-general-consagradas\/#primaryimage"},"thumbnailUrl":"https:\/\/regnumchristi.org\/wp-content\/uploads\/2020\/03\/49431524232_857a00ee2e_c.jpg","keywords":["Asamblea General","Consagradas del Regnum Christi","vida consagrada"],"articleSection":["Destacadas","Noticias"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/regnumchristi.org\/concluye-la-asamblea-general-consagradas\/","url":"https:\/\/regnumchristi.org\/concluye-la-asamblea-general-consagradas\/","name":"Concluye la Asamblea General de las Consagradas del Regnum Christi","isPartOf":{"@id":"https:\/\/regnumchristi.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/regnumchristi.org\/concluye-la-asamblea-general-consagradas\/#primaryimage"},"image":{"@id":"https:\/\/regnumchristi.org\/concluye-la-asamblea-general-consagradas\/#primaryimage"},"thumbnailUrl":"https:\/\/regnumchristi.org\/wp-content\/uploads\/2020\/03\/49431524232_857a00ee2e_c.jpg","datePublished":"2020-03-09T13:44:57+00:00","dateModified":"2023-07-14T16:24:00+00:00","description":"Las Consagradas del Regnum Christi han concluido el viernes 6 de marzo su primera Asamblea General Ordinaria como Sociedad de Vida Apost\u00f3lica (SVA).","breadcrumb":{"@id":"https:\/\/regnumchristi.org\/concluye-la-asamblea-general-consagradas\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/regnumchristi.org\/concluye-la-asamblea-general-consagradas\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/regnumchristi.org\/concluye-la-asamblea-general-consagradas\/#primaryimage","url":"https:\/\/regnumchristi.org\/wp-content\/uploads\/2020\/03\/49431524232_857a00ee2e_c.jpg","contentUrl":"https:\/\/regnumchristi.org\/wp-content\/uploads\/2020\/03\/49431524232_857a00ee2e_c.jpg","width":799,"height":533,"caption":"Concluye la Asamblea General 2020 de las Consagradas del Regnum Christi"},{"@type":"BreadcrumbList","@id":"https:\/\/regnumchristi.org\/concluye-la-asamblea-general-consagradas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/regnumchristi.org\/es\/"},{"@type":"ListItem","position":2,"name":"Concluye la Asamblea General 2020 de las Consagradas del Regnum Christi"}]},{"@type":"WebSite","@id":"https:\/\/regnumchristi.org\/#website","url":"https:\/\/regnumchristi.org\/","name":"Regnum Christi Internacional","description":"El Regnum Christi es una realidad de la Iglesia cat\u00f3lica cuya misi\u00f3n es hacer presente el Reino de Cristo","publisher":{"@id":"https:\/\/regnumchristi.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/regnumchristi.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/regnumchristi.org\/#organization","name":"Regnum Christi Internacional","url":"https:\/\/regnumchristi.org\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/regnumchristi.org\/#\/schema\/logo\/image\/","url":"https:\/\/regnumchristi.es\/wp-content\/uploads\/2023\/03\/Favicon-RC_ligh-cuadrado.png","contentUrl":"https:\/\/regnumchristi.es\/wp-content\/uploads\/2023\/03\/Favicon-RC_ligh-cuadrado.png","width":1080,"height":1080,"caption":"Regnum Christi Internacional"},"image":{"@id":"https:\/\/regnumchristi.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/RegnumChristiEspana\/","https:\/\/x.com\/rc_espana","https:\/\/www.instagram.com\/rc_espana\/","https:\/\/es.linkedin.com\/company\/regnumchristiespaa"]},{"@type":"Person","@id":"https:\/\/regnumchristi.org\/#\/schema\/person\/73f2e414269cfbf8edecc2fd90af81f2","name":"Autores varios","url":"https:\/\/regnumchristi.org\/es\/author\/jarceocaesc-com\/"}]}},"_links":{"self":[{"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/posts\/25227","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/users\/49"}],"replies":[{"embeddable":true,"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/comments?post=25227"}],"version-history":[{"count":1,"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/posts\/25227\/revisions"}],"predecessor-version":[{"id":92881,"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/posts\/25227\/revisions\/92881"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/media\/25228"}],"wp:attachment":[{"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/media?parent=25227"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/categories?post=25227"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/tags?post=25227"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}