{"id":25635,"date":"2020-04-10T11:53:41","date_gmt":"2020-04-10T16:53:41","guid":{"rendered":"https:\/\/www.regnumchristi.org\/es\/?p=25635"},"modified":"2023-07-14T18:23:40","modified_gmt":"2023-07-14T16:23:40","slug":"experimentar-el-deseo-de-dios","status":"publish","type":"post","link":"https:\/\/regnumchristi.org\/es\/experimentar-el-deseo-de-dios\/","title":{"rendered":"Experimentar el deseo de Dios"},"content":{"rendered":"<h5 style=\"text-align: right;\"><em>Por Andr\u00e9s Felipe Garc\u00eda, LC<\/em><\/h5>\n<p><a href=\"https:\/\/regnumchristi.org\/wp-content\/uploads\/2020\/04\/20150329-_CES5578.jpg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignright size-medium wp-image-25637\" src=\"https:\/\/regnumchristi.org\/wp-content\/uploads\/2020\/04\/20150329-_CES5578-300x200.jpg\" alt=\"Experimentar el deseo de Dios\" width=\"300\" height=\"200\" srcset=\"https:\/\/regnumchristi.org\/wp-content\/uploads\/2020\/04\/20150329-_CES5578-300x200.jpg 300w, https:\/\/regnumchristi.org\/wp-content\/uploads\/2020\/04\/20150329-_CES5578-1024x684.jpg 1024w, https:\/\/regnumchristi.org\/wp-content\/uploads\/2020\/04\/20150329-_CES5578-768x513.jpg 768w, https:\/\/regnumchristi.org\/wp-content\/uploads\/2020\/04\/20150329-_CES5578-1536x1025.jpg 1536w, https:\/\/regnumchristi.org\/wp-content\/uploads\/2020\/04\/20150329-_CES5578.jpg 2048w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>La pregunta que pasa por nuestro coraz\u00f3n es: \u00bfc\u00f3mo encontrarnos con Dios en esta semana santa, semana de amor, semana de dolor, semana de angustia, semana de esperanza?<\/p>\n<p>Los cat\u00f3licos que creemos en la presencia real de Cristo en la Eucarist\u00eda podemos sentirnos en estos momentos turbados, tristes al saber que no podremos estar f\u00edsicamente presentes en adoraci\u00f3n en estos d\u00edas y no podremos recibir al Pan de la Vida. No podremos acompa\u00f1ar mediante la adoraci\u00f3n a quien sufre por amor a nosotros, a quien ha cargado sobre s\u00ed el mal, el dolor y las angustias del mundo. Y sentimos una gran a\u00f1oranza de todos los elementos externos que embellecen estos misterios: las procesiones, los monumentos, el fervor de los otros que nos motiva.<\/p>\n<p>Pero entonces, \u00bfqu\u00e9 podemos hacer?<\/p>\n<p>Podemos ejercitar nuestra fe. Nosotros creemos en el Dios real, en el Dios cercano que hace todas las cosas nuevas. Creemos en el Dios creativo, que tiene sed y quiere realmente encontrarse con nosotros, en el Dios que permite el mal \u2013no lo quiere, pero lo permite\u2013 y sabe sacar cosas buenas del mal mismo. Ese Dios quiere hacerse presente de un modo muy especial en esta semana santa.<\/p>\n<p>Pero \u00bfqu\u00e9 bien puede sacar Dios de esta situaci\u00f3n y c\u00f3mo encontrarnos con \u00c9l?<\/p>\n<p><a href=\"https:\/\/regnumchristi.org\/wp-content\/uploads\/2020\/04\/20150305-untitled-51.jpg\"><img decoding=\"async\" class=\"alignleft size-medium wp-image-25638\" src=\"https:\/\/regnumchristi.org\/wp-content\/uploads\/2020\/04\/20150305-untitled-51-300x200.jpg\" alt=\"Experimentar el deseo de Dios\" width=\"300\" height=\"200\" srcset=\"https:\/\/regnumchristi.org\/wp-content\/uploads\/2020\/04\/20150305-untitled-51-300x200.jpg 300w, https:\/\/regnumchristi.org\/wp-content\/uploads\/2020\/04\/20150305-untitled-51-1024x684.jpg 1024w, https:\/\/regnumchristi.org\/wp-content\/uploads\/2020\/04\/20150305-untitled-51-768x513.jpg 768w, https:\/\/regnumchristi.org\/wp-content\/uploads\/2020\/04\/20150305-untitled-51-1536x1025.jpg 1536w, https:\/\/regnumchristi.org\/wp-content\/uploads\/2020\/04\/20150305-untitled-51.jpg 2048w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>Podemos estar seguros de que este momento es un momento de purificaci\u00f3n en el amor, de descubrimiento de lo que realmente importa, de desear lo verdadero, lo bueno y lo bello.<\/p>\n<p>Dios est\u00e1 aprovechando este momento para aumentar nuestro deseo de \u00c9l, para que despu\u00e9s de que este periodo termine, salgamos m\u00e1s centrados en lo esencial de nuestra vida: un profundo deseo de amar a Dios y a nuestro pr\u00f3jimo, un deseo de cambiar el mundo con la fuerza del amor.<\/p>\n<p>Podr\u00edamos definir este tiempo como el tiempo del deseo. El deseo es una reacci\u00f3n ante el bien querido, pero que en ese momento no se posee, que est\u00e1 ausente y por ello se siente a\u00f1oranza. \u00a1Y aunque Dios es un Dios presente siempre tendremos sed y a\u00f1oranza de \u00c9l, pues la infinitud de su amor nunca se acaba!<\/p>\n<p>Este deseo puede ser llenado muy profundamente en estos d\u00edas santos. Dios se har\u00e1 presente, Dios tocar\u00e1 nuestros corazones en estos d\u00edas. Es hermoso sentir el deseo de Dios, el deseo de encontrarnos con \u00c9l, de recibir de \u00c9l la respuesta a los interrogantes m\u00e1s profundos de nuestro coraz\u00f3n: Se\u00f1or, \u00bfrealmente te interesas por nosotros?, \u00bfen realidad puedes sanarme?, \u00bfme amas, me acompa\u00f1as?, \u00bfpor qu\u00e9 tanto mal?<\/p>\n<p>Por eso es momento de orar, de hablar con Dios de coraz\u00f3n a coraz\u00f3n, de hablar con el se\u00f1or de una manera renovada. Benedicto XVI defin\u00eda la oraci\u00f3n como \u00abel encuentro entre la sed de Dios y la sed del hombre\u00bb. el hombre tiene sed de Dios y Dios tiene sed de que el hombre tenga sed de \u00c9l.<\/p>\n<p><a href=\"https:\/\/regnumchristi.org\/wp-content\/uploads\/2020\/04\/20150403-_CES5613.jpg\"><img decoding=\"async\" class=\"alignright size-medium wp-image-25639\" src=\"https:\/\/regnumchristi.org\/wp-content\/uploads\/2020\/04\/20150403-_CES5613-300x200.jpg\" alt=\"Experimentar el deseo de Dios\" width=\"300\" height=\"200\" srcset=\"https:\/\/regnumchristi.org\/wp-content\/uploads\/2020\/04\/20150403-_CES5613-300x200.jpg 300w, https:\/\/regnumchristi.org\/wp-content\/uploads\/2020\/04\/20150403-_CES5613-1024x684.jpg 1024w, https:\/\/regnumchristi.org\/wp-content\/uploads\/2020\/04\/20150403-_CES5613-768x513.jpg 768w, https:\/\/regnumchristi.org\/wp-content\/uploads\/2020\/04\/20150403-_CES5613-1536x1025.jpg 1536w, https:\/\/regnumchristi.org\/wp-content\/uploads\/2020\/04\/20150403-_CES5613.jpg 2048w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>Misteriosamente no solo nosotros estamos sedientos, sino que Dios tambi\u00e9n est\u00e1 sediento de nosotros. Y \u00c9l, que es todopoderoso y que ve en lo secreto, nos llenar\u00e1 con su amor. \u00c9l encontrar\u00e1 la forma de que experimentemos su amor. Con la oraci\u00f3n estamos colmando esta sed de Dios, pues nuestra sed de \u00c9l est\u00e1 creciendo. Estos d\u00edas santos nos muestran las consecuencias de la sed que Dios tiene de nosotros.<\/p>\n<p>En resumen, \u00bfqu\u00e9 nos quiere decir Dios en esta semana santa?<\/p>\n<p>Nos quiere decir que nos ama, que somos importantes para \u00c9l, tan importantes que ha cargado sobre s\u00ed todo el peso del pecado del mundo, todo el mal.<\/p>\n<p>Quiere mostrarnos sus heridas y demostrarnos que \u00c9l con las suyas puede sanar las nuestras.<\/p>\n<p>Quiere que sepamos que \u00c9l nos comprende, que se hizo hombre y que experiment\u00f3 lo que nosotros experimentamos: el miedo, el abandono, la traici\u00f3n, el rechazo, la humillaci\u00f3n, la inseguridad.<\/p>\n<p>Quiere ense\u00f1arnos que no se vence el mal con el odio, con la guerra, con el rechazo; sino con la entrega, con el amor que hace nuevas todas las cosas.<\/p>\n<p>Quiere que sepamos que \u00c9l nos pide una verdadera conversi\u00f3n, pero no con castigos sino con su amor que recibe voluntariamente los golpes que nosotros merecer\u00edamos.<\/p>\n<p><a href=\"https:\/\/www.regnumchristi.org\/es\/wp-content\/uploads\/2020\/04\/DSC_7652-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-25640\" src=\"https:\/\/www.regnumchristi.org\/es\/wp-content\/uploads\/2020\/04\/DSC_7652-300x201.jpg\" alt=\"Experimentar el deseo de Dios\" width=\"300\" height=\"201\" \/><\/a>Quiere que experimentemos otros modos de su presencia, adem\u00e1s de la participaci\u00f3n de las celebraciones digitales: en la belleza de la creaci\u00f3n, en el pr\u00f3jimo (en la sonrisa de un ni\u00f1o, en la acaricia de la persona amada), pero tambi\u00e9n en el que sufre; ya que como los tratamos a ellos as\u00ed lo tratamos a \u00c9l.<\/p>\n<p>Quiere ense\u00f1arnos que es imposible sacarlo de este mundo porque \u00c9l realmente ama a este mundo m\u00e1s que nosotros mismos. Los hombres podr\u00e1n cerrar las iglesias, podr\u00e1n quitar los crucifijos de los lugares p\u00fablicos, podr\u00e1n eliminar todos los objetos religiosos, pero no a Dios. Para eliminar a Dios de la vida de los hombres tendr\u00edamos que eliminar al hombre mismo, que incluso sin quererlo lleva en s\u00ed la imagen de Dios y un coraz\u00f3n sediento hasta que no descanse en \u00e9l (cf. san Agust\u00edn).<\/p>\n<p>Por eso en estos d\u00edas el coraz\u00f3n ser\u00e1 el sagrario al que Dios quiere bajar. Y quiere bajar para quedarse. Y una vez que podamos volver a verlo f\u00edsicamente en la Eucarist\u00eda reconoceremos que era \u00c9l quien camin\u00f3 de una manera especial con nosotros esta semana. Y as\u00ed aprovecharemos para decirle: Se\u00f1or qu\u00e9date siempre nosotros. Y nos daremos cuenta de que depende m\u00e1s de nosotros que el Se\u00f1or se quede, ya que \u00c9l est\u00e1 continuamente tocando a las puertas de nuestro coraz\u00f3n.<\/p>\n<p>Estoy seguro de que el mundo necesita de Dios, necesita al Dios de la esperanza, el Dios que vence el mal. El Dios vivo y real que es el \u00fanico que puede llenar los deseos m\u00e1s profundos del coraz\u00f3n humano. El Dios que vence la muerte y que da una esperanza no solo para esta vida, sino tambi\u00e9n para la que nos espera.<\/p>\n<p>Quiz\u00e1s esta ocasi\u00f3n es un momento especial para encontrarnos con ese Dios especial, quiz\u00e1s ya podemos estar experimentando de una manera nueva su presencia. Quiz\u00e1s este a\u00f1o nos dejemos conquistar completamente de su amor, \u00a1un amor m\u00e1s fuerte que la muerte!<\/p>\n<p>Que Dios nos d\u00e9 la gracia de acerquemos a este triduo sacro con el coraz\u00f3n abierto, con reverencia, con amor, como quien sabe que el Se\u00f1or nos puede sorprender. Quit\u00e9monos las sandalias como lo hizo Mois\u00e9s al ver esa zarza ardiente del amor de Dios que no se consum\u00eda. Amor que no se apaga tampoco hoy. Amor que siempre est\u00e1 ah\u00ed para que nosotros lo acojamos y podamos experimentar cu\u00e1n importante somos para \u00c9l.<\/p>\n<h5><em>Andr\u00e9s Felipe Garc\u00eda, LC es un religioso de los Legionarios de Cristo actualmente <a href=\"https:\/\/colegiolcroma.org\/\" target=\"_blank\" rel=\"noopener noreferrer\">estudiando en Roma<\/a>.<\/em><\/h5>\n<p>Te puede interesar: <a href=\"https:\/\/www.regnumchristi.org\/es\/retiro-espiritual-cuaresma-2020\/\" target=\"_blank\" rel=\"noopener noreferrer\">Los protagonistas de la Pasi\u00f3n de Cristo, \u00bfen cu\u00e1l de ellos me retrato?<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p> [&hellip;]<\/p>\n","protected":false},"author":49,"featured_media":25636,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"_daextrevop_audio_file_creation_date":"","_daextrevop_text_to_speech":"","_daextrevop_document_type":"","footnotes":""},"categories":[3031,1687],"tags":[3051,131,686],"class_list":["post-25635","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-destacadas","category-noticias","tag-esperanza","tag-fe","tag-semana-santa"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Experimentar el deseo de Dios - \u00bfC\u00f3mo encontrarse con Dios hoy?<\/title>\n<meta name=\"description\" content=\"\u00bfC\u00f3mo encontrarnos con Dios en esta semana santa, semana de amor, semana de dolor, semana de angustia, semana de esperanza? Experimentar el deseo de Dios.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/regnumchristi.org\/es\/experimentar-el-deseo-de-dios\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Experimentar el deseo de Dios - \u00bfC\u00f3mo encontrarse con Dios hoy?\" \/>\n<meta property=\"og:description\" content=\"\u00bfC\u00f3mo encontrarnos con Dios en esta semana santa, semana de amor, semana de dolor, semana de angustia, semana de esperanza? Experimentar el deseo de Dios.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/regnumchristi.org\/es\/experimentar-el-deseo-de-dios\/\" \/>\n<meta property=\"og:site_name\" content=\"Regnum Christi Internacional\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/RegnumChristiEspana\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-04-10T16:53:41+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-07-14T16:23:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/regnumchristi.org\/wp-content\/uploads\/2020\/04\/14054112_1718001558461486_4637922578385991986_n.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"736\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Autores varios\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Autores varios\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/en\\\/experimentar-el-deseo-de-dios\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/en\\\/experimentar-el-deseo-de-dios\\\/\"},\"author\":{\"name\":\"Autores varios\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#\\\/schema\\\/person\\\/73f2e414269cfbf8edecc2fd90af81f2\"},\"headline\":\"Experimentar el deseo de Dios\",\"datePublished\":\"2020-04-10T16:53:41+00:00\",\"dateModified\":\"2023-07-14T16:23:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/en\\\/experimentar-el-deseo-de-dios\\\/\"},\"wordCount\":1213,\"publisher\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/en\\\/experimentar-el-deseo-de-dios\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/regnumchristi.org\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/14054112_1718001558461486_4637922578385991986_n.jpg\",\"keywords\":[\"esperanza\",\"fe\",\"semana santa\"],\"articleSection\":[\"Destacadas\",\"Noticias\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/en\\\/experimentar-el-deseo-de-dios\\\/\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/en\\\/experimentar-el-deseo-de-dios\\\/\",\"name\":\"Experimentar el deseo de Dios - \u00bfC\u00f3mo encontrarse con Dios hoy?\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/en\\\/experimentar-el-deseo-de-dios\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/en\\\/experimentar-el-deseo-de-dios\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/regnumchristi.org\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/14054112_1718001558461486_4637922578385991986_n.jpg\",\"datePublished\":\"2020-04-10T16:53:41+00:00\",\"dateModified\":\"2023-07-14T16:23:40+00:00\",\"description\":\"\u00bfC\u00f3mo encontrarnos con Dios en esta semana santa, semana de amor, semana de dolor, semana de angustia, semana de esperanza? Experimentar el deseo de Dios.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/en\\\/experimentar-el-deseo-de-dios\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/regnumchristi.org\\\/en\\\/experimentar-el-deseo-de-dios\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/en\\\/experimentar-el-deseo-de-dios\\\/#primaryimage\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/14054112_1718001558461486_4637922578385991986_n.jpg\",\"contentUrl\":\"https:\\\/\\\/regnumchristi.org\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/14054112_1718001558461486_4637922578385991986_n.jpg\",\"width\":960,\"height\":736,\"caption\":\"Experimentar el deseo de Dios\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/en\\\/experimentar-el-deseo-de-dios\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/regnumchristi.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Experimentar el deseo de Dios\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#website\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/\",\"name\":\"Regnum Christi Internacional\",\"description\":\"El Regnum Christi es una realidad de la Iglesia cat\u00f3lica cuya misi\u00f3n es hacer presente el Reino de Cristo\",\"publisher\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/regnumchristi.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#organization\",\"name\":\"Regnum Christi Internacional\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/regnumchristi.es\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Favicon-RC_ligh-cuadrado.png\",\"contentUrl\":\"https:\\\/\\\/regnumchristi.es\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Favicon-RC_ligh-cuadrado.png\",\"width\":1080,\"height\":1080,\"caption\":\"Regnum Christi Internacional\"},\"image\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/RegnumChristiEspana\\\/\",\"https:\\\/\\\/x.com\\\/rc_espana\",\"https:\\\/\\\/www.instagram.com\\\/rc_espana\\\/\",\"https:\\\/\\\/es.linkedin.com\\\/company\\\/regnumchristiespaa\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#\\\/schema\\\/person\\\/73f2e414269cfbf8edecc2fd90af81f2\",\"name\":\"Autores varios\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/es\\\/author\\\/jarceocaesc-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Experimentar el deseo de Dios - \u00bfC\u00f3mo encontrarse con Dios hoy?","description":"\u00bfC\u00f3mo encontrarnos con Dios en esta semana santa, semana de amor, semana de dolor, semana de angustia, semana de esperanza? Experimentar el deseo de Dios.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/regnumchristi.org\/es\/experimentar-el-deseo-de-dios\/","og_locale":"es_MX","og_type":"article","og_title":"Experimentar el deseo de Dios - \u00bfC\u00f3mo encontrarse con Dios hoy?","og_description":"\u00bfC\u00f3mo encontrarnos con Dios en esta semana santa, semana de amor, semana de dolor, semana de angustia, semana de esperanza? Experimentar el deseo de Dios.","og_url":"https:\/\/regnumchristi.org\/es\/experimentar-el-deseo-de-dios\/","og_site_name":"Regnum Christi Internacional","article_publisher":"https:\/\/www.facebook.com\/RegnumChristiEspana\/","article_published_time":"2020-04-10T16:53:41+00:00","article_modified_time":"2023-07-14T16:23:40+00:00","og_image":[{"width":960,"height":736,"url":"https:\/\/regnumchristi.org\/wp-content\/uploads\/2020\/04\/14054112_1718001558461486_4637922578385991986_n.jpg","type":"image\/jpeg"}],"author":"Autores varios","twitter_misc":{"Escrito por":"Autores varios","Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/regnumchristi.org\/en\/experimentar-el-deseo-de-dios\/#article","isPartOf":{"@id":"https:\/\/regnumchristi.org\/en\/experimentar-el-deseo-de-dios\/"},"author":{"name":"Autores varios","@id":"https:\/\/regnumchristi.org\/#\/schema\/person\/73f2e414269cfbf8edecc2fd90af81f2"},"headline":"Experimentar el deseo de Dios","datePublished":"2020-04-10T16:53:41+00:00","dateModified":"2023-07-14T16:23:40+00:00","mainEntityOfPage":{"@id":"https:\/\/regnumchristi.org\/en\/experimentar-el-deseo-de-dios\/"},"wordCount":1213,"publisher":{"@id":"https:\/\/regnumchristi.org\/#organization"},"image":{"@id":"https:\/\/regnumchristi.org\/en\/experimentar-el-deseo-de-dios\/#primaryimage"},"thumbnailUrl":"https:\/\/regnumchristi.org\/wp-content\/uploads\/2020\/04\/14054112_1718001558461486_4637922578385991986_n.jpg","keywords":["esperanza","fe","semana santa"],"articleSection":["Destacadas","Noticias"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/regnumchristi.org\/en\/experimentar-el-deseo-de-dios\/","url":"https:\/\/regnumchristi.org\/en\/experimentar-el-deseo-de-dios\/","name":"Experimentar el deseo de Dios - \u00bfC\u00f3mo encontrarse con Dios hoy?","isPartOf":{"@id":"https:\/\/regnumchristi.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/regnumchristi.org\/en\/experimentar-el-deseo-de-dios\/#primaryimage"},"image":{"@id":"https:\/\/regnumchristi.org\/en\/experimentar-el-deseo-de-dios\/#primaryimage"},"thumbnailUrl":"https:\/\/regnumchristi.org\/wp-content\/uploads\/2020\/04\/14054112_1718001558461486_4637922578385991986_n.jpg","datePublished":"2020-04-10T16:53:41+00:00","dateModified":"2023-07-14T16:23:40+00:00","description":"\u00bfC\u00f3mo encontrarnos con Dios en esta semana santa, semana de amor, semana de dolor, semana de angustia, semana de esperanza? Experimentar el deseo de Dios.","breadcrumb":{"@id":"https:\/\/regnumchristi.org\/en\/experimentar-el-deseo-de-dios\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/regnumchristi.org\/en\/experimentar-el-deseo-de-dios\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/regnumchristi.org\/en\/experimentar-el-deseo-de-dios\/#primaryimage","url":"https:\/\/regnumchristi.org\/wp-content\/uploads\/2020\/04\/14054112_1718001558461486_4637922578385991986_n.jpg","contentUrl":"https:\/\/regnumchristi.org\/wp-content\/uploads\/2020\/04\/14054112_1718001558461486_4637922578385991986_n.jpg","width":960,"height":736,"caption":"Experimentar el deseo de Dios"},{"@type":"BreadcrumbList","@id":"https:\/\/regnumchristi.org\/en\/experimentar-el-deseo-de-dios\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/regnumchristi.org\/es\/"},{"@type":"ListItem","position":2,"name":"Experimentar el deseo de Dios"}]},{"@type":"WebSite","@id":"https:\/\/regnumchristi.org\/#website","url":"https:\/\/regnumchristi.org\/","name":"Regnum Christi Internacional","description":"El Regnum Christi es una realidad de la Iglesia cat\u00f3lica cuya misi\u00f3n es hacer presente el Reino de Cristo","publisher":{"@id":"https:\/\/regnumchristi.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/regnumchristi.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/regnumchristi.org\/#organization","name":"Regnum Christi Internacional","url":"https:\/\/regnumchristi.org\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/regnumchristi.org\/#\/schema\/logo\/image\/","url":"https:\/\/regnumchristi.es\/wp-content\/uploads\/2023\/03\/Favicon-RC_ligh-cuadrado.png","contentUrl":"https:\/\/regnumchristi.es\/wp-content\/uploads\/2023\/03\/Favicon-RC_ligh-cuadrado.png","width":1080,"height":1080,"caption":"Regnum Christi Internacional"},"image":{"@id":"https:\/\/regnumchristi.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/RegnumChristiEspana\/","https:\/\/x.com\/rc_espana","https:\/\/www.instagram.com\/rc_espana\/","https:\/\/es.linkedin.com\/company\/regnumchristiespaa"]},{"@type":"Person","@id":"https:\/\/regnumchristi.org\/#\/schema\/person\/73f2e414269cfbf8edecc2fd90af81f2","name":"Autores varios","url":"https:\/\/regnumchristi.org\/es\/author\/jarceocaesc-com\/"}]}},"_links":{"self":[{"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/posts\/25635","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/users\/49"}],"replies":[{"embeddable":true,"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/comments?post=25635"}],"version-history":[{"count":1,"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/posts\/25635\/revisions"}],"predecessor-version":[{"id":92868,"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/posts\/25635\/revisions\/92868"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/media\/25636"}],"wp:attachment":[{"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/media?parent=25635"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/categories?post=25635"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/tags?post=25635"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}