{"id":25788,"date":"2020-04-20T08:37:57","date_gmt":"2020-04-20T13:37:57","guid":{"rendered":"https:\/\/www.regnumchristi.org\/es\/?p=25788"},"modified":"2020-04-20T08:37:57","modified_gmt":"2020-04-20T13:37:57","slug":"lunes-20-de-abril-de-2020-la-vida-de-cristo-en-mi-vida","status":"publish","type":"post","link":"https:\/\/regnumchristi.org\/es\/lunes-20-de-abril-de-2020-la-vida-de-cristo-en-mi-vida\/","title":{"rendered":"Lunes 20 de abril de 2020 &#8211; La vida de Cristo en mi vida."},"content":{"rendered":"<p>H. Francisco Posada, L.C.<\/p>\n<p>En el nombre del Padre y del Hijo y del Esp\u00edritu Santo. Am\u00e9n.<\/p>\n<p>Cristo, Rey nuestro. \u00a1Venga tu Reino!<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>Oraci\u00f3n preparatoria <\/strong><em>(para ponerme en presencia de Dios)<\/em><\/p>\n<p>Se\u00f1or, T\u00fa que est\u00e1s tan cerca de m\u00ed que hasta te puedo tocar, ay\u00fadame a comunicar esta experiencia maravillosa en mi vida a la gente que me rodea, especialmente a mi familia. Te pido que, en momentos dif\u00edciles, pueda ver tu cruz y tomar fuerzas de tu sufrimiento salv\u00edfico para sobrellevar mi cruz. Te doy gracias por todo lo que me has dado.<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>Evangelio del d\u00eda <\/strong><em>(para orientar tu meditaci\u00f3n)<\/em><\/p>\n<p>Del santo Evangelio seg\u00fan san Juan 3, 1-8<\/p>\n<p>Hab\u00eda un fariseo llamado Nicodemo, hombre principal entre los jud\u00edos, que fue de noche a ver a Jes\u00fas y le dijo: &#8220;Maestro, sabemos que has venido de parte de Dios, como maestro; porque nadie puede hacer los signos que t\u00fa haces, si Dios no est\u00e1 con \u00e9l&#8221;.<\/p>\n<p>&nbsp;<\/p>\n<p>Jes\u00fas le contest\u00f3: &#8220;Yo te aseguro que quien no renace de lo alto, no puede ver el Reino de Dios&#8221;. Nicodemo le pregunt\u00f3: &#8220;\u00bfC\u00f3mo puede nacer un hombre siendo ya viejo? \u00bfAcaso puede, por segunda vez, entrar en el vientre de su madre y volver a nacer?&#8221;.<\/p>\n<p>&nbsp;<\/p>\n<p>Le respondi\u00f3 Jes\u00fas: &#8220;Yo te aseguro que el que no nace del agua y del Esp\u00edritu, no puede entrar en el Reino de Dios.\u00a0 Lo que nace de la carne, es carne; lo que nace del Esp\u00edritu, es esp\u00edritu. No te extra\u00f1es de que te haya dicho: &#8216;Tienen que renacer de lo alto&#8217;. El viento sopla donde quiere y oyes su ruido, pero no sabes de d\u00f3nde viene ni a d\u00f3nde va. As\u00ed pasa con quien ha nacido del Esp\u00edritu&#8221;.<\/p>\n<p>&nbsp;<\/p>\n<p>Palabra del Se\u00f1or.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Medita lo que Dios te dice en el Evangelio<\/strong><\/p>\n<p>En este tiempo tan especial de Pascua y con las circunstancias especiales de la pandemia, una cosa que me vino en mente al ver tantos videos, im\u00e1genes, canciones religiosas o cristianas en el internet. \u00bfQu\u00e9 pensar\u00eda un no creyente al ver todo esto? Creo que sin duda se dar\u00eda cuenta que este Cristo es alguien importante, que tiene una madre maravillosa y, extra\u00f1amente, muchas personas la invocan con las mismas palabras: madre; que hay gente a la que les importa mucho la iglesia y lo que el hombre de blanco (el Papa) dice al mundo. En una palabra, se encontrar\u00edan con que los cristianos creen en una persona viva que sienten presente en sus vidas. Es este Cristo que se hizo pecado y muri\u00f3 en la cruz para tomar nuestros pecados sobre \u00c9l; y as\u00ed como Dios mand\u00f3 a Mois\u00e9s que hiciera una serpiente para librar de la muerte a los jud\u00edos en el desierto, as\u00ed ha pasado con Cristo elevado en una cruz. Y ahora celebramos que la historia no se ha quedado ah\u00ed, celebramos la vida y la vida eterna, celebramos que Cristo ha resucitado de la muerte y nos invita a ser parte de su vida nueva.<\/p>\n<p>Para experimentar los frutos de la resurrecci\u00f3n del Se\u00f1or necesitamos estar cerca de \u00c9l para dejarnos formar por \u00c9l que quiere, con todo el coraz\u00f3n, ser parte de nuestras vidas. Invitemos a Jes\u00fas a nuestra casa, a nuestro trabajo, con nuestra familia, con nuestros amigos, etc., porque con \u00c9l podemos hacer cosas inimaginables ya que somos capaces de todo en Aquel que nos conforta.<\/p>\n<p>\u00abNicodemo no entend\u00eda la l\u00f3gica de Dios, que es la l\u00f3gica de la gracia, de la misericordia, por la cual el que se hace peque\u00f1o se vuelve grande, el que se hace \u00faltimo pasa a ser el primero, el que se reconoce enfermo se cura. Esto significa dejar realmente la primac\u00eda al Padre, a Jes\u00fas y al Esp\u00edritu Santo en nuestra vida. Atenci\u00f3n: no se trata de convertirse en sacerdotes &#8220;pose\u00eddos&#8221;, casi como si se fuera depositario de un carisma extraordinario. No. Sacerdotes ordinarios, simples, humildes, equilibrados, pero capaces de dejarse regenerar constantemente por el Esp\u00edritu, d\u00f3ciles a su fuerza, interiormente libres \u2014sobre todo de s\u00ed mismos\u2014 porque les mueve el &#8220;viento&#8221; del Esp\u00edritu que sopla donde quiere.\u00bb<\/p>\n<p>(Homil\u00eda de S.S. Francisco, 10 de abril de 2018).<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>Di\u00e1logo con Cristo<\/strong><\/p>\n<p><em>\u00c9sta es la parte m\u00e1s importante de tu oraci\u00f3n, disponte a platicar con mucho amor con Aquel que te ama.<\/em><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>Prop\u00f3sito<\/strong><\/p>\n<p><em>Proponte uno personal. El que m\u00e1s amor implique en respuesta al Amado\u2026 o, si crees que es lo que Dios te pide, vive lo que se te sugiere a continuaci\u00f3n.<\/em><\/p>\n<p>Compartir un momento de gracia especial con Cristo a una persona.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Despedida<\/strong><\/p>\n<p>Te damos gracias, Se\u00f1or, por todos tus beneficios, a Ti que vives y reinas por los siglos de los siglos.<\/p>\n<p>Am\u00e9n.<\/p>\n<p>&nbsp;<\/p>\n<p>\u00a1Cristo, Rey nuestro!<\/p>\n<p>\u00a1Venga tu Reino!<\/p>\n<p>&nbsp;<\/p>\n<p>Virgen prudent\u00edsima, Mar\u00eda, Madre de la Iglesia.<\/p>\n<p>Ruega por nosotros.<\/p>\n<p>&nbsp;<\/p>\n<p>En el nombre del Padre y del Hijo y del Esp\u00edritu Santo. Am\u00e9n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p> [&hellip;]<\/p>\n","protected":false},"author":33,"featured_media":93233,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"_daextrevop_audio_file_creation_date":"","_daextrevop_text_to_speech":"","_daextrevop_document_type":"","footnotes":""},"categories":[3164],"tags":[],"class_list":["post-25788","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-meditacion-del-dia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Lunes 20 de abril de 2020 - La vida de Cristo en mi vida. - Regnum Christi Internacional<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/regnumchristi.org\/es\/lunes-20-de-abril-de-2020-la-vida-de-cristo-en-mi-vida\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lunes 20 de abril de 2020 - La vida de Cristo en mi vida. - Regnum Christi Internacional\" \/>\n<meta property=\"og:description\" content=\"[&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/regnumchristi.org\/es\/lunes-20-de-abril-de-2020-la-vida-de-cristo-en-mi-vida\/\" \/>\n<meta property=\"og:site_name\" content=\"Regnum Christi Internacional\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/RegnumChristiEspana\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-04-20T13:37:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/regnumchristi.org\/wp-content\/uploads\/2020\/04\/200420.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"628\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Mar Morales\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mar Morales\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/lunes-20-de-abril-de-2020-la-vida-de-cristo-en-mi-vida\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/lunes-20-de-abril-de-2020-la-vida-de-cristo-en-mi-vida\\\/\"},\"author\":{\"name\":\"Mar Morales\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#\\\/schema\\\/person\\\/390cded3fbd2800d0daee38acaecd350\"},\"headline\":\"Lunes 20 de abril de 2020 &#8211; La vida de Cristo en mi vida.\",\"datePublished\":\"2020-04-20T13:37:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/lunes-20-de-abril-de-2020-la-vida-de-cristo-en-mi-vida\\\/\"},\"wordCount\":882,\"publisher\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/lunes-20-de-abril-de-2020-la-vida-de-cristo-en-mi-vida\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/regnumchristi.org\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/200420.jpg\",\"articleSection\":[\"Meditaci\u00f3n del d\u00eda\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/lunes-20-de-abril-de-2020-la-vida-de-cristo-en-mi-vida\\\/\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/lunes-20-de-abril-de-2020-la-vida-de-cristo-en-mi-vida\\\/\",\"name\":\"Lunes 20 de abril de 2020 - La vida de Cristo en mi vida. - Regnum Christi Internacional\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/lunes-20-de-abril-de-2020-la-vida-de-cristo-en-mi-vida\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/lunes-20-de-abril-de-2020-la-vida-de-cristo-en-mi-vida\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/regnumchristi.org\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/200420.jpg\",\"datePublished\":\"2020-04-20T13:37:57+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/lunes-20-de-abril-de-2020-la-vida-de-cristo-en-mi-vida\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/regnumchristi.org\\\/lunes-20-de-abril-de-2020-la-vida-de-cristo-en-mi-vida\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/lunes-20-de-abril-de-2020-la-vida-de-cristo-en-mi-vida\\\/#primaryimage\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/200420.jpg\",\"contentUrl\":\"https:\\\/\\\/regnumchristi.org\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/200420.jpg\",\"width\":1200,\"height\":628},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/lunes-20-de-abril-de-2020-la-vida-de-cristo-en-mi-vida\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/regnumchristi.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lunes 20 de abril de 2020 &#8211; La vida de Cristo en mi vida.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#website\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/\",\"name\":\"Regnum Christi Internacional\",\"description\":\"El Regnum Christi es una realidad de la Iglesia cat\u00f3lica cuya misi\u00f3n es hacer presente el Reino de Cristo\",\"publisher\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/regnumchristi.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#organization\",\"name\":\"Regnum Christi Internacional\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/regnumchristi.es\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Favicon-RC_ligh-cuadrado.png\",\"contentUrl\":\"https:\\\/\\\/regnumchristi.es\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Favicon-RC_ligh-cuadrado.png\",\"width\":1080,\"height\":1080,\"caption\":\"Regnum Christi Internacional\"},\"image\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/RegnumChristiEspana\\\/\",\"https:\\\/\\\/x.com\\\/rc_espana\",\"https:\\\/\\\/www.instagram.com\\\/rc_espana\\\/\",\"https:\\\/\\\/es.linkedin.com\\\/company\\\/regnumchristiespaa\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#\\\/schema\\\/person\\\/390cded3fbd2800d0daee38acaecd350\",\"name\":\"Mar Morales\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/es\\\/author\\\/mmoralesserviciosrc-org\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lunes 20 de abril de 2020 - La vida de Cristo en mi vida. - Regnum Christi Internacional","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/regnumchristi.org\/es\/lunes-20-de-abril-de-2020-la-vida-de-cristo-en-mi-vida\/","og_locale":"es_MX","og_type":"article","og_title":"Lunes 20 de abril de 2020 - La vida de Cristo en mi vida. - Regnum Christi Internacional","og_description":"[&hellip;]","og_url":"https:\/\/regnumchristi.org\/es\/lunes-20-de-abril-de-2020-la-vida-de-cristo-en-mi-vida\/","og_site_name":"Regnum Christi Internacional","article_publisher":"https:\/\/www.facebook.com\/RegnumChristiEspana\/","article_published_time":"2020-04-20T13:37:57+00:00","og_image":[{"width":1200,"height":628,"url":"https:\/\/regnumchristi.org\/wp-content\/uploads\/2020\/04\/200420.jpg","type":"image\/jpeg"}],"author":"Mar Morales","twitter_misc":{"Escrito por":"Mar Morales","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/regnumchristi.org\/lunes-20-de-abril-de-2020-la-vida-de-cristo-en-mi-vida\/#article","isPartOf":{"@id":"https:\/\/regnumchristi.org\/lunes-20-de-abril-de-2020-la-vida-de-cristo-en-mi-vida\/"},"author":{"name":"Mar Morales","@id":"https:\/\/regnumchristi.org\/#\/schema\/person\/390cded3fbd2800d0daee38acaecd350"},"headline":"Lunes 20 de abril de 2020 &#8211; La vida de Cristo en mi vida.","datePublished":"2020-04-20T13:37:57+00:00","mainEntityOfPage":{"@id":"https:\/\/regnumchristi.org\/lunes-20-de-abril-de-2020-la-vida-de-cristo-en-mi-vida\/"},"wordCount":882,"publisher":{"@id":"https:\/\/regnumchristi.org\/#organization"},"image":{"@id":"https:\/\/regnumchristi.org\/lunes-20-de-abril-de-2020-la-vida-de-cristo-en-mi-vida\/#primaryimage"},"thumbnailUrl":"https:\/\/regnumchristi.org\/wp-content\/uploads\/2020\/04\/200420.jpg","articleSection":["Meditaci\u00f3n del d\u00eda"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/regnumchristi.org\/lunes-20-de-abril-de-2020-la-vida-de-cristo-en-mi-vida\/","url":"https:\/\/regnumchristi.org\/lunes-20-de-abril-de-2020-la-vida-de-cristo-en-mi-vida\/","name":"Lunes 20 de abril de 2020 - La vida de Cristo en mi vida. - Regnum Christi Internacional","isPartOf":{"@id":"https:\/\/regnumchristi.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/regnumchristi.org\/lunes-20-de-abril-de-2020-la-vida-de-cristo-en-mi-vida\/#primaryimage"},"image":{"@id":"https:\/\/regnumchristi.org\/lunes-20-de-abril-de-2020-la-vida-de-cristo-en-mi-vida\/#primaryimage"},"thumbnailUrl":"https:\/\/regnumchristi.org\/wp-content\/uploads\/2020\/04\/200420.jpg","datePublished":"2020-04-20T13:37:57+00:00","breadcrumb":{"@id":"https:\/\/regnumchristi.org\/lunes-20-de-abril-de-2020-la-vida-de-cristo-en-mi-vida\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/regnumchristi.org\/lunes-20-de-abril-de-2020-la-vida-de-cristo-en-mi-vida\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/regnumchristi.org\/lunes-20-de-abril-de-2020-la-vida-de-cristo-en-mi-vida\/#primaryimage","url":"https:\/\/regnumchristi.org\/wp-content\/uploads\/2020\/04\/200420.jpg","contentUrl":"https:\/\/regnumchristi.org\/wp-content\/uploads\/2020\/04\/200420.jpg","width":1200,"height":628},{"@type":"BreadcrumbList","@id":"https:\/\/regnumchristi.org\/lunes-20-de-abril-de-2020-la-vida-de-cristo-en-mi-vida\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/regnumchristi.org\/es\/"},{"@type":"ListItem","position":2,"name":"Lunes 20 de abril de 2020 &#8211; La vida de Cristo en mi vida."}]},{"@type":"WebSite","@id":"https:\/\/regnumchristi.org\/#website","url":"https:\/\/regnumchristi.org\/","name":"Regnum Christi Internacional","description":"El Regnum Christi es una realidad de la Iglesia cat\u00f3lica cuya misi\u00f3n es hacer presente el Reino de Cristo","publisher":{"@id":"https:\/\/regnumchristi.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/regnumchristi.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/regnumchristi.org\/#organization","name":"Regnum Christi Internacional","url":"https:\/\/regnumchristi.org\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/regnumchristi.org\/#\/schema\/logo\/image\/","url":"https:\/\/regnumchristi.es\/wp-content\/uploads\/2023\/03\/Favicon-RC_ligh-cuadrado.png","contentUrl":"https:\/\/regnumchristi.es\/wp-content\/uploads\/2023\/03\/Favicon-RC_ligh-cuadrado.png","width":1080,"height":1080,"caption":"Regnum Christi Internacional"},"image":{"@id":"https:\/\/regnumchristi.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/RegnumChristiEspana\/","https:\/\/x.com\/rc_espana","https:\/\/www.instagram.com\/rc_espana\/","https:\/\/es.linkedin.com\/company\/regnumchristiespaa"]},{"@type":"Person","@id":"https:\/\/regnumchristi.org\/#\/schema\/person\/390cded3fbd2800d0daee38acaecd350","name":"Mar Morales","url":"https:\/\/regnumchristi.org\/es\/author\/mmoralesserviciosrc-org\/"}]}},"_links":{"self":[{"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/posts\/25788","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/users\/33"}],"replies":[{"embeddable":true,"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/comments?post=25788"}],"version-history":[{"count":0,"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/posts\/25788\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/media\/93233"}],"wp:attachment":[{"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/media?parent=25788"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/categories?post=25788"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/tags?post=25788"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}