{"id":27528,"date":"2020-07-03T09:42:24","date_gmt":"2020-07-03T14:42:24","guid":{"rendered":"https:\/\/www.regnumchristi.org\/es\/?p=27528"},"modified":"2023-07-14T18:22:38","modified_gmt":"2023-07-14T16:22:38","slug":"fernando-rincon-gallardo-elguero","status":"publish","type":"post","link":"https:\/\/regnumchristi.org\/es\/fernando-rincon-gallardo-elguero\/","title":{"rendered":"Fernando Rinc\u00f3n Gallardo Elguero"},"content":{"rendered":"<p>Naci\u00f3 el 14 de mayo de 1978 en la Ciudad de M\u00e9xico y se consagr\u00f3 el 15 de septiembre de 1996. Es Ingeniero Industrial y maestro en desarrollo de capital humano por la Universidad An\u00e1huac M\u00e9xico. Fue formador del Centro Estudiantil de M\u00e9xico, delegado para centros educativos en los territorios de Monterrey y Chile y Argentina, subdirector del Instituto Irland\u00e9s de Monterrey, Director Nacional de los apostolados de Regnum Christi en Brasil, Director del ECYD en Monterrey y director de la comunidad de laicos consagrados en Monterrey. Desde 2013 ha sido consejero general de los Laicos Consagrados del Regnum Christi, desde 2018 director de la comunidad de Roma y desde 2017 es responsable del \u00e1rea de apostolados y secciones juveniles en el \u00e1rea de Vida y misi\u00f3n del Regnum Christi de la Direcci\u00f3n General de la Federaci\u00f3n Regnum Christi. Fue elegido segundo consejero general el 12 de febrero de 2020.<\/p>\n","protected":false},"excerpt":{"rendered":"<p> [&hellip;]<\/p>\n","protected":false},"author":49,"featured_media":27529,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"_daextrevop_audio_file_creation_date":"","_daextrevop_text_to_speech":"","_daextrevop_document_type":"","footnotes":""},"categories":[1687],"tags":[91],"class_list":["post-27528","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-laicos-consagrados-del-regnum-christi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Fernando Rinc\u00f3n Gallardo Elguero - Regnum Christi Internacional<\/title>\n<meta name=\"description\" content=\"Desde 2013 ha sido consejero general de los Laicos Consagrados del Regnum Christi, desde 2018 director de la comunidad de Roma y desde 2017 es responsable del \u00e1rea de apostolados y secciones juveniles en el \u00e1rea de Vida y misi\u00f3n del Regnum Christi de la Direcci\u00f3n General de la Federaci\u00f3n Regnum Christi. Fue elegido segundo consejero general el 12 de febrero de 2020.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/regnumchristi.org\/es\/fernando-rincon-gallardo-elguero\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fernando Rinc\u00f3n Gallardo Elguero - Regnum Christi Internacional\" \/>\n<meta property=\"og:description\" content=\"Desde 2013 ha sido consejero general de los Laicos Consagrados del Regnum Christi, desde 2018 director de la comunidad de Roma y desde 2017 es responsable del \u00e1rea de apostolados y secciones juveniles en el \u00e1rea de Vida y misi\u00f3n del Regnum Christi de la Direcci\u00f3n General de la Federaci\u00f3n Regnum Christi. Fue elegido segundo consejero general el 12 de febrero de 2020.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/regnumchristi.org\/es\/fernando-rincon-gallardo-elguero\/\" \/>\n<meta property=\"og:site_name\" content=\"Regnum Christi Internacional\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/RegnumChristiEspana\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-07-03T14:42:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-07-14T16:22:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/regnumchristi.org\/wp-content\/uploads\/2020\/09\/Fernando-rincon-e1599144264969.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"551\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Autores varios\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Autores varios\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/fernando-rincon-gallardo-elguero\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/fernando-rincon-gallardo-elguero\\\/\"},\"author\":{\"name\":\"Autores varios\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#\\\/schema\\\/person\\\/73f2e414269cfbf8edecc2fd90af81f2\"},\"headline\":\"Fernando Rinc\u00f3n Gallardo Elguero\",\"datePublished\":\"2020-07-03T14:42:24+00:00\",\"dateModified\":\"2023-07-14T16:22:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/fernando-rincon-gallardo-elguero\\\/\"},\"wordCount\":154,\"publisher\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/fernando-rincon-gallardo-elguero\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/regnumchristi.org\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/Fernando-rincon-e1599144264969.jpg\",\"keywords\":[\"Laicos Consagrados del Regnum Christi\"],\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/fernando-rincon-gallardo-elguero\\\/\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/fernando-rincon-gallardo-elguero\\\/\",\"name\":\"Fernando Rinc\u00f3n Gallardo Elguero - Regnum Christi Internacional\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/fernando-rincon-gallardo-elguero\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/fernando-rincon-gallardo-elguero\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/regnumchristi.org\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/Fernando-rincon-e1599144264969.jpg\",\"datePublished\":\"2020-07-03T14:42:24+00:00\",\"dateModified\":\"2023-07-14T16:22:38+00:00\",\"description\":\"Desde 2013 ha sido consejero general de los Laicos Consagrados del Regnum Christi, desde 2018 director de la comunidad de Roma y desde 2017 es responsable del \u00e1rea de apostolados y secciones juveniles en el \u00e1rea de Vida y misi\u00f3n del Regnum Christi de la Direcci\u00f3n General de la Federaci\u00f3n Regnum Christi. Fue elegido segundo consejero general el 12 de febrero de 2020.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/fernando-rincon-gallardo-elguero\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/regnumchristi.org\\\/fernando-rincon-gallardo-elguero\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/fernando-rincon-gallardo-elguero\\\/#primaryimage\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/Fernando-rincon-e1599144264969.jpg\",\"contentUrl\":\"https:\\\/\\\/regnumchristi.org\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/Fernando-rincon-e1599144264969.jpg\",\"width\":900,\"height\":551},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/fernando-rincon-gallardo-elguero\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/regnumchristi.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fernando Rinc\u00f3n Gallardo Elguero\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#website\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/\",\"name\":\"Regnum Christi Internacional\",\"description\":\"El Regnum Christi es una realidad de la Iglesia cat\u00f3lica cuya misi\u00f3n es hacer presente el Reino de Cristo\",\"publisher\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/regnumchristi.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#organization\",\"name\":\"Regnum Christi Internacional\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/regnumchristi.es\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Favicon-RC_ligh-cuadrado.png\",\"contentUrl\":\"https:\\\/\\\/regnumchristi.es\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Favicon-RC_ligh-cuadrado.png\",\"width\":1080,\"height\":1080,\"caption\":\"Regnum Christi Internacional\"},\"image\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/RegnumChristiEspana\\\/\",\"https:\\\/\\\/x.com\\\/rc_espana\",\"https:\\\/\\\/www.instagram.com\\\/rc_espana\\\/\",\"https:\\\/\\\/es.linkedin.com\\\/company\\\/regnumchristiespaa\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#\\\/schema\\\/person\\\/73f2e414269cfbf8edecc2fd90af81f2\",\"name\":\"Autores varios\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/es\\\/author\\\/jarceocaesc-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fernando Rinc\u00f3n Gallardo Elguero - Regnum Christi Internacional","description":"Desde 2013 ha sido consejero general de los Laicos Consagrados del Regnum Christi, desde 2018 director de la comunidad de Roma y desde 2017 es responsable del \u00e1rea de apostolados y secciones juveniles en el \u00e1rea de Vida y misi\u00f3n del Regnum Christi de la Direcci\u00f3n General de la Federaci\u00f3n Regnum Christi. Fue elegido segundo consejero general el 12 de febrero de 2020.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/regnumchristi.org\/es\/fernando-rincon-gallardo-elguero\/","og_locale":"es_MX","og_type":"article","og_title":"Fernando Rinc\u00f3n Gallardo Elguero - Regnum Christi Internacional","og_description":"Desde 2013 ha sido consejero general de los Laicos Consagrados del Regnum Christi, desde 2018 director de la comunidad de Roma y desde 2017 es responsable del \u00e1rea de apostolados y secciones juveniles en el \u00e1rea de Vida y misi\u00f3n del Regnum Christi de la Direcci\u00f3n General de la Federaci\u00f3n Regnum Christi. Fue elegido segundo consejero general el 12 de febrero de 2020.","og_url":"https:\/\/regnumchristi.org\/es\/fernando-rincon-gallardo-elguero\/","og_site_name":"Regnum Christi Internacional","article_publisher":"https:\/\/www.facebook.com\/RegnumChristiEspana\/","article_published_time":"2020-07-03T14:42:24+00:00","article_modified_time":"2023-07-14T16:22:38+00:00","og_image":[{"width":900,"height":551,"url":"https:\/\/regnumchristi.org\/wp-content\/uploads\/2020\/09\/Fernando-rincon-e1599144264969.jpg","type":"image\/jpeg"}],"author":"Autores varios","twitter_misc":{"Escrito por":"Autores varios","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/regnumchristi.org\/fernando-rincon-gallardo-elguero\/#article","isPartOf":{"@id":"https:\/\/regnumchristi.org\/fernando-rincon-gallardo-elguero\/"},"author":{"name":"Autores varios","@id":"https:\/\/regnumchristi.org\/#\/schema\/person\/73f2e414269cfbf8edecc2fd90af81f2"},"headline":"Fernando Rinc\u00f3n Gallardo Elguero","datePublished":"2020-07-03T14:42:24+00:00","dateModified":"2023-07-14T16:22:38+00:00","mainEntityOfPage":{"@id":"https:\/\/regnumchristi.org\/fernando-rincon-gallardo-elguero\/"},"wordCount":154,"publisher":{"@id":"https:\/\/regnumchristi.org\/#organization"},"image":{"@id":"https:\/\/regnumchristi.org\/fernando-rincon-gallardo-elguero\/#primaryimage"},"thumbnailUrl":"https:\/\/regnumchristi.org\/wp-content\/uploads\/2020\/09\/Fernando-rincon-e1599144264969.jpg","keywords":["Laicos Consagrados del Regnum Christi"],"articleSection":["Noticias"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/regnumchristi.org\/fernando-rincon-gallardo-elguero\/","url":"https:\/\/regnumchristi.org\/fernando-rincon-gallardo-elguero\/","name":"Fernando Rinc\u00f3n Gallardo Elguero - Regnum Christi Internacional","isPartOf":{"@id":"https:\/\/regnumchristi.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/regnumchristi.org\/fernando-rincon-gallardo-elguero\/#primaryimage"},"image":{"@id":"https:\/\/regnumchristi.org\/fernando-rincon-gallardo-elguero\/#primaryimage"},"thumbnailUrl":"https:\/\/regnumchristi.org\/wp-content\/uploads\/2020\/09\/Fernando-rincon-e1599144264969.jpg","datePublished":"2020-07-03T14:42:24+00:00","dateModified":"2023-07-14T16:22:38+00:00","description":"Desde 2013 ha sido consejero general de los Laicos Consagrados del Regnum Christi, desde 2018 director de la comunidad de Roma y desde 2017 es responsable del \u00e1rea de apostolados y secciones juveniles en el \u00e1rea de Vida y misi\u00f3n del Regnum Christi de la Direcci\u00f3n General de la Federaci\u00f3n Regnum Christi. Fue elegido segundo consejero general el 12 de febrero de 2020.","breadcrumb":{"@id":"https:\/\/regnumchristi.org\/fernando-rincon-gallardo-elguero\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/regnumchristi.org\/fernando-rincon-gallardo-elguero\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/regnumchristi.org\/fernando-rincon-gallardo-elguero\/#primaryimage","url":"https:\/\/regnumchristi.org\/wp-content\/uploads\/2020\/09\/Fernando-rincon-e1599144264969.jpg","contentUrl":"https:\/\/regnumchristi.org\/wp-content\/uploads\/2020\/09\/Fernando-rincon-e1599144264969.jpg","width":900,"height":551},{"@type":"BreadcrumbList","@id":"https:\/\/regnumchristi.org\/fernando-rincon-gallardo-elguero\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/regnumchristi.org\/es\/"},{"@type":"ListItem","position":2,"name":"Fernando Rinc\u00f3n Gallardo Elguero"}]},{"@type":"WebSite","@id":"https:\/\/regnumchristi.org\/#website","url":"https:\/\/regnumchristi.org\/","name":"Regnum Christi Internacional","description":"El Regnum Christi es una realidad de la Iglesia cat\u00f3lica cuya misi\u00f3n es hacer presente el Reino de Cristo","publisher":{"@id":"https:\/\/regnumchristi.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/regnumchristi.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/regnumchristi.org\/#organization","name":"Regnum Christi Internacional","url":"https:\/\/regnumchristi.org\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/regnumchristi.org\/#\/schema\/logo\/image\/","url":"https:\/\/regnumchristi.es\/wp-content\/uploads\/2023\/03\/Favicon-RC_ligh-cuadrado.png","contentUrl":"https:\/\/regnumchristi.es\/wp-content\/uploads\/2023\/03\/Favicon-RC_ligh-cuadrado.png","width":1080,"height":1080,"caption":"Regnum Christi Internacional"},"image":{"@id":"https:\/\/regnumchristi.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/RegnumChristiEspana\/","https:\/\/x.com\/rc_espana","https:\/\/www.instagram.com\/rc_espana\/","https:\/\/es.linkedin.com\/company\/regnumchristiespaa"]},{"@type":"Person","@id":"https:\/\/regnumchristi.org\/#\/schema\/person\/73f2e414269cfbf8edecc2fd90af81f2","name":"Autores varios","url":"https:\/\/regnumchristi.org\/es\/author\/jarceocaesc-com\/"}]}},"_links":{"self":[{"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/posts\/27528","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/users\/49"}],"replies":[{"embeddable":true,"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/comments?post=27528"}],"version-history":[{"count":1,"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/posts\/27528\/revisions"}],"predecessor-version":[{"id":92817,"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/posts\/27528\/revisions\/92817"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/media\/27529"}],"wp:attachment":[{"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/media?parent=27528"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/categories?post=27528"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/tags?post=27528"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}