{"id":27842,"date":"2020-09-22T11:08:30","date_gmt":"2020-09-22T16:08:30","guid":{"rendered":"https:\/\/www.regnumchristi.org\/es\/?p=27842"},"modified":"2023-07-14T18:22:15","modified_gmt":"2023-07-14T16:22:15","slug":"julian-frommling-emite-votos-definitivos","status":"publish","type":"post","link":"https:\/\/regnumchristi.org\/es\/julian-frommling-emite-votos-definitivos\/","title":{"rendered":"\u00abLa gran alegr\u00eda de vivir el resto de mi vida perteneciendo a Jes\u00fas\u00bb \u2014 Julian Frommling emite votos definitivos"},"content":{"rendered":"<p>Julian Frommling ha emitido el domingo, 13 de septiembre, sus votos definitivos como <a href=\"https:\/\/consagradasrc.org\/\" target=\"_blank\" rel=\"noopener noreferrer\">consagrada del Regnum Christi<\/a>. La ceremonia ha tenido lugar en la parroquia Santa Mar\u00eda de Can\u00e1, en Pozuelo, y Julian ha estado acompa\u00f1ada online por su familia, y rodeada de miembros del Regnum Christi, y compa\u00f1eros y profesores de la Universidad de San D\u00e1maso, donde estudia 4\u00ba de Teolog\u00eda. Julian tiene 26 a\u00f1os, y explica que siente \u201cmucha gratitud por haber sido llamada a esta vocaci\u00f3n, y la gran alegr\u00eda de poder vivir el resto de mi vida perteneciendo a Jes\u00fas\u201d. Se reconoce ilusionada ante esta nueva aventura: \u201cEs un regalo de Dios que solamente podr\u00e9 entender en el cielo\u201d, contaba en una entrevista a pocas horas de la ceremonia.<\/p>\n<h4>\u201cUn gran regalo que me ha renovado la esperanza, la alegr\u00eda en esta vocaci\u00f3n que compartimos\u201d<strong><br \/>\n<\/strong><\/h4>\n<p>Ha sido Betty Rivera, Directora Territorial de las Consagradas en Espa\u00f1a y miembro del Colegio Directivo territorial del Regnum Christi, a quien le corresponde recibir los votos de Julian en presencia de toda la asamblea durante la misa: \u201cEs un regalo inmenso recibir los votos de una hermana a la que me toc\u00f3 conocer cuando era peque\u00f1a, y haberla acompa\u00f1ado un poco de lejos en su trayectoria\u201d, explic\u00f3 Betty en entrevista. \u201cEs emocionante ver la respuesta generosa de Julian que ratifica su s\u00ed al Se\u00f1or dando su vida entera para amarlo y para que otros conozcan el amor de Dios\u201d, reconoc\u00eda Betty. \u201cRecibir sus votos hoy en nombre de las Consagradas del Regnum Christi, en el servicio de autoridad que me toca en estos a\u00f1os, ha sido un gran regalo que me ha renovado la esperanza, la alegr\u00eda en esta vocaci\u00f3n que compartimos\u201d, ha asegurado. \u201cEstamos muy orgullosos de Julian\u201d, les dec\u00eda a sus padres \u201ces realmente un regalo para todos nosotros, para esta familia espiritual\u201d, les aseguraba al saludarles en la retransmisi\u00f3n online.<\/p>\n<p>Betty tambi\u00e9n explic\u00f3 en entrevista que conoci\u00f3 a Julian en sexto de primaria, cuando era miembro del <a href=\"https:\/\/www.ecyd.org\/\" target=\"_blank\" rel=\"noopener noreferrer\">ECYD<\/a>. Ya entonces era una ni\u00f1a \u201csumamente alegre, entusiasta, abierta y accesible\u201d. Y ahora \u201cme parece precioso pensar en su recorrido de todos estos a\u00f1os de discernimiento, verificaci\u00f3n vocacional y confirmaci\u00f3n vocacional\u201d, y mas siendo testigo \u201cde que sigue con la misma alegr\u00eda y frescura pero ahora con una profundidad m\u00e1s honda y enraizamiento en Dios\u201d.<\/p>\n<h4>\u201cQue la Iglesia hoy crezca en santidad en lo que tiene de humana porque Julian escoge vivir para siempre para su divino esposo\u201d.<\/h4>\n<p>La misa estuvo presidida por el P. Javier Cereceda, Director Territorial de los <a href=\"https:\/\/legionariosdecristo.org\/\" target=\"_blank\" rel=\"noopener noreferrer\">Legionarios de Cristo<\/a>: \u201cCelebramos que Julian hoy le dice al Se\u00f1or \u2018Aqu\u00ed estoy, vengo porque me has llamado\u2019. No es la primera vez que lo dices, pero hoy lo dices de forma definitiva\u201d, destac\u00f3 el P. Javier. \u201cA lo largo de estos a\u00f1os has querido ser cada d\u00eda m\u00e1s de Dios. Le has querido conocer m\u00e1s, y descubrir poco a poco qu\u00e9 es lo que Cristo, que es quien nos llama, quiere de ti\u201d.<\/p>\n<p>El Director Territorial de los Legionarios de Cristo, y miembro del Colegio Directivo Territorial del Regnum Christi, subray\u00f3 algo importante para Julian, como ella misma quiso compartir en sus palabras de agradecimiento al final de la misa: el deseo de que con su vida y su entrega, \u201cla Iglesia hoy crezca en santidad en lo que tiene de parte humana, porque Julian escoge hoy vivir para siempre para su amado, su divino esposo, que le ha llamado, al que le responde: \u2018aqu\u00ed estoy, cuenta conmigo para que las personas encuentran el amor que les quieres ofrecer, Se\u00f1or\u2019\u201d.<\/p>\n<p>El P. Javier Cereceda pidi\u00f3 a toda la familia del Regnum Christi que le ayude a Julian a \u201cvivir fiel\u201d y que \u201cel amor de Cristo llegue a todas las personas que \u00c9l quiera a trav\u00e9s de este carisma que nos ha dado al Regnum Christi\u201d, concluy\u00f3.<\/p>\n<h4>La emisi\u00f3n de votos definitivos es \u201cllegar a vivir este d\u00eda como quieres seguir viviendo toda la vida\u201d.<\/h4>\n<p>Al final de la misa, Julian dirigi\u00f3 unas palabras para agradecer a todos los miembros del Regnum Christi su presencia. Quiso recordar que hace un a\u00f1o, tras los ejercicios espirituales en los que decidi\u00f3 prepararse para solicitar la emisi\u00f3n de los votos definitivos, fue justamente el P. Javier Cereceda quien le dijo algo que le marc\u00f3: \u201cPrepararse para los votos no es prepararse para vivir un d\u00eda, sino empezar a vivir ya como quieres llegar a vivir ese d\u00eda de tal manera que, cuando llegues a ese d\u00eda, quieras seguir viviendo toda la vida as\u00ed\u201d.<\/p>\n<p>Tambi\u00e9n ha tenido unas palabras entra\u00f1ables para su familia, de Ohio (EE.UU), que ha participado a trav\u00e9s de la retransmisi\u00f3n online por Youtube y Facebook: \u201cAunque haya distancia f\u00edsica est\u00e1is aqu\u00ed mismo en mi coraz\u00f3n\u201d, asegur\u00f3 Julian.<\/p>\n<h4>La comunidad, \u201cayuda para seguir al Se\u00f1or\u201d, y \u201cbuscar desde Su coraz\u00f3n transmitir Su amor\u201d.<\/h4>\n<p>Tras la emisi\u00f3n de sus votos definitivos, se abre a partir de ahora para Julian la dedicaci\u00f3n completa al apostolado con \u201cel testimonio y anuncio del amor misericordioso de Cristo a todos los hombres, desde su maternidad espiritual, con alma ardiente de ap\u00f3stol\u201d, como apuntan las Constituciones (4.2).<\/p>\n<p>\u201cLa comunidad es un regalo para que juntas podamos estimularnos y ayudarnos en la vivencia de nuestra vocaci\u00f3n\u201d, explicaba Betty a la salida de la ceremonia. \u201cMe da gusto que en su comunidad, Julian tiene grandes amigas a las que va a poder acompa\u00f1ar y de las que se va a dejar acompa\u00f1ar para que cada d\u00eda puedan seguir m\u00e1s de cerca a nuestro Se\u00f1or, y buscar desde Su coraz\u00f3n transmitir Su amor a todas las personas con las que se encuentren\u201d.<\/p>\n<h4>\u201cLos diferentes carismas reflejan el rostro mismo de la Iglesia\u201d.<\/h4>\n<p>Estaba entre los participantes \u00c1frica Pem\u00e1n, actual consejera general, encargada a nivel internacional de las etapas de formaci\u00f3n inicial de las Consagradas: \u201cEs muy bonito ver los lazos, el \u00a0hecho de que se genera de verdaderamente una familia con otros carismas, con los seminaristas; que hay un aprecio mutuo que no es solo una cuesti\u00f3n humana, sino que es el reflejo de la Iglesia donde los diferentes carismas reflejan el rostro mismo de la Iglesia. Es muy sencillo y muy profundo\u201d, manifestaba \u00c1frica ante la presencia en la ceremonia de los compa\u00f1eros de clase y profesores de Julian en la facultad de teolog\u00eda de San D\u00e1maso.<\/p>\n<h4>\u201cLe digo a Julian que permanezca en la indigencia, siendo peque\u00f1a delante de Dios\u201d.<\/h4>\n<p>Uno de los sacerdotes amigos de Julian presentes en la ceremonia fue el P. Roberto Gonz\u00e1lez Tapia, formador del proped\u00e9utico en el seminario diocesano de Madrid. \u201cCada vez que una mujer se consagra a Dios es testimonio de que Jesucristo merece la pena y merece la pena darle todo el coraz\u00f3n, no solamente algo\u201d, comentaba a la salida en una entrevista, \u201cy a Julian le digo que permanezca en la indigencia, siendo peque\u00f1a delante de Dios, porque al final es testimonio para todos nosotros de que Dios es verdaderamente Padre, Jesucristo es Salvador y el Esp\u00edritu Santo es vida. Gracias al Regnum Christi por seguir siendo presencia de Dios en el mundo\u201d, afirm\u00f3.<\/p>\n<h4>\u201cEl Se\u00f1or lo vale todo\u201d<\/h4>\n<p>Las\u00a0<em>Constituciones de las Consagradas del Regnum Christi<\/em>\u00a0indican que su fin es \u201cla santificaci\u00f3n personal y la extensi\u00f3n del Reino de Cristo en el coraz\u00f3n de cada persona y en la sociedad aportando, especialmente, la propia consagraci\u00f3n laical\u201d (n. 4). Por eso Julian ha se\u00f1alado que quiere, por medio de la gracia de Dios, \u201cconstruir y aportar a la santidad de la Iglesia\u201d con la suya propia. Tambi\u00e9n ha explicado que esta decisi\u00f3n de dar su vida que no le ha resultado dif\u00edcil: \u201cNo cuesta decir \u2018s\u00ed\u2019 al Se\u00f1or, porque \u00c9l lo vale todo\u201d.<\/p>\n<div class=\"ast-oembed-container \" style=\"height: 100%;\"><iframe title=\"\ud83d\udd06 Votos definitivos de Julian Frommling | #RCenSalida #familiaRC #consagradasRC\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/1b94ful0hGo?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n<h5><em>Fuente: <a href=\"https:\/\/regnumchristi.es\/\" target=\"_blank\" rel=\"noopener noreferrer\">RegnumChristi.Es<\/a><\/em><\/h5>\n","protected":false},"excerpt":{"rendered":"<p> [&hellip;]<\/p>\n","protected":false},"author":49,"featured_media":27844,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"_daextrevop_audio_file_creation_date":"","_daextrevop_text_to_speech":"","_daextrevop_document_type":"","footnotes":""},"categories":[3031,1687],"tags":[90,124,499],"class_list":["post-27842","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-destacadas","category-noticias","tag-consagradas-del-regnum-christi","tag-vocacion","tag-votos-definitivos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Julian Frommling emite los votos definitivos con las consagradas RC<\/title>\n<meta name=\"description\" content=\"Tras la emisi\u00f3n de sus votos definitivos, en Espa\u00f1a, se abre a partir de ahora para Julian la dedicaci\u00f3n completa al apostolado.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/regnumchristi.org\/es\/julian-frommling-emite-votos-definitivos\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Julian Frommling emite los votos definitivos con las consagradas RC\" \/>\n<meta property=\"og:description\" content=\"Tras la emisi\u00f3n de sus votos definitivos, en Espa\u00f1a, se abre a partir de ahora para Julian la dedicaci\u00f3n completa al apostolado.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/regnumchristi.org\/es\/julian-frommling-emite-votos-definitivos\/\" \/>\n<meta property=\"og:site_name\" content=\"Regnum Christi Internacional\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/RegnumChristiEspana\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-09-22T16:08:30+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-07-14T16:22:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/regnumchristi.org\/wp-content\/uploads\/2020\/09\/Julianvotosdefinitivos.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Autores varios\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Autores varios\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/julian-frommling-emite-votos-definitivos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/julian-frommling-emite-votos-definitivos\\\/\"},\"author\":{\"name\":\"Autores varios\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#\\\/schema\\\/person\\\/73f2e414269cfbf8edecc2fd90af81f2\"},\"headline\":\"\u00abLa gran alegr\u00eda de vivir el resto de mi vida perteneciendo a Jes\u00fas\u00bb \u2014 Julian Frommling emite votos definitivos\",\"datePublished\":\"2020-09-22T16:08:30+00:00\",\"dateModified\":\"2023-07-14T16:22:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/julian-frommling-emite-votos-definitivos\\\/\"},\"wordCount\":1386,\"publisher\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/julian-frommling-emite-votos-definitivos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/regnumchristi.org\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/Julianvotosdefinitivos.jpg\",\"keywords\":[\"Consagradas del Regnum Christi\",\"vocaci\u00f3n\",\"votos definitivos\"],\"articleSection\":[\"Destacadas\",\"Noticias\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/julian-frommling-emite-votos-definitivos\\\/\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/julian-frommling-emite-votos-definitivos\\\/\",\"name\":\"Julian Frommling emite los votos definitivos con las consagradas RC\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/julian-frommling-emite-votos-definitivos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/julian-frommling-emite-votos-definitivos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/regnumchristi.org\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/Julianvotosdefinitivos.jpg\",\"datePublished\":\"2020-09-22T16:08:30+00:00\",\"dateModified\":\"2023-07-14T16:22:15+00:00\",\"description\":\"Tras la emisi\u00f3n de sus votos definitivos, en Espa\u00f1a, se abre a partir de ahora para Julian la dedicaci\u00f3n completa al apostolado.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/julian-frommling-emite-votos-definitivos\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/regnumchristi.org\\\/julian-frommling-emite-votos-definitivos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/julian-frommling-emite-votos-definitivos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/Julianvotosdefinitivos.jpg\",\"contentUrl\":\"https:\\\/\\\/regnumchristi.org\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/Julianvotosdefinitivos.jpg\",\"width\":1200,\"height\":800,\"caption\":\"Julian Frommling emite votos definitivos\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/julian-frommling-emite-votos-definitivos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/regnumchristi.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00abLa gran alegr\u00eda de vivir el resto de mi vida perteneciendo a Jes\u00fas\u00bb \u2014 Julian Frommling emite votos definitivos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#website\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/\",\"name\":\"Regnum Christi Internacional\",\"description\":\"El Regnum Christi es una realidad de la Iglesia cat\u00f3lica cuya misi\u00f3n es hacer presente el Reino de Cristo\",\"publisher\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/regnumchristi.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#organization\",\"name\":\"Regnum Christi Internacional\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/regnumchristi.es\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Favicon-RC_ligh-cuadrado.png\",\"contentUrl\":\"https:\\\/\\\/regnumchristi.es\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Favicon-RC_ligh-cuadrado.png\",\"width\":1080,\"height\":1080,\"caption\":\"Regnum Christi Internacional\"},\"image\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/RegnumChristiEspana\\\/\",\"https:\\\/\\\/x.com\\\/rc_espana\",\"https:\\\/\\\/www.instagram.com\\\/rc_espana\\\/\",\"https:\\\/\\\/es.linkedin.com\\\/company\\\/regnumchristiespaa\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#\\\/schema\\\/person\\\/73f2e414269cfbf8edecc2fd90af81f2\",\"name\":\"Autores varios\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/es\\\/author\\\/jarceocaesc-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Julian Frommling emite los votos definitivos con las consagradas RC","description":"Tras la emisi\u00f3n de sus votos definitivos, en Espa\u00f1a, se abre a partir de ahora para Julian la dedicaci\u00f3n completa al apostolado.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/regnumchristi.org\/es\/julian-frommling-emite-votos-definitivos\/","og_locale":"es_MX","og_type":"article","og_title":"Julian Frommling emite los votos definitivos con las consagradas RC","og_description":"Tras la emisi\u00f3n de sus votos definitivos, en Espa\u00f1a, se abre a partir de ahora para Julian la dedicaci\u00f3n completa al apostolado.","og_url":"https:\/\/regnumchristi.org\/es\/julian-frommling-emite-votos-definitivos\/","og_site_name":"Regnum Christi Internacional","article_publisher":"https:\/\/www.facebook.com\/RegnumChristiEspana\/","article_published_time":"2020-09-22T16:08:30+00:00","article_modified_time":"2023-07-14T16:22:15+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/regnumchristi.org\/wp-content\/uploads\/2020\/09\/Julianvotosdefinitivos.jpg","type":"image\/jpeg"}],"author":"Autores varios","twitter_misc":{"Escrito por":"Autores varios","Tiempo de lectura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/regnumchristi.org\/julian-frommling-emite-votos-definitivos\/#article","isPartOf":{"@id":"https:\/\/regnumchristi.org\/julian-frommling-emite-votos-definitivos\/"},"author":{"name":"Autores varios","@id":"https:\/\/regnumchristi.org\/#\/schema\/person\/73f2e414269cfbf8edecc2fd90af81f2"},"headline":"\u00abLa gran alegr\u00eda de vivir el resto de mi vida perteneciendo a Jes\u00fas\u00bb \u2014 Julian Frommling emite votos definitivos","datePublished":"2020-09-22T16:08:30+00:00","dateModified":"2023-07-14T16:22:15+00:00","mainEntityOfPage":{"@id":"https:\/\/regnumchristi.org\/julian-frommling-emite-votos-definitivos\/"},"wordCount":1386,"publisher":{"@id":"https:\/\/regnumchristi.org\/#organization"},"image":{"@id":"https:\/\/regnumchristi.org\/julian-frommling-emite-votos-definitivos\/#primaryimage"},"thumbnailUrl":"https:\/\/regnumchristi.org\/wp-content\/uploads\/2020\/09\/Julianvotosdefinitivos.jpg","keywords":["Consagradas del Regnum Christi","vocaci\u00f3n","votos definitivos"],"articleSection":["Destacadas","Noticias"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/regnumchristi.org\/julian-frommling-emite-votos-definitivos\/","url":"https:\/\/regnumchristi.org\/julian-frommling-emite-votos-definitivos\/","name":"Julian Frommling emite los votos definitivos con las consagradas RC","isPartOf":{"@id":"https:\/\/regnumchristi.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/regnumchristi.org\/julian-frommling-emite-votos-definitivos\/#primaryimage"},"image":{"@id":"https:\/\/regnumchristi.org\/julian-frommling-emite-votos-definitivos\/#primaryimage"},"thumbnailUrl":"https:\/\/regnumchristi.org\/wp-content\/uploads\/2020\/09\/Julianvotosdefinitivos.jpg","datePublished":"2020-09-22T16:08:30+00:00","dateModified":"2023-07-14T16:22:15+00:00","description":"Tras la emisi\u00f3n de sus votos definitivos, en Espa\u00f1a, se abre a partir de ahora para Julian la dedicaci\u00f3n completa al apostolado.","breadcrumb":{"@id":"https:\/\/regnumchristi.org\/julian-frommling-emite-votos-definitivos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/regnumchristi.org\/julian-frommling-emite-votos-definitivos\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/regnumchristi.org\/julian-frommling-emite-votos-definitivos\/#primaryimage","url":"https:\/\/regnumchristi.org\/wp-content\/uploads\/2020\/09\/Julianvotosdefinitivos.jpg","contentUrl":"https:\/\/regnumchristi.org\/wp-content\/uploads\/2020\/09\/Julianvotosdefinitivos.jpg","width":1200,"height":800,"caption":"Julian Frommling emite votos definitivos"},{"@type":"BreadcrumbList","@id":"https:\/\/regnumchristi.org\/julian-frommling-emite-votos-definitivos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/regnumchristi.org\/es\/"},{"@type":"ListItem","position":2,"name":"\u00abLa gran alegr\u00eda de vivir el resto de mi vida perteneciendo a Jes\u00fas\u00bb \u2014 Julian Frommling emite votos definitivos"}]},{"@type":"WebSite","@id":"https:\/\/regnumchristi.org\/#website","url":"https:\/\/regnumchristi.org\/","name":"Regnum Christi Internacional","description":"El Regnum Christi es una realidad de la Iglesia cat\u00f3lica cuya misi\u00f3n es hacer presente el Reino de Cristo","publisher":{"@id":"https:\/\/regnumchristi.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/regnumchristi.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/regnumchristi.org\/#organization","name":"Regnum Christi Internacional","url":"https:\/\/regnumchristi.org\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/regnumchristi.org\/#\/schema\/logo\/image\/","url":"https:\/\/regnumchristi.es\/wp-content\/uploads\/2023\/03\/Favicon-RC_ligh-cuadrado.png","contentUrl":"https:\/\/regnumchristi.es\/wp-content\/uploads\/2023\/03\/Favicon-RC_ligh-cuadrado.png","width":1080,"height":1080,"caption":"Regnum Christi Internacional"},"image":{"@id":"https:\/\/regnumchristi.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/RegnumChristiEspana\/","https:\/\/x.com\/rc_espana","https:\/\/www.instagram.com\/rc_espana\/","https:\/\/es.linkedin.com\/company\/regnumchristiespaa"]},{"@type":"Person","@id":"https:\/\/regnumchristi.org\/#\/schema\/person\/73f2e414269cfbf8edecc2fd90af81f2","name":"Autores varios","url":"https:\/\/regnumchristi.org\/es\/author\/jarceocaesc-com\/"}]}},"_links":{"self":[{"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/posts\/27842","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/users\/49"}],"replies":[{"embeddable":true,"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/comments?post=27842"}],"version-history":[{"count":1,"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/posts\/27842\/revisions"}],"predecessor-version":[{"id":92796,"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/posts\/27842\/revisions\/92796"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/media\/27844"}],"wp:attachment":[{"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/media?parent=27842"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/categories?post=27842"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/tags?post=27842"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}