{"id":28972,"date":"2021-01-15T17:30:23","date_gmt":"2021-01-15T23:30:23","guid":{"rendered":"https:\/\/www.regnumchristi.org\/es\/?p=28972"},"modified":"2023-08-02T14:00:15","modified_gmt":"2023-08-02T20:00:15","slug":"sabado-16-de-enero-de-2021-cristo-nos-llama","status":"publish","type":"post","link":"https:\/\/regnumchristi.org\/es\/sabado-16-de-enero-de-2021-cristo-nos-llama\/","title":{"rendered":"S\u00e1bado 16 de enero de 2021 &#8211; Cristo nos llama"},"content":{"rendered":"<p>H. Erick Flores Ar\u00e9chiga, L.C.<\/p>\n<p>&nbsp;<\/p>\n<p>En el nombre del Padre y del Hijo y del Esp\u00edritu Santo. Am\u00e9n.<\/p>\n<p>Cristo, Rey nuestro. \u00a1Venga tu Reino!<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>Oraci\u00f3n preparatoria <\/strong><em>(para ponerme en presencia de Dios)<\/em><\/p>\n<p>Me pongo en tu presencia, Se\u00f1or, pues te necesito. Que la oraci\u00f3n sea un tiempo para ver tu acci\u00f3n en mi vida, contemplando tus misterios desde la manera en que ves mi existencia, como muestra de amor para m\u00ed y para el mundo. Y verme como una obra de tus manos y que me haces un don para los demas.<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>Evangelio del d\u00eda <\/strong><em>(para orientar tu meditaci\u00f3n)<\/em><\/p>\n<p>Del santo Evangelio seg\u00fan san Marcos 2, 13-17<\/p>\n<p>En aquel tiempo, Jes\u00fas sali\u00f3 de nuevo a caminar por la orilla del lago; toda la muchedumbre lo segu\u00eda y \u00e9l les hablaba. Al pasar, vio a Lev\u00ed (Mateo), el hijo de Alfeo, sentado en el banco de los impuestos, y le dijo: \u201cS\u00edgueme\u201d. El se levant\u00f3 y lo sigui\u00f3.<\/p>\n<p>Mientras Jes\u00fas estaba a la mesa en casa de Lev\u00ed, muchos publicanos y pecadores se sentaron a la mesa junto con Jes\u00fas y sus disc\u00edpulos, porque eran muchos los que lo segu\u00edan. Entonces unos escribas de la secta de los fariseos, vi\u00e9ndolo comer con los pecadores y publicanos, preguntaron a sus disc\u00edpulos: \u201c\u00bfPor qu\u00e9 su maestro come y bebe en compa\u00f1\u00eda de publicanos y pecadores?\u201d<\/p>\n<p>Habiendo o\u00eddo esto, Jes\u00fas les dijo: \u201cNo son los sanos los que tienen necesidad del m\u00e9dico, sino los enfermos. Yo no he venido para llamar a los justos, sino a los pecadores\u201d.<\/p>\n<p>Palabra del Se\u00f1or.<\/p>\n<p><em>\u00a0<\/em><\/p>\n<p><strong>Medita lo que Dios te dice en el Evangelio<\/strong><\/p>\n<p>Cristo quiere salvarnos a todos y lo hace llam\u00e1ndonos por nuestro nombre. Es asombroso el llamado que Cristo hace a cada uno, pues de estar con la muchedumbre, tal vez los 5000 que di\u00f3 de comer, se fija en nosotros. De estar con muchos pasa a vernos, inclusive quiere compartir la mesa, signo de confianza, cercan\u00eda, respeto y amor. Nuestro Se\u00f1or tiene un gran deseo de cada uno de nosotros.<\/p>\n<p>Jesucrito conoce nuestro interior, sabe que somos pecadores y nuestra debilidad se vuelve un est\u00edmulo potente para el coraz\u00f3n misericordioso de Hijo amado. Cristo sabe que tiene la palabra y el poder para sanar nuestra alma sucia y herida y, tambi\u00e9n, los que est\u00e1n en la mesa con Lev\u00ed lo saben, pues dicen: \u00ab\u00bfPor qu\u00e9 su maestro come y bebe en compa\u00f1\u00eda de publicanos y pecadores? \u00bb \u00bfCu\u00e1ntas veces nuestro juicio se vuelve una espada que lastima al hermano, amigo, pariente, pareja o hermano?<\/p>\n<p>Cristo con amor aut\u00e9ntico, fiel y respetuoso dice \u00abNo son los sanos los que tienen necesidad del m\u00e9dico, sino los enfermos. Yo no he venido para llamar a los justos, sino a los pecadores\u00bb. Son palabras que revelan parte de su misi\u00f3n como salvador. Cristo sabe que todos en la muchedumbre son enfermos y pecadores, pero tambi\u00e9n sabe que el camino de la verdadera conversi\u00f3n en un proceso personal y de toda una vida en relaci\u00f3n de pecador y salvador.<\/p>\n<p>As\u00ed pues, dejemos que caiga el edificio de nuestro ser ego\u00edsta y soberbio, quien se cree autosuficiente. Dejemos que Dios mueva nuestras vidas, revel\u00e1ndonos qui\u00e9nes somos y qui\u00e9n es \u00c9l, Cristo misericordioso, quien nos llama a ser misericordiosos como el Padre es misericordioso.<\/p>\n<p>&nbsp;<\/p>\n<p>\u00abJes\u00fas escogi\u00f3 a un ap\u00f3stol entre aquella gente, la peor. A continuaci\u00f3n, este Mateo, invitado a comer, estaba alegre. Antes, cuando me alojaba en Via della Scrofa, me gustaba ir, ahora no puedo, a San Luis de los Franceses para ver el cuadro de Caravaggio, La conversi\u00f3n de Mateo: \u00e9l agarrado al dinero as\u00ed [hace el gesto] y Jes\u00fas lo indica con el dedo. Se aferraba al dinero. Y Jes\u00fas lo escoge. Invita a toda la banda a almorzar, a los traidores, los cobradores de impuestos. Al ver esto, los fariseos que se cre\u00edan justos, que juzgaban a todos y dec\u00edan: \u201cPero \u00bfpor qu\u00e9 vuestro Maestro tiene esa compa\u00f1\u00eda?\u201d. Jes\u00fas dice: \u201cNo he venido a llamar a justos, sino a pecadores\u201d. Esto me consuela mucho, porque creo que Jes\u00fas ha venido por m\u00ed. Porque todos somos pecadores. Todos. Todos tenemos esta \u201clicenciatura\u201d, somos licenciados. Cada uno sabe cu\u00e1l es su pecado, su debilidad m\u00e1s fuerte.\u00bb<\/p>\n<p>(Homil\u00eda de S.S. Francisco, 7 de julio de 2017).<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>Di\u00e1logo con Cristo<\/strong><\/p>\n<p><em>\u00c9sta es la parte m\u00e1s importante de tu oraci\u00f3n, disponte a platicar con mucho amor con Aquel que te ama.<\/em><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>Prop\u00f3sito<\/strong><\/p>\n<p><em>Proponte uno personal. El que m\u00e1s amor implique en respuesta al Amado\u2026 o, si crees que es lo que Dios te pide, vive lo que se te sugiere a continuaci\u00f3n.<\/em><\/p>\n<p>Rezar un padre nuestro en cada comida, recordando que Cristo se sento en la mesa junto a los pecadores y publicanos.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Despedida<\/strong><\/p>\n<p>Te damos gracias, Se\u00f1or, por todos tus beneficios, a Ti que vives y reinas por los siglos de los siglos.<\/p>\n<p>Am\u00e9n.<\/p>\n<p>&nbsp;<\/p>\n<p>\u00a1Cristo, Rey nuestro!<\/p>\n<p>\u00a1Venga tu Reino!<\/p>\n<p>&nbsp;<\/p>\n<p>Virgen prudent\u00edsima, Mar\u00eda, Madre de la Iglesia.<\/p>\n<p>Ruega por nosotros.<\/p>\n<p>&nbsp;<\/p>\n<p>En el nombre del Padre y del Hijo y del Esp\u00edritu Santo. Am\u00e9n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p> [&hellip;]<\/p>\n","protected":false},"author":58,"featured_media":28984,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"_daextrevop_audio_file_creation_date":"","_daextrevop_text_to_speech":"","_daextrevop_document_type":"","footnotes":""},"categories":[3164],"tags":[],"class_list":["post-28972","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-meditacion-del-dia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>S\u00e1bado 16 de enero de 2021 - Cristo nos llama - Regnum Christi Internacional<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/regnumchristi.org\/es\/sabado-16-de-enero-de-2021-cristo-nos-llama\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"S\u00e1bado 16 de enero de 2021 - Cristo nos llama - Regnum Christi Internacional\" \/>\n<meta property=\"og:description\" content=\"[&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/regnumchristi.org\/es\/sabado-16-de-enero-de-2021-cristo-nos-llama\/\" \/>\n<meta property=\"og:site_name\" content=\"Regnum Christi Internacional\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/RegnumChristiEspana\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-01-15T23:30:23+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-08-02T20:00:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/regnumchristi.org\/wp-content\/uploads\/2021\/01\/160121.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"628\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Meditaciones Diarias\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Meditaciones Diarias\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/sabado-16-de-enero-de-2021-cristo-nos-llama\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/sabado-16-de-enero-de-2021-cristo-nos-llama\\\/\"},\"author\":{\"name\":\"Meditaciones Diarias\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#\\\/schema\\\/person\\\/a5ad8b3c4bd3cb3a0abe8a1474fe8f0a\"},\"headline\":\"S\u00e1bado 16 de enero de 2021 &#8211; Cristo nos llama\",\"datePublished\":\"2021-01-15T23:30:23+00:00\",\"dateModified\":\"2023-08-02T20:00:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/sabado-16-de-enero-de-2021-cristo-nos-llama\\\/\"},\"wordCount\":914,\"publisher\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/sabado-16-de-enero-de-2021-cristo-nos-llama\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/regnumchristi.org\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/160121.jpg\",\"articleSection\":[\"Meditaci\u00f3n del d\u00eda\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/sabado-16-de-enero-de-2021-cristo-nos-llama\\\/\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/sabado-16-de-enero-de-2021-cristo-nos-llama\\\/\",\"name\":\"S\u00e1bado 16 de enero de 2021 - Cristo nos llama - Regnum Christi Internacional\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/sabado-16-de-enero-de-2021-cristo-nos-llama\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/sabado-16-de-enero-de-2021-cristo-nos-llama\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/regnumchristi.org\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/160121.jpg\",\"datePublished\":\"2021-01-15T23:30:23+00:00\",\"dateModified\":\"2023-08-02T20:00:15+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/sabado-16-de-enero-de-2021-cristo-nos-llama\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/regnumchristi.org\\\/sabado-16-de-enero-de-2021-cristo-nos-llama\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/sabado-16-de-enero-de-2021-cristo-nos-llama\\\/#primaryimage\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/160121.jpg\",\"contentUrl\":\"https:\\\/\\\/regnumchristi.org\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/160121.jpg\",\"width\":1200,\"height\":628,\"caption\":\"mueva nuestras vidas\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/sabado-16-de-enero-de-2021-cristo-nos-llama\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/regnumchristi.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"S\u00e1bado 16 de enero de 2021 &#8211; Cristo nos llama\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#website\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/\",\"name\":\"Regnum Christi Internacional\",\"description\":\"El Regnum Christi es una realidad de la Iglesia cat\u00f3lica cuya misi\u00f3n es hacer presente el Reino de Cristo\",\"publisher\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/regnumchristi.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#organization\",\"name\":\"Regnum Christi Internacional\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/regnumchristi.es\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Favicon-RC_ligh-cuadrado.png\",\"contentUrl\":\"https:\\\/\\\/regnumchristi.es\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Favicon-RC_ligh-cuadrado.png\",\"width\":1080,\"height\":1080,\"caption\":\"Regnum Christi Internacional\"},\"image\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/RegnumChristiEspana\\\/\",\"https:\\\/\\\/x.com\\\/rc_espana\",\"https:\\\/\\\/www.instagram.com\\\/rc_espana\\\/\",\"https:\\\/\\\/es.linkedin.com\\\/company\\\/regnumchristiespaa\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#\\\/schema\\\/person\\\/a5ad8b3c4bd3cb3a0abe8a1474fe8f0a\",\"name\":\"Meditaciones Diarias\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/es\\\/author\\\/meditacionesd\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"S\u00e1bado 16 de enero de 2021 - Cristo nos llama - Regnum Christi Internacional","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/regnumchristi.org\/es\/sabado-16-de-enero-de-2021-cristo-nos-llama\/","og_locale":"es_MX","og_type":"article","og_title":"S\u00e1bado 16 de enero de 2021 - Cristo nos llama - Regnum Christi Internacional","og_description":"[&hellip;]","og_url":"https:\/\/regnumchristi.org\/es\/sabado-16-de-enero-de-2021-cristo-nos-llama\/","og_site_name":"Regnum Christi Internacional","article_publisher":"https:\/\/www.facebook.com\/RegnumChristiEspana\/","article_published_time":"2021-01-15T23:30:23+00:00","article_modified_time":"2023-08-02T20:00:15+00:00","og_image":[{"width":1200,"height":628,"url":"https:\/\/regnumchristi.org\/wp-content\/uploads\/2021\/01\/160121.jpg","type":"image\/jpeg"}],"author":"Meditaciones Diarias","twitter_misc":{"Escrito por":"Meditaciones Diarias","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/regnumchristi.org\/sabado-16-de-enero-de-2021-cristo-nos-llama\/#article","isPartOf":{"@id":"https:\/\/regnumchristi.org\/sabado-16-de-enero-de-2021-cristo-nos-llama\/"},"author":{"name":"Meditaciones Diarias","@id":"https:\/\/regnumchristi.org\/#\/schema\/person\/a5ad8b3c4bd3cb3a0abe8a1474fe8f0a"},"headline":"S\u00e1bado 16 de enero de 2021 &#8211; Cristo nos llama","datePublished":"2021-01-15T23:30:23+00:00","dateModified":"2023-08-02T20:00:15+00:00","mainEntityOfPage":{"@id":"https:\/\/regnumchristi.org\/sabado-16-de-enero-de-2021-cristo-nos-llama\/"},"wordCount":914,"publisher":{"@id":"https:\/\/regnumchristi.org\/#organization"},"image":{"@id":"https:\/\/regnumchristi.org\/sabado-16-de-enero-de-2021-cristo-nos-llama\/#primaryimage"},"thumbnailUrl":"https:\/\/regnumchristi.org\/wp-content\/uploads\/2021\/01\/160121.jpg","articleSection":["Meditaci\u00f3n del d\u00eda"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/regnumchristi.org\/sabado-16-de-enero-de-2021-cristo-nos-llama\/","url":"https:\/\/regnumchristi.org\/sabado-16-de-enero-de-2021-cristo-nos-llama\/","name":"S\u00e1bado 16 de enero de 2021 - Cristo nos llama - Regnum Christi Internacional","isPartOf":{"@id":"https:\/\/regnumchristi.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/regnumchristi.org\/sabado-16-de-enero-de-2021-cristo-nos-llama\/#primaryimage"},"image":{"@id":"https:\/\/regnumchristi.org\/sabado-16-de-enero-de-2021-cristo-nos-llama\/#primaryimage"},"thumbnailUrl":"https:\/\/regnumchristi.org\/wp-content\/uploads\/2021\/01\/160121.jpg","datePublished":"2021-01-15T23:30:23+00:00","dateModified":"2023-08-02T20:00:15+00:00","breadcrumb":{"@id":"https:\/\/regnumchristi.org\/sabado-16-de-enero-de-2021-cristo-nos-llama\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/regnumchristi.org\/sabado-16-de-enero-de-2021-cristo-nos-llama\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/regnumchristi.org\/sabado-16-de-enero-de-2021-cristo-nos-llama\/#primaryimage","url":"https:\/\/regnumchristi.org\/wp-content\/uploads\/2021\/01\/160121.jpg","contentUrl":"https:\/\/regnumchristi.org\/wp-content\/uploads\/2021\/01\/160121.jpg","width":1200,"height":628,"caption":"mueva nuestras vidas"},{"@type":"BreadcrumbList","@id":"https:\/\/regnumchristi.org\/sabado-16-de-enero-de-2021-cristo-nos-llama\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/regnumchristi.org\/es\/"},{"@type":"ListItem","position":2,"name":"S\u00e1bado 16 de enero de 2021 &#8211; Cristo nos llama"}]},{"@type":"WebSite","@id":"https:\/\/regnumchristi.org\/#website","url":"https:\/\/regnumchristi.org\/","name":"Regnum Christi Internacional","description":"El Regnum Christi es una realidad de la Iglesia cat\u00f3lica cuya misi\u00f3n es hacer presente el Reino de Cristo","publisher":{"@id":"https:\/\/regnumchristi.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/regnumchristi.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/regnumchristi.org\/#organization","name":"Regnum Christi Internacional","url":"https:\/\/regnumchristi.org\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/regnumchristi.org\/#\/schema\/logo\/image\/","url":"https:\/\/regnumchristi.es\/wp-content\/uploads\/2023\/03\/Favicon-RC_ligh-cuadrado.png","contentUrl":"https:\/\/regnumchristi.es\/wp-content\/uploads\/2023\/03\/Favicon-RC_ligh-cuadrado.png","width":1080,"height":1080,"caption":"Regnum Christi Internacional"},"image":{"@id":"https:\/\/regnumchristi.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/RegnumChristiEspana\/","https:\/\/x.com\/rc_espana","https:\/\/www.instagram.com\/rc_espana\/","https:\/\/es.linkedin.com\/company\/regnumchristiespaa"]},{"@type":"Person","@id":"https:\/\/regnumchristi.org\/#\/schema\/person\/a5ad8b3c4bd3cb3a0abe8a1474fe8f0a","name":"Meditaciones Diarias","url":"https:\/\/regnumchristi.org\/es\/author\/meditacionesd\/"}]}},"_links":{"self":[{"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/posts\/28972","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/comments?post=28972"}],"version-history":[{"count":1,"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/posts\/28972\/revisions"}],"predecessor-version":[{"id":96792,"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/posts\/28972\/revisions\/96792"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/media\/28984"}],"wp:attachment":[{"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/media?parent=28972"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/categories?post=28972"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/tags?post=28972"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}