{"id":30427,"date":"2021-06-15T10:20:48","date_gmt":"2021-06-15T15:20:48","guid":{"rendered":"https:\/\/www.regnumchristi.org\/es\/?p=30427"},"modified":"2021-06-15T10:20:48","modified_gmt":"2021-06-15T15:20:48","slug":"isabelle-de-rochefort-camino-conversion","status":"publish","type":"post","link":"https:\/\/regnumchristi.org\/es\/isabelle-de-rochefort-camino-conversion\/","title":{"rendered":"\u00abAunque ciertas culturas repitan que Jes\u00fas debe ser invisible, \u00c9l sale constantemente a nuestro encuentro\u00bb"},"content":{"rendered":"<h3 class=\"gdlr-blog-title\">Isabelle de Rochefort: Empec\u00e9 mi camino de conversi\u00f3n con 39 a\u00f1os, de la mano del Regnum Christi aqu\u00ed en Espa\u00f1a.<\/h3>\n<p><em>Isabelle de Rochefort naci\u00f3 en Par\u00eds, se enamor\u00f3 de un sevillano y ah\u00ed form\u00f3 una familia que define como \u201csu vocaci\u00f3n\u201d. A trav\u00e9s de <a href=\"https:\/\/www.highlandssevilla.es\/\" target=\"_blank\" rel=\"noopener noreferrer\">Highlands School Sevilla<\/a>\u00a0conoci\u00f3 el\u00a0Regnum Christi y desde 2012 forma parte de esta familia espiritual. Es periodista y fil\u00f3loga y colabora con C\u00e1ritas parroquial, con Altius Sevilla como formadora, con Radio Mar\u00eda editando programas, con ClubHouse comentando el evangelio diariamente con el P. Ricardo S\u00e1enz, LC\u2026 Pero Isabelle es noticia porque <a href=\"https:\/\/www.amazon.es\/s?k=isabelle+de+rochefort&amp;__mk_es_ES=%C3%85M%C3%85%C5%BD%C3%95%C3%91&amp;crid=2Q0BUFSXGE7T9&amp;sprefix=isabelle+de+roc%2Caps%2C175&amp;ref=nb_sb_ss_ts-doa-p_1_15\" target=\"_blank\" rel=\"noopener noreferrer\">tambi\u00e9n escribe libros<\/a> y en los \u00faltimos a\u00f1os ha publicado una colecci\u00f3n titulada \u201cTe conoc\u00eda de o\u00eddas\u201d formada por cuatro libros que hablan sobre muchos aspectos de los cristianos como la oraci\u00f3n o las dudas en la fe que pueden ayudar a crecer. <\/em><em>En esta entrevista nos explica c\u00f3mo ha sido el proceso de creaci\u00f3n de estos libros y qu\u00e9 ha supuesto en su vida espiritual.<\/em><\/p>\n<h4>\u00bfEn qu\u00e9 medida tu experiencia vital en el Regnum Christi te ayuda a escribir estos libros?<\/h4>\n<p>El Regnum Christi ha sido y es el medio que me ha llevado a la mayor\u00eda de las experiencias vividas y que vienen reflejadas en los libros. Doy gracias a Dios por haberme puesto en el camino al Regnum Christi. Para m\u00ed ha sido primordial la atenci\u00f3n en direcci\u00f3n espiritual con legionarios y consagradas a lo largo de los a\u00f1os y todas las actividades. Al cuidado cotidiano, tengo que a\u00f1adir las adoraciones mensuales, los ejercicios espirituales anuales, las peregrinaciones a Medjugorje, Tierra Santa, las misiones a Guinea Ecuatorial\u2026 todas estas experiencias han hecho surgir los libros.<\/p>\n<p>Y durante la pandemia ha sido providencial para las familias tener este apoyo desde las redes durante los meses de confinamiento, misas diarias de sacerdotes legionarios de Cristo desde Madrid y desde Par\u00eds con el P. Paul Habsburg, el \u00c1ngelus y adoraciones con <a href=\"https:\/\/consagradasrc.org\/\" target=\"_blank\" rel=\"noopener noreferrer\">las consagradas<\/a> en Instagram desde Cerro del Coto\u2026<\/p>\n<p>Sobre todo, mi experiencia vital del Regnum Christi a lo largo de los a\u00f1os es el trato con personas que viven y comparten la misma espiritualidad y se vuelven profundas amistades en Cristo. Los frutos del Regnum Christi en m\u00ed se encuentran reflejados en los libros.<\/p>\n<h4>\u00bfY qu\u00e9 te ha llevado a escribirlos?<\/h4>\n<p>M\u00e1s que una experiencia, creo que es la suma de experiencias que se vuelve sobre abundante y no caben m\u00e1s entre mis manos, quiz\u00e1s es el desbordamiento de los escritos, quiz\u00e1s es porque hab\u00eda llegado el momento de compartir y dejar descansar las vivencias en el papel. No lo ten\u00eda planeado ni previsto, surgi\u00f3 como el suave empuj\u00f3n del Esp\u00edritu Santo y me puse manos a la obra sin tener calculado ni asegurado fueran a hacerse realidad.<\/p>\n<h4>\u00bfC\u00f3mo ha sido la selecci\u00f3n de los temas?<strong><br \/>\n<\/strong><\/h4>\n<p>Por mi formaci\u00f3n literaria, tengo la costumbre de escribir mucho. Repasando las vivencias y direcciones espirituales, han ido surgiendo los temas, con naturalidad. Primero una intuici\u00f3n, una posibilidad que se va consolidando hasta imponerse y hacerse criterio. Una vez determinados los temas, he ido descartando y seleccionando los textos.\u00a0Poco a poco, emergieron cuatro temas y los textos se iban articulando unos con otros. Tard\u00e9 un a\u00f1o en escribirlos, ocuparon mis d\u00edas y mi mente. Despu\u00e9s tard\u00e9 nueve meses, entre pruebas y correcciones, portadas y encuadernaci\u00f3n.<\/p>\n<h4>\u00bfQu\u00e9 es lo que m\u00e1s te ha ayudado durante el camino? \u00bfY aquello que m\u00e1s te ha costado?<\/h4>\n<p>Lo que m\u00e1s me ha ayudado sin duda ha sido mi familia, mi marido y mis hijas, que a pesar de lo \u201cincomprensible\u201d y a veces \u201cmolesto\u201d que puede ser el empe\u00f1o de alguien por una obra, respetaron y me animaron siempre y en todo para que siga con los apostolados. Apoyan y ven con buenos ojos todo lo que hacemos para Gloria de Dios y extender su Reino en la tierra, al final son el motor y la llave que pone en marcha el proyecto. Nunca han puesto barreras a mis \u201clocuras\u201d apost\u00f3licas, y les aseguro que ha habido si no se ve con los ojos de la fe\u2026 Me ayud\u00f3 tambi\u00e9n la disposici\u00f3n de un legionario que se prest\u00f3 a leerlos y corregir las dudas que ten\u00eda. Me dio mucha seguridad en cuanto a la ortodoxia de doctrina espiritual.<\/p>\n<p>Quiz\u00e1s los peores momentos son los \u00faltimos, porque mientras vas escribiendo, te lleva la ilusi\u00f3n de un proyecto, el fuego creativo, el ir construyendo hacia la meta. En cambio las correcciones son m\u00e1s ingratas porque son severas y exigentes. El \u00faltimo libro ha sido el m\u00e1s trabajado a la hora de cambios y correcciones importantes, y quiz\u00e1s el m\u00e1s doloroso porque fue el m\u00e1s solitario y silenciado. Al mismo tiempo, esta fatiga ha retumbado quiz\u00e1s para ser el que m\u00e1s est\u00e1 ayudando a los lectores.<\/p>\n<h4>\u00bfPor qu\u00e9 has decidido incluir las reflexiones del P. Miguel Segura, LC?<\/h4>\n<p>Se me ocurri\u00f3 hacerlo a partir del segundo libro. Encontr\u00e9 m\u00e1s justo y m\u00e1s vivo distinguir la tipograf\u00eda y establecer un di\u00e1logo informal; como un teatro a dos voces. Las otras voces a veces contrastan, o al contrario aterrizan las vivencias, otras veces confirman intuiciones y profundizan con el valor a\u00f1adido de la predicaci\u00f3n sacerdotal. Incluir al P. Miguel Segura y a otras personas citadas es a la vez mi modo de agradecerles y el modo de evitar libros egoc\u00e9ntricos.<\/p>\n<h4>El primer libro habla de un Jes\u00fas invisible en la oraci\u00f3n, los sacramentos, las cruces, en los estados de vida\u2026 Tambi\u00e9n, hablas, a partir de esto, de la duda en la fe. \u00bfQu\u00e9 puede aportar la duda en la vida de un cristiano?<\/h4>\n<p>Aunque ciertas culturas como la m\u00eda repitan que Jes\u00fas debe ser invisible, \u00c9l sale constantemente a nuestro encuentro. Jes\u00fas invisible parte de experiencias reales, ancladas en la tierra, en los sentidos, en la vista, el tocar, o\u00edr. Est\u00e1 imbuido en lo humano, en Jesucristo hombre verdadero entre los hombres; est\u00e1 basado en hechos, experiencias y observaciones objetivas, un libro muy terrenal, pero en todo estos episodios transciende la presencia y actuaci\u00f3n de Jesucristo. Desde el Evangelio, a trav\u00e9s de la historia de la humanidad hasta en cada una de nuestras vidas cotidianas y actuales.<\/p>\n<h4>\u00bfQu\u00e9 puede aportar la duda en la fe?<\/h4>\n<p>Creo que avanzamos a golpe de dudas de fe. Empec\u00e9 mi camino de conversi\u00f3n con 39 a\u00f1os, de la mano del Regnum Christi aqu\u00ed en Espa\u00f1a. Mi cultura francesa y formaci\u00f3n human\u00edstica han sido fuertemente relativistas, enraizadas en el racionalismo y el culto por lo absurdo y ef\u00edmero. Ser cat\u00f3lica en mi ambiente pertenece a la esfera privada. No se comparte, no se habla de creer en Dios, ni se debate, porque es una debilidad. Ortodoxa de coraz\u00f3n por mi madre, viv\u00eda intr\u00ednsecamente una contradicci\u00f3n entre mi convencimiento intelectual y un sentir transcendente fuerte. Mi conversi\u00f3n es un vaiv\u00e9n incesante entre persuasi\u00f3n y dudas, entre saber y entender, entre buscar y encontrar a Dios, entre intuir, pedir y experimentar el amor de Cristo, o los cuidados de la Virgen.<\/p>\n<p>Creo que avanzamos tanteando, pero que cada paso consolida nuestra fe y esta es cada vez m\u00e1s fuerte. Las dudas no son un par\u00f3n o dar un paso hacia atr\u00e1s, todo lo contrario; creo que las dudas son pasos hacia adelante. Por eso no hay que dejar de buscar a Dios, la multiplicidad de los medios, de los apostolados, la necesidad de peregrinar, de ir a los sitios, y de repetir los encuentros con Cristo\u2026. Nunca agotaremos los encuentros con el amor de Dios.<\/p>\n<h4>\u00bfQu\u00e9 supone esta experiencia en la vida de una persona que no es cristiana?<\/h4>\n<p>\u00a1En la pr\u00e1ctica era mi caso! Por eso siento que puedo responderte as\u00ed: Supone un cambio radical. Cambia nuestra manera de ser, nuestra manera de vivir, nuestra manera de relacionarnos con los amigos, nuestra manera de trabajar, nuestra manera de educar a los hijos, nuestra manera de amar en el matrimonio, nuestra manera de vivir en el mundo, nuestra manera de tratar a los dem\u00e1s, nuestra manera de involucrarnos en la sociedad, nuestra manera de ver la Iglesia, la manera de ver y tratar con las almas consagradas, la manera de enfocar los sufrimientos, las enfermedades, la manera de ver la muerte y encauzar la vida.<\/p>\n<h4>\u00bfC\u00f3mo es tu vida de oraci\u00f3n?<\/h4>\n<p>Aunque hablo de la oraci\u00f3n en cada libro, el cuarto y \u00faltimo libro trata de manera m\u00e1s exclusiva de la oraci\u00f3n. Mi experiencia es que la vida de oraci\u00f3n, como la de la fe, es progresiva. Mientras oremos, siempre iremos hacia adelante; aunque parezca que nuestra oraci\u00f3n es seca o nuestra vida espiritual un desierto donde no encontramos a Dios, podemos estar seguro que estamos avanzando hacia \u00c9l, hacia el encuentro con el Se\u00f1or. Es un camino sorprendente porque no dirigimos la barca de nuestra oraci\u00f3n, y es un camino sin l\u00edmites porque as\u00ed nos lo ense\u00f1an los Santos m\u00edsticos, y es un camino sin fin porque hasta en el cielo podremos interceder para la salvaci\u00f3n de las almas. Quien busca la verdad, encuentra a Dios. Quien ora, encuentra la verdad.<\/p>\n<h4>\u00bfPuedes darnos algunos consejos?<\/h4>\n<p>Creo que la vida de oraci\u00f3n, como las personas, es \u00fanica e irrepetible. Si est\u00e1s empezando, aconsejar\u00eda acercarte a una iglesia o arrodillarte ante el Sant\u00edsimo en alguna adoraci\u00f3n eucar\u00edstica, y ofrecer al Se\u00f1or un Padre Nuestro. La oraci\u00f3n se ejercita. Es como subir la ladera de una monta\u00f1a: se empieza desde abajo levantando la mirada, y la cima est\u00e1 lejos, fuera de nuestro alcance. Mu\u00e9strate y manifiesta tu deseo de encontrarte con Dios, una, dos o m\u00e1s veces.<\/p>\n<p>\u00c9l te ense\u00f1ar\u00e1 tu camino de oraci\u00f3n con inspiraciones y providencias del Esp\u00edritu de Dios. Y a medida que subes por la ladera, cuando el camino recorrido es m\u00e1s largo que el camino restante, sabr\u00e1s que ya nadie ni nada te desviar\u00e1 del camino a la cima. Nadie te apartar\u00e1 de tu vida de oraci\u00f3n, y te encontrar\u00e1s libre, pleno y feliz, pase lo que pase en tu vida, porque estar\u00e1s contemplando la grandeza y la belleza de la obra de Dios desde la cima.<\/p>\n<h5><em>Fuente: <a href=\"https:\/\/regnumchristi.es\/\" target=\"_blank\" rel=\"noopener noreferrer\">regnumchristi.es<\/a><\/em><\/h5>\n","protected":false},"excerpt":{"rendered":"<p> [&hellip;]<\/p>\n","protected":false},"author":49,"featured_media":30428,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"_daextrevop_audio_file_creation_date":"","_daextrevop_text_to_speech":"","_daextrevop_document_type":"","footnotes":""},"categories":[3031,1687],"tags":[860,3110,1871],"class_list":["post-30427","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-destacadas","category-noticias","tag-familia-rc","tag-publicaciones","tag-vida-de-oracion"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Isabelle de Rochefort: Empec\u00e9 mi camino de conversi\u00f3n con 39 a\u00f1os<\/title>\n<meta name=\"description\" content=\"Entrevista - Isabelle de Rochefort naci\u00f3 en Par\u00eds, se enamor\u00f3 de un sevillano y en Sevilla form\u00f3 una familia que define como \u201csu vocaci\u00f3n\u201d.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/regnumchristi.org\/es\/isabelle-de-rochefort-camino-conversion\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Isabelle de Rochefort: Empec\u00e9 mi camino de conversi\u00f3n con 39 a\u00f1os\" \/>\n<meta property=\"og:description\" content=\"Entrevista - Isabelle de Rochefort naci\u00f3 en Par\u00eds, se enamor\u00f3 de un sevillano y en Sevilla form\u00f3 una familia que define como \u201csu vocaci\u00f3n\u201d.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/regnumchristi.org\/es\/isabelle-de-rochefort-camino-conversion\/\" \/>\n<meta property=\"og:site_name\" content=\"Regnum Christi Internacional\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/RegnumChristiEspana\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-15T15:20:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/regnumchristi.org\/wp-content\/uploads\/2021\/06\/isabelle-libro-2-1.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"724\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Autores varios\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Autores varios\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/isabelle-de-rochefort-camino-conversion\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/isabelle-de-rochefort-camino-conversion\\\/\"},\"author\":{\"name\":\"Autores varios\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#\\\/schema\\\/person\\\/73f2e414269cfbf8edecc2fd90af81f2\"},\"headline\":\"\u00abAunque ciertas culturas repitan que Jes\u00fas debe ser invisible, \u00c9l sale constantemente a nuestro encuentro\u00bb\",\"datePublished\":\"2021-06-15T15:20:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/isabelle-de-rochefort-camino-conversion\\\/\"},\"wordCount\":1809,\"publisher\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/isabelle-de-rochefort-camino-conversion\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/regnumchristi.org\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/isabelle-libro-2-1.jpeg\",\"keywords\":[\"familia RC\",\"publicaciones\",\"vida de oraci\u00f3n\"],\"articleSection\":[\"Destacadas\",\"Noticias\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/isabelle-de-rochefort-camino-conversion\\\/\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/isabelle-de-rochefort-camino-conversion\\\/\",\"name\":\"Isabelle de Rochefort: Empec\u00e9 mi camino de conversi\u00f3n con 39 a\u00f1os\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/isabelle-de-rochefort-camino-conversion\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/isabelle-de-rochefort-camino-conversion\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/regnumchristi.org\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/isabelle-libro-2-1.jpeg\",\"datePublished\":\"2021-06-15T15:20:48+00:00\",\"description\":\"Entrevista - Isabelle de Rochefort naci\u00f3 en Par\u00eds, se enamor\u00f3 de un sevillano y en Sevilla form\u00f3 una familia que define como \u201csu vocaci\u00f3n\u201d.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/isabelle-de-rochefort-camino-conversion\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/regnumchristi.org\\\/isabelle-de-rochefort-camino-conversion\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/isabelle-de-rochefort-camino-conversion\\\/#primaryimage\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/isabelle-libro-2-1.jpeg\",\"contentUrl\":\"https:\\\/\\\/regnumchristi.org\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/isabelle-libro-2-1.jpeg\",\"width\":1200,\"height\":724,\"caption\":\"Isabelle de Rochefort: Empec\u00e9 mi camino de conversi\u00f3n con 39 a\u00f1os, de la mano del Regnum Christi aqu\u00ed en Espa\u00f1a.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/isabelle-de-rochefort-camino-conversion\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/regnumchristi.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00abAunque ciertas culturas repitan que Jes\u00fas debe ser invisible, \u00c9l sale constantemente a nuestro encuentro\u00bb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#website\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/\",\"name\":\"Regnum Christi Internacional\",\"description\":\"El Regnum Christi es una realidad de la Iglesia cat\u00f3lica cuya misi\u00f3n es hacer presente el Reino de Cristo\",\"publisher\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/regnumchristi.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#organization\",\"name\":\"Regnum Christi Internacional\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/regnumchristi.es\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Favicon-RC_ligh-cuadrado.png\",\"contentUrl\":\"https:\\\/\\\/regnumchristi.es\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Favicon-RC_ligh-cuadrado.png\",\"width\":1080,\"height\":1080,\"caption\":\"Regnum Christi Internacional\"},\"image\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/RegnumChristiEspana\\\/\",\"https:\\\/\\\/x.com\\\/rc_espana\",\"https:\\\/\\\/www.instagram.com\\\/rc_espana\\\/\",\"https:\\\/\\\/es.linkedin.com\\\/company\\\/regnumchristiespaa\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#\\\/schema\\\/person\\\/73f2e414269cfbf8edecc2fd90af81f2\",\"name\":\"Autores varios\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/es\\\/author\\\/jarceocaesc-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Isabelle de Rochefort: Empec\u00e9 mi camino de conversi\u00f3n con 39 a\u00f1os","description":"Entrevista - Isabelle de Rochefort naci\u00f3 en Par\u00eds, se enamor\u00f3 de un sevillano y en Sevilla form\u00f3 una familia que define como \u201csu vocaci\u00f3n\u201d.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/regnumchristi.org\/es\/isabelle-de-rochefort-camino-conversion\/","og_locale":"es_MX","og_type":"article","og_title":"Isabelle de Rochefort: Empec\u00e9 mi camino de conversi\u00f3n con 39 a\u00f1os","og_description":"Entrevista - Isabelle de Rochefort naci\u00f3 en Par\u00eds, se enamor\u00f3 de un sevillano y en Sevilla form\u00f3 una familia que define como \u201csu vocaci\u00f3n\u201d.","og_url":"https:\/\/regnumchristi.org\/es\/isabelle-de-rochefort-camino-conversion\/","og_site_name":"Regnum Christi Internacional","article_publisher":"https:\/\/www.facebook.com\/RegnumChristiEspana\/","article_published_time":"2021-06-15T15:20:48+00:00","og_image":[{"width":1200,"height":724,"url":"https:\/\/regnumchristi.org\/wp-content\/uploads\/2021\/06\/isabelle-libro-2-1.jpeg","type":"image\/jpeg"}],"author":"Autores varios","twitter_misc":{"Escrito por":"Autores varios","Tiempo de lectura":"9 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/regnumchristi.org\/isabelle-de-rochefort-camino-conversion\/#article","isPartOf":{"@id":"https:\/\/regnumchristi.org\/isabelle-de-rochefort-camino-conversion\/"},"author":{"name":"Autores varios","@id":"https:\/\/regnumchristi.org\/#\/schema\/person\/73f2e414269cfbf8edecc2fd90af81f2"},"headline":"\u00abAunque ciertas culturas repitan que Jes\u00fas debe ser invisible, \u00c9l sale constantemente a nuestro encuentro\u00bb","datePublished":"2021-06-15T15:20:48+00:00","mainEntityOfPage":{"@id":"https:\/\/regnumchristi.org\/isabelle-de-rochefort-camino-conversion\/"},"wordCount":1809,"publisher":{"@id":"https:\/\/regnumchristi.org\/#organization"},"image":{"@id":"https:\/\/regnumchristi.org\/isabelle-de-rochefort-camino-conversion\/#primaryimage"},"thumbnailUrl":"https:\/\/regnumchristi.org\/wp-content\/uploads\/2021\/06\/isabelle-libro-2-1.jpeg","keywords":["familia RC","publicaciones","vida de oraci\u00f3n"],"articleSection":["Destacadas","Noticias"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/regnumchristi.org\/isabelle-de-rochefort-camino-conversion\/","url":"https:\/\/regnumchristi.org\/isabelle-de-rochefort-camino-conversion\/","name":"Isabelle de Rochefort: Empec\u00e9 mi camino de conversi\u00f3n con 39 a\u00f1os","isPartOf":{"@id":"https:\/\/regnumchristi.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/regnumchristi.org\/isabelle-de-rochefort-camino-conversion\/#primaryimage"},"image":{"@id":"https:\/\/regnumchristi.org\/isabelle-de-rochefort-camino-conversion\/#primaryimage"},"thumbnailUrl":"https:\/\/regnumchristi.org\/wp-content\/uploads\/2021\/06\/isabelle-libro-2-1.jpeg","datePublished":"2021-06-15T15:20:48+00:00","description":"Entrevista - Isabelle de Rochefort naci\u00f3 en Par\u00eds, se enamor\u00f3 de un sevillano y en Sevilla form\u00f3 una familia que define como \u201csu vocaci\u00f3n\u201d.","breadcrumb":{"@id":"https:\/\/regnumchristi.org\/isabelle-de-rochefort-camino-conversion\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/regnumchristi.org\/isabelle-de-rochefort-camino-conversion\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/regnumchristi.org\/isabelle-de-rochefort-camino-conversion\/#primaryimage","url":"https:\/\/regnumchristi.org\/wp-content\/uploads\/2021\/06\/isabelle-libro-2-1.jpeg","contentUrl":"https:\/\/regnumchristi.org\/wp-content\/uploads\/2021\/06\/isabelle-libro-2-1.jpeg","width":1200,"height":724,"caption":"Isabelle de Rochefort: Empec\u00e9 mi camino de conversi\u00f3n con 39 a\u00f1os, de la mano del Regnum Christi aqu\u00ed en Espa\u00f1a."},{"@type":"BreadcrumbList","@id":"https:\/\/regnumchristi.org\/isabelle-de-rochefort-camino-conversion\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/regnumchristi.org\/es\/"},{"@type":"ListItem","position":2,"name":"\u00abAunque ciertas culturas repitan que Jes\u00fas debe ser invisible, \u00c9l sale constantemente a nuestro encuentro\u00bb"}]},{"@type":"WebSite","@id":"https:\/\/regnumchristi.org\/#website","url":"https:\/\/regnumchristi.org\/","name":"Regnum Christi Internacional","description":"El Regnum Christi es una realidad de la Iglesia cat\u00f3lica cuya misi\u00f3n es hacer presente el Reino de Cristo","publisher":{"@id":"https:\/\/regnumchristi.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/regnumchristi.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/regnumchristi.org\/#organization","name":"Regnum Christi Internacional","url":"https:\/\/regnumchristi.org\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/regnumchristi.org\/#\/schema\/logo\/image\/","url":"https:\/\/regnumchristi.es\/wp-content\/uploads\/2023\/03\/Favicon-RC_ligh-cuadrado.png","contentUrl":"https:\/\/regnumchristi.es\/wp-content\/uploads\/2023\/03\/Favicon-RC_ligh-cuadrado.png","width":1080,"height":1080,"caption":"Regnum Christi Internacional"},"image":{"@id":"https:\/\/regnumchristi.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/RegnumChristiEspana\/","https:\/\/x.com\/rc_espana","https:\/\/www.instagram.com\/rc_espana\/","https:\/\/es.linkedin.com\/company\/regnumchristiespaa"]},{"@type":"Person","@id":"https:\/\/regnumchristi.org\/#\/schema\/person\/73f2e414269cfbf8edecc2fd90af81f2","name":"Autores varios","url":"https:\/\/regnumchristi.org\/es\/author\/jarceocaesc-com\/"}]}},"_links":{"self":[{"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/posts\/30427","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/users\/49"}],"replies":[{"embeddable":true,"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/comments?post=30427"}],"version-history":[{"count":0,"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/posts\/30427\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/media\/30428"}],"wp:attachment":[{"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/media?parent=30427"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/categories?post=30427"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/tags?post=30427"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}