{"id":33200,"date":"2022-06-01T20:14:41","date_gmt":"2022-06-02T01:14:41","guid":{"rendered":"https:\/\/www.regnumchristi.org\/es\/?p=33200"},"modified":"2023-07-14T20:25:07","modified_gmt":"2023-07-14T18:25:07","slug":"primer-encuentro-yios-de-universitarios-y-profesionistas-eb-chile","status":"publish","type":"post","link":"https:\/\/regnumchristi.org\/es\/primer-encuentro-yios-de-universitarios-y-profesionistas-eb-chile\/","title":{"rendered":"\u00abUn encuentro con Jes\u00fas a rostro descubierto\u00bb \u2013 Primer encuentro &#8220;YIOS&#8221; en Chile"},"content":{"rendered":"<p>Entre el 13 y 15 de mayo se realiz\u00f3 la primera versi\u00f3n del retiro YIOS en Chile. Se trata de una actividad organizada por universitarios y profesionistas del Regnum Christi dirigido a sus pares: j\u00f3venes cat\u00f3licos del Regnum Christi y de otros movimientos o carismas. \u201cAprend\u00ed a reconocer mi identidad como una hija amad\u00edsima de Dios\u201d, comenta Trinidad Henr\u00edquez (21), alumna de cuarto a\u00f1o de Literatura y que vivi\u00f3 esta experiencia.<\/p>\n<p>Alrededor de 80 j\u00f3venes de entre 19 y 30 a\u00f1os, provenientes de diversos lugares y movimientos, participaron en esta actividad. \u201cFue un encuentro con Jes\u00fas a rostro descubierto\u201d, afirma Trinidad.<\/p>\n<p>La metodolog\u00eda del retiro YIOS proviene de la secci\u00f3n de j\u00f3venes de Espa\u00f1a, basado en la Teolog\u00eda del Cuerpo, es decir, las catequesis de San Juan Pablo II sobre el amor humano. El quipo organizador \u201cstaff\u201d est\u00e1 conformado por aproximadamente 30 personas, quienes son miembros de las secciones de j\u00f3venes de Las Condes, La Dehesa, Buin y Rancagua guiados y acompa\u00f1ados constantemente por sacerdotes y consagradas. \u201cLa teolog\u00eda del cuerpo es una joya que requiere mucha cabeza, pero especialmente oraci\u00f3n, as\u00ed que me quedo con esa tarea\u201d, explica Trinidad.<\/p>\n<p>Durante el retiro YIOS se realizaron diferentes charlas sobre cada uno de los ciclos de la Teolog\u00eda del Cuerpo. En ellas se expuso de manera fiel y cercana los contenidos de la catequesis, con ejemplos de la vida cotidiana y testimonios, con el fin de que los participantes hicieran propia la Teolog\u00eda del Cuerpo. \u201cFue un fin de semana desafiante y regocijante porque por una parte nos entregaron muy buen material de formaci\u00f3n en temas abstractos, que a ratos cuesta comprender, pero al mismo tiempo se cre\u00f3 una atm\u00f3sfera especial al interior de este grupo de j\u00f3venes que nos juntamos a conocer m\u00e1s a Dios en un tema tan bonito como es la teolog\u00eda del cuerpo\u201d, se\u00f1ala Enzo Rivera (23), egresado de Derecho.<\/p>\n<p>Adem\u00e1s, hubo instancias de conversaciones grupales con el fin de decantar y compartir los contenidos expuestos, lo que se combin\u00f3 con instancias de oraci\u00f3n y din\u00e1micas experienciales que promovieron una apertura y disposici\u00f3n de los corazones hacia la Teolog\u00eda del Cuerpo.<\/p>\n<p>En este encuentro se abordaron preguntas existenciales y las personas vivieron una profunda experiencia para encontrar su identidad como hijos de Dios. \u201cTen\u00eda una aproximaci\u00f3n a la teolog\u00eda del cuerpo desde la sexualidad y aspectos concretos, pero me di cuenta que tiene un sentido mucho m\u00e1s amplio: es una historia de amor de Dios con cada uno de nosotros, y c\u00f3mo ese amor se puede multiplicar a trav\u00e9s nuestro en distintos \u00e1mbitos de relaciones como amorosas, familiares y de amistad\u201d, concluye Enzo.<\/p>\n<p><strong>El pr\u00f3ximo retiro se realizar\u00e1 el 30 de septiembre, 1 y<\/strong>\u00a0<strong>2 de octubre,<\/strong> cuyas inscripciones se realizar\u00e1n de manera online.<\/p>\n<div class=\"ast-oembed-container \" style=\"height: 100%;\"><iframe title=\"Retiro Y\u00edos, mayo 2022\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/RIWXmaWLRf0?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n<h5><em>Fuente: <a href=\"https:\/\/www.regnumchristichile.cl\/\" target=\"_blank\" rel=\"noopener noreferrer\">regnumchristi.cl<\/a><\/em><\/h5>\n","protected":false},"excerpt":{"rendered":"<p> [&hellip;]<\/p>\n","protected":false},"author":49,"featured_media":33202,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"_daextrevop_audio_file_creation_date":"","_daextrevop_text_to_speech":"","_daextrevop_document_type":"","footnotes":""},"categories":[3031,1687],"tags":[207,1171],"class_list":["post-33200","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-destacadas","category-noticias","tag-juventud","tag-yios"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Primer encuentro &quot;YIOS&quot; de universitarios y profesionistas en Chile<\/title>\n<meta name=\"description\" content=\"Entre el 13 y 15 de mayo se realiz\u00f3 la primera versi\u00f3n del retiro YIOS en Chile. Participaron alrededor de 80 j\u00f3venes de entre 19 y 30 a\u00f1os.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/regnumchristi.org\/es\/primer-encuentro-yios-de-universitarios-y-profesionistas-eb-chile\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Primer encuentro &quot;YIOS&quot; de universitarios y profesionistas en Chile\" \/>\n<meta property=\"og:description\" content=\"Entre el 13 y 15 de mayo se realiz\u00f3 la primera versi\u00f3n del retiro YIOS en Chile. Participaron alrededor de 80 j\u00f3venes de entre 19 y 30 a\u00f1os.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/regnumchristi.org\/es\/primer-encuentro-yios-de-universitarios-y-profesionistas-eb-chile\/\" \/>\n<meta property=\"og:site_name\" content=\"Regnum Christi Internacional\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/RegnumChristiEspana\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-06-02T01:14:41+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-07-14T18:25:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/regnumchristi.org\/wp-content\/uploads\/2022\/06\/yios.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"668\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Autores varios\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Autores varios\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/primer-encuentro-yios-de-universitarios-y-profesionistas-eb-chile\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/primer-encuentro-yios-de-universitarios-y-profesionistas-eb-chile\\\/\"},\"author\":{\"name\":\"Autores varios\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#\\\/schema\\\/person\\\/73f2e414269cfbf8edecc2fd90af81f2\"},\"headline\":\"\u00abUn encuentro con Jes\u00fas a rostro descubierto\u00bb \u2013 Primer encuentro &#8220;YIOS&#8221; en Chile\",\"datePublished\":\"2022-06-02T01:14:41+00:00\",\"dateModified\":\"2023-07-14T18:25:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/primer-encuentro-yios-de-universitarios-y-profesionistas-eb-chile\\\/\"},\"wordCount\":505,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/primer-encuentro-yios-de-universitarios-y-profesionistas-eb-chile\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/regnumchristi.org\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/yios.jpeg\",\"keywords\":[\"juventud\",\"Yi\u00f3s\"],\"articleSection\":[\"Destacadas\",\"Noticias\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/regnumchristi.org\\\/primer-encuentro-yios-de-universitarios-y-profesionistas-eb-chile\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/primer-encuentro-yios-de-universitarios-y-profesionistas-eb-chile\\\/\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/primer-encuentro-yios-de-universitarios-y-profesionistas-eb-chile\\\/\",\"name\":\"Primer encuentro \\\"YIOS\\\" de universitarios y profesionistas en Chile\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/primer-encuentro-yios-de-universitarios-y-profesionistas-eb-chile\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/primer-encuentro-yios-de-universitarios-y-profesionistas-eb-chile\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/regnumchristi.org\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/yios.jpeg\",\"datePublished\":\"2022-06-02T01:14:41+00:00\",\"dateModified\":\"2023-07-14T18:25:07+00:00\",\"description\":\"Entre el 13 y 15 de mayo se realiz\u00f3 la primera versi\u00f3n del retiro YIOS en Chile. Participaron alrededor de 80 j\u00f3venes de entre 19 y 30 a\u00f1os.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/primer-encuentro-yios-de-universitarios-y-profesionistas-eb-chile\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/regnumchristi.org\\\/primer-encuentro-yios-de-universitarios-y-profesionistas-eb-chile\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/primer-encuentro-yios-de-universitarios-y-profesionistas-eb-chile\\\/#primaryimage\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/yios.jpeg\",\"contentUrl\":\"https:\\\/\\\/regnumchristi.org\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/yios.jpeg\",\"width\":1000,\"height\":668,\"caption\":\"YIOS \u00abUn encuentro con Jes\u00fas a rostro descubierto\u00bb \u2013 Primer encuentro \\\"YIOS\\\" en Chile\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/primer-encuentro-yios-de-universitarios-y-profesionistas-eb-chile\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/regnumchristi.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00abUn encuentro con Jes\u00fas a rostro descubierto\u00bb \u2013 Primer encuentro &#8220;YIOS&#8221; en Chile\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#website\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/\",\"name\":\"Regnum Christi Internacional\",\"description\":\"El Regnum Christi es una realidad de la Iglesia cat\u00f3lica cuya misi\u00f3n es hacer presente el Reino de Cristo\",\"publisher\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/regnumchristi.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#organization\",\"name\":\"Regnum Christi Internacional\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/regnumchristi.es\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Favicon-RC_ligh-cuadrado.png\",\"contentUrl\":\"https:\\\/\\\/regnumchristi.es\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Favicon-RC_ligh-cuadrado.png\",\"width\":1080,\"height\":1080,\"caption\":\"Regnum Christi Internacional\"},\"image\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/RegnumChristiEspana\\\/\",\"https:\\\/\\\/x.com\\\/rc_espana\",\"https:\\\/\\\/www.instagram.com\\\/rc_espana\\\/\",\"https:\\\/\\\/es.linkedin.com\\\/company\\\/regnumchristiespaa\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#\\\/schema\\\/person\\\/73f2e414269cfbf8edecc2fd90af81f2\",\"name\":\"Autores varios\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/es\\\/author\\\/jarceocaesc-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Primer encuentro \"YIOS\" de universitarios y profesionistas en Chile","description":"Entre el 13 y 15 de mayo se realiz\u00f3 la primera versi\u00f3n del retiro YIOS en Chile. Participaron alrededor de 80 j\u00f3venes de entre 19 y 30 a\u00f1os.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/regnumchristi.org\/es\/primer-encuentro-yios-de-universitarios-y-profesionistas-eb-chile\/","og_locale":"es_MX","og_type":"article","og_title":"Primer encuentro \"YIOS\" de universitarios y profesionistas en Chile","og_description":"Entre el 13 y 15 de mayo se realiz\u00f3 la primera versi\u00f3n del retiro YIOS en Chile. Participaron alrededor de 80 j\u00f3venes de entre 19 y 30 a\u00f1os.","og_url":"https:\/\/regnumchristi.org\/es\/primer-encuentro-yios-de-universitarios-y-profesionistas-eb-chile\/","og_site_name":"Regnum Christi Internacional","article_publisher":"https:\/\/www.facebook.com\/RegnumChristiEspana\/","article_published_time":"2022-06-02T01:14:41+00:00","article_modified_time":"2023-07-14T18:25:07+00:00","og_image":[{"width":1000,"height":668,"url":"https:\/\/regnumchristi.org\/wp-content\/uploads\/2022\/06\/yios.jpeg","type":"image\/jpeg"}],"author":"Autores varios","twitter_misc":{"Escrito por":"Autores varios","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/regnumchristi.org\/primer-encuentro-yios-de-universitarios-y-profesionistas-eb-chile\/#article","isPartOf":{"@id":"https:\/\/regnumchristi.org\/primer-encuentro-yios-de-universitarios-y-profesionistas-eb-chile\/"},"author":{"name":"Autores varios","@id":"https:\/\/regnumchristi.org\/#\/schema\/person\/73f2e414269cfbf8edecc2fd90af81f2"},"headline":"\u00abUn encuentro con Jes\u00fas a rostro descubierto\u00bb \u2013 Primer encuentro &#8220;YIOS&#8221; en Chile","datePublished":"2022-06-02T01:14:41+00:00","dateModified":"2023-07-14T18:25:07+00:00","mainEntityOfPage":{"@id":"https:\/\/regnumchristi.org\/primer-encuentro-yios-de-universitarios-y-profesionistas-eb-chile\/"},"wordCount":505,"commentCount":0,"publisher":{"@id":"https:\/\/regnumchristi.org\/#organization"},"image":{"@id":"https:\/\/regnumchristi.org\/primer-encuentro-yios-de-universitarios-y-profesionistas-eb-chile\/#primaryimage"},"thumbnailUrl":"https:\/\/regnumchristi.org\/wp-content\/uploads\/2022\/06\/yios.jpeg","keywords":["juventud","Yi\u00f3s"],"articleSection":["Destacadas","Noticias"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/regnumchristi.org\/primer-encuentro-yios-de-universitarios-y-profesionistas-eb-chile\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/regnumchristi.org\/primer-encuentro-yios-de-universitarios-y-profesionistas-eb-chile\/","url":"https:\/\/regnumchristi.org\/primer-encuentro-yios-de-universitarios-y-profesionistas-eb-chile\/","name":"Primer encuentro \"YIOS\" de universitarios y profesionistas en Chile","isPartOf":{"@id":"https:\/\/regnumchristi.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/regnumchristi.org\/primer-encuentro-yios-de-universitarios-y-profesionistas-eb-chile\/#primaryimage"},"image":{"@id":"https:\/\/regnumchristi.org\/primer-encuentro-yios-de-universitarios-y-profesionistas-eb-chile\/#primaryimage"},"thumbnailUrl":"https:\/\/regnumchristi.org\/wp-content\/uploads\/2022\/06\/yios.jpeg","datePublished":"2022-06-02T01:14:41+00:00","dateModified":"2023-07-14T18:25:07+00:00","description":"Entre el 13 y 15 de mayo se realiz\u00f3 la primera versi\u00f3n del retiro YIOS en Chile. Participaron alrededor de 80 j\u00f3venes de entre 19 y 30 a\u00f1os.","breadcrumb":{"@id":"https:\/\/regnumchristi.org\/primer-encuentro-yios-de-universitarios-y-profesionistas-eb-chile\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/regnumchristi.org\/primer-encuentro-yios-de-universitarios-y-profesionistas-eb-chile\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/regnumchristi.org\/primer-encuentro-yios-de-universitarios-y-profesionistas-eb-chile\/#primaryimage","url":"https:\/\/regnumchristi.org\/wp-content\/uploads\/2022\/06\/yios.jpeg","contentUrl":"https:\/\/regnumchristi.org\/wp-content\/uploads\/2022\/06\/yios.jpeg","width":1000,"height":668,"caption":"YIOS \u00abUn encuentro con Jes\u00fas a rostro descubierto\u00bb \u2013 Primer encuentro \"YIOS\" en Chile"},{"@type":"BreadcrumbList","@id":"https:\/\/regnumchristi.org\/primer-encuentro-yios-de-universitarios-y-profesionistas-eb-chile\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/regnumchristi.org\/es\/"},{"@type":"ListItem","position":2,"name":"\u00abUn encuentro con Jes\u00fas a rostro descubierto\u00bb \u2013 Primer encuentro &#8220;YIOS&#8221; en Chile"}]},{"@type":"WebSite","@id":"https:\/\/regnumchristi.org\/#website","url":"https:\/\/regnumchristi.org\/","name":"Regnum Christi Internacional","description":"El Regnum Christi es una realidad de la Iglesia cat\u00f3lica cuya misi\u00f3n es hacer presente el Reino de Cristo","publisher":{"@id":"https:\/\/regnumchristi.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/regnumchristi.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/regnumchristi.org\/#organization","name":"Regnum Christi Internacional","url":"https:\/\/regnumchristi.org\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/regnumchristi.org\/#\/schema\/logo\/image\/","url":"https:\/\/regnumchristi.es\/wp-content\/uploads\/2023\/03\/Favicon-RC_ligh-cuadrado.png","contentUrl":"https:\/\/regnumchristi.es\/wp-content\/uploads\/2023\/03\/Favicon-RC_ligh-cuadrado.png","width":1080,"height":1080,"caption":"Regnum Christi Internacional"},"image":{"@id":"https:\/\/regnumchristi.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/RegnumChristiEspana\/","https:\/\/x.com\/rc_espana","https:\/\/www.instagram.com\/rc_espana\/","https:\/\/es.linkedin.com\/company\/regnumchristiespaa"]},{"@type":"Person","@id":"https:\/\/regnumchristi.org\/#\/schema\/person\/73f2e414269cfbf8edecc2fd90af81f2","name":"Autores varios","url":"https:\/\/regnumchristi.org\/es\/author\/jarceocaesc-com\/"}]}},"_links":{"self":[{"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/posts\/33200","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/users\/49"}],"replies":[{"embeddable":true,"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/comments?post=33200"}],"version-history":[{"count":1,"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/posts\/33200\/revisions"}],"predecessor-version":[{"id":93056,"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/posts\/33200\/revisions\/93056"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/media\/33202"}],"wp:attachment":[{"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/media?parent=33200"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/categories?post=33200"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/tags?post=33200"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}