{"id":36167,"date":"2023-04-13T20:00:06","date_gmt":"2023-04-14T02:00:06","guid":{"rendered":"https:\/\/www.regnumchristi.org\/es\/?p=36167"},"modified":"2023-08-02T13:25:58","modified_gmt":"2023-08-02T19:25:58","slug":"viernes-14-de-abril-de-2023-nunca-mas-solos-todo-con-jesus","status":"publish","type":"post","link":"https:\/\/regnumchristi.org\/es\/viernes-14-de-abril-de-2023-nunca-mas-solos-todo-con-jesus\/","title":{"rendered":"Viernes 14 de abril de 2023 \u2013 \u00abNunca m\u00e1s solos, todo con Jes\u00fas\u00bb"},"content":{"rendered":"<p><i><span data-contrast=\"none\">Paulina Tena Gonz\u00e1lez M\u00e9ndez, CRC<\/span><\/i><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"none\">En el nombre del Padre y del Hijo y del Esp\u00edritu Santo.<\/span><br \/>\n<span data-contrast=\"none\">Am\u00e9n.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"none\">Cristo, Rey nuestro.<\/span><br \/>\n<span data-contrast=\"none\">\u00a1Venga tu Reino!<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><span style=\"color: #800000;\"><b>Oraci\u00f3n preparatoria <\/b><\/span><i><span data-contrast=\"none\">(para ponerme en presencia de Dios)<\/span><\/i><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"none\">Te entrego mis manos para hacer el trabajo contigo, te entrego mis pies para caminar contigo, te entrego mis ojos para ver lo que t\u00fa ves, te entrego mi lengua para hablar tus palabras, te lo entrego todo y lo recibo todo de ti, en esta oraci\u00f3n y en cada instante de mi vida. As\u00ed, en tu presencia \u00faneme a tu coraz\u00f3n resucitado, que esta oraci\u00f3n sea para gloria de Dios y por todos los que me has dado.\u00a0<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><span style=\"color: #800000;\"><b>Evangelio del d\u00eda <\/b><\/span><i><span data-contrast=\"none\">(para orientar tu meditaci\u00f3n)<\/span><\/i><br \/>\n<span data-contrast=\"none\">Del santo Evangelio seg\u00fan san Juan 21, 1-14<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"none\">En aquel tiempo, Jes\u00fas se apareci\u00f3 otra vez a los disc\u00edpulos junto al lago de Tiber\u00edades. Y se apareci\u00f3 de esta manera: Estaban juntos Sim\u00f3n Pedro, Tom\u00e1s apodado el Mellizo, Natanael el de Can\u00e1 de Galilea, los Zebedeos y otros dos disc\u00edpulos suyos. Sim\u00f3n Pedro les dice: &#8220;Me voy a pescar.&#8221; Ellos contestan: &#8220;Vamos tambi\u00e9n nosotros contigo&#8221;. Salieron y se embarcaron; y aquella noche no cogieron nada. Estaba ya amaneciendo, cuando Jes\u00fas se present\u00f3 en la orilla; pero los disc\u00edpulos no sab\u00edan que era Jes\u00fas. Jes\u00fas les dice: &#8220;Muchachos, \u00bften\u00e9is pescado?&#8221;. Ellos contestaron: &#8220;No&#8221;. \u00c9l les dice: &#8220;Echad la red a la derecha de la barca y encontrar\u00e9is&#8221;. La echaron, y no ten\u00edan fuerzas para sacarla, por la multitud de peces. Y aquel disc\u00edpulo que Jes\u00fas tanto quer\u00eda le dice a Pedro: &#8220;Es el Se\u00f1or&#8221;. Al o\u00edr que era el Se\u00f1or, Sim\u00f3n Pedro, que estaba desnudo, se at\u00f3 la t\u00fanica y se ech\u00f3 al agua. Los dem\u00e1s disc\u00edpulos se acercaron en la barca, porque no distaban de tierra m\u00e1s que unos cien metros, remolcando la red con los peces. Al saltar a tierra, ven unas brasas con un pescado puesto encima y pan. Jes\u00fas les dice: &#8220;Traed de los peces que acab\u00e1is de coger&#8221;. Sim\u00f3n Pedro subi\u00f3 a la barca y arrastr\u00f3 hasta la orilla la red repleta de peces grandes: ciento cincuenta y tres. Y aunque eran tantos, no se rompi\u00f3 la red. Jes\u00fas les dice: &#8220;Vamos, almorzad&#8221;. Ninguno de los disc\u00edpulos se atrev\u00eda a preguntarle qui\u00e9n era, porque sab\u00edan bien que era el Se\u00f1or. Jes\u00fas se acerca, toma el pan y se lo da, y lo mismo el pescado. Esta fue la tercera vez que Jes\u00fas se apareci\u00f3 a los disc\u00edpulos, despu\u00e9s de resucitar de entre los muertos.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><i><span data-contrast=\"none\">Palabra del Se\u00f1or<\/span><\/i><span data-contrast=\"none\">.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><span style=\"color: #800000;\"><b>Medita lo que Dios te dice en el Evangelio<\/b>\u00a0<\/span><\/p>\n<p><span data-contrast=\"none\">Te me has revelado, me has hecho experimentar tu amor al extremo, resucitaste para darme vida en abundancia y aun as\u00ed mi fragilidad me hace pensar que me las tengo que arreglar solo. Salgo a \u201cpescar\u201d en mi barca vieja. Busco resolver asuntos con mis cualidades y mis propias fuerzas. Pero me conoces y sales a mi encuentro\u2026; en mis esfuerzos me dices: &#8220;Echad la red a la derecha de la barca y encontrar\u00e9is&#8221;. \u00a1Y as\u00ed sucede!<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"none\">Contigo siempre encuentro, contigo puedo. CONTIGO. Es otra forma de experimentarte constantemente vivo. Hacer las cosas juntos. Conversar contigo de lo que har\u00e9 o de las decisiones que quiero tomar. Resolver los asuntos, desahogar el coraz\u00f3n, ilusionarme contigo.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"none\">\u00bfCu\u00e1l es el efecto? Que cada vez podr\u00e9 palpar m\u00e1s tu presencia, tu huella en los acontecimientos de la vida y, como Juan, podr\u00e9 decir desde el fondo de mi coraz\u00f3n \u201c\u00a1Es el Se\u00f1or!\u201d.\u00a0<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"none\">Al decirlo otros tambi\u00e9n te podr\u00e1n reconocer. Como Pedro, que le bast\u00f3 escuchar esa afirmaci\u00f3n para tirarse de la barca e ir a ti. Deseo que muchos puedan ir a ti y hoy me dejas ver que reconoci\u00e9ndote y compartiendo mi experiencia de ti, ser\u00e1 un camino claro que anuncie que est\u00e1s vivo.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><i><span data-contrast=\"none\">\u00abLa presencia de Jes\u00fas resucitado transforma todas las cosas: la oscuridad es vencida por la luz, el trabajo in\u00fatil es nuevamente fructuoso y prometedor, el sentido de cansancio y de abandono deja espacio a un nuevo impulso y a la certeza de que \u00c9l est\u00e1 con nosotros\u00bb. (S.S. Francisco, Regina Caeli del 10 de abril de 2016).<\/span><\/i><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><span style=\"color: #800000;\"><b>Di\u00e1logo con Cristo<\/b>\u00a0<\/span><\/p>\n<p><i><span data-contrast=\"none\">\u00c9sta es la parte m\u00e1s importante de tu oraci\u00f3n, disponte a platicar con mucho amor con Aquel que te ama.<\/span><\/i><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><span style=\"color: #800000;\"><b>Prop\u00f3sito<\/b>\u00a0<\/span><\/p>\n<p><i><span data-contrast=\"none\">Proponte uno personal. El que m\u00e1s amor implique en respuesta al Amado\u2026 o, si crees que es lo que Dios te pide, vive lo que se te sugiere a continuaci\u00f3n.<\/span><\/i><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"none\">Busca hacer conciencia, cuando empieces a hacer alguna de tus actividades, para hacerlas con Jes\u00fas.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><span style=\"color: #800000;\"><b>Despedida<\/b>\u00a0<\/span><\/p>\n<p><span data-contrast=\"none\">Te damos gracias, Se\u00f1or, por todos tus beneficios, a ti que vives y reinas por los siglos de los siglos.<\/span><br \/>\n<span data-contrast=\"none\">Am\u00e9n.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"none\">\u00a1Cristo, Rey nuestro!<\/span><br \/>\n<span data-contrast=\"none\">\u00a1Venga tu Reino!<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"none\">Virgen prudent\u00edsima, Mar\u00eda, Madre de la Iglesia.<\/span><br \/>\n<span data-contrast=\"none\">Ruega por nosotros.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"none\">En el nombre del Padre y del Hijo y del Esp\u00edritu Santo.<\/span><br \/>\n<span data-contrast=\"none\">Am\u00e9n.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p> [&hellip;]<\/p>\n","protected":false},"author":58,"featured_media":36261,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"_daextrevop_audio_file_creation_date":"","_daextrevop_text_to_speech":"","_daextrevop_document_type":"","footnotes":""},"categories":[3164],"tags":[3162,3163,3067],"class_list":["post-36167","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-meditacion-del-dia","tag-evangelio","tag-meditacion","tag-reflexion"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Viernes 14 de abril de 2023 \u2013 \u00abNunca m\u00e1s solos, todo con Jes\u00fas\u00bb - Regnum Christi Internacional<\/title>\n<meta name=\"description\" content=\"Te entrego mis manos para hacer el trabajo contigo, te entrego mis pies para caminar contigo, te entrego mis ojos para ver lo que t\u00fa ves.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/regnumchristi.org\/es\/viernes-14-de-abril-de-2023-nunca-mas-solos-todo-con-jesus\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Viernes 14 de abril de 2023 \u2013 \u00abNunca m\u00e1s solos, todo con Jes\u00fas\u00bb - Regnum Christi Internacional\" \/>\n<meta property=\"og:description\" content=\"Te entrego mis manos para hacer el trabajo contigo, te entrego mis pies para caminar contigo, te entrego mis ojos para ver lo que t\u00fa ves.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/regnumchristi.org\/es\/viernes-14-de-abril-de-2023-nunca-mas-solos-todo-con-jesus\/\" \/>\n<meta property=\"og:site_name\" content=\"Regnum Christi Internacional\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/RegnumChristiEspana\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-04-14T02:00:06+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-08-02T19:25:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/regnumchristi.org\/wp-content\/uploads\/2023\/04\/imagenes_meditaciones_diarias_14abr.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"563\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Meditaciones Diarias\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Meditaciones Diarias\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/viernes-14-de-abril-de-2023-nunca-mas-solos-todo-con-jesus\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/viernes-14-de-abril-de-2023-nunca-mas-solos-todo-con-jesus\\\/\"},\"author\":{\"name\":\"Meditaciones Diarias\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#\\\/schema\\\/person\\\/a5ad8b3c4bd3cb3a0abe8a1474fe8f0a\"},\"headline\":\"Viernes 14 de abril de 2023 \u2013 \u00abNunca m\u00e1s solos, todo con Jes\u00fas\u00bb\",\"datePublished\":\"2023-04-14T02:00:06+00:00\",\"dateModified\":\"2023-08-02T19:25:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/viernes-14-de-abril-de-2023-nunca-mas-solos-todo-con-jesus\\\/\"},\"wordCount\":895,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/viernes-14-de-abril-de-2023-nunca-mas-solos-todo-con-jesus\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/regnumchristi.org\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/imagenes_meditaciones_diarias_14abr.jpg\",\"keywords\":[\"Evangelio\",\"meditaci\u00f3n\",\"Reflexi\u00f3n\"],\"articleSection\":[\"Meditaci\u00f3n del d\u00eda\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/regnumchristi.org\\\/viernes-14-de-abril-de-2023-nunca-mas-solos-todo-con-jesus\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/viernes-14-de-abril-de-2023-nunca-mas-solos-todo-con-jesus\\\/\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/viernes-14-de-abril-de-2023-nunca-mas-solos-todo-con-jesus\\\/\",\"name\":\"Viernes 14 de abril de 2023 \u2013 \u00abNunca m\u00e1s solos, todo con Jes\u00fas\u00bb - Regnum Christi Internacional\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/viernes-14-de-abril-de-2023-nunca-mas-solos-todo-con-jesus\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/viernes-14-de-abril-de-2023-nunca-mas-solos-todo-con-jesus\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/regnumchristi.org\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/imagenes_meditaciones_diarias_14abr.jpg\",\"datePublished\":\"2023-04-14T02:00:06+00:00\",\"dateModified\":\"2023-08-02T19:25:58+00:00\",\"description\":\"Te entrego mis manos para hacer el trabajo contigo, te entrego mis pies para caminar contigo, te entrego mis ojos para ver lo que t\u00fa ves.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/viernes-14-de-abril-de-2023-nunca-mas-solos-todo-con-jesus\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/regnumchristi.org\\\/viernes-14-de-abril-de-2023-nunca-mas-solos-todo-con-jesus\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/viernes-14-de-abril-de-2023-nunca-mas-solos-todo-con-jesus\\\/#primaryimage\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/imagenes_meditaciones_diarias_14abr.jpg\",\"contentUrl\":\"https:\\\/\\\/regnumchristi.org\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/imagenes_meditaciones_diarias_14abr.jpg\",\"width\":900,\"height\":563},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/viernes-14-de-abril-de-2023-nunca-mas-solos-todo-con-jesus\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/regnumchristi.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Viernes 14 de abril de 2023 \u2013 \u00abNunca m\u00e1s solos, todo con Jes\u00fas\u00bb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#website\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/\",\"name\":\"Regnum Christi Internacional\",\"description\":\"El Regnum Christi es una realidad de la Iglesia cat\u00f3lica cuya misi\u00f3n es hacer presente el Reino de Cristo\",\"publisher\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/regnumchristi.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#organization\",\"name\":\"Regnum Christi Internacional\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/regnumchristi.es\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Favicon-RC_ligh-cuadrado.png\",\"contentUrl\":\"https:\\\/\\\/regnumchristi.es\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Favicon-RC_ligh-cuadrado.png\",\"width\":1080,\"height\":1080,\"caption\":\"Regnum Christi Internacional\"},\"image\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/RegnumChristiEspana\\\/\",\"https:\\\/\\\/x.com\\\/rc_espana\",\"https:\\\/\\\/www.instagram.com\\\/rc_espana\\\/\",\"https:\\\/\\\/es.linkedin.com\\\/company\\\/regnumchristiespaa\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#\\\/schema\\\/person\\\/a5ad8b3c4bd3cb3a0abe8a1474fe8f0a\",\"name\":\"Meditaciones Diarias\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/es\\\/author\\\/meditacionesd\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Viernes 14 de abril de 2023 \u2013 \u00abNunca m\u00e1s solos, todo con Jes\u00fas\u00bb - Regnum Christi Internacional","description":"Te entrego mis manos para hacer el trabajo contigo, te entrego mis pies para caminar contigo, te entrego mis ojos para ver lo que t\u00fa ves.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/regnumchristi.org\/es\/viernes-14-de-abril-de-2023-nunca-mas-solos-todo-con-jesus\/","og_locale":"es_MX","og_type":"article","og_title":"Viernes 14 de abril de 2023 \u2013 \u00abNunca m\u00e1s solos, todo con Jes\u00fas\u00bb - Regnum Christi Internacional","og_description":"Te entrego mis manos para hacer el trabajo contigo, te entrego mis pies para caminar contigo, te entrego mis ojos para ver lo que t\u00fa ves.","og_url":"https:\/\/regnumchristi.org\/es\/viernes-14-de-abril-de-2023-nunca-mas-solos-todo-con-jesus\/","og_site_name":"Regnum Christi Internacional","article_publisher":"https:\/\/www.facebook.com\/RegnumChristiEspana\/","article_published_time":"2023-04-14T02:00:06+00:00","article_modified_time":"2023-08-02T19:25:58+00:00","og_image":[{"width":900,"height":563,"url":"https:\/\/regnumchristi.org\/wp-content\/uploads\/2023\/04\/imagenes_meditaciones_diarias_14abr.jpg","type":"image\/jpeg"}],"author":"Meditaciones Diarias","twitter_misc":{"Escrito por":"Meditaciones Diarias","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/regnumchristi.org\/viernes-14-de-abril-de-2023-nunca-mas-solos-todo-con-jesus\/#article","isPartOf":{"@id":"https:\/\/regnumchristi.org\/viernes-14-de-abril-de-2023-nunca-mas-solos-todo-con-jesus\/"},"author":{"name":"Meditaciones Diarias","@id":"https:\/\/regnumchristi.org\/#\/schema\/person\/a5ad8b3c4bd3cb3a0abe8a1474fe8f0a"},"headline":"Viernes 14 de abril de 2023 \u2013 \u00abNunca m\u00e1s solos, todo con Jes\u00fas\u00bb","datePublished":"2023-04-14T02:00:06+00:00","dateModified":"2023-08-02T19:25:58+00:00","mainEntityOfPage":{"@id":"https:\/\/regnumchristi.org\/viernes-14-de-abril-de-2023-nunca-mas-solos-todo-con-jesus\/"},"wordCount":895,"commentCount":0,"publisher":{"@id":"https:\/\/regnumchristi.org\/#organization"},"image":{"@id":"https:\/\/regnumchristi.org\/viernes-14-de-abril-de-2023-nunca-mas-solos-todo-con-jesus\/#primaryimage"},"thumbnailUrl":"https:\/\/regnumchristi.org\/wp-content\/uploads\/2023\/04\/imagenes_meditaciones_diarias_14abr.jpg","keywords":["Evangelio","meditaci\u00f3n","Reflexi\u00f3n"],"articleSection":["Meditaci\u00f3n del d\u00eda"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/regnumchristi.org\/viernes-14-de-abril-de-2023-nunca-mas-solos-todo-con-jesus\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/regnumchristi.org\/viernes-14-de-abril-de-2023-nunca-mas-solos-todo-con-jesus\/","url":"https:\/\/regnumchristi.org\/viernes-14-de-abril-de-2023-nunca-mas-solos-todo-con-jesus\/","name":"Viernes 14 de abril de 2023 \u2013 \u00abNunca m\u00e1s solos, todo con Jes\u00fas\u00bb - Regnum Christi Internacional","isPartOf":{"@id":"https:\/\/regnumchristi.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/regnumchristi.org\/viernes-14-de-abril-de-2023-nunca-mas-solos-todo-con-jesus\/#primaryimage"},"image":{"@id":"https:\/\/regnumchristi.org\/viernes-14-de-abril-de-2023-nunca-mas-solos-todo-con-jesus\/#primaryimage"},"thumbnailUrl":"https:\/\/regnumchristi.org\/wp-content\/uploads\/2023\/04\/imagenes_meditaciones_diarias_14abr.jpg","datePublished":"2023-04-14T02:00:06+00:00","dateModified":"2023-08-02T19:25:58+00:00","description":"Te entrego mis manos para hacer el trabajo contigo, te entrego mis pies para caminar contigo, te entrego mis ojos para ver lo que t\u00fa ves.","breadcrumb":{"@id":"https:\/\/regnumchristi.org\/viernes-14-de-abril-de-2023-nunca-mas-solos-todo-con-jesus\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/regnumchristi.org\/viernes-14-de-abril-de-2023-nunca-mas-solos-todo-con-jesus\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/regnumchristi.org\/viernes-14-de-abril-de-2023-nunca-mas-solos-todo-con-jesus\/#primaryimage","url":"https:\/\/regnumchristi.org\/wp-content\/uploads\/2023\/04\/imagenes_meditaciones_diarias_14abr.jpg","contentUrl":"https:\/\/regnumchristi.org\/wp-content\/uploads\/2023\/04\/imagenes_meditaciones_diarias_14abr.jpg","width":900,"height":563},{"@type":"BreadcrumbList","@id":"https:\/\/regnumchristi.org\/viernes-14-de-abril-de-2023-nunca-mas-solos-todo-con-jesus\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/regnumchristi.org\/es\/"},{"@type":"ListItem","position":2,"name":"Viernes 14 de abril de 2023 \u2013 \u00abNunca m\u00e1s solos, todo con Jes\u00fas\u00bb"}]},{"@type":"WebSite","@id":"https:\/\/regnumchristi.org\/#website","url":"https:\/\/regnumchristi.org\/","name":"Regnum Christi Internacional","description":"El Regnum Christi es una realidad de la Iglesia cat\u00f3lica cuya misi\u00f3n es hacer presente el Reino de Cristo","publisher":{"@id":"https:\/\/regnumchristi.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/regnumchristi.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/regnumchristi.org\/#organization","name":"Regnum Christi Internacional","url":"https:\/\/regnumchristi.org\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/regnumchristi.org\/#\/schema\/logo\/image\/","url":"https:\/\/regnumchristi.es\/wp-content\/uploads\/2023\/03\/Favicon-RC_ligh-cuadrado.png","contentUrl":"https:\/\/regnumchristi.es\/wp-content\/uploads\/2023\/03\/Favicon-RC_ligh-cuadrado.png","width":1080,"height":1080,"caption":"Regnum Christi Internacional"},"image":{"@id":"https:\/\/regnumchristi.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/RegnumChristiEspana\/","https:\/\/x.com\/rc_espana","https:\/\/www.instagram.com\/rc_espana\/","https:\/\/es.linkedin.com\/company\/regnumchristiespaa"]},{"@type":"Person","@id":"https:\/\/regnumchristi.org\/#\/schema\/person\/a5ad8b3c4bd3cb3a0abe8a1474fe8f0a","name":"Meditaciones Diarias","url":"https:\/\/regnumchristi.org\/es\/author\/meditacionesd\/"}]}},"_links":{"self":[{"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/posts\/36167","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/comments?post=36167"}],"version-history":[{"count":1,"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/posts\/36167\/revisions"}],"predecessor-version":[{"id":93826,"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/posts\/36167\/revisions\/93826"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/media\/36261"}],"wp:attachment":[{"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/media?parent=36167"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/categories?post=36167"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/tags?post=36167"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}