{"id":92769,"date":"2020-11-23T09:47:39","date_gmt":"2020-11-23T15:47:39","guid":{"rendered":"https:\/\/www.regnumchristi.org\/es\/?p=28480"},"modified":"2023-07-14T18:22:14","modified_gmt":"2023-07-14T16:22:14","slug":"prelatura-cancun-chetumal-a-diocesis","status":"publish","type":"post","link":"https:\/\/regnumchristi.org\/es\/prelatura-cancun-chetumal-a-diocesis\/","title":{"rendered":"Se celebra la elevaci\u00f3n de la Prelatura Canc\u00fan-Chetumal a Di\u00f3cesis"},"content":{"rendered":"<p><a href=\"https:\/\/regnumchristi.org\/wp-content\/uploads\/2020\/11\/2020-11-21__PLN5686.png\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignright size-medium wp-image-28482\" src=\"https:\/\/regnumchristi.org\/wp-content\/uploads\/2020\/11\/2020-11-21__PLN5686-300x200.png\" alt=\"Se celebra la elevaci\u00f3n de la Prelatura Canc\u00fan-Chetumal a Di\u00f3cesis\" width=\"300\" height=\"200\" srcset=\"https:\/\/regnumchristi.org\/wp-content\/uploads\/2020\/11\/2020-11-21__PLN5686-300x200.png 300w, https:\/\/regnumchristi.org\/wp-content\/uploads\/2020\/11\/2020-11-21__PLN5686-1024x683.png 1024w, https:\/\/regnumchristi.org\/wp-content\/uploads\/2020\/11\/2020-11-21__PLN5686-768x512.png 768w, https:\/\/regnumchristi.org\/wp-content\/uploads\/2020\/11\/2020-11-21__PLN5686-1536x1024.png 1536w, https:\/\/regnumchristi.org\/wp-content\/uploads\/2020\/11\/2020-11-21__PLN5686.png 1980w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>El s\u00e1bado 21 de noviembre el nuncio apost\u00f3lico en M\u00e9xico, Mons. Franco Coppola elev\u00f3 la antigua Prelatura de Canc\u00fan-Chetumal a <a href=\"https:\/\/cancunchetumal.org\/\" target=\"_blank\" rel=\"noopener noreferrer\">Di\u00f3cesis<\/a>. En la misa celebrada en la Catedral de la Sant\u00edsima Trinidad de Canc\u00fan, Mons. Pedro Pablo Elizondo fue elevado a obispo diocesano. Durante la ceremonia fue acompa\u00f1ado, adem\u00e1s del nuncio apost\u00f3lico y del obispo em\u00e9rito Mons. Jorge Bernal, LC, por los obispos de la provincia: el arzobispo de Tuxtla Guti\u00e9rrez, Mons. Fabio Mart\u00ednez Castilla; el arzobispo de Yucat\u00e1n \u00a0Mons. Gustavo Rodr\u00edguez Vega, el arzobispo em\u00e9rito Mons. Emilio Carlos Berlie y el obispo auxiliar Mons. Pedro Mena; de Campeche Mons. Francisco Gonz\u00e1lez.<\/p>\n<p>El Papa Francisco se hizo presente por medio de una carta donde expresa su cercan\u00eda. En este mensaje se uni\u00f3 espiritualmente a la acci\u00f3n de gracias por los frutos de los 50 a\u00f1os de la Prelatura y pide a la Iglesia particular que lleve la alegr\u00eda del Evangelio especialmente a los m\u00e1s pobres y necesitados. Tambi\u00e9n fue entregada la bula, donde el papa Francisco confirma la elevaci\u00f3n a Di\u00f3cesis de la Prelatura Canc\u00fan-Chetumal y a Mons. Pedro Pablo Elizondo, LC como primer obispo diocesano.<\/p>\n<figure id=\"attachment_28483\" aria-describedby=\"caption-attachment-28483\" style=\"width: 300px\" class=\"wp-caption alignleft\"><a href=\"https:\/\/regnumchristi.org\/wp-content\/uploads\/2020\/11\/2020-11-21__PLN5669.png\"><img decoding=\"async\" class=\"size-medium wp-image-28483\" src=\"https:\/\/regnumchristi.org\/wp-content\/uploads\/2020\/11\/2020-11-21__PLN5669-300x200.png\" alt=\"Se celebra la elevaci\u00f3n de la Prelatura Canc\u00fan-Chetumal a Di\u00f3cesis\" width=\"300\" height=\"200\" srcset=\"https:\/\/regnumchristi.org\/wp-content\/uploads\/2020\/11\/2020-11-21__PLN5669-300x200.png 300w, https:\/\/regnumchristi.org\/wp-content\/uploads\/2020\/11\/2020-11-21__PLN5669-1024x683.png 1024w, https:\/\/regnumchristi.org\/wp-content\/uploads\/2020\/11\/2020-11-21__PLN5669-768x512.png 768w, https:\/\/regnumchristi.org\/wp-content\/uploads\/2020\/11\/2020-11-21__PLN5669-1536x1024.png 1536w, https:\/\/regnumchristi.org\/wp-content\/uploads\/2020\/11\/2020-11-21__PLN5669.png 1980w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><figcaption id=\"caption-attachment-28483\" class=\"wp-caption-text\">Mons. Franco Coppola, Nuncio de Su Santidad en M\u00e9xico.<\/figcaption><\/figure>\n<p>Al menos un centenar de sacerdotes concelebraron la misa, entre ellos algunos de los religiosos que han visto la evoluci\u00f3n obrada desde sus inicios. Fue el 23 de mayo de 1970 cuando el Sumo Pont\u00edfice Pablo VI encomienda a los <a href=\"https:\/\/legionariosdecristo.org\/\" target=\"_blank\" rel=\"noopener noreferrer\">Legionarios de Cristo<\/a> la Prelatura de Chetumal, nombrando a Mons. Jorge Bernal Vargas, LC, administrador apost\u00f3lico y cuatro a\u00f1os despu\u00e9s recibe el orden episcopal.<\/p>\n<p>Entre los sacerdotes presentes se encontraba Patrick Corrigan, LC, que reci\u00e9n ordenado fue enviado al territorio de Quintana Roo hace ya 50 a\u00f1os. Narra la siguiente experiencia en su libro <em>&#8220;Mis memorias, una hojeada en el tiempo&#8221;<\/em>: \u00abComo antes de que lleg\u00e1ramos los Legionarios de Cristo no hab\u00eda un obispo que visitara las comunidades\u2026 Pr\u00e1cticamente ning\u00fan cat\u00f3lico de las 32 primeras comunidades que me toc\u00f3 hab\u00eda sido confirmado\u2026me program\u00e9 con Mons. Jorge Bernal para visitar las comunidades ya preparadas para la confirmaci\u00f3n. El itinerario se hizo para quince d\u00edas; dos y tres pueblos por d\u00eda, calculando distancia y n\u00famero de cat\u00f3licos\u00bb.<\/p>\n<p>Por su parte, el nuncio Franco Coppola en su homil\u00eda comparaba la nueva di\u00f3cesis Canc\u00fan-Chetumal a un ni\u00f1o, pues \u00ablos tiempos de la Iglesia son un poco m\u00e1s largos, entonces 50 a\u00f1os sigue siendo un ni\u00f1o, puede caminar ya con sus pies, pero tiene mucho que aprender\u00bb.<\/p>\n<p><a href=\"https:\/\/regnumchristi.org\/wp-content\/uploads\/2020\/11\/2020-11-21__Z6C5048.png\"><img decoding=\"async\" class=\"alignright size-medium wp-image-28484\" src=\"https:\/\/regnumchristi.org\/wp-content\/uploads\/2020\/11\/2020-11-21__Z6C5048-300x200.png\" alt=\"Se celebra la elevaci\u00f3n de la Prelatura Canc\u00fan-Chetumal a Di\u00f3cesis\" width=\"300\" height=\"200\" srcset=\"https:\/\/regnumchristi.org\/wp-content\/uploads\/2020\/11\/2020-11-21__Z6C5048-300x200.png 300w, https:\/\/regnumchristi.org\/wp-content\/uploads\/2020\/11\/2020-11-21__Z6C5048-1024x681.png 1024w, https:\/\/regnumchristi.org\/wp-content\/uploads\/2020\/11\/2020-11-21__Z6C5048-768x511.png 768w, https:\/\/regnumchristi.org\/wp-content\/uploads\/2020\/11\/2020-11-21__Z6C5048-1536x1022.png 1536w, https:\/\/regnumchristi.org\/wp-content\/uploads\/2020\/11\/2020-11-21__Z6C5048.png 1980w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>Los fieles laicos tambi\u00e9n se hicieron presentes a trav\u00e9s de devociones de piedad popular. Desde el s\u00e1bado por la ma\u00f1ana parti\u00f3 de Chetumal una caravana de autos aleg\u00f3ricos, en donde se exhib\u00edan los patronos de las diversas parroquias de los ocho decanatos de la di\u00f3cesis. El Sant\u00edsimo Sacramento recorri\u00f3 todo el trayecto, pasando por varias ciudades hasta llegar a la Catedral de Canc\u00fan. Durante la misa se tuvieron detalles tanto en la primera lectura al ser en lengua maya, como en el ofertorio al pasar vestidos con la ropa t\u00edpica regional de fiesta para presentar los dones.<\/p>\n<p>Al final de la celebraci\u00f3n eucar\u00edstica Mons. Pedro Pablo Elizondo, LC, dio unas palabras de agradecimiento tomando las palabras de la Virgen Mar\u00eda con el <em>Magnificat<\/em>. Agradeci\u00f3 a cada uno de los grupos presentes y concluy\u00f3 una parte de su discurso mencionando los elementos que constituyen el nuevo logo de la di\u00f3cesis con la cruz maya, el color verde de la selva y el mar azul turquesa.<\/p>\n<p>\u00abBenditas tierras de Quintana Roo, por su cristalino mar turquesa que las ba\u00f1a y abraza, por el sol radiante que las ilumina y calienta, por la selva verde y generosa que las viste y arropa. Pero sobre todo benditas tierras de Quintana Roo porque ellas recibieron los primeros rayos del sol de la Evangelizaci\u00f3n cristiana en la naci\u00f3n mexicana\u00bb.<\/p>\n<h3>Mensaje del Papa Francisco a Mons. Pedro Pablo Elizondo, L.C. y a la nueva di\u00f3cesis<\/h3>\n<p><a href=\"https:\/\/regnumchristi.org\/wp-content\/uploads\/2020\/11\/2020-11-21__Z6C5092.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-28485\" src=\"https:\/\/regnumchristi.org\/wp-content\/uploads\/2020\/11\/2020-11-21__Z6C5092-300x200.png\" alt=\"Se celebra la elevaci\u00f3n de la Prelatura Canc\u00fan-Chetumal a Di\u00f3cesis\" width=\"300\" height=\"200\" srcset=\"https:\/\/regnumchristi.org\/wp-content\/uploads\/2020\/11\/2020-11-21__Z6C5092-300x200.png 300w, https:\/\/regnumchristi.org\/wp-content\/uploads\/2020\/11\/2020-11-21__Z6C5092-1024x681.png 1024w, https:\/\/regnumchristi.org\/wp-content\/uploads\/2020\/11\/2020-11-21__Z6C5092-768x511.png 768w, https:\/\/regnumchristi.org\/wp-content\/uploads\/2020\/11\/2020-11-21__Z6C5092-1536x1022.png 1536w, https:\/\/regnumchristi.org\/wp-content\/uploads\/2020\/11\/2020-11-21__Z6C5092.png 1980w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>Su excelencia reverend\u00edsima Mons. Pedro Pablo Elizondo C\u00e1rdenas obispo de Canc\u00fan-Chetumal. Su Santidad saluda cordialmente a vuestra excelencia, al obispo prelado em\u00e9rito, as\u00ed como clero, consagrados y fieles laicos con motivo del L aniversario de la erecci\u00f3n can\u00f3nica de esa jurisdicci\u00f3n eclesi\u00e1stica y de su elevaci\u00f3n a di\u00f3cesis.<\/p>\n<p>El Santo Padre se une espiritualmente a la ferviente acci\u00f3n de gracias al Se\u00f1or, por los abundantes frutos conseguidos a lo largo de este tiempo y los anima a tener presente el amor misericordioso de N. S. Jesucristo de quien brota toda verdad, bondad y belleza, para que todos los que forman parte de esa Iglesia particular prosigan incansablemente su actividad evangelizadora llevando a todos la alegr\u00eda del Evangelio y el consuelo de la caridad fraterna, particularmente a los m\u00e1s pobres y necesitados. Con estos sentimientos el Papa Francisco a la vez que suplica que recen por \u00e9l y por su servicio al santo pueblo de Dios, invocando a la maternal protecci\u00f3n de la B. V. de Guadalupe sobre todos los hijos e hijas de esa di\u00f3cesis, en parte complacido la implorada bendici\u00f3n apost\u00f3lica como prenda de copiosos dones celestiales.<\/p>\n<p>Card. Pietro Parolin. Secretario de estado. Desde El Vaticano, 21 de noviembre de 2020.<\/p>\n<h3>Carta del Santa Padre de elevaci\u00f3n de la Prelatura Canc\u00fan-Chetumal a di\u00f3cesis y de confirmaci\u00f3n de Mons. Pedro Pablo Elizondo C\u00e1rdenas como primer obispo diocesano<\/h3>\n<p><em>(Versi\u00f3n traducida de lat\u00edn al espa\u00f1ol)<\/em><\/p>\n<p><a href=\"https:\/\/regnumchristi.org\/wp-content\/uploads\/2020\/11\/2020-11-21__Z6C5105.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium wp-image-28486\" src=\"https:\/\/regnumchristi.org\/wp-content\/uploads\/2020\/11\/2020-11-21__Z6C5105-300x200.png\" alt=\"Se celebra la elevaci\u00f3n de la Prelatura Canc\u00fan-Chetumal a Di\u00f3cesis\" width=\"300\" height=\"200\" srcset=\"https:\/\/regnumchristi.org\/wp-content\/uploads\/2020\/11\/2020-11-21__Z6C5105-300x200.png 300w, https:\/\/regnumchristi.org\/wp-content\/uploads\/2020\/11\/2020-11-21__Z6C5105-1024x681.png 1024w, https:\/\/regnumchristi.org\/wp-content\/uploads\/2020\/11\/2020-11-21__Z6C5105-768x511.png 768w, https:\/\/regnumchristi.org\/wp-content\/uploads\/2020\/11\/2020-11-21__Z6C5105-1536x1022.png 1536w, https:\/\/regnumchristi.org\/wp-content\/uploads\/2020\/11\/2020-11-21__Z6C5105.png 1980w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>Francisco, obispo, siervo de los siervos de Dios para perpetua memoria. Habiendo crecido admirablemente con manifiesta bendici\u00f3n de Dios en n\u00famero y en deseo espiritual el pueblo de la prelatura territorial de Canc\u00fan Chetumal, despu\u00e9s de casi 50 a\u00f1os desde su erecci\u00f3n. El venerable hermano Pedro Pablo Elizondo C\u00e1rdenas Obispo prelado, habiendo escuchado a la Conferencia de los Obispos en M\u00e9xico, pidi\u00f3 hace poco a la Sede apost\u00f3lica que esta sede prelaticia fuera elevada al grado y dignidad de di\u00f3cesis, por eso contando de antemano con el voto favorable del venerable Franco Coppola, arzobispo titular de Vinda y nuncio Apost\u00f3lico en M\u00e9xico, con el consejo de la Congregaci\u00f3n para los Obispos, hemos determinado acoger de buen grado esta iniciativa que ser\u00e1 de mucho provecho para el futuro bien espiritual de las almas. As\u00ed pues, en virtud de la plenitud de nuestra potestad apost\u00f3lica elevamos al grado de di\u00f3cesis a la Prelatura Territorial de Canc\u00fan-Chetumal conservando el mismo nombre y territorio. Establecemos la sede de esta di\u00f3cesis en la misma ciudad donde ha estado hasta el presente y elevamos su templo al grado y dignidad de Iglesia Catedral, concedi\u00e9ndole los debidos derechos y privilegios, determinamos que la nueva comunidad diocesana sea sufrag\u00e1nea de la iglesia metropolitana de Yucat\u00e1n y que el obispo <em>pro tempore<\/em> de la nueva di\u00f3cesis quede sometido a la jurisdicci\u00f3n del arzobispo de dicha iglesia metropolitana. Las restantes disposiciones c\u00famplanse de acuerdo con las normas del derecho can\u00f3nico. Adem\u00e1s, confirmamos como ordinario y pastor de la nueva di\u00f3cesis de Canc\u00fan-Chetumal al venerable hermano Pedro Pablo Elizondo C\u00e1rdenas, L.C. quien hasta el presenta ha sido obispo prelado de esta circunscripci\u00f3n. Para realizar todas estas disposiciones nombramos al venerable hermano Franco Coppola, arzobispo titular de Vinda y nuncio apost\u00f3lico en M\u00e9xico, otorg\u00e1ndole todas las necesarias y oportunas facultades, incluso de subdelegar para este acto a cualquier ministro constituido en la dignidad eclesi\u00e1stica, con la obligaci\u00f3n de remitir a la Congregaci\u00f3n para los Obispos el documento aut\u00e9ntico del cumplimiento de lo mandado. Mandamos finalmente que esta constituci\u00f3n nuestra se mantenga ahora y en el porvenir sin que nada obste. Dado en Roma en el Laterano el 15 de febrero del a\u00f1o del Se\u00f1or de 2020, s\u00e9ptimo de nuestro pontificado. Rubrican esta bula el cardenal Pietro Parolin, secretario de estado. Cardenal Marc Ouellet, prefecto de la Congregaci\u00f3n para los Obispos.<\/p>\n<h3>Homil\u00eda del nuncio apost\u00f3lico, Mons. Franco Coppola<\/h3>\n<p><a href=\"https:\/\/regnumchristi.org\/wp-content\/uploads\/2020\/11\/2020-11-21__Z6C5171.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-28487\" src=\"https:\/\/regnumchristi.org\/wp-content\/uploads\/2020\/11\/2020-11-21__Z6C5171-300x200.png\" alt=\"Se celebra la elevaci\u00f3n de la Prelatura Canc\u00fan-Chetumal a Di\u00f3cesis\" width=\"300\" height=\"200\" srcset=\"https:\/\/regnumchristi.org\/wp-content\/uploads\/2020\/11\/2020-11-21__Z6C5171-300x200.png 300w, https:\/\/regnumchristi.org\/wp-content\/uploads\/2020\/11\/2020-11-21__Z6C5171-1024x681.png 1024w, https:\/\/regnumchristi.org\/wp-content\/uploads\/2020\/11\/2020-11-21__Z6C5171-768x511.png 768w, https:\/\/regnumchristi.org\/wp-content\/uploads\/2020\/11\/2020-11-21__Z6C5171-1536x1022.png 1536w, https:\/\/regnumchristi.org\/wp-content\/uploads\/2020\/11\/2020-11-21__Z6C5171.png 1980w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>Quiero a\u00f1adir mis felicitaciones por el cumplimiento de una etapa, claro que estamos hablando de una etapa. Los tiempos de la Iglesia son un poco m\u00e1s largos, entonces 50 a\u00f1os sigue siendo un ni\u00f1o, puede caminar ya con sus pies, pero tiene mucho que aprender.<\/p>\n<p>Hemos escuchado en la primera lectura el ap\u00f3stol Pedro saliendo del cen\u00e1culo de Pentecost\u00e9s se dirige a la gente que hab\u00eda visto algo extra\u00f1o que pasaba y les dirige la palabra: todo Israel este cierto de que al mismo Jes\u00fas de que vosotros crucificasteis Dios lo ha constituido Se\u00f1or y Mes\u00edas. Esas palabras son siempre verdaderas es por eso que la Iglesia todas las misas inician pidi\u00e9ndonos el pedir perd\u00f3n, a nosotros que estamos acostumbrados a tener la culpa a los dem\u00e1s, nunca mi culpa, la Iglesia nos ense\u00f1a a decir por mi culpa por mi cupla por mi gran culpa, soy yo que ha participado en la crucifixi\u00f3n de Jes\u00fas.<\/p>\n<p>Me dec\u00eda monse\u00f1or que cuando lleg\u00f3 a la Prelatura hab\u00eda 5 parroquias, ahora son casi 70, un gran trabajo. Yo no conozco Canc\u00fan, s\u00ed me han llevado a conocer realidades muy lindas como el seminario, el santuario de la Virgen Desatanudos, caminando he visto cosas muy bonitas, modernos, hasta lujosos. Me doy cuenta de que tambi\u00e9n hay otras colonias con casas m\u00e1s peque\u00f1as, me cuentan que hay lugares donde la gente llega y hace casas con estructuras de cart\u00f3n. Tenemos mucho que trabajar.<\/p>\n<p><a href=\"https:\/\/regnumchristi.org\/wp-content\/uploads\/2020\/11\/2020-11-21__Z6C5325.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium wp-image-28488\" src=\"https:\/\/regnumchristi.org\/wp-content\/uploads\/2020\/11\/2020-11-21__Z6C5325-300x200.png\" alt=\"Se celebra la elevaci\u00f3n de la Prelatura Canc\u00fan-Chetumal a Di\u00f3cesis\" width=\"300\" height=\"200\" srcset=\"https:\/\/regnumchristi.org\/wp-content\/uploads\/2020\/11\/2020-11-21__Z6C5325-300x200.png 300w, https:\/\/regnumchristi.org\/wp-content\/uploads\/2020\/11\/2020-11-21__Z6C5325-1024x681.png 1024w, https:\/\/regnumchristi.org\/wp-content\/uploads\/2020\/11\/2020-11-21__Z6C5325-768x511.png 768w, https:\/\/regnumchristi.org\/wp-content\/uploads\/2020\/11\/2020-11-21__Z6C5325-1536x1022.png 1536w, https:\/\/regnumchristi.org\/wp-content\/uploads\/2020\/11\/2020-11-21__Z6C5325.png 1980w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>Aqu\u00ed hay madres y padres de familia, pi\u00e9nsenlo: \u00bfAceptar\u00edan ustedes padres de familia que unos de sus hijos est\u00e9n viviendo lujosamente y otros padeciendo de hambre? No se puede soportar, pues son mis hijos, esto hace parte de la crucifixi\u00f3n del Se\u00f1or, esto no se puede cambiar de un d\u00eda al otro, pero tenemos que trabajar para ser un ejemplo de una Iglesia que es familia de los hijos de Dios, todos hermanos. Hace poco el Papa ha escrito su carta enc\u00edclica \u201cTodos hermanos\u201d, desafortunadamente este concepto no resulta tan evidente, tenemos que trabajar, claro que no es un problema de Canc\u00fan sino de la Iglesia en todo el mundo, todav\u00eda hoy participamos de la crucifixi\u00f3n del Se\u00f1or de esta manera. Pedro nos anuncia la Resurrecci\u00f3n, el Se\u00f1or no se ha ofendido, ha resucitado, es una fuerza nueva que entra al mundo, y que quiere regalarnos una fuerza nueva a trav\u00e9s de esta etapa que nos regala. Como en el ejemplo que mencion\u00e9 al inicio del ni\u00f1o, que hace un paso, pero que le falta mucho para graduarse, ya ha caminado bien, seguimos adelante, pero \u00bfC\u00f3mo?<\/p>\n<p>El ap\u00f3stol Pedro nos sugiere algo en la segunda lectura: Convi\u00e9rtanse en modelo de reba\u00f1o. Buena sugerencia que nos dice a todos: Obispos, sacerdotes, pero tambi\u00e9n padres de familia, somos muy capaces de hablar, pero Pedro lo dice, hay que ser modelos, lo que digo lo tengo que encarnar y vivir yo primero, sino no sirve. Vivimos en un tiempo donde esto vale m\u00e1s que nunca, hab\u00eda un tiempo de sentido de respeto a la autoridad eclesial y pol\u00edtica donde uno escuchaba y obedec\u00eda, pero ahora no. Si la palabra no corresponde a los hechos no nos siguen. Si t\u00fa no crees en tu palabra yo no tendr\u00eda motivo para creerte. Para nosotros obispos, sacerdotes, pero tambi\u00e9n padres de familia, todos los que tenemos una responsabilidad frente a los dem\u00e1s, las palabras sirven, pero s\u00f3lo si va acompa\u00f1ado por el ejemplo. Esto lo hab\u00eda dicho ya hace mucho tiempo un papa para muchos de ustedes no conocido por ser ustedes j\u00f3venes, es Pablo VI cuando dijo que nuestro tiempo es un tiempo que no acepta m\u00e1s maestros, o si lo acepta es porque son testigos, porque viven lo que dicen, tenemos que vivir lo que decimos, poro \u00bfvivir qu\u00e9?<\/p>\n<p><a href=\"https:\/\/regnumchristi.org\/wp-content\/uploads\/2020\/11\/2020-11-21__Z6C5340.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-28489\" src=\"https:\/\/regnumchristi.org\/wp-content\/uploads\/2020\/11\/2020-11-21__Z6C5340-300x200.png\" alt=\"Se celebra la elevaci\u00f3n de la Prelatura Canc\u00fan-Chetumal a Di\u00f3cesis\" width=\"300\" height=\"200\" srcset=\"https:\/\/regnumchristi.org\/wp-content\/uploads\/2020\/11\/2020-11-21__Z6C5340-300x200.png 300w, https:\/\/regnumchristi.org\/wp-content\/uploads\/2020\/11\/2020-11-21__Z6C5340-1024x681.png 1024w, https:\/\/regnumchristi.org\/wp-content\/uploads\/2020\/11\/2020-11-21__Z6C5340-768x511.png 768w, https:\/\/regnumchristi.org\/wp-content\/uploads\/2020\/11\/2020-11-21__Z6C5340-1536x1022.png 1536w, https:\/\/regnumchristi.org\/wp-content\/uploads\/2020\/11\/2020-11-21__Z6C5340.png 1980w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>Jes\u00fas hablando de s\u00ed como el Buen Pastor como la puerta por donde pasan las ovejas, concluye el Evangelio de hoy diciendo yo he venido para que tengan vida y vida en abundancia. Esto es lo que yo tengo que decir, como obispo, sacerdote o como padre de familia. Vivimos en un tiempo en el que vivimos lo contrario, en el que cada uno piensa para s\u00ed, por lo que le falta, no. Jes\u00fas no ha venido por esto, podr\u00eda haberse quedado muy tranquilo en el para\u00edso, pero no quiso. Vino en medio de nosotros para que tengamos vida, este es el testimonio cristiano. En esto tenemos que salvarnos de esta generaci\u00f3n perversa como dice el ap\u00f3stol San Pedro en la primera lectura, una generaci\u00f3n que piensa en s\u00ed mismo, todo lo contrario de la fe cristiana que creemos en un Dios que se ha entregado a s\u00ed mismo por nosotros. Esto tiene que ser mi vida, entregado a la gente que me ha sido confiada. Si soy obispo por mis sacerdotes; si soy sacerdote por mis fieles; si soy pap\u00e1 o mam\u00e1 mis hijos. Mi vida entregada por ellos, no buscando mis satisfacciones, no, esto es lo contrario de Jes\u00fas, \u00c9l se ha entregado hasta dar la vida, en el altar celebramos el sacrificio del Se\u00f1or, y en el altar la Iglesia nos ense\u00f1a a ofrecernos.<\/p>\n<p>En Italia hay una broma, se dice que el queso suave \u201c<em>Formaggino<\/em>\u201d que se da a los ni\u00f1os se llama m\u00edo, porque el ni\u00f1o piensa en clave de que es m\u00edo en sobrevivir, tiene que pensar en s\u00ed mismo, pero conforme uno crece tiene que pensar en los dem\u00e1s. Somos una Iglesia joven, somos llamados a crecer, a entregar nuestra vida. A hacer entrega de nuestra vida.<\/p>\n<p>Si pensamos en las condiciones como se encontraba el territorio hace 50 a\u00f1os como ha cambiado, cuanto se ha trabajado. Pero ahora tenemos que vencer el esp\u00edritu del mundo que nos hace concentrarnos en nosotros mismos, lo que a m\u00ed me gusta. Ser cristianos significa ser disc\u00edpulos de Jes\u00fas que vino a darnos vida, para que tengamos vida, hacemos de esto nuestro lema para que todos nuestros hermanos y hermanas tengan una vida digna.<\/p>\n<h5><em>Redacci\u00f3n: H. Jes\u00fas Silva Sosa, LC<\/em><br \/>\n<em>Fotograf\u00eda: P. Eduardo Linares, LC<\/em><\/h5>\n","protected":false},"excerpt":{"rendered":"<p> [&hellip;]<\/p>\n","protected":false},"author":49,"featured_media":28481,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"_daextrevop_audio_file_creation_date":"","_daextrevop_text_to_speech":"","_daextrevop_document_type":"","footnotes":""},"categories":[3031,1687],"tags":[1023,2624,3099],"class_list":["post-92769","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-destacadas","category-noticias","tag-50-aniversario","tag-diocesis-de-cancun-chetumal","tag-nuncio"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Se celebra la elevaci\u00f3n de la Prelatura Canc\u00fan-Chetumal a Di\u00f3cesis<\/title>\n<meta name=\"description\" content=\"El s\u00e1bado 21 de noviembre el nuncio apost\u00f3lico en M\u00e9xico, Mons. Franco Coppola elev\u00f3 la antigua Prelatura de Canc\u00fan-Chetumal a Di\u00f3cesis.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/regnumchristi.org\/es\/prelatura-cancun-chetumal-a-diocesis\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Se celebra la elevaci\u00f3n de la Prelatura Canc\u00fan-Chetumal a Di\u00f3cesis\" \/>\n<meta property=\"og:description\" content=\"El s\u00e1bado 21 de noviembre el nuncio apost\u00f3lico en M\u00e9xico, Mons. Franco Coppola elev\u00f3 la antigua Prelatura de Canc\u00fan-Chetumal a Di\u00f3cesis.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/regnumchristi.org\/es\/prelatura-cancun-chetumal-a-diocesis\/\" \/>\n<meta property=\"og:site_name\" content=\"Regnum Christi Internacional\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/RegnumChristiEspana\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-11-23T15:47:39+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-07-14T16:22:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/regnumchristi.org\/wp-content\/uploads\/2020\/11\/2020-11-21__PLN5698-1024x576.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"576\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Autores varios\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Autores varios\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"12 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/prelatura-cancun-chetumal-a-diocesis\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/prelatura-cancun-chetumal-a-diocesis\\\/\"},\"author\":{\"name\":\"Autores varios\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#\\\/schema\\\/person\\\/73f2e414269cfbf8edecc2fd90af81f2\"},\"headline\":\"Se celebra la elevaci\u00f3n de la Prelatura Canc\u00fan-Chetumal a Di\u00f3cesis\",\"datePublished\":\"2020-11-23T15:47:39+00:00\",\"dateModified\":\"2023-07-14T16:22:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/prelatura-cancun-chetumal-a-diocesis\\\/\"},\"wordCount\":2502,\"publisher\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/prelatura-cancun-chetumal-a-diocesis\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/regnumchristi.org\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/2020-11-21__PLN5698.png\",\"keywords\":[\"50 aniversario\",\"Di\u00f3cesis de Canc\u00fan-Chetumal\",\"Nuncio\"],\"articleSection\":[\"Destacadas\",\"Noticias\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/prelatura-cancun-chetumal-a-diocesis\\\/\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/prelatura-cancun-chetumal-a-diocesis\\\/\",\"name\":\"Se celebra la elevaci\u00f3n de la Prelatura Canc\u00fan-Chetumal a Di\u00f3cesis\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/prelatura-cancun-chetumal-a-diocesis\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/prelatura-cancun-chetumal-a-diocesis\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/regnumchristi.org\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/2020-11-21__PLN5698.png\",\"datePublished\":\"2020-11-23T15:47:39+00:00\",\"dateModified\":\"2023-07-14T16:22:14+00:00\",\"description\":\"El s\u00e1bado 21 de noviembre el nuncio apost\u00f3lico en M\u00e9xico, Mons. Franco Coppola elev\u00f3 la antigua Prelatura de Canc\u00fan-Chetumal a Di\u00f3cesis.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/prelatura-cancun-chetumal-a-diocesis\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/regnumchristi.org\\\/prelatura-cancun-chetumal-a-diocesis\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/prelatura-cancun-chetumal-a-diocesis\\\/#primaryimage\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/2020-11-21__PLN5698.png\",\"contentUrl\":\"https:\\\/\\\/regnumchristi.org\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/2020-11-21__PLN5698.png\",\"width\":1980,\"height\":1113,\"caption\":\"Se celebra la elevaci\u00f3n de la Prelatura Canc\u00fan-Chetumal a Di\u00f3cesis\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/prelatura-cancun-chetumal-a-diocesis\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/regnumchristi.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Se celebra la elevaci\u00f3n de la Prelatura Canc\u00fan-Chetumal a Di\u00f3cesis\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#website\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/\",\"name\":\"Regnum Christi Internacional\",\"description\":\"El Regnum Christi es una realidad de la Iglesia cat\u00f3lica cuya misi\u00f3n es hacer presente el Reino de Cristo\",\"publisher\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/regnumchristi.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#organization\",\"name\":\"Regnum Christi Internacional\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/regnumchristi.es\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Favicon-RC_ligh-cuadrado.png\",\"contentUrl\":\"https:\\\/\\\/regnumchristi.es\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Favicon-RC_ligh-cuadrado.png\",\"width\":1080,\"height\":1080,\"caption\":\"Regnum Christi Internacional\"},\"image\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/RegnumChristiEspana\\\/\",\"https:\\\/\\\/x.com\\\/rc_espana\",\"https:\\\/\\\/www.instagram.com\\\/rc_espana\\\/\",\"https:\\\/\\\/es.linkedin.com\\\/company\\\/regnumchristiespaa\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#\\\/schema\\\/person\\\/73f2e414269cfbf8edecc2fd90af81f2\",\"name\":\"Autores varios\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/es\\\/author\\\/jarceocaesc-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Se celebra la elevaci\u00f3n de la Prelatura Canc\u00fan-Chetumal a Di\u00f3cesis","description":"El s\u00e1bado 21 de noviembre el nuncio apost\u00f3lico en M\u00e9xico, Mons. Franco Coppola elev\u00f3 la antigua Prelatura de Canc\u00fan-Chetumal a Di\u00f3cesis.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/regnumchristi.org\/es\/prelatura-cancun-chetumal-a-diocesis\/","og_locale":"es_MX","og_type":"article","og_title":"Se celebra la elevaci\u00f3n de la Prelatura Canc\u00fan-Chetumal a Di\u00f3cesis","og_description":"El s\u00e1bado 21 de noviembre el nuncio apost\u00f3lico en M\u00e9xico, Mons. Franco Coppola elev\u00f3 la antigua Prelatura de Canc\u00fan-Chetumal a Di\u00f3cesis.","og_url":"https:\/\/regnumchristi.org\/es\/prelatura-cancun-chetumal-a-diocesis\/","og_site_name":"Regnum Christi Internacional","article_publisher":"https:\/\/www.facebook.com\/RegnumChristiEspana\/","article_published_time":"2020-11-23T15:47:39+00:00","article_modified_time":"2023-07-14T16:22:14+00:00","og_image":[{"width":1024,"height":576,"url":"https:\/\/regnumchristi.org\/wp-content\/uploads\/2020\/11\/2020-11-21__PLN5698-1024x576.png","type":"image\/png"}],"author":"Autores varios","twitter_misc":{"Escrito por":"Autores varios","Tiempo de lectura":"12 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/regnumchristi.org\/prelatura-cancun-chetumal-a-diocesis\/#article","isPartOf":{"@id":"https:\/\/regnumchristi.org\/prelatura-cancun-chetumal-a-diocesis\/"},"author":{"name":"Autores varios","@id":"https:\/\/regnumchristi.org\/#\/schema\/person\/73f2e414269cfbf8edecc2fd90af81f2"},"headline":"Se celebra la elevaci\u00f3n de la Prelatura Canc\u00fan-Chetumal a Di\u00f3cesis","datePublished":"2020-11-23T15:47:39+00:00","dateModified":"2023-07-14T16:22:14+00:00","mainEntityOfPage":{"@id":"https:\/\/regnumchristi.org\/prelatura-cancun-chetumal-a-diocesis\/"},"wordCount":2502,"publisher":{"@id":"https:\/\/regnumchristi.org\/#organization"},"image":{"@id":"https:\/\/regnumchristi.org\/prelatura-cancun-chetumal-a-diocesis\/#primaryimage"},"thumbnailUrl":"https:\/\/regnumchristi.org\/wp-content\/uploads\/2020\/11\/2020-11-21__PLN5698.png","keywords":["50 aniversario","Di\u00f3cesis de Canc\u00fan-Chetumal","Nuncio"],"articleSection":["Destacadas","Noticias"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/regnumchristi.org\/prelatura-cancun-chetumal-a-diocesis\/","url":"https:\/\/regnumchristi.org\/prelatura-cancun-chetumal-a-diocesis\/","name":"Se celebra la elevaci\u00f3n de la Prelatura Canc\u00fan-Chetumal a Di\u00f3cesis","isPartOf":{"@id":"https:\/\/regnumchristi.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/regnumchristi.org\/prelatura-cancun-chetumal-a-diocesis\/#primaryimage"},"image":{"@id":"https:\/\/regnumchristi.org\/prelatura-cancun-chetumal-a-diocesis\/#primaryimage"},"thumbnailUrl":"https:\/\/regnumchristi.org\/wp-content\/uploads\/2020\/11\/2020-11-21__PLN5698.png","datePublished":"2020-11-23T15:47:39+00:00","dateModified":"2023-07-14T16:22:14+00:00","description":"El s\u00e1bado 21 de noviembre el nuncio apost\u00f3lico en M\u00e9xico, Mons. Franco Coppola elev\u00f3 la antigua Prelatura de Canc\u00fan-Chetumal a Di\u00f3cesis.","breadcrumb":{"@id":"https:\/\/regnumchristi.org\/prelatura-cancun-chetumal-a-diocesis\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/regnumchristi.org\/prelatura-cancun-chetumal-a-diocesis\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/regnumchristi.org\/prelatura-cancun-chetumal-a-diocesis\/#primaryimage","url":"https:\/\/regnumchristi.org\/wp-content\/uploads\/2020\/11\/2020-11-21__PLN5698.png","contentUrl":"https:\/\/regnumchristi.org\/wp-content\/uploads\/2020\/11\/2020-11-21__PLN5698.png","width":1980,"height":1113,"caption":"Se celebra la elevaci\u00f3n de la Prelatura Canc\u00fan-Chetumal a Di\u00f3cesis"},{"@type":"BreadcrumbList","@id":"https:\/\/regnumchristi.org\/prelatura-cancun-chetumal-a-diocesis\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/regnumchristi.org\/es\/"},{"@type":"ListItem","position":2,"name":"Se celebra la elevaci\u00f3n de la Prelatura Canc\u00fan-Chetumal a Di\u00f3cesis"}]},{"@type":"WebSite","@id":"https:\/\/regnumchristi.org\/#website","url":"https:\/\/regnumchristi.org\/","name":"Regnum Christi Internacional","description":"El Regnum Christi es una realidad de la Iglesia cat\u00f3lica cuya misi\u00f3n es hacer presente el Reino de Cristo","publisher":{"@id":"https:\/\/regnumchristi.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/regnumchristi.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/regnumchristi.org\/#organization","name":"Regnum Christi Internacional","url":"https:\/\/regnumchristi.org\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/regnumchristi.org\/#\/schema\/logo\/image\/","url":"https:\/\/regnumchristi.es\/wp-content\/uploads\/2023\/03\/Favicon-RC_ligh-cuadrado.png","contentUrl":"https:\/\/regnumchristi.es\/wp-content\/uploads\/2023\/03\/Favicon-RC_ligh-cuadrado.png","width":1080,"height":1080,"caption":"Regnum Christi Internacional"},"image":{"@id":"https:\/\/regnumchristi.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/RegnumChristiEspana\/","https:\/\/x.com\/rc_espana","https:\/\/www.instagram.com\/rc_espana\/","https:\/\/es.linkedin.com\/company\/regnumchristiespaa"]},{"@type":"Person","@id":"https:\/\/regnumchristi.org\/#\/schema\/person\/73f2e414269cfbf8edecc2fd90af81f2","name":"Autores varios","url":"https:\/\/regnumchristi.org\/es\/author\/jarceocaesc-com\/"}]}},"_links":{"self":[{"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/posts\/92769","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/users\/49"}],"replies":[{"embeddable":true,"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/comments?post=92769"}],"version-history":[{"count":1,"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/posts\/92769\/revisions"}],"predecessor-version":[{"id":92781,"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/posts\/92769\/revisions\/92781"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/media\/28481"}],"wp:attachment":[{"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/media?parent=92769"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/categories?post=92769"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/tags?post=92769"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}