{"id":93235,"date":"2020-04-29T00:01:08","date_gmt":"2020-04-29T05:01:08","guid":{"rendered":"https:\/\/www.regnumchristi.org\/es\/?p=25897"},"modified":"2020-04-29T00:01:08","modified_gmt":"2020-04-29T05:01:08","slug":"jueves-30-de-abril-de-2020-el-alimento-de-vida","status":"publish","type":"post","link":"https:\/\/regnumchristi.org\/es\/jueves-30-de-abril-de-2020-el-alimento-de-vida\/","title":{"rendered":"Jueves 30 de abril de 2020 &#8211; El alimento de vida."},"content":{"rendered":"<p>H. Leonel de las Cuevas, L.C.<br \/>\nEn el nombre del Padre y del Hijo y del Esp\u00edritu Santo. Am\u00e9n.<br \/>\nCristo, Rey nuestro. \u00a1Venga tu Reino!<\/p>\n<p><strong>Oraci\u00f3n preparatoria\u00a0<\/strong><em>(para ponerme en presencia de Dios)<\/em><br \/>\nSe\u00f1or, gracias por acordarte siempre de m\u00ed, por regalarme un nuevo d\u00eda, y por estar conmigo acompa\u00f1\u00e1ndome en cada paso que doy. Tu presencia y compa\u00f1\u00eda son el regalo m\u00e1s grande que puedes darme. Contigo nada me falta, jam\u00e1s permitas que me separe de Ti. Yo quiero estar siempre a tu lado.<\/p>\n<p><strong>Evangelio del d\u00eda\u00a0<\/strong><em>(para orientar tu meditaci\u00f3n)<\/em><br \/>\nDel santo Evangelio seg\u00fan san Juan 6, 44-51<br \/>\nEn aquel tiempo, Jes\u00fas dijo a los jud\u00edos: \u00a8Nadie puede venir a m\u00ed, si no lo atrae el Padre, que me ha enviado; y a ese yo lo resucitar\u00e9 el \u00faltimo d\u00eda. Est\u00e1 escrito en los profetas:\u00a0<em>Todos ser\u00e1n disc\u00edpulos de Dios.\u00a0<\/em>Todo aquel que escucha al Padre y aprende de \u00e9l, se acerca a m\u00ed. No es que alguien haya visto al Padre, fuera de aqu\u00e9l que procede de Dios. Ese s\u00ed ha visto al Padre.<br \/>\nYo les aseguro: el que cree en m\u00ed, tiene vida eterna. Yo soy el pan de la vida. Sus padres comieron el man\u00e1 en el desierto y sin embargo, murieron. Este es el pan que ha bajado del cielo para que, quien lo coma, no muera. Yo soy el pan vivo que ha bajado del cielo; el que coma de este pan vivir\u00e1 para siempre, y el pan que yo les voy a dar es mi carne para que el mundo tenga vida\u00a8.<br \/>\nPalabra del Se\u00f1or.<\/p>\n<p><strong>Medita lo que Dios te dice en el Evangelio<\/strong><\/p>\n<p>El Antiguo Testamento nos cuenta c\u00f3mo los jud\u00edos se quejaron ante Mois\u00e9s, en el desierto, por la falta de pan y alimento. Dios, en su bondad y amor, les provey\u00f3 el man\u00e1 para que pudieran tener el pan de cada d\u00eda. Pero Dios es un Padre bueno y ten\u00eda algo, todav\u00eda mejor, preparado. Sabe que no solo del pan material vive el hombre, y, aunque es importante, su saciedad es pasajera. Dios tiene algo para dar que es mucho m\u00e1s valioso que eso, o que cualquier otro don material. Su don m\u00e1s valioso, el verdadero pan, es el don de s\u00ed mismo que se dona totalmente a nosotros para entrar en nuestra vida y quedarse en ella, en total uni\u00f3n de amor con \u00c9l. Dios no es un Padre que regala solamente \u00abcosas\u00bb, es un Padre que nos da toda su persona, todo su amor y toda su compa\u00f1\u00eda. Es un Padre que quiere estar siempre ah\u00ed, a nuestro lado.<\/p>\n<p>Por eso, la Eucarist\u00eda es el regalo m\u00e1s valioso que Dios nos ha dejado, pues no se trata de \u00abalgo\u00bb, se trata de \u00abAlguien\u00bb. Se trata de estar cara a cara, en un momento de total uni\u00f3n, con quien m\u00e1s nos ama y nos protege. Pidamos para que podamos siempre saber disfrutar de la Eucarist\u00eda. Que podamos disfrutar de la presencia de Aquel para quien estar con cada uno de nosotros es tan importante.<\/p>\n<p>Cristo es el pan de la vida. \u00danico alimento capaz de saciarnos y de transformar nuestras vidas haci\u00e9ndolas, poco a poco, cada vez m\u00e1s plenas. Solo unidos a Dios comenzamos a vivir la verdadera vida.<\/p>\n<p>\u00abEl pan que pedimos hoy, es tambi\u00e9n el pan del que muchos carecen cada d\u00eda, mientras que unos pocos poseen lo superfluo. El Padrenuestro no es una oraci\u00f3n que tranquiliza, sino un grito ante las carest\u00edas de amor de nuestro tiempo, ante el individualismo y la indiferencia que profanan tu nombre, Padre. Ay\u00fadanos a tener hambre de darnos. Recu\u00e9rdanos, cada vez que rezamos, que para vivir no tenemos necesidad de conservarnos, sino de partirnos; de compartir, en vez de atesorar; de sustentar a los dem\u00e1s, en lugar de saciarnos a nosotros mismos, porque el bienestar es tal si pertenece \u00fanicamente a todos.\u00bb<br \/>\n(Homil\u00eda de S.S. Francisco, 31 de mayo de 2019).<\/p>\n<p><strong>Di\u00e1logo con Cristo<\/strong><br \/>\n<em>\u00c9sta es la parte m\u00e1s importante de tu oraci\u00f3n, disponte a platicar con mucho amor con Aquel que te ama.<\/em><\/p>\n<p><strong>Prop\u00f3sito<\/strong><br \/>\n<em>Proponte uno personal. El que m\u00e1s amor implique en respuesta al Amado\u2026 o, si crees que es lo que Dios te pide, vive lo que se te sugiere a continuaci\u00f3n.<\/em><br \/>\nHacer memoria de aquellos momentos de intimidad que he pasado con Cristo Eucarist\u00eda, agradec\u00e9rselos, y proponerme firmemente acudir a la comuni\u00f3n la pr\u00f3xima vez que tenga la oportunidad.<\/p>\n<p><strong>Despedida<\/strong><br \/>\nTe damos gracias, Se\u00f1or, por todos tus beneficios, a Ti que vives y reinas por los siglos de los siglos.<br \/>\nAm\u00e9n.<\/p>\n<p>\u00a1Cristo, Rey nuestro!<br \/>\n\u00a1Venga tu Reino!<\/p>\n<p>Virgen prudent\u00edsima, Mar\u00eda, Madre de la Iglesia.<br \/>\nRuega por nosotros.<\/p>\n<p>En el nombre del Padre y del Hijo y del Esp\u00edritu Santo. Am\u00e9n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p> [&hellip;]<\/p>\n","protected":false},"author":33,"featured_media":25899,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"_daextrevop_audio_file_creation_date":"","_daextrevop_text_to_speech":"","_daextrevop_document_type":"","footnotes":""},"categories":[3164],"tags":[],"class_list":["post-93235","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-meditacion-del-dia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Jueves 30 de abril de 2020 - El alimento de vida. - Regnum Christi Internacional<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/regnumchristi.org\/es\/jueves-30-de-abril-de-2020-el-alimento-de-vida\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Jueves 30 de abril de 2020 - El alimento de vida. - Regnum Christi Internacional\" \/>\n<meta property=\"og:description\" content=\"[&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/regnumchristi.org\/es\/jueves-30-de-abril-de-2020-el-alimento-de-vida\/\" \/>\n<meta property=\"og:site_name\" content=\"Regnum Christi Internacional\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/RegnumChristiEspana\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-04-29T05:01:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/regnumchristi.org\/wp-content\/uploads\/2020\/04\/300420.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"628\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Mar Morales\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mar Morales\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/jueves-30-de-abril-de-2020-el-alimento-de-vida\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/jueves-30-de-abril-de-2020-el-alimento-de-vida\\\/\"},\"author\":{\"name\":\"Mar Morales\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#\\\/schema\\\/person\\\/390cded3fbd2800d0daee38acaecd350\"},\"headline\":\"Jueves 30 de abril de 2020 &#8211; El alimento de vida.\",\"datePublished\":\"2020-04-29T05:01:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/jueves-30-de-abril-de-2020-el-alimento-de-vida\\\/\"},\"wordCount\":853,\"publisher\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/jueves-30-de-abril-de-2020-el-alimento-de-vida\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/regnumchristi.org\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/300420.jpg\",\"articleSection\":[\"Meditaci\u00f3n del d\u00eda\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/jueves-30-de-abril-de-2020-el-alimento-de-vida\\\/\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/jueves-30-de-abril-de-2020-el-alimento-de-vida\\\/\",\"name\":\"Jueves 30 de abril de 2020 - El alimento de vida. - Regnum Christi Internacional\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/jueves-30-de-abril-de-2020-el-alimento-de-vida\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/jueves-30-de-abril-de-2020-el-alimento-de-vida\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/regnumchristi.org\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/300420.jpg\",\"datePublished\":\"2020-04-29T05:01:08+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/jueves-30-de-abril-de-2020-el-alimento-de-vida\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/regnumchristi.org\\\/jueves-30-de-abril-de-2020-el-alimento-de-vida\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/jueves-30-de-abril-de-2020-el-alimento-de-vida\\\/#primaryimage\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/300420.jpg\",\"contentUrl\":\"https:\\\/\\\/regnumchristi.org\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/300420.jpg\",\"width\":1200,\"height\":628,\"caption\":\"eucaristia\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/jueves-30-de-abril-de-2020-el-alimento-de-vida\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/regnumchristi.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Jueves 30 de abril de 2020 &#8211; El alimento de vida.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#website\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/\",\"name\":\"Regnum Christi Internacional\",\"description\":\"El Regnum Christi es una realidad de la Iglesia cat\u00f3lica cuya misi\u00f3n es hacer presente el Reino de Cristo\",\"publisher\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/regnumchristi.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#organization\",\"name\":\"Regnum Christi Internacional\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/regnumchristi.es\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Favicon-RC_ligh-cuadrado.png\",\"contentUrl\":\"https:\\\/\\\/regnumchristi.es\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Favicon-RC_ligh-cuadrado.png\",\"width\":1080,\"height\":1080,\"caption\":\"Regnum Christi Internacional\"},\"image\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/RegnumChristiEspana\\\/\",\"https:\\\/\\\/x.com\\\/rc_espana\",\"https:\\\/\\\/www.instagram.com\\\/rc_espana\\\/\",\"https:\\\/\\\/es.linkedin.com\\\/company\\\/regnumchristiespaa\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#\\\/schema\\\/person\\\/390cded3fbd2800d0daee38acaecd350\",\"name\":\"Mar Morales\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/es\\\/author\\\/mmoralesserviciosrc-org\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Jueves 30 de abril de 2020 - El alimento de vida. - Regnum Christi Internacional","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/regnumchristi.org\/es\/jueves-30-de-abril-de-2020-el-alimento-de-vida\/","og_locale":"es_MX","og_type":"article","og_title":"Jueves 30 de abril de 2020 - El alimento de vida. - Regnum Christi Internacional","og_description":"[&hellip;]","og_url":"https:\/\/regnumchristi.org\/es\/jueves-30-de-abril-de-2020-el-alimento-de-vida\/","og_site_name":"Regnum Christi Internacional","article_publisher":"https:\/\/www.facebook.com\/RegnumChristiEspana\/","article_published_time":"2020-04-29T05:01:08+00:00","og_image":[{"width":1200,"height":628,"url":"https:\/\/regnumchristi.org\/wp-content\/uploads\/2020\/04\/300420.jpg","type":"image\/jpeg"}],"author":"Mar Morales","twitter_misc":{"Escrito por":"Mar Morales","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/regnumchristi.org\/jueves-30-de-abril-de-2020-el-alimento-de-vida\/#article","isPartOf":{"@id":"https:\/\/regnumchristi.org\/jueves-30-de-abril-de-2020-el-alimento-de-vida\/"},"author":{"name":"Mar Morales","@id":"https:\/\/regnumchristi.org\/#\/schema\/person\/390cded3fbd2800d0daee38acaecd350"},"headline":"Jueves 30 de abril de 2020 &#8211; El alimento de vida.","datePublished":"2020-04-29T05:01:08+00:00","mainEntityOfPage":{"@id":"https:\/\/regnumchristi.org\/jueves-30-de-abril-de-2020-el-alimento-de-vida\/"},"wordCount":853,"publisher":{"@id":"https:\/\/regnumchristi.org\/#organization"},"image":{"@id":"https:\/\/regnumchristi.org\/jueves-30-de-abril-de-2020-el-alimento-de-vida\/#primaryimage"},"thumbnailUrl":"https:\/\/regnumchristi.org\/wp-content\/uploads\/2020\/04\/300420.jpg","articleSection":["Meditaci\u00f3n del d\u00eda"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/regnumchristi.org\/jueves-30-de-abril-de-2020-el-alimento-de-vida\/","url":"https:\/\/regnumchristi.org\/jueves-30-de-abril-de-2020-el-alimento-de-vida\/","name":"Jueves 30 de abril de 2020 - El alimento de vida. - Regnum Christi Internacional","isPartOf":{"@id":"https:\/\/regnumchristi.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/regnumchristi.org\/jueves-30-de-abril-de-2020-el-alimento-de-vida\/#primaryimage"},"image":{"@id":"https:\/\/regnumchristi.org\/jueves-30-de-abril-de-2020-el-alimento-de-vida\/#primaryimage"},"thumbnailUrl":"https:\/\/regnumchristi.org\/wp-content\/uploads\/2020\/04\/300420.jpg","datePublished":"2020-04-29T05:01:08+00:00","breadcrumb":{"@id":"https:\/\/regnumchristi.org\/jueves-30-de-abril-de-2020-el-alimento-de-vida\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/regnumchristi.org\/jueves-30-de-abril-de-2020-el-alimento-de-vida\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/regnumchristi.org\/jueves-30-de-abril-de-2020-el-alimento-de-vida\/#primaryimage","url":"https:\/\/regnumchristi.org\/wp-content\/uploads\/2020\/04\/300420.jpg","contentUrl":"https:\/\/regnumchristi.org\/wp-content\/uploads\/2020\/04\/300420.jpg","width":1200,"height":628,"caption":"eucaristia"},{"@type":"BreadcrumbList","@id":"https:\/\/regnumchristi.org\/jueves-30-de-abril-de-2020-el-alimento-de-vida\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/regnumchristi.org\/es\/"},{"@type":"ListItem","position":2,"name":"Jueves 30 de abril de 2020 &#8211; El alimento de vida."}]},{"@type":"WebSite","@id":"https:\/\/regnumchristi.org\/#website","url":"https:\/\/regnumchristi.org\/","name":"Regnum Christi Internacional","description":"El Regnum Christi es una realidad de la Iglesia cat\u00f3lica cuya misi\u00f3n es hacer presente el Reino de Cristo","publisher":{"@id":"https:\/\/regnumchristi.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/regnumchristi.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/regnumchristi.org\/#organization","name":"Regnum Christi Internacional","url":"https:\/\/regnumchristi.org\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/regnumchristi.org\/#\/schema\/logo\/image\/","url":"https:\/\/regnumchristi.es\/wp-content\/uploads\/2023\/03\/Favicon-RC_ligh-cuadrado.png","contentUrl":"https:\/\/regnumchristi.es\/wp-content\/uploads\/2023\/03\/Favicon-RC_ligh-cuadrado.png","width":1080,"height":1080,"caption":"Regnum Christi Internacional"},"image":{"@id":"https:\/\/regnumchristi.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/RegnumChristiEspana\/","https:\/\/x.com\/rc_espana","https:\/\/www.instagram.com\/rc_espana\/","https:\/\/es.linkedin.com\/company\/regnumchristiespaa"]},{"@type":"Person","@id":"https:\/\/regnumchristi.org\/#\/schema\/person\/390cded3fbd2800d0daee38acaecd350","name":"Mar Morales","url":"https:\/\/regnumchristi.org\/es\/author\/mmoralesserviciosrc-org\/"}]}},"_links":{"self":[{"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/posts\/93235","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/users\/33"}],"replies":[{"embeddable":true,"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/comments?post=93235"}],"version-history":[{"count":0,"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/posts\/93235\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/media\/25899"}],"wp:attachment":[{"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/media?parent=93235"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/categories?post=93235"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/tags?post=93235"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}