{"id":93239,"date":"2020-05-13T17:30:46","date_gmt":"2020-05-13T22:30:46","guid":{"rendered":"https:\/\/www.regnumchristi.org\/es\/?p=26035"},"modified":"2020-05-13T17:30:46","modified_gmt":"2020-05-13T22:30:46","slug":"jueves-14-de-mayo-de-2020-yo-soy-su-amigo","status":"publish","type":"post","link":"https:\/\/regnumchristi.org\/es\/jueves-14-de-mayo-de-2020-yo-soy-su-amigo\/","title":{"rendered":"Jueves 14 de mayo de 2020 &#8211; Yo soy su amigo."},"content":{"rendered":"<h2 class=\"null\">San Mat\u00edas, ap\u00f3stol<\/h2>\n<p>H \u00c1lvaro Garc\u00eda, L.C.<br \/>\nEn el nombre del Padre y del Hijo y del Esp\u00edritu Santo. Am\u00e9n.<br \/>\nCristo, Rey nuestro. \u00a1Venga tu Reino!<\/p>\n<p><strong>Oraci\u00f3n preparatoria\u00a0<\/strong><em>(para ponerme en presencia de Dios)<\/em><br \/>\nEsp\u00edritu Santo, ven. Hazme un ap\u00f3stol como Mat\u00edas. Ll\u00e9name de tu sabidur\u00eda y cuida el silencio de mi coraz\u00f3n para que pueda escucharte. Mar\u00eda, dame la gracia de una oraci\u00f3n sincera.<\/p>\n<p><strong>Evangelio del d\u00eda\u00a0<\/strong><em>(para orientar tu meditaci\u00f3n)<\/em><br \/>\nDel santo Evangelio seg\u00fan san Juan 15, 9-17<br \/>\nEn aquel tiempo, Jes\u00fas dijo sus disc\u00edpulos: \u201cComo el Padre me ama, as\u00ed los amo yo. Permanezcan en mi amor. Si cumplen mis mandamientos, permanecen en mi amor; lo mismo que yo cumplo los mandamientos de mi Padre y permanezco en su amor. Les he dicho esto para que mi alegr\u00eda est\u00e9 en ustedes y su alegr\u00eda sea plena.<br \/>\nEste es mi mandamiento: que se amen los unos a los otros como yo los he amado. Nadie tiene amor m\u00e1s grande a sus amigos que el que da la vida por ellos. Ustedes son mis amigos, si hacen lo que yo les mando. Ya no los llamo siervos, porque el siervo no sabe lo que hace su amo; a ustedes los llamo amigos, porque les he dado a conocer todo lo que le he o\u00eddo a mi Padre.<br \/>\nNo son ustedes los que me han elegido, soy yo quien los ha elegido y los he destinado para que vayan y den fruto y su fruto permanezca, de modo que el Padre les conceda cuanto le pidan en mi nombre. Esto es lo que les mando: que se amen los unos a los otros\u201d.<\/p>\n<p>Palabra del Se\u00f1or<\/p>\n<p><strong>Medita lo que Dios te dice en el Evangelio<\/strong><br \/>\nSan Mat\u00edas, el santo de hoy, es muy especial. Se hace llamar uno de los ap\u00f3stoles, pero en realidad, \u00e9l no fue llamado directamente por Jes\u00fas como los dem\u00e1s. San Mat\u00edas fue elegido a suertes para sustituir a Judas en el grupo de los doce ap\u00f3stoles. Y esto nos interpela a cada uno: yo puedo ser otro Mat\u00edas, un ap\u00f3stol escogido hoy para evangelizar.<br \/>\n\u00bfY qu\u00e9 me pide Cristo para ser uno de sus ap\u00f3stoles? Los requisitos aparecen en el Evangelio de hoy. Primero me dice que cumpla sus mandamientos para ser feliz. \u00bfY todos los mandamientos por igual? No, uno en especial: el amar a mis amigos y enemigos como Jes\u00fas lo ha hecho. \u00bfY c\u00f3mo lo ha hecho Jes\u00fas? Dando su vida con alegr\u00eda, porque ese es el amor m\u00e1s grande.<br \/>\nEs el Se\u00f1or el que nos llama a cada uno de nosotros a ser sus ap\u00f3stoles y a dar la vida. Como Mat\u00edas, nosotros somos sus amigos y nos env\u00eda para dar fruto. Pregunt\u00e9mosle: \u00bfqu\u00e9 fruto quieres que d\u00e9, Se\u00f1or?<\/p>\n<p>\u00abEl Se\u00f1or Jes\u00fas dej\u00f3 a sus disc\u00edpulos una ense\u00f1anza exigente cuando les dijo: \u201cOs he destinado para que vay\u00e1is y deis fruto, y que vuestro fruto permanezca\u201d. Ir, dar fruto y permanecer. Esta es la llamada a la que no se puede escapar cuando se encuentra al Se\u00f1or y se es conquistado por su Evangelio. Ciertamente, Jes\u00fas no les dijo a sus disc\u00edpulos que ver\u00edan los frutos de su trabajo. S\u00f3lo les asegur\u00f3 que los frutos permanecer\u00edan. Esta promesa tambi\u00e9n es v\u00e1lida para nosotros. Es humano pensar que despu\u00e9s de tanto trabajo se quiera ver el fruto de nuestro compromiso; sin embargo, el Evangelio nos empuja en una direcci\u00f3n diferente.\u00bb<br \/>\n(Discurso de S.S. Francisco,18 de noviembre de 2019).<\/p>\n<p><strong>Di\u00e1logo con Cristo<\/strong><br \/>\n<em>\u00c9sta es la parte m\u00e1s importante de tu oraci\u00f3n, disponte a platicar con mucho amor con Aquel que te ama.<\/em><\/p>\n<p><strong>Prop\u00f3sito<\/strong><br \/>\n<em>Proponte uno personal. El que m\u00e1s amor implique en respuesta al Amado\u2026 o, si crees que es lo que Dios te pide, vive lo que se te sugiere a continuaci\u00f3n.<\/em><br \/>\nCuando me asalte el ego\u00edsmo de querer pensar en m\u00ed mismo, voy a ofrecer una oraci\u00f3n por aquellos que han sufrido una p\u00e9rdida por la epidemia del COVID.<\/p>\n<p><strong>Despedida<\/strong><br \/>\nTe damos gracias, Se\u00f1or, por todos tus beneficios, a Ti que vives y reinas por los siglos de los siglos.<br \/>\nAm\u00e9n.<\/p>\n<p>\u00a1Cristo, Rey nuestro!<br \/>\n\u00a1Venga tu Reino!<\/p>\n<p>Virgen prudent\u00edsima, Mar\u00eda, Madre de la Iglesia.<br \/>\nRuega por nosotros.<br \/>\nEn el nombre del Padre y del Hijo y del Esp\u00edritu Santo. Am\u00e9n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p> [&hellip;]<\/p>\n","protected":false},"author":33,"featured_media":26037,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"_daextrevop_audio_file_creation_date":"","_daextrevop_text_to_speech":"","_daextrevop_document_type":"","footnotes":""},"categories":[3164],"tags":[],"class_list":["post-93239","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-meditacion-del-dia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Jueves 14 de mayo de 2020 - Yo soy su amigo. - Regnum Christi Internacional<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/regnumchristi.org\/es\/jueves-14-de-mayo-de-2020-yo-soy-su-amigo\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Jueves 14 de mayo de 2020 - Yo soy su amigo. - Regnum Christi Internacional\" \/>\n<meta property=\"og:description\" content=\"[&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/regnumchristi.org\/es\/jueves-14-de-mayo-de-2020-yo-soy-su-amigo\/\" \/>\n<meta property=\"og:site_name\" content=\"Regnum Christi Internacional\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/RegnumChristiEspana\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-05-13T22:30:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/regnumchristi.org\/wp-content\/uploads\/2020\/05\/140520.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"628\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Mar Morales\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mar Morales\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/jueves-14-de-mayo-de-2020-yo-soy-su-amigo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/jueves-14-de-mayo-de-2020-yo-soy-su-amigo\\\/\"},\"author\":{\"name\":\"Mar Morales\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#\\\/schema\\\/person\\\/390cded3fbd2800d0daee38acaecd350\"},\"headline\":\"Jueves 14 de mayo de 2020 &#8211; Yo soy su amigo.\",\"datePublished\":\"2020-05-13T22:30:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/jueves-14-de-mayo-de-2020-yo-soy-su-amigo\\\/\"},\"wordCount\":792,\"publisher\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/jueves-14-de-mayo-de-2020-yo-soy-su-amigo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/regnumchristi.org\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/140520.jpg\",\"articleSection\":[\"Meditaci\u00f3n del d\u00eda\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/jueves-14-de-mayo-de-2020-yo-soy-su-amigo\\\/\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/jueves-14-de-mayo-de-2020-yo-soy-su-amigo\\\/\",\"name\":\"Jueves 14 de mayo de 2020 - Yo soy su amigo. - Regnum Christi Internacional\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/jueves-14-de-mayo-de-2020-yo-soy-su-amigo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/jueves-14-de-mayo-de-2020-yo-soy-su-amigo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/regnumchristi.org\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/140520.jpg\",\"datePublished\":\"2020-05-13T22:30:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/jueves-14-de-mayo-de-2020-yo-soy-su-amigo\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/regnumchristi.org\\\/jueves-14-de-mayo-de-2020-yo-soy-su-amigo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/jueves-14-de-mayo-de-2020-yo-soy-su-amigo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/140520.jpg\",\"contentUrl\":\"https:\\\/\\\/regnumchristi.org\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/140520.jpg\",\"width\":1200,\"height\":628,\"caption\":\"frutos\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/jueves-14-de-mayo-de-2020-yo-soy-su-amigo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/regnumchristi.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Jueves 14 de mayo de 2020 &#8211; Yo soy su amigo.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#website\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/\",\"name\":\"Regnum Christi Internacional\",\"description\":\"El Regnum Christi es una realidad de la Iglesia cat\u00f3lica cuya misi\u00f3n es hacer presente el Reino de Cristo\",\"publisher\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/regnumchristi.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#organization\",\"name\":\"Regnum Christi Internacional\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/regnumchristi.es\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Favicon-RC_ligh-cuadrado.png\",\"contentUrl\":\"https:\\\/\\\/regnumchristi.es\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Favicon-RC_ligh-cuadrado.png\",\"width\":1080,\"height\":1080,\"caption\":\"Regnum Christi Internacional\"},\"image\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/RegnumChristiEspana\\\/\",\"https:\\\/\\\/x.com\\\/rc_espana\",\"https:\\\/\\\/www.instagram.com\\\/rc_espana\\\/\",\"https:\\\/\\\/es.linkedin.com\\\/company\\\/regnumchristiespaa\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#\\\/schema\\\/person\\\/390cded3fbd2800d0daee38acaecd350\",\"name\":\"Mar Morales\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/es\\\/author\\\/mmoralesserviciosrc-org\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Jueves 14 de mayo de 2020 - Yo soy su amigo. - Regnum Christi Internacional","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/regnumchristi.org\/es\/jueves-14-de-mayo-de-2020-yo-soy-su-amigo\/","og_locale":"es_MX","og_type":"article","og_title":"Jueves 14 de mayo de 2020 - Yo soy su amigo. - Regnum Christi Internacional","og_description":"[&hellip;]","og_url":"https:\/\/regnumchristi.org\/es\/jueves-14-de-mayo-de-2020-yo-soy-su-amigo\/","og_site_name":"Regnum Christi Internacional","article_publisher":"https:\/\/www.facebook.com\/RegnumChristiEspana\/","article_published_time":"2020-05-13T22:30:46+00:00","og_image":[{"width":1200,"height":628,"url":"https:\/\/regnumchristi.org\/wp-content\/uploads\/2020\/05\/140520.jpg","type":"image\/jpeg"}],"author":"Mar Morales","twitter_misc":{"Escrito por":"Mar Morales","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/regnumchristi.org\/jueves-14-de-mayo-de-2020-yo-soy-su-amigo\/#article","isPartOf":{"@id":"https:\/\/regnumchristi.org\/jueves-14-de-mayo-de-2020-yo-soy-su-amigo\/"},"author":{"name":"Mar Morales","@id":"https:\/\/regnumchristi.org\/#\/schema\/person\/390cded3fbd2800d0daee38acaecd350"},"headline":"Jueves 14 de mayo de 2020 &#8211; Yo soy su amigo.","datePublished":"2020-05-13T22:30:46+00:00","mainEntityOfPage":{"@id":"https:\/\/regnumchristi.org\/jueves-14-de-mayo-de-2020-yo-soy-su-amigo\/"},"wordCount":792,"publisher":{"@id":"https:\/\/regnumchristi.org\/#organization"},"image":{"@id":"https:\/\/regnumchristi.org\/jueves-14-de-mayo-de-2020-yo-soy-su-amigo\/#primaryimage"},"thumbnailUrl":"https:\/\/regnumchristi.org\/wp-content\/uploads\/2020\/05\/140520.jpg","articleSection":["Meditaci\u00f3n del d\u00eda"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/regnumchristi.org\/jueves-14-de-mayo-de-2020-yo-soy-su-amigo\/","url":"https:\/\/regnumchristi.org\/jueves-14-de-mayo-de-2020-yo-soy-su-amigo\/","name":"Jueves 14 de mayo de 2020 - Yo soy su amigo. - Regnum Christi Internacional","isPartOf":{"@id":"https:\/\/regnumchristi.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/regnumchristi.org\/jueves-14-de-mayo-de-2020-yo-soy-su-amigo\/#primaryimage"},"image":{"@id":"https:\/\/regnumchristi.org\/jueves-14-de-mayo-de-2020-yo-soy-su-amigo\/#primaryimage"},"thumbnailUrl":"https:\/\/regnumchristi.org\/wp-content\/uploads\/2020\/05\/140520.jpg","datePublished":"2020-05-13T22:30:46+00:00","breadcrumb":{"@id":"https:\/\/regnumchristi.org\/jueves-14-de-mayo-de-2020-yo-soy-su-amigo\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/regnumchristi.org\/jueves-14-de-mayo-de-2020-yo-soy-su-amigo\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/regnumchristi.org\/jueves-14-de-mayo-de-2020-yo-soy-su-amigo\/#primaryimage","url":"https:\/\/regnumchristi.org\/wp-content\/uploads\/2020\/05\/140520.jpg","contentUrl":"https:\/\/regnumchristi.org\/wp-content\/uploads\/2020\/05\/140520.jpg","width":1200,"height":628,"caption":"frutos"},{"@type":"BreadcrumbList","@id":"https:\/\/regnumchristi.org\/jueves-14-de-mayo-de-2020-yo-soy-su-amigo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/regnumchristi.org\/es\/"},{"@type":"ListItem","position":2,"name":"Jueves 14 de mayo de 2020 &#8211; Yo soy su amigo."}]},{"@type":"WebSite","@id":"https:\/\/regnumchristi.org\/#website","url":"https:\/\/regnumchristi.org\/","name":"Regnum Christi Internacional","description":"El Regnum Christi es una realidad de la Iglesia cat\u00f3lica cuya misi\u00f3n es hacer presente el Reino de Cristo","publisher":{"@id":"https:\/\/regnumchristi.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/regnumchristi.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/regnumchristi.org\/#organization","name":"Regnum Christi Internacional","url":"https:\/\/regnumchristi.org\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/regnumchristi.org\/#\/schema\/logo\/image\/","url":"https:\/\/regnumchristi.es\/wp-content\/uploads\/2023\/03\/Favicon-RC_ligh-cuadrado.png","contentUrl":"https:\/\/regnumchristi.es\/wp-content\/uploads\/2023\/03\/Favicon-RC_ligh-cuadrado.png","width":1080,"height":1080,"caption":"Regnum Christi Internacional"},"image":{"@id":"https:\/\/regnumchristi.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/RegnumChristiEspana\/","https:\/\/x.com\/rc_espana","https:\/\/www.instagram.com\/rc_espana\/","https:\/\/es.linkedin.com\/company\/regnumchristiespaa"]},{"@type":"Person","@id":"https:\/\/regnumchristi.org\/#\/schema\/person\/390cded3fbd2800d0daee38acaecd350","name":"Mar Morales","url":"https:\/\/regnumchristi.org\/es\/author\/mmoralesserviciosrc-org\/"}]}},"_links":{"self":[{"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/posts\/93239","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/users\/33"}],"replies":[{"embeddable":true,"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/comments?post=93239"}],"version-history":[{"count":0,"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/posts\/93239\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/media\/26037"}],"wp:attachment":[{"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/media?parent=93239"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/categories?post=93239"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/tags?post=93239"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}