{"id":94401,"date":"2020-04-15T05:00:03","date_gmt":"2020-04-15T10:00:03","guid":{"rendered":"http:\/\/www.regnumchristi.org\/es\/?p=7208"},"modified":"2025-10-03T11:48:40","modified_gmt":"2025-10-03T17:48:40","slug":"el-don-de-la-paz","status":"publish","type":"post","link":"https:\/\/regnumchristi.org\/es\/el-don-de-la-paz\/","title":{"rendered":"El don de la paz (Jn 20,19-31)"},"content":{"rendered":"<p><strong><span style=\"color: #990000;\">Evangelio:<\/span><\/strong>\u00a0<em>Juan 20, 19-31<\/em><br \/>\nAl anochecer de aquel d\u00eda, el primero de la semana, estaban los disc\u00edpulos en una casa, con las puertas cerradas por miedo a los jud\u00edos. Y en esto entr\u00f3 Jes\u00fas, se puso en medio y les dijo: &#8220;Paz a vosotros&#8221;. Y, diciendo esto, les ense\u00f1\u00f3 las manos y el costado. Y los disc\u00edpulos se llenaron de alegr\u00eda al ver al Se\u00f1or. Jes\u00fas repiti\u00f3: &#8220;Paz a vosotros. Como el Padre me ha enviado, as\u00ed tambi\u00e9n os env\u00edo yo&#8221;. Y, dicho esto, exhal\u00f3 su aliento sobre ellos y les dijo: &#8220;Recibid el Esp\u00edritu Santo; a quienes les perdon\u00e9is los pecados, les quedan perdonados; a quienes se los reteng\u00e1is, les quedan retenidos&#8221;. Tom\u00e1s, uno de los Doce, llamado el Mellizo, no estaba con ellos cuando vino Jes\u00fas. Y los otros disc\u00edpulos le dec\u00edan: &#8220;Hemos visto al Se\u00f1or&#8221;. Pero \u00e9l les contest\u00f3: &#8220;Si no veo en sus manos la se\u00f1al de los clavos, si no meto el dedo en el agujero de los clavos y no meto la mano en su costado, no lo creo&#8221;. A los ocho d\u00edas, estaban otra vez dentro los disc\u00edpulos y Tom\u00e1s con ellos. Lleg\u00f3 Jes\u00fas, estando cerradas las puertas, se puso en medio y dijo: &#8220;Paz a vosotros&#8221;. Luego dijo a Tom\u00e1s: &#8220;Trae tu dedo, aqu\u00ed tienes mis manos; trae tu mano y m\u00e9tela en mi costado; y no seas incr\u00e9dulo, sino creyente&#8221;. Contest\u00f3 Tom\u00e1s: &#8220;\u00a1Se\u00f1or m\u00edo y Dios m\u00edo!&#8221;. Jes\u00fas le dijo: &#8220;\u00bfPorque me has visto has cre\u00eddo? Dichosos los que crean sin haber visto&#8221;. Muchos otros signos que no est\u00e1n escritos en este libro hizo Jes\u00fas a la vista de sus disc\u00edpulos. Estos se han escrito para que cre\u00e1is que Jes\u00fas es el Mes\u00edas, el Hijo de Dios, y para que creyendo teng\u00e1is vida en su nombre.<\/p>\n<p><b><span style=\"color: #990000;\">Fruto:<\/span><\/b> Dejar que Cristo\u00a0infunda el don de la paz en mi vida y en la de mi familia.<\/p>\n<p><b><span style=\"color: #990000;\">Pautas para la reflexi\u00f3n<br \/>\n<\/span><\/b>Todas las apariciones de Jesucristo resucitado tienen algunos elementos comunes, que siempre se repiten.\u00a0Tal parece\u00a0que el Se\u00f1or nos quiere condensar toda su predicaci\u00f3n en unos puntos esenciales. Una de esas notas siempre presentes es el saludo inicial: &#8220;<i>Paz a vosotros<\/i>&#8220;, os traigo la paz.<\/p>\n<p><em>1. La tensi\u00f3n de los ap\u00f3stoles<\/em><br \/>\nPong\u00e1monos en contexto: Jesucristo ha sido detenido, procesado, maltratado y crucificado como un malhechor; peor a\u00fan, ha sido tratado como un blasfemo, ultrajado, vejado&#8230; Durante la Semana Santa hemos contemplado con duro realismo este sufrimiento del Maestro. La reacci\u00f3n normal de cualquiera de sus seguidores es la que vemos en los ap\u00f3stoles: miedo, temor, ocultamiento&#8230; &#8220;<i>no sea que nos hagan a nosotros lo mismo<\/i>&#8220;. Los Once (Judas ya se hab\u00eda ahorcado) estaban\u00a0temerosos a puerta cerrada. Llegan unas mujeres anunciando que el Maestro, tan brutalmente crucificado, est\u00e1 vivo. \u00bfNo ser\u00e1 una alucinaci\u00f3n? \u00bfUn sue\u00f1o de unas mujeres piadosas? \u00bfUna imaginaci\u00f3n, fruto de un sincero deseo? \u00bfUna puerta de escape ante el sinsentido de la vida de estos hombres?<\/p>\n<p><em>2. El don de la paz<\/em><br \/>\nEn esa dura situaci\u00f3n an\u00edmica, en la que nada era capaz de consolarles, llega Jes\u00fas, estando cerradas todas las puertas por miedo a los jud\u00edos. Su primera palabra no es una queja, una reprimenda por haberle abandonado en la pasi\u00f3n. Ni siquiera una protesta por no creer el testimonio de las mujeres, que ya le hab\u00edan visto vivo. Su primera palabra es PAZ, <em>shaloom<\/em>. \u00c9l conoce mejor que nadie el sufrimiento de los ap\u00f3stoles; \u00c9l conoce perfectamente nuestro sufrimiento, pues \u00c9l mismo ha sufrido y mucho. Por eso su primer regalo, su principal regalo despu\u00e9s de la resurrecci\u00f3n, es la paz: &#8220;<i>Paz a vosotros<\/i>&#8220;. Es una paz que no deja de tener un matiz misterioso, superior a la raz\u00f3n humana, como todo el cristianismo. Se aparece con un cuerpo glorioso, espl\u00e9ndido, pero que sigue teniendo las se\u00f1ales de la pasi\u00f3n, os agujeros de los clavos. Cristo nos da su paz, no una paz como la da el mundo, sino una paz del coraz\u00f3n, profunda, incluso en los momentos de turbaci\u00f3n, sufrimiento, dolor.<\/p>\n<p><em>3. Un detalle personal<\/em><br \/>\nEl Evangelio narra c\u00f3mo Tom\u00e1s, uno de los ap\u00f3stoles, no estaba en el Cen\u00e1culo cuando se apareci\u00f3 el Maestro. Cuando le cuentan la maravillosa noticia, no les cree. Demasiado bonito para ser verdadero. &#8220;<em>Si no meto el dedo&#8230; Si no meto la mano&#8230;<\/em>&#8220;. Jes\u00fas, que ama a cada uno personalmente, se acercar\u00e1 pocos d\u00edas despu\u00e9s, a buscar a Tom\u00e1s. De nuevo se aparece a los Once, les saluda, y se dirige directamente al destinatario de esa segunda aparici\u00f3n: Tom\u00e1s, comprendo que te cueste creer, pero aqu\u00ed me tienes. Tienes delante la prueba m\u00e1s evidente. La respuesta del ap\u00f3stol nos deja de ser conmovedora: &#8220;<i>Se\u00f1or m\u00edo y Dios m\u00edo<\/i>&#8220;, mi Dios y mi todo.<\/p>\n<p><b><span style=\"color: #990000;\">Prop\u00f3sito:<\/span><\/b> Dejar\u00e9 entrar en mi coraz\u00f3n la paz de Cristo Resucitado, abri\u00e9ndome a sus palabras y respondiendo con generosidad a lo que \u00c9l me pida.<\/p>\n<p><em>Escucha tambi\u00e9n nuestro retiro mensual en l\u00ednea.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p> [&hellip;]<\/p>\n","protected":false},"author":49,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"_daextrevop_audio_file_creation_date":"","_daextrevop_text_to_speech":"","_daextrevop_document_type":"","footnotes":""},"categories":[3243],"tags":[117,229],"class_list":["post-94401","post","type-post","status-publish","format-standard","hentry","category-hora-eucaristica","tag-hora-eucaristica","tag-hora-santa"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El don de la paz que Jes\u00fas nos da (Jn 20,19-31) - Hora Eucar\u00edstica<\/title>\n<meta name=\"description\" content=\"Una de esas notas siempre presentes en las apariciones de Cristo resucitado es el saludo inicial: &quot;La paz a vosotros&quot;, os traigo la paz.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/regnumchristi.org\/es\/el-don-de-la-paz\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El don de la paz que Jes\u00fas nos da (Jn 20,19-31) - Hora Eucar\u00edstica\" \/>\n<meta property=\"og:description\" content=\"Una de esas notas siempre presentes en las apariciones de Cristo resucitado es el saludo inicial: &quot;La paz a vosotros&quot;, os traigo la paz.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/regnumchristi.org\/es\/el-don-de-la-paz\/\" \/>\n<meta property=\"og:site_name\" content=\"Regnum Christi Internacional\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/RegnumChristiEspana\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-04-15T10:00:03+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-03T17:48:40+00:00\" \/>\n<meta name=\"author\" content=\"Autores varios\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Autores varios\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/el-don-de-la-paz\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/el-don-de-la-paz\\\/\"},\"author\":{\"name\":\"Autores varios\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#\\\/schema\\\/person\\\/73f2e414269cfbf8edecc2fd90af81f2\"},\"headline\":\"El don de la paz (Jn 20,19-31)\",\"datePublished\":\"2020-04-15T10:00:03+00:00\",\"dateModified\":\"2025-10-03T17:48:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/el-don-de-la-paz\\\/\"},\"wordCount\":905,\"publisher\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#organization\"},\"keywords\":[\"Hora Eucar\u00edstica\",\"hora santa\"],\"articleSection\":[\"Hora Eucar\u00edstica\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/el-don-de-la-paz\\\/\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/el-don-de-la-paz\\\/\",\"name\":\"El don de la paz que Jes\u00fas nos da (Jn 20,19-31) - Hora Eucar\u00edstica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#website\"},\"datePublished\":\"2020-04-15T10:00:03+00:00\",\"dateModified\":\"2025-10-03T17:48:40+00:00\",\"description\":\"Una de esas notas siempre presentes en las apariciones de Cristo resucitado es el saludo inicial: \\\"La paz a vosotros\\\", os traigo la paz.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/el-don-de-la-paz\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/regnumchristi.org\\\/el-don-de-la-paz\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/el-don-de-la-paz\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/regnumchristi.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El don de la paz (Jn 20,19-31)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#website\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/\",\"name\":\"Regnum Christi Internacional\",\"description\":\"El Regnum Christi es una realidad de la Iglesia cat\u00f3lica cuya misi\u00f3n es hacer presente el Reino de Cristo\",\"publisher\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/regnumchristi.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#organization\",\"name\":\"Regnum Christi Internacional\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/regnumchristi.es\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Favicon-RC_ligh-cuadrado.png\",\"contentUrl\":\"https:\\\/\\\/regnumchristi.es\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Favicon-RC_ligh-cuadrado.png\",\"width\":1080,\"height\":1080,\"caption\":\"Regnum Christi Internacional\"},\"image\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/RegnumChristiEspana\\\/\",\"https:\\\/\\\/x.com\\\/rc_espana\",\"https:\\\/\\\/www.instagram.com\\\/rc_espana\\\/\",\"https:\\\/\\\/es.linkedin.com\\\/company\\\/regnumchristiespaa\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#\\\/schema\\\/person\\\/73f2e414269cfbf8edecc2fd90af81f2\",\"name\":\"Autores varios\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/es\\\/author\\\/jarceocaesc-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El don de la paz que Jes\u00fas nos da (Jn 20,19-31) - Hora Eucar\u00edstica","description":"Una de esas notas siempre presentes en las apariciones de Cristo resucitado es el saludo inicial: \"La paz a vosotros\", os traigo la paz.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/regnumchristi.org\/es\/el-don-de-la-paz\/","og_locale":"es_MX","og_type":"article","og_title":"El don de la paz que Jes\u00fas nos da (Jn 20,19-31) - Hora Eucar\u00edstica","og_description":"Una de esas notas siempre presentes en las apariciones de Cristo resucitado es el saludo inicial: \"La paz a vosotros\", os traigo la paz.","og_url":"https:\/\/regnumchristi.org\/es\/el-don-de-la-paz\/","og_site_name":"Regnum Christi Internacional","article_publisher":"https:\/\/www.facebook.com\/RegnumChristiEspana\/","article_published_time":"2020-04-15T10:00:03+00:00","article_modified_time":"2025-10-03T17:48:40+00:00","author":"Autores varios","twitter_misc":{"Escrito por":"Autores varios","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/regnumchristi.org\/el-don-de-la-paz\/#article","isPartOf":{"@id":"https:\/\/regnumchristi.org\/el-don-de-la-paz\/"},"author":{"name":"Autores varios","@id":"https:\/\/regnumchristi.org\/#\/schema\/person\/73f2e414269cfbf8edecc2fd90af81f2"},"headline":"El don de la paz (Jn 20,19-31)","datePublished":"2020-04-15T10:00:03+00:00","dateModified":"2025-10-03T17:48:40+00:00","mainEntityOfPage":{"@id":"https:\/\/regnumchristi.org\/el-don-de-la-paz\/"},"wordCount":905,"publisher":{"@id":"https:\/\/regnumchristi.org\/#organization"},"keywords":["Hora Eucar\u00edstica","hora santa"],"articleSection":["Hora Eucar\u00edstica"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/regnumchristi.org\/el-don-de-la-paz\/","url":"https:\/\/regnumchristi.org\/el-don-de-la-paz\/","name":"El don de la paz que Jes\u00fas nos da (Jn 20,19-31) - Hora Eucar\u00edstica","isPartOf":{"@id":"https:\/\/regnumchristi.org\/#website"},"datePublished":"2020-04-15T10:00:03+00:00","dateModified":"2025-10-03T17:48:40+00:00","description":"Una de esas notas siempre presentes en las apariciones de Cristo resucitado es el saludo inicial: \"La paz a vosotros\", os traigo la paz.","breadcrumb":{"@id":"https:\/\/regnumchristi.org\/el-don-de-la-paz\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/regnumchristi.org\/el-don-de-la-paz\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/regnumchristi.org\/el-don-de-la-paz\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/regnumchristi.org\/es\/"},{"@type":"ListItem","position":2,"name":"El don de la paz (Jn 20,19-31)"}]},{"@type":"WebSite","@id":"https:\/\/regnumchristi.org\/#website","url":"https:\/\/regnumchristi.org\/","name":"Regnum Christi Internacional","description":"El Regnum Christi es una realidad de la Iglesia cat\u00f3lica cuya misi\u00f3n es hacer presente el Reino de Cristo","publisher":{"@id":"https:\/\/regnumchristi.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/regnumchristi.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/regnumchristi.org\/#organization","name":"Regnum Christi Internacional","url":"https:\/\/regnumchristi.org\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/regnumchristi.org\/#\/schema\/logo\/image\/","url":"https:\/\/regnumchristi.es\/wp-content\/uploads\/2023\/03\/Favicon-RC_ligh-cuadrado.png","contentUrl":"https:\/\/regnumchristi.es\/wp-content\/uploads\/2023\/03\/Favicon-RC_ligh-cuadrado.png","width":1080,"height":1080,"caption":"Regnum Christi Internacional"},"image":{"@id":"https:\/\/regnumchristi.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/RegnumChristiEspana\/","https:\/\/x.com\/rc_espana","https:\/\/www.instagram.com\/rc_espana\/","https:\/\/es.linkedin.com\/company\/regnumchristiespaa"]},{"@type":"Person","@id":"https:\/\/regnumchristi.org\/#\/schema\/person\/73f2e414269cfbf8edecc2fd90af81f2","name":"Autores varios","url":"https:\/\/regnumchristi.org\/es\/author\/jarceocaesc-com\/"}]}},"_links":{"self":[{"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/posts\/94401","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/users\/49"}],"replies":[{"embeddable":true,"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/comments?post=94401"}],"version-history":[{"count":1,"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/posts\/94401\/revisions"}],"predecessor-version":[{"id":113949,"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/posts\/94401\/revisions\/113949"}],"wp:attachment":[{"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/media?parent=94401"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/categories?post=94401"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/tags?post=94401"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}