{"id":97007,"date":"2023-08-16T20:00:01","date_gmt":"2023-08-17T02:00:01","guid":{"rendered":"https:\/\/regnumchristi.org\/es\/?p=97007"},"modified":"2023-08-16T07:41:14","modified_gmt":"2023-08-16T13:41:14","slug":"jueves-17-de-agosto-de-2023-una-gota-del-perfume-del-perdon","status":"publish","type":"post","link":"https:\/\/regnumchristi.org\/es\/jueves-17-de-agosto-de-2023-una-gota-del-perfume-del-perdon\/","title":{"rendered":"Jueves 17 de agosto de 2023 &#8211; \u00abUna gota del perfume del perd\u00f3n\u00bb"},"content":{"rendered":"<p><em>Balam Loza, LC<\/em><\/p>\n<p>En el nombre del Padre y del Hijo y del Esp\u00edritu Santo.<br \/>\nAm\u00e9n.<\/p>\n<p>Cristo, Rey nuestro.<br \/>\n\u00a1Venga tu Reino!<\/p>\n<p><strong><span style=\"color: #800000;\">Oraci\u00f3n preparatoria<\/span>\u00a0<\/strong><em>(para ponerme en presencia de Dios)<\/em><\/p>\n<p>Jes\u00fas, ens\u00e9\u00f1ame en este d\u00eda a llevar tu amor. No quiero vivir esta oraci\u00f3n para m\u00ed sino quiero encontrarme con tu amor que me perdona siempre y no mira la grandeza de mis faltas. Me amas profundamente y quiero aprender amar como T\u00fa lo has hecho conmigo. Quiero estar aqu\u00ed y ver la historia maravillosa de tu amor en mi vida. Quiero ver todas las veces que he salido de casa, me he perdido, me he manchado y T\u00fa, me has esperado con la mesa puesta y con los brazos abiertos.<\/p>\n<p><strong><span style=\"color: #800000;\">Evangelio del d\u00eda<\/span>\u00a0<\/strong><em>(para orientar tu meditaci\u00f3n)<\/em><br \/>\nDel santo Evangelio seg\u00fan san Mateo 18,21-19,1<\/p>\n<p>En aquel tiempo, Pedro se acerc\u00f3 a Jes\u00fas y le pregunt\u00f3: &#8220;Si mi hermano me ofende, \u00bfcu\u00e1ntas veces tengo que perdonarlo? \u00bfHasta siete veces?&#8221; Jes\u00fas le contest\u00f3: &#8220;No s\u00f3lo hasta siete, sino hasta setenta veces siete&#8221;. Entonces Jes\u00fas les dijo: &#8220;El Reino de los cielos es semejante a un rey que quiso ajustar cuentas con sus servidores. El primero que le presentaron le deb\u00eda muchos millones. Como no ten\u00eda con qu\u00e9 pagar, el se\u00f1or mand\u00f3 que lo vendieran a \u00e9l, a su mujer, a sus hijos y todas sus posesiones, para saldar la deuda. El servidor, arroj\u00e1ndose a sus pies, le suplicaba, diciendo: \u2018Ten paciencia conmigo y te lo pagar\u00e9 todo\u2019. El rey tuvo l\u00e1stima de aquel servidor, lo solt\u00f3 y hasta le perdon\u00f3 la deuda. Pero, apenas hab\u00eda salido aquel servidor, se encontr\u00f3 con uno de sus compa\u00f1eros, que le deb\u00eda poco dinero. Entonces lo agarr\u00f3 por el cuello y casi lo estrangulaba, mientras le dec\u00eda: \u2018P\u00e1game lo que me debes\u2019. El compa\u00f1ero se le arrodill\u00f3 y le rogaba: \u2018Ten paciencia conmigo y te lo pagar\u00e9 todo\u2019. Pero el otro no quiso escucharlo, sino que fue y lo meti\u00f3 en la c\u00e1rcel hasta que le pagara la deuda. Al ver lo ocurrido, sus compa\u00f1eros se llenaron de indignaci\u00f3n y fueron a contarle al rey lo sucedido. Entonces el se\u00f1or lo llam\u00f3 y le dijo: \u2018Siervo malvado. Te perdon\u00e9 toda aquella deuda porque me lo suplicaste. \u00bfNo deb\u00edas t\u00fa tambi\u00e9n haber tenido compasi\u00f3n de tu compa\u00f1ero, como yo tuve compasi\u00f3n de ti?\u2019 Y el se\u00f1or encolerizado, lo entreg\u00f3 a los verdugos para que no lo soltaran hasta que pagara lo que deb\u00eda. Pues lo mismo har\u00e1 mi Padre celestial con ustedes si cada cual no perdona de coraz\u00f3n a su hermano&#8221;. Cuando Jes\u00fas termin\u00f3 de hablar, sali\u00f3 de Galilea y fue a la regi\u00f3n de Judea que queda al otro lado del Jord\u00e1n.<\/p>\n<p><em>Palabra del Se\u00f1or.<\/em><\/p>\n<p><span style=\"color: #800000;\"><strong>Medita lo que Dios te dice en el Evangelio<\/strong><\/span><\/p>\n<p>Con los brazos abiertos. Cu\u00e1ntas veces al sentirnos libres abrimos los brazos, podemos decir que es el s\u00edmbolo de la libertad. Pero si pensamos un poco en ese gesto podemos darnos cuenta de que solamente quien es libre puede recibir a otro. Solamente quien aprende a perdonar se libera de unas cadenas pesadas. Pensemos por un momento en eso que nos puede estar atando. Esas cadenas que puedan estar quit\u00e1ndonos la libertad y la paz. \u00a1Cu\u00e1ntas noches sin dormir pensando en alguna palabra, tal vez muy peque\u00f1a, que me pudo haber ofendido!<\/p>\n<p>Muchas veces el problema lo agrandamos m\u00e1s y nos pesa. Es verdad que en ocasiones es m\u00e1s dif\u00edcil ya que nuestra confianza ha sido pisada. \u00bfQu\u00e9 hacer? Perd\u00f3n. Es una palabra de seis letras pero que sana el coraz\u00f3n. Es una fragancia que llena las estancias m\u00e1s pobres y m\u00e1s tristes. Es una palabra, en fin, que da vida y libertad.<\/p>\n<p>&#8220;Padre, perd\u00f3nalos porque no saben lo que hacen&#8221; Un hombre en una cruz insultado supo decir &#8220;te perdono&#8221;, pero no s\u00f3lo eso, esa palabra era la fragancia m\u00e1s valiosa porque estaba cargada de amor. Ese amor me sana y me da vida cada vez que pienso que no soy digno. Detr\u00e1s del &#8220;Yo te absuelvo de tus pecados&#8221; hay una mirada de amor que da vida a nuestro coraz\u00f3n, que sana, que libera, que da paz. Eseperd\u00f3n ilumina nuestras vidas e historias. \u00bfQu\u00e9 pasar\u00eda si no recibi\u00e9semos el perd\u00f3n de Dios?<\/p>\n<p>Y nosotros somos instrumentos del amor para los dem\u00e1s. A veces podemos encontrarnos con personas que pueden sufrir por dentro y nos hacen sufrir por sus acciones. A veces no las comprendemos, pero es importante ir m\u00e1s all\u00e1 de un acto ofensivo. Mirar como Jes\u00fas mira es el ideal del cristiano. Amar, aunque duela y perdonar siempre, es lo que puede cambiar el mundo de hoy. Una mirada que llega al fondo y no se queda en la primera impresi\u00f3n es lo que puede iluminar a mi hermano que puede estar sufriendo.<\/p>\n<p><em>\u00abEn esta escena encontramos todo el drama de nuestras relaciones humanas. Cuando estamos nosotros en deuda con los dem\u00e1s, pretendemos la misericordia; en cambio cuando estamos en cr\u00e9dito, invocamos la justicia. Todos hacemos as\u00ed, todos. Esta no es la reacci\u00f3n del disc\u00edpulo de Cristo ni puede ser el estilo de vida de los cristianos. Jes\u00fas nos ense\u00f1a a perdonar, y a hacerlo sin l\u00edmites: &#8220;No te digo hasta siete veces, sino hasta setenta veces siete&#8221;\u00bb.<\/em><br \/>\n(Homil\u00eda de S.S. Francisco, 4 de agosto de 2016).<\/p>\n<p><span style=\"color: #800000;\"><strong>Di\u00e1logo con Cristo<\/strong><\/span><\/p>\n<p><em>\u00c9sta es la parte m\u00e1s importante de tu oraci\u00f3n, disponte a platicar con mucho amor con Aquel que te ama.<\/em><\/p>\n<p><span style=\"color: #800000;\"><strong>Prop\u00f3sito<\/strong><\/span><\/p>\n<p><em>Proponte uno personal. El que m\u00e1s amor implique en respuesta al Amado\u2026 o, si crees que es lo que Dios te pide, vive lo que se te sugiere a continuaci\u00f3n.<\/em><\/p>\n<p>Hoy, o durante la pr\u00f3xima semana, voy a acercarme al sacramento de la reconciliaci\u00f3n con una actitud de querer encontrarme con Jes\u00fas que sana mi vida y mi coraz\u00f3n.<\/p>\n<p><span style=\"color: #800000;\"><strong>Despedida<\/strong><\/span><\/p>\n<p>Te damos gracias, Se\u00f1or, por todos tus beneficios, a ti que vives y reinas por los siglos de los siglos.<br \/>\nAm\u00e9n.<\/p>\n<p>\u00a1Cristo, Rey nuestro!<br \/>\n\u00a1Venga tu Reino!<\/p>\n<p>Virgen prudent\u00edsima, Mar\u00eda, Madre de la Iglesia.<br \/>\nRuega por nosotros.<\/p>\n<p>En el nombre del Padre y del Hijo y del Esp\u00edritu Santo.<br \/>\nAm\u00e9n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p> [&hellip;]<\/p>\n","protected":false},"author":58,"featured_media":97290,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"site-sidebar-layout":"default","site-content-layout":"default","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"default","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"_daextrevop_audio_file_creation_date":"","_daextrevop_text_to_speech":"","_daextrevop_document_type":"","footnotes":""},"categories":[3164],"tags":[3162,3163,3067],"class_list":["post-97007","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-meditacion-del-dia","tag-evangelio","tag-meditacion","tag-reflexion"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Jueves 17 de agosto de 2023 - \u00abUna gota del perfume del perd\u00f3n\u00bb - Regnum Christi Internacional<\/title>\n<meta name=\"description\" content=\"Jes\u00fas, ens\u00e9\u00f1ame en este d\u00eda a llevar tu amor. No quiero vivir esta oraci\u00f3n para m\u00ed sino quiero encontrarme con tu amor que me perdona siempre.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/regnumchristi.org\/es\/jueves-17-de-agosto-de-2023-una-gota-del-perfume-del-perdon\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Jueves 17 de agosto de 2023 - \u00abUna gota del perfume del perd\u00f3n\u00bb - Regnum Christi Internacional\" \/>\n<meta property=\"og:description\" content=\"Jes\u00fas, ens\u00e9\u00f1ame en este d\u00eda a llevar tu amor. No quiero vivir esta oraci\u00f3n para m\u00ed sino quiero encontrarme con tu amor que me perdona siempre.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/regnumchristi.org\/es\/jueves-17-de-agosto-de-2023-una-gota-del-perfume-del-perdon\/\" \/>\n<meta property=\"og:site_name\" content=\"Regnum Christi Internacional\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/RegnumChristiEspana\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-08-17T02:00:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/regnumchristi.org\/wp-content\/uploads\/2023\/08\/imagenes_meditaciones_diarias_17-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"563\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Meditaciones Diarias\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Meditaciones Diarias\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/jueves-17-de-agosto-de-2023-una-gota-del-perfume-del-perdon\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/jueves-17-de-agosto-de-2023-una-gota-del-perfume-del-perdon\\\/\"},\"author\":{\"name\":\"Meditaciones Diarias\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#\\\/schema\\\/person\\\/a5ad8b3c4bd3cb3a0abe8a1474fe8f0a\"},\"headline\":\"Jueves 17 de agosto de 2023 &#8211; \u00abUna gota del perfume del perd\u00f3n\u00bb\",\"datePublished\":\"2023-08-17T02:00:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/jueves-17-de-agosto-de-2023-una-gota-del-perfume-del-perdon\\\/\"},\"wordCount\":1116,\"publisher\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/jueves-17-de-agosto-de-2023-una-gota-del-perfume-del-perdon\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/regnumchristi.org\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/imagenes_meditaciones_diarias_17.jpg\",\"keywords\":[\"Evangelio\",\"meditaci\u00f3n\",\"Reflexi\u00f3n\"],\"articleSection\":[\"Meditaci\u00f3n del d\u00eda\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/jueves-17-de-agosto-de-2023-una-gota-del-perfume-del-perdon\\\/\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/jueves-17-de-agosto-de-2023-una-gota-del-perfume-del-perdon\\\/\",\"name\":\"Jueves 17 de agosto de 2023 - \u00abUna gota del perfume del perd\u00f3n\u00bb - Regnum Christi Internacional\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/jueves-17-de-agosto-de-2023-una-gota-del-perfume-del-perdon\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/jueves-17-de-agosto-de-2023-una-gota-del-perfume-del-perdon\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/regnumchristi.org\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/imagenes_meditaciones_diarias_17.jpg\",\"datePublished\":\"2023-08-17T02:00:01+00:00\",\"description\":\"Jes\u00fas, ens\u00e9\u00f1ame en este d\u00eda a llevar tu amor. No quiero vivir esta oraci\u00f3n para m\u00ed sino quiero encontrarme con tu amor que me perdona siempre.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/jueves-17-de-agosto-de-2023-una-gota-del-perfume-del-perdon\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/regnumchristi.org\\\/jueves-17-de-agosto-de-2023-una-gota-del-perfume-del-perdon\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/jueves-17-de-agosto-de-2023-una-gota-del-perfume-del-perdon\\\/#primaryimage\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/imagenes_meditaciones_diarias_17.jpg\",\"contentUrl\":\"https:\\\/\\\/regnumchristi.org\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/imagenes_meditaciones_diarias_17.jpg\",\"width\":900,\"height\":563},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/jueves-17-de-agosto-de-2023-una-gota-del-perfume-del-perdon\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/regnumchristi.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Jueves 17 de agosto de 2023 &#8211; \u00abUna gota del perfume del perd\u00f3n\u00bb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#website\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/\",\"name\":\"Regnum Christi Internacional\",\"description\":\"El Regnum Christi es una realidad de la Iglesia cat\u00f3lica cuya misi\u00f3n es hacer presente el Reino de Cristo\",\"publisher\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/regnumchristi.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#organization\",\"name\":\"Regnum Christi Internacional\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/regnumchristi.es\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Favicon-RC_ligh-cuadrado.png\",\"contentUrl\":\"https:\\\/\\\/regnumchristi.es\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Favicon-RC_ligh-cuadrado.png\",\"width\":1080,\"height\":1080,\"caption\":\"Regnum Christi Internacional\"},\"image\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/RegnumChristiEspana\\\/\",\"https:\\\/\\\/x.com\\\/rc_espana\",\"https:\\\/\\\/www.instagram.com\\\/rc_espana\\\/\",\"https:\\\/\\\/es.linkedin.com\\\/company\\\/regnumchristiespaa\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#\\\/schema\\\/person\\\/a5ad8b3c4bd3cb3a0abe8a1474fe8f0a\",\"name\":\"Meditaciones Diarias\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/es\\\/author\\\/meditacionesd\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Jueves 17 de agosto de 2023 - \u00abUna gota del perfume del perd\u00f3n\u00bb - Regnum Christi Internacional","description":"Jes\u00fas, ens\u00e9\u00f1ame en este d\u00eda a llevar tu amor. No quiero vivir esta oraci\u00f3n para m\u00ed sino quiero encontrarme con tu amor que me perdona siempre.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/regnumchristi.org\/es\/jueves-17-de-agosto-de-2023-una-gota-del-perfume-del-perdon\/","og_locale":"es_MX","og_type":"article","og_title":"Jueves 17 de agosto de 2023 - \u00abUna gota del perfume del perd\u00f3n\u00bb - Regnum Christi Internacional","og_description":"Jes\u00fas, ens\u00e9\u00f1ame en este d\u00eda a llevar tu amor. No quiero vivir esta oraci\u00f3n para m\u00ed sino quiero encontrarme con tu amor que me perdona siempre.","og_url":"https:\/\/regnumchristi.org\/es\/jueves-17-de-agosto-de-2023-una-gota-del-perfume-del-perdon\/","og_site_name":"Regnum Christi Internacional","article_publisher":"https:\/\/www.facebook.com\/RegnumChristiEspana\/","article_published_time":"2023-08-17T02:00:01+00:00","og_image":[{"width":900,"height":563,"url":"https:\/\/regnumchristi.org\/wp-content\/uploads\/2023\/08\/imagenes_meditaciones_diarias_17-1.jpg","type":"image\/jpeg"}],"author":"Meditaciones Diarias","twitter_misc":{"Escrito por":"Meditaciones Diarias","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/regnumchristi.org\/jueves-17-de-agosto-de-2023-una-gota-del-perfume-del-perdon\/#article","isPartOf":{"@id":"https:\/\/regnumchristi.org\/jueves-17-de-agosto-de-2023-una-gota-del-perfume-del-perdon\/"},"author":{"name":"Meditaciones Diarias","@id":"https:\/\/regnumchristi.org\/#\/schema\/person\/a5ad8b3c4bd3cb3a0abe8a1474fe8f0a"},"headline":"Jueves 17 de agosto de 2023 &#8211; \u00abUna gota del perfume del perd\u00f3n\u00bb","datePublished":"2023-08-17T02:00:01+00:00","mainEntityOfPage":{"@id":"https:\/\/regnumchristi.org\/jueves-17-de-agosto-de-2023-una-gota-del-perfume-del-perdon\/"},"wordCount":1116,"publisher":{"@id":"https:\/\/regnumchristi.org\/#organization"},"image":{"@id":"https:\/\/regnumchristi.org\/jueves-17-de-agosto-de-2023-una-gota-del-perfume-del-perdon\/#primaryimage"},"thumbnailUrl":"https:\/\/regnumchristi.org\/wp-content\/uploads\/2023\/08\/imagenes_meditaciones_diarias_17.jpg","keywords":["Evangelio","meditaci\u00f3n","Reflexi\u00f3n"],"articleSection":["Meditaci\u00f3n del d\u00eda"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/regnumchristi.org\/jueves-17-de-agosto-de-2023-una-gota-del-perfume-del-perdon\/","url":"https:\/\/regnumchristi.org\/jueves-17-de-agosto-de-2023-una-gota-del-perfume-del-perdon\/","name":"Jueves 17 de agosto de 2023 - \u00abUna gota del perfume del perd\u00f3n\u00bb - Regnum Christi Internacional","isPartOf":{"@id":"https:\/\/regnumchristi.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/regnumchristi.org\/jueves-17-de-agosto-de-2023-una-gota-del-perfume-del-perdon\/#primaryimage"},"image":{"@id":"https:\/\/regnumchristi.org\/jueves-17-de-agosto-de-2023-una-gota-del-perfume-del-perdon\/#primaryimage"},"thumbnailUrl":"https:\/\/regnumchristi.org\/wp-content\/uploads\/2023\/08\/imagenes_meditaciones_diarias_17.jpg","datePublished":"2023-08-17T02:00:01+00:00","description":"Jes\u00fas, ens\u00e9\u00f1ame en este d\u00eda a llevar tu amor. No quiero vivir esta oraci\u00f3n para m\u00ed sino quiero encontrarme con tu amor que me perdona siempre.","breadcrumb":{"@id":"https:\/\/regnumchristi.org\/jueves-17-de-agosto-de-2023-una-gota-del-perfume-del-perdon\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/regnumchristi.org\/jueves-17-de-agosto-de-2023-una-gota-del-perfume-del-perdon\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/regnumchristi.org\/jueves-17-de-agosto-de-2023-una-gota-del-perfume-del-perdon\/#primaryimage","url":"https:\/\/regnumchristi.org\/wp-content\/uploads\/2023\/08\/imagenes_meditaciones_diarias_17.jpg","contentUrl":"https:\/\/regnumchristi.org\/wp-content\/uploads\/2023\/08\/imagenes_meditaciones_diarias_17.jpg","width":900,"height":563},{"@type":"BreadcrumbList","@id":"https:\/\/regnumchristi.org\/jueves-17-de-agosto-de-2023-una-gota-del-perfume-del-perdon\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/regnumchristi.org\/es\/"},{"@type":"ListItem","position":2,"name":"Jueves 17 de agosto de 2023 &#8211; \u00abUna gota del perfume del perd\u00f3n\u00bb"}]},{"@type":"WebSite","@id":"https:\/\/regnumchristi.org\/#website","url":"https:\/\/regnumchristi.org\/","name":"Regnum Christi Internacional","description":"El Regnum Christi es una realidad de la Iglesia cat\u00f3lica cuya misi\u00f3n es hacer presente el Reino de Cristo","publisher":{"@id":"https:\/\/regnumchristi.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/regnumchristi.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/regnumchristi.org\/#organization","name":"Regnum Christi Internacional","url":"https:\/\/regnumchristi.org\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/regnumchristi.org\/#\/schema\/logo\/image\/","url":"https:\/\/regnumchristi.es\/wp-content\/uploads\/2023\/03\/Favicon-RC_ligh-cuadrado.png","contentUrl":"https:\/\/regnumchristi.es\/wp-content\/uploads\/2023\/03\/Favicon-RC_ligh-cuadrado.png","width":1080,"height":1080,"caption":"Regnum Christi Internacional"},"image":{"@id":"https:\/\/regnumchristi.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/RegnumChristiEspana\/","https:\/\/x.com\/rc_espana","https:\/\/www.instagram.com\/rc_espana\/","https:\/\/es.linkedin.com\/company\/regnumchristiespaa"]},{"@type":"Person","@id":"https:\/\/regnumchristi.org\/#\/schema\/person\/a5ad8b3c4bd3cb3a0abe8a1474fe8f0a","name":"Meditaciones Diarias","url":"https:\/\/regnumchristi.org\/es\/author\/meditacionesd\/"}]}},"_links":{"self":[{"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/posts\/97007","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/comments?post=97007"}],"version-history":[{"count":2,"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/posts\/97007\/revisions"}],"predecessor-version":[{"id":97289,"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/posts\/97007\/revisions\/97289"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/media\/97290"}],"wp:attachment":[{"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/media?parent=97007"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/categories?post=97007"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/tags?post=97007"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}