{"id":98746,"date":"2023-10-08T20:00:47","date_gmt":"2023-10-09T02:00:47","guid":{"rendered":"https:\/\/regnumchristi.org\/es\/?p=98746"},"modified":"2023-10-08T15:20:26","modified_gmt":"2023-10-08T21:20:26","slug":"lunes-9-de-octubre-de-20203-una-nueva-oportunidad-para-un-si","status":"publish","type":"post","link":"https:\/\/regnumchristi.org\/es\/lunes-9-de-octubre-de-20203-una-nueva-oportunidad-para-un-si\/","title":{"rendered":"Lunes 9 de octubre de 20203 &#8211; \u00abUna nueva oportunidad para un &#8220;s\u00ed&#8221;\u00bb"},"content":{"rendered":"<p><em>Balam Loza, LC<\/em><\/p>\n<p>En el nombre del Padre y del Hijo y del Esp\u00edritu Santo.<br \/>\nAm\u00e9n.<\/p>\n<p>Cristo, Rey nuestro.<br \/>\n\u00a1Venga tu Reino!<\/p>\n<p><strong><span style=\"color: #800000;\">Oraci\u00f3n preparatoria<\/span>\u00a0<\/strong><em>(para ponerme en presencia de Dios)<\/em><\/p>\n<p>Al mirar el vuelo de las golondrinas, el surgir de las flores, la hermosa vista de la monta\u00f1a, veo tu mano en cada uno de estos acontecimientos. \u00bfQui\u00e9n soy yo? Nada y todo. Nada porque en realidad el hombre es una mota de polvo, pero todo porque soy tu hijo. Eso vale m\u00e1s que todo. Me siento entre tus manos como un ni\u00f1o se siente seguro en los brazos de su padre. Padre Dios, hoy quiero gozar como cuando me divert\u00eda de peque\u00f1o con mi padre. Quiero presumirte entre mis amigos; quiero decir con gran sencillez: &#8220;Mi Pap\u00e1 es el mejor del mundo&#8221;<\/p>\n<p><strong><span style=\"color: #800000;\">Evangelio del d\u00eda<\/span>\u00a0<\/strong><em>(para orientar tu meditaci\u00f3n)<br \/>\n<\/em>Del santo Evangelio seg\u00fan san Lucas 10, 25-37<\/p>\n<p>En aquel tiempo, se present\u00f3 ante Jes\u00fas un doctor de la ley para ponerlo a prueba y le pregunt\u00f3: &#8220;Maestro, \u00bfqu\u00e9 debo hacer para conseguir la vida eterna?&#8221; Jes\u00fas le dijo: &#8220;\u00bfQu\u00e9 es lo que est\u00e1 escrito en la ley? \u00bfQu\u00e9 lees en ella?&#8221;. El doctor de la ley contest\u00f3<em>: &#8220;Amar\u00e1s al Se\u00f1or tu Dios, con todo tu coraz\u00f3n, con toda tu alma, con todas tus fuerzas y con todo tu ser, y a tu pr\u00f3jimo como a ti mismo&#8221;. Jes\u00fas le dijo: &#8220;Has contestado bien; si haces eso, vivir\u00e1s&#8221;. <\/em>El doctor de la ley, para justificarse, le pregunt\u00f3 a Jes\u00fas: &#8220;\u00bfY qui\u00e9n es mi pr\u00f3jimo?&#8221; Jes\u00fas le dijo: &#8220;Un hombre que bajaba por el camino de Jerusal\u00e9n a Jeric\u00f3, cay\u00f3 en manos de unos ladrones, los cuales lo robaron, lo hirieron y lo dejaron medio muerto. Sucedi\u00f3 que por el mismo camino bajaba un sacerdote, el cual lo vio y pas\u00f3 de largo. De igual modo, un levita que pas\u00f3 por ah\u00ed, lo vio y sigui\u00f3 adelante. Pero un samaritano que iba de viaje, al verlo, se compadeci\u00f3 de \u00e9l, se le acerc\u00f3, ungi\u00f3 sus heridas con aceite y vino y se las vend\u00f3; luego lo puso sobre su cabalgadura, lo llev\u00f3 a un mes\u00f3n y cuid\u00f3 de \u00e9l. Al d\u00eda siguiente sac\u00f3 dos denarios, se los dio al due\u00f1o del mes\u00f3n y le dijo: \u2018Cuida de \u00e9l y lo que gastes de m\u00e1s, te lo pagar\u00e9 a mi regreso\u2019. \u00bfCu\u00e1l de estos tres te parece que se port\u00f3 como pr\u00f3jimo del hombre que fue asaltado por los ladrones?&#8221;. El doctor de la ley le respondi\u00f3: &#8220;El que tuvo compasi\u00f3n de \u00e9l&#8221;. Entonces Jes\u00fas le dijo: &#8220;Anda y haz t\u00fa lo mismo&#8221;.<\/p>\n<p><em>Palabra del Se\u00f1or.<\/em><\/p>\n<p><span style=\"color: #800000;\"><strong>Medita lo que Dios te dice en el Evangelio<\/strong><\/span><\/p>\n<p>&#8220;Anda, haz t\u00fa lo mismo&#8221; El mensaje del cristiano es un mensaje de amor. Pero este amor no es m\u00e1gico o plat\u00f3nico. No es un amor que se logra sin esfuerzo. Requiere un trabajo constante, sacrificado, desprendido. Es, en dos palabras, amor crucificado. Cuesta, pero lo que cuesta vale. La producci\u00f3n de una m\u00ednima cantidad de seda cuesta gran parte de la vida de una oruga y largos meses de cuidados delicados. Cristo me am\u00f3 hasta el extremo dando hasta la \u00faltima gota de su sangre.<\/p>\n<p>No es posible imaginar una vida entregada a los dem\u00e1s que no cueste. Y Jes\u00fas, en este Evangelio le dice al fariseo, que conoc\u00eda la teor\u00eda al dedillo: &#8220;\u00a1Anda! \u00a1Haz!&#8221;. De nada sirve saber qu\u00e9 es lo que tenemos que hacer si no lo hacemos. Cada d\u00eda ha de ser un comenzar de nuevo. Sin duda tendremos altas y bajas. Habr\u00e1 momentos en que nos dejaremos llevar por lo m\u00e1s c\u00f3modo o por el ego\u00edsmo. Pero siempre tendremos una nueva oportunidad para recoger, limpiar y vestir al que est\u00e1 necesitado.<\/p>\n<p>Nuestros calendarios est\u00e1n llenos de actividades que apenas nos dejan un momento para respirar, para ver a los ojos de los dem\u00e1s, para preguntar e interesarnos por aquellos con los que pasamos gran parte del tiempo. Sin duda muchos de los que pasaron a un lado del samaritano no se giraron tan siquiera para ver a este pobre hombre. Era un elemento para el cual no hab\u00eda lugar ni en su agenda ni en su cuenta de gastos.<\/p>\n<p>\u00bfYo tengo lugar para otro en mi vida? \u00bfEstoy dispuesto a decir &#8220;no&#8221; a mis cosas para decir &#8220;s\u00ed&#8221; a otros? No importa la respuesta pues toda la vida es una b\u00fasqueda y una lucha para alcanzar este amor perfecto. Sin duda que todos aquellos que pasaron a un lado del samaritano y dijeron &#8220;no&#8221; dijeron &#8220;s\u00ed&#8221; en otros momentos. Podremos haber fallado muchas veces pero siempre hay una nueva oportunidad.<\/p>\n<p><em>\u00abAnte este contenido tan esencial de la fe, la Iglesia no puede permitirse actuar como lo hicieron el sacerdote y el levita con el hombre abandonado medio muerto en el camino. No se puede mirar para otro lado y dar la espalda para no ver muchas formas de pobreza que piden misericordia. Dar la espalda para no ver el hambre, la enfermedad, las personas explotadas\u2026, es un pecado grave; es tambi\u00e9n un pecado moderno, un pecado actual. Nosotros cristianos no nos lo podemos permitir. No ser\u00eda digno de la Iglesia ni de un cristiano &#8220;pasar de largo&#8221; y pretender tener la conciencia tranquila s\u00f3lo porque se ha rezado o porque se ha ido el domingo a Misa\u00bb.<\/em><br \/>\n(Homil\u00eda de S.S. Francisco, 3 de septiembre de 2016).<\/p>\n<p><span style=\"color: #800000;\"><strong>Di\u00e1logo con Cristo<\/strong><\/span><\/p>\n<p><em>\u00c9sta es la parte m\u00e1s importante de tu oraci\u00f3n, disponte a platicar con mucho amor con Aquel que te ama.<\/em><\/p>\n<p><span style=\"color: #800000;\"><strong>Prop\u00f3sito<\/strong><\/span><\/p>\n<p><em>Proponte uno personal. El que m\u00e1s amor implique en respuesta al Amado\u2026 o, si crees que es lo que Dios te pide, vive lo que se te sugiere a continuaci\u00f3n.<\/em><\/p>\n<p>Hoy voy a detenerme cuando vea a un pobre y voy comprarle algo de comer. Adem\u00e1s le dedicar\u00e9 un rato de mi tiempo sin preocuparme por nada m\u00e1s.<\/p>\n<p><span style=\"color: #800000;\"><strong>Despedida<\/strong><\/span><\/p>\n<p>Te damos gracias, Se\u00f1or, por todos tus beneficios, a ti que vives y reinas por los siglos de los siglos.<br \/>\nAm\u00e9n.<\/p>\n<p>\u00a1Cristo, Rey nuestro!<br \/>\n\u00a1Venga tu Reino!<\/p>\n<p>Virgen prudent\u00edsima, Mar\u00eda, Madre de la Iglesia.<br \/>\nRuega por nosotros.<\/p>\n<p>En el nombre del Padre y del Hijo y del Esp\u00edritu Santo.<br \/>\nAm\u00e9n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p> [&hellip;]<\/p>\n","protected":false},"author":58,"featured_media":99165,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"default","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"_daextrevop_audio_file_creation_date":"","_daextrevop_text_to_speech":"","_daextrevop_document_type":"","footnotes":""},"categories":[3164],"tags":[3162,3163,3067],"class_list":["post-98746","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-meditacion-del-dia","tag-evangelio","tag-meditacion","tag-reflexion"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Lunes 9 de octubre de 20203 - \u00abUna nueva oportunidad para un &quot;s\u00ed&quot;\u00bb - Regnum Christi Internacional<\/title>\n<meta name=\"description\" content=\"Al mirar el vuelo de las golondrinas, el surgir de las flores, la hermosa vista de la monta\u00f1a, veo tu mano en cada uno de los acontecimientos.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/regnumchristi.org\/es\/lunes-9-de-octubre-de-20203-una-nueva-oportunidad-para-un-si\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lunes 9 de octubre de 20203 - \u00abUna nueva oportunidad para un &quot;s\u00ed&quot;\u00bb - Regnum Christi Internacional\" \/>\n<meta property=\"og:description\" content=\"Al mirar el vuelo de las golondrinas, el surgir de las flores, la hermosa vista de la monta\u00f1a, veo tu mano en cada uno de los acontecimientos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/regnumchristi.org\/es\/lunes-9-de-octubre-de-20203-una-nueva-oportunidad-para-un-si\/\" \/>\n<meta property=\"og:site_name\" content=\"Regnum Christi Internacional\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/RegnumChristiEspana\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-10-09T02:00:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/regnumchristi.org\/wp-content\/uploads\/2023\/10\/imagenes_meditaciones_diarias_9oct.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"563\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Meditaciones Diarias\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Meditaciones Diarias\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/lunes-9-de-octubre-de-20203-una-nueva-oportunidad-para-un-si\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/lunes-9-de-octubre-de-20203-una-nueva-oportunidad-para-un-si\\\/\"},\"author\":{\"name\":\"Meditaciones Diarias\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#\\\/schema\\\/person\\\/a5ad8b3c4bd3cb3a0abe8a1474fe8f0a\"},\"headline\":\"Lunes 9 de octubre de 20203 &#8211; \u00abUna nueva oportunidad para un &#8220;s\u00ed&#8221;\u00bb\",\"datePublished\":\"2023-10-09T02:00:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/lunes-9-de-octubre-de-20203-una-nueva-oportunidad-para-un-si\\\/\"},\"wordCount\":1105,\"publisher\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/lunes-9-de-octubre-de-20203-una-nueva-oportunidad-para-un-si\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/regnumchristi.org\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/imagenes_meditaciones_diarias_9oct.jpg\",\"keywords\":[\"Evangelio\",\"meditaci\u00f3n\",\"Reflexi\u00f3n\"],\"articleSection\":[\"Meditaci\u00f3n del d\u00eda\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/lunes-9-de-octubre-de-20203-una-nueva-oportunidad-para-un-si\\\/\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/lunes-9-de-octubre-de-20203-una-nueva-oportunidad-para-un-si\\\/\",\"name\":\"Lunes 9 de octubre de 20203 - \u00abUna nueva oportunidad para un \\\"s\u00ed\\\"\u00bb - Regnum Christi Internacional\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/lunes-9-de-octubre-de-20203-una-nueva-oportunidad-para-un-si\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/lunes-9-de-octubre-de-20203-una-nueva-oportunidad-para-un-si\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/regnumchristi.org\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/imagenes_meditaciones_diarias_9oct.jpg\",\"datePublished\":\"2023-10-09T02:00:47+00:00\",\"description\":\"Al mirar el vuelo de las golondrinas, el surgir de las flores, la hermosa vista de la monta\u00f1a, veo tu mano en cada uno de los acontecimientos.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/lunes-9-de-octubre-de-20203-una-nueva-oportunidad-para-un-si\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/regnumchristi.org\\\/lunes-9-de-octubre-de-20203-una-nueva-oportunidad-para-un-si\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/lunes-9-de-octubre-de-20203-una-nueva-oportunidad-para-un-si\\\/#primaryimage\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/imagenes_meditaciones_diarias_9oct.jpg\",\"contentUrl\":\"https:\\\/\\\/regnumchristi.org\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/imagenes_meditaciones_diarias_9oct.jpg\",\"width\":900,\"height\":563},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/lunes-9-de-octubre-de-20203-una-nueva-oportunidad-para-un-si\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/regnumchristi.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lunes 9 de octubre de 20203 &#8211; \u00abUna nueva oportunidad para un &#8220;s\u00ed&#8221;\u00bb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#website\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/\",\"name\":\"Regnum Christi Internacional\",\"description\":\"El Regnum Christi es una realidad de la Iglesia cat\u00f3lica cuya misi\u00f3n es hacer presente el Reino de Cristo\",\"publisher\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/regnumchristi.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#organization\",\"name\":\"Regnum Christi Internacional\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/regnumchristi.es\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Favicon-RC_ligh-cuadrado.png\",\"contentUrl\":\"https:\\\/\\\/regnumchristi.es\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Favicon-RC_ligh-cuadrado.png\",\"width\":1080,\"height\":1080,\"caption\":\"Regnum Christi Internacional\"},\"image\":{\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/RegnumChristiEspana\\\/\",\"https:\\\/\\\/x.com\\\/rc_espana\",\"https:\\\/\\\/www.instagram.com\\\/rc_espana\\\/\",\"https:\\\/\\\/es.linkedin.com\\\/company\\\/regnumchristiespaa\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/regnumchristi.org\\\/#\\\/schema\\\/person\\\/a5ad8b3c4bd3cb3a0abe8a1474fe8f0a\",\"name\":\"Meditaciones Diarias\",\"url\":\"https:\\\/\\\/regnumchristi.org\\\/es\\\/author\\\/meditacionesd\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lunes 9 de octubre de 20203 - \u00abUna nueva oportunidad para un \"s\u00ed\"\u00bb - Regnum Christi Internacional","description":"Al mirar el vuelo de las golondrinas, el surgir de las flores, la hermosa vista de la monta\u00f1a, veo tu mano en cada uno de los acontecimientos.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/regnumchristi.org\/es\/lunes-9-de-octubre-de-20203-una-nueva-oportunidad-para-un-si\/","og_locale":"es_MX","og_type":"article","og_title":"Lunes 9 de octubre de 20203 - \u00abUna nueva oportunidad para un \"s\u00ed\"\u00bb - Regnum Christi Internacional","og_description":"Al mirar el vuelo de las golondrinas, el surgir de las flores, la hermosa vista de la monta\u00f1a, veo tu mano en cada uno de los acontecimientos.","og_url":"https:\/\/regnumchristi.org\/es\/lunes-9-de-octubre-de-20203-una-nueva-oportunidad-para-un-si\/","og_site_name":"Regnum Christi Internacional","article_publisher":"https:\/\/www.facebook.com\/RegnumChristiEspana\/","article_published_time":"2023-10-09T02:00:47+00:00","og_image":[{"width":900,"height":563,"url":"https:\/\/regnumchristi.org\/wp-content\/uploads\/2023\/10\/imagenes_meditaciones_diarias_9oct.jpg","type":"image\/jpeg"}],"author":"Meditaciones Diarias","twitter_misc":{"Escrito por":"Meditaciones Diarias","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/regnumchristi.org\/lunes-9-de-octubre-de-20203-una-nueva-oportunidad-para-un-si\/#article","isPartOf":{"@id":"https:\/\/regnumchristi.org\/lunes-9-de-octubre-de-20203-una-nueva-oportunidad-para-un-si\/"},"author":{"name":"Meditaciones Diarias","@id":"https:\/\/regnumchristi.org\/#\/schema\/person\/a5ad8b3c4bd3cb3a0abe8a1474fe8f0a"},"headline":"Lunes 9 de octubre de 20203 &#8211; \u00abUna nueva oportunidad para un &#8220;s\u00ed&#8221;\u00bb","datePublished":"2023-10-09T02:00:47+00:00","mainEntityOfPage":{"@id":"https:\/\/regnumchristi.org\/lunes-9-de-octubre-de-20203-una-nueva-oportunidad-para-un-si\/"},"wordCount":1105,"publisher":{"@id":"https:\/\/regnumchristi.org\/#organization"},"image":{"@id":"https:\/\/regnumchristi.org\/lunes-9-de-octubre-de-20203-una-nueva-oportunidad-para-un-si\/#primaryimage"},"thumbnailUrl":"https:\/\/regnumchristi.org\/wp-content\/uploads\/2023\/10\/imagenes_meditaciones_diarias_9oct.jpg","keywords":["Evangelio","meditaci\u00f3n","Reflexi\u00f3n"],"articleSection":["Meditaci\u00f3n del d\u00eda"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/regnumchristi.org\/lunes-9-de-octubre-de-20203-una-nueva-oportunidad-para-un-si\/","url":"https:\/\/regnumchristi.org\/lunes-9-de-octubre-de-20203-una-nueva-oportunidad-para-un-si\/","name":"Lunes 9 de octubre de 20203 - \u00abUna nueva oportunidad para un \"s\u00ed\"\u00bb - Regnum Christi Internacional","isPartOf":{"@id":"https:\/\/regnumchristi.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/regnumchristi.org\/lunes-9-de-octubre-de-20203-una-nueva-oportunidad-para-un-si\/#primaryimage"},"image":{"@id":"https:\/\/regnumchristi.org\/lunes-9-de-octubre-de-20203-una-nueva-oportunidad-para-un-si\/#primaryimage"},"thumbnailUrl":"https:\/\/regnumchristi.org\/wp-content\/uploads\/2023\/10\/imagenes_meditaciones_diarias_9oct.jpg","datePublished":"2023-10-09T02:00:47+00:00","description":"Al mirar el vuelo de las golondrinas, el surgir de las flores, la hermosa vista de la monta\u00f1a, veo tu mano en cada uno de los acontecimientos.","breadcrumb":{"@id":"https:\/\/regnumchristi.org\/lunes-9-de-octubre-de-20203-una-nueva-oportunidad-para-un-si\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/regnumchristi.org\/lunes-9-de-octubre-de-20203-una-nueva-oportunidad-para-un-si\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/regnumchristi.org\/lunes-9-de-octubre-de-20203-una-nueva-oportunidad-para-un-si\/#primaryimage","url":"https:\/\/regnumchristi.org\/wp-content\/uploads\/2023\/10\/imagenes_meditaciones_diarias_9oct.jpg","contentUrl":"https:\/\/regnumchristi.org\/wp-content\/uploads\/2023\/10\/imagenes_meditaciones_diarias_9oct.jpg","width":900,"height":563},{"@type":"BreadcrumbList","@id":"https:\/\/regnumchristi.org\/lunes-9-de-octubre-de-20203-una-nueva-oportunidad-para-un-si\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/regnumchristi.org\/es\/"},{"@type":"ListItem","position":2,"name":"Lunes 9 de octubre de 20203 &#8211; \u00abUna nueva oportunidad para un &#8220;s\u00ed&#8221;\u00bb"}]},{"@type":"WebSite","@id":"https:\/\/regnumchristi.org\/#website","url":"https:\/\/regnumchristi.org\/","name":"Regnum Christi Internacional","description":"El Regnum Christi es una realidad de la Iglesia cat\u00f3lica cuya misi\u00f3n es hacer presente el Reino de Cristo","publisher":{"@id":"https:\/\/regnumchristi.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/regnumchristi.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/regnumchristi.org\/#organization","name":"Regnum Christi Internacional","url":"https:\/\/regnumchristi.org\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/regnumchristi.org\/#\/schema\/logo\/image\/","url":"https:\/\/regnumchristi.es\/wp-content\/uploads\/2023\/03\/Favicon-RC_ligh-cuadrado.png","contentUrl":"https:\/\/regnumchristi.es\/wp-content\/uploads\/2023\/03\/Favicon-RC_ligh-cuadrado.png","width":1080,"height":1080,"caption":"Regnum Christi Internacional"},"image":{"@id":"https:\/\/regnumchristi.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/RegnumChristiEspana\/","https:\/\/x.com\/rc_espana","https:\/\/www.instagram.com\/rc_espana\/","https:\/\/es.linkedin.com\/company\/regnumchristiespaa"]},{"@type":"Person","@id":"https:\/\/regnumchristi.org\/#\/schema\/person\/a5ad8b3c4bd3cb3a0abe8a1474fe8f0a","name":"Meditaciones Diarias","url":"https:\/\/regnumchristi.org\/es\/author\/meditacionesd\/"}]}},"_links":{"self":[{"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/posts\/98746","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/comments?post=98746"}],"version-history":[{"count":3,"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/posts\/98746\/revisions"}],"predecessor-version":[{"id":99164,"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/posts\/98746\/revisions\/99164"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/media\/99165"}],"wp:attachment":[{"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/media?parent=98746"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/categories?post=98746"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/regnumchristi.org\/es\/wp-json\/wp\/v2\/tags?post=98746"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}